{"id":60,"date":"2018-02-22T12:18:16","date_gmt":"2018-02-22T12:18:16","guid":{"rendered":"http:\/\/www.ull.es\/doctorados\/estudios-interdisciplinares-genero\/?page_id=60"},"modified":"2025-08-20T11:09:14","modified_gmt":"2025-08-20T11:09:14","slug":"actividades-formativas","status":"publish","type":"page","link":"https:\/\/www.ull.es\/doctorados\/estudios-interdisciplinares-genero\/organizacion-del-programa\/actividades-formativas\/","title":{"rendered":"Actividades formativas"},"content":{"rendered":"\n<div class=\"wp-block-stackable-columns alignfull stk-block-columns stk-block stk-2314a6b\" data-block-id=\"2314a6b\"><style>.stk-2314a6b {padding-bottom:0px !important;margin-top:-100px !important;margin-bottom:0px !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-2314a6b-column alignfull\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-1d1764d\" data-v=\"4\" data-block-id=\"1d1764d\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-1d1764d-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-1d1764d-inner-blocks\"><style id=\"depicter-1-inline-pre-css\">\n\n.depicter-1:not(.depicter-ready){\n\theight:450px;\n}\n\n\/***** Tablet *****\/\n@media screen and (max-width: 1024px){\n\n.depicter-1:not(.depicter-ready){\n\theight:700px;\n}\n\n}\n\/***** Mobile *****\/\n@media screen and (max-width: 767px){\n\n.depicter-1:not(.depicter-ready){\n\theight:360px;\n}\n\n}\n<\/style>\n<div id=\"depicter-1\" class=\"depicter depicter-document depicter-revert depicter-1 depicter-layout-fullwidth\">\n\n<div class=\"depicter-loading-container depicter-loading dotFlashing-dark\"><div class=\"depicter-loading-dark depicter-dot-flashing\">\n   <span><\/span>\n   <span><\/span>\n   <span><\/span>\n<\/div>\n<\/div>\n<div id=\"depicter-1-section-1\" class=\"depicter-section depicter-1-section-1\" data-name=\"Section 1\" data-type=\"section\" data-local-id=\"section-1\">\n<picture class=\"depicter-bg\">\n<source data-depicter-srcset=\"https:\/\/www.ull.es\/doctorados\/estudios-interdisciplinares-genero\/wp-content\/uploads\/sites\/15\/2025\/05\/Headers-Doctorados_DoctoradoEstudios-de-Genero-768x248.jpg, https:\/\/www.ull.es\/doctorados\/estudios-interdisciplinares-genero\/wp-content\/uploads\/sites\/15\/2025\/05\/Headers-Doctorados_DoctoradoEstudios-de-Genero.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(max-width: 1024px)\" \/>\n\n<source data-depicter-srcset=\"https:\/\/www.ull.es\/doctorados\/estudios-interdisciplinares-genero\/wp-content\/uploads\/sites\/15\/2025\/05\/Headers-Doctorados_DoctoradoEstudios-de-Genero.jpg, https:\/\/www.ull.es\/doctorados\/estudios-interdisciplinares-genero\/wp-content\/uploads\/sites\/15\/2025\/05\/Headers-Doctorados_DoctoradoEstudios-de-Genero-2000x645.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(min-width: 1025px)\" \/>\n<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-ken-burns=\"false\" data-tablet-ken-burns=\"false\" data-mobile-ken-burns=\"false\" alt=\"\" data-depicter-src=\"https:\/\/www.ull.es\/doctorados\/estudios-interdisciplinares-genero\/wp-content\/uploads\/sites\/15\/2025\/05\/Headers-Doctorados_DoctoradoEstudios-de-Genero.jpg\" data-object-fit=\"custom,custom,\" data-object-position=\"center top,,\" data-crop=\"{'focalPoint':{'x':0.5,'y':0.5},'mediaSize':{'width':1395.3488372093024736386723816394805908203125,'height':450}}\" data-tablet-crop=\"{'focalPoint':{'x':0.5,'y':0.5},'mediaSize':{'width':2170.54263565891460530110634863376617431640625,'height':700}}\" data-mobile-crop=\"{'focalPoint':{'x':0.5,'y':0.5},'mediaSize':{'width':2294.57364341085258274688385426998138427734375,'height':740}}\" \/>\n<\/picture>\n\n\n<h1 id=\"depicter-1-element-5\" class=\"depicter-element depicter-layer depicter-1-element-5\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 2\" data-local-id=\"element-5\" data-offset=\"x:0px;y:114px;origin:tl\" data-tablet-offset=\"x:149px;y:237px;origin:tl\" data-mobile-offset=\"x:8px;y:94px;origin:tl\" data-width=\"1200px,auto,348px\" data-height=\"auto,auto,auto\" data-responsive-scale=\"true,,\">Programa de Doctorado en <br>Estudios Interdisciplinares de G\u00e9nero<\/h1>\n\n<div id=\"depicter-1-element-10\" class=\"depicter-element depicter-layer depicter-1-element-10\" data-type=\"shape\" data-wrap=\"true\" data-name=\"Shape 1\" data-local-id=\"element-10\" data-offset=\"x:0px;y:370px;origin:tl\" data-tablet-offset=\"x:149px;y:453px;origin:tl\" data-mobile-offset=\"x:10px;y:342px;origin:tl\" data-width=\"1054px,794px,340px\" data-height=\"8px,8px,8px\" data-responsive-scale=\"true,,\"><\/div>\n<\/div>\n<\/div>\n<script>\n(window.depicterSetups = window.depicterSetups || []).push(function(){\n\tDepicter.basePath = 'https:\/\/www.ull.es\/doctorados\/estudios-interdisciplinares-genero\/wp-content\/plugins\/depicter\/resources\/scripts\/player\/';\n\tconst dpPlayer = Depicter.setup('.depicter-1',\n\t\t{\"width\":[\"1200\",\"1024\",\"360\"],\"height\":[\"450\",\"700\",\"360\"],\"view\":\"basic\",\"keepAspectRatio\":true,\"preload\":0,\"layout\":\"fullwidth\",\"rtl\":false,\"initAfterAppear\":false,\"ajaxApiUrl\":\"https:\\\/\\\/www.ull.es\\\/doctorados\\\/estudios-interdisciplinares-genero\\\/wp-admin\\\/admin-ajax.php\",\"mouseSwipe\":true,\"touchSwipe\":true,\"useWatermark\":false}\n\t);\n});\n<\/script><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns alignfull stk-block-columns stk--hide-mobile stk-block stk-6394276 stk-block-background\" data-block-id=\"6394276\"><style>.stk-6394276 {background-color:#f33f4e !important;padding-top:10px !important;margin-bottom:0px !important;}.stk-6394276:before{background-color:#f33f4e !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-6394276-column alignfull\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-8a66885\" data-v=\"4\" data-block-id=\"8a66885\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-8a66885-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-8a66885-inner-blocks\">\n<div class=\"wp-block-stackable-spacer stk-block-spacer stk--no-padding stk-block stk-bc89b3e\" data-block-id=\"bc89b3e\"><style>.stk-bc89b3e {height:0px !important;}<\/style><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns stk-block-columns stk-block stk-8b59b96\" data-block-id=\"8b59b96\"><style>.stk-8b59b96 .stk--block-align-8b59b96{align-items:flex-start !important;}.stk-8b59b96 {margin-top:50px !important;}.stk-8b59b96-column{--stk-columns-spacing:0px !important;--stk-column-gap:50px !important;}<\/style><div class=\"stk-row stk-inner-blocks stk--block-align-8b59b96 stk-block-content stk-content-align stk-8b59b96-column\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-dbb7e15\" data-v=\"4\" data-block-id=\"dbb7e15\"><style>@media screen and (min-width: 768px){.stk-dbb7e15 {flex:var(--stk-flex-grow, 1) 1 66.7% !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-dbb7e15-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-dbb7e15-inner-blocks\">\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-cc0239e\" id=\"complementos-de-formacion\" data-block-id=\"cc0239e\"><style>.stk-cc0239e .stk-block-heading__text{color:#000000 !important;font-weight:500 !important;}<\/style><h1 class=\"stk-block-heading__text has-text-color\">Actividades formativas<\/h1><\/div>\n\n\n\n<details class=\"wp-block-stackable-accordion stk-block-accordion stk-inner-blocks stk-block-content stk-block stk-7c390cd is-style-default\" id=\"seminarios\" data-block-id=\"7c390cd\"><style>.stk-7c390cd {border-style:solid !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;margin-bottom:11px !important;}<\/style>\n<summary class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-c927805 stk--container-small stk-block-accordion__heading\" data-v=\"4\" data-block-id=\"c927805\"><style>.stk-c927805 {padding-top:2px !important;padding-right:2px !important;padding-bottom:2px !important;padding-left:2px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-c927805-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-c927805-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-7935446\" data-block-id=\"7935446\"><style>.stk-7935446 .stk-inner-blocks{gap:39px !important;}@media screen and (max-width: 1023px){.stk-7935446 .stk-inner-blocks{gap:39px !important;}}@media screen and (max-width: 767px){.stk-7935446 .stk-inner-blocks{gap:39px !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-icon stk-block-icon stk-block stk-9a468d5\" data-block-id=\"9a468d5\"><style>.stk-9a468d5 .stk--svg-wrapper .stk--inner-svg svg:last-child{height:25px !important;width:25px !important;}.stk-9a468d5 .stk--svg-wrapper .stk--inner-svg svg:last-child, .stk-9a468d5 .stk--svg-wrapper .stk--inner-svg svg:last-child :is(g, path, rect, polygon, ellipse){fill:#f33f4e !important;}<\/style><span class=\"stk--svg-wrapper stk--has-icon2\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-9a468d5\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-9-a-468-d-5-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-9-a-468-d-5-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M256 288A144 144 0 1 0 256 0a144 144 0 1 0 0 288zm-94.7 32C72.2 320 0 392.2 0 481.3c0 17 13.8 30.7 30.7 30.7H481.3c17 0 30.7-13.8 30.7-30.7C512 392.2 439.8 320 350.7 320H161.3z\"><\/path><\/svg><\/div><div class=\"stk--inner-svg stk--icon-2\" style=\"display:none\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-9a468d5\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-9-a-468-d-5-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-9-a-468-d-5-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M304 128a80 80 0 1 0 -160 0 80 80 0 1 0 160 0zM96 128a128 128 0 1 1 256 0A128 128 0 1 1 96 128zM49.3 464H398.7c-8.9-63.3-63.3-112-129-112H178.3c-65.7 0-120.1 48.7-129 112zM0 482.3C0 383.8 79.8 304 178.3 304h91.4C368.2 304 448 383.8 448 482.3c0 16.4-13.3 29.7-29.7 29.7H29.7C13.3 512 0 498.7 0 482.3z\"><\/path><\/svg><\/div><\/span><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-31863c1\" id=\"seminarios-de-investigacion-en-estudios-interdisciplinares-de-genero\" data-block-id=\"31863c1\"><style>.stk-31863c1 .stk-block-heading__text{color:#000000 !important;font-weight:500 !important;font-family:\"ArgentumSans\", Sans-serif !important;}<\/style><h4 class=\"stk-block-heading__text has-text-color\">Seminarios de Investigaci\u00f3n en Estudios Interdisciplinares de G\u00e9nero<\/h4><\/div>\n<\/div><\/div>\n<\/div><\/div><\/summary>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-5222666 stk-block-accordion__content\" data-v=\"4\" data-block-id=\"5222666\"><style>.stk-5222666 {margin-top:-30px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-5222666-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-5222666-inner-blocks\">\n<ul class=\"wp-block-list\">\n<li>N\u00famero de horas: 40<\/li>\n\n\n\n<li>Descripci\u00f3n:&nbsp;Actividad de car\u00e1cter obligatorio para todo el estudiantado, desarrollado de modo compartido por todas las l\u00edneas de investigaci\u00f3n. En dicha actividad&nbsp;el\/la doctorando\/a deber\u00e1 preparar y presentar anualmente los avances de su investigaci\u00f3n, centr\u00e1ndose en el marco conceptual y metodol\u00f3gico del&nbsp;mismo. Supondr\u00e1 una manera de trabajar directamente en su proyecto de investigaci\u00f3n, as\u00ed como tambi\u00e9n en la comprensi\u00f3n de herramientas metodol\u00f3gicas&nbsp;y te\u00f3ricas necesarias para su formaci\u00f3n. Deber\u00e1 ser capaz de mostrar sus habilidades para selecci\u00f3n, recogida y comprensi\u00f3n de la bibliograf\u00eda necesaria para el desarrollo de su investigaci\u00f3n, as\u00ed como tambi\u00e9n ense\u00f1ar sus habilidades en el planteamiento de una investigaci\u00f3n original.&nbsp;Todas las universidades disponen de los medios necesarios y recursos telem\u00e1ticos que permiten participar en los seminarios a distancia. Planificaci\u00f3n temporal: Los\/ las estudiantes a tiempo completo realizar\u00e1n dicha actividad desde el primer a\u00f1o de sus estudios y en los a\u00f1os sucesivos ( 40 horas\/a\u00f1o). Los\/ las estudiantes a tiempo parcial realizar\u00e1n esta actividad de su formaci\u00f3n bianualmente. Las universidades y centros participantes habilitar\u00e1n y activar\u00e1n la posibilidad de que los\/las estudiantes del programa participen en dichos seminarios a trav\u00e9s de contactos en red peri\u00f3dicos, mediante plataformas docentes, foros, etc. Competencias vinculadas: CB11, CB14, CB15, CA02, CA05, CA06.<\/li>\n\n\n\n<li>Procedimiento de control:El Director(a)\/Tutora del doctorando incluir\u00e1 en el Documento de Actividades del doctorando\/a todos los datos de asistencia a Seminarios. Este documento&nbsp;se remitir\u00e1 a la Comisi\u00f3n Acad\u00e9mica, que incorporar\u00e1 los datos al registro de actividades del doctorando\/a.&nbsp;La evaluaci\u00f3n de esta actividad formativa se integrar\u00e1 en la evaluaci\u00f3n anual del Documento de Actividades de cada estudiante, la nota final de esta&nbsp;actividad ser\u00e1 una media ponderada de cada uno de los seminarios anuales.&nbsp;La Comisi\u00f3n Acad\u00e9mica valorar\u00e1 en su informe anual el cumplimiento o no cumplimento por parte del doctorando\/a de las actividades exigidas y especialmente&nbsp;en relaci\u00f3n con la definici\u00f3n del Plan de Investigaci\u00f3n.<\/li>\n\n\n\n<li>Actuaciones de movilidad: Su realizaci\u00f3n contempla la disponibilidad de los procedimientos de movilidad habituales:<\/li>\n<\/ul>\n<\/div><\/div><\/div>\n<\/details>\n\n\n\n<details class=\"wp-block-stackable-accordion stk-block-accordion stk-inner-blocks stk-block-content stk-block stk-269744c is-style-default\" id=\"asistencia\" data-block-id=\"269744c\"><style>.stk-269744c {border-style:solid !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;margin-bottom:11px !important;}<\/style>\n<summary class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-f352a66 stk--container-small stk-block-accordion__heading\" data-v=\"4\" data-block-id=\"f352a66\"><style>.stk-f352a66 {padding-top:2px !important;padding-right:2px !important;padding-bottom:2px !important;padding-left:2px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-f352a66-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-f352a66-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-cef9962\" data-block-id=\"cef9962\"><style>.stk-cef9962 .stk-inner-blocks{gap:39px !important;}@media screen and (max-width: 1023px){.stk-cef9962 .stk-inner-blocks{gap:39px !important;}}@media screen and (max-width: 767px){.stk-cef9962 .stk-inner-blocks{gap:39px !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-icon stk-block-icon stk-block stk-ebb4252\" data-block-id=\"ebb4252\"><style>.stk-ebb4252 .stk--svg-wrapper .stk--inner-svg svg:last-child{height:25px !important;width:25px !important;}.stk-ebb4252 .stk--svg-wrapper .stk--inner-svg svg:last-child, .stk-ebb4252 .stk--svg-wrapper .stk--inner-svg svg:last-child :is(g, path, rect, polygon, ellipse){fill:#f33f4e !important;}<\/style><span class=\"stk--svg-wrapper stk--has-icon2\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-ebb4252\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-ebb-4252-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-ebb-4252-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 640 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M320 32c-8.1 0-16.1 1.4-23.7 4.1L15.8 137.4C6.3 140.9 0 149.9 0 160s6.3 19.1 15.8 22.6l57.9 20.9C57.3 229.3 48 259.8 48 291.9v28.1c0 28.4-10.8 57.7-22.3 80.8c-6.5 13-13.9 25.8-22.5 37.6C0 442.7-.9 448.3 .9 453.4s6 8.9 11.2 10.2l64 16c4.2 1.1 8.7 .3 12.4-2s6.3-6.1 7.1-10.4c8.6-42.8 4.3-81.2-2.1-108.7C90.3 344.3 86 329.8 80 316.5V291.9c0-30.2 10.2-58.7 27.9-81.5c12.9-15.5 29.6-28 49.2-35.7l157-61.7c8.2-3.2 17.5 .8 20.7 9s-.8 17.5-9 20.7l-157 61.7c-12.4 4.9-23.3 12.4-32.2 21.6l159.6 57.6c7.6 2.7 15.6 4.1 23.7 4.1s16.1-1.4 23.7-4.1L624.2 182.6c9.5-3.4 15.8-12.5 15.8-22.6s-6.3-19.1-15.8-22.6L343.7 36.1C336.1 33.4 328.1 32 320 32zM128 408c0 35.3 86 72 192 72s192-36.7 192-72L496.7 262.6 354.5 314c-11.1 4-22.8 6-34.5 6s-23.5-2-34.5-6L143.3 262.6 128 408z\"><\/path><\/svg><\/div><div class=\"stk--inner-svg stk--icon-2\" style=\"display:none\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-ebb4252\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-ebb-4252-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-ebb-4252-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M219.3 .5c3.1-.6 6.3-.6 9.4 0l200 40C439.9 42.7 448 52.6 448 64s-8.1 21.3-19.3 23.5L352 102.9V160c0 70.7-57.3 128-128 128s-128-57.3-128-128V102.9L48 93.3v65.1l15.7 78.4c.9 4.7-.3 9.6-3.3 13.3s-7.6 5.9-12.4 5.9H16c-4.8 0-9.3-2.1-12.4-5.9s-4.3-8.6-3.3-13.3L16 158.4V86.6C6.5 83.3 0 74.3 0 64C0 52.6 8.1 42.7 19.3 40.5l200-40zM111.9 327.7c10.5-3.4 21.8 .4 29.4 8.5l71 75.5c6.3 6.7 17 6.7 23.3 0l71-75.5c7.6-8.1 18.9-11.9 29.4-8.5C401 348.6 448 409.4 448 481.3c0 17-13.8 30.7-30.7 30.7H30.7C13.8 512 0 498.2 0 481.3c0-71.9 47-132.7 111.9-153.6z\"><\/path><\/svg><\/div><\/span><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-2822238\" id=\"asistencia-y-presentacion-de-trabajos-en-congresos-cientificos-nacionales-o-internacionales\" data-block-id=\"2822238\"><style>.stk-2822238 .stk-block-heading__text{color:#000000 !important;font-weight:500 !important;font-family:\"ArgentumSans\", Sans-serif !important;}<\/style><h4 class=\"stk-block-heading__text has-text-color\">Asistencia y presentaci\u00f3n de trabajos en Congresos cient\u00edficos nacionales o internacionales<\/h4><\/div>\n<\/div><\/div>\n<\/div><\/div><\/summary>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-8d57570 stk-block-accordion__content\" data-v=\"4\" data-block-id=\"8d57570\"><style>.stk-8d57570 {margin-top:-30px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-8d57570-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-8d57570-inner-blocks\">\n<ul class=\"wp-block-list\">\n<li>N\u00famero de&nbsp;horas: &nbsp;40<\/li>\n\n\n\n<li>Descripci\u00f3n:&nbsp;Esta Actividad es obligatoria para todo el estudiantado. El objetivo es promover la mejora en el conocimiento y aplicaci\u00f3n de procedimientos espec\u00edficos,&nbsp;la complementaci\u00f3n de la formaci\u00f3n te\u00f3rica e instrumental y la introducci\u00f3n del alumnado en los principales debates metodol\u00f3gicos y te\u00f3ricos de<br>la disciplina y \u00e1rea de investigaci\u00f3n especializada. Esta actividad se desarrolla a iniciativa de cada l\u00ednea de investigaci\u00f3n, si bien el doctorando\/a podr\u00e1&nbsp;participar en las actividades impulsadas desde otras l\u00edneas adem\u00e1s de las que proponga la l\u00ednea en la que se encuadre, puede incluir tambi\u00e9n la asistencia&nbsp;a cursos especializados organizados por grupos de investigaci\u00f3n y centros ajenos al programa de doctorado.&nbsp;Planificaci\u00f3n temporal: El estudiante de doctorado a tiempo completo y a tiempo parcial deber\u00e1 al menos participar en dos congresos cient\u00edficos nacionales o internacionales a lo largo de&nbsp;todo su periodo de formaci\u00f3n, en los cuales presentar\u00e1 una contribuci\u00f3n cient\u00edfica en forma de comunicaci\u00f3n oral o p\u00f3ster.&nbsp;Competencias vinculadas: CB15, CA05, CA06<\/li>\n\n\n\n<li>Procedimiento de adaptaci\u00f3n:&nbsp;El Director\/Tutora del doctorando incluir\u00e1 en el Documento de Actividades del doctorando\/a todos los datos de trabajos presentados en congresos cient\u00edficos.&nbsp;En particular se indicar\u00e1 el t\u00edtulo y fecha de celebraci\u00f3n del congreso, el t\u00edtulo y car\u00e1cter de la presentaci\u00f3n (comunicaci\u00f3n oral o p\u00f3ster) y se incluir\u00e1 el&nbsp;resumen de la misma y el certificado de asistencia. Este documento se remitir\u00e1 a la Comisi\u00f3n Acad\u00e9mica que incorporar\u00e1 los datos al registro de actividades&nbsp;del doctorando\/a.&nbsp;Evaluaci\u00f3n de la actividad: El tutor\/a elevar\u00e1 un informe a la Comisi\u00f3n Acad\u00e9mica en el que detallar\u00e1 el grado de consecuci\u00f3n por parte del doctorando\/&nbsp;a de las competencias adecuadas a la actividad. La Comisi\u00f3n Acad\u00e9mica evaluar\u00e1 la documentaci\u00f3n integrada en la evaluaci\u00f3n del Documento de&nbsp;Actividades de cada estudiante, y el informe del tutor\/a.<\/li>\n\n\n\n<li>Actuaciones de movilidad:&nbsp;Su realizaci\u00f3n contempla la disponibilidad de los procedimientos de movilidad habituales:<\/li>\n<\/ul>\n<\/div><\/div><\/div>\n<\/details>\n\n\n\n<details class=\"wp-block-stackable-accordion stk-block-accordion stk-inner-blocks stk-block-content stk-block stk-1893d1d is-style-default\" id=\"elaboracion\" data-block-id=\"1893d1d\"><style>.stk-1893d1d {border-style:solid !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;margin-bottom:11px !important;}<\/style>\n<summary class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-572ba50 stk--container-small stk-block-accordion__heading\" data-v=\"4\" data-block-id=\"572ba50\"><style>.stk-572ba50 {padding-top:2px !important;padding-right:2px !important;padding-bottom:2px !important;padding-left:2px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-572ba50-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-572ba50-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-fcb2298\" data-block-id=\"fcb2298\"><style>.stk-fcb2298 .stk-inner-blocks{gap:39px !important;}@media screen and (max-width: 1023px){.stk-fcb2298 .stk-inner-blocks{gap:39px !important;}}@media screen and (max-width: 767px){.stk-fcb2298 .stk-inner-blocks{gap:39px !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-icon stk-block-icon stk-block stk-a546e8c\" data-block-id=\"a546e8c\"><style>.stk-a546e8c .stk--svg-wrapper .stk--inner-svg svg:last-child{height:25px !important;width:25px !important;}.stk-a546e8c .stk--svg-wrapper .stk--inner-svg svg:last-child, .stk-a546e8c .stk--svg-wrapper .stk--inner-svg svg:last-child :is(g, path, rect, polygon, ellipse){fill:#f33f4e !important;}<\/style><span class=\"stk--svg-wrapper stk--has-icon2\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-a546e8c\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-a-546-e-8-c-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-a-546-e-8-c-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M512 240c0 114.9-114.6 208-256 208c-37.1 0-72.3-6.4-104.1-17.9c-11.9 8.7-31.3 20.6-54.3 30.6C73.6 471.1 44.7 480 16 480c-6.5 0-12.3-3.9-14.8-9.9c-2.5-6-1.1-12.8 3.4-17.4l0 0 0 0 0 0 0 0 .3-.3c.3-.3 .7-.7 1.3-1.4c1.1-1.2 2.8-3.1 4.9-5.7c4.1-5 9.6-12.4 15.2-21.6c10-16.6 19.5-38.4 21.4-62.9C17.7 326.8 0 285.1 0 240C0 125.1 114.6 32 256 32s256 93.1 256 208z\"><\/path><\/svg><\/div><div class=\"stk--inner-svg stk--icon-2\" style=\"display:none\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-a546e8c\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-a-546-e-8-c-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-a-546-e-8-c-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M256 448c141.4 0 256-93.1 256-208S397.4 32 256 32S0 125.1 0 240c0 45.1 17.7 86.8 47.7 120.9c-1.9 24.5-11.4 46.3-21.4 62.9c-5.5 9.2-11.1 16.6-15.2 21.6c-2.1 2.5-3.7 4.4-4.9 5.7c-.6 .6-1 1.1-1.3 1.4l-.3 .3 0 0 0 0 0 0 0 0c-4.6 4.6-5.9 11.4-3.4 17.4c2.5 6 8.3 9.9 14.8 9.9c28.7 0 57.6-8.9 81.6-19.3c22.9-10 42.4-21.9 54.3-30.6c31.8 11.5 67 17.9 104.1 17.9zM128 208a32 32 0 1 1 0 64 32 32 0 1 1 0-64zm128 0a32 32 0 1 1 0 64 32 32 0 1 1 0-64zm96 32a32 32 0 1 1 64 0 32 32 0 1 1 -64 0z\"><\/path><\/svg><\/div><\/span><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-ecc88dd\" id=\"elaboracion-de-trabajos-publicables-en-revistas-cientificas\" data-block-id=\"ecc88dd\"><style>.stk-ecc88dd .stk-block-heading__text{color:#000000 !important;font-weight:500 !important;font-family:\"ArgentumSans\", Sans-serif !important;}<\/style><h4 class=\"stk-block-heading__text has-text-color\">Elaboraci\u00f3n de trabajos publicables en revistas cient\u00edficas<\/h4><\/div>\n<\/div><\/div>\n<\/div><\/div><\/summary>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-221465e stk-block-accordion__content\" data-v=\"4\" data-block-id=\"221465e\"><style>.stk-221465e {margin-top:-30px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-221465e-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-221465e-inner-blocks\">\n<ul class=\"wp-block-list\">\n<li>N\u00famero de&nbsp;horas: 200 horas<\/li>\n\n\n\n<li>Descripci\u00f3n:&nbsp;Actividad obligatoria para todos los estudiantes. Los estudiantes a tiempo completo deber\u00e1n realizar esta actividad entre el segundo y tercer a\u00f1o de su&nbsp;formaci\u00f3n. Y los estudiantes a tiempo parcial entre el tercer y cuarto a\u00f1o. todos ellos deber\u00e1n elaborar al menos un trabajo publicable en revistas cient\u00edficas a lo largo de todo el periodo de su formaci\u00f3n. La candidata o el candidato a doctor\/a deber\u00e1 participar de forma activa en la redacci\u00f3n de art\u00edculos que recojan los resultados de su investigaci\u00f3n con vistas a su publicaci\u00f3n&nbsp;en revistas de car\u00e1cter cient\u00edfico. Se considera que una parte b\u00e1sica de su formaci\u00f3n es adquirir habilidades como ser efectivo en la revisi\u00f3n&nbsp;de literatura y b\u00fasqueda de informaci\u00f3n cient\u00edfica preexistente, tener capacidad de s\u00edntesis a la hora de presentar los resultados o leer y escribir en ingl\u00e9s.&nbsp;Tambi\u00e9n deber\u00e1 aprender todo el proceso que implica la realizaci\u00f3n de una publicaci\u00f3n cient\u00edfica, contacto con editores, evaluadores y revisi\u00f3n de&nbsp;pruebas de imprenta.&nbsp;Competencias vinculadas: CB12, CB14, CB15, CA04, CA05, CA06<\/li>\n\n\n\n<li>Procedimiento de control:&nbsp;El Director\/Tutora del doctorado\/a incluir\u00e1 en el Documento de Actividades del doctorando\/a todos los trabajos publicados en revistas cient\u00edficas, o env\u00edas&nbsp;de publicaci\u00f3n, en los que la candidata o el candidato a doctor\/a tenga alg\u00fan grado de colaboraci\u00f3n. Se indicar\u00e1 brevemente el grado en el que el estudiante ha&nbsp;estado involucrado\/a en la preparaci\u00f3n y redacci\u00f3n del manuscrito. Este documento se remitir\u00e1 a la Comisi\u00f3n Acad\u00e9mica que incorporar\u00e1 los datos al registro de actividades del doctorando\/a.&nbsp;La evaluaci\u00f3n de esta actividad se realizar\u00e1 teniendo en cuenta la calidad de los trabajos presentados atendiendo a los \u00edndices cient\u00edficos internacionalmente&nbsp;reconocidos.<\/li>\n<\/ul>\n<\/div><\/div><\/div>\n<\/details>\n\n\n\n<details class=\"wp-block-stackable-accordion stk-block-accordion stk-inner-blocks stk-block-content stk-block stk-e2afeed is-style-default\" id=\"estancias\" data-block-id=\"e2afeed\"><style>.stk-e2afeed {border-style:solid !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;margin-bottom:11px !important;}<\/style>\n<summary class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-b716f05 stk--container-small stk-block-accordion__heading\" data-v=\"4\" data-block-id=\"b716f05\"><style>.stk-b716f05 {padding-top:2px !important;padding-right:2px !important;padding-bottom:2px !important;padding-left:2px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-b716f05-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-b716f05-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-fd1f34a\" data-block-id=\"fd1f34a\"><style>.stk-fd1f34a .stk-inner-blocks{gap:39px !important;}@media screen and (max-width: 1023px){.stk-fd1f34a .stk-inner-blocks{gap:39px !important;}}@media screen and (max-width: 767px){.stk-fd1f34a .stk-inner-blocks{gap:39px !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-icon stk-block-icon stk-block stk-b19d67d\" data-block-id=\"b19d67d\"><style>.stk-b19d67d .stk--svg-wrapper .stk--inner-svg svg:last-child{height:25px !important;width:25px !important;}.stk-b19d67d .stk--svg-wrapper .stk--inner-svg svg:last-child, .stk-b19d67d .stk--svg-wrapper .stk--inner-svg svg:last-child :is(g, path, rect, polygon, ellipse){fill:#f33f4e !important;}<\/style><span class=\"stk--svg-wrapper stk--has-icon2\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-b19d67d\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-b-19-d-67-d-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-b-19-d-67-d-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 640 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M381 114.9L186.1 41.8c-16.7-6.2-35.2-5.3-51.1 2.7L89.1 67.4C78 73 77.2 88.5 87.6 95.2l146.9 94.5L136 240 77.8 214.1c-8.7-3.9-18.8-3.7-27.3 .6L18.3 230.8c-9.3 4.7-11.8 16.8-5 24.7l73.1 85.3c6.1 7.1 15 11.2 24.3 11.2H248.4c5 0 9.9-1.2 14.3-3.4L535.6 212.2c46.5-23.3 82.5-63.3 100.8-112C645.9 75 627.2 48 600.2 48H542.8c-20.2 0-40.2 4.8-58.2 14L381 114.9zM0 480c0 17.7 14.3 32 32 32H608c17.7 0 32-14.3 32-32s-14.3-32-32-32H32c-17.7 0-32 14.3-32 32z\"><\/path><\/svg><\/div><div class=\"stk--inner-svg stk--icon-2\" style=\"display:none\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-b19d67d\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-b-19-d-67-d-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-b-19-d-67-d-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 640 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M.3 166.9L0 68C0 57.7 9.5 50.1 19.5 52.3l35.6 7.9c10.6 2.3 19.2 9.9 23 20L96 128l127.3 37.6L181.8 20.4C178.9 10.2 186.6 0 197.2 0h40.1c11.6 0 22.2 6.2 27.9 16.3l109 193.8 107.2 31.7c15.9 4.7 30.8 12.5 43.7 22.8l34.4 27.6c24 19.2 18.1 57.3-10.7 68.2c-41.2 15.6-86.2 18.1-128.8 7L121.7 289.8c-11.1-2.9-21.2-8.7-29.3-16.9L9.5 189.4c-5.9-6-9.3-14.1-9.3-22.5zM32 448H608c17.7 0 32 14.3 32 32s-14.3 32-32 32H32c-17.7 0-32-14.3-32-32s14.3-32 32-32zm96-80a32 32 0 1 1 64 0 32 32 0 1 1 -64 0zm128-16a32 32 0 1 1 0 64 32 32 0 1 1 0-64z\"><\/path><\/svg><\/div><\/span><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-baaa203\" id=\"estancias-de-investigacion-en-centros-nacionales-o-extranjeros\" data-block-id=\"baaa203\"><style>.stk-baaa203 .stk-block-heading__text{color:#000000 !important;font-weight:500 !important;font-family:\"ArgentumSans\", Sans-serif !important;}<\/style><h4 class=\"stk-block-heading__text has-text-color\">Estancias de investigaci\u00f3n en centros nacionales o extranjeros<\/h4><\/div>\n<\/div><\/div>\n<\/div><\/div><\/summary>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-ea32acc stk-block-accordion__content\" data-v=\"4\" data-block-id=\"ea32acc\"><style>.stk-ea32acc {margin-top:-30px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-ea32acc-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-ea32acc-inner-blocks\">\n<ul class=\"wp-block-list\">\n<li>N\u00famero de&nbsp;horas: 350<\/li>\n\n\n\n<li>Descripci\u00f3n:&nbsp;Actividad optativa<br>Aunque altamente recomendable, las exigencias de movilidad de esta actividad obligan a concederle car\u00e1cter optativo tanto para el estudiantado a&nbsp;tiempo parcial, como a tiempo completo. Estas estancias, con una duraci\u00f3n total entre 8 y 12 semanas, tendr\u00e1n como fin principal para el doctorando\/a,&nbsp;el realizar parte de su investigaci\u00f3n. Sin embargo, se consideran tambi\u00e9n una pieza fundamental en su formaci\u00f3n, ya que supone acercarse a otros sistemas&nbsp;educativos y de investigaci\u00f3n, acceder a seminarios y cursos realizados en otras universidades, mejorar su conocimiento de una segunda lengua&nbsp;y crear su propia red de contactos. La realizaci\u00f3n de estas estancias es un requisito para obtener la menci\u00f3n internacional al t\u00edtulo de doctor\/a, que&nbsp;se fomentar\u00e1 para todos los\/ las estudiantes del Programa.&nbsp;El n\u00famero de horas indicado se refiere al tiempo que se considera que el\/la estudiante dedicar\u00e1 a actividades formativas: aprendizaje de nuevas t\u00e9cnicas,&nbsp;asistencia a cursos y seminarios, etc. Se entiende que la mayor\u00eda de estudiantes a tiempo parcial tendr\u00e1n m\u00e1s dificultades para realizar estas estancias,&nbsp;por lo que en estos casos se promover\u00e1 la realizaci\u00f3n de estancias m\u00e1s cortas o la divisi\u00f3n de la estancia en varios periodos.&nbsp;Competencias vinculadas: CB13, CA04<\/li>\n\n\n\n<li>Procedimiento de control:&nbsp;De modo previo a la realizaci\u00f3n de la estancia, la Comisi\u00f3n Acad\u00e9mica ser\u00e1 informada de los detalles de la misma y autorizar\u00e1 su realizaci\u00f3n. Durante&nbsp;su estancia el\/la estudiante trabajar\u00e1 supervisado\/a por un profesor\/a o investigador\/a del centro de destino, quien realizar\u00e1 un informe final sobre el&nbsp;trabajo realizado durante la estancia y el rendimiento del\/la estudiante. Dicho informe reflejar\u00e1 no s\u00f3lo las actividades de investigaci\u00f3n, sino cualquier&nbsp;otra actividad formativa realizada durante la misma (asistencias o impartici\u00f3n de seminarios, asistencia a cursos especializados, etc.), as\u00ed como la formaci\u00f3n&nbsp;recibida por el estudiante en t\u00e9cnicas espec\u00edficas, y deber\u00e1 estar avalado por el director\/a de esa instituci\u00f3n o centro.&nbsp;El Director\/Tutor\/a incluir\u00e1 en el Documento de Actividades del doctorando\/a dicho informe junto con una valoraci\u00f3n personal del resultado de la estancia.&nbsp;Toda la documentaci\u00f3n relevante se remitir\u00e1 a la comisi\u00f3n acad\u00e9mica, que incorporar\u00e1 los datos al registro de actividades del doctorando\/a. La Comisi\u00f3n&nbsp;Acad\u00e9mica incorporar\u00e1 en su informe anual una valoraci\u00f3n de esta actividad.<\/li>\n\n\n\n<li>Actuaciones de movilidad:&nbsp;Su realizaci\u00f3n contempla la disponibilidad de los procedimientos de movilidad habituales:<\/li>\n<\/ul>\n<\/div><\/div><\/div>\n<\/details>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-53ec762\" data-v=\"4\" data-block-id=\"53ec762\"><style>.stk-53ec762-inner-blocks{row-gap:0px !important;}.stk-53ec762 {padding-top:0px !important;padding-right:0px !important;padding-bottom:0px !important;padding-left:0px !important;}@media screen and (min-width: 768px){.stk-53ec762 {flex:var(--stk-flex-grow, 1) 1 33.3% !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-53ec762-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-53ec762-inner-blocks\">\n\n<ul class=\"widget-box\">\n<li class='contacto-header'>Informaci\u00f3n de contacto<\/li><li><i class=\"fa fa-map-marker\"><\/i> Avda. Astrof\u00edsico Francisco S\u00e1nchez, SN. Edificio Calabaza \u2013 AN.2D Apdo. 456 38200 San Crist\u00f3bal de La Laguna<\/li><li><i class=\"fa fa-envelope\"><\/i>  <a href=mailto:doctorado.genero@ull.es>doctorado.genero@ull.es<\/a><\/li><li><i class=\"fa fa-calendar\"><\/i><a href=\"http:\/\/citaprevia.ull.es\/index.php?s=edpo\"> Cita previa<\/a><\/li>\n<\/ul>\n\n\n<\/div><\/div><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Actividades formativas Seminarios de Investigaci\u00f3n en Estudios Interdisciplinares de G\u00e9nero Asistencia y presentaci\u00f3n de trabajos en Congresos cient\u00edficos nacionales o internacionales Elaboraci\u00f3n de trabajos publicables en revistas cient\u00edficas Estancias de investigaci\u00f3n en centros nacionales o extranjeros<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":27,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/template-frontpage.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-60","page","type-page","status-publish","hentry"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 06:25:20","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.ull.es\/doctorados\/estudios-interdisciplinares-genero\/wp-json\/wp\/v2\/pages\/60","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ull.es\/doctorados\/estudios-interdisciplinares-genero\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ull.es\/doctorados\/estudios-interdisciplinares-genero\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ull.es\/doctorados\/estudios-interdisciplinares-genero\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ull.es\/doctorados\/estudios-interdisciplinares-genero\/wp-json\/wp\/v2\/comments?post=60"}],"version-history":[{"count":13,"href":"https:\/\/www.ull.es\/doctorados\/estudios-interdisciplinares-genero\/wp-json\/wp\/v2\/pages\/60\/revisions"}],"predecessor-version":[{"id":343,"href":"https:\/\/www.ull.es\/doctorados\/estudios-interdisciplinares-genero\/wp-json\/wp\/v2\/pages\/60\/revisions\/343"}],"up":[{"embeddable":true,"href":"https:\/\/www.ull.es\/doctorados\/estudios-interdisciplinares-genero\/wp-json\/wp\/v2\/pages\/27"}],"wp:attachment":[{"href":"https:\/\/www.ull.es\/doctorados\/estudios-interdisciplinares-genero\/wp-json\/wp\/v2\/media?parent=60"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}