{"id":76,"date":"2018-02-22T13:37:55","date_gmt":"2018-02-22T13:37:55","guid":{"rendered":"http:\/\/www.ull.es\/doctorados\/filosofia\/?page_id=76"},"modified":"2025-08-20T11:16:59","modified_gmt":"2025-08-20T11:16:59","slug":"acceso-admision","status":"publish","type":"page","link":"https:\/\/www.ull.es\/doctorados\/filosofia\/fr\/informacion-academica\/acceso-admision\/","title":{"rendered":"Acc\u00e8s et admission"},"content":{"rendered":"\n<div class=\"wp-block-stackable-columns alignfull stk-block-columns stk-block stk-2314a6b\" data-block-id=\"2314a6b\"><style>.stk-2314a6b {padding-bottom:0px !important;margin-top:-100px !important;margin-bottom:0px !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-2314a6b-column alignfull\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-1d1764d\" data-v=\"4\" data-block-id=\"1d1764d\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-1d1764d-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-1d1764d-inner-blocks\"><style id=\"depicter-1-inline-pre-css\">\n\n.depicter-1:not(.depicter-ready){\n\theight:450px;\n}\n\n\/***** Tablet *****\/\n@media screen and (max-width: 1024px){\n\n.depicter-1:not(.depicter-ready){\n\theight:700px;\n}\n\n}\n\/***** Mobile *****\/\n@media screen and (max-width: 767px){\n\n.depicter-1:not(.depicter-ready){\n\theight:360px;\n}\n\n}\n<\/style>\n<div id=\"depicter-1\" class=\"depicter depicter-document depicter-revert depicter-1 depicter-layout-fullwidth\">\n\n<div class=\"depicter-loading-container depicter-loading dotFlashing-dark\"><div class=\"depicter-loading-dark depicter-dot-flashing\">\n   <span><\/span>\n   <span><\/span>\n   <span><\/span>\n<\/div>\n<\/div>\n<div id=\"depicter-1-section-1\" class=\"depicter-section depicter-1-section-1\" data-name=\"Section 1\" data-type=\"section\" data-local-id=\"section-1\">\n<picture class=\"depicter-bg\">\n<source data-depicter-srcset=\"https:\/\/www.ull.es\/doctorados\/filosofia\/wp-content\/uploads\/sites\/16\/2025\/05\/Headers-Doctorados_Doctorado-Filosofia-768x248.jpg, https:\/\/www.ull.es\/doctorados\/filosofia\/wp-content\/uploads\/sites\/16\/2025\/05\/Headers-Doctorados_Doctorado-Filosofia.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(max-width: 1024px)\" \/>\n\n<source data-depicter-srcset=\"https:\/\/www.ull.es\/doctorados\/filosofia\/wp-content\/uploads\/sites\/16\/2025\/05\/Headers-Doctorados_Doctorado-Filosofia.jpg, https:\/\/www.ull.es\/doctorados\/filosofia\/wp-content\/uploads\/sites\/16\/2025\/05\/Headers-Doctorados_Doctorado-Filosofia-2000x645.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(min-width: 1025px)\" \/>\n<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-ken-burns=\"false\" data-tablet-ken-burns=\"false\" data-mobile-ken-burns=\"false\" alt=\"\" data-depicter-src=\"https:\/\/www.ull.es\/doctorados\/filosofia\/wp-content\/uploads\/sites\/16\/2025\/05\/Headers-Doctorados_Doctorado-Filosofia.jpg\" data-object-fit=\"cover,custom,\" data-object-position=\"center top,,\" data-crop=\"{'focalPoint':{'x':0.5,'y':0.409999999999999975575093458246556110680103302001953125},'mediaSize':{'width':1791,'height':577}}\" data-tablet-crop=\"{'focalPoint':{'x':0.6999999999999999555910790149937383830547332763671875,'y':0.5},'mediaSize':{'width':2170,'height':700}}\" data-mobile-crop=\"{'focalPoint':{'x':0.82999999999999996003197111349436454474925994873046875,'y':0.330000000000000015543122344752191565930843353271484375},'mediaSize':{'width':2294,'height':740}}\" \/>\n<\/picture>\n\n\n<h1 id=\"depicter-1-element-5\" class=\"depicter-element depicter-layer depicter-1-element-5\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 2\" data-local-id=\"element-5\" data-offset=\"x:0px;y:138px;origin:tl\" data-tablet-offset=\"x:176px;y:206px;origin:tl\" data-mobile-offset=\"x:39px;y:139px;origin:tl\" data-width=\"1200px,auto,348px\" data-height=\"auto,auto,auto\" data-responsive-scale=\"true,,\">Programa de Doctorado en Filosof\u00eda<\/h1>\n\n<div id=\"depicter-1-element-10\" class=\"depicter-element depicter-layer depicter-1-element-10\" data-type=\"shape\" data-wrap=\"true\" data-name=\"Shape 1\" data-local-id=\"element-10\" data-offset=\"x:0px;y:311px;origin:tl\" data-tablet-offset=\"x:215px;y:361px;origin:tl\" data-mobile-offset=\"x:39px;y:293px;origin:tl\" data-width=\"983px,647px,282px\" data-height=\"8px,8px,8px\" data-responsive-scale=\"true,,\"><\/div>\n<\/div>\n<\/div>\n<script>\n(window.depicterSetups = window.depicterSetups || []).push(function(){\n\tDepicter.basePath = 'https:\/\/www.ull.es\/doctorados\/filosofia\/wp-content\/plugins\/depicter\/resources\/scripts\/player\/';\n\tconst dpPlayer = Depicter.setup('.depicter-1',\n\t\t{\"width\":[\"1200\",\"1024\",\"360\"],\"height\":[\"450\",\"700\",\"360\"],\"view\":\"basic\",\"keepAspectRatio\":true,\"preload\":0,\"layout\":\"fullwidth\",\"rtl\":false,\"initAfterAppear\":false,\"ajaxApiUrl\":\"https:\\\/\\\/www.ull.es\\\/doctorados\\\/filosofia\\\/wp-admin\\\/admin-ajax.php\",\"mouseSwipe\":true,\"touchSwipe\":true,\"useWatermark\":false}\n\t);\n});\n<\/script><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns alignfull stk-block-columns stk--hide-mobile stk-block stk-6394276 stk-block-background\" data-block-id=\"6394276\"><style>.stk-6394276 {background-color:#f33f4e !important;padding-top:10px !important;margin-bottom:0px !important;}.stk-6394276:before{background-color:#f33f4e !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-6394276-column alignfull\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-8a66885\" data-v=\"4\" data-block-id=\"8a66885\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-8a66885-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-8a66885-inner-blocks\">\n<div class=\"wp-block-stackable-spacer stk-block-spacer stk--no-padding stk-block stk-bc89b3e\" data-block-id=\"bc89b3e\"><style>.stk-bc89b3e {height:0px !important;}<\/style><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns stk-block-columns stk-block stk-8b59b96\" data-block-id=\"8b59b96\"><style>.stk-8b59b96 .stk--block-align-8b59b96{align-items:flex-start !important;}.stk-8b59b96 {margin-top:25px !important;}.stk-8b59b96-column{--stk-columns-spacing:0px !important;--stk-column-gap:50px !important;}<\/style><div class=\"stk-row stk-inner-blocks stk--block-align-8b59b96 stk-block-content stk-content-align stk-8b59b96-column\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-dbb7e15\" data-v=\"4\" data-block-id=\"dbb7e15\"><style>@media screen and (min-width: 768px){.stk-dbb7e15 {flex:var(--stk-flex-grow, 1) 1 66.7% !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-dbb7e15-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-dbb7e15-inner-blocks\">\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-cc0239e\" id=\"complementos-de-formacion\" data-block-id=\"cc0239e\"><style>.stk-cc0239e .stk-block-heading__text{color:#000000 !important;font-weight:500 !important;}<\/style><h1 class=\"stk-block-heading__text has-text-color\">Acceso y admisi\u00f3n<\/h1><\/div>\n\n\n\n<details class=\"wp-block-stackable-accordion stk-block-accordion stk-inner-blocks stk-block-content stk-block stk-7c390cd is-style-default\" id=\"sistemas\" data-block-id=\"7c390cd\"><style>.stk-7c390cd {border-style:solid !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;margin-bottom:11px !important;}<\/style>\n<summary class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-c927805 stk--container-small stk-block-accordion__heading\" data-v=\"4\" data-block-id=\"c927805\"><style>.stk-c927805 {padding-top:2px !important;padding-right:2px !important;padding-bottom:2px !important;padding-left:2px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-c927805-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-c927805-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-7935446\" data-block-id=\"7935446\"><style>.stk-7935446 .stk-inner-blocks{gap:39px !important;}@media screen and (max-width: 1023px){.stk-7935446 .stk-inner-blocks{gap:39px !important;}}@media screen and (max-width: 767px){.stk-7935446 .stk-inner-blocks{gap:39px !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-icon stk-block-icon stk-block stk-9a468d5\" data-block-id=\"9a468d5\"><style>.stk-9a468d5 .stk--svg-wrapper .stk--inner-svg svg:last-child{height:25px !important;width:25px !important;}.stk-9a468d5 .stk--svg-wrapper .stk--inner-svg svg:last-child, .stk-9a468d5 .stk--svg-wrapper .stk--inner-svg svg:last-child :is(g, path, rect, polygon, ellipse){fill:#f33f4e !important;}<\/style><span class=\"stk--svg-wrapper stk--has-icon2\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-9a468d5\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-9-a-468-d-5-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-9-a-468-d-5-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M256 512A256 256 0 1 0 256 0a256 256 0 1 0 0 512zM216 336h24V272H216c-13.3 0-24-10.7-24-24s10.7-24 24-24h48c13.3 0 24 10.7 24 24v88h8c13.3 0 24 10.7 24 24s-10.7 24-24 24H216c-13.3 0-24-10.7-24-24s10.7-24 24-24zm40-208a32 32 0 1 1 0 64 32 32 0 1 1 0-64z\"><\/path><\/svg><\/div><div class=\"stk--inner-svg stk--icon-2\" style=\"display:none\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-9a468d5\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-9-a-468-d-5-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-9-a-468-d-5-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 192 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M48 80a48 48 0 1 1 96 0A48 48 0 1 1 48 80zM0 224c0-17.7 14.3-32 32-32H96c17.7 0 32 14.3 32 32V448h32c17.7 0 32 14.3 32 32s-14.3 32-32 32H32c-17.7 0-32-14.3-32-32s14.3-32 32-32H64V256H32c-17.7 0-32-14.3-32-32z\"><\/path><\/svg><\/div><\/span><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-31863c1\" id=\"sistemas-de-informacion-previo\" data-block-id=\"31863c1\"><style>.stk-31863c1 .stk-block-heading__text{color:#000000 !important;font-weight:500 !important;font-family:\"ArgentumSans\", Sans-serif !important;}<\/style><h4 class=\"stk-block-heading__text has-text-color\">Sistemas de informaci\u00f3n previo<\/h4><\/div>\n<\/div><\/div>\n<\/div><\/div><\/summary>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-5222666 stk-block-accordion__content\" data-v=\"4\" data-block-id=\"5222666\"><style>.stk-5222666 {margin-top:-30px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-5222666-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-5222666-inner-blocks\">\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-8866a8d\" data-block-id=\"8866a8d\"><p class=\"stk-block-text__text\"><strong>Fase previa a la matriculaci\u00f3n<\/strong><\/p><\/div>\n\n\n\n<p>La informaci\u00f3n a las personas potencialmente interesadas sobre las caracter\u00edsticas del programa, los criterios de acceso y admisi\u00f3n y el procedimiento administrativo para la admisi\u00f3n y matr\u00edcula ser\u00e1 a trav\u00e9s de las v\u00edas habituales y dentro de la oferta de estudios de doctorado: canal virtual, carteles, medios de comunicaci\u00f3n, redes sociales institucionales entre otras v\u00edas oficiales.<\/p>\n\n\n\n<p>La informaci\u00f3n de contacto del Negociado de Doctorado de la ULL es la siguiente:<br><a href=\"https:\/\/www.ull.es\/citaprevia\/\" target=\"_blank\" rel=\"noopener\">Cita previa<\/a><br>Horario de atenci\u00f3n al p\u00fablico: 9:00 a 14:00<br>Direcci\u00f3n: Campus de Anchieta. Avda. Astrof\u00edsico Francisco S\u00e1nchez, S\/N. Edificio Calabaza &#8211; AN.2D Apdo. 456. 38200 San Crist\u00f3bal de La Laguna.<\/p>\n\n\n\n<p>Tel\u00e9fonos: 922317270 y 922317269<br>Correo electr\u00f3nico: doctorado@ull.es<\/p>\n\n\n\n<p>La universidad dispone igualmente de un Servicio de Informaci\u00f3n y Orientaci\u00f3n (SIO) que es la oficina destinada a informar, asesorar y orientar a los futuros estudiantes en temas relacionados con la formaci\u00f3n y la vida universitaria, as\u00ed como dirigirlos convenientemente, en las demandas m\u00e1s espec\u00edficas, a las oficinas correspondientes. El SIO est\u00e1 ubicado en la Planta baja del Edificio Central del Campus Central de la Universidad de La Laguna, en la calle Pedro Zerolo de La Laguna. <a href=\"https:\/\/www.ull.es\/servicios\/servicio-de-informacion-y-orientacion-sio\/\" target=\"_blank\" rel=\"noopener\">P\u00e1gina web<\/a><\/p>\n\n\n\n<p><strong>Acogida y orientaci\u00f3n de nuevo ingreso<\/strong><\/p>\n\n\n\n<p>Desde la Escuela de Doctorado se ofrecer\u00e1 una jornada de bienvenida al alumnado de nuevo ingreso, adem\u00e1s de jornadas informativas sobre temas concretos de inter\u00e9s. Asimismo, todo el alumnado est\u00e1 matriculado en un aula virtual para avisos y canal de comunicaci\u00f3n.<br>Por su parte, el alumnado tambi\u00e9n tendr\u00e1 una sesi\u00f3n de presentaci\u00f3n del programa por parte de quien coordine la comisi\u00f3n acad\u00e9mica de la Universidad de La Laguna y ser\u00e1 incluido en un aula virtual del programa.<br>En&nbsp;<a target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">la Web de la Escuela de Doctorado<\/a>&nbsp;hay varios enlaces con informaci\u00f3n sobre todos los procedimientos precisos para la realizaci\u00f3n de la tesis doctoral, as\u00ed como los formularios relacionados. De importancia especial para el alumnado de nuevo ingreso puede ser la p\u00e1gina donde se recoge toda la normativa de los estudios de doctorado.<\/p>\n\n\n\n<p><strong>Servicio de Garant\u00eda Interno de Calidad de la Universidad de La Laguna<\/strong><\/p>\n\n\n\n<p>Como garant\u00eda de la calidad de la ense\u00f1anza, de su mejora, as\u00ed como de la garant\u00eda de los derechos del alumnado y del profesorado, el t\u00edtulo cuenta con normativa espec\u00edfica relativa a los mecanismos de difusi\u00f3n dentro del Sistema de Garant\u00eda Interno de Calidad de la Universidad de La Laguna.<\/p>\n<\/div><\/div><\/div>\n<\/details>\n\n\n\n<details class=\"wp-block-stackable-accordion stk-block-accordion stk-inner-blocks stk-block-content stk-block stk-88a7c9c is-style-default\" id=\"requisitos\" data-block-id=\"88a7c9c\"><style>.stk-88a7c9c {border-style:solid !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;margin-bottom:10px !important;}<\/style>\n<summary class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-27019df stk--container-small stk-block-accordion__heading\" data-v=\"4\" data-block-id=\"27019df\"><style>.stk-27019df {padding-top:2px !important;padding-right:2px !important;padding-bottom:2px !important;padding-left:2px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-27019df-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-27019df-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-9c9ce7e\" data-block-id=\"9c9ce7e\"><style>.stk-9c9ce7e .stk-inner-blocks{gap:39px !important;}@media screen and (max-width: 1023px){.stk-9c9ce7e .stk-inner-blocks{gap:39px !important;}}@media screen and (max-width: 767px){.stk-9c9ce7e .stk-inner-blocks{gap:39px !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-icon stk-block-icon stk-block stk-61c8ad3\" data-block-id=\"61c8ad3\"><style>.stk-61c8ad3 .stk--svg-wrapper .stk--inner-svg svg:last-child{height:25px !important;width:25px !important;}.stk-61c8ad3 .stk--svg-wrapper .stk--inner-svg svg:last-child, .stk-61c8ad3 .stk--svg-wrapper .stk--inner-svg svg:last-child :is(g, path, rect, polygon, ellipse){fill:#f33f4e !important;}<\/style><span class=\"stk--svg-wrapper stk--has-icon2\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-61c8ad3\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-61-c-8-ad-3-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-61-c-8-ad-3-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M256 512A256 256 0 1 0 256 0a256 256 0 1 0 0 512zM169.8 165.3c7.9-22.3 29.1-37.3 52.8-37.3h58.3c34.9 0 63.1 28.3 63.1 63.1c0 22.6-12.1 43.5-31.7 54.8L280 264.4c-.2 13-10.9 23.6-24 23.6c-13.3 0-24-10.7-24-24V250.5c0-8.6 4.6-16.5 12.1-20.8l44.3-25.4c4.7-2.7 7.6-7.7 7.6-13.1c0-8.4-6.8-15.1-15.1-15.1H222.6c-3.4 0-6.4 2.1-7.5 5.3l-.4 1.2c-4.4 12.5-18.2 19-30.6 14.6s-19-18.2-14.6-30.6l.4-1.2zM224 352a32 32 0 1 1 64 0 32 32 0 1 1 -64 0z\"><\/path><\/svg><\/div><div class=\"stk--inner-svg stk--icon-2\" style=\"display:none\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-61c8ad3\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-61-c-8-ad-3-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-61-c-8-ad-3-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M464 256A208 208 0 1 0 48 256a208 208 0 1 0 416 0zM0 256a256 256 0 1 1 512 0A256 256 0 1 1 0 256zm169.8-90.7c7.9-22.3 29.1-37.3 52.8-37.3h58.3c34.9 0 63.1 28.3 63.1 63.1c0 22.6-12.1 43.5-31.7 54.8L280 264.4c-.2 13-10.9 23.6-24 23.6c-13.3 0-24-10.7-24-24V250.5c0-8.6 4.6-16.5 12.1-20.8l44.3-25.4c4.7-2.7 7.6-7.7 7.6-13.1c0-8.4-6.8-15.1-15.1-15.1H222.6c-3.4 0-6.4 2.1-7.5 5.3l-.4 1.2c-4.4 12.5-18.2 19-30.6 14.6s-19-18.2-14.6-30.6l.4-1.2zM224 352a32 32 0 1 1 64 0 32 32 0 1 1 -64 0z\"><\/path><\/svg><\/div><\/span><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-bcb6d4e\" id=\"requisitos-de-acceso\" data-block-id=\"bcb6d4e\"><style>.stk-bcb6d4e .stk-block-heading__text{color:#000000 !important;font-weight:500 !important;font-family:\"ArgentumSans\", Sans-serif !important;}<\/style><h4 class=\"stk-block-heading__text has-text-color\">Requisitos de acceso<\/h4><\/div>\n<\/div><\/div>\n<\/div><\/div><\/summary>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-76d605c stk-block-accordion__content\" data-v=\"4\" data-block-id=\"76d605c\"><style>.stk-76d605c {margin-top:-30px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-76d605c-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-76d605c-inner-blocks\">\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-287324e\" data-block-id=\"287324e\"><p class=\"stk-block-text__text\">Para acceder a alguno de los programas de doctorado de la ULL se deben cumplir los requisitos establecidos en el Reglamento de Ense\u00f1anzas Oficiales de Doctorado de la Universidad de La Laguna en su art\u00edculo 5.<\/p><\/div>\n\n\n\n<p>La persona solicitante deber\u00e1 presentar el aval de un investigador o investigadora adscrito al programa como posible director o directora de la tesis doctoral, cumpliendo con los requisitos del art\u00edculo 10 del Reglamento de Doctorado de la ULL.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/drive.google.com\/file\/d\/1TDLcCndz5O6cYEmbkVQ82JJpFEAucIlw\/view?usp=drive_link\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">Modelo de Aval para descargar<\/a><\/li>\n<\/ul>\n\n\n\n<p><strong>Perfil de ingreso<\/strong><\/p>\n\n\n\n<p>El perfil de ingreso necesario para acceder a este programa de doctorado es el siguiente:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Perfil 1.<\/strong>&nbsp;Personas graduadas o licenciadas en Filosof\u00eda que hayan realizado un m\u00e1ster universitario en Filosof\u00eda. Por su car\u00e1cter transdisciplinar, el programa tambi\u00e9n permite los siguientes perfiles de ingreso:<\/li>\n\n\n\n<li><strong>Perfil 2.<\/strong>&nbsp;Personas graduadas o licenciadas en cualquier rama de conocimiento que hayan cursado un m\u00e1ster universitario en Filosof\u00eda.<\/li>\n\n\n\n<li><strong>Perfil 3.<\/strong>&nbsp;Personas graduadas o licenciadas en Filosof\u00eda o Humanidades que hayan cursado el M\u00e1ster de Formaci\u00f3n del Profesorado de Ense\u00f1anza Secundaria (especialidad de Filosof\u00eda)<\/li>\n\n\n\n<li><strong>Perfil 4.<\/strong>&nbsp;Personas graduadas o licenciadas en la rama de Artes y Humanidades u otras, siempre que la l\u00ednea de investigaci\u00f3n elegida sea coherente con la formaci\u00f3n acad\u00e9mica e investigadora recibida en grado y\/o m\u00e1ster y realice un complemento formativo adecuado.<\/li>\n<\/ul>\n\n\n\n<p>Si bien no se exige la acreditaci\u00f3n de un nivel B1 o superior en un segundo idioma moderno habitual para la comunicaci\u00f3n cient\u00edfica, se requerir\u00e1 el compromiso idiom\u00e1tico del doctorando de seguir las directrices propuestas por tutores y directores a trav\u00e9s de estancias en centros extranjeros o de cursos de idiomas espec\u00edficos de las distintas universidades del programa.<\/p>\n\n\n\n<p>Las personas que accedan al Programa desde el M\u00e1ster en Formaci\u00f3n del Profesorado de Educaci\u00f3n Secundaria Obligatoria y Bachillerato, Formaci\u00f3n Profesional y Ense\u00f1anza de Idiomas deber\u00e1n realizar un trabajo equivalente a los trabajos fin de m\u00e1ster que se ofertan en los M\u00e1steres Universitarios en Filosof\u00eda que ofertan las diferentes universidades integrantes del programa. El trabajo podr\u00e1 ser dirigido por la misma persona que la tesis doctoral y ser\u00e1 defendido previamente a la lectura y defensa de esta, conforme a la normativa. No obstante, podr\u00e1n acceder directamente al programa de doctorado quienes habiendo cursado el M\u00e1ster de Profesorado en Secundaria (especialidad de Filosof\u00eda) deseen realizar su doctorado en la l\u00ednea de investigaci\u00f3n de Did\u00e1ctica de la Filosof\u00eda o \u00c9tica y docencia.<\/p>\n\n\n\n<p><strong>Alumnado con necesidades espec\u00edficas de apoyo educativo<\/strong><\/p>\n\n\n\n<p>En cumplimiento del Real Decreto 99\/2011, de 28 de enero, por el que se regulan las ense\u00f1anzas oficiales de doctorado se cuenta con un programa espec\u00edfico de ayuda al alumnado con necesidades espec\u00edficas de apoyo educativo para favorecer su integraci\u00f3n educativa y social. M\u00e1s informaci\u00f3n aqu\u00ed (hiperv\u00ednculo:&nbsp;<a href=\"https:\/\/www.ull.es\/la-universidad\/inclusion\/#becas-PAED\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">https:\/\/www.ull.es\/la-universidad\/inclusion\/#becas-PAED<\/a>).<\/p>\n<\/div><\/div><\/div>\n<\/details>\n\n\n\n<details class=\"wp-block-stackable-accordion stk-block-accordion stk-inner-blocks stk-block-content stk-block stk-6320006 is-style-default\" id=\"criterios\" data-block-id=\"6320006\"><style>.stk-6320006 {border-style:solid !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;margin-bottom:9px !important;}<\/style>\n<summary class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-ae2ad76 stk--container-small stk-block-accordion__heading\" data-v=\"4\" data-block-id=\"ae2ad76\"><style>.stk-ae2ad76 {padding-top:2px !important;padding-right:2px !important;padding-bottom:2px !important;padding-left:2px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-ae2ad76-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-ae2ad76-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-16db2af\" data-block-id=\"16db2af\"><style>.stk-16db2af .stk-inner-blocks{gap:39px !important;}@media screen and (max-width: 1023px){.stk-16db2af .stk-inner-blocks{gap:39px !important;}}@media screen and (max-width: 767px){.stk-16db2af .stk-inner-blocks{gap:39px !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-icon stk-block-icon stk-block stk-38bb3f8\" data-block-id=\"38bb3f8\"><style>.stk-38bb3f8 .stk--svg-wrapper .stk--inner-svg svg:last-child{height:25px !important;width:25px !important;}.stk-38bb3f8 .stk--svg-wrapper .stk--inner-svg svg:last-child, .stk-38bb3f8 .stk--svg-wrapper .stk--inner-svg svg:last-child :is(g, path, rect, polygon, ellipse){fill:#f33f4e !important;}<\/style><span class=\"stk--svg-wrapper stk--has-icon2\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-38bb3f8\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-38-bb-3-f-8-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-38-bb-3-f-8-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M96 0C43 0 0 43 0 96V416c0 53 43 96 96 96H384h32c17.7 0 32-14.3 32-32s-14.3-32-32-32V384c17.7 0 32-14.3 32-32V32c0-17.7-14.3-32-32-32H384 96zm0 384H352v64H96c-17.7 0-32-14.3-32-32s14.3-32 32-32zm32-240c0-8.8 7.2-16 16-16H336c8.8 0 16 7.2 16 16s-7.2 16-16 16H144c-8.8 0-16-7.2-16-16zm16 48H336c8.8 0 16 7.2 16 16s-7.2 16-16 16H144c-8.8 0-16-7.2-16-16s7.2-16 16-16z\"><\/path><\/svg><\/div><div class=\"stk--inner-svg stk--icon-2\" style=\"display:none\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-38bb3f8\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-38-bb-3-f-8-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-38-bb-3-f-8-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 576 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M249.6 471.5c10.8 3.8 22.4-4.1 22.4-15.5V78.6c0-4.2-1.6-8.4-5-11C247.4 52 202.4 32 144 32C93.5 32 46.3 45.3 18.1 56.1C6.8 60.5 0 71.7 0 83.8V454.1c0 11.9 12.8 20.2 24.1 16.5C55.6 460.1 105.5 448 144 448c33.9 0 79 14 105.6 23.5zm76.8 0C353 462 398.1 448 432 448c38.5 0 88.4 12.1 119.9 22.6c11.3 3.8 24.1-4.6 24.1-16.5V83.8c0-12.1-6.8-23.3-18.1-27.6C529.7 45.3 482.5 32 432 32c-58.4 0-103.4 20-123 35.6c-3.3 2.6-5 6.8-5 11V456c0 11.4 11.7 19.3 22.4 15.5z\"><\/path><\/svg><\/div><\/span><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-a35761a\" id=\"criterios-de-admision\" data-block-id=\"a35761a\"><style>.stk-a35761a .stk-block-heading__text{color:#000000 !important;font-weight:500 !important;font-family:\"ArgentumSans\", Sans-serif !important;}<\/style><h4 class=\"stk-block-heading__text has-text-color\">Criterios de admisi\u00f3n<\/h4><\/div>\n<\/div><\/div>\n<\/div><\/div><\/summary>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-81ecc51 stk-block-accordion__content\" data-v=\"4\" data-block-id=\"81ecc51\"><style>.stk-81ecc51 {margin-top:-30px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-81ecc51-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-81ecc51-inner-blocks\">\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-7508b1a\" data-block-id=\"7508b1a\"><p class=\"stk-block-text__text\">Tal y como establece el art\u00edculo 6 del Reglamento de Doctorado de la ULL, la comisi\u00f3n acad\u00e9mica podr\u00e1 establecer criterios de selecci\u00f3n y admisi\u00f3n del alumnado. En el caso de este programa, se aplicar\u00e1 el siguiente baremo para la evaluaci\u00f3n de las solicitudes:<\/p><\/div>\n\n\n\n<p>a.&nbsp;Expediente acad\u00e9mico&nbsp;(40%)<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Grado o Licenciatura en Filosof\u00eda: hasta 2 puntos<\/li>\n\n\n\n<li>Grado o Licenciatura en \u00e1rea de Artes y Humanidades o Ciencias Sociales: hasta 1 punto<\/li>\n\n\n\n<li>M\u00e1ster en Filosof\u00eda: hasta 1 punto<\/li>\n\n\n\n<li>M\u00e1ster Interuniversitario en Investigaci\u00f3n en Filosof\u00eda de la ULL: 1 punto<\/li>\n<\/ul>\n\n\n\n<p>b.&nbsp;M\u00e9ritos de especial relevancia&nbsp;(60%)<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>M\u00e9ritos investigadores relacionados con Filosof\u00eda: hasta 3 puntos<\/li>\n\n\n\n<li>M\u00e9ritos de formaci\u00f3n relacionados con Filosof\u00eda: hasta 2 puntos<\/li>\n\n\n\n<li>M\u00e9ritos de divulgaci\u00f3n o de experiencia laboral relacionados con Filosof\u00eda: hasta 1 punto<\/li>\n<\/ul>\n\n\n\n<p><strong>\u00d3rganos encargados del proceso de admisi\u00f3n<\/strong><\/p>\n\n\n\n<p>El \u00f3rgano encargado del proceso de admisi\u00f3n es la Comisi\u00f3n Acad\u00e9mica del Programa de Doctorado en Filosof\u00eda de la Universidad de La Laguna.<\/p>\n<\/div><\/div><\/div>\n<\/details>\n\n\n\n<details class=\"wp-block-stackable-accordion stk-block-accordion stk-inner-blocks stk-block-content stk-block stk-9d40cce is-style-default\" id=\"complementos-de-formacion\" data-block-id=\"9d40cce\"><style>.stk-9d40cce {border-style:solid !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;}<\/style>\n<summary class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-ef7f17a stk--container-small stk-block-accordion__heading\" data-v=\"4\" data-block-id=\"ef7f17a\"><style>.stk-ef7f17a {padding-top:2px !important;padding-right:2px !important;padding-bottom:2px !important;padding-left:2px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-ef7f17a-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-ef7f17a-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-da3b93e\" data-block-id=\"da3b93e\"><style>.stk-da3b93e .stk-inner-blocks{gap:39px !important;}@media screen and (max-width: 1023px){.stk-da3b93e .stk-inner-blocks{gap:39px !important;}}@media screen and (max-width: 767px){.stk-da3b93e .stk-inner-blocks{gap:39px !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-icon stk-block-icon stk-block stk-8c84b2d\" data-block-id=\"8c84b2d\"><style>.stk-8c84b2d .stk--svg-wrapper .stk--inner-svg svg:last-child{height:25px !important;width:25px !important;}.stk-8c84b2d .stk--svg-wrapper .stk--inner-svg svg:last-child, .stk-8c84b2d .stk--svg-wrapper .stk--inner-svg svg:last-child :is(g, path, rect, polygon, ellipse){fill:#f33f4e !important;}<\/style><span class=\"stk--svg-wrapper stk--has-icon2\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-8c84b2d\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-8-c-84-b-2-d-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-8-c-84-b-2-d-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 384 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M64 0C28.7 0 0 28.7 0 64V448c0 35.3 28.7 64 64 64H320c35.3 0 64-28.7 64-64V160H256c-17.7 0-32-14.3-32-32V0H64zM256 0V128H384L256 0zM112 256H272c8.8 0 16 7.2 16 16s-7.2 16-16 16H112c-8.8 0-16-7.2-16-16s7.2-16 16-16zm0 64H272c8.8 0 16 7.2 16 16s-7.2 16-16 16H112c-8.8 0-16-7.2-16-16s7.2-16 16-16zm0 64H272c8.8 0 16 7.2 16 16s-7.2 16-16 16H112c-8.8 0-16-7.2-16-16s7.2-16 16-16z\"><\/path><\/svg><\/div><div class=\"stk--inner-svg stk--icon-2\" style=\"display:none\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-8c84b2d\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-8-c-84-b-2-d-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-8-c-84-b-2-d-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 384 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M64 464c-8.8 0-16-7.2-16-16V64c0-8.8 7.2-16 16-16H224v80c0 17.7 14.3 32 32 32h80V448c0 8.8-7.2 16-16 16H64zM64 0C28.7 0 0 28.7 0 64V448c0 35.3 28.7 64 64 64H320c35.3 0 64-28.7 64-64V154.5c0-17-6.7-33.3-18.7-45.3L274.7 18.7C262.7 6.7 246.5 0 229.5 0H64zm56 256c-13.3 0-24 10.7-24 24s10.7 24 24 24H264c13.3 0 24-10.7 24-24s-10.7-24-24-24H120zm0 96c-13.3 0-24 10.7-24 24s10.7 24 24 24H264c13.3 0 24-10.7 24-24s-10.7-24-24-24H120z\"><\/path><\/svg><\/div><\/span><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-d69e378\" id=\"complementos-de-formacion\" data-block-id=\"d69e378\"><style>.stk-d69e378 .stk-block-heading__text{color:#000000 !important;font-weight:500 !important;font-family:\"ArgentumSans\", Sans-serif !important;}<\/style><h4 class=\"stk-block-heading__text has-text-color\">Complementos de formaci\u00f3n<\/h4><\/div>\n<\/div><\/div>\n<\/div><\/div><\/summary>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-9404ebc stk-block-accordion__content\" data-v=\"4\" data-block-id=\"9404ebc\"><style>.stk-9404ebc {margin-top:-30px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-9404ebc-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-9404ebc-inner-blocks\">\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-22281da\" data-block-id=\"22281da\"><p class=\"stk-block-text__text\">El Reglamento de Doctorado de ULL establece que la admisi\u00f3n a los programas de doctorado podr\u00e1 incluir la exigencia de complementos de formaci\u00f3n espec\u00edficos, en consonancia con los perfiles de admisi\u00f3n establecidos para el programa de doctorado correspondiente. Dichos complementos de formaci\u00f3n espec\u00edficos tendr\u00e1n, a efectos de precios p\u00fablicos y de concesi\u00f3n de becas y ayudas al estudio, la consideraci\u00f3n de formaci\u00f3n de nivel de doctorado.<br>Por su car\u00e1cter transdisciplinar, el programa exige que las titulaciones de grado o m\u00e1ster que permitan el acceso no se limiten a Filosof\u00eda o Humanidades. Sin embargo, los diferentes perfiles exigen tener en cuenta las siguientes instrucciones:<\/p><\/div>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Podr\u00e1n acceder sin limitaciones al programa aquellos estudiantes que hayan realizado sus estudios de grado o m\u00e1ster en Filosof\u00eda o Humanidades en una universidad espa\u00f1ola, en centros del Espacio Europeo de Educaci\u00f3n Superior o en otra que tengan estudios equivalentes, previo reconocimiento por parte de la Comisi\u00f3n Acad\u00e9mica de Doctorado.<\/li>\n\n\n\n<li>Las personas que accedan al Programa desde el M\u00e1ster en Formaci\u00f3n del Profesorado de Educaci\u00f3n Secundaria Obligatoria y Bachillerato, Formaci\u00f3n Profesional y Ense\u00f1anza de Idiomas deber\u00e1n realizar un trabajo equivalente a los trabajos fin de m\u00e1ster que se ofertan en los M\u00e1steres Universitarios en Filosof\u00eda que ofertan las diferentes universidades integrantes del programa. El trabajo podr\u00e1 ser dirigido por la misma persona que la tesis doctoral y ser\u00e1 defendido previamente a la lectura y defensa de esta, conforme a la normativa. No obstante, podr\u00e1n acceder directamente al programa de doctorado quienes habiendo cursado el M\u00e1ster de Profesorado en Secundaria (especialidad de Filosof\u00eda) deseen realizar su doctorado en la l\u00ednea de investigaci\u00f3n de Did\u00e1ctica de la Filosof\u00eda o \u00c9tica y docencia.<\/li>\n\n\n\n<li>Las personas que accedan al programa sin haber cursado un Grado o M\u00e1ster de investigaci\u00f3n en Filosof\u00eda o Humanidades deber\u00e1n mostrar que la tesis doctoral que se pretende realizar es coherente con la formaci\u00f3n acad\u00e9mica e investigadora recibida. Si la Comisi\u00f3n Acad\u00e9mica apreciara incoherencia, se le exigir\u00eda un complemento formativo adecuado, que puede consistir en cursar durante el primer a\u00f1o determinadas materias de los m\u00e1steres ofertados por las universidades que participan en el programa y que, en todo caso, implicar\u00e1 la realizaci\u00f3n y defensa en el primer a\u00f1o de Doctorado un trabajo fin de m\u00e1ster (TFM). La tutela de estos trabajos ser\u00e1 ejercida por la persona que dirija la tesis.<\/li>\n<\/ol>\n<\/div><\/div><\/div>\n<\/details>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-53ec762\" data-v=\"4\" data-block-id=\"53ec762\"><style>.stk-53ec762-inner-blocks{row-gap:0px !important;}.stk-53ec762 {padding-top:0px !important;padding-right:0px !important;padding-bottom:0px !important;padding-left:0px !important;}@media screen and (min-width: 768px){.stk-53ec762 {flex:var(--stk-flex-grow, 1) 1 33.3% !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-53ec762-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-53ec762-inner-blocks\">\n\n<ul class=\"widget-box\">\n<li class='contacto-header'>Informaci\u00f3n de contacto<\/li><li><i class=\"fa fa-map-marker\"><\/i> Avda. Astrof\u00edsico Francisco S\u00e1nchez, SN. Edificio Calabaza \u2013 AN.2D Apdo. 456 38200 San Crist\u00f3bal de La Laguna<\/li><li><i class=\"fa fa-envelope\"><\/i>  <a href=mailto:doctorado.filosofia@ull.es>doctorado.filosofia@ull.es<\/a><\/li><li><i class=\"fa fa-calendar\"><\/i><a href=\"http:\/\/citaprevia.ull.es\/index.php?s=edpo\"> Cita previa<\/a><\/li>\n<\/ul>\n\n\n<\/div><\/div><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Syst\u00e8mes d&#039;information d&#039;acc\u00e8s et d&#039;admission Phase de pr\u00e9inscription Les informations destin\u00e9es aux personnes potentiellement int\u00e9ress\u00e9es concernant les caract\u00e9ristiques du programme, les crit\u00e8res d&#039;acc\u00e8s et d&#039;admission, ainsi que la proc\u00e9dure administrative d&#039;admission et d&#039;inscription, seront fournies par les voies habituelles et dans le cadre des programmes doctoraux propos\u00e9s :\u2026<\/p>","protected":false},"author":1,"featured_media":0,"parent":17,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/template-frontpage.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-76","page","type-page","status-publish","hentry"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 05:36:30","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.ull.es\/doctorados\/filosofia\/fr\/wp-json\/wp\/v2\/pages\/76","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ull.es\/doctorados\/filosofia\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ull.es\/doctorados\/filosofia\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ull.es\/doctorados\/filosofia\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ull.es\/doctorados\/filosofia\/fr\/wp-json\/wp\/v2\/comments?post=76"}],"version-history":[{"count":16,"href":"https:\/\/www.ull.es\/doctorados\/filosofia\/fr\/wp-json\/wp\/v2\/pages\/76\/revisions"}],"predecessor-version":[{"id":364,"href":"https:\/\/www.ull.es\/doctorados\/filosofia\/fr\/wp-json\/wp\/v2\/pages\/76\/revisions\/364"}],"up":[{"embeddable":true,"href":"https:\/\/www.ull.es\/doctorados\/filosofia\/fr\/wp-json\/wp\/v2\/pages\/17"}],"wp:attachment":[{"href":"https:\/\/www.ull.es\/doctorados\/filosofia\/fr\/wp-json\/wp\/v2\/media?parent=76"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}