{"id":72,"date":"2018-02-22T13:28:20","date_gmt":"2018-02-22T13:28:20","guid":{"rendered":"http:\/\/www.ull.es\/doctorados\/filosofia\/?page_id=72"},"modified":"2026-07-26T18:26:00","modified_gmt":"2026-07-26T18:26:00","slug":"seguimiento-doctorando","status":"publish","type":"page","link":"https:\/\/www.ull.es\/doctorados\/filosofia\/organizacion-del-programa\/seguimiento-doctorando\/","title":{"rendered":"Seguimiento del doctorando"},"content":{"rendered":"\n<div class=\"wp-block-stackable-columns alignfull stk-block-columns stk-block stk-2314a6b\" data-block-id=\"2314a6b\"><style>.stk-2314a6b {padding-bottom:0px !important;margin-top:-100px !important;margin-bottom:0px !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-2314a6b-column alignfull\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-1d1764d\" data-v=\"4\" data-block-id=\"1d1764d\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-1d1764d-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-1d1764d-inner-blocks\"><style id=\"depicter-1-inline-pre-css\">\n\n.depicter-1:not(.depicter-ready){\n\theight:450px;\n}\n\n\/***** Tablet *****\/\n@media screen and (max-width: 1024px){\n\n.depicter-1:not(.depicter-ready){\n\theight:700px;\n}\n\n}\n\/***** Mobile *****\/\n@media screen and (max-width: 767px){\n\n.depicter-1:not(.depicter-ready){\n\theight:360px;\n}\n\n}\n<\/style>\n<div id=\"depicter-1\" class=\"depicter depicter-document depicter-revert depicter-1 depicter-layout-fullwidth\">\n\n<div class=\"depicter-loading-container depicter-loading dotFlashing-dark\"><div class=\"depicter-loading-dark depicter-dot-flashing\">\n   <span><\/span>\n   <span><\/span>\n   <span><\/span>\n<\/div>\n<\/div>\n<div id=\"depicter-1-section-1\" class=\"depicter-section depicter-1-section-1\" data-name=\"Section 1\" data-type=\"section\" data-local-id=\"section-1\">\n<picture class=\"depicter-bg\">\n<source data-depicter-srcset=\"https:\/\/www.ull.es\/doctorados\/filosofia\/wp-content\/uploads\/sites\/16\/2025\/05\/Headers-Doctorados_Doctorado-Filosofia-768x248.jpg, https:\/\/www.ull.es\/doctorados\/filosofia\/wp-content\/uploads\/sites\/16\/2025\/05\/Headers-Doctorados_Doctorado-Filosofia.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(max-width: 1024px)\" \/>\n\n<source data-depicter-srcset=\"https:\/\/www.ull.es\/doctorados\/filosofia\/wp-content\/uploads\/sites\/16\/2025\/05\/Headers-Doctorados_Doctorado-Filosofia.jpg, https:\/\/www.ull.es\/doctorados\/filosofia\/wp-content\/uploads\/sites\/16\/2025\/05\/Headers-Doctorados_Doctorado-Filosofia-2000x645.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(min-width: 1025px)\" \/>\n<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-ken-burns=\"false\" data-tablet-ken-burns=\"false\" data-mobile-ken-burns=\"false\" alt=\"\" data-depicter-src=\"https:\/\/www.ull.es\/doctorados\/filosofia\/wp-content\/uploads\/sites\/16\/2025\/05\/Headers-Doctorados_Doctorado-Filosofia.jpg\" data-object-fit=\"cover,custom,\" data-object-position=\"center top,,\" data-crop=\"{&apos;focalPoint&apos;:{&apos;x&apos;:0.5,&apos;y&apos;:0.409999999999999975575093458246556110680103302001953125},&apos;mediaSize&apos;:{&apos;width&apos;:1791,&apos;height&apos;:577}}\" data-tablet-crop=\"{&apos;focalPoint&apos;:{&apos;x&apos;:0.6999999999999999555910790149937383830547332763671875,&apos;y&apos;:0.5},&apos;mediaSize&apos;:{&apos;width&apos;:2170,&apos;height&apos;:700}}\" data-mobile-crop=\"{&apos;focalPoint&apos;:{&apos;x&apos;:0.82999999999999996003197111349436454474925994873046875,&apos;y&apos;:0.330000000000000015543122344752191565930843353271484375},&apos;mediaSize&apos;:{&apos;width&apos;:2294,&apos;height&apos;:740}}\" \/>\n<\/picture>\n\n\n<h1 id=\"depicter-1-element-5\" class=\"depicter-element depicter-layer depicter-1-element-5\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 2\" data-local-id=\"element-5\" data-offset=\"x:0px;y:138px;origin:tl\" data-tablet-offset=\"x:176px;y:206px;origin:tl\" data-mobile-offset=\"x:39px;y:139px;origin:tl\" data-width=\"1200px,auto,348px\" data-height=\"auto,auto,auto\" data-responsive-scale=\"true,,\">Programa de Doctorado en Filosof\u00eda<\/h1>\n\n<div id=\"depicter-1-element-10\" class=\"depicter-element depicter-layer depicter-1-element-10\" data-type=\"shape\" data-wrap=\"true\" data-name=\"Shape 1\" data-local-id=\"element-10\" data-offset=\"x:0px;y:311px;origin:tl\" data-tablet-offset=\"x:215px;y:361px;origin:tl\" data-mobile-offset=\"x:39px;y:293px;origin:tl\" data-width=\"983px,647px,282px\" data-height=\"8px,8px,8px\" data-responsive-scale=\"true,,\"><\/div>\n<\/div>\n<\/div>\n<script>\n(window.depicterSetups = window.depicterSetups || []).push(function(){\n\tDepicter.basePath = 'https:\/\/www.ull.es\/doctorados\/filosofia\/wp-content\/plugins\/depicter\/resources\/scripts\/player\/';\n\tconst dpPlayer = Depicter.setup('.depicter-1',\n\t\t{\"width\":[\"1200\",\"1024\",\"360\"],\"height\":[\"450\",\"700\",\"360\"],\"view\":\"basic\",\"keepAspectRatio\":true,\"preload\":0,\"layout\":\"fullwidth\",\"rtl\":false,\"initAfterAppear\":false,\"ajaxApiUrl\":\"https:\\\/\\\/www.ull.es\\\/doctorados\\\/filosofia\\\/wp-admin\\\/admin-ajax.php\",\"mouseSwipe\":true,\"touchSwipe\":true,\"useWatermark\":false}\n\t);\n});\n<\/script><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns alignfull stk-block-columns stk--hide-mobile stk-block stk-6394276 stk-block-background\" data-block-id=\"6394276\"><style>.stk-6394276 {background-color:#f33f4e !important;padding-top:10px !important;margin-bottom:0px !important;}.stk-6394276:before{background-color:#f33f4e !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-6394276-column alignfull\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-8a66885\" data-v=\"4\" data-block-id=\"8a66885\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-8a66885-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-8a66885-inner-blocks\">\n<div class=\"wp-block-stackable-spacer stk-block-spacer stk--no-padding stk-block stk-bc89b3e\" data-block-id=\"bc89b3e\"><style>.stk-bc89b3e {height:0px !important;}<\/style><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns stk-block-columns stk-block stk-8b59b96\" data-block-id=\"8b59b96\"><style>.stk-8b59b96 .stk--block-align-8b59b96{align-items:flex-start !important;}.stk-8b59b96 {margin-top:50px !important;}.stk-8b59b96-column{--stk-columns-spacing:0px !important;--stk-column-gap:50px !important;}<\/style><div class=\"stk-row stk-inner-blocks stk--block-align-8b59b96 stk-block-content stk-content-align stk-8b59b96-column\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-dbb7e15\" data-v=\"4\" data-block-id=\"dbb7e15\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-dbb7e15-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-dbb7e15-inner-blocks\">\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-cc0239e\" id=\"complementos-de-formacion\" data-block-id=\"cc0239e\"><style>.stk-cc0239e .stk-block-heading__text{color:#000000 !important;font-weight:500 !important;}<\/style><h1 class=\"stk-block-heading__text has-text-color\">Seguimiento del doctorando<\/h1><\/div>\n\n\n\n<p class=\"wp-block-hidden-desktop wp-block-hidden-mobile wp-block-hidden-tablet wp-block-paragraph\"><strong>Direcci\u00f3n y tutela<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Siguiendo las directrices marcadas por el art\u00edculo 11 del Real Decreto 99\/2011, de 28 de enero, por el que se regulan las ense\u00f1anzas oficiales de doctorado y por lo expuesto en el Reglamento de Ense\u00f1anzas Oficiales de Doctorado de la Universidad de La Laguna, la supervisi\u00f3n de tesis y el seguimiento de cada doctorando se implementar\u00e1 atendiendo a las siguientes consideraciones:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Cada doctorando admitido en el programa se matricular\u00e1 anualmente en concepto de tutor\u00eda acad\u00e9mica.<\/li>\n\n\n\n<li>A cada doctorando se le asignar\u00e1 un tutor y, al menos, un director por parte de la comisi\u00f3n acad\u00e9mica del programa. El tutor velar\u00e1 por la interacci\u00f3n del doctorando con el programa. Estas asignaciones podr\u00e1n ser modificadas por la comisi\u00f3n en cualquier momento, una vez o\u00eddo el doctorando, si concurren causas justificadas. Esa solicitud deber\u00e1 hacerse por el <a href=\"https:\/\/sede.ull.es\/ecivilis-site\/catalog\/showProcedure\/298\" target=\"_blank\" rel=\"noopener\">procedimiento electr\u00f3nico<\/a> habilitado al efecto.<\/li>\n\n\n\n<li>Antes de la finalizaci\u00f3n del primer a\u00f1o deber\u00e1 elaborarse un plan de investigaci\u00f3n que incluir\u00e1, al menos, la metodolog\u00eda que se va a utilizar y los objetivos que se pretenden alcanzar, as\u00ed como los medios y la planificaci\u00f3n temporal para lograrlos. Dicho plan se podr\u00e1 mejorar y detallar a lo largo de su estancia en el programa.<\/li>\n\n\n\n<li>Adicionalmente, y tambi\u00e9n antes de la finalizaci\u00f3n del primer a\u00f1o, deber\u00e1 elaborar un plan de formaci\u00f3n personal que contendr\u00e1 la previsi\u00f3n de las distintas actividades formativas que se prev\u00e9 que se vayan a desarrollar durante el per\u00edodo de realizaci\u00f3n de la tesis doctoral. Dicho documento se podr\u00e1 mejorar y ampliar a lo largo de la estancia en el programa de doctorado. Este documento ser\u00e1 regularmente revisado por el tutor y los directores de tesis.<\/li>\n\n\n\n<li>Anualmente la comisi\u00f3n acad\u00e9mica del programa evaluar\u00e1 el desarrollo del plan de investigaci\u00f3n, el plan de formaci\u00f3n personal y el documento de registro de las diversas actividades hechas durante el curso, junto con los informes que, a tal efecto, deben emitir tutores y directores.<\/li>\n\n\n\n<li>La evaluaci\u00f3n positiva ser\u00e1 requisito indispensable para continuar en el programa. En caso de evaluaci\u00f3n negativa, la comisi\u00f3n acad\u00e9mica emitir\u00e1 un informe motiv\u00e1ndola, en el que se propondr\u00e1n las medidas correctoras oportunas de cara a la siguiente evaluaci\u00f3n. En el caso de evaluaci\u00f3n negativa, el doctorando deber\u00e1 ser de nuevo evaluado en el plazo de seis meses. En el supuesto de producirse una nueva evaluaci\u00f3n negativa, el doctorando causar\u00e1 baja definitiva en el programa, seg\u00fan lo dispuesto en la Normativa de Dedicaci\u00f3n y Permanencia en los estudios de doctorado de la ULL.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-hidden-desktop wp-block-hidden-mobile wp-block-hidden-tablet wp-block-paragraph\"><strong>Registro y valoraci\u00f3n de actividades<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De lo expuesto se puede asegurar que existe una trazabilidad completa de la actividad desarrollada por el doctorando, supervisada por el director de tesis y la comisi\u00f3n acad\u00e9mica, adem\u00e1s de por la EDEP, pues queda todo ello registrado en la aplicaci\u00f3n inform\u00e1tica creada a tal fin, bajo la denominaci\u00f3n Registro de Actividades y Plan de Investigaci\u00f3n (RAPI).<\/p>\n\n\n\n<p class=\"wp-block-hidden-desktop wp-block-hidden-mobile wp-block-hidden-tablet wp-block-paragraph\"><strong>Documentos de compromiso<\/strong>De lo expuesto se puede asegurar que existe una trazabilidad completa de la actividad desarrollada por el doctorando, supervisada por el director de tesis y la comisi\u00f3n acad\u00e9mica, adem\u00e1s de por la EDEP, pues queda todo ello registrado en la aplicaci\u00f3n inform\u00e1tica creada a tal fin, bajo la denominaci\u00f3n Registro de Actividades y Plan de Investigaci\u00f3n (RAPI).<\/p>\n\n\n\n<p class=\"wp-block-hidden-desktop wp-block-hidden-mobile wp-block-hidden-tablet wp-block-paragraph\"><strong>Procedimiento de resoluci\u00f3n de conflictos<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Comisi\u00f3n acad\u00e9mica<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El programa de doctorado cuenta con una comisi\u00f3n acad\u00e9mica cuyos miembros tienen dilatada experiencia en materia investigadora y que cumplen con los requisitos del Reglamento de Ense\u00f1anzas Oficiales de Doctorado de la Universidad de La Laguna.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Documento de compromiso y buenas pr\u00e1cticas en la investigaci\u00f3n<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las funciones de supervisi\u00f3n de se establecer\u00e1n mediante un compromiso documental, en modelo normalizado establecido por la EDEP, firmado el estudiante de doctorado, y las personas responsables de la direcci\u00f3n y tutorizaci\u00f3n. El compromiso debe ser firmado a la mayor brevedad posible despu\u00e9s de la admisi\u00f3n y matr\u00edcula y, en todo caso, en el plazo m\u00e1ximo de seis meses desde la asignaci\u00f3n de tutor o tutora y de director o directora de tesis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>El documento de compromiso, una vez suscrito por los intervinientes, ser\u00e1 archivado en el expediente del estudiante.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-53ec762\" data-v=\"4\" data-block-id=\"53ec762\"><style>.stk-53ec762-inner-blocks{row-gap:0px !important;}.stk-53ec762 {padding-top:0px !important;padding-right:0px !important;padding-bottom:0px !important;padding-left:0px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-53ec762-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-53ec762-inner-blocks\">\n\n<ul class=\"widget-box\">\n<li class='contacto-header'>Informaci\u00f3n de contacto<\/li><li><i class=\"fa fa-map-marker\"><\/i> Avda. Astrof\u00edsico Francisco S\u00e1nchez, SN. Edificio Calabaza \u2013 AN.2D Apdo. 456 38200 San Crist\u00f3bal de La Laguna<\/li><li><i class=\"fa fa-envelope\"><\/i>  <a href=mailto:doctorado.filosofia@ull.es>doctorado.filosofia@ull.es<\/a><\/li><li><i class=\"fa fa-calendar\"><\/i><a href=\"http:\/\/citaprevia.ull.es\/index.php?s=edpo\"> Cita previa<\/a><\/li>\n<\/ul>\n\n\n<\/div><\/div><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Seguimiento del doctorando Direcci\u00f3n y tutela Siguiendo las directrices marcadas por el art\u00edculo 11 del Real Decreto 99\/2011, de 28 de enero, por el que se regulan las ense\u00f1anzas oficiales de doctorado y por lo expuesto en el Reglamento de Ense\u00f1anzas Oficiales de Doctorado de la Universidad de La Laguna, la supervisi\u00f3n de tesis y&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":27,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/template-frontpage.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-72","page","type-page","status-publish","hentry"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 09:50:53","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.ull.es\/doctorados\/filosofia\/wp-json\/wp\/v2\/pages\/72","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ull.es\/doctorados\/filosofia\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ull.es\/doctorados\/filosofia\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ull.es\/doctorados\/filosofia\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ull.es\/doctorados\/filosofia\/wp-json\/wp\/v2\/comments?post=72"}],"version-history":[{"count":11,"href":"https:\/\/www.ull.es\/doctorados\/filosofia\/wp-json\/wp\/v2\/pages\/72\/revisions"}],"predecessor-version":[{"id":407,"href":"https:\/\/www.ull.es\/doctorados\/filosofia\/wp-json\/wp\/v2\/pages\/72\/revisions\/407"}],"up":[{"embeddable":true,"href":"https:\/\/www.ull.es\/doctorados\/filosofia\/wp-json\/wp\/v2\/pages\/27"}],"wp:attachment":[{"href":"https:\/\/www.ull.es\/doctorados\/filosofia\/wp-json\/wp\/v2\/media?parent=72"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}