{"id":32,"date":"2018-04-10T08:32:40","date_gmt":"2018-04-10T08:32:40","guid":{"rendered":"http:\/\/www.ull.es\/doctorados\/?page_id=32"},"modified":"2026-07-03T10:27:17","modified_gmt":"2026-07-03T10:27:17","slug":"acceso-y-admision","status":"publish","type":"page","link":"https:\/\/www.ull.es\/doctorados\/fr\/acceso-y-admision\/","title":{"rendered":"Crit\u00e8res d&#039;acc\u00e8s et d&#039;admission"},"content":{"rendered":"\n<div class=\"wp-block-stackable-columns alignfull stk-block-columns stk-block stk-2314a6b\" data-block-id=\"2314a6b\"><style>.stk-2314a6b {padding-bottom:0px !important;margin-top:-30px !important;margin-bottom:0px !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-2314a6b-column alignfull\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-1d1764d\" data-v=\"4\" data-block-id=\"1d1764d\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-1d1764d-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-1d1764d-inner-blocks\"><style id=\"depicter-14-inline-pre-css\">\n\n.depicter-14:not(.depicter-ready){\n\theight:500px;\n}\n\n\/***** Tablet *****\/\n@media screen and (max-width: 1024px){\n\n.depicter-14:not(.depicter-ready){\n\theight:700px;\n}\n\n}\n\/***** Mobile *****\/\n@media screen and (max-width: 767px){\n\n.depicter-14:not(.depicter-ready){\n\theight:360px;\n}\n\n}\n<\/style>\n<div id=\"depicter-14\" class=\"depicter depicter-document depicter-revert depicter-14 depicter-layout-fullwidth\">\n\n<div class=\"depicter-loading-container depicter-loading dotFlashing-dark\"><div class=\"depicter-loading-dark depicter-dot-flashing\">\n   <span><\/span>\n   <span><\/span>\n   <span><\/span>\n<\/div>\n<\/div>\n<div id=\"depicter-14-section-1\" class=\"depicter-section depicter-14-section-1\" data-name=\"Section 1\" data-type=\"section\" data-local-id=\"section-1\">\n<picture class=\"depicter-bg\">\n<source data-depicter-srcset=\"https:\/\/www.ull.es\/doctorados\/wp-content\/uploads\/2026\/03\/mobile-1-7047.jpg, https:\/\/www.ull.es\/doctorados\/wp-content\/uploads\/2026\/03\/mobile-1-7047-1000x1100.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(max-width: 767px)\" \/>\n\n<source data-depicter-srcset=\"https:\/\/www.ull.es\/doctorados\/wp-content\/uploads\/2026\/03\/mobile-3.jpg, https:\/\/www.ull.es\/doctorados\/wp-content\/uploads\/2026\/03\/mobile-3-1000x1100.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(max-width: 1024px)\" \/>\n\n<source data-depicter-srcset=\"https:\/\/www.ull.es\/doctorados\/wp-content\/uploads\/2026\/03\/web-4.jpg, https:\/\/www.ull.es\/doctorados\/wp-content\/uploads\/2026\/03\/web-4-1920x600.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(min-width: 1025px)\" \/>\n<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-ken-burns=\"{&apos;scale&apos;:1,&apos;duration&apos;:&apos;5000&apos;,&apos;focalPoint&apos;:{&apos;x&apos;:0.5,&apos;y&apos;:0.38000000000000000444089209850062616169452667236328125},&apos;easing&apos;:&apos;linear&apos;}\" data-tablet-ken-burns=\"{&apos;scale&apos;:0.75,&apos;duration&apos;:0,&apos;focalPoint&apos;:{&apos;x&apos;:0.5,&apos;y&apos;:0.38000000000000000444089209850062616169452667236328125},&apos;easing&apos;:&apos;linear&apos;}\" data-mobile-ken-burns=\"{&apos;scale&apos;:1,&apos;duration&apos;:0,&apos;focalPoint&apos;:{&apos;x&apos;:0.5,&apos;y&apos;:0.38000000000000000444089209850062616169452667236328125},&apos;easing&apos;:&apos;linear&apos;}\" alt=\"\" data-depicter-src=\"https:\/\/www.ull.es\/doctorados\/wp-content\/uploads\/2026\/03\/web-4.jpg\" data-object-fit=\"cover,custom,custom\" data-object-position=\",,center center\" data-crop=\"{&apos;focalPoint&apos;:{&apos;x&apos;:0.5,&apos;y&apos;:0.5},&apos;mediaSize&apos;:{&apos;width&apos;:1280,&apos;height&apos;:400}}\" data-tablet-crop=\"{&apos;focalPoint&apos;:{&apos;x&apos;:0.5,&apos;y&apos;:0.5},&apos;mediaSize&apos;:{&apos;width&apos;:1024,&apos;height&apos;:1126.40000000000009094947017729282379150390625}}\" data-mobile-crop=\"{&apos;focalPoint&apos;:{&apos;x&apos;:0.5,&apos;y&apos;:0.38000000000000000444089209850062616169452667236328125},&apos;mediaSize&apos;:{&apos;width&apos;:767,&apos;height&apos;:843}}\" \/>\n<\/picture>\n\n\n<picture id=\"depicter-14-element-19\" class=\"depicter-element depicter-layer depicter-14-element-19\" data-type=\"image\" data-wrap=\"true\" data-name=\"Image 12\" data-local-id=\"element-19\" data-offset=\"x:-192px;y:-373px;origin:tl\" data-tablet-offset=\"x:-299px;y:-254px;origin:tl\" data-mobile-offset=\"x:-22px;y:-30px;origin:tl\" data-width=\"262px,262px,403px\" data-height=\"288px,288px,442px\" data-responsive-scale=\"true,,\" data-crop=\"false\">\n<source data-depicter-srcset=\"https:\/\/www.ull.es\/doctorados\/wp-content\/uploads\/2026\/03\/mobile-3-403x442.jpg, https:\/\/www.ull.es\/doctorados\/wp-content\/uploads\/2026\/03\/mobile-3-806x884.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(max-width: 767px)\" \/>\n\n<source data-depicter-srcset=\"https:\/\/www.ull.es\/doctorados\/wp-content\/uploads\/2026\/03\/mobile-3-262x288.jpg, https:\/\/www.ull.es\/doctorados\/wp-content\/uploads\/2026\/03\/mobile-3-524x576.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(min-width: 768px)\" \/>\n<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-depicter-src=\"https:\/\/www.ull.es\/doctorados\/wp-content\/uploads\/2026\/03\/mobile-3-262x288.jpg\" alt=\"\" \/>\n<\/picture>\n<h2 id=\"depicter-14-element-15\" class=\"depicter-element depicter-layer depicter-14-element-15\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 3\" data-local-id=\"element-15\" data-offset=\"x:390px;y:202px;origin:tl\" data-tablet-offset=\"x:59px;y:308px;origin:tl\" data-mobile-offset=\"x:0px;y:173px;origin:tl\" data-width=\"421px,906px,360px\" data-height=\"auto,auto,auto\" data-responsive-scale=\"true,,\">Doctorados<br><\/h2>\n\n<div id=\"depicter-14-element-16\" class=\"depicter-element depicter-layer depicter-14-element-16\" data-type=\"shape\" data-wrap=\"true\" data-name=\"Shape 1\" data-local-id=\"element-16\" data-offset=\"x:390px;y:304px;origin:tl\" data-tablet-offset=\"x:364px;y:398px;origin:tl\" data-mobile-offset=\"x:96px;y:209px;origin:tl\" data-width=\"405px,297px,172px\" data-height=\"8px,8px,8px\" data-responsive-scale=\"true,,\"><\/div>\n<\/div>\n<\/div>\n<script>\n(window.depicterSetups = window.depicterSetups || []).push(function(){\n\tDepicter.basePath = 'https:\/\/www.ull.es\/doctorados\/wp-content\/plugins\/depicter\/resources\/scripts\/player\/';\n\tconst dpPlayer = Depicter.setup('.depicter-14',\n\t\t{\"width\":[\"1200\",\"1024\",\"360\"],\"height\":[\"500\",\"700\",\"360\"],\"view\":\"basic\",\"keepAspectRatio\":true,\"preload\":0,\"layout\":\"fullwidth\",\"rtl\":false,\"initAfterAppear\":false,\"ajaxApiUrl\":\"https:\\\/\\\/www.ull.es\\\/doctorados\\\/wp-admin\\\/admin-ajax.php\",\"mouseSwipe\":true,\"touchSwipe\":true,\"useWatermark\":false}\n\t);\n});\n<\/script><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading alignfull stk-block-heading stk--hide-mobile stk-block-heading--v2 stk-block stk-67e3263 stk-block-background\" id=\"oferta-de-doctorados-universitarios-curso-2026-2027\" data-block-id=\"67e3263\"><style>.stk-67e3263 {background-color:#f33f4e !important;padding-top:35px !important;padding-bottom:35px !important;margin-top:-40px !important;margin-bottom:41px !important;}.stk-67e3263:before{background-color:#f33f4e !important;}.stk-67e3263 .stk-block-heading__text{font-size:20px !important;color:#ffffff !important;font-weight:500 !important;font-family:\"ArgentumSans\", Sans-serif !important;}@media screen and (max-width: 1023px){.stk-67e3263 .stk-block-heading__text{font-size:20px !important;}}<\/style><h2 class=\"stk-block-heading__text has-text-color has-text-align-center\">OFERTA DE DOCTORADOS UNIVERSITARIOS CURSO 2026-2027<\/h2><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns alignwide stk-block-columns stk-block stk-6d3c23a\" data-block-id=\"6d3c23a\"><style>.stk-6d3c23a {padding-right:5% !important;padding-left:5% !important;}.stk-6d3c23a-column{--stk-column-gap:35px !important;}@media screen and (max-width: 767px){.stk-6d3c23a {padding-right:0px !important;padding-left:0px !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-6d3c23a-column alignwide\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-c85aebf\" data-v=\"4\" data-block-id=\"c85aebf\"><style>@media screen and (min-width: 768px){.stk-c85aebf {flex:var(--stk-flex-grow, 1) 1 66.7% !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-c85aebf-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-c85aebf-inner-blocks\">\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-37ecbc0\" id=\"criterios-de-acceso-y-admision\" data-block-id=\"37ecbc0\"><style>.stk-37ecbc0 {margin-bottom:40px !important;}.stk-37ecbc0 .stk-block-heading__text{color:#000000 !important;font-weight:700 !important;}<\/style><h1 class=\"stk-block-heading__text has-text-color has-text-align-center-mobile\">Criterios de Acceso y Admisi\u00f3n<\/h1><\/div>\n\n\n\n<details class=\"wp-block-stackable-accordion stk-block-accordion stk-inner-blocks stk-block-content stk-block stk-d25072d is-style-default\" id=\"generales\" data-block-id=\"d25072d\"><style>.stk-d25072d {margin-bottom:15px !important;}<\/style>\n<summary class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-892c21e stk--container-small stk-block-accordion__heading\" data-v=\"4\" data-block-id=\"892c21e\"><style>.stk-892c21e {border-style:solid !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-892c21e-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-892c21e-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-956ee49\" data-block-id=\"956ee49\"><style>.stk-956ee49 .stk-inner-blocks{gap:40px !important;}@media screen and (max-width: 1023px){.stk-956ee49 .stk-inner-blocks{gap:40px !important;}}@media screen and (max-width: 767px){.stk-956ee49 .stk-inner-blocks{gap:40px !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-icon stk-block-icon stk-block stk-693af38\" data-block-id=\"693af38\"><style>.stk-693af38 .stk--svg-wrapper .stk--inner-svg svg:last-child{height:24px !important;width:24px !important;}.stk-693af38 .stk--svg-wrapper .stk--inner-svg svg:last-child, .stk-693af38 .stk--svg-wrapper .stk--inner-svg svg:last-child :is(g, path, rect, polygon, ellipse){fill:#f33f4e !important;}<\/style><span class=\"stk--svg-wrapper stk--has-icon2\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-693af38\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-693-af-38-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-693-af-38-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 640 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M320 32c-8.1 0-16.1 1.4-23.7 4.1L15.8 137.4C6.3 140.9 0 149.9 0 160s6.3 19.1 15.8 22.6l57.9 20.9C57.3 229.3 48 259.8 48 291.9v28.1c0 28.4-10.8 57.7-22.3 80.8c-6.5 13-13.9 25.8-22.5 37.6C0 442.7-.9 448.3 .9 453.4s6 8.9 11.2 10.2l64 16c4.2 1.1 8.7 .3 12.4-2s6.3-6.1 7.1-10.4c8.6-42.8 4.3-81.2-2.1-108.7C90.3 344.3 86 329.8 80 316.5V291.9c0-30.2 10.2-58.7 27.9-81.5c12.9-15.5 29.6-28 49.2-35.7l157-61.7c8.2-3.2 17.5 .8 20.7 9s-.8 17.5-9 20.7l-157 61.7c-12.4 4.9-23.3 12.4-32.2 21.6l159.6 57.6c7.6 2.7 15.6 4.1 23.7 4.1s16.1-1.4 23.7-4.1L624.2 182.6c9.5-3.4 15.8-12.5 15.8-22.6s-6.3-19.1-15.8-22.6L343.7 36.1C336.1 33.4 328.1 32 320 32zM128 408c0 35.3 86 72 192 72s192-36.7 192-72L496.7 262.6 354.5 314c-11.1 4-22.8 6-34.5 6s-23.5-2-34.5-6L143.3 262.6 128 408z\" \/><\/svg><\/div><div class=\"stk--inner-svg stk--icon-2\" style=\"display:none\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-693af38\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-693-af-38-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-693-af-38-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M219.3 .5c3.1-.6 6.3-.6 9.4 0l200 40C439.9 42.7 448 52.6 448 64s-8.1 21.3-19.3 23.5L352 102.9V160c0 70.7-57.3 128-128 128s-128-57.3-128-128V102.9L48 93.3v65.1l15.7 78.4c.9 4.7-.3 9.6-3.3 13.3s-7.6 5.9-12.4 5.9H16c-4.8 0-9.3-2.1-12.4-5.9s-4.3-8.6-3.3-13.3L16 158.4V86.6C6.5 83.3 0 74.3 0 64C0 52.6 8.1 42.7 19.3 40.5l200-40zM111.9 327.7c10.5-3.4 21.8 .4 29.4 8.5l71 75.5c6.3 6.7 17 6.7 23.3 0l71-75.5c7.6-8.1 18.9-11.9 29.4-8.5C401 348.6 448 409.4 448 481.3c0 17-13.8 30.7-30.7 30.7H30.7C13.8 512 0 498.2 0 481.3c0-71.9 47-132.7 111.9-153.6z\" \/><\/svg><\/div><\/span><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-6c2fa1d\" id=\"criterios-generales\" data-block-id=\"6c2fa1d\"><style>.stk-6c2fa1d .stk-block-heading__text{font-size:18px !important;font-weight:700 !important;font-family:\"Montserrat\", Sans-serif !important;}@media screen and (max-width: 1023px){.stk-6c2fa1d .stk-block-heading__text{font-size:18px !important;}}<\/style><p class=\"stk-block-heading__text\">Criterios generales<\/p><\/div>\n<\/div><\/div>\n<\/div><\/div><\/summary>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-4f2fad4 stk-block-accordion__content\" data-v=\"4\" data-block-id=\"4f2fad4\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-4f2fad4-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-4f2fad4-inner-blocks\">\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-6b4057d\" data-block-id=\"6b4057d\"><style>.stk-6b4057d .stk-block-text__text{font-size:16px !important;}@media screen and (max-width: 1023px){.stk-6b4057d .stk-block-text__text{font-size:16px !important;}}<\/style><p class=\"stk-block-text__text\">Con car\u00e1cter general, para el acceso a un programa de doctorado ser\u00e1 necesario estar en posesi\u00f3n de los t\u00edtulos oficiales espa\u00f1oles de grado (o equivalente) y de m\u00e1ster universitario (o equivalente) siempre que se hayan superado, al menos, 300 cr\u00e9ditos del Sistema Europeo de Transferencia de Cr\u00e9ditos (ECTS, por sus siglas en ingl\u00e9s) en el conjunto de estas dos ense\u00f1anzas.&nbsp;<\/p><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, podr\u00e1n acceder quienes se encuentren en alguno de los siguientes supuestos:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Estar en posesi\u00f3n de t\u00edtulos universitarios oficiales espa\u00f1oles o t\u00edtulos espa\u00f1oles equivalentes siempre que se hayan superado, al menos, 300 cr\u00e9ditos ECTS en el conjunto de estas ense\u00f1anzas y acreditar un nivel 3 del MECES (<a href=\"https:\/\/www.ciencia.gob.es\/Universidades\/MECES.html\" target=\"_blank\" rel=\"noopener\">referencia al listado de titulaciones que supongan un nivel MECES 3<\/a>).\u00a0<\/li>\n\n\n\n<li>Estar en posesi\u00f3n de un t\u00edtulo obtenido conforme a sistemas educativos extranjeros pertenecientes al EEES, sin necesidad de su homologaci\u00f3n, que acredite un nivel 7 del Marco Europeo de Cualificaciones (EQF) siempre que dicho t\u00edtulo faculte para el acceso a estudios de doctorado en el pa\u00eds de expedici\u00f3n. Esta admisi\u00f3n no implicar\u00e1, en ning\u00fan caso, la homologaci\u00f3n del t\u00edtulo previo del que est\u00e9 en posesi\u00f3n la persona interesada ni su reconocimiento a otros efectos que el del acceso a ense\u00f1anzas de doctorado.\u00a0<\/li>\n\n\n\n<li>Estar en posesi\u00f3n de un t\u00edtulo obtenido conforme a sistemas educativos extranjeros ajenos al EEES, sin necesidad de su homologaci\u00f3n, previa <a href=\"https:\/\/sede.ull.es\/ecivilis-site\/catalog\/showProcedure\/575\" target=\"_blank\" rel=\"noopener\">comprobaci\u00f3n <\/a>por la universidad de que \u00e9ste acredita un nivel de formaci\u00f3n equivalente a la del t\u00edtulo oficial espa\u00f1ol de m\u00e1ster universitario y que faculta en el pa\u00eds de expedici\u00f3n del t\u00edtulo para el acceso a estudios de doctorado (seg\u00fan art\u00edculo 6 de esta instrucci\u00f3n). Esta admisi\u00f3n no implicar\u00e1, en ning\u00fan caso, la homologaci\u00f3n del t\u00edtulo previo del que est\u00e9 en posesi\u00f3n la persona interesada ni su reconocimiento a otros efectos que el del acceso a ense\u00f1anzas de doctorado.<\/li>\n\n\n\n<li>Estar en posesi\u00f3n de otro t\u00edtulo de doctor.<\/li>\n\n\n\n<li>Haber obtenido previamente una plaza en formaci\u00f3n en la correspondiente prueba de acceso a plazas de formaci\u00f3n sanitaria especializada y haber superado con evaluaci\u00f3n positiva al menos dos a\u00f1os de formaci\u00f3n de un programa para la obtenci\u00f3n del t\u00edtulo oficial de alguna de las especialidades en Ciencias de la Salud<\/li>\n<\/ul>\n<\/div><\/div><\/div>\n<\/details>\n\n\n\n<details class=\"wp-block-stackable-accordion stk-block-accordion stk-inner-blocks stk-block-content stk-block stk-63b0e61 is-style-default\" id=\"especificos\" data-block-id=\"63b0e61\">\n<summary class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-7a88921 stk--container-small stk-block-accordion__heading\" data-v=\"4\" data-block-id=\"7a88921\"><style>.stk-7a88921 {border-style:solid !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-7a88921-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-7a88921-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-2d4eaa7\" data-block-id=\"2d4eaa7\"><style>.stk-2d4eaa7 .stk-inner-blocks{gap:40px !important;}@media screen and (max-width: 1023px){.stk-2d4eaa7 .stk-inner-blocks{gap:40px !important;}}@media screen and (max-width: 767px){.stk-2d4eaa7 .stk-inner-blocks{gap:40px !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-icon stk-block-icon stk-block stk-673f014\" data-block-id=\"673f014\"><style>.stk-673f014 .stk--svg-wrapper .stk--inner-svg svg:last-child{height:24px !important;width:24px !important;}.stk-673f014 .stk--svg-wrapper .stk--inner-svg svg:last-child, .stk-673f014 .stk--svg-wrapper .stk--inner-svg svg:last-child :is(g, path, rect, polygon, ellipse){fill:#f33f4e !important;}<\/style><span class=\"stk--svg-wrapper stk--has-icon2\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-673f014\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-673-f-014-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-673-f-014-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M96 0C43 0 0 43 0 96V416c0 53 43 96 96 96H384h32c17.7 0 32-14.3 32-32s-14.3-32-32-32V384c17.7 0 32-14.3 32-32V32c0-17.7-14.3-32-32-32H384 96zm0 384H352v64H96c-17.7 0-32-14.3-32-32s14.3-32 32-32zm32-240c0-8.8 7.2-16 16-16H336c8.8 0 16 7.2 16 16s-7.2 16-16 16H144c-8.8 0-16-7.2-16-16zm16 48H336c8.8 0 16 7.2 16 16s-7.2 16-16 16H144c-8.8 0-16-7.2-16-16s7.2-16 16-16z\" \/><\/svg><\/div><div class=\"stk--inner-svg stk--icon-2\" style=\"display:none\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-673f014\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-673-f-014-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-673-f-014-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 576 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M249.6 471.5c10.8 3.8 22.4-4.1 22.4-15.5V78.6c0-4.2-1.6-8.4-5-11C247.4 52 202.4 32 144 32C93.5 32 46.3 45.3 18.1 56.1C6.8 60.5 0 71.7 0 83.8V454.1c0 11.9 12.8 20.2 24.1 16.5C55.6 460.1 105.5 448 144 448c33.9 0 79 14 105.6 23.5zm76.8 0C353 462 398.1 448 432 448c38.5 0 88.4 12.1 119.9 22.6c11.3 3.8 24.1-4.6 24.1-16.5V83.8c0-12.1-6.8-23.3-18.1-27.6C529.7 45.3 482.5 32 432 32c-58.4 0-103.4 20-123 35.6c-3.3 2.6-5 6.8-5 11V456c0 11.4 11.7 19.3 22.4 15.5z\" \/><\/svg><\/div><\/span><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-279d68b\" id=\"criterios-especificos\" data-block-id=\"279d68b\"><style>.stk-279d68b .stk-block-heading__text{font-size:18px !important;font-weight:700 !important;font-family:\"Montserrat\", Sans-serif !important;}@media screen and (max-width: 1023px){.stk-279d68b .stk-block-heading__text{font-size:18px !important;}}<\/style><p class=\"stk-block-heading__text\">Criterios espec\u00edficos<\/p><\/div>\n<\/div><\/div>\n<\/div><\/div><\/summary>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-cd2e899 stk-block-accordion__content\" data-v=\"4\" data-block-id=\"cd2e899\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-cd2e899-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-cd2e899-inner-blocks\">\n<p class=\"wp-block-paragraph\">Las personas solicitantes, adem\u00e1s de cumplir los requisitos del art\u00edculo anterior, deber\u00e1n cumplir los espec\u00edficos que cada titulaci\u00f3n haya establecido como obligatorios para poder ser admitidos (titulaciones espec\u00edficas, realizaci\u00f3n de pruebas de acceso, conocimientos m\u00ednimos en alguna materia, exigencia adicional de idiomas, aval del director\/a de tesis propuesto\/a, etc.) y que est\u00e1n publicados en <a href=\"https:\/\/www.ull.es\/doctorados\/listado-doctorados\/\" target=\"_blank\" rel=\"noopener\">p\u00e1gina web de cada titulaci\u00f3n,<\/a> en el apartado de acceso y admisi\u00f3n.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre los requisitos espec\u00edficos m\u00e1s comunes est\u00e1n:&nbsp;<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Aportar el aval de una investigador\/a como posible director\/a de la tesis doctoral y la acreditaci\u00f3n de un nivel de idioma (ver Anexo I y art\u00edculo 7 de esta instrucci\u00f3n).\u00a0<\/li>\n\n\n\n<li>Incluir la exigencia de complementos de formaci\u00f3n espec\u00edficos, en consonancia con los perfiles de admisi\u00f3n establecidos para el programa correspondiente, que deber\u00e1n ser superados durante el primer curso acad\u00e9mico. Excepcionalmente, en los supuestos en los que los complementos formativos de ese curso acad\u00e9mico se hubiesen impartido (total o parcialmente) antes de la formalizaci\u00f3n de la matr\u00edcula, el periodo para superarlos se ampl\u00eda hasta el segundo curso acad\u00e9mico. De esta excepcionalidad se deber\u00e1 dejar constancia en el plan de formaci\u00f3n personal.<\/li>\n<\/ol>\n<\/div><\/div><\/div>\n<\/details>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-901a5ad\" data-v=\"4\" data-block-id=\"901a5ad\"><style>@media screen and (min-width: 768px){.stk-901a5ad {flex:var(--stk-flex-grow, 1) 1 33.3% !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-901a5ad-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-901a5ad-inner-blocks\">\n<div style=\"border:2px solid black;padding:0px 30px 30px 25px\"><h4><span style=\"color: #f33f4e;font-size: 16px\"><strong>INFORMACI\u00d3N DE CONTACTO<\/strong><\/span><\/h4>\n<p style=\"font-size: 12px;line-height: 12px;font-weight: 500\"><strong style=\"font-weight: 500\">Direcci\u00f3n : <\/strong><span style=\"font-weight: 400\">Avda. Astrof\u00edsico Francisco S\u00e1nchez, SN. Edificio Calabaza\u00a0 38200 San Crist\u00f3bal de La Laguna.<\/span><\/p>\n<p style=\"font-size: 12px;line-height: 12px;font-weight: 500\"><strong style=\"font-weight: 500\">Tel\u00e9fono<\/strong>: <span style=\"color: #000000;line-height: 12px;font-weight: 400\"><a style=\"color: #000000\" target=\"_blank\" rel=\"noopener\" target=\"_blank\" rel=\"noopener\">(+34)  922 31 72 69<\/a><\/span><\/p>\n<p style=\"font-size: 12px;line-height: 12px;font-weight: 500\"><strong style=\"font-weight: 500\">Correo<\/strong>: <span style=\"color: #000000;line-height: 2px;font-weight: 400\"><a style=\"color: #000000\" href=\"mailto:doctorado@ull.es\" target=\"_blank\" rel=\"noopener\" target=\"_blank\" rel=\"noopener\">doctorado@ull.es<\/a><\/span><\/p>\n<p style=\"font-size: 12px;line-height: 12px;font-weight: 500\"><strong style=\"font-weight: 500\">Online:\u00a0<\/strong><a href=\"https:\/\/www.ull.es\/doctorados\" target=\"_blank\" rel=\"noopener\" target=\"_blank\" rel=\"noopener\">\u00a0<span style=\"color: #000000;text-decoration: underline;font-weight: 400\">P\u00e1gina web<\/span><\/a> \/ <a href=\"http:\/\/citaprevia.ull.es\/index.php?s=edpo\" target=\"_blank\" rel=\"noopener\" target=\"_blank\" rel=\"noopener\">\u00a0<span style=\"color: #000000;text-decoration: underline;font-weight: 400\">Cita previa<\/span><\/a> \/ <a href=\"https:\/\/sede.ull.es\/ecivilis-site\/catalog\/showProcedure\/484\" target=\"_blank\" rel=\"noopener\" target=\"_blank\" rel=\"noopener\">\u00a0<span style=\"color: #000000;text-decoration: underline;font-weight: 400\">Procedimiento para quejas, sugerencias y felicitaciones<\/span><\/a><\/p><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>PROGRAMMES DOCTORAUX UNIVERSITAIRES OFFERTS POUR L&#039;ANN\u00c9E UNIVERSITAIRE 2026-2027 Crit\u00e8res d&#039;acc\u00e8s et d&#039;admission Crit\u00e8res g\u00e9n\u00e9raux En g\u00e9n\u00e9ral, l&#039;acc\u00e8s \u00e0 un programme de doctorat requiert la possession d&#039;un dipl\u00f4me officiel espagnol de premier cycle (ou \u00e9quivalent) et d&#039;un master (ou \u00e9quivalent), \u00e0 condition d&#039;avoir valid\u00e9 au moins 300 cr\u00e9dits du syst\u00e8me universitaire espagnol\u2026<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/template-frontpage.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-32","page","type-page","status-publish","hentry"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-02 08:34:42","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.ull.es\/doctorados\/fr\/wp-json\/wp\/v2\/pages\/32","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ull.es\/doctorados\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ull.es\/doctorados\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ull.es\/doctorados\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ull.es\/doctorados\/fr\/wp-json\/wp\/v2\/comments?post=32"}],"version-history":[{"count":235,"href":"https:\/\/www.ull.es\/doctorados\/fr\/wp-json\/wp\/v2\/pages\/32\/revisions"}],"predecessor-version":[{"id":4841,"href":"https:\/\/www.ull.es\/doctorados\/fr\/wp-json\/wp\/v2\/pages\/32\/revisions\/4841"}],"wp:attachment":[{"href":"https:\/\/www.ull.es\/doctorados\/fr\/wp-json\/wp\/v2\/media?parent=32"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}