{"id":74,"date":"2018-02-22T13:34:00","date_gmt":"2018-02-22T13:34:00","guid":{"rendered":"http:\/\/www.ull.es\/doctorados\/ingenieria-industrial-informatica-medioambiental\/?page_id=74"},"modified":"2026-07-26T11:26:19","modified_gmt":"2026-07-26T11:26:19","slug":"normativa-presentacion-lectura-tesis","status":"publish","type":"page","link":"https:\/\/www.ull.es\/doctorados\/ingenieria-informatica-medioambiental\/en\/organizacion-del-programa\/normativa-presentacion-lectura-tesis\/","title":{"rendered":"Regulations for the presentation and reading of theses"},"content":{"rendered":"\n<div class=\"wp-block-stackable-columns alignfull stk-block-columns stk-block stk-2314a6b\" data-block-id=\"2314a6b\"><style>.stk-2314a6b {padding-bottom:0px !important;margin-top:-100px !important;margin-bottom:0px !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-2314a6b-column alignfull\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-1d1764d\" data-v=\"4\" data-block-id=\"1d1764d\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-1d1764d-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-1d1764d-inner-blocks\"><style id=\"depicter-1-inline-pre-css\">\n\n.depicter-1:not(.depicter-ready){\n\theight:450px;\n}\n\n\/***** Tablet *****\/\n@media screen and (max-width: 1024px){\n\n.depicter-1:not(.depicter-ready){\n\theight:700px;\n}\n\n}\n\/***** Mobile *****\/\n@media screen and (max-width: 767px){\n\n.depicter-1:not(.depicter-ready){\n\theight:360px;\n}\n\n}\n<\/style>\n<div id=\"depicter-1\" class=\"depicter depicter-document depicter-revert depicter-1 depicter-layout-fullwidth\">\n\n<div class=\"depicter-loading-container depicter-loading dotFlashing-dark\"><div class=\"depicter-loading-dark depicter-dot-flashing\">\n   <span><\/span>\n   <span><\/span>\n   <span><\/span>\n<\/div>\n<\/div>\n<div id=\"depicter-1-section-1\" class=\"depicter-section depicter-1-section-1\" data-name=\"Section 1\" data-type=\"section\" data-local-id=\"section-1\">\n<picture class=\"depicter-bg\">\n<source data-depicter-srcset=\"https:\/\/www.ull.es\/doctorados\/ingenieria-informatica-medioambiental\/wp-content\/uploads\/sites\/11\/2025\/05\/Headers-Doctorados_Doctorado-en-Ingenieria-Industrial-Informatica-y-Medioambiental-768x248.jpg, https:\/\/www.ull.es\/doctorados\/ingenieria-informatica-medioambiental\/wp-content\/uploads\/sites\/11\/2025\/05\/Headers-Doctorados_Doctorado-en-Ingenieria-Industrial-Informatica-y-Medioambiental.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(max-width: 1024px)\" \/>\n\n<source data-depicter-srcset=\"https:\/\/www.ull.es\/doctorados\/ingenieria-informatica-medioambiental\/wp-content\/uploads\/sites\/11\/2025\/05\/Headers-Doctorados_Doctorado-en-Ingenieria-Industrial-Informatica-y-Medioambiental.jpg, https:\/\/www.ull.es\/doctorados\/ingenieria-informatica-medioambiental\/wp-content\/uploads\/sites\/11\/2025\/05\/Headers-Doctorados_Doctorado-en-Ingenieria-Industrial-Informatica-y-Medioambiental-2000x645.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(min-width: 1025px)\" \/>\n<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-ken-burns=\"false\" data-tablet-ken-burns=\"false\" data-mobile-ken-burns=\"false\" alt=\"\" data-depicter-src=\"https:\/\/www.ull.es\/doctorados\/ingenieria-informatica-medioambiental\/wp-content\/uploads\/sites\/11\/2025\/05\/Headers-Doctorados_Doctorado-en-Ingenieria-Industrial-Informatica-y-Medioambiental.jpg\" data-object-fit=\"custom,custom,\" data-object-position=\"center top,,\" data-crop=\"{&apos;focalPoint&apos;:{&apos;x&apos;:0.5,&apos;y&apos;:0.5},&apos;mediaSize&apos;:{&apos;width&apos;:1395.3488372093024736386723816394805908203125,&apos;height&apos;:450}}\" data-tablet-crop=\"{&apos;focalPoint&apos;:{&apos;x&apos;:0.5,&apos;y&apos;:0.5},&apos;mediaSize&apos;:{&apos;width&apos;:2170.54263565891460530110634863376617431640625,&apos;height&apos;:700}}\" data-mobile-crop=\"{&apos;focalPoint&apos;:{&apos;x&apos;:0.5,&apos;y&apos;:0.5},&apos;mediaSize&apos;:{&apos;width&apos;:2294.57364341085258274688385426998138427734375,&apos;height&apos;:740}}\" \/>\n<\/picture>\n\n\n<h1 id=\"depicter-1-element-5\" class=\"depicter-element depicter-layer depicter-1-element-5\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 2\" data-local-id=\"element-5\" data-offset=\"x:0px;y:97px;origin:tl\" data-tablet-offset=\"x:208px;y:192px;origin:tl\" data-mobile-offset=\"x:-18px;y:67px;origin:tl\" data-width=\"1200px,auto,472px\" data-height=\"auto,auto,auto\" data-responsive-scale=\"true,,\">Programa de Doctorado en Ingenier\u00eda Industrial, Inform\u00e1tica y Medioambiental<\/h1>\n\n<div id=\"depicter-1-element-10\" class=\"depicter-element depicter-layer depicter-1-element-10\" data-type=\"shape\" data-wrap=\"true\" data-name=\"Shape 1\" data-local-id=\"element-10\" data-offset=\"x:0px;y:370px;origin:tl\" data-tablet-offset=\"x:208px;y:496px;origin:tl\" data-mobile-offset=\"x:-18px;y:316px;origin:tl\" data-width=\"1175px,647px,402px\" data-height=\"8px,8px,8px\" data-responsive-scale=\"true,,\"><\/div>\n<\/div>\n<\/div>\n<script>\n(window.depicterSetups = window.depicterSetups || []).push(function(){\n\tDepicter.basePath = 'https:\/\/www.ull.es\/doctorados\/ingenieria-informatica-medioambiental\/wp-content\/plugins\/depicter\/resources\/scripts\/player\/';\n\tconst dpPlayer = Depicter.setup('.depicter-1',\n\t\t{\"width\":[\"1200\",\"1024\",\"360\"],\"height\":[\"450\",\"700\",\"360\"],\"view\":\"basic\",\"keepAspectRatio\":true,\"preload\":0,\"layout\":\"fullwidth\",\"rtl\":false,\"initAfterAppear\":false,\"ajaxApiUrl\":\"https:\\\/\\\/www.ull.es\\\/doctorados\\\/ingenieria-informatica-medioambiental\\\/wp-admin\\\/admin-ajax.php\",\"mouseSwipe\":true,\"touchSwipe\":true,\"useWatermark\":false}\n\t);\n});\n<\/script><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns alignfull stk-block-columns stk--hide-mobile stk-block stk-6394276 stk-block-background\" data-block-id=\"6394276\"><style>.stk-6394276 {background-color:#f33f4e !important;padding-top:10px !important;margin-bottom:0px !important;}.stk-6394276:before{background-color:#f33f4e !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-6394276-column alignfull\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-8a66885\" data-v=\"4\" data-block-id=\"8a66885\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-8a66885-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-8a66885-inner-blocks\">\n<div class=\"wp-block-stackable-spacer stk-block-spacer stk--no-padding stk-block stk-bc89b3e\" data-block-id=\"bc89b3e\"><style>.stk-bc89b3e {height:0px !important;}<\/style><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns stk-block-columns stk-block stk-8b59b96\" data-block-id=\"8b59b96\"><style>.stk-8b59b96 .stk--block-align-8b59b96{align-items:flex-start !important;}.stk-8b59b96 {margin-top:50px !important;}.stk-8b59b96-column{--stk-columns-spacing:0px !important;--stk-column-gap:50px !important;}<\/style><div class=\"stk-row stk-inner-blocks stk--block-align-8b59b96 stk-block-content stk-content-align stk-8b59b96-column\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-dbb7e15\" data-v=\"4\" data-block-id=\"dbb7e15\"><style>@media screen and (min-width: 768px){.stk-dbb7e15 {flex:var(--stk-flex-grow, 1) 1 66.7% !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-dbb7e15-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-dbb7e15-inner-blocks\">\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-cc0239e\" id=\"complementos-de-formacion\" data-block-id=\"cc0239e\"><style>.stk-cc0239e .stk-block-heading__text{color:#000000 !important;font-weight:500 !important;}<\/style><h1 class=\"stk-block-heading__text has-text-color\">Normativa de presentaci\u00f3n y lectura de tesis<\/h1><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">El programa de doctorado sigue el Reglamento de Ense\u00f1anzas Oficiales de Doctorado de la ULL que en su cap\u00edtulo III, art\u00edculos 23 a 32 se refiere a la presentaci\u00f3n y lectura de tesis doctorales, que se ajusta a lo establecido en el Real Decreto 99\/2011. En este sentido, se regula los requisitos previos que debe cumplir el proyecto de investigaci\u00f3n, la propuesta y nombramiento de los evaluadores externos, del tribunal de evaluaci\u00f3n de tesis, la defensa de la tesis, las diferentes posibles menciones, la cotutela y la modalidad de tesis por compendio de publicaciones.<\/p>\n\n\n\n<div class=\"wp-block-stackable-image stk-block-image stk-block stk-fad5863 wp-block-hidden-desktop wp-block-hidden-mobile wp-block-hidden-tablet\" data-block-id=\"fad5863\"><figure><span class=\"stk-img-wrapper stk-image--shape-stretch\"><img loading=\"lazy\" decoding=\"async\" fetchpriority=\"auto\" class=\"stk-img wp-image-290\" src=\"https:\/\/www.ull.es\/doctorados\/ingenieria-informatica-medioambiental\/wp-content\/uploads\/sites\/11\/2024\/10\/2024-I3MA-Normativa-Tesis-Page-1.drawio.jpg\" width=\"806\" height=\"1019\" srcset=\"https:\/\/www.ull.es\/doctorados\/ingenieria-informatica-medioambiental\/wp-content\/uploads\/sites\/11\/2024\/10\/2024-I3MA-Normativa-Tesis-Page-1.drawio.jpg 806w, https:\/\/www.ull.es\/doctorados\/ingenieria-informatica-medioambiental\/wp-content\/uploads\/sites\/11\/2024\/10\/2024-I3MA-Normativa-Tesis-Page-1.drawio-237x300.jpg 237w, https:\/\/www.ull.es\/doctorados\/ingenieria-informatica-medioambiental\/wp-content\/uploads\/sites\/11\/2024\/10\/2024-I3MA-Normativa-Tesis-Page-1.drawio-768x971.jpg 768w, https:\/\/www.ull.es\/doctorados\/ingenieria-informatica-medioambiental\/wp-content\/uploads\/sites\/11\/2024\/10\/2024-I3MA-Normativa-Tesis-Page-1.drawio-375x474.jpg 375w, https:\/\/www.ull.es\/doctorados\/ingenieria-informatica-medioambiental\/wp-content\/uploads\/sites\/11\/2024\/10\/2024-I3MA-Normativa-Tesis-Page-1.drawio-750x948.jpg 750w\" sizes=\"auto, (max-width: 806px) 100vw, 806px\" \/><\/span><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">La normativa actualizada se puede encontrar <a href=\"https:\/\/sede.ull.es\/ecivilis-site\/bulletinBoard\/showBulletin\/32064:1\" target=\"_blank\" rel=\"noopener\">aqu\u00ed<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para m\u00e1s informaci\u00f3n detallada y la consulta de gu\u00edas de ayuda se puede acudir al siguiente enlace: <a href=\"https:\/\/www.ull.es\/doctorados\/tesis_doctoral\/\" target=\"_blank\" rel=\"noopener\">aqu\u00ed<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El art\u00edculo 23 de esta normativa prev\u00e9 la posibilidad de que cada programa de doctorado cuente con requisitos espec\u00edficos que deben cumplirse con car\u00e1cter previo al dep\u00f3sito. En el caso de este programa, esto implica lo siguiente:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Previamente al comienzo del procedimiento de designaci\u00f3n de evaluadores externos, debe cumplirse con tener una publicaci\u00f3n Journal Citations Reports (JCR) o bien una patente aceptada para autorizar la defensa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para la tesis por compendio, como norma general, se requieren tres publicaciones en revistas cient\u00edficas que figuren en la relaci\u00f3n de revistas del JCR.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su defecto, se plantean los siguientes m\u00ednimos: dos de las publicaciones deben ser art\u00edculos publicados en revistas indexadas en JCR en sus cuartiles Q1-Q2 o art\u00edculos asociados a congresos indexados en el ICORE en sus rankings A*\/A o una combinaci\u00f3n de ambos criterios. La tercera publicaci\u00f3n, como m\u00ednimo, debe estar asociada a una revista indexada en Scopus o a un congreso indexado en el ICORE en sus rankings A\/B. El doctorando o doctoranda debe ser primer o segundo autor de las publicaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-53ec762\" data-v=\"4\" data-block-id=\"53ec762\"><style>.stk-53ec762-inner-blocks{row-gap:0px !important;}.stk-53ec762 {padding-top:0px !important;padding-right:0px !important;padding-bottom:0px !important;padding-left:0px !important;}@media screen and (min-width: 768px){.stk-53ec762 {flex:var(--stk-flex-grow, 1) 1 33.3% !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-53ec762-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-53ec762-inner-blocks\">\n\n<ul class=\"widget-box\">\n<li class='contacto-header'>Informaci\u00f3n de contacto<\/li><li><i class=\"fa fa-map-marker\"><\/i> Avda. Astrof\u00edsico Francisco S\u00e1nchez, SN. Edificio Calabaza \u2013 AN.2D Apdo. 456 38200 San Crist\u00f3bal de La Laguna<\/li><li><i class=\"fa fa-envelope\"><\/i>  <a href=mailto:doctorado.industrial@ull.es>doctorado.industrial@ull.es<\/a><\/li><li><i class=\"fa fa-calendar\"><\/i><a href=\"http:\/\/citaprevia.ull.es\/index.php?s=edpo\"> Cita previa<\/a><\/li>\n<\/ul>\n\n\n<\/div><\/div><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Regulations for the presentation and defense of doctoral theses The doctoral program follows the Regulations for Official Doctoral Studies of the ULL, which in Chapter III, Articles 23 to 32, refers to the presentation and defense of doctoral theses, in accordance with the provisions of Royal Decree 99\/2011. In this regard,\u2026<\/p>","protected":false},"author":1,"featured_media":0,"parent":27,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/template-frontpage.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-74","page","type-page","status-publish","hentry"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 09:53:09","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.ull.es\/doctorados\/ingenieria-informatica-medioambiental\/en\/wp-json\/wp\/v2\/pages\/74","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ull.es\/doctorados\/ingenieria-informatica-medioambiental\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ull.es\/doctorados\/ingenieria-informatica-medioambiental\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ull.es\/doctorados\/ingenieria-informatica-medioambiental\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ull.es\/doctorados\/ingenieria-informatica-medioambiental\/en\/wp-json\/wp\/v2\/comments?post=74"}],"version-history":[{"count":16,"href":"https:\/\/www.ull.es\/doctorados\/ingenieria-informatica-medioambiental\/en\/wp-json\/wp\/v2\/pages\/74\/revisions"}],"predecessor-version":[{"id":431,"href":"https:\/\/www.ull.es\/doctorados\/ingenieria-informatica-medioambiental\/en\/wp-json\/wp\/v2\/pages\/74\/revisions\/431"}],"up":[{"embeddable":true,"href":"https:\/\/www.ull.es\/doctorados\/ingenieria-informatica-medioambiental\/en\/wp-json\/wp\/v2\/pages\/27"}],"wp:attachment":[{"href":"https:\/\/www.ull.es\/doctorados\/ingenieria-informatica-medioambiental\/en\/wp-json\/wp\/v2\/media?parent=74"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}