{"id":188,"date":"2018-10-04T10:08:32","date_gmt":"2018-10-04T10:08:32","guid":{"rendered":"http:\/\/www.ull.es\/doctorados\/islas-atlanticas\/?page_id=188"},"modified":"2025-09-24T10:52:42","modified_gmt":"2025-09-24T10:52:42","slug":"indicadores-y-resultados-del-titulo","status":"publish","type":"page","link":"https:\/\/www.ull.es\/doctorados\/islas-atlanticas\/fr\/calidad\/indicadores-y-resultados-del-titulo\/","title":{"rendered":"Indicateurs et r\u00e9sultats du titre"},"content":{"rendered":"\n<div class=\"wp-block-stackable-columns alignfull stk-block-columns stk-block stk-2314a6b\" data-block-id=\"2314a6b\"><style>.stk-2314a6b {padding-bottom:0px !important;margin-top:-100px !important;margin-bottom:0px !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-2314a6b-column alignfull\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-1d1764d\" data-v=\"4\" data-block-id=\"1d1764d\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-1d1764d-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-1d1764d-inner-blocks\"><style id=\"depicter-1-inline-pre-css\">\n\n.depicter-1:not(.depicter-ready){\n\theight:450px;\n}\n\n\/***** Tablet *****\/\n@media screen and (max-width: 1024px){\n\n.depicter-1:not(.depicter-ready){\n\theight:700px;\n}\n\n}\n\/***** Mobile *****\/\n@media screen and (max-width: 767px){\n\n.depicter-1:not(.depicter-ready){\n\theight:360px;\n}\n\n}\n<\/style>\n<div id=\"depicter-1\" class=\"depicter depicter-document depicter-revert depicter-1 depicter-layout-fullwidth\">\n\n<div class=\"depicter-loading-container depicter-loading dotFlashing-dark\"><div class=\"depicter-loading-dark depicter-dot-flashing\">\n   <span><\/span>\n   <span><\/span>\n   <span><\/span>\n<\/div>\n<\/div>\n<div id=\"depicter-1-section-1\" class=\"depicter-section depicter-1-section-1\" data-name=\"Section 1\" data-type=\"section\" data-local-id=\"section-1\">\n<picture class=\"depicter-bg\">\n<source data-depicter-srcset=\"https:\/\/www.ull.es\/doctorados\/islas-atlanticas\/wp-content\/uploads\/sites\/13\/2025\/05\/Headers-Doctorados_Doctorado-Islas-Atlanticas-768x248.jpg, https:\/\/www.ull.es\/doctorados\/islas-atlanticas\/wp-content\/uploads\/sites\/13\/2025\/05\/Headers-Doctorados_Doctorado-Islas-Atlanticas.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(max-width: 1024px)\" \/>\n\n<source data-depicter-srcset=\"https:\/\/www.ull.es\/doctorados\/islas-atlanticas\/wp-content\/uploads\/sites\/13\/2025\/05\/Headers-Doctorados_Doctorado-Islas-Atlanticas.jpg, https:\/\/www.ull.es\/doctorados\/islas-atlanticas\/wp-content\/uploads\/sites\/13\/2025\/05\/Headers-Doctorados_Doctorado-Islas-Atlanticas-2000x645.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(min-width: 1025px)\" \/>\n<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-ken-burns=\"false\" data-tablet-ken-burns=\"false\" data-mobile-ken-burns=\"false\" alt=\"\" data-depicter-src=\"https:\/\/www.ull.es\/doctorados\/islas-atlanticas\/wp-content\/uploads\/sites\/13\/2025\/05\/Headers-Doctorados_Doctorado-Islas-Atlanticas.jpg\" data-object-fit=\"custom,custom,\" data-object-position=\"center top,,\" data-crop=\"{&apos;focalPoint&apos;:{&apos;x&apos;:0.5,&apos;y&apos;:0.5},&apos;mediaSize&apos;:{&apos;width&apos;:1395.3488372093024736386723816394805908203125,&apos;height&apos;:450}}\" data-tablet-crop=\"{&apos;focalPoint&apos;:{&apos;x&apos;:0.5,&apos;y&apos;:0.5},&apos;mediaSize&apos;:{&apos;width&apos;:2170.54263565891460530110634863376617431640625,&apos;height&apos;:700}}\" data-mobile-crop=\"{&apos;focalPoint&apos;:{&apos;x&apos;:0.5,&apos;y&apos;:0.5},&apos;mediaSize&apos;:{&apos;width&apos;:2294.57364341085258274688385426998138427734375,&apos;height&apos;:740}}\" \/>\n<\/picture>\n\n\n<h1 id=\"depicter-1-element-5\" class=\"depicter-element depicter-layer depicter-1-element-5\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 2\" data-local-id=\"element-5\" data-offset=\"x:0px;y:139px;origin:tl\" data-tablet-offset=\"x:215px;y:194px;origin:tl\" data-mobile-offset=\"x:29px;y:102px;origin:tl\" data-width=\"1200px,auto,348px\" data-height=\"auto,auto,auto\" data-responsive-scale=\"true,,\">Programa de Doctorado en Islas Atl\u00e1nticas<\/h1>\n\n<div id=\"depicter-1-element-10\" class=\"depicter-element depicter-layer depicter-1-element-10\" data-type=\"shape\" data-wrap=\"true\" data-name=\"Shape 1\" data-local-id=\"element-10\" data-offset=\"x:0px;y:312px;origin:tl\" data-tablet-offset=\"x:215px;y:361px;origin:tl\" data-mobile-offset=\"x:29px;y:301px;origin:tl\" data-width=\"1171px,647px,282px\" data-height=\"8px,8px,8px\" data-responsive-scale=\"true,,\"><\/div>\n<\/div>\n<\/div>\n<script>\n(window.depicterSetups = window.depicterSetups || []).push(function(){\n\tDepicter.basePath = 'https:\/\/www.ull.es\/doctorados\/islas-atlanticas\/wp-content\/plugins\/depicter\/resources\/scripts\/player\/';\n\tconst dpPlayer = Depicter.setup('.depicter-1',\n\t\t{\"width\":[\"1200\",\"1024\",\"360\"],\"height\":[\"450\",\"700\",\"360\"],\"view\":\"basic\",\"keepAspectRatio\":true,\"preload\":0,\"layout\":\"fullwidth\",\"rtl\":false,\"initAfterAppear\":false,\"ajaxApiUrl\":\"https:\\\/\\\/www.ull.es\\\/doctorados\\\/islas-atlanticas\\\/wp-admin\\\/admin-ajax.php\",\"mouseSwipe\":true,\"touchSwipe\":true,\"useWatermark\":false}\n\t);\n});\n<\/script><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns alignfull stk-block-columns stk--hide-mobile stk-block stk-6394276 stk-block-background\" data-block-id=\"6394276\"><style>.stk-6394276 {background-color:#f33f4e !important;padding-top:10px !important;margin-bottom:0px !important;}.stk-6394276:before{background-color:#f33f4e !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-6394276-column alignfull\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-8a66885\" data-v=\"4\" data-block-id=\"8a66885\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-8a66885-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-8a66885-inner-blocks\">\n<div class=\"wp-block-stackable-spacer stk-block-spacer stk--no-padding stk-block stk-bc89b3e\" data-block-id=\"bc89b3e\"><style>.stk-bc89b3e {height:0px !important;}<\/style><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns stk-block-columns stk-block stk-8b59b96\" data-block-id=\"8b59b96\"><style>.stk-8b59b96 .stk--block-align-8b59b96{align-items:flex-start !important;}.stk-8b59b96 {margin-top:50px !important;}.stk-8b59b96-column{--stk-columns-spacing:0px !important;--stk-column-gap:50px !important;}<\/style><div class=\"stk-row stk-inner-blocks stk--block-align-8b59b96 stk-block-content stk-content-align stk-8b59b96-column\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-dbb7e15\" data-v=\"4\" data-block-id=\"dbb7e15\"><style>@media screen and (min-width: 768px){.stk-dbb7e15 {flex:var(--stk-flex-grow, 1) 1 66.7% !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-dbb7e15-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-dbb7e15-inner-blocks\">\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-cc0239e\" id=\"complementos-de-formacion\" data-block-id=\"cc0239e\"><style>.stk-cc0239e .stk-block-heading__text{color:#000000 !important;font-weight:500 !important;}<\/style><h1 class=\"stk-block-heading__text has-text-color\">Indicadores y resultados del t\u00edtulo<\/h1><\/div>\n\n\n\n<details class=\"wp-block-stackable-accordion stk-block-accordion stk-inner-blocks stk-block-content stk-block stk-7c390cd is-style-default\" id=\"tasas\" data-block-id=\"7c390cd\"><style>.stk-7c390cd {border-style:solid !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;margin-bottom:11px !important;}<\/style>\n<summary class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-c927805 stk--container-small stk-block-accordion__heading\" data-v=\"4\" data-block-id=\"c927805\"><style>.stk-c927805 {padding-top:2px !important;padding-right:2px !important;padding-bottom:2px !important;padding-left:2px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-c927805-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-c927805-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-7935446\" data-block-id=\"7935446\"><style>.stk-7935446 .stk-inner-blocks{gap:39px !important;}@media screen and (max-width: 1023px){.stk-7935446 .stk-inner-blocks{gap:39px !important;}}@media screen and (max-width: 767px){.stk-7935446 .stk-inner-blocks{gap:39px !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-icon stk-block-icon stk-block stk-9a468d5\" data-block-id=\"9a468d5\"><style>.stk-9a468d5 .stk--svg-wrapper .stk--inner-svg svg:last-child{height:25px !important;width:25px !important;}.stk-9a468d5 .stk--svg-wrapper .stk--inner-svg svg:last-child, .stk-9a468d5 .stk--svg-wrapper .stk--inner-svg svg:last-child :is(g, path, rect, polygon, ellipse){fill:#f33f4e !important;}<\/style><span class=\"stk--svg-wrapper stk--has-icon2\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-9a468d5\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-9-a-468-d-5-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-9-a-468-d-5-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M224 256A128 128 0 1 0 224 0a128 128 0 1 0 0 256zm-45.7 48C79.8 304 0 383.8 0 482.3C0 498.7 13.3 512 29.7 512H418.3c16.4 0 29.7-13.3 29.7-29.7C448 383.8 368.2 304 269.7 304H178.3z\"><\/path><\/svg><\/div><div class=\"stk--inner-svg stk--icon-2\" style=\"display:none\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-9a468d5\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-9-a-468-d-5-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-9-a-468-d-5-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M304 128a80 80 0 1 0 -160 0 80 80 0 1 0 160 0zM96 128a128 128 0 1 1 256 0A128 128 0 1 1 96 128zM49.3 464H398.7c-8.9-63.3-63.3-112-129-112H178.3c-65.7 0-120.1 48.7-129 112zM0 482.3C0 383.8 79.8 304 178.3 304h91.4C368.2 304 448 383.8 448 482.3c0 16.4-13.3 29.7-29.7 29.7H29.7C13.3 512 0 498.7 0 482.3z\"><\/path><\/svg><\/div><\/span><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-31863c1\" id=\"tasas-de-rendimiento-academico\" data-block-id=\"31863c1\"><style>.stk-31863c1 .stk-block-heading__text{color:#000000 !important;font-weight:500 !important;font-family:\"ArgentumSans\", Sans-serif !important;}<\/style><h4 class=\"stk-block-heading__text has-text-color\">Tasas de rendimiento acad\u00e9mico<\/h4><\/div>\n<\/div><\/div>\n<\/div><\/div><\/summary>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-5222666 stk-block-accordion__content\" data-v=\"4\" data-block-id=\"5222666\"><style>.stk-5222666 {margin-top:-30px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-5222666-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-5222666-inner-blocks\">\nDatos extra\u00eddos del sistema de informaci\u00f3n de la ULL y resultados previstos de la memoria de verificaci\u00f3n\/modificaci\u00f3n del t\u00edtulo.\n<table>\n<tbody>\n<tr>\n<td colspan=\"6\" width=\"562\"><strong>EVOLUCI\u00d3N DE TASAS [%, N]<\/strong><\/td>\n<\/tr>\n<tr>\n<td colspan=\"6\" width=\"562\"><strong>PD en en Islas Atl\u00e1nticas: Historia, Patrimonio y Marco Jur\u00eddico Institucional <\/strong><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td>\n<p style=\"text-align: center;\">Previsi\u00f3n Memoria Verificaci\u00f3n<\/p>\n<\/td>\n<td style=\"text-align: center;\">Curso\n16-17<\/td>\n<td style=\"text-align: center;\">Curso\n17-18<\/td>\n<td style=\"text-align: center;\" width=\"42\">Curso 18-19<\/td>\n<td style=\"text-align: center;\">Curso\n19-20<\/td>\n<td style=\"text-align: center;\">Curso\n20-21<\/td>\n<\/tr>\n<tr>\n<td>N\u00ba de <strong>tesis defendidas<\/strong> dentro del tiempo establecido (&lt;=3 a\u00f1os) (1)<\/td>\n<td style=\"text-align: center;\">&#8211;<\/td>\n<td style=\"text-align: center;\">0<\/td>\n<td style=\"text-align: center;\">1<\/td>\n<td style=\"text-align: center;\" width=\"42\">1<\/td>\n<td style=\"text-align: center;\">0<\/td>\n<td style=\"text-align: center;\">0<\/td>\n<\/tr>\n<tr>\n<td>N\u00ba de doctorandos que <strong>abandonan<\/strong> el programa de doctorado (1)<\/td>\n<td style=\"text-align: center;\">&#8211;<\/td>\n<td style=\"text-align: center;\">3<\/td>\n<td style=\"text-align: center;\">0<\/td>\n<td style=\"text-align: center;\" width=\"42\">2<\/td>\n<td style=\"text-align: center;\">0<\/td>\n<td style=\"text-align: center;\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td><strong>Tasa de \u00e9xito<\/strong> (&lt;= 3 a\u00f1os) a TC [%] (1)<\/td>\n<td style=\"text-align: center;\">&#8211;<\/td>\n<td style=\"text-align: center;\">0<\/td>\n<td style=\"text-align: center;\">100<\/td>\n<td style=\"text-align: center;\" width=\"42\">25<\/td>\n<td style=\"text-align: center;\">0<\/td>\n<td style=\"text-align: center;\">0<\/td>\n<\/tr>\n<tr>\n<td><strong>Tasa de \u00e9xito<\/strong> (>3 a\u00f1os) a TC [%] (1)<\/td>\n<td style=\"text-align: center;\">&#8211;<\/td>\n<td style=\"text-align: center;\">20<\/td>\n<td style=\"text-align: center;\">0<\/td>\n<td style=\"text-align: center;\" width=\"42\">0<\/td>\n<td style=\"text-align: center;\">0<\/td>\n<td style=\"text-align: center;\">0<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<span style=\"color: #000000;\">\u00ab(1) Datos provisionales a fecha <b>28\/02\/2022<\/b>\u00ab<\/span>\n<\/div><\/div><\/div>\n<\/details>\n\n\n\n<details class=\"wp-block-stackable-accordion stk-block-accordion stk-inner-blocks stk-block-content stk-block stk-88a7c9c is-style-default\" id=\"satisfaccion\" data-block-id=\"88a7c9c\"><style>.stk-88a7c9c {border-style:solid !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;margin-bottom:10px !important;}<\/style>\n<summary class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-27019df stk--container-small stk-block-accordion__heading\" data-v=\"4\" data-block-id=\"27019df\"><style>.stk-27019df {padding-top:2px !important;padding-right:2px !important;padding-bottom:2px !important;padding-left:2px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-27019df-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-27019df-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-9c9ce7e\" data-block-id=\"9c9ce7e\"><style>.stk-9c9ce7e .stk-inner-blocks{gap:39px !important;}@media screen and (max-width: 1023px){.stk-9c9ce7e .stk-inner-blocks{gap:39px !important;}}@media screen and (max-width: 767px){.stk-9c9ce7e .stk-inner-blocks{gap:39px !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-icon stk-block-icon stk-block stk-61c8ad3\" data-block-id=\"61c8ad3\"><style>.stk-61c8ad3 .stk--svg-wrapper .stk--inner-svg svg:last-child{height:25px !important;width:25px !important;}.stk-61c8ad3 .stk--svg-wrapper .stk--inner-svg svg:last-child, .stk-61c8ad3 .stk--svg-wrapper .stk--inner-svg svg:last-child :is(g, path, rect, polygon, ellipse){fill:#f33f4e !important;}<\/style><span class=\"stk--svg-wrapper stk--has-icon2\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-61c8ad3\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-61-c-8-ad-3-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-61-c-8-ad-3-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M256 512A256 256 0 1 0 256 0a256 256 0 1 0 0 512zM164.1 325.5C182 346.2 212.6 368 256 368s74-21.8 91.9-42.5c5.8-6.7 15.9-7.4 22.6-1.6s7.4 15.9 1.6 22.6C349.8 372.1 311.1 400 256 400s-93.8-27.9-116.1-53.5c-5.8-6.7-5.1-16.8 1.6-22.6s16.8-5.1 22.6 1.6zM144.4 208a32 32 0 1 1 64 0 32 32 0 1 1 -64 0zm192-32a32 32 0 1 1 0 64 32 32 0 1 1 0-64z\"><\/path><\/svg><\/div><div class=\"stk--inner-svg stk--icon-2\" style=\"display:none\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-61c8ad3\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-61-c-8-ad-3-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-61-c-8-ad-3-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M464 256A208 208 0 1 0 48 256a208 208 0 1 0 416 0zM0 256a256 256 0 1 1 512 0A256 256 0 1 1 0 256zm177.6 62.1C192.8 334.5 218.8 352 256 352s63.2-17.5 78.4-33.9c9-9.7 24.2-10.4 33.9-1.4s10.4 24.2 1.4 33.9c-22 23.8-60 49.4-113.6 49.4s-91.7-25.5-113.6-49.4c-9-9.7-8.4-24.9 1.4-33.9s24.9-8.4 33.9 1.4zM144.4 208a32 32 0 1 1 64 0 32 32 0 1 1 -64 0zm192-32a32 32 0 1 1 0 64 32 32 0 1 1 0-64z\"><\/path><\/svg><\/div><\/span><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-bcb6d4e\" id=\"satisfaccion-grupos-de-interes\" data-block-id=\"bcb6d4e\"><style>.stk-bcb6d4e .stk-block-heading__text{color:#000000 !important;font-weight:500 !important;font-family:\"ArgentumSans\", Sans-serif !important;}<\/style><h4 class=\"stk-block-heading__text has-text-color\">Satisfacci\u00f3n grupos de inter\u00e9s<\/h4><\/div>\n<\/div><\/div>\n<\/div><\/div><\/summary>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-76d605c stk-block-accordion__content\" data-v=\"4\" data-block-id=\"76d605c\"><style>.stk-76d605c {margin-top:-30px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-76d605c-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-76d605c-inner-blocks\">\nEl SGIC cuenta con procedimientos espec\u00edficos para recoger la satisfacci\u00f3n de los diferentes colectivos que participan en los t\u00edtulos, y su implementaci\u00f3n se vertebra a nivel institucional. La Unidad T\u00e9cnica de Calidad, en colaboraci\u00f3n con los centros\/t\u00edtulos y otros agentes implicados, es la encargada de la gesti\u00f3n, planificaci\u00f3n y aplicaci\u00f3n integral de las encuestas de satisfacci\u00f3n que dan respuesta a los programas de evaluaci\u00f3n y calidad institucionales (ACREDITA, AUDIT, DOCENTIA\u2026). Las campa\u00f1as de encuestas de satisfacci\u00f3n a los diferentes grupos de inter\u00e9s (estudiantes, profesorado, egresados, tutores externos -potenciales empleadores-, etc.,) son aplicadas peri\u00f3dicamente y de forma sistem\u00e1tica.\n<table style=\"height: 535px;\" width=\"563\">\n<tbody>\n<tr>\n<td colspan=\"2\">&nbsp;\n\n<strong>GRADO DE SATISFACCI\u00d3N DE LOS GRUPOS DE INTER\u00c9S [Escala Likert 1 a 5]<\/strong><\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\"><strong>PD en Islas Atl\u00e1nticas: Historia, Patrimonio y Marco Jur\u00eddico Institucional<\/strong><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td>\n<p style=\"text-align: center;\">Curso 17-18<\/p>\n<\/td>\n<td>\n<p style=\"text-align: center;\">Curso 18-19<\/p>\n<\/td>\n<td>\n<p style=\"text-align: center;\">Curso 19-20<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>Grado de satisfacci\u00f3n global de los estudiantes con el t\u00edtulo<\/td>\n<td style=\"text-align: center;\">3,67<\/td>\n<td>\n<p style=\"text-align: center;\">4,24<\/p>\n<\/td>\n<td>\n<p style=\"text-align: center;\">3,71<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>Grado de satisfacci\u00f3n estudiantes con el profesorado<\/td>\n<td>\n<p style=\"text-align: center;\">4,33<\/p>\n<\/td>\n<td style=\"text-align: center;\">4,12<\/td>\n<td style=\"text-align: center;\">4,14<\/td>\n<\/tr>\n<tr>\n<td>Grado de satisfacci\u00f3n estudiantes con los recursos materiales<\/td>\n<td>\n<p style=\"text-align: center;\">3,75<\/p>\n<\/td>\n<td>\n<p style=\"text-align: center;\">4,00<\/p>\n<\/td>\n<td>\n<p style=\"text-align: center;\">3,67<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>Grado de satisfacci\u00f3n del profesorado investigador con el t\u00edtulo<\/td>\n<td>\n<p style=\"text-align: center;\">4,00<\/p>\n<\/td>\n<td>\n<p style=\"text-align: center;\">4,00<\/p>\n<\/td>\n<td>\n<p style=\"text-align: center;\">4,00<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>Grado de satisfacci\u00f3n de los egresados con el t\u00edtulo (>2 a\u00f1os tras egreso) (1)<\/td>\n<td>\n<p style=\"text-align: center;\">&#8211;<\/p>\n<\/td>\n<td style=\"text-align: center;\">&#8211;<\/td>\n<td>\n<p style=\"text-align: center;\">&#8211;<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div>\n<div><\/div>\n<div><span style=\"color: #666666;\">(1) <i>Datos asignados al curso de aplicaci\u00f3n de la encuesta, correspondientes a cohortes de egreso de cursos anteriores.<\/i><\/span><\/div>\n<\/div>\n<\/div><\/div><\/div>\n<\/details>\n\n\n\n<details class=\"wp-block-stackable-accordion stk-block-accordion stk-inner-blocks stk-block-content stk-block stk-6320006 is-style-default\" id=\"indicadores\" data-block-id=\"6320006\"><style>.stk-6320006 {border-style:solid !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;margin-bottom:9px !important;}<\/style>\n<summary class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-ae2ad76 stk--container-small stk-block-accordion__heading\" data-v=\"4\" data-block-id=\"ae2ad76\"><style>.stk-ae2ad76 {padding-top:2px !important;padding-right:2px !important;padding-bottom:2px !important;padding-left:2px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-ae2ad76-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-ae2ad76-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-16db2af\" data-block-id=\"16db2af\"><style>.stk-16db2af .stk-inner-blocks{gap:39px !important;}@media screen and (max-width: 1023px){.stk-16db2af .stk-inner-blocks{gap:39px !important;}}@media screen and (max-width: 767px){.stk-16db2af .stk-inner-blocks{gap:39px !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-icon stk-block-icon stk-block stk-38bb3f8\" data-block-id=\"38bb3f8\"><style>.stk-38bb3f8 .stk--svg-wrapper .stk--inner-svg svg:last-child{height:25px !important;width:25px !important;}.stk-38bb3f8 .stk--svg-wrapper .stk--inner-svg svg:last-child, .stk-38bb3f8 .stk--svg-wrapper .stk--inner-svg svg:last-child :is(g, path, rect, polygon, ellipse){fill:#f33f4e !important;}<\/style><span class=\"stk--svg-wrapper stk--has-icon2\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-38bb3f8\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-38-bb-3-f-8-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-38-bb-3-f-8-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M256 512A256 256 0 1 0 256 0a256 256 0 1 0 0 512zM216 336h24V272H216c-13.3 0-24-10.7-24-24s10.7-24 24-24h48c13.3 0 24 10.7 24 24v88h8c13.3 0 24 10.7 24 24s-10.7 24-24 24H216c-13.3 0-24-10.7-24-24s10.7-24 24-24zm40-208a32 32 0 1 1 0 64 32 32 0 1 1 0-64z\"><\/path><\/svg><\/div><div class=\"stk--inner-svg stk--icon-2\" style=\"display:none\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-38bb3f8\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-38-bb-3-f-8-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-38-bb-3-f-8-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 192 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M48 80a48 48 0 1 1 96 0A48 48 0 1 1 48 80zM0 224c0-17.7 14.3-32 32-32H96c17.7 0 32 14.3 32 32V448h32c17.7 0 32 14.3 32 32s-14.3 32-32 32H32c-17.7 0-32-14.3-32-32s14.3-32 32-32H64V256H32c-17.7 0-32-14.3-32-32z\"><\/path><\/svg><\/div><\/span><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-a35761a\" id=\"indicadores\" data-block-id=\"a35761a\"><style>.stk-a35761a .stk-block-heading__text{color:#000000 !important;font-weight:500 !important;font-family:\"ArgentumSans\", Sans-serif !important;}<\/style><h4 class=\"stk-block-heading__text has-text-color\">Indicadores<\/h4><\/div>\n<\/div><\/div>\n<\/div><\/div><\/summary>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-81ecc51 stk-block-accordion__content\" data-v=\"4\" data-block-id=\"81ecc51\"><style>.stk-81ecc51 {margin-top:-30px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-81ecc51-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-81ecc51-inner-blocks\">\nDatos extra\u00eddos del sistema de informaci\u00f3n de la ULL.\n<table>\n<tbody>\n<tr>\n<td colspan=\"5\"><strong>EVOLUCI\u00d3N DE INDICADORES<\/strong><\/td>\n<\/tr>\n<tr>\n<td colspan=\"5\"><strong>PD en Islas Atl\u00e1nticas: Historia, Patrimonio y Marco Jur\u00eddico Institucional<\/strong><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td style=\"text-align: center;\">Curso\n16-17<\/td>\n<td style=\"text-align: center;\">Curso\n17-18<\/td>\n<td style=\"text-align: center;\">Curso\n18-19<\/td>\n<td style=\"text-align: center;\">Curso\n19-20<\/td>\n<td style=\"text-align: center;\">Curso\n20-21<\/td>\n<\/tr>\n<tr>\n<td>N\u00ba de estudiantes de nuevo ingreso matriculados<\/td>\n<td style=\"text-align: center;\">10<\/td>\n<td style=\"text-align: center;\">2<\/td>\n<td style=\"text-align: center;\">6<\/td>\n<td style=\"text-align: center;\">2<\/td>\n<td style=\"text-align: center;\">2<\/td>\n<\/tr>\n<tr>\n<td>N\u00ba de estudiantes totales matriculados<\/td>\n<td style=\"text-align: center;\">23<\/td>\n<td style=\"text-align: center;\">21<\/td>\n<td style=\"text-align: center;\">28<\/td>\n<td style=\"text-align: center;\">22<\/td>\n<td style=\"text-align: center;\">19<\/td>\n<\/tr>\n<tr>\n<td>N\u00ba de estudiantes internacionales<\/td>\n<td style=\"text-align: center;\">2<\/td>\n<td style=\"text-align: center;\">2<\/td>\n<td style=\"text-align: center;\">2<\/td>\n<td style=\"text-align: center;\">1<\/td>\n<td style=\"text-align: center;\">1<\/td>\n<\/tr>\n<tr>\n<td>N\u00ba total de tesis defendidas en el programa (egresados) (1)<\/td>\n<td style=\"text-align: center;\">&#8211;<\/td>\n<td style=\"text-align: center;\">&#8211;<\/td>\n<td style=\"text-align: center;\">4<\/td>\n<td style=\"text-align: center;\">4<\/td>\n<td style=\"text-align: center;\">1<\/td>\n<\/tr>\n<tr>\n<td>Duraci\u00f3n media de los estudios (TC: Tiempo Completo)[a\u00f1os] (1)<\/td>\n<td style=\"text-align: center;\">&#8211;<\/td>\n<td style=\"text-align: center;\">&#8211;<\/td>\n<td style=\"text-align: center;\">4<\/td>\n<td style=\"text-align: center;\">3,9<\/td>\n<td style=\"text-align: center;\">2,8<\/td>\n<\/tr>\n<tr>\n<td>Duraci\u00f3n media de los estudios (TP: Tiempo Parcial)[a\u00f1os]<\/td>\n<td style=\"text-align: center;\">&#8211;<\/td>\n<td style=\"text-align: center;\">&#8211;<\/td>\n<td style=\"text-align: center;\">&#8211;<\/td>\n<td style=\"text-align: center;\">&#8211;<\/td>\n<td style=\"text-align: center;\">&#8211;<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<span style=\"color: #000000;\">\u00ab(1) Datos provisionales a fecha <b>28\/02\/2022<\/b>\u00ab<\/span>\n<\/div><\/div><\/div>\n<\/details>\n\n\n\n<details class=\"wp-block-stackable-accordion stk-block-accordion stk-inner-blocks stk-block-content stk-block stk-1feffea is-style-default\" id=\"insercion\" data-block-id=\"1feffea\"><style>.stk-1feffea {border-style:solid !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;margin-bottom:9px !important;}<\/style>\n<summary class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-2b3197b stk--container-small stk-block-accordion__heading\" data-v=\"4\" data-block-id=\"2b3197b\"><style>.stk-2b3197b {padding-top:2px !important;padding-right:2px !important;padding-bottom:2px !important;padding-left:2px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-2b3197b-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-2b3197b-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-0a6ac0f\" data-block-id=\"0a6ac0f\"><style>.stk-0a6ac0f .stk-inner-blocks{gap:39px !important;}@media screen and (max-width: 1023px){.stk-0a6ac0f .stk-inner-blocks{gap:39px !important;}}@media screen and (max-width: 767px){.stk-0a6ac0f .stk-inner-blocks{gap:39px !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-icon stk-block-icon stk-block stk-783add4\" data-block-id=\"783add4\"><style>.stk-783add4 .stk--svg-wrapper .stk--inner-svg svg:last-child{height:25px !important;width:25px !important;}.stk-783add4 .stk--svg-wrapper .stk--inner-svg svg:last-child, .stk-783add4 .stk--svg-wrapper .stk--inner-svg svg:last-child :is(g, path, rect, polygon, ellipse){fill:#f33f4e !important;}<\/style><span class=\"stk--svg-wrapper stk--has-icon2\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-783add4\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-783-add-4-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-783-add-4-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M313.4 32.9c26 5.2 42.9 30.5 37.7 56.5l-2.3 11.4c-5.3 26.7-15.1 52.1-28.8 75.2H464c26.5 0 48 21.5 48 48c0 18.5-10.5 34.6-25.9 42.6C497 275.4 504 288.9 504 304c0 23.4-16.8 42.9-38.9 47.1c4.4 7.3 6.9 15.8 6.9 24.9c0 21.3-13.9 39.4-33.1 45.6c.7 3.3 1.1 6.8 1.1 10.4c0 26.5-21.5 48-48 48H294.5c-19 0-37.5-5.6-53.3-16.1l-38.5-25.7C176 420.4 160 390.4 160 358.3V320 272 247.1c0-29.2 13.3-56.7 36-75l7.4-5.9c26.5-21.2 44.6-51 51.2-84.2l2.3-11.4c5.2-26 30.5-42.9 56.5-37.7zM32 192H96c17.7 0 32 14.3 32 32V448c0 17.7-14.3 32-32 32H32c-17.7 0-32-14.3-32-32V224c0-17.7 14.3-32 32-32z\"><\/path><\/svg><\/div><div class=\"stk--inner-svg stk--icon-2\" style=\"display:none\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-783add4\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-783-add-4-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-783-add-4-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M323.8 34.8c-38.2-10.9-78.1 11.2-89 49.4l-5.7 20c-3.7 13-10.4 25-19.5 35l-51.3 56.4c-8.9 9.8-8.2 25 1.6 33.9s25 8.2 33.9-1.6l51.3-56.4c14.1-15.5 24.4-34 30.1-54.1l5.7-20c3.6-12.7 16.9-20.1 29.7-16.5s20.1 16.9 16.5 29.7l-5.7 20c-5.7 19.9-14.7 38.7-26.6 55.5c-5.2 7.3-5.8 16.9-1.7 24.9s12.3 13 21.3 13L448 224c8.8 0 16 7.2 16 16c0 6.8-4.3 12.7-10.4 15c-7.4 2.8-13 9-14.9 16.7s.1 15.8 5.3 21.7c2.5 2.8 4 6.5 4 10.6c0 7.8-5.6 14.3-13 15.7c-8.2 1.6-15.1 7.3-18 15.2s-1.6 16.7 3.6 23.3c2.1 2.7 3.4 6.1 3.4 9.9c0 6.7-4.2 12.6-10.2 14.9c-11.5 4.5-17.7 16.9-14.4 28.8c.4 1.3 .6 2.8 .6 4.3c0 8.8-7.2 16-16 16H286.5c-12.6 0-25-3.7-35.5-10.7l-61.7-41.1c-11-7.4-25.9-4.4-33.3 6.7s-4.4 25.9 6.7 33.3l61.7 41.1c18.4 12.3 40 18.8 62.1 18.8H384c34.7 0 62.9-27.6 64-62c14.6-11.7 24-29.7 24-50c0-4.5-.5-8.8-1.3-13c15.4-11.7 25.3-30.2 25.3-51c0-6.5-1-12.8-2.8-18.7C504.8 273.7 512 257.7 512 240c0-35.3-28.6-64-64-64l-92.3 0c4.7-10.4 8.7-21.2 11.8-32.2l5.7-20c10.9-38.2-11.2-78.1-49.4-89zM32 192c-17.7 0-32 14.3-32 32V448c0 17.7 14.3 32 32 32H96c17.7 0 32-14.3 32-32V224c0-17.7-14.3-32-32-32H32z\"><\/path><\/svg><\/div><\/span><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-018688c\" id=\"insercion-laboral\" data-block-id=\"018688c\"><style>.stk-018688c .stk-block-heading__text{color:#000000 !important;font-weight:500 !important;font-family:\"ArgentumSans\", Sans-serif !important;}<\/style><h4 class=\"stk-block-heading__text has-text-color\">Inserci\u00f3n laboral<\/h4><\/div>\n<\/div><\/div>\n<\/div><\/div><\/summary>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-bf216cd stk-block-accordion__content\" data-v=\"4\" data-block-id=\"bf216cd\"><style>.stk-bf216cd {margin-top:-30px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-bf216cd-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-bf216cd-inner-blocks\">\n<p class=\"wp-block-paragraph\">El Sistema de Aseguramiento de la Calidad (SAIC) cuenta con procedimientos espec\u00edficos para recabar informaci\u00f3n acerca de la empleabilidad e inserci\u00f3n laboral de las personas tituladas en la ULL. Principalmente, dispone de los valores obtenidos a partir del cruce de datos administrativos facilitados por los organismos oficiales con competencias en este \u00e1mbito (afiliaciones, demandas de empleo, padr\u00f3n de habitantes, \u2026) y, en su caso, de los resultados del seguimiento de las personas egresadas realizado a trav\u00e9s de las encuestas institucionales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los&nbsp;<strong>resultados de inserci\u00f3n laboral<\/strong>&nbsp;se pueden consultar a continuaci\u00f3n:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Cuadro de mandos de indicadores de Inserci\u00f3n Laboral:\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/app.powerbi.com\/view?r=eyJrIjoiMjc3OThiMzEtYmM2Zi00YTVmLWFlYTgtYTE2NjI4ZTUwNTUyIiwidCI6IjMyOGJkMzc4LTJiNDItNDAyMS05ODQyLTgyN2FiNmU4M2Y0ZiIsImMiOjh9&amp;pageName=f0e379600160184cc00a\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">Datos administrativos<\/a>\u00a0(Canarias: ULL-ISTAC)<\/li>\n\n\n\n<li><a href=\"https:\/\/app.powerbi.com\/view?r=eyJrIjoiZTAzMDE2YTYtMDYwMS00YTUwLTk3MWMtNWNmMTIyNzFhNGUwIiwidCI6IjMyOGJkMzc4LTJiNDItNDAyMS05ODQyLTgyN2FiNmU4M2Y0ZiIsImMiOjh9&amp;pageName=e51a167960ac80c251e1\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">Datos encuesta de egreso<\/a>\u00a0(ULL)<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Otras fuentes de informaci\u00f3n:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www3.gobiernodecanarias.org\/accuee\/evalapp\/webaccuee\/insercion_laboral\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">Estad\u00edsticas de Inserci\u00f3n Laboral en estudios universitarios<\/a>\u00a0(Canarias:\u00a0<a href=\"https:\/\/www3.gobiernodecanarias.org\/educacion\/accuee\/universitario\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">ACCUEE<\/a>\u00a0\u2013\u00a0<a href=\"https:\/\/www.gobiernodecanarias.org\/istac\/temas_estadisticos\/empleo\/\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">ISTAC<\/a>)<\/li>\n\n\n\n<li>Estad\u00edsticas de Inserci\u00f3n Laboral de egresados\u00a0universitarios (Nacional: Grados y M\u00e1steres)\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.ciencia.gob.es\/Ministerio\/Estadisticas\/SIIU\/Afiliacion\/InfografiaEASSEU.html\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">Comparativa nivel \u00e1mbito de estudios<\/a>\u00a0(<a href=\"https:\/\/www.ciencia.gob.es\/Ministerio\/Estadisticas\/SIIU\/Afiliacion.html\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">SIIU<\/a>)<\/li>\n\n\n\n<li><a href=\"https:\/\/www.ciencia.gob.es\/qedu.html\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">Comparativa nivel titulaci\u00f3n<\/a>\u00a0(<a href=\"https:\/\/www.ciencia.gob.es\/Universidades\/QEDU.html\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">QEDU<\/a>)<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Los programas relacionados con&nbsp;<strong>orientaci\u00f3n<\/strong>&nbsp;<strong>profesional<\/strong>, el<strong>&nbsp;emprendimiento&nbsp;<\/strong>y la&nbsp;<strong>inserci\u00f3n laboral&nbsp;<\/strong>(Bolsas de trabajo, becas, etc.) pueden consultarse en la web:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.ull.es\/observatorio-formacion-empleo\/\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">Observatorio de Formaci\u00f3n y Empleo<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/fg.ull.es\/empleo\/\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">Agencia Universitaria de Empleo<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/sede.fg.ull.es\/es\/empleo\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">Oferta de Empleo, Becas y Pr\u00e1cticas<\/a><\/li>\n<\/ul>\n<\/div><\/div><\/div>\n<\/details>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-53ec762\" data-v=\"4\" data-block-id=\"53ec762\"><style>.stk-53ec762-inner-blocks{row-gap:0px !important;}.stk-53ec762 {padding-top:0px !important;padding-right:0px !important;padding-bottom:0px !important;padding-left:0px !important;}@media screen and (min-width: 768px){.stk-53ec762 {flex:var(--stk-flex-grow, 1) 1 33.3% !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-53ec762-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-53ec762-inner-blocks\">\n\n<ul class=\"widget-box\">\n<li class='contacto-header'>Informaci\u00f3n de contacto<\/li><li><i class=\"fa fa-map-marker\"><\/i> Avda. Astrof\u00edsico Francisco S\u00e1nchez, SN. Edificio Calabaza \u2013 AN.2D Apdo. 456 38200 San Crist\u00f3bal de La Laguna<\/li><li><i class=\"fa fa-envelope\"><\/i>  <a href=mailto:doctorado.islasatlanticas@ull.es>doctorado.islasatlanticas@ull.es<\/a><\/li><li><i class=\"fa fa-calendar\"><\/i><a href=\"http:\/\/citaprevia.ull.es\/index.php?s=edpo\"> Cita previa<\/a><\/li>\n<\/ul>\n\n\n<\/div><\/div><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Indicadores y resultados del t\u00edtulo Tasas de rendimiento acad\u00e9mico Datos extra\u00eddos del sistema de informaci\u00f3n de la ULL y resultados previstos de la memoria de verificaci\u00f3n\/modificaci\u00f3n del t\u00edtulo. EVOLUCI\u00d3N DE TASAS [%, N] PD en en Islas Atl\u00e1nticas: Historia, Patrimonio y Marco Jur\u00eddico Institucional Previsi\u00f3n Memoria Verificaci\u00f3n Curso 16-17 Curso 17-18 Curso 18-19 Curso 19-20&#8230;<\/p>\n","protected":false},"author":8,"featured_media":0,"parent":84,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/template-frontpage.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-188","page","type-page","status-publish","hentry"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 20:29:29","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.ull.es\/doctorados\/islas-atlanticas\/fr\/wp-json\/wp\/v2\/pages\/188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ull.es\/doctorados\/islas-atlanticas\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ull.es\/doctorados\/islas-atlanticas\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ull.es\/doctorados\/islas-atlanticas\/fr\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ull.es\/doctorados\/islas-atlanticas\/fr\/wp-json\/wp\/v2\/comments?post=188"}],"version-history":[{"count":18,"href":"https:\/\/www.ull.es\/doctorados\/islas-atlanticas\/fr\/wp-json\/wp\/v2\/pages\/188\/revisions"}],"predecessor-version":[{"id":403,"href":"https:\/\/www.ull.es\/doctorados\/islas-atlanticas\/fr\/wp-json\/wp\/v2\/pages\/188\/revisions\/403"}],"up":[{"embeddable":true,"href":"https:\/\/www.ull.es\/doctorados\/islas-atlanticas\/fr\/wp-json\/wp\/v2\/pages\/84"}],"wp:attachment":[{"href":"https:\/\/www.ull.es\/doctorados\/islas-atlanticas\/fr\/wp-json\/wp\/v2\/media?parent=188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}