{"id":19,"date":"2018-02-22T11:02:50","date_gmt":"2018-02-22T11:02:50","guid":{"rendered":"http:\/\/localhost\/ull\/doctorados\/?page_id=19"},"modified":"2025-08-20T10:49:30","modified_gmt":"2025-08-20T10:49:30","slug":"descripcion-del-titulo","status":"publish","type":"page","link":"https:\/\/www.ull.es\/doctorados\/islas-atlanticas\/informacion-academica\/descripcion-del-titulo\/","title":{"rendered":"Descripci\u00f3n del t\u00edtulo"},"content":{"rendered":"\n<div class=\"wp-block-stackable-columns alignfull stk-block-columns stk-block stk-2314a6b\" data-block-id=\"2314a6b\"><style>.stk-2314a6b {padding-bottom:0px !important;margin-top:-100px !important;margin-bottom:0px !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-2314a6b-column alignfull\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-1d1764d\" data-v=\"4\" data-block-id=\"1d1764d\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-1d1764d-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-1d1764d-inner-blocks\"><style id=\"depicter-1-inline-pre-css\">\n\n.depicter-1:not(.depicter-ready){\n\theight:450px;\n}\n\n\/***** Tablet *****\/\n@media screen and (max-width: 1024px){\n\n.depicter-1:not(.depicter-ready){\n\theight:700px;\n}\n\n}\n\/***** Mobile *****\/\n@media screen and (max-width: 767px){\n\n.depicter-1:not(.depicter-ready){\n\theight:360px;\n}\n\n}\n<\/style>\n<div id=\"depicter-1\" class=\"depicter depicter-document depicter-revert depicter-1 depicter-layout-fullwidth\">\n\n<div class=\"depicter-loading-container depicter-loading dotFlashing-dark\"><div class=\"depicter-loading-dark depicter-dot-flashing\">\n   <span><\/span>\n   <span><\/span>\n   <span><\/span>\n<\/div>\n<\/div>\n<div id=\"depicter-1-section-1\" class=\"depicter-section depicter-1-section-1\" data-name=\"Section 1\" data-type=\"section\" data-local-id=\"section-1\">\n<picture class=\"depicter-bg\">\n<source data-depicter-srcset=\"https:\/\/www.ull.es\/doctorados\/islas-atlanticas\/wp-content\/uploads\/sites\/13\/2025\/05\/Headers-Doctorados_Doctorado-Islas-Atlanticas-768x248.jpg, https:\/\/www.ull.es\/doctorados\/islas-atlanticas\/wp-content\/uploads\/sites\/13\/2025\/05\/Headers-Doctorados_Doctorado-Islas-Atlanticas.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(max-width: 1024px)\" \/>\n\n<source data-depicter-srcset=\"https:\/\/www.ull.es\/doctorados\/islas-atlanticas\/wp-content\/uploads\/sites\/13\/2025\/05\/Headers-Doctorados_Doctorado-Islas-Atlanticas.jpg, https:\/\/www.ull.es\/doctorados\/islas-atlanticas\/wp-content\/uploads\/sites\/13\/2025\/05\/Headers-Doctorados_Doctorado-Islas-Atlanticas-2000x645.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(min-width: 1025px)\" \/>\n<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-ken-burns=\"false\" data-tablet-ken-burns=\"false\" data-mobile-ken-burns=\"false\" alt=\"\" data-depicter-src=\"https:\/\/www.ull.es\/doctorados\/islas-atlanticas\/wp-content\/uploads\/sites\/13\/2025\/05\/Headers-Doctorados_Doctorado-Islas-Atlanticas.jpg\" data-object-fit=\"custom,custom,\" data-object-position=\"center top,,\" data-crop=\"{&apos;focalPoint&apos;:{&apos;x&apos;:0.5,&apos;y&apos;:0.5},&apos;mediaSize&apos;:{&apos;width&apos;:1395.3488372093024736386723816394805908203125,&apos;height&apos;:450}}\" data-tablet-crop=\"{&apos;focalPoint&apos;:{&apos;x&apos;:0.5,&apos;y&apos;:0.5},&apos;mediaSize&apos;:{&apos;width&apos;:2170.54263565891460530110634863376617431640625,&apos;height&apos;:700}}\" data-mobile-crop=\"{&apos;focalPoint&apos;:{&apos;x&apos;:0.5,&apos;y&apos;:0.5},&apos;mediaSize&apos;:{&apos;width&apos;:2294.57364341085258274688385426998138427734375,&apos;height&apos;:740}}\" \/>\n<\/picture>\n\n\n<h1 id=\"depicter-1-element-5\" class=\"depicter-element depicter-layer depicter-1-element-5\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 2\" data-local-id=\"element-5\" data-offset=\"x:0px;y:139px;origin:tl\" data-tablet-offset=\"x:215px;y:194px;origin:tl\" data-mobile-offset=\"x:29px;y:102px;origin:tl\" data-width=\"1200px,auto,348px\" data-height=\"auto,auto,auto\" data-responsive-scale=\"true,,\">Programa de Doctorado en Islas Atl\u00e1nticas<\/h1>\n\n<div id=\"depicter-1-element-10\" class=\"depicter-element depicter-layer depicter-1-element-10\" data-type=\"shape\" data-wrap=\"true\" data-name=\"Shape 1\" data-local-id=\"element-10\" data-offset=\"x:0px;y:312px;origin:tl\" data-tablet-offset=\"x:215px;y:361px;origin:tl\" data-mobile-offset=\"x:29px;y:301px;origin:tl\" data-width=\"1171px,647px,282px\" data-height=\"8px,8px,8px\" data-responsive-scale=\"true,,\"><\/div>\n<\/div>\n<\/div>\n<script>\n(window.depicterSetups = window.depicterSetups || []).push(function(){\n\tDepicter.basePath = 'https:\/\/www.ull.es\/doctorados\/islas-atlanticas\/wp-content\/plugins\/depicter\/resources\/scripts\/player\/';\n\tconst dpPlayer = Depicter.setup('.depicter-1',\n\t\t{\"width\":[\"1200\",\"1024\",\"360\"],\"height\":[\"450\",\"700\",\"360\"],\"view\":\"basic\",\"keepAspectRatio\":true,\"preload\":0,\"layout\":\"fullwidth\",\"rtl\":false,\"initAfterAppear\":false,\"ajaxApiUrl\":\"https:\\\/\\\/www.ull.es\\\/doctorados\\\/islas-atlanticas\\\/wp-admin\\\/admin-ajax.php\",\"mouseSwipe\":true,\"touchSwipe\":true,\"useWatermark\":false}\n\t);\n});\n<\/script><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns alignfull stk-block-columns stk--hide-mobile stk-block stk-6394276 stk-block-background\" data-block-id=\"6394276\"><style>.stk-6394276 {background-color:#f33f4e !important;padding-top:10px !important;margin-bottom:0px !important;}.stk-6394276:before{background-color:#f33f4e !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-6394276-column alignfull\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-8a66885\" data-v=\"4\" data-block-id=\"8a66885\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-8a66885-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-8a66885-inner-blocks\">\n<div class=\"wp-block-stackable-spacer stk-block-spacer stk--no-padding stk-block stk-bc89b3e\" data-block-id=\"bc89b3e\"><style>.stk-bc89b3e {height:0px !important;}<\/style><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns stk-block-columns stk-block stk-8b59b96\" data-block-id=\"8b59b96\"><style>.stk-8b59b96 .stk--block-align-8b59b96{align-items:flex-start !important;}.stk-8b59b96 {margin-top:50px !important;}.stk-8b59b96-column{--stk-columns-spacing:0px !important;--stk-column-gap:50px !important;}<\/style><div class=\"stk-row stk-inner-blocks stk--block-align-8b59b96 stk-block-content stk-content-align stk-8b59b96-column\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-dbb7e15\" data-v=\"4\" data-block-id=\"dbb7e15\"><style>@media screen and (min-width: 768px){.stk-dbb7e15 {flex:var(--stk-flex-grow, 1) 1 66.7% !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-dbb7e15-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-dbb7e15-inner-blocks\">\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-cc0239e\" id=\"complementos-de-formacion\" data-block-id=\"cc0239e\"><style>.stk-cc0239e .stk-block-heading__text{color:#000000 !important;font-weight:500 !important;}<\/style><h1 class=\"stk-block-heading__text has-text-color\">Descripci\u00f3n del t\u00edtulo<\/h1><\/div>\n\n\n\n<table class=\"grales\" width=\"100%\">\n<tbody>\n<tr>\n<td class=\"bluecolumn\">Denominaci\u00f3n del programa:<\/td>\n<td class=\"td1Izda\">Programa de Doctorado en Islas Atl\u00e1nticas: Historia, Patrimonio y Marco Jur\u00eddico Institucional por la Universidad de La Laguna; la <a href=\"http:\/\/www2.ulpgc.es\/index.php?pagina=plan_estudio&amp;ver=wpe002&amp;codTitulacion=6017&amp;tipotitulacion=D\" target=\"_blank\" rel=\"noopener\" target=\"_blank\" rel=\"noopener\">Universidad de Las Palmas de Gran Canaria<\/a>; <a href=\"https:\/\/www.uma.pt\/ensino\/3o-ciclo\/doutoramento-em-ilhas-atlanticas-historia-patrimonio-e-quadro-juridico-institucional-2\/\" target=\"_blank\" rel=\"noopener\" target=\"_blank\" rel=\"noopener\">Universidade da Madeira<\/a>\u00a0(Portugal) y <a href=\"http:\/\/novoportal.uac.pt\/pt-pt\/ensino-doutoramentos#ilhas-atl-nticas-hist-ria-patrim-nio-e-quadro-jur-dico-institucional-\" target=\"_blank\" rel=\"noopener\" target=\"_blank\" rel=\"noopener\">Universidade dos A\u00e7ores<\/a>\u00a0(Portugal)<\/td>\n<\/tr>\n<tr>\n<td class=\"bluecolumn\">Universidades participantes:<\/td>\n<td class=\"td2Izda\"><a href=\"https:\/\/www.ulpgc.es\/\" target=\"_blank\" rel=\"noopener\" target=\"_blank\" rel=\"noopener\">Universidad de Las Palmas de Gran Canaria<\/a> (universidad coordinadora)<\/p>\n<p>Universidad de La Laguna<\/p>\n<p><a href=\"https:\/\/www.uma.pt\/\" target=\"_blank\" rel=\"noopener\" target=\"_blank\" rel=\"noopener\">Universidade da Madeira<\/a><\/p>\n<p><a href=\"http:\/\/www.uac.pt\/pt-pt\" target=\"_blank\" rel=\"noopener\" target=\"_blank\" rel=\"noopener\">Universidade dos A\u00e7ores<\/a><\/td>\n<\/tr>\n<tr>\n<td class=\"bluecolumn\">Lugar de impartici\u00f3n:<\/td>\n<td class=\"td1Izda\"><a href=\"https:\/\/www.ull.es\/centros\/facultad-humanidades\/\" target=\"_blank\" rel=\"noopener\" target=\"_blank\" rel=\"noopener\">Facultad de Humanidades.<\/a> <a href=\"https:\/\/www.ull.es\/centros\/facultad-humanidades\/informacion-general\/#seccion-geografia-historia\" target=\"_blank\" rel=\"noopener\" target=\"_blank\" rel=\"noopener\">Secci\u00f3n de Geograf\u00eda e Historia<\/a> de la Universidad de La Laguna<\/td>\n<\/tr>\n<tr>\n<td class=\"bluecolumn\" width=\"30%\">Internacional:<\/td>\n<td class=\"td2Izda\" width=\"70%\">S\u00ed<\/td>\n<\/tr>\n<tr>\n<td class=\"bluecolumn\">Fecha de implantaci\u00f3n:<\/td>\n<td class=\"td1Izda\">2014 \/ 2015<\/td>\n<\/tr>\n<tr>\n<td class=\"bluecolumn\">Plazas ofertadas:<\/td>\n<td class=\"td2Izda\">10<\/td>\n<\/tr>\n<tr>\n<td class=\"bluecolumn\">Idiomas:<\/td>\n<td class=\"td1Izda\">Espa\u00f1ol y Portugu\u00e9s<\/td>\n<\/tr>\n<tr>\n<td class=\"bluecolumn\">\u00d3rgano responsable:<\/td>\n<td class=\"td2Izda\"><a href=\"https:\/\/www.ull.es\/centros\/escuela-doctorado-estudios-posgrado\/\" target=\"_blank\" rel=\"noopener\" target=\"_blank\" rel=\"noopener\">Escuela de Doctorado y Estudios de Posgrado<\/a><\/td>\n<\/tr>\n<tr>\n<td class=\"bluecolumn\">Justificaci\u00f3n del t\u00edtulo<\/td>\n<td class=\"td1Izda\"><a href=\"https:\/\/www.ull.es\/doctorados\/islas-atlanticas\/justificacion-del-titulo\/\" target=\"_blank\" rel=\"noopener\">Acceso a la justificaci\u00f3n<\/a><\/td>\n<\/tr>\n<tr>\n<td class=\"bluecolumn\">Entidades participantes<\/td>\n<td class=\"td1Izda\"><a href=\"https:\/\/www.ull.es\/doctorados\/islas-atlanticas\/entidades-participantes\/\" target=\"_blank\" rel=\"noopener\">Consultar entidades participantes<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-53ec762\" data-v=\"4\" data-block-id=\"53ec762\"><style>.stk-53ec762-inner-blocks{row-gap:0px !important;}.stk-53ec762 {padding-top:0px !important;padding-right:0px !important;padding-bottom:0px !important;padding-left:0px !important;}@media screen and (min-width: 768px){.stk-53ec762 {flex:var(--stk-flex-grow, 1) 1 33.3% !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-53ec762-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-53ec762-inner-blocks\">\n\n<ul class=\"widget-box\">\n<li class='contacto-header'>Informaci\u00f3n de contacto<\/li><li><i class=\"fa fa-map-marker\"><\/i> Avda. Astrof\u00edsico Francisco S\u00e1nchez, SN. Edificio Calabaza \u2013 AN.2D Apdo. 456 38200 San Crist\u00f3bal de La Laguna<\/li><li><i class=\"fa fa-envelope\"><\/i>  <a href=mailto:doctorado.islasatlanticas@ull.es>doctorado.islasatlanticas@ull.es<\/a><\/li><li><i class=\"fa fa-calendar\"><\/i><a href=\"http:\/\/citaprevia.ull.es\/index.php?s=edpo\"> Cita previa<\/a><\/li>\n<\/ul>\n\n\n<\/div><\/div><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Descripci\u00f3n del t\u00edtulo Denominaci\u00f3n del programa: Programa de Doctorado en Islas Atl\u00e1nticas: Historia, Patrimonio y Marco Jur\u00eddico Institucional por la Universidad de La Laguna; la Universidad de Las Palmas de Gran Canaria; Universidade da Madeira\u00a0(Portugal) y Universidade dos A\u00e7ores\u00a0(Portugal) Universidades participantes: Universidad de Las Palmas de Gran Canaria (universidad coordinadora) Universidad de La Laguna Universidade&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":17,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/template-frontpage.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-19","page","type-page","status-publish","hentry"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 21:12:23","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.ull.es\/doctorados\/islas-atlanticas\/wp-json\/wp\/v2\/pages\/19","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ull.es\/doctorados\/islas-atlanticas\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ull.es\/doctorados\/islas-atlanticas\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ull.es\/doctorados\/islas-atlanticas\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ull.es\/doctorados\/islas-atlanticas\/wp-json\/wp\/v2\/comments?post=19"}],"version-history":[{"count":10,"href":"https:\/\/www.ull.es\/doctorados\/islas-atlanticas\/wp-json\/wp\/v2\/pages\/19\/revisions"}],"predecessor-version":[{"id":385,"href":"https:\/\/www.ull.es\/doctorados\/islas-atlanticas\/wp-json\/wp\/v2\/pages\/19\/revisions\/385"}],"up":[{"embeddable":true,"href":"https:\/\/www.ull.es\/doctorados\/islas-atlanticas\/wp-json\/wp\/v2\/pages\/17"}],"wp:attachment":[{"href":"https:\/\/www.ull.es\/doctorados\/islas-atlanticas\/wp-json\/wp\/v2\/media?parent=19"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}