{"id":88,"date":"2018-02-22T14:20:39","date_gmt":"2018-02-22T14:20:39","guid":{"rendered":"http:\/\/www.ull.es\/doctorados\/islas-atlanticas\/?page_id=88"},"modified":"2025-08-20T10:52:56","modified_gmt":"2025-08-20T10:52:56","slug":"documentacion-evaluacion-titulo","status":"publish","type":"page","link":"https:\/\/www.ull.es\/doctorados\/islas-atlanticas\/calidad\/documentacion-evaluacion-titulo\/","title":{"rendered":"Documentaci\u00f3n de evaluaci\u00f3n del t\u00edtulo"},"content":{"rendered":"\n<div class=\"wp-block-stackable-columns alignfull stk-block-columns stk-block stk-2314a6b\" data-block-id=\"2314a6b\"><style>.stk-2314a6b {padding-bottom:0px !important;margin-top:-100px !important;margin-bottom:0px !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-2314a6b-column alignfull\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-1d1764d\" data-v=\"4\" data-block-id=\"1d1764d\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-1d1764d-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-1d1764d-inner-blocks\"><style id=\"depicter-1-inline-pre-css\">\n\n.depicter-1:not(.depicter-ready){\n\theight:450px;\n}\n\n\/***** Tablet *****\/\n@media screen and (max-width: 1024px){\n\n.depicter-1:not(.depicter-ready){\n\theight:700px;\n}\n\n}\n\/***** Mobile *****\/\n@media screen and (max-width: 767px){\n\n.depicter-1:not(.depicter-ready){\n\theight:360px;\n}\n\n}\n<\/style>\n<div id=\"depicter-1\" class=\"depicter depicter-document depicter-revert depicter-1 depicter-layout-fullwidth\">\n\n<div class=\"depicter-loading-container depicter-loading dotFlashing-dark\"><div class=\"depicter-loading-dark depicter-dot-flashing\">\n   <span><\/span>\n   <span><\/span>\n   <span><\/span>\n<\/div>\n<\/div>\n<div id=\"depicter-1-section-1\" class=\"depicter-section depicter-1-section-1\" data-name=\"Section 1\" data-type=\"section\" data-local-id=\"section-1\">\n<picture class=\"depicter-bg\">\n<source data-depicter-srcset=\"https:\/\/www.ull.es\/doctorados\/islas-atlanticas\/wp-content\/uploads\/sites\/13\/2025\/05\/Headers-Doctorados_Doctorado-Islas-Atlanticas-768x248.jpg, https:\/\/www.ull.es\/doctorados\/islas-atlanticas\/wp-content\/uploads\/sites\/13\/2025\/05\/Headers-Doctorados_Doctorado-Islas-Atlanticas.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(max-width: 1024px)\" \/>\n\n<source data-depicter-srcset=\"https:\/\/www.ull.es\/doctorados\/islas-atlanticas\/wp-content\/uploads\/sites\/13\/2025\/05\/Headers-Doctorados_Doctorado-Islas-Atlanticas.jpg, https:\/\/www.ull.es\/doctorados\/islas-atlanticas\/wp-content\/uploads\/sites\/13\/2025\/05\/Headers-Doctorados_Doctorado-Islas-Atlanticas-2000x645.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(min-width: 1025px)\" \/>\n<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-ken-burns=\"false\" data-tablet-ken-burns=\"false\" data-mobile-ken-burns=\"false\" alt=\"\" data-depicter-src=\"https:\/\/www.ull.es\/doctorados\/islas-atlanticas\/wp-content\/uploads\/sites\/13\/2025\/05\/Headers-Doctorados_Doctorado-Islas-Atlanticas.jpg\" data-object-fit=\"custom,custom,\" data-object-position=\"center top,,\" data-crop=\"{&apos;focalPoint&apos;:{&apos;x&apos;:0.5,&apos;y&apos;:0.5},&apos;mediaSize&apos;:{&apos;width&apos;:1395.3488372093024736386723816394805908203125,&apos;height&apos;:450}}\" data-tablet-crop=\"{&apos;focalPoint&apos;:{&apos;x&apos;:0.5,&apos;y&apos;:0.5},&apos;mediaSize&apos;:{&apos;width&apos;:2170.54263565891460530110634863376617431640625,&apos;height&apos;:700}}\" data-mobile-crop=\"{&apos;focalPoint&apos;:{&apos;x&apos;:0.5,&apos;y&apos;:0.5},&apos;mediaSize&apos;:{&apos;width&apos;:2294.57364341085258274688385426998138427734375,&apos;height&apos;:740}}\" \/>\n<\/picture>\n\n\n<h1 id=\"depicter-1-element-5\" class=\"depicter-element depicter-layer depicter-1-element-5\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 2\" data-local-id=\"element-5\" data-offset=\"x:0px;y:139px;origin:tl\" data-tablet-offset=\"x:215px;y:194px;origin:tl\" data-mobile-offset=\"x:29px;y:102px;origin:tl\" data-width=\"1200px,auto,348px\" data-height=\"auto,auto,auto\" data-responsive-scale=\"true,,\">Programa de Doctorado en Islas Atl\u00e1nticas<\/h1>\n\n<div id=\"depicter-1-element-10\" class=\"depicter-element depicter-layer depicter-1-element-10\" data-type=\"shape\" data-wrap=\"true\" data-name=\"Shape 1\" data-local-id=\"element-10\" data-offset=\"x:0px;y:312px;origin:tl\" data-tablet-offset=\"x:215px;y:361px;origin:tl\" data-mobile-offset=\"x:29px;y:301px;origin:tl\" data-width=\"1171px,647px,282px\" data-height=\"8px,8px,8px\" data-responsive-scale=\"true,,\"><\/div>\n<\/div>\n<\/div>\n<script>\n(window.depicterSetups = window.depicterSetups || []).push(function(){\n\tDepicter.basePath = 'https:\/\/www.ull.es\/doctorados\/islas-atlanticas\/wp-content\/plugins\/depicter\/resources\/scripts\/player\/';\n\tconst dpPlayer = Depicter.setup('.depicter-1',\n\t\t{\"width\":[\"1200\",\"1024\",\"360\"],\"height\":[\"450\",\"700\",\"360\"],\"view\":\"basic\",\"keepAspectRatio\":true,\"preload\":0,\"layout\":\"fullwidth\",\"rtl\":false,\"initAfterAppear\":false,\"ajaxApiUrl\":\"https:\\\/\\\/www.ull.es\\\/doctorados\\\/islas-atlanticas\\\/wp-admin\\\/admin-ajax.php\",\"mouseSwipe\":true,\"touchSwipe\":true,\"useWatermark\":false}\n\t);\n});\n<\/script><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns alignfull stk-block-columns stk--hide-mobile stk-block stk-6394276 stk-block-background\" data-block-id=\"6394276\"><style>.stk-6394276 {background-color:#f33f4e !important;padding-top:10px !important;margin-bottom:0px !important;}.stk-6394276:before{background-color:#f33f4e !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-6394276-column alignfull\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-8a66885\" data-v=\"4\" data-block-id=\"8a66885\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-8a66885-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-8a66885-inner-blocks\">\n<div class=\"wp-block-stackable-spacer stk-block-spacer stk--no-padding stk-block stk-bc89b3e\" data-block-id=\"bc89b3e\"><style>.stk-bc89b3e {height:0px !important;}<\/style><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns stk-block-columns stk-block stk-8b59b96\" data-block-id=\"8b59b96\"><style>.stk-8b59b96 .stk--block-align-8b59b96{align-items:flex-start !important;}.stk-8b59b96 {margin-top:50px !important;}.stk-8b59b96-column{--stk-columns-spacing:0px !important;--stk-column-gap:50px !important;}<\/style><div class=\"stk-row stk-inner-blocks stk--block-align-8b59b96 stk-block-content stk-content-align stk-8b59b96-column\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-dbb7e15\" data-v=\"4\" data-block-id=\"dbb7e15\"><style>@media screen and (min-width: 768px){.stk-dbb7e15 {flex:var(--stk-flex-grow, 1) 1 66.7% !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-dbb7e15-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-dbb7e15-inner-blocks\">\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-cc0239e\" id=\"complementos-de-formacion\" data-block-id=\"cc0239e\"><style>.stk-cc0239e .stk-block-heading__text{color:#000000 !important;font-weight:500 !important;}<\/style><h1 class=\"stk-block-heading__text has-text-color\">Documentaci\u00f3n de evaluaci\u00f3n del t\u00edtulo<\/h1><\/div>\n\n\n\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-c5ba493\" data-block-id=\"c5ba493\"><p class=\"stk-block-text__text\">Las titulaciones oficiales de Grado, M\u00e1ster y Doctorado est\u00e1n sometidas, a un modelo de evaluaci\u00f3n dividido en tres fases que conforman su ciclo de vida (ciclo VSMA): ex ante (Verificaci\u00f3n), durante (Seguimiento y Modificaci\u00f3n) y ex post (renovaci\u00f3n de la Acreditaci\u00f3n). Este proceso de evaluaci\u00f3n, revisi\u00f3n y mejora se realiza con el objetivo de garantizar la calidad de las titulaciones y asegurar que se cumple con los requisitos y criterios establecidos en el marco del Espacio Europeo de Educaci\u00f3n Superior (EEES).<\/p><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">El modelo queda recogido en la&nbsp;<a href=\"https:\/\/www.boe.es\/buscar\/act.php?id=BOE-A-2023-7500\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">Ley Org\u00e1nica 2\/2023<\/a>, del Sistema Universitario (LOSU) y en los Reales Decretos de ordenaci\u00f3n de las ense\u00f1anzas universitarias: fundamentalmente el&nbsp;<a href=\"https:\/\/www.boe.es\/buscar\/act.php?id=BOE-A-2021-15781\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">RD 822\/2021<\/a>, por el que se establece la organizaci\u00f3n de las ense\u00f1anzas universitarias y del procedimiento de aseguramiento de su calidad; el&nbsp;<a href=\"https:\/\/www.boe.es\/buscar\/act.php?id=BOE-A-2011-2541\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">RD 99\/2011<\/a>, por el que se regulan las ense\u00f1anzas oficiales de doctorado y el&nbsp;<a href=\"https:\/\/www.boe.es\/buscar\/act.php?id=BOE-A-2021-12613\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">RD 640\/2021<\/a>, de creaci\u00f3n, reconocimiento y autorizaci\u00f3n de universidades y centros universitarios, y acreditaci\u00f3n institucional de centros universitarios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Puede consultarse la documentaci\u00f3n oficial de los procesos de evaluaci\u00f3n del t\u00edtulo que certifica el cumplimiento de los est\u00e1ndares de calidad en los siguientes apartados.<\/p>\n\n\n\n<details class=\"wp-block-stackable-accordion stk-block-accordion stk-inner-blocks stk-block-content stk-block stk-7c390cd is-style-default\" id=\"verificacion\" data-block-id=\"7c390cd\"><style>.stk-7c390cd {border-style:solid !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;margin-bottom:11px !important;}<\/style>\n<summary class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-c927805 stk--container-small stk-block-accordion__heading\" data-v=\"4\" data-block-id=\"c927805\"><style>.stk-c927805 {padding-top:2px !important;padding-right:2px !important;padding-bottom:2px !important;padding-left:2px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-c927805-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-c927805-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-7935446\" data-block-id=\"7935446\"><style>.stk-7935446 .stk-inner-blocks{gap:39px !important;}@media screen and (max-width: 1023px){.stk-7935446 .stk-inner-blocks{gap:39px !important;}}@media screen and (max-width: 767px){.stk-7935446 .stk-inner-blocks{gap:39px !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-icon stk-block-icon stk-block stk-9a468d5\" data-block-id=\"9a468d5\"><style>.stk-9a468d5 .stk--svg-wrapper .stk--inner-svg svg:last-child{height:25px !important;width:25px !important;}.stk-9a468d5 .stk--svg-wrapper .stk--inner-svg svg:last-child, .stk-9a468d5 .stk--svg-wrapper .stk--inner-svg svg:last-child :is(g, path, rect, polygon, ellipse){fill:#f33f4e !important;}<\/style><span class=\"stk--svg-wrapper stk--has-icon2\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-9a468d5\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-9-a-468-d-5-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-9-a-468-d-5-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M256 512A256 256 0 1 0 256 0a256 256 0 1 0 0 512zM369 209L241 337c-9.4 9.4-24.6 9.4-33.9 0l-64-64c-9.4-9.4-9.4-24.6 0-33.9s24.6-9.4 33.9 0l47 47L335 175c9.4-9.4 24.6-9.4 33.9 0s9.4 24.6 0 33.9z\"><\/path><\/svg><\/div><div class=\"stk--inner-svg stk--icon-2\" style=\"display:none\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-9a468d5\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-9-a-468-d-5-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-9-a-468-d-5-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M256 48a208 208 0 1 1 0 416 208 208 0 1 1 0-416zm0 464A256 256 0 1 0 256 0a256 256 0 1 0 0 512zM369 209c9.4-9.4 9.4-24.6 0-33.9s-24.6-9.4-33.9 0l-111 111-47-47c-9.4-9.4-24.6-9.4-33.9 0s-9.4 24.6 0 33.9l64 64c9.4 9.4 24.6 9.4 33.9 0L369 209z\"><\/path><\/svg><\/div><\/span><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-31863c1\" id=\"verificacion-modificacion\" data-block-id=\"31863c1\"><style>.stk-31863c1 .stk-block-heading__text{color:#000000 !important;font-weight:500 !important;font-family:\"ArgentumSans\", Sans-serif !important;}<\/style><h4 class=\"stk-block-heading__text has-text-color\">Verificaci\u00f3n\/ Modificaci\u00f3n<\/h4><\/div>\n<\/div><\/div>\n<\/div><\/div><\/summary>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-5222666 stk-block-accordion__content\" data-v=\"4\" data-block-id=\"5222666\"><style>.stk-5222666 {margin-top:-30px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-5222666-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-5222666-inner-blocks\">\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-8866a8d\" data-block-id=\"8866a8d\"><p class=\"stk-block-text__text\"><strong>Memoria de Verificaci\u00f3n\/Modificaci\u00f3n<\/strong><\/p><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/drive.google.com\/open?id=0Bxi8Rp1_THQzaXZYYmE3bzhWeHM\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">Memoria del Doctorado en Islas Atl\u00e1nticas: Historia, Patrimonio y Marco Jur\u00eddico Institucional<\/a><br><a href=\"https:\/\/www.educacion.gob.es\/ruct\/estudiouniversidad.action?codigoCiclo=SC&amp;codigoEstudio=5601070&amp;actual=universidad\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">Enlace al Registro de Universidades, Centros y T\u00edtulos (RUCT)<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Documentos de tr\u00e1mite: ANECA-Consejo Universidades (Ministerio Educaci\u00f3n)<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/srv.aneca.es\/ListadoTitulos\/sites\/default\/files\/informes\/modificaciones\/InformeFinal_1_5601070_2014.pdf\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">Informe Final Favorable de Verificaci\u00f3n (2014)<\/a><br><a href=\"https:\/\/drive.google.com\/file\/d\/1QBtWucrSKsiy7zp1phZ0jBTOMpfRzBAx\/view?usp=sharing\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">Resoluci\u00f3n de Verificaci\u00f3n del Consejo de Universidades<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Documentos de tr\u00e1mite:&nbsp;ACCUEE-ACECAU (CCAA Canarias)<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/drive.google.com\/open?id=1wO3y0eAbNPHZ1m_L574v5vp5fuepRT3A\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">Informe Definitivo Favorable de Autorizaci\u00f3n de la Implantaci\u00f3n (2014)<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Publicaci\u00f3n Plan de Estudios (BOC-BOE)<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/www.gobiernodecanarias.org\/boc\/2014\/114\/003.html\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">Publicaci\u00f3n BOC (Decreto 62\/2014, de 5 de junio: autorizaci\u00f3n)<\/a><br><a href=\"https:\/\/www.boe.es\/diario_boe\/txt.php?id=BOE-A-2014-10575\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">Publicaci\u00f3n BOE (Resoluci\u00f3n de 2 de octubre de 2014)<\/a><\/p>\n<\/div><\/div><\/div>\n<\/details>\n\n\n\n<details class=\"wp-block-stackable-accordion stk-block-accordion stk-inner-blocks stk-block-content stk-block stk-88a7c9c is-style-default\" id=\"seguimiento\" data-block-id=\"88a7c9c\"><style>.stk-88a7c9c {border-style:solid !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;margin-bottom:10px !important;}<\/style>\n<summary class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-27019df stk--container-small stk-block-accordion__heading\" data-v=\"4\" data-block-id=\"27019df\"><style>.stk-27019df {padding-top:2px !important;padding-right:2px !important;padding-bottom:2px !important;padding-left:2px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-27019df-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-27019df-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-9c9ce7e\" data-block-id=\"9c9ce7e\"><style>.stk-9c9ce7e .stk-inner-blocks{gap:39px !important;}@media screen and (max-width: 1023px){.stk-9c9ce7e .stk-inner-blocks{gap:39px !important;}}@media screen and (max-width: 767px){.stk-9c9ce7e .stk-inner-blocks{gap:39px !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-icon stk-block-icon stk-block stk-61c8ad3\" data-block-id=\"61c8ad3\"><style>.stk-61c8ad3 .stk--svg-wrapper .stk--inner-svg svg:last-child{height:25px !important;width:25px !important;}.stk-61c8ad3 .stk--svg-wrapper .stk--inner-svg svg:last-child, .stk-61c8ad3 .stk--svg-wrapper .stk--inner-svg svg:last-child :is(g, path, rect, polygon, ellipse){fill:#f33f4e !important;}<\/style><span class=\"stk--svg-wrapper stk--has-icon2\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-61c8ad3\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-61-c-8-ad-3-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-61-c-8-ad-3-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 640 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M160 64c0-35.3 28.7-64 64-64H576c35.3 0 64 28.7 64 64V352c0 35.3-28.7 64-64 64H336.8c-11.8-25.5-29.9-47.5-52.4-64H384V320c0-17.7 14.3-32 32-32h64c17.7 0 32 14.3 32 32v32h64V64L224 64v49.1C205.2 102.2 183.3 96 160 96V64zm0 64a96 96 0 1 1 0 192 96 96 0 1 1 0-192zM133.3 352h53.3C260.3 352 320 411.7 320 485.3c0 14.7-11.9 26.7-26.7 26.7H26.7C11.9 512 0 500.1 0 485.3C0 411.7 59.7 352 133.3 352z\"><\/path><\/svg><\/div><div class=\"stk--inner-svg stk--icon-2\" style=\"display:none\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-61c8ad3\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-61-c-8-ad-3-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-61-c-8-ad-3-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 640 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M192 96a48 48 0 1 0 0-96 48 48 0 1 0 0 96zm-8 384V352h16V480c0 17.7 14.3 32 32 32s32-14.3 32-32V192h56 64 16c17.7 0 32-14.3 32-32s-14.3-32-32-32H384V64H576V256H384V224H320v48c0 26.5 21.5 48 48 48H592c26.5 0 48-21.5 48-48V48c0-26.5-21.5-48-48-48H368c-26.5 0-48 21.5-48 48v80H243.1 177.1c-33.7 0-64.9 17.7-82.3 46.6l-58.3 97c-9.1 15.1-4.2 34.8 10.9 43.9s34.8 4.2 43.9-10.9L120 256.9V480c0 17.7 14.3 32 32 32s32-14.3 32-32z\"><\/path><\/svg><\/div><\/span><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-bcb6d4e\" id=\"seguimiento\" data-block-id=\"bcb6d4e\"><style>.stk-bcb6d4e .stk-block-heading__text{color:#000000 !important;font-weight:500 !important;font-family:\"ArgentumSans\", Sans-serif !important;}<\/style><h4 class=\"stk-block-heading__text has-text-color\">Seguimiento<\/h4><\/div>\n<\/div><\/div>\n<\/div><\/div><\/summary>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-76d605c stk-block-accordion__content\" data-v=\"4\" data-block-id=\"76d605c\"><style>.stk-76d605c {margin-top:-30px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-76d605c-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-76d605c-inner-blocks\">\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-287324e\" data-block-id=\"287324e\"><p class=\"stk-block-text__text\">En l\u00ednea con las directrices establecidas a nivel nacional (RD 861\/2010), la Agencia Canaria de Calidad Universitaria y Evaluaci\u00f3n Educativa (ACCUEE) establece el Protocolo de Seguimiento que deben seguir las Titulaciones Oficiales de la Comunidad Aut\u00f3noma Canaria, el cual se centra fundamentalmente en la informaci\u00f3n que las universidades deben publicar y actualizar, y en la importancia del Sistema de Garant\u00eda Interna de Calidad (SGIC) y los mecanismos dise\u00f1ados para realizar el seguimiento de las mismas y su posterior acreditaci\u00f3n.<\/p><\/div>\n<\/div><\/div><\/div>\n<\/details>\n\n\n\n<details class=\"wp-block-stackable-accordion stk-block-accordion stk-inner-blocks stk-block-content stk-block stk-6320006 is-style-default\" id=\"acreditacion\" data-block-id=\"6320006\"><style>.stk-6320006 {border-style:solid !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;margin-bottom:9px !important;}<\/style>\n<summary class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-ae2ad76 stk--container-small stk-block-accordion__heading\" data-v=\"4\" data-block-id=\"ae2ad76\"><style>.stk-ae2ad76 {padding-top:2px !important;padding-right:2px !important;padding-bottom:2px !important;padding-left:2px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-ae2ad76-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-ae2ad76-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-16db2af\" data-block-id=\"16db2af\"><style>.stk-16db2af .stk-inner-blocks{gap:39px !important;}@media screen and (max-width: 1023px){.stk-16db2af .stk-inner-blocks{gap:39px !important;}}@media screen and (max-width: 767px){.stk-16db2af .stk-inner-blocks{gap:39px !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-icon stk-block-icon stk-block stk-38bb3f8\" data-block-id=\"38bb3f8\"><style>.stk-38bb3f8 .stk--svg-wrapper .stk--inner-svg svg:last-child{height:25px !important;width:25px !important;}.stk-38bb3f8 .stk--svg-wrapper .stk--inner-svg svg:last-child, .stk-38bb3f8 .stk--svg-wrapper .stk--inner-svg svg:last-child :is(g, path, rect, polygon, ellipse){fill:#f33f4e !important;}<\/style><span class=\"stk--svg-wrapper stk--has-icon2\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-38bb3f8\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-38-bb-3-f-8-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-38-bb-3-f-8-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 576 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M64 32C28.7 32 0 60.7 0 96V416c0 35.3 28.7 64 64 64H512c35.3 0 64-28.7 64-64V96c0-35.3-28.7-64-64-64H64zm80 256h64c44.2 0 80 35.8 80 80c0 8.8-7.2 16-16 16H80c-8.8 0-16-7.2-16-16c0-44.2 35.8-80 80-80zm-32-96a64 64 0 1 1 128 0 64 64 0 1 1 -128 0zm256-32H496c8.8 0 16 7.2 16 16s-7.2 16-16 16H368c-8.8 0-16-7.2-16-16s7.2-16 16-16zm0 64H496c8.8 0 16 7.2 16 16s-7.2 16-16 16H368c-8.8 0-16-7.2-16-16s7.2-16 16-16zm0 64H496c8.8 0 16 7.2 16 16s-7.2 16-16 16H368c-8.8 0-16-7.2-16-16s7.2-16 16-16z\"><\/path><\/svg><\/div><div class=\"stk--inner-svg stk--icon-2\" style=\"display:none\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-38bb3f8\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-38-bb-3-f-8-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-38-bb-3-f-8-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 576 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M512 80c8.8 0 16 7.2 16 16V416c0 8.8-7.2 16-16 16H64c-8.8 0-16-7.2-16-16V96c0-8.8 7.2-16 16-16H512zM64 32C28.7 32 0 60.7 0 96V416c0 35.3 28.7 64 64 64H512c35.3 0 64-28.7 64-64V96c0-35.3-28.7-64-64-64H64zM208 256a64 64 0 1 0 0-128 64 64 0 1 0 0 128zm-32 32c-44.2 0-80 35.8-80 80c0 8.8 7.2 16 16 16H304c8.8 0 16-7.2 16-16c0-44.2-35.8-80-80-80H176zM376 144c-13.3 0-24 10.7-24 24s10.7 24 24 24h80c13.3 0 24-10.7 24-24s-10.7-24-24-24H376zm0 96c-13.3 0-24 10.7-24 24s10.7 24 24 24h80c13.3 0 24-10.7 24-24s-10.7-24-24-24H376z\"><\/path><\/svg><\/div><\/span><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-a35761a\" id=\"acreditacion\" data-block-id=\"a35761a\"><style>.stk-a35761a .stk-block-heading__text{color:#000000 !important;font-weight:500 !important;font-family:\"ArgentumSans\", Sans-serif !important;}<\/style><h4 class=\"stk-block-heading__text has-text-color\">Acreditaci\u00f3n<\/h4><\/div>\n<\/div><\/div>\n<\/div><\/div><\/summary>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-81ecc51 stk-block-accordion__content\" data-v=\"4\" data-block-id=\"81ecc51\"><style>.stk-81ecc51 {margin-top:-30px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-81ecc51-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-81ecc51-inner-blocks\">\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-7508b1a\" data-block-id=\"7508b1a\"><p class=\"stk-block-text__text\">Dentro del proceso de renovaci\u00f3n de la acreditaci\u00f3n del Programa de Doctorado, y una vez finalizada la fase de evaluaci\u00f3n interna, se procede a la publicaci\u00f3n del Informe de Autoevaluaci\u00f3n (IA) del Programa; un programa coordinado por la ULPGC en el que participan diversas universidades, entre ellas la ULL:<\/p><\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/drive.google.com\/open?id=1huQnmySLZ9gb3UD37_Bwi_Ed7jgmo6Q-\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">Informe de Autoevaluaci\u00f3n del Programa de Doctorado en Islas Atl\u00e1nticas (IA-2019)<\/a><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Como resultado del proceso de Renovaci\u00f3n de la Acreditaci\u00f3n del Programa de Doctorado en t\u00e9rminos FAVORABLES, se procede a la publicaci\u00f3n del Informe Final de Acreditaci\u00f3n (IFA):<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/drive.google.com\/file\/d\/1M9iHfslKAMP_vlu6IO_L_Op48lMN3qa3\/view?usp=sharing\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">Informe Final Favorable de Acreditaci\u00f3n (IFA \u2013 2020)<\/a><\/li>\n<\/ul>\n<\/div><\/div><\/div>\n<\/details>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-53ec762\" data-v=\"4\" data-block-id=\"53ec762\"><style>.stk-53ec762-inner-blocks{row-gap:0px !important;}.stk-53ec762 {padding-top:0px !important;padding-right:0px !important;padding-bottom:0px !important;padding-left:0px !important;}@media screen and (min-width: 768px){.stk-53ec762 {flex:var(--stk-flex-grow, 1) 1 33.3% !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-53ec762-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-53ec762-inner-blocks\">\n\n<ul class=\"widget-box\">\n<li class='contacto-header'>Informaci\u00f3n de contacto<\/li><li><i class=\"fa fa-map-marker\"><\/i> Avda. Astrof\u00edsico Francisco S\u00e1nchez, SN. Edificio Calabaza \u2013 AN.2D Apdo. 456 38200 San Crist\u00f3bal de La Laguna<\/li><li><i class=\"fa fa-envelope\"><\/i>  <a href=mailto:doctorado.islasatlanticas@ull.es>doctorado.islasatlanticas@ull.es<\/a><\/li><li><i class=\"fa fa-calendar\"><\/i><a href=\"http:\/\/citaprevia.ull.es\/index.php?s=edpo\"> Cita previa<\/a><\/li>\n<\/ul>\n\n\n<\/div><\/div><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Documentaci\u00f3n de evaluaci\u00f3n del t\u00edtulo Las titulaciones oficiales de Grado, M\u00e1ster y Doctorado est\u00e1n sometidas, a un modelo de evaluaci\u00f3n dividido en tres fases que conforman su ciclo de vida (ciclo VSMA): ex ante (Verificaci\u00f3n), durante (Seguimiento y Modificaci\u00f3n) y ex post (renovaci\u00f3n de la Acreditaci\u00f3n). Este proceso de evaluaci\u00f3n, revisi\u00f3n y mejora se realiza&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":84,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/template-frontpage.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-88","page","type-page","status-publish","hentry"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 22:10:38","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.ull.es\/doctorados\/islas-atlanticas\/wp-json\/wp\/v2\/pages\/88","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ull.es\/doctorados\/islas-atlanticas\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ull.es\/doctorados\/islas-atlanticas\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ull.es\/doctorados\/islas-atlanticas\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ull.es\/doctorados\/islas-atlanticas\/wp-json\/wp\/v2\/comments?post=88"}],"version-history":[{"count":19,"href":"https:\/\/www.ull.es\/doctorados\/islas-atlanticas\/wp-json\/wp\/v2\/pages\/88\/revisions"}],"predecessor-version":[{"id":393,"href":"https:\/\/www.ull.es\/doctorados\/islas-atlanticas\/wp-json\/wp\/v2\/pages\/88\/revisions\/393"}],"up":[{"embeddable":true,"href":"https:\/\/www.ull.es\/doctorados\/islas-atlanticas\/wp-json\/wp\/v2\/pages\/84"}],"wp:attachment":[{"href":"https:\/\/www.ull.es\/doctorados\/islas-atlanticas\/wp-json\/wp\/v2\/media?parent=88"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}