{"id":21,"date":"2018-02-22T11:07:35","date_gmt":"2018-02-22T11:07:35","guid":{"rendered":"http:\/\/localhost\/ull\/doctorados\/?page_id=21"},"modified":"2018-03-09T08:17:56","modified_gmt":"2018-03-09T08:17:56","slug":"entidades-participantes","status":"publish","type":"page","link":"https:\/\/www.ull.es\/doctorados\/logica-filosofia-ciencia\/en\/entidades-participantes\/","title":{"rendered":"Participating entities"},"content":{"rendered":"<p>[vc_row][vc_column][vc_column_text]<\/p>\n<h1>Entidades participantes<\/h1>\n<p><strong>Colaboraciones con Convenio<\/strong><\/p>\n<ul>\n<li>Universidad de Pittsburgh: Intercambio de Personal P\u00fablico.<\/li>\n<li>Centro Superior de Investigaciones Cient\u00edficas.<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text] Entidades participantes Colaboraciones con Convenio Universidad de Pittsburgh: Intercambio de Personal P\u00fablico. Centro Superior de Investigaciones Cient\u00edficas. [\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-21","page","type-page","status-publish","hentry"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 21:37:36","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.ull.es\/doctorados\/logica-filosofia-ciencia\/en\/wp-json\/wp\/v2\/pages\/21","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ull.es\/doctorados\/logica-filosofia-ciencia\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ull.es\/doctorados\/logica-filosofia-ciencia\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ull.es\/doctorados\/logica-filosofia-ciencia\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ull.es\/doctorados\/logica-filosofia-ciencia\/en\/wp-json\/wp\/v2\/comments?post=21"}],"version-history":[{"count":2,"href":"https:\/\/www.ull.es\/doctorados\/logica-filosofia-ciencia\/en\/wp-json\/wp\/v2\/pages\/21\/revisions"}],"predecessor-version":[{"id":153,"href":"https:\/\/www.ull.es\/doctorados\/logica-filosofia-ciencia\/en\/wp-json\/wp\/v2\/pages\/21\/revisions\/153"}],"wp:attachment":[{"href":"https:\/\/www.ull.es\/doctorados\/logica-filosofia-ciencia\/en\/wp-json\/wp\/v2\/media?parent=21"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}