{"id":76,"date":"2018-02-22T13:37:55","date_gmt":"2018-02-22T13:37:55","guid":{"rendered":"http:\/\/www.ull.es\/doctorados\/logica-filosofia-ciencia\/?page_id=76"},"modified":"2025-08-20T10:57:24","modified_gmt":"2025-08-20T10:57:24","slug":"acceso-admision","status":"publish","type":"page","link":"https:\/\/www.ull.es\/doctorados\/logica-filosofia-ciencia\/en\/informacion-academica\/acceso-admision\/","title":{"rendered":"Access and admission"},"content":{"rendered":"\n<div class=\"wp-block-stackable-columns alignfull stk-block-columns stk-block stk-2314a6b\" data-block-id=\"2314a6b\"><style>.stk-2314a6b {padding-bottom:0px !important;margin-top:-100px !important;margin-bottom:0px !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-2314a6b-column alignfull\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-1d1764d\" data-v=\"4\" data-block-id=\"1d1764d\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-1d1764d-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-1d1764d-inner-blocks\"><style id=\"depicter-1-inline-pre-css\">\n\n.depicter-1:not(.depicter-ready){\n\theight:450px;\n}\n\n\/***** Tablet *****\/\n@media screen and (max-width: 1024px){\n\n.depicter-1:not(.depicter-ready){\n\theight:700px;\n}\n\n}\n\/***** Mobile *****\/\n@media screen and (max-width: 767px){\n\n.depicter-1:not(.depicter-ready){\n\theight:360px;\n}\n\n}\n<\/style>\n<div id=\"depicter-1\" class=\"depicter depicter-document depicter-revert depicter-1 depicter-layout-fullwidth\">\n\n<div class=\"depicter-loading-container depicter-loading dotFlashing-dark\"><div class=\"depicter-loading-dark depicter-dot-flashing\">\n   <span><\/span>\n   <span><\/span>\n   <span><\/span>\n<\/div>\n<\/div>\n<div id=\"depicter-1-section-1\" class=\"depicter-section depicter-1-section-1\" data-name=\"Section 1\" data-type=\"section\" data-local-id=\"section-1\">\n<picture class=\"depicter-bg\">\n<source data-depicter-srcset=\"https:\/\/www.ull.es\/doctorados\/logica-filosofia-ciencia\/wp-content\/uploads\/sites\/14\/2025\/05\/Headers-Doctorados_Doctorado-Logica-y-Filosofia-768x248.jpg, https:\/\/www.ull.es\/doctorados\/logica-filosofia-ciencia\/wp-content\/uploads\/sites\/14\/2025\/05\/Headers-Doctorados_Doctorado-Logica-y-Filosofia.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(max-width: 1024px)\" \/>\n\n<source data-depicter-srcset=\"https:\/\/www.ull.es\/doctorados\/logica-filosofia-ciencia\/wp-content\/uploads\/sites\/14\/2025\/05\/Headers-Doctorados_Doctorado-Logica-y-Filosofia.jpg, https:\/\/www.ull.es\/doctorados\/logica-filosofia-ciencia\/wp-content\/uploads\/sites\/14\/2025\/05\/Headers-Doctorados_Doctorado-Logica-y-Filosofia-2000x645.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(min-width: 1025px)\" \/>\n<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-ken-burns=\"false\" data-tablet-ken-burns=\"false\" data-mobile-ken-burns=\"false\" alt=\"\" data-depicter-src=\"https:\/\/www.ull.es\/doctorados\/logica-filosofia-ciencia\/wp-content\/uploads\/sites\/14\/2025\/05\/Headers-Doctorados_Doctorado-Logica-y-Filosofia.jpg\" data-object-fit=\"custom,custom,\" data-object-position=\"center top,,\" data-crop=\"{&apos;focalPoint&apos;:{&apos;x&apos;:0.5,&apos;y&apos;:0.5},&apos;mediaSize&apos;:{&apos;width&apos;:1395.3488372093024736386723816394805908203125,&apos;height&apos;:450}}\" data-tablet-crop=\"{&apos;focalPoint&apos;:{&apos;x&apos;:0.5,&apos;y&apos;:0.5},&apos;mediaSize&apos;:{&apos;width&apos;:2170.54263565891460530110634863376617431640625,&apos;height&apos;:700}}\" data-mobile-crop=\"{&apos;focalPoint&apos;:{&apos;x&apos;:0.520000000000000017763568394002504646778106689453125,&apos;y&apos;:0.330000000000000015543122344752191565930843353271484375},&apos;mediaSize&apos;:{&apos;width&apos;:2294,&apos;height&apos;:740}}\" \/>\n<\/picture>\n\n\n<h1 id=\"depicter-1-element-5\" class=\"depicter-element depicter-layer depicter-1-element-5\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 2\" data-local-id=\"element-5\" data-offset=\"x:0px;y:140px;origin:tl\" data-tablet-offset=\"x:161px;y:194px;origin:tl\" data-mobile-offset=\"x:28px;y:82px;origin:tl\" data-width=\"1200px,auto,348px\" data-height=\"auto,auto,auto\" data-responsive-scale=\"true,,\">Programa de Doctorado en L\u00f3gica y Filosof\u00eda de la Ciencia<\/h1>\n\n<div id=\"depicter-1-element-10\" class=\"depicter-element depicter-layer depicter-1-element-10\" data-type=\"shape\" data-wrap=\"true\" data-name=\"Shape 1\" data-local-id=\"element-10\" data-offset=\"x:0px;y:317px;origin:tl\" data-tablet-offset=\"x:170px;y:410px;origin:tl\" data-mobile-offset=\"x:28px;y:328px;origin:tl\" data-width=\"1069px,692px,282px\" data-height=\"8px,8px,8px\" data-responsive-scale=\"true,,\"><\/div>\n<\/div>\n<\/div>\n<script>\n(window.depicterSetups = window.depicterSetups || []).push(function(){\n\tDepicter.basePath = 'https:\/\/www.ull.es\/doctorados\/logica-filosofia-ciencia\/wp-content\/plugins\/depicter\/resources\/scripts\/player\/';\n\tconst dpPlayer = Depicter.setup('.depicter-1',\n\t\t{\"width\":[\"1200\",\"1024\",\"360\"],\"height\":[\"450\",\"700\",\"360\"],\"view\":\"basic\",\"keepAspectRatio\":true,\"preload\":0,\"layout\":\"fullwidth\",\"rtl\":false,\"initAfterAppear\":false,\"ajaxApiUrl\":\"https:\\\/\\\/www.ull.es\\\/doctorados\\\/logica-filosofia-ciencia\\\/wp-admin\\\/admin-ajax.php\",\"mouseSwipe\":true,\"touchSwipe\":true,\"useWatermark\":false}\n\t);\n});\n<\/script><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns alignfull stk-block-columns stk--hide-mobile stk-block stk-6394276 stk-block-background\" data-block-id=\"6394276\"><style>.stk-6394276 {background-color:#f33f4e !important;padding-top:10px !important;margin-bottom:0px !important;}.stk-6394276:before{background-color:#f33f4e !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-6394276-column alignfull\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-8a66885\" data-v=\"4\" data-block-id=\"8a66885\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-8a66885-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-8a66885-inner-blocks\">\n<div class=\"wp-block-stackable-spacer stk-block-spacer stk--no-padding stk-block stk-bc89b3e\" data-block-id=\"bc89b3e\"><style>.stk-bc89b3e {height:0px !important;}<\/style><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns stk-block-columns stk-block stk-8b59b96\" data-block-id=\"8b59b96\"><style>.stk-8b59b96 .stk--block-align-8b59b96{align-items:flex-start !important;}.stk-8b59b96 {margin-top:25px !important;}.stk-8b59b96-column{--stk-columns-spacing:0px !important;--stk-column-gap:50px !important;}<\/style><div class=\"stk-row stk-inner-blocks stk--block-align-8b59b96 stk-block-content stk-content-align stk-8b59b96-column\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-dbb7e15\" data-v=\"4\" data-block-id=\"dbb7e15\"><style>@media screen and (min-width: 768px){.stk-dbb7e15 {flex:var(--stk-flex-grow, 1) 1 66.7% !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-dbb7e15-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-dbb7e15-inner-blocks\">\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-cc0239e\" id=\"complementos-de-formacion\" data-block-id=\"cc0239e\"><style>.stk-cc0239e .stk-block-heading__text{color:#000000 !important;font-weight:500 !important;}<\/style><h1 class=\"stk-block-heading__text has-text-color\">Acceso y admisi\u00f3n<\/h1><\/div>\n\n\n\n<details class=\"wp-block-stackable-accordion stk-block-accordion stk-inner-blocks stk-block-content stk-block stk-7c390cd is-style-default\" id=\"sistemas\" data-block-id=\"7c390cd\"><style>.stk-7c390cd {border-style:solid !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;margin-bottom:11px !important;}<\/style>\n<summary class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-c927805 stk--container-small stk-block-accordion__heading\" data-v=\"4\" data-block-id=\"c927805\"><style>.stk-c927805 {padding-top:2px !important;padding-right:2px !important;padding-bottom:2px !important;padding-left:2px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-c927805-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-c927805-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-7935446\" data-block-id=\"7935446\"><style>.stk-7935446 .stk-inner-blocks{gap:39px !important;}@media screen and (max-width: 1023px){.stk-7935446 .stk-inner-blocks{gap:39px !important;}}@media screen and (max-width: 767px){.stk-7935446 .stk-inner-blocks{gap:39px !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-icon stk-block-icon stk-block stk-9a468d5\" data-block-id=\"9a468d5\"><style>.stk-9a468d5 .stk--svg-wrapper .stk--inner-svg svg:last-child{height:25px !important;width:25px !important;}.stk-9a468d5 .stk--svg-wrapper .stk--inner-svg svg:last-child, .stk-9a468d5 .stk--svg-wrapper .stk--inner-svg svg:last-child :is(g, path, rect, polygon, ellipse){fill:#f33f4e !important;}<\/style><span class=\"stk--svg-wrapper stk--has-icon2\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-9a468d5\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-9-a-468-d-5-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-9-a-468-d-5-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M256 512A256 256 0 1 0 256 0a256 256 0 1 0 0 512zM216 336h24V272H216c-13.3 0-24-10.7-24-24s10.7-24 24-24h48c13.3 0 24 10.7 24 24v88h8c13.3 0 24 10.7 24 24s-10.7 24-24 24H216c-13.3 0-24-10.7-24-24s10.7-24 24-24zm40-208a32 32 0 1 1 0 64 32 32 0 1 1 0-64z\"><\/path><\/svg><\/div><div class=\"stk--inner-svg stk--icon-2\" style=\"display:none\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-9a468d5\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-9-a-468-d-5-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-9-a-468-d-5-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 192 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M48 80a48 48 0 1 1 96 0A48 48 0 1 1 48 80zM0 224c0-17.7 14.3-32 32-32H96c17.7 0 32 14.3 32 32V448h32c17.7 0 32 14.3 32 32s-14.3 32-32 32H32c-17.7 0-32-14.3-32-32s14.3-32 32-32H64V256H32c-17.7 0-32-14.3-32-32z\"><\/path><\/svg><\/div><\/span><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-31863c1\" id=\"sistemas-de-informacion-previo\" data-block-id=\"31863c1\"><style>.stk-31863c1 .stk-block-heading__text{color:#000000 !important;font-weight:500 !important;font-family:\"ArgentumSans\", Sans-serif !important;}<\/style><h4 class=\"stk-block-heading__text has-text-color\">Sistemas de informaci\u00f3n previo<\/h4><\/div>\n<\/div><\/div>\n<\/div><\/div><\/summary>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-5222666 stk-block-accordion__content\" data-v=\"4\" data-block-id=\"5222666\"><style>.stk-5222666 {margin-top:-30px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-5222666-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-5222666-inner-blocks\">\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-8866a8d\" data-block-id=\"8866a8d\"><p class=\"stk-block-text__text\">El estudiante potencial puede obtener una informaci\u00f3n precisa sobre el Programa de Doctorado (PD), antes del proceso de matriculaci\u00f3n, a trav\u00e9s de diferentes v\u00edas.<\/p><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Las universidades participantes elaboran anualmente la oferta de titulaciones oficiales seg\u00fan la normativa vigente. Para elaborar la oferta de programas de doctorado se realiza una primera fase de consulta a las comisiones acad\u00e9micas de dichos programas con el fin de determinar el n\u00famero de plazas, cupos para estudiantes con titulaciones extranjeras, as\u00ed como los posibles criterios espec\u00edficos de admisi\u00f3n complementarios a los indicados en la memoria de la titulaci\u00f3n. Estas propuestas ser\u00e1n evaluadas de acuerdo con la normativa de cada universidad y sometidas a la aprobaci\u00f3n de sus \u00f3rganos de gobierno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez aprobada, la oferta de programas de doctorado ser\u00e1 difundida a trav\u00e9s de:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">a) las p\u00e1ginas web de las universidades participantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">b) las escuelas de doctorado correspondientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez determinada la oferta de estudios oficiales, las universidades participantes publican la convocatoria de matr\u00edcula, los calendarios de los distintos procesos de gesti\u00f3n acad\u00e9mica, as\u00ed como otra normativa de aplicaci\u00f3n en los enlaces siguientes:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la p\u00e1gina web institucional los servicios de posgrado y doctorado de las universidades participantes. En los enlaces que se proporcionan a continuaci\u00f3n existe informaci\u00f3n detallada acerca de los plazos y los requisitos exigidos por cada universidad en el momento de la matr\u00edcula.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/doctorado.usal.es\/\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">Universidad de Salamanca<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/www.gobiernodecanarias.org\/boc\/2009\/031\/007.html\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">Universidad de La Laguna&nbsp;<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/www.uv.es\/uvweb\/universidad\/es\/estudios-postgrado\/doctorados\/normativas-1285847058722.html\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">Universitat de Val\u00e8ncia<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La atenci\u00f3n directa se ofrece en:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Universidad de Salamanca . Facultad de Filosof\u00eda; Campus Miguel de Unamuno, 37007 Salamanca;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tel\u00e9fono: +34 923 294 400. Ext.: 3432;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Email:&nbsp;<a href=\"mailto:adm.ffs@usal.es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">adm.ffs@usal.es<\/a>;&nbsp;<a href=\"mailto:elenavm@usal.es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">elenavm@usal.es<\/a>&nbsp;[USAL]<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Universidad de Valladolid . Servicios Centrales, Servicio de Ordenaci\u00f3n Acad\u00e9mica, Posgrado y T\u00edtulos, C\/ Real de Burgos s\/n, Cp: 47011, Valladolid,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tlfn: 98342-3253, Fax: 98318-6397, Email:&nbsp;<a href=\"mailto:servicio.ordenacion.posgrado@uva.es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">servicio.ordenacion.posgrado@uva.es<\/a>&nbsp;[UVa]<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Universidad de Santiago de Compostela . CENTRO DE POSGRADO: Viviendas de los Catedr\u00e1ticos, Avenida de las Ciencias, s\/n , 15782 Santiago de Compostela.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tel\u00e9fono: 00 +34 881 811000 ext.: 14360\/ 14361\/ 14433. Fax: 00 +34 881 814364<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Correo Electr\u00f3nico<a href=\"mailto:%20adm.ffs@usal.es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">:&nbsp;<\/a><a href=\"mailto:cpg@usc.es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">cpg@usc.es<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La gesti\u00f3n administrativa del estudiantado queda excluida de las competencias del CPG.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Universidad de A Coru\u00f1a : Unidade de Estudos Propios de Posgrao, Pavill\u00f3n de Estudantes, Campus de Elvi\u00f1a s\/n; 15071 A Coru\u00f1a.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tfno: +34 981.16.70.00 (Ext. 1964, 1969). Fax: +34 981.16.71.98 (Ext. interna 1195).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">E-mail:&nbsp;<a href=\"mailto:uepp@udc.es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">uepp@udc.es<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Universidad de La Laguna . Centro de Posgrado Universidad de La Laguna. Campus Central. Planta baja. C\/ Pedro Zerolo, s\/n. 38200, La Laguna.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Correo electr\u00f3nico:&nbsp;<a href=\"mailto:doctorado@ull.es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">doctorado@ull.es<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Universitat de Val\u00e8ncia . Centro de Posgrado. Rectorado. Av. Blasco Ib\u00e0\u00f1ez, 13. 46010, Valencia<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tel\u00e9fono doctorado: (34) 9639 83006; fax doctorado: (34) 9638 64977<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Correo electr\u00f3nico:&nbsp;<a href=\"mailto:doctorado@uv.es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">doctorado@uv.es<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Toda esta informaci\u00f3n estar\u00e1 disponible con antelaci\u00f3n al periodo de admisi\u00f3n en los programas de doctorado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el caso de este Programa de Doctorado, la Comisi\u00f3n Acad\u00e9mica divulgar\u00e1 informaci\u00f3n sobre el mismo a trav\u00e9s de:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Jornadas informativas dirigidas a estudiantes de grado y m\u00e1ster en las distintas universidades participantes.<\/li>\n\n\n\n<li>Estimulaci\u00f3n de la captaci\u00f3n de estudiantes con buen expediente a trav\u00e9s de la b\u00fasqueda de financiaci\u00f3n para contratos predoctorales<\/li>\n\n\n\n<li>Redes tem\u00e1ticas: Los interesados podr\u00e1n asimismo obtener la informaci\u00f3n en los boletines y networks de las principales sociedades nacionales e internacionales de filosof\u00eda, l\u00f3gica y filosof\u00eda de la ciencia, filosof\u00eda anal\u00edtica, adonde se remitir\u00e1n para su publicaci\u00f3n anuncios biling\u00fces (espa\u00f1ol e ingl\u00e9s) informativos acerca del PD Dichos anuncios se enviar\u00e1n igualmente a networks especializados en el \u00e1rea, a los departamentos de l\u00f3gica y filosof\u00eda de la ciencia de las principales universidades en Europa, Am\u00e9rica Latina y Filipinas.<\/li>\n\n\n\n<li>P\u00e1gina&nbsp;<a href=\"https:\/\/doctoradologifici.usal.es\/\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">web propia<\/a>:<\/li>\n\n\n\n<li>A trav\u00e9s de los listados actualizados con los correos electr\u00f3nicos de egresados del PD y de otras titulaciones ofrecidas por la universidades firmantes del convenio.<\/li>\n\n\n\n<li>Diversos soportes audiovisuales: entrevistas disponibles en internet con profesorado y estudiantado del Programa de Doctorado, p\u00f3sters, etc.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Perfil de ingreso recomendado:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El programa interuniversitario de doctorado en L\u00f3gica y Filosof\u00eda de la Ciencia se dise\u00f1a con el objeto de atender fundamentalmente a la demanda de los actuales titulados universitarios que deseen recibir una especializaci\u00f3n adicional o formaci\u00f3n investigadora y que haya realizado un m\u00e1ster relacionado con el campo de la l\u00f3gica y la filosof\u00eda de la ciencia, a los estudiantes de sistemas universitarios extranjeros que deseen cursar estudios de doctorado en nuestro pa\u00eds, y a la de profesionales titulados universitarios que decidan actualizar sus conocimientos y destrezas o modificar su perfil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nuestros estudiantes ser\u00e1n previsiblemente:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Titulados en Filosof\u00eda (graduados que hayan realizado un m\u00e1ster af\u00edn al PD o Doctores que deseen variar su perfil).<\/li>\n\n\n\n<li>Titulados en el \u00e1rea de las ciencias naturales, matem\u00e1ticas e inform\u00e1tica (Graduados o Doctores que hayan realizado un m\u00e1ster af\u00edn al PD).<\/li>\n\n\n\n<li>Titulados en el \u00e1rea de las ciencias sociales y filolog\u00edas (Graduados o Doctores que hayan realizado un m\u00e1ster af\u00edn al PD).<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Es necesario que el investigador en formaci\u00f3n pueda leer correctamente textos filos\u00f3ficos y cient\u00edficos al menos en espa\u00f1ol e ingl\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Acogida y orientaci\u00f3n a los estudiantes de nuevo ingreso:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La informaci\u00f3n relativa a la preinscripci\u00f3n, matr\u00edcula e incorporaci\u00f3n al PD podr\u00e1 encontrarse en las webs oficiales de cualquiera de las universidades firmantes del convenio, entre ellas, la de la universidad coordinadora:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Universitat de Val\u00e8ncia<\/li>\n\n\n\n<li>Universidad de Salamanca<\/li>\n\n\n\n<li>Universidad de Santiago de Compostela<\/li>\n\n\n\n<li>Universidad de la Laguna<\/li>\n\n\n\n<li>Universidad de Valladolid<\/li>\n\n\n\n<li>Universidad de A Coru\u00f1a<\/li>\n<\/ul>\n<\/div><\/div><\/div>\n<\/details>\n\n\n\n<details class=\"wp-block-stackable-accordion stk-block-accordion stk-inner-blocks stk-block-content stk-block stk-88a7c9c is-style-default\" id=\"requisitos\" data-block-id=\"88a7c9c\"><style>.stk-88a7c9c {border-style:solid !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;margin-bottom:10px !important;}<\/style>\n<summary class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-27019df stk--container-small stk-block-accordion__heading\" data-v=\"4\" data-block-id=\"27019df\"><style>.stk-27019df {padding-top:2px !important;padding-right:2px !important;padding-bottom:2px !important;padding-left:2px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-27019df-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-27019df-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-9c9ce7e\" data-block-id=\"9c9ce7e\"><style>.stk-9c9ce7e .stk-inner-blocks{gap:39px !important;}@media screen and (max-width: 1023px){.stk-9c9ce7e .stk-inner-blocks{gap:39px !important;}}@media screen and (max-width: 767px){.stk-9c9ce7e .stk-inner-blocks{gap:39px !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-icon stk-block-icon stk-block stk-61c8ad3\" data-block-id=\"61c8ad3\"><style>.stk-61c8ad3 .stk--svg-wrapper .stk--inner-svg svg:last-child{height:25px !important;width:25px !important;}.stk-61c8ad3 .stk--svg-wrapper .stk--inner-svg svg:last-child, .stk-61c8ad3 .stk--svg-wrapper .stk--inner-svg svg:last-child :is(g, path, rect, polygon, ellipse){fill:#f33f4e !important;}<\/style><span class=\"stk--svg-wrapper stk--has-icon2\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-61c8ad3\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-61-c-8-ad-3-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-61-c-8-ad-3-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M256 512A256 256 0 1 0 256 0a256 256 0 1 0 0 512zM169.8 165.3c7.9-22.3 29.1-37.3 52.8-37.3h58.3c34.9 0 63.1 28.3 63.1 63.1c0 22.6-12.1 43.5-31.7 54.8L280 264.4c-.2 13-10.9 23.6-24 23.6c-13.3 0-24-10.7-24-24V250.5c0-8.6 4.6-16.5 12.1-20.8l44.3-25.4c4.7-2.7 7.6-7.7 7.6-13.1c0-8.4-6.8-15.1-15.1-15.1H222.6c-3.4 0-6.4 2.1-7.5 5.3l-.4 1.2c-4.4 12.5-18.2 19-30.6 14.6s-19-18.2-14.6-30.6l.4-1.2zM224 352a32 32 0 1 1 64 0 32 32 0 1 1 -64 0z\"><\/path><\/svg><\/div><div class=\"stk--inner-svg stk--icon-2\" style=\"display:none\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-61c8ad3\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-61-c-8-ad-3-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-61-c-8-ad-3-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M464 256A208 208 0 1 0 48 256a208 208 0 1 0 416 0zM0 256a256 256 0 1 1 512 0A256 256 0 1 1 0 256zm169.8-90.7c7.9-22.3 29.1-37.3 52.8-37.3h58.3c34.9 0 63.1 28.3 63.1 63.1c0 22.6-12.1 43.5-31.7 54.8L280 264.4c-.2 13-10.9 23.6-24 23.6c-13.3 0-24-10.7-24-24V250.5c0-8.6 4.6-16.5 12.1-20.8l44.3-25.4c4.7-2.7 7.6-7.7 7.6-13.1c0-8.4-6.8-15.1-15.1-15.1H222.6c-3.4 0-6.4 2.1-7.5 5.3l-.4 1.2c-4.4 12.5-18.2 19-30.6 14.6s-19-18.2-14.6-30.6l.4-1.2zM224 352a32 32 0 1 1 64 0 32 32 0 1 1 -64 0z\"><\/path><\/svg><\/div><\/span><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-bcb6d4e\" id=\"requisitos-de-acceso\" data-block-id=\"bcb6d4e\"><style>.stk-bcb6d4e .stk-block-heading__text{color:#000000 !important;font-weight:500 !important;font-family:\"ArgentumSans\", Sans-serif !important;}<\/style><h4 class=\"stk-block-heading__text has-text-color\">Requisitos de acceso<\/h4><\/div>\n<\/div><\/div>\n<\/div><\/div><\/summary>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-76d605c stk-block-accordion__content\" data-v=\"4\" data-block-id=\"76d605c\"><style>.stk-76d605c {margin-top:-30px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-76d605c-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-76d605c-inner-blocks\">\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-287324e\" data-block-id=\"287324e\"><p class=\"stk-block-text__text\"><strong>Requisitos generales:<\/strong><\/p><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">1. Los requisitos para el acceso a los programas de doctorado vienen establecidos por el Real Decreto 99\/2011, de 28 de enero, por el que se regulan las ense\u00f1anzas oficiales de doctorado, que establece que, para acceder a las mismas, ser\u00e1 necesario estar en posesi\u00f3n de los t\u00edtulos oficiales espa\u00f1oles de Grado, o equivalente, y de M\u00e1ster Universitario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n puede accederse a ellas si se cumple alguno de estos otros requisitos:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2013 Estar en posesi\u00f3n de un t\u00edtulo oficial espa\u00f1ol, o equivalente, y haber obtenido la Suficiencia Investigadora (regulada en el Real Decreto 185\/1985, de 23 de enero).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2013 Estar en posesi\u00f3n de un t\u00edtulo oficial espa\u00f1ol, o equivalente, y haber obtenido Diploma de Estudios Avanzados (de acuerdo al Real Decreto 778\/1998, de 30 de abril).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2013 Estar en posesi\u00f3n de otro t\u00edtulo espa\u00f1ol de Doctor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2. Los estudiantes que est\u00e9n en posesi\u00f3n de un t\u00edtulo de educaci\u00f3n superior extranjero y pretendan cursar en Espa\u00f1a estudios de Doctorado podr\u00e1n acceder a estos previa homologaci\u00f3n de aquel al t\u00edtulo espa\u00f1ol que habilite para dicho acceso, de conformidad con el procedimiento previsto en la normativa vigente al respecto. No obstante lo anterior, las universidades podr\u00e1n admitir a titulados conforme a sistemas educativos extranjeros sin necesidad de la homologaci\u00f3n de sus t\u00edtulos, previa comprobaci\u00f3n de que aquellos acreditan un nivel de formaci\u00f3n equivalente a los correspondientes t\u00edtulos espa\u00f1oles de Grado y de M\u00e1ster y que facultan en el pa\u00eds expedidor del t\u00edtulo para el acceso a estudios de Doctorado. Esta admisi\u00f3n no implicar\u00e1, en ning\u00fan caso, la homologaci\u00f3n del t\u00edtulo extranjero de que est\u00e9 en posesi\u00f3n el interesado, ni su reconocimiento a otros efectos que el de cursar los estudios de Doctorado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">3. Los estudiantes podr\u00e1n acceder a cualquier programa oficial de Doctorado relacionado o no cient\u00edficamente con su curr\u00edculum universitario, y en cualquier universidad, previa admisi\u00f3n efectuada por el \u00f3rgano responsable del indicado programa, conforme a los requisitos de admisi\u00f3n espec\u00edficos y criterios de valoraci\u00f3n de m\u00e9ritos que, en su caso, establezca la universidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el caso de estudiantes extranjeros cuya lengua materna no sea ninguna de las del PD (espa\u00f1ol e ingl\u00e9s) se podr\u00e1 pedir que acrediten un nivel de conocimiento adecuado de dichas lenguas (nivel B1).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los estudiantes de cualquiera de las universidades participantes deber\u00e1n realizar en su universidad una solicitud de inscripci\u00f3n en el PD. Las solicitudes ser\u00e1n remitidas a la Comisi\u00f3n de Coordinaci\u00f3n del PD e ir\u00e1n acompa\u00f1adas de un curr\u00edculum, del expediente acad\u00e9mico y de una carta del interesado explicando sus motivaciones. Asimismo, cuando se trate de universidades que no formen parte del PD, de dos cartas de presentaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Requisitos adicionales:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">a) Acreditar mediante certificado oficial el rendimiento acad\u00e9mico en el Grado o Licenciatura y en el M\u00e1ster de procedencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">b) Presentar ante la Comisi\u00f3n Acad\u00e9mica un breve documento (de extensi\u00f3n m\u00e1xima de tres p\u00e1ginas) en las que se indiquen las razones e intereses investigadores que han motivado la solicitud de ingreso en el programa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Requisitos para los estudiantes que provienen del otro PD que se extingue:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Conforme al Calendario de Extinci\u00f3n de las Ense\u00f1anzas de Doctorado regualdas por el R.D. 778\/1998 impartidas en la UVa (Acuerdo de la Comisi\u00f3n de Doctorado de 13 de enero de 2012 adaptando el aprobado el 15 de junio de 2009), Los estudiantes que en cursos anteriores hayan iniciado sus estudios de doctorado seg\u00fan el R. D. 778\/1998, podr\u00e1n: Matricularse de la Tutela Acad\u00e9mica por la inscripci\u00f3n de la Tesis Doctoral, Presentar y defender la Tesis Doctoral. Se admitir\u00e1n estudiantes procedentes de traslados en la Tutela por inscripci\u00f3n de Tesis Doctoral<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El documento de actividades del doctorando ser\u00e1 sustituido por un certificado de actividades realizadas en el Programa de Doctorado cursado, emitido por el servicio administrativo responsable de doctorado, en el que se incluya, en su caso, el periodo formativo, si el programa lo contemplara.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Perfil de ingreso recomendado:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El programa interuniversitario de doctorado en L\u00f3gica y Filosof\u00eda de la Ciencia se dise\u00f1a con el objeto de atender fundamentalmente a la demanda de los actuales titulados universitarios que deseen recibir una especializaci\u00f3n adicional o formaci\u00f3n investigadora y que haya realizado un m\u00e1ster relacionado con el campo de la l\u00f3gica y la filosof\u00eda de la ciencia, a los estudiantes de sistemas universitarios extranjeros que deseen cursar estudios de doctorado en nuestro pa\u00eds, y a la de profesionales titulados universitarios que decidan actualizar sus conocimientos y destrezas o modificar su perfil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nuestros estudiantes ser\u00e1n previsiblemente:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Titulados en Filosof\u00eda (graduados que hayan realizado un m\u00e1ster af\u00edn al PD o Doctores que deseen variar su perfil).<\/li>\n\n\n\n<li>Titulados en el \u00e1rea de las ciencias naturales, matem\u00e1ticas e inform\u00e1tica (Graduados o Doctores que hayan realizado un m\u00e1ster af\u00edn al PD).<\/li>\n\n\n\n<li>Titulados en el \u00e1rea de las ciencias sociales y filolog\u00edas (Graduados o Doctores que hayan realizado un m\u00e1ster af\u00edn al PD).<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Es necesario que el investigador en formaci\u00f3n pueda leer correctamente textos filos\u00f3ficos y cient\u00edficos al menos en espa\u00f1ol e ingl\u00e9s.<\/p>\n<\/div><\/div><\/div>\n<\/details>\n\n\n\n<details class=\"wp-block-stackable-accordion stk-block-accordion stk-inner-blocks stk-block-content stk-block stk-6320006 is-style-default\" id=\"criterios\" data-block-id=\"6320006\"><style>.stk-6320006 {border-style:solid !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;margin-bottom:9px !important;}<\/style>\n<summary class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-ae2ad76 stk--container-small stk-block-accordion__heading\" data-v=\"4\" data-block-id=\"ae2ad76\"><style>.stk-ae2ad76 {padding-top:2px !important;padding-right:2px !important;padding-bottom:2px !important;padding-left:2px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-ae2ad76-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-ae2ad76-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-16db2af\" data-block-id=\"16db2af\"><style>.stk-16db2af .stk-inner-blocks{gap:39px !important;}@media screen and (max-width: 1023px){.stk-16db2af .stk-inner-blocks{gap:39px !important;}}@media screen and (max-width: 767px){.stk-16db2af .stk-inner-blocks{gap:39px !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-icon stk-block-icon stk-block stk-38bb3f8\" data-block-id=\"38bb3f8\"><style>.stk-38bb3f8 .stk--svg-wrapper .stk--inner-svg svg:last-child{height:25px !important;width:25px !important;}.stk-38bb3f8 .stk--svg-wrapper .stk--inner-svg svg:last-child, .stk-38bb3f8 .stk--svg-wrapper .stk--inner-svg svg:last-child :is(g, path, rect, polygon, ellipse){fill:#f33f4e !important;}<\/style><span class=\"stk--svg-wrapper stk--has-icon2\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-38bb3f8\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-38-bb-3-f-8-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-38-bb-3-f-8-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M96 0C43 0 0 43 0 96V416c0 53 43 96 96 96H384h32c17.7 0 32-14.3 32-32s-14.3-32-32-32V384c17.7 0 32-14.3 32-32V32c0-17.7-14.3-32-32-32H384 96zm0 384H352v64H96c-17.7 0-32-14.3-32-32s14.3-32 32-32zm32-240c0-8.8 7.2-16 16-16H336c8.8 0 16 7.2 16 16s-7.2 16-16 16H144c-8.8 0-16-7.2-16-16zm16 48H336c8.8 0 16 7.2 16 16s-7.2 16-16 16H144c-8.8 0-16-7.2-16-16s7.2-16 16-16z\"><\/path><\/svg><\/div><div class=\"stk--inner-svg stk--icon-2\" style=\"display:none\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-38bb3f8\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-38-bb-3-f-8-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-38-bb-3-f-8-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 576 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M249.6 471.5c10.8 3.8 22.4-4.1 22.4-15.5V78.6c0-4.2-1.6-8.4-5-11C247.4 52 202.4 32 144 32C93.5 32 46.3 45.3 18.1 56.1C6.8 60.5 0 71.7 0 83.8V454.1c0 11.9 12.8 20.2 24.1 16.5C55.6 460.1 105.5 448 144 448c33.9 0 79 14 105.6 23.5zm76.8 0C353 462 398.1 448 432 448c38.5 0 88.4 12.1 119.9 22.6c11.3 3.8 24.1-4.6 24.1-16.5V83.8c0-12.1-6.8-23.3-18.1-27.6C529.7 45.3 482.5 32 432 32c-58.4 0-103.4 20-123 35.6c-3.3 2.6-5 6.8-5 11V456c0 11.4 11.7 19.3 22.4 15.5z\"><\/path><\/svg><\/div><\/span><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-a35761a\" id=\"criterios-de-admision\" data-block-id=\"a35761a\"><style>.stk-a35761a .stk-block-heading__text{color:#000000 !important;font-weight:500 !important;font-family:\"ArgentumSans\", Sans-serif !important;}<\/style><h4 class=\"stk-block-heading__text has-text-color\">Criterios de admisi\u00f3n<\/h4><\/div>\n<\/div><\/div>\n<\/div><\/div><\/summary>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-81ecc51 stk-block-accordion__content\" data-v=\"4\" data-block-id=\"81ecc51\"><style>.stk-81ecc51 {margin-top:-30px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-81ecc51-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-81ecc51-inner-blocks\">\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-7508b1a\" data-block-id=\"7508b1a\"><p class=\"stk-block-text__text\"><strong>Selecci\u00f3n y Admisi\u00f3n. Criterios de valoraci\u00f3n y \u00f3rgano encargado:<\/strong><\/p><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">La Comisi\u00f3n Acad\u00e9mica del PD, por medio de la subcomisi\u00f3n delegada, resolver\u00e1 sobre la admisi\u00f3n de cada una de las solicitudes, pudiendo, si lo estima oportuno, convocar a una entrevista al candidato, cuya valoraci\u00f3n global ser\u00e1, como m\u00e1ximo, de un 30% de la evaluaci\u00f3n total. La resoluci\u00f3n ser\u00e1 comunicada a los interesados que a partir de ese momento y dentro de los plazos que disponga cada universidad podr\u00e1n formalizar la matr\u00edcula en el PD.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los criterios de valoraci\u00f3n de las solicitudes ser\u00e1n los siguientes:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">a) Adecuaci\u00f3n de la titulaci\u00f3n alegada para el ingreso y media del expediente acad\u00e9mico en el t\u00edtulo de grado (o licenciatura) y en el t\u00edtulo de m\u00e1ster. Se entiende que tendr\u00e1n preferencia los estudiantes que provienen o bien del M\u00e1ster en L\u00f3gica y Filosof\u00eda de la Ciencia o del M\u00e1ster en Estudios Sociales de la Ciencia y la Tecnolog\u00eda o los que, siendo procedentes de otros estudios de nivel equivalente, hayan cursado materias que faciliten la asimilaci\u00f3n de los conocimientos y competencias ofrecidos desde el PD: hasta 40 puntos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">b) Experiencia profesional (desarrollada dentro o fuera de la universidad, en centros p\u00fablicos o privados relacionados con la educaci\u00f3n, la investigaci\u00f3n o la gesti\u00f3n): hasta 20 puntos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">c) Realizaciones de cursos, asistencias a congresos, estancias en otras Universidades, etc.: hasta 20 puntos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">d) Dominio documentado del ingl\u00e9s o de otros idiomas extranjeros: hasta 20 puntos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Servicios de apoyo para estudiantes con necesidades educativas especiales:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En general las universidades integradas en este doctorado disponen de servicios de apoyo a los estudiantes. Disponen tambi\u00e9n de programas de integraci\u00f3n de personas con discapacidad y distintos servicios en donde se asesora y atiende a personas con distintos tipos de discapacidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Programas<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Uva<\/li>\n\n\n\n<li><a href=\"http:\/\/sas.usal.es\/index.php\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">USAL<\/a><\/li>\n\n\n\n<li><a href=\"http:\/\/www.usc.es\/es\/servizos\/axudas\/index.html\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">USC&nbsp;<\/a><\/li>\n\n\n\n<li><a href=\"http:\/\/www.udc.es\/sape\/\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">UdC<\/a><\/li>\n\n\n\n<li><a href=\"http:\/\/www.uv.es\/uvweb\/universitat\/es\/estudis-grau\/informacio-academica-administrativa\/informacio-contacte\/servei-estudiants\/ubicacio-contacte-1285852458430.html\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">Universitat de Val\u00e8ncia<\/a><\/li>\n\n\n\n<li>ULL<a href=\"http:\/\/www.ull.es\/view\/institucional\/ull\/Ayudas_a_la_discapacidad\/es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\"><\/a><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">En los casos en los que proceda, se realizar\u00e1n adaptaciones curriculares individualizadas a cada estudiante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Estudiantes con dedicaci\u00f3n a tiempo parcial:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El r\u00e9gimen de dedicaci\u00f3n de los estudiantes a este PD ser\u00e1 preferentemente a tiempo completo. No obstante, algunas de las plazas ofertadas podr\u00e1n ser ocupadas por estudiantes a los cuales se les reconozca una dedicaci\u00f3n a tiempo parcial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los estudiantes que deseen realizar los estudios de este PD en r\u00e9gimen de dedicaci\u00f3n a tiempo parcial deber\u00e1n solicitarlo a la Comisi\u00f3n Acad\u00e9mica del Programa cuando presenten la solicitud de admisi\u00f3n al mismo o, una vez admitidos, cuando concurran en ellos alguna de las circunstancias que se recogen a continuaci\u00f3n y posibiliten el reconocimiento como estudiantes a tiempo parcial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre otros, ser\u00e1n criterios para la admisi\u00f3n de estudiantes a tiempo parcial en este PD los siguientes:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1) Estar trabajando y acreditar documentalmente la relaci\u00f3n laboral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2) Estar afectado por un grado de discapacidad f\u00edsica, sensorial o ps\u00edquica determinante de la necesidad de cursar los estudios de doctorado a tiempo parcial. En este caso el estudiante deber\u00e1 acreditar documentalmente el grado de discapacitaci\u00f3n reconocido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">3) Estar realizando otra formaci\u00f3n de car\u00e1cter especializado, en la misma o en otra Universidad, con dedicaci\u00f3n a tiempo parcial y acreditar la condici\u00f3n de estar admitido o matriculado en dichos estudios como estudiante a tiempo parcial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">4) Tener la consideraci\u00f3n de cuidador principal de personas dependientes y acreditarlo mediante la presentaci\u00f3n de documentaci\u00f3n justificativa y certificaci\u00f3n expedida por el organismo competente para el reconocimiento de la situaci\u00f3n de dependencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">5) Tener hijos menores de 3 a\u00f1os a su cargo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">6) Ser deportista de alto nivel de competici\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">7) Ejercer tareas de representaci\u00f3n estudiantil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">8) Otras debidamente justificadas (por ejemplo, ser v\u00edctima de violencia de g\u00e9nero, de terrorismo, etc.).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El reconocimiento de esta condici\u00f3n deber\u00e1 ser ratificada anualmente y tendr\u00e1 efectos hasta la conclusi\u00f3n de los estudios de doctorado con la presentaci\u00f3n y defensa de la tesis doctoral. No obstante lo anterior, durante el desarrollo del PD, se podr\u00e1 solicitar cambios en la modalidad de la dedicaci\u00f3n a estos estudios siempre que concurran las siguientes circunstancias:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2013 Los doctorandos con dedicaci\u00f3n a tiempo parcial que a lo largo del PD pierdan la circunstancia por la cual fueron admitidos y reconocidos como tal, pasar\u00e1n autom\u00e1ticamente a ser estudiantes del PD con dedicaci\u00f3n a tiempo completo. A partir de ese momento, dispondr\u00e1n de tres a\u00f1os hasta la presentaci\u00f3n de la solicitud de dep\u00f3sito de la tesis doctoral, siempre que no hayan transcurridos m\u00e1s de dos a\u00f1os bajo la condici\u00f3n de estudiante a tiempo parcial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2013 Los doctorandos que habiendo iniciado los estudios de doctorado en r\u00e9gimen de dedicaci\u00f3n a tiempo completo se vean en la necesidad de solicitar la condici\u00f3n de estudiante a tiempo parcial y cumplan alguno de los requisitos expresados anteriormente, dispondr\u00e1n desde la concesi\u00f3n de dicha condici\u00f3n hasta la presentaci\u00f3n de la solicitud de dep\u00f3sito de la tesis doctoral de un m\u00e1ximo de tiempo que en su conjunto, con el ya transcurrido, no supere los 5 a\u00f1os.<\/p>\n<\/div><\/div><\/div>\n<\/details>\n\n\n\n<details class=\"wp-block-stackable-accordion stk-block-accordion stk-inner-blocks stk-block-content stk-block stk-9d40cce is-style-default\" id=\"complementos-de-formacion\" data-block-id=\"9d40cce\"><style>.stk-9d40cce {border-style:solid !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;}<\/style>\n<summary class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-ef7f17a stk--container-small stk-block-accordion__heading\" data-v=\"4\" data-block-id=\"ef7f17a\"><style>.stk-ef7f17a {padding-top:2px !important;padding-right:2px !important;padding-bottom:2px !important;padding-left:2px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-ef7f17a-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-ef7f17a-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-da3b93e\" data-block-id=\"da3b93e\"><style>.stk-da3b93e .stk-inner-blocks{gap:39px !important;}@media screen and (max-width: 1023px){.stk-da3b93e .stk-inner-blocks{gap:39px !important;}}@media screen and (max-width: 767px){.stk-da3b93e .stk-inner-blocks{gap:39px !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-icon stk-block-icon stk-block stk-8c84b2d\" data-block-id=\"8c84b2d\"><style>.stk-8c84b2d .stk--svg-wrapper .stk--inner-svg svg:last-child{height:25px !important;width:25px !important;}.stk-8c84b2d .stk--svg-wrapper .stk--inner-svg svg:last-child, .stk-8c84b2d .stk--svg-wrapper .stk--inner-svg svg:last-child :is(g, path, rect, polygon, ellipse){fill:#f33f4e !important;}<\/style><span class=\"stk--svg-wrapper stk--has-icon2\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-8c84b2d\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-8-c-84-b-2-d-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-8-c-84-b-2-d-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 384 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M64 0C28.7 0 0 28.7 0 64V448c0 35.3 28.7 64 64 64H320c35.3 0 64-28.7 64-64V160H256c-17.7 0-32-14.3-32-32V0H64zM256 0V128H384L256 0zM112 256H272c8.8 0 16 7.2 16 16s-7.2 16-16 16H112c-8.8 0-16-7.2-16-16s7.2-16 16-16zm0 64H272c8.8 0 16 7.2 16 16s-7.2 16-16 16H112c-8.8 0-16-7.2-16-16s7.2-16 16-16zm0 64H272c8.8 0 16 7.2 16 16s-7.2 16-16 16H112c-8.8 0-16-7.2-16-16s7.2-16 16-16z\"><\/path><\/svg><\/div><div class=\"stk--inner-svg stk--icon-2\" style=\"display:none\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-8c84b2d\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-8-c-84-b-2-d-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-8-c-84-b-2-d-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 384 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M64 464c-8.8 0-16-7.2-16-16V64c0-8.8 7.2-16 16-16H224v80c0 17.7 14.3 32 32 32h80V448c0 8.8-7.2 16-16 16H64zM64 0C28.7 0 0 28.7 0 64V448c0 35.3 28.7 64 64 64H320c35.3 0 64-28.7 64-64V154.5c0-17-6.7-33.3-18.7-45.3L274.7 18.7C262.7 6.7 246.5 0 229.5 0H64zm56 256c-13.3 0-24 10.7-24 24s10.7 24 24 24H264c13.3 0 24-10.7 24-24s-10.7-24-24-24H120zm0 96c-13.3 0-24 10.7-24 24s10.7 24 24 24H264c13.3 0 24-10.7 24-24s-10.7-24-24-24H120z\"><\/path><\/svg><\/div><\/span><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-d69e378\" id=\"complementos-de-formacion\" data-block-id=\"d69e378\"><style>.stk-d69e378 .stk-block-heading__text{color:#000000 !important;font-weight:500 !important;font-family:\"ArgentumSans\", Sans-serif !important;}<\/style><h4 class=\"stk-block-heading__text has-text-color\">Complementos de formaci\u00f3n<\/h4><\/div>\n<\/div><\/div>\n<\/div><\/div><\/summary>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-9404ebc stk-block-accordion__content\" data-v=\"4\" data-block-id=\"9404ebc\"><style>.stk-9404ebc {margin-top:-30px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-9404ebc-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-9404ebc-inner-blocks\">\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-22281da\" data-block-id=\"22281da\"><p class=\"stk-block-text__text\">La Comisi\u00f3n Acad\u00e9mica del programa decidir\u00e1 para cada estudiante admitido, en funci\u00f3n de su perfil de ingreso y la formaci\u00f3n previa adquirida, la necesidad o no de realizar determinada formaci\u00f3n en investigaci\u00f3n. En particular, en el caso de estudiantes que no hubieran cursado ni el \u201cM\u00e1ster en L\u00f3gica y Filosof\u00eda de la Ciencia\u201d ni el \u201cM\u00e1ster en Estudios Sociales de la Ciencia y la Tecnolog\u00eda\u201d, pero que sin embargo reuniesen los requisitos de acceso, la Comisi\u00f3n Acad\u00e9mica del Programa de Doctorado podr\u00e1 establecer que el aspirante curse hasta un m\u00e1ximo de cinco asignaturas (total: 25 Cr\u00e9ditos ECTS) de uno de los dos m\u00e1steres mencionados. En particular, tendr\u00e1n que cursas complementos de formaci\u00f3n aquellos estudiantes que no hayan cursado alguna titulaci\u00f3n que les haya proporcionado conocimientos suficientes en el \u00c1rea de L\u00f3gica y Filosof\u00eda de la Ciencia.<\/p><\/div>\n<\/div><\/div><\/div>\n<\/details>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-53ec762\" data-v=\"4\" data-block-id=\"53ec762\"><style>.stk-53ec762-inner-blocks{row-gap:0px !important;}.stk-53ec762 {padding-top:0px !important;padding-right:0px !important;padding-bottom:0px !important;padding-left:0px !important;}@media screen and (min-width: 768px){.stk-53ec762 {flex:var(--stk-flex-grow, 1) 1 33.3% !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-53ec762-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-53ec762-inner-blocks\">\n\n<ul class=\"widget-box\">\n<li class='contacto-header'>Informaci\u00f3n de contacto<\/li><li><i class=\"fa fa-map-marker\"><\/i> Avda. Astrof\u00edsico Francisco S\u00e1nchez, SN. Edificio Calabaza \u2013 AN.2D Apdo. 456 38200 San Crist\u00f3bal de La Laguna<\/li><li><i class=\"fa fa-envelope\"><\/i>  <a href=mailto:doctorado.logicafilosofia@ull.es>doctorado.logicafilosofia@ull.es<\/a><\/li><li><i class=\"fa fa-calendar\"><\/i><a href=\"http:\/\/citaprevia.ull.es\/index.php?s=edpo\"> Cita previa<\/a><\/li>\n<\/ul>\n\n\n<\/div><\/div><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Access and Admission Information Systems Prospective students can obtain accurate information about the Doctoral Program (DP) before the enrollment process through various channels. Participating universities annually prepare their official degree offerings in accordance with current regulations. To develop the doctoral program offerings, a survey is conducted\u2026<\/p>","protected":false},"author":1,"featured_media":0,"parent":17,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/template-frontpage.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-76","page","type-page","status-publish","hentry"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 20:40:41","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.ull.es\/doctorados\/logica-filosofia-ciencia\/en\/wp-json\/wp\/v2\/pages\/76","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ull.es\/doctorados\/logica-filosofia-ciencia\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ull.es\/doctorados\/logica-filosofia-ciencia\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ull.es\/doctorados\/logica-filosofia-ciencia\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ull.es\/doctorados\/logica-filosofia-ciencia\/en\/wp-json\/wp\/v2\/comments?post=76"}],"version-history":[{"count":15,"href":"https:\/\/www.ull.es\/doctorados\/logica-filosofia-ciencia\/en\/wp-json\/wp\/v2\/pages\/76\/revisions"}],"predecessor-version":[{"id":376,"href":"https:\/\/www.ull.es\/doctorados\/logica-filosofia-ciencia\/en\/wp-json\/wp\/v2\/pages\/76\/revisions\/376"}],"up":[{"embeddable":true,"href":"https:\/\/www.ull.es\/doctorados\/logica-filosofia-ciencia\/en\/wp-json\/wp\/v2\/pages\/17"}],"wp:attachment":[{"href":"https:\/\/www.ull.es\/doctorados\/logica-filosofia-ciencia\/en\/wp-json\/wp\/v2\/media?parent=76"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}