{"id":70,"date":"2018-02-22T13:26:52","date_gmt":"2018-02-22T13:26:52","guid":{"rendered":"http:\/\/www.ull.es\/doctorados\/nanociencia-nanotecnologia\/?page_id=70"},"modified":"2026-07-28T20:54:34","modified_gmt":"2026-07-28T20:54:34","slug":"supervision-tesis","status":"publish","type":"page","link":"https:\/\/www.ull.es\/doctorados\/nanociencia-nanotecnologia\/en\/organizacion-del-programa\/supervision-tesis\/","title":{"rendered":"Thesis supervision"},"content":{"rendered":"\n<div class=\"wp-block-stackable-columns alignfull stk-block-columns stk-block stk-2314a6b\" data-block-id=\"2314a6b\"><style>.stk-2314a6b {padding-bottom:0px !important;margin-top:-100px !important;margin-bottom:0px !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-2314a6b-column alignfull\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-1d1764d\" data-v=\"4\" data-block-id=\"1d1764d\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-1d1764d-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-1d1764d-inner-blocks\"><style id=\"depicter-6-inline-pre-css\">\n\n.depicter-6:not(.depicter-ready){\n\theight:450px;\n}\n\n\/***** Tablet *****\/\n@media screen and (max-width: 1024px){\n\n.depicter-6:not(.depicter-ready){\n\theight:700px;\n}\n\n}\n\/***** Mobile *****\/\n@media screen and (max-width: 767px){\n\n.depicter-6:not(.depicter-ready){\n\theight:740px;\n}\n\n}\n<\/style>\n<div id=\"depicter-6\" class=\"depicter depicter-document depicter-revert depicter-6 depicter-layout-fullwidth\">\n\n<div class=\"depicter-loading-container depicter-loading dotFlashing-dark\"><div class=\"depicter-loading-dark depicter-dot-flashing\">\n   <span><\/span>\n   <span><\/span>\n   <span><\/span>\n<\/div>\n<\/div>\n<div id=\"depicter-6-section-1\" class=\"depicter-section depicter-6-section-1\" data-name=\"Section 1\" data-type=\"section\" data-local-id=\"section-1\">\n<picture class=\"depicter-bg\">\n<source data-depicter-srcset=\"https:\/\/www.ull.es\/doctorados\/nanociencia-nanotecnologia\/wp-content\/uploads\/sites\/17\/2025\/05\/Headers-Doctorados_Doctorado-Nanociencia-768x248.jpg, https:\/\/www.ull.es\/doctorados\/nanociencia-nanotecnologia\/wp-content\/uploads\/sites\/17\/2025\/05\/Headers-Doctorados_Doctorado-Nanociencia.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(max-width: 1024px)\" \/>\n\n<source data-depicter-srcset=\"https:\/\/www.ull.es\/doctorados\/nanociencia-nanotecnologia\/wp-content\/uploads\/sites\/17\/2025\/05\/Headers-Doctorados_Doctorado-Nanociencia.jpg, https:\/\/www.ull.es\/doctorados\/nanociencia-nanotecnologia\/wp-content\/uploads\/sites\/17\/2025\/05\/Headers-Doctorados_Doctorado-Nanociencia-2000x645.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(min-width: 1025px)\" \/>\n<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-ken-burns=\"false\" data-tablet-ken-burns=\"false\" data-mobile-ken-burns=\"false\" alt=\"\" data-depicter-src=\"https:\/\/www.ull.es\/doctorados\/nanociencia-nanotecnologia\/wp-content\/uploads\/sites\/17\/2025\/05\/Headers-Doctorados_Doctorado-Nanociencia.jpg\" data-object-fit=\"custom,custom,\" data-object-position=\"center top,,\" data-crop=\"{&apos;focalPoint&apos;:{&apos;x&apos;:0.5,&apos;y&apos;:0.5},&apos;mediaSize&apos;:{&apos;width&apos;:1395.3488372093024736386723816394805908203125,&apos;height&apos;:450}}\" data-tablet-crop=\"{&apos;focalPoint&apos;:{&apos;x&apos;:0.5,&apos;y&apos;:0.5},&apos;mediaSize&apos;:{&apos;width&apos;:2170.54263565891460530110634863376617431640625,&apos;height&apos;:700}}\" data-mobile-crop=\"{&apos;focalPoint&apos;:{&apos;x&apos;:0.5,&apos;y&apos;:0.5},&apos;mediaSize&apos;:{&apos;width&apos;:2294.57364341085258274688385426998138427734375,&apos;height&apos;:740}}\" \/>\n<\/picture>\n\n\n<h1 id=\"depicter-6-element-5\" class=\"depicter-element depicter-layer depicter-6-element-5\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 2\" data-local-id=\"element-5\" data-offset=\"x:0px;y:139px;origin:tl\" data-tablet-offset=\"x:290px;y:193px;origin:tl\" data-mobile-offset=\"x:40px;y:272px;origin:tl\" data-width=\"1409px,auto,348px\" data-height=\"auto,auto,auto\" data-responsive-scale=\"true,,\">Programa de Doctorado en <br>Nanociencia y Nanotecnolog\u00eda<\/h1>\n\n<div id=\"depicter-6-element-10\" class=\"depicter-element depicter-layer depicter-6-element-10\" data-type=\"shape\" data-wrap=\"true\" data-name=\"Shape 1\" data-local-id=\"element-10\" data-offset=\"x:0px;y:323px;origin:tl\" data-tablet-offset=\"x:290px;y:489px;origin:tl\" data-mobile-offset=\"x:40px;y:471px;origin:tl\" data-width=\"1094px,478px,313px\" data-height=\"8px,8px,8px\" data-responsive-scale=\"true,,\"><\/div>\n<\/div>\n<\/div>\n<script>\n(window.depicterSetups = window.depicterSetups || []).push(function(){\n\tDepicter.basePath = 'https:\/\/www.ull.es\/doctorados\/nanociencia-nanotecnologia\/wp-content\/plugins\/depicter\/resources\/scripts\/player\/';\n\tconst dpPlayer = Depicter.setup('.depicter-6',\n\t\t{\"width\":[\"1200\",\"1024\",\"360\"],\"height\":[\"450\",\"700\",\"740\"],\"view\":\"basic\",\"keepAspectRatio\":true,\"preload\":0,\"layout\":\"fullwidth\",\"rtl\":false,\"initAfterAppear\":false,\"ajaxApiUrl\":\"https:\\\/\\\/www.ull.es\\\/doctorados\\\/nanociencia-nanotecnologia\\\/wp-admin\\\/admin-ajax.php\",\"mouseSwipe\":true,\"touchSwipe\":true,\"useWatermark\":false}\n\t);\n});\n<\/script><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns alignfull stk-block-columns stk--hide-mobile stk-block stk-6394276 stk-block-background\" data-block-id=\"6394276\"><style>.stk-6394276 {background-color:#f33f4e !important;padding-top:10px !important;margin-bottom:0px !important;}.stk-6394276:before{background-color:#f33f4e !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-6394276-column alignfull\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-8a66885\" data-v=\"4\" data-block-id=\"8a66885\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-8a66885-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-8a66885-inner-blocks\">\n<div class=\"wp-block-stackable-spacer stk-block-spacer stk--no-padding stk-block stk-bc89b3e\" data-block-id=\"bc89b3e\"><style>.stk-bc89b3e {height:0px !important;}<\/style><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns stk-block-columns stk-block stk-8b59b96\" data-block-id=\"8b59b96\"><style>.stk-8b59b96 .stk--block-align-8b59b96{align-items:flex-start !important;}.stk-8b59b96 {margin-top:50px !important;}.stk-8b59b96-column{--stk-columns-spacing:0px !important;--stk-column-gap:50px !important;}<\/style><div class=\"stk-row stk-inner-blocks stk--block-align-8b59b96 stk-block-content stk-content-align stk-8b59b96-column\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-dbb7e15\" data-v=\"4\" data-block-id=\"dbb7e15\"><style>@media screen and (min-width: 768px){.stk-dbb7e15 {flex:var(--stk-flex-grow, 1) 1 66.7% !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-dbb7e15-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-dbb7e15-inner-blocks\">\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-cc0239e\" id=\"complementos-de-formacion\" data-block-id=\"cc0239e\"><style>.stk-cc0239e .stk-block-heading__text{color:#000000 !important;font-weight:500 !important;}<\/style><h1 class=\"stk-block-heading__text has-text-color\">Supervisi\u00f3n de tesis<\/h1><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Direcci\u00f3n de tesis<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cada tesis doctoral deber\u00e1 estar dirigida por un director de tesis que ser\u00e1 un investigador doctor que cumpla los requisitos m\u00ednimos establecidos en el Reglamento de Ense\u00f1anzas Oficiales de Doctorado de la Universidad de La Laguna y que ser\u00e1 asignado por la comisi\u00f3n acad\u00e9mica. Salvo causa justificada, este papel recaer\u00e1 en la persona que haya avalado la solicitud de admisi\u00f3n.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No podr\u00e1 asign\u00e1rsele al estudiante de doctorado como director o directora de tesis el profesorado que tenga un v\u00ednculo matrimonial o situaci\u00f3n de hecho asimilable o parentesco de consanguinidad dentro del cuarto grado, o de afinidad dentro del segundo, con el estudiante de doctorado.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Resulta posible contar con hasta dos directores adicionales m\u00e1s, siempre que se solicite y la comisi\u00f3n acad\u00e9mica lo apruebe, cuando concurran razones de \u00edndole acad\u00e9mica o de interdisciplinariedad tem\u00e1tica o cuando se trate de programas desarrollados en colaboraci\u00f3n nacional o internacional. En particular, la tercera direcci\u00f3n deber\u00e1 estar muy justificada y especialmente prevista para los supuestos en los que la tesis se realice en r\u00e9gimen de cotutela, que se vaya a solicitar la menci\u00f3n industrial, que se haya firmado un convenio que lo exija o, excepcionalmente, en otros supuestos, siempre que est\u00e9 debidamente justificado por su car\u00e1cter multidisciplinar.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La labor de direcci\u00f3n de tesis ser\u00e1 reconocida como parte de la dedicaci\u00f3n docente e investigadora del profesorado en los t\u00e9rminos que establezca la normativa correspondiente de la Universidad de La Laguna. En particular la normativa de contrataci\u00f3n considera como valorable el haber dirigido tesis doctorales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Tutorizaci\u00f3n de tesis<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La comisi\u00f3n acad\u00e9mica le asignar\u00e1 al doctorando una persona que se encargue de la tutorizaci\u00f3n, que podr\u00e1 coincidir o no con la persona responsable de la direcci\u00f3n de la tesis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El tutor deber\u00e1 ser un investigador doctor que ser\u00e1 preferentemente personal docente e investigador a tiempo completo de la Universidad de La Laguna. Al tutor le corresponder\u00e1 velar por la interacci\u00f3n del estudiante de doctorado con la comisi\u00f3n acad\u00e9mica.<\/p>\n\n\n\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-022d17b wp-block-hidden-desktop wp-block-hidden-mobile wp-block-hidden-tablet\" data-block-id=\"022d17b\"><style>.stk-022d17b {max-width:1500px !important;min-width:auto !important;}<\/style><p class=\"stk-block-text__text\">Las distintas universidades participantes contabilizar\u00e1n como actividad docente el&nbsp;tiempo dedicado a la direcci\u00f3n y tutorizaci\u00f3n de tesis. Aunque cada Universidad tiene&nbsp;su normativa propia, en todas ellas se fomentar\u00e1 y valorar\u00e1 la direcci\u00f3n de tesis&nbsp;doctorales y las labores de tutorizaci\u00f3n.<\/p><\/div>\n\n\n\n<p class=\"wp-block-hidden-desktop wp-block-hidden-mobile wp-block-hidden-tablet wp-block-paragraph\">De hecho, el Servicio de Investigaci\u00f3n de todas las universidades participantes valora&nbsp;la supervisi\u00f3n de tesis en las ayudas a la investigaci\u00f3n que recibe el Departamento&nbsp;\/ Instituto donde el director desarrolla esta actividad y en las ayudas a la investigaci\u00f3n&nbsp;que reciben los grupos de investigaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-hidden-desktop wp-block-hidden-mobile wp-block-hidden-tablet wp-block-paragraph\">Desde la CAD se fomentar\u00e1 que la mayor parte de las tesis presentadas en el programa&nbsp;de doctorado tengan la menci\u00f3n internacional, lo que implicar\u00e1, la realizaci\u00f3n&nbsp;de al menos una estancia de m\u00ednimo 3 meses de duraci\u00f3n en un centro de investigaci\u00f3n&nbsp;extranjero, que la tesis sea informada previamente por dos expertos doctores&nbsp;de instituciones de educaci\u00f3n superior o de investigaci\u00f3n no espa\u00f1olas y que al<br>menos un miembro del tribunal evaluador de la tesis tambi\u00e9n lo sea. Se marca como&nbsp;objetivo que el porcentaje de tesis que obtengan la menci\u00f3n internacional sea&nbsp;superior al 60% del total de tesis defendidas. Este porcentaje est\u00e1 basado en el historial&nbsp;previo de tesis que alcanzaron la menci\u00f3n internacional.<\/p>\n\n\n\n<p class=\"wp-block-hidden-desktop wp-block-hidden-mobile wp-block-hidden-tablet wp-block-paragraph\">Debe indicarse que, como regla general y al margen de que la tesis tenga o no&nbsp;menci\u00f3n internacional, tanto en los informes previos como en el tribunal de la tesis&nbsp;se cuenta con la presencia de expertos internacionales de reconocido prestigio (al&nbsp;menos dos expertos extranjeros en total)<\/p>\n\n\n\n<p class=\"wp-block-hidden-desktop wp-block-hidden-mobile wp-block-hidden-tablet wp-block-paragraph\">A trav\u00e9s de la experiencia previa en el Programa de Doctorado, se sabe que la mayor\u00eda&nbsp;de los doctorandos, en especial aquellos que han disfrutado de una beca de&nbsp;investigaci\u00f3n\/formaci\u00f3n, han realizado una o varias estancias durante la realizaci\u00f3n&nbsp;de su tesis doctoral. De las tesis defendidas en el Programa de Doctorado en los \u00faltimos&nbsp;a\u00f1os, una parte importante se ha dirigido en r\u00e9gimen de co-tutela y ha obtenido&nbsp;tambi\u00e9n la menci\u00f3n europea.<\/p>\n\n\n\n<p class=\"wp-block-hidden-desktop wp-block-hidden-mobile wp-block-hidden-tablet wp-block-paragraph\">En el pasado este Programa ha mostrado su capacidad de desarrollar un n\u00famero importante de tesis en co-tutela. La mayor\u00eda de estas tesis han implicado a centros franceses (Univ. Paris VI, Univ. Paul Sabatier) que se encuentran integrados en el Instituto Europeo de Magnetismo Molecular. Este instituto tambi\u00e9n expide la menci\u00f3n de \u201cdoctorado europeo en Magnetismo Molecular\u201d. Un objetivo del presente Programa de Doctorado es incentivar en el futuro esta v\u00eda europea.<\/p>\n\n\n\n<p class=\"wp-block-hidden-desktop wp-block-hidden-mobile wp-block-hidden-tablet wp-block-paragraph\">Previsi\u00f3n de estancias en otros centros, co-tutelas y menciones europeas:&nbsp;A trav\u00e9s de la experiencia previa en el Programa de Doctorado, se sabe que la mayor\u00eda de los doctorandos, en especial aquellos que han disfrutado de una beca de investigaci\u00f3n\/ formaci\u00f3n, han realizado una o varias estancias durante la realizaci\u00f3n de su tesis doctoral. De las tesis defendidas en el Programa de Doctorado en los \u00faltimos a\u00f1os, una parte importante se ha dirigido en r\u00e9gimen de co-tutela y ha obtenido tambi\u00e9n la menci\u00f3n europea.<\/p>\n\n\n\n<p class=\"wp-block-hidden-desktop wp-block-hidden-mobile wp-block-hidden-tablet wp-block-paragraph\">En a\u00f1os sucesivos se estima que todos los doctorandos del Programa realizar\u00e1n estancias en otras universidades o centros (en realidad \u00e9sta es una de las actividades formativas contempladas en el Programa) y que, tal y como acabamos de se\u00f1alar en el apartado anterior, el 60 % de las tesis optar\u00e1n a la menci\u00f3n internacional.<\/p>\n\n\n\n<p class=\"wp-block-hidden-desktop wp-block-hidden-mobile wp-block-hidden-tablet wp-block-paragraph\">Dado el car\u00e1cter interuniversitario del Programa existe una Comisi\u00f3n Acad\u00e9mica de Doctorado encargada de la coordinaci\u00f3n de las diferentes universidades para la realizaci\u00f3n de actividades conjuntas (las Escuelas ENMM y ESMOLNA descritas anteriormente), para fomentar la colaboraci\u00f3n entre grupos y codirecci\u00f3n y co-tutela de tesis y para velar para que el doctorado cumpla las normas de calidad exigibles a un doctorado de excelencia.<\/p>\n\n\n\n<p class=\"wp-block-hidden-desktop wp-block-hidden-mobile wp-block-hidden-tablet wp-block-paragraph\">Por otra parte, las direcciones de tesis doctoral deben de cumplir la normativa general establecida por las universidades participantes:<\/p>\n\n\n\n<p class=\"wp-block-hidden-desktop wp-block-hidden-mobile wp-block-hidden-tablet wp-block-paragraph\">1. La CAD asignar\u00e1 a cada doctorando, en el plazo m\u00e1ximo de seis meses desde su matr\u00edcula, un director de tesis doctoral que podr\u00e1 ser coincidente o no con el tutor o tutora. Esta asignaci\u00f3n podr\u00e1 recaer en cualquier doctor con experiencia investigadora debidamente acreditada, con independencia de la Universidad, Centro o Instituto en el que preste sus servicios.<\/p>\n\n\n\n<p class=\"wp-block-hidden-desktop wp-block-hidden-mobile wp-block-hidden-tablet wp-block-paragraph\">2. Una tesis doctoral puede ser codirigida como m\u00e1ximo por tres doctores que re\u00fanan las condiciones anteriores, previa autorizaci\u00f3n de la comisi\u00f3n acad\u00e9mica en los supuestos de interdisciplinariedad tem\u00e1tica o programas desarrollados en colaboraci\u00f3n con otras Universidades del Estado o internacionales.<\/p>\n\n\n\n<p class=\"wp-block-hidden-desktop wp-block-hidden-mobile wp-block-hidden-tablet wp-block-paragraph\">3. Ning\u00fan doctor podr\u00e1 dirigir o codirigir m\u00e1s de 10 tesis simult\u00e1neamente.<\/p>\n\n\n\n<p class=\"wp-block-hidden-desktop wp-block-hidden-mobile wp-block-hidden-tablet wp-block-paragraph\">4. El director podr\u00e1 renunciar a la direcci\u00f3n, mediante escrito motivado presentado a la CAD, que resolver\u00e1 la solicitud y proceder\u00e1 al nombramiento de otro director para continuar el doctorado.<\/p>\n\n\n\n<p class=\"wp-block-hidden-desktop wp-block-hidden-mobile wp-block-hidden-tablet wp-block-paragraph\">5. La CAD podr\u00e1 modificar, con audiencia del doctorando y siempre que concurran razones justificadas, el nombramiento del director de tesis doctoral en cualquier momento de la realizaci\u00f3n de la tesis.<\/p>\n\n\n\n<p class=\"wp-block-hidden-desktop wp-block-hidden-mobile wp-block-hidden-tablet wp-block-paragraph\">6. La normativa de cada Universidad que regule la actividad del profesorado establecer\u00e1 la equivalencia en cr\u00e9ditos de la tutorizaci\u00f3n y de la direcci\u00f3n de tesis doctorales.<\/p>\n\n\n\n<p class=\"wp-block-hidden-desktop wp-block-hidden-mobile wp-block-hidden-tablet wp-block-paragraph\">7. Cada Universidad participante podr\u00e1 formalizar convenios con universidades extranjeras para la realizaci\u00f3n de tesis doctorales en r\u00e9gimen de cotutela. En este caso los doctorandos realizar\u00e1n sus trabajos de la tesis bajo el control y la responsabilidad de al menos un director de tesis de cada una de las Universidades firmantes del convenio.<\/p>\n\n\n\n<p class=\"wp-block-hidden-desktop wp-block-hidden-mobile wp-block-hidden-tablet wp-block-paragraph\">8. A efectos del dep\u00f3sito, evaluaci\u00f3n y defensa de la tesis doctoral cada Universidad participante seguir\u00e1 la normativa aprobada al efecto. Debemos aclarar que cada Universidad ha establecido en su reglamento sobre el Doctorado aspectos espec\u00edficos sobre la asignaci\u00f3n del tutor y director de tesis, la supervisi\u00f3n y seguimiento del doctorando, y la direcci\u00f3n de tesis. De todas formas, los reglamentos de todas las universidades se basan en la normativa establecida en el Real Decreto 99\/2011 de 28 de Enero por el que se regulan las ense\u00f1anzas oficiales de doctorado. Por tanto, podemos afirmar que el procedimiento para la asignaci\u00f3n del tutor y director de tesis es \u00fanico para el programa de doctorado presentado. Lo mismo ocurre en relaci\u00f3n con el procedimiento establecido para el posible cambio en la asignaci\u00f3n de tutor y\/o del director (punto 5 de la normativa general) y para el seguimiento de las actividades del doctorando (ver punto siguiente).<\/p>\n\n\n\n<p class=\"wp-block-hidden-desktop wp-block-hidden-mobile wp-block-hidden-tablet wp-block-paragraph\">Con el fin de asegurar un trato \u00fanico para todos los estudiantes en lo que a las normativas de aplicaci\u00f3n se refiere, los procedimientos y plazos establecidos en la asignaci\u00f3n del tutor y director de tesis del doctorando ser\u00e1n los establecidos por la Universidad de Valencia, independientemente de la universidad en la que se matricule el estudiante.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-53ec762\" data-v=\"4\" data-block-id=\"53ec762\"><style>.stk-53ec762-inner-blocks{row-gap:0px !important;}.stk-53ec762 {padding-top:0px !important;padding-right:0px !important;padding-bottom:0px !important;padding-left:0px !important;}@media screen and (min-width: 768px){.stk-53ec762 {flex:var(--stk-flex-grow, 1) 1 33.3% !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-53ec762-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-53ec762-inner-blocks\">\n\n<ul class=\"widget-box\">\n<li class='contacto-header'>Informaci\u00f3n de contacto<\/li><li><i class=\"fa fa-map-marker\"><\/i> Avda. Astrof\u00edsico Francisco S\u00e1nchez, SN. Edificio Calabaza \u2013 AN.2D Apdo. 456 38200 San Crist\u00f3bal de La Laguna<\/li><li><i class=\"fa fa-phone\"><\/i> (+34) 922 31 72 67<\/li><li><i class=\"fa fa-envelope\"><\/i>  <a href=mailto:doctorado.nanociencia@ull.es>doctorado.nanociencia@ull.es<\/a><\/li><li><i class=\"fa fa-calendar\"><\/i><a href=\"http:\/\/citaprevia.ull.es\/index.php?s=edpo\"> Cita previa<\/a><\/li>\n<\/ul>\n\n\n<\/div><\/div><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Thesis Supervision. Thesis Direction. Each doctoral thesis must be directed by a thesis director who will be a doctoral researcher meeting the minimum requirements established in the Regulations for Official Doctoral Studies of the University of La Laguna and who will be assigned by the academic committee. Except for justified reasons, this role\u2026<\/p>","protected":false},"author":1,"featured_media":0,"parent":27,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/template-frontpage.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-70","page","type-page","status-publish","hentry"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 10:33:05","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.ull.es\/doctorados\/nanociencia-nanotecnologia\/en\/wp-json\/wp\/v2\/pages\/70","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ull.es\/doctorados\/nanociencia-nanotecnologia\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ull.es\/doctorados\/nanociencia-nanotecnologia\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ull.es\/doctorados\/nanociencia-nanotecnologia\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ull.es\/doctorados\/nanociencia-nanotecnologia\/en\/wp-json\/wp\/v2\/comments?post=70"}],"version-history":[{"count":7,"href":"https:\/\/www.ull.es\/doctorados\/nanociencia-nanotecnologia\/en\/wp-json\/wp\/v2\/pages\/70\/revisions"}],"predecessor-version":[{"id":450,"href":"https:\/\/www.ull.es\/doctorados\/nanociencia-nanotecnologia\/en\/wp-json\/wp\/v2\/pages\/70\/revisions\/450"}],"up":[{"embeddable":true,"href":"https:\/\/www.ull.es\/doctorados\/nanociencia-nanotecnologia\/en\/wp-json\/wp\/v2\/pages\/27"}],"wp:attachment":[{"href":"https:\/\/www.ull.es\/doctorados\/nanociencia-nanotecnologia\/en\/wp-json\/wp\/v2\/media?parent=70"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}