{"id":74,"date":"2018-02-22T13:34:00","date_gmt":"2018-02-22T13:34:00","guid":{"rendered":"http:\/\/www.ull.es\/doctorados\/territorio-sociedad\/?page_id=74"},"modified":"2025-08-20T11:46:19","modified_gmt":"2025-08-20T11:46:19","slug":"normativa-presentacion-lectura-tesis","status":"publish","type":"page","link":"https:\/\/www.ull.es\/doctorados\/territorio-sociedad\/en\/organizacion-del-programa\/normativa-presentacion-lectura-tesis\/","title":{"rendered":"Regulations for the presentation and reading of theses"},"content":{"rendered":"\n<div class=\"wp-block-stackable-columns alignfull stk-block-columns stk-block stk-2314a6b\" data-block-id=\"2314a6b\"><style>.stk-2314a6b {padding-bottom:0px !important;margin-top:-100px !important;margin-bottom:0px !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-2314a6b-column alignfull\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-1d1764d\" data-v=\"4\" data-block-id=\"1d1764d\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-1d1764d-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-1d1764d-inner-blocks\"><style id=\"depicter-1-inline-pre-css\">\n\n.depicter-1:not(.depicter-ready){\n\theight:450px;\n}\n\n\/***** Tablet *****\/\n@media screen and (max-width: 1024px){\n\n.depicter-1:not(.depicter-ready){\n\theight:700px;\n}\n\n}\n\/***** Mobile *****\/\n@media screen and (max-width: 767px){\n\n.depicter-1:not(.depicter-ready){\n\theight:360px;\n}\n\n}\n<\/style>\n<div id=\"depicter-1\" class=\"depicter depicter-document depicter-revert depicter-1 depicter-layout-fullwidth\">\n\n<div class=\"depicter-loading-container depicter-loading dotFlashing-dark\"><div class=\"depicter-loading-dark depicter-dot-flashing\">\n   <span><\/span>\n   <span><\/span>\n   <span><\/span>\n<\/div>\n<\/div>\n<div id=\"depicter-1-section-1\" class=\"depicter-section depicter-1-section-1\" data-name=\"Section 1\" data-type=\"section\" data-local-id=\"section-1\">\n<picture class=\"depicter-bg\">\n<source data-depicter-srcset=\"https:\/\/www.ull.es\/doctorados\/territorio-sociedad\/wp-content\/uploads\/sites\/18\/2025\/05\/Headers-Doctorados_Doctorado-Territorio-y-Sociedad-768x248.jpg, https:\/\/www.ull.es\/doctorados\/territorio-sociedad\/wp-content\/uploads\/sites\/18\/2025\/05\/Headers-Doctorados_Doctorado-Territorio-y-Sociedad.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(max-width: 1024px)\" \/>\n\n<source data-depicter-srcset=\"https:\/\/www.ull.es\/doctorados\/territorio-sociedad\/wp-content\/uploads\/sites\/18\/2025\/05\/Headers-Doctorados_Doctorado-Territorio-y-Sociedad.jpg, https:\/\/www.ull.es\/doctorados\/territorio-sociedad\/wp-content\/uploads\/sites\/18\/2025\/05\/Headers-Doctorados_Doctorado-Territorio-y-Sociedad-2000x645.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(min-width: 1025px)\" \/>\n<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-ken-burns=\"false\" data-tablet-ken-burns=\"false\" data-mobile-ken-burns=\"false\" alt=\"\" data-depicter-src=\"https:\/\/www.ull.es\/doctorados\/territorio-sociedad\/wp-content\/uploads\/sites\/18\/2025\/05\/Headers-Doctorados_Doctorado-Territorio-y-Sociedad.jpg\" data-object-fit=\"custom,custom,\" data-object-position=\"center top,,\" data-crop=\"{&apos;focalPoint&apos;:{&apos;x&apos;:0.5,&apos;y&apos;:0.5},&apos;mediaSize&apos;:{&apos;width&apos;:1395.3488372093024736386723816394805908203125,&apos;height&apos;:450}}\" data-tablet-crop=\"{&apos;focalPoint&apos;:{&apos;x&apos;:0.5,&apos;y&apos;:0.5},&apos;mediaSize&apos;:{&apos;width&apos;:2170.54263565891460530110634863376617431640625,&apos;height&apos;:700}}\" data-mobile-crop=\"{&apos;focalPoint&apos;:{&apos;x&apos;:0.5,&apos;y&apos;:0.5},&apos;mediaSize&apos;:{&apos;width&apos;:2294.57364341085258274688385426998138427734375,&apos;height&apos;:740}}\" \/>\n<\/picture>\n\n\n<h1 id=\"depicter-1-element-5\" class=\"depicter-element depicter-layer depicter-1-element-5\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 2\" data-local-id=\"element-5\" data-offset=\"x:0px;y:100px;origin:tl\" data-tablet-offset=\"x:207px;y:236px;origin:tl\" data-mobile-offset=\"x:28px;y:104px;origin:tl\" data-width=\"1200px,auto,348px\" data-height=\"auto,auto,auto\" data-responsive-scale=\"true,,\">Programa de Doctorado en extinci\u00f3n DOCTESO Territorio y Sociedad<\/h1>\n\n<div id=\"depicter-1-element-10\" class=\"depicter-element depicter-layer depicter-1-element-10\" data-type=\"shape\" data-wrap=\"true\" data-name=\"Shape 1\" data-local-id=\"element-10\" data-offset=\"x:0px;y:356px;origin:tl\" data-tablet-offset=\"x:215px;y:396px;origin:tl\" data-mobile-offset=\"x:39px;y:303px;origin:tl\" data-width=\"950px,647px,288px\" data-height=\"8px,8px,8px\" data-responsive-scale=\"true,,\"><\/div>\n<\/div>\n<\/div>\n<script>\n(window.depicterSetups = window.depicterSetups || []).push(function(){\n\tDepicter.basePath = 'https:\/\/www.ull.es\/doctorados\/territorio-sociedad\/wp-content\/plugins\/depicter\/resources\/scripts\/player\/';\n\tconst dpPlayer = Depicter.setup('.depicter-1',\n\t\t{\"width\":[\"1200\",\"1024\",\"360\"],\"height\":[\"450\",\"700\",\"360\"],\"view\":\"basic\",\"keepAspectRatio\":true,\"preload\":0,\"layout\":\"fullwidth\",\"rtl\":false,\"initAfterAppear\":false,\"ajaxApiUrl\":\"https:\\\/\\\/www.ull.es\\\/doctorados\\\/territorio-sociedad\\\/wp-admin\\\/admin-ajax.php\",\"mouseSwipe\":true,\"touchSwipe\":true,\"useWatermark\":false}\n\t);\n});\n<\/script><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns alignfull stk-block-columns stk--hide-mobile stk-block stk-6394276 stk-block-background\" data-block-id=\"6394276\"><style>.stk-6394276 {background-color:#f33f4e !important;padding-top:10px !important;margin-bottom:0px !important;}.stk-6394276:before{background-color:#f33f4e !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-6394276-column alignfull\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-8a66885\" data-v=\"4\" data-block-id=\"8a66885\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-8a66885-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-8a66885-inner-blocks\">\n<div class=\"wp-block-stackable-spacer stk-block-spacer stk--no-padding stk-block stk-bc89b3e\" data-block-id=\"bc89b3e\"><style>.stk-bc89b3e {height:0px !important;}<\/style><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns stk-block-columns stk-block stk-8b59b96\" data-block-id=\"8b59b96\"><style>.stk-8b59b96 .stk--block-align-8b59b96{align-items:flex-start !important;}.stk-8b59b96 {margin-top:50px !important;}.stk-8b59b96-column{--stk-columns-spacing:0px !important;--stk-column-gap:50px !important;}<\/style><div class=\"stk-row stk-inner-blocks stk--block-align-8b59b96 stk-block-content stk-content-align stk-8b59b96-column\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-dbb7e15\" data-v=\"4\" data-block-id=\"dbb7e15\"><style>@media screen and (min-width: 768px){.stk-dbb7e15 {flex:var(--stk-flex-grow, 1) 1 66.7% !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-dbb7e15-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-dbb7e15-inner-blocks\">\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-cc0239e\" id=\"complementos-de-formacion\" data-block-id=\"cc0239e\"><style>.stk-cc0239e .stk-block-heading__text{color:#000000 !important;font-weight:500 !important;}<\/style><h1 class=\"stk-block-heading__text has-text-color\">Normativa de presentaci\u00f3n y lectura de tesis<\/h1><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">La normativa de lectura de tesis de este Programa queda recogida por lo estipulado en el Convenio para la organizaci\u00f3n del programa de doctorado suscrito entre las universidades de Las Palmas de Gran Canaria y de La Laguna por el que recae la coordinaci\u00f3n general en la ULPGC y en particular la constituci\u00f3n de los tribunales de evaluaci\u00f3n que se rigen por la normativa vigente de la universidad coordinadora. Dicha normativa se desarrolla en el&nbsp;<a href=\"http:\/\/www.ulpgc.es\/hege\/almacen\/download\/7102\/7102133\/reglamento_de_estudios_de_doctorado_de_17_de_diciembre_de_2012_modificado_el_23_de_octubre_de_2013.pdf\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">Reglamento de Estudios de Doctorado de la ULPGC<\/a>, en sus Cap\u00edtulos III, IV y V donde se expone todo lo relativo al formato y autorizaci\u00f3n de defensa de la tesis doctoral, defensa de la tesis doctoral y la menci\u00f3n internacional en el t\u00edtulo de doctor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para asegurar un mayor flujo de conocimientos, se ha establecido que podr\u00e1n formar parte de la Comisi\u00f3n Acad\u00e9mica hasta dos personas de reconocido prestigio ajenas al Programa de Doctorado, y por tanto tendr\u00edan encomendado el seguimiento de los doctorandos. Estas personas pueden ser de cualquier nacionalidad. En cuanto a la participaci\u00f3n de expertos internacionales en la evaluaci\u00f3n de las tesis doctorales hay que distinguir entre dos supuestos diferentes. Por una parte, aquellas tesis que opten a la Menci\u00f3n Internacional deber\u00e1n estar informadas obligatoriamente por dos personas que pertenezcan a organismos no nacionales y luego tendr\u00e1 que participar como miembro del tribunal otra tercera persona que tampoco pertenezca a un organismo espa\u00f1ol. En el caso de las tesis que no opten a la menci\u00f3n internacional, se propone que \u00e9sta sea informada por una persona experta ajena al programa de doctorado, que puede ser espa\u00f1ola o no, dependiendo de su adecuaci\u00f3n para evaluar el tema del trabajo de investigaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A continuaci\u00f3n se hace un extracto de dichos cap\u00edtulos del reglamento con la inclusi\u00f3n de la menci\u00f3n a la Universidad de La Laguna en los puntos pertinentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Cap\u00edtulo III. Formato y autorizaci\u00f3n de defensa de la tesis doctoral<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Art\u00edculo 8.- Autorizaci\u00f3n y Dep\u00f3sito de la tesis doctoral<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1. Finalizada la elaboraci\u00f3n de la tesis doctoral, el doctorando entregar\u00e1 una copia de la misma, acompa\u00f1ada de la autorizaci\u00f3n del director\/es, a la Comisi\u00f3n Acad\u00e9mica del Programa de Doctorado (Impreso \u201cAutorizaci\u00f3n Presentaci\u00f3n Tesis\u201d).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2. La Comisi\u00f3n Acad\u00e9mica del Programa de Doctorado, en un plazo m\u00e1ximo de 15 d\u00edas, dar\u00e1 o no la conformidad para su tramitaci\u00f3n. Para ello, la Comisi\u00f3n Acad\u00e9mica establecer\u00e1 criterios objetivos que incluir\u00e1n, al menos, la obligatoriedad de que el doctorando haya producido, como primer autor o autor principal, una contribuci\u00f3n cient\u00edfica (publicaciones en revistas, libros o cap\u00edtulos de libro, patentes u obras art\u00edsticas) de calidad contrastada y que contribuya al sostenimiento de Programa de Doctorado, derivada de la Tesis Doctoral, antes de su dep\u00f3sito. Para acreditar la condici\u00f3n de autor principal, esta deber\u00e1 ser reconocida por el resto de los autores de la contribuci\u00f3n cient\u00edfica, al mismo tiempo que ninguno de los otros autores podr\u00e1 presentar la misma contribuci\u00f3n cient\u00edfica en calidad de autor principal para obtener la conformidad para la tramitaci\u00f3n de su propia tesis doctoral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">3. El doctorando que haya obtenido la conformidad para el dep\u00f3sito de la tesis doctoral, entregar\u00e1 en los servicios administrativos de la Universidad nueve ejemplares encuadernados de la misma y una copia en formato digital, acompa\u00f1ados de un folio con un resumen de la tesis a una cara y a doble espacio, tambi\u00e9n en formato digital, y la autorizaci\u00f3n del director\/es y de la unidad responsable del Programa de Doctorado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">4. El plazo de dep\u00f3sito ser\u00e1 de 15 d\u00edas h\u00e1biles, durante dicho periodo la tesis podr\u00e1 ser examinada por otros doctores que podr\u00e1n remitir a la unidad responsable del Programa de Doctorado y al Vicerrectorado con competencias en estudios de Doctorado, las observaciones sobre su contenido que estimen oportunas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">5. Los servicios administrativos de la Universidad har\u00e1n p\u00fablica la informaci\u00f3n relativa a las tesis doctorales, desde su presentaci\u00f3n a dep\u00f3sito hasta su defensa, en la web institucional de la Universidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Art\u00edculo 9.- Contenido de la tesis doctoral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La tesis doctoral consistir\u00e1 en un trabajo original de investigaci\u00f3n elaborado por el doctorando sobre un tema relacionada con el campo cient\u00edfico, t\u00e9cnico o art\u00edstico, propio del Programa de Doctorado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El trabajo contendr\u00e1, al menos, una introducci\u00f3n o estado de la cuesti\u00f3n, los objetivos planteados, la metodolog\u00eda desarrollada, los resultados y la discusi\u00f3n de los mismos, as\u00ed como las conclusiones m\u00e1s relevantes y la bibliograf\u00eda utilizada. No ser\u00e1 necesario que tales contenidos figuren en ep\u00edgrafes espec\u00edficos en el documento final que se presente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Art\u00edculo 10.- Lengua de la tesis doctoral<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La tesis podr\u00e1 ser desarrollada y, en su caso, defendida, en los idiomas habituales para la comunicaci\u00f3n cient\u00edfica en su campo de conocimiento. Las tesis doctorales escritas en una lengua distinta a la espa\u00f1ola, deber\u00e1n contener en la propia encuadernaci\u00f3n un resumen en espa\u00f1ol sobre el contenido de la misma, de una extensi\u00f3n de entre 5 y 20 p\u00e1ginas, en el que se incluyan los objetivos y las conclusiones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Art\u00edculo 11.- Formato de la memoria de tesis<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En los ejemplares de la tesis doctoral deber\u00e1n figurar los siguientes datos:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1. En la cubierta de todos los ejemplares, el logotipo, de acuerdo al manual de imagen corporativa, el nombre de la Universidad de Las Palmas de Gran Canaria o de la Universidad de La Laguna, el nombre del Programa de Doctorado, t\u00edtulo, autor, fecha y lugar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2. Un ejemplar, que a todos los efectos se considerar\u00e1 el original, contendr\u00e1 dos p\u00e1ginas iniciales adicionales. Una primera p\u00e1gina en blanco donde los servicios administrativos de la Universidad har\u00e1n constar, en su momento, el tribunal, calificaci\u00f3n global otorgada, fecha y firmas. La segunda p\u00e1gina contendr\u00e1 la certificaci\u00f3n de la Comisi\u00f3n Acad\u00e9mica del Programa de Doctorado con la autorizaci\u00f3n para su presentaci\u00f3n a dep\u00f3sito.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">3. En todos los ejemplares la siguiente p\u00e1gina contendr\u00e1 los siguientes datos: el logotipo o escudo y nombre de la Universidad de Las Palmas de Gran Canaria o de la Universidad de La Laguna, el nombre del Programa de Doctorado cursado, el nombre de la unidad responsable del Programa de Doctorado donde se ha realizado la tesis doctoral, el t\u00edtulo de la misma, nombre y firmas del autor y director\/es, y el lugar y fecha de finalizaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">4. Una vez registrados los ejemplares, los servicios administrativos de la Universidad devolver\u00e1n al estudiante siete ejemplares para que puedan ser remitidos a los miembros del tribunal a trav\u00e9s de la unidad responsable del Programa de Doctorado, cuando los servicios administrativos de la Universidad comuniquen la designaci\u00f3n de los mismos. El octavo ejemplar quedar\u00e1 en dep\u00f3sito en la unidad responsable del Programa de Doctorado. El noveno ejemplar, el original, y la memoria de la tesis en soporte digital quedar\u00e1n en dep\u00f3sito.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Art\u00edculo 12.- Tesis por compendio de publicaciones<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1. Para la presentaci\u00f3n de tesis por compendio de publicaciones ser\u00e1 necesario:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">a. Un m\u00ednimo de tres publicaciones, con unidad tem\u00e1tica, indexadas en el Journal Citations Reports, Arts and Humanities Citation Index o equivalentes, de las que el doctorando sea el primer autor o autor principal. Al menos una de ellas deber\u00e1 haber sido publicada en una revista cuyo \u00edndice de impacto la sit\u00fae dentro de la primera mitad en orden decreciente de \u00edndice de impacto entre las revistas del \u00e1rea.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">b. Para acreditar la condici\u00f3n de autor principal, esta deber\u00e1 ser reconocida por el resto de los autores de las publicaciones presentadas como n\u00facleo de la tesis doctoral, al mismo tiempo que estos deber\u00e1n renunciar a utilizar estas publicaciones como n\u00facleo principal de otras tesis doctorales, sin perjuicio de que dichas publicaciones puedan ser presentadas como m\u00e9ritos complementarios en las tesis doctorales que pudieran presentar los otros autores de dichas publicaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">c. En \u00e1reas de especial incidencia tecnol\u00f3gica dos de estas publicaciones podr\u00e1n ser sustituidas por patentes en explotaci\u00f3n o publicaciones en congresos reconocidos por la ANEP en sus baremos para la obtenci\u00f3n de sexenios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">d. Que en las publicaciones o patentes conste la ULPGC o la ULL a trav\u00e9s de la filiaci\u00f3n del director o del doctorando.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2. Las tesis doctorales presentadas como compendio de publicaciones deber\u00e1n ajustarse al formato establecido y contener los apartados siguientes:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">a. Una introducci\u00f3n en la que se presenten los objetivos de la tesis, los trabajos publicados y la justificaci\u00f3n de la unidad tem\u00e1tica de la tesis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">b. Una copia de los trabajos publicados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">c. Las conclusiones finales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">d. En el caso de que lo dispuesto en los apartados a y c se haya redactado en una lengua diferente del Espa\u00f1ol, deber\u00e1 incluirse un resumen en Espa\u00f1ol.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Art\u00edculo 13.- Autorizaci\u00f3n de defensa de la tesis<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1. Transcurrido el plazo de dep\u00f3sito sin haberse producido ninguna incidencia, el Vicerrectorado con competencias en estudios de doctorado autorizar\u00e1, en el plazo m\u00e1ximo de 15 d\u00edas, la defensa de la tesis doctoral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2. En caso contrario, el Vicerrectorado con competencias en estudios de doctorado, previa consulta a la Comisi\u00f3n de Doctorado, decidir\u00e1 sobre la autorizaci\u00f3n o no de la defensa de la tesis doctoral, previa audiencia del doctorando, de todo lo cual informar\u00e1 al doctorando, al director\/es y a la unidad responsable del Programa de Doctorado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">3. Tras la autorizaci\u00f3n de la defensa, se dispone de un plazo de 7 d\u00edas para que el doctorando formalice la correspondiente matr\u00edcula y para que la unidad responsable del Programa de Doctorado remita al Vicerrectorado con competencias en estudios de doctorado la propuesta de tribunal (Impreso \u201cPropuesta Tribunal Tesis\u201d) acompa\u00f1ado de copia del documento de actividades del doctorando a que hace referencia el art. 3, apartado 7.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Cap\u00edtulo IV. Defensa de la tesis doctoral<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Art\u00edculo 14. Tribunal de la tesis doctoral<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez realizada la matr\u00edcula de la tesis doctoral, el Vicerrectorado con competencias en estudios de doctorado, a propuesta de la Comisi\u00f3n Acad\u00e9mica del Programa de Doctorado, designar\u00e1 y comunicar\u00e1 en el plazo m\u00e1ximo de 7 d\u00edas desde la recepci\u00f3n de la propuesta, siete miembros para conformar el tribunal evaluador de la tesis doctoral de los cuales, cinco ser\u00e1n miembros titulares y dos suplentes. Dicha designaci\u00f3n ser\u00e1 notificada a la unidad responsable del Programa de Doctorado. En la composici\u00f3n del tribunal se deber\u00e1n tener en cuenta:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1. Todos los miembros deber\u00e1n ser doctores con experiencia investigadora acreditada, equivalente a la exigida para ser director una tesis doctoral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2. En la propuesta del tribunal se har\u00e1 constar para cada miembro la categor\u00eda administrativa, la antig\u00fcedad en la misma, organismo al que pertenece y direcci\u00f3n a efectos de notificaciones y remisi\u00f3n del ejemplar de tesis doctoral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">3. El tribunal estar\u00e1 formado por una mayor\u00eda de miembros externos a la Universidad de Las Palmas de Gran Canaria y en su caso de La Laguna y a las instituciones colaboradoras en el Programa de Doctorado y, en ning\u00fan caso, podr\u00e1 formar parte del mismo el director\/es de la tesis doctoral. En todo caso, deber\u00e1n formar parte del tribunal, al menos, tres profesores\/investigadores de universidades\/instituciones espa\u00f1olas y, al menos, el tribunal contendr\u00e1 cuatro profesores\/ investigadores del EEES, respetando el m\u00e1ximo de dos miembros del mismo departamento\/centro o universidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">4. De entre los propuestos, el presidente y el secretario ser\u00e1n nombrados por la Comisi\u00f3n Acad\u00e9mica del programa de doctorado. El secretario, que pertenecer\u00e1 siempre que sea posible a la Universidad de Las Palmas de Gran Canaria o en su caso a La Laguna, realizar\u00e1 las actuaciones administrativas y de gesti\u00f3n econ\u00f3mica propias del tribunal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">5. Para que el acto de defensa pueda celebrarse, el tribunal deber\u00e1 estar constituido por cinco miembros, para lo cual el Presidente, con la colaboraci\u00f3n de la comisi\u00f3n acad\u00e9mica del Programa de Doctorado o persona\/s delegada\/s por esta comisi\u00f3n, realizar\u00e1 las actuaciones en cuanto a decisi\u00f3n de la fecha de lectura y sustituci\u00f3n de los miembros titulares por los suplentes cuando ello sea necesario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Art\u00edculo 15-. Acto de defensa de la tesis doctoral<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1. Una vez recibido el nombramiento para tribunal del Vicerrectorado con competencias en estudios de doctorado, el presidente proceder\u00e1 a convocar en el plazo m\u00e1ximo de 15 d\u00edas el acto de defensa de la tesis doctoral. El secretario del tribunal comunicar\u00e1 dicha convocatoria a los miembros titulares y suplentes del tribunal, a la unidad responsable del Programa de Doctorado y a los servicios administrativos de la Universidad, que har\u00e1n p\u00fablico el lugar y fecha del acto de defensa y preparar\u00e1n el expediente para el acto de lectura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2. El acto de defensa de la tesis doctoral tendr\u00e1 lugar en sesi\u00f3n p\u00fablica en el periodo comprendido entre 15 d\u00edas y 2 meses contados a partir de la fecha de la comunicaci\u00f3n enviada por el secretario. La unidad responsable del Programa de Doctorado remitir\u00e1 un ejemplar de la tesis doctoral a cada miembro del tribunal, con antelaci\u00f3n suficiente para su an\u00e1lisis antes de la fecha de lectura. El acto defensa de la tesis tendr\u00e1 lugar en sesi\u00f3n p\u00fablica durante el periodo lectivo del calendario acad\u00e9mico. A estos efectos, se considerar\u00e1 como periodo no lectivo el comprendido entre el 1 y el 31 de agosto, ambos inclusive, todos los s\u00e1bados, domingos y los d\u00edas fijados expresamente como festivos por la Comunidad Aut\u00f3noma de Canarias, as\u00ed como los previstos en el calendario acad\u00e9mico aprobado por el Consejo de Gobierno de la Universidad. Excepcionalmente, previa autorizaci\u00f3n del Vicerrector competente en materia de doctorado, podr\u00e1 desarrollarse el acto de defensa de la tesis doctoral dentro de los periodos anteriormente se\u00f1alados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">3. La defensa de la tesis doctoral deber\u00e1 realizarse preferiblemente en las instalaciones de la Universidad de Las Palmas de Gran Canaria y en su caso de la Universidad de La Laguna. La Comisi\u00f3n Acad\u00e9mica del Programa de Doctorado articular\u00e1 los mecanismos adecuados para ello. En caso de que se desee realizar la defensa en instalaciones ajenas a la Universidad de Las Palmas de Gran Canaria o en su caso de la Universidad de La Laguna, ser\u00e1 necesaria la autorizaci\u00f3n expresa del Vicerrector con competencias en estudios de Doctorado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">4. En lo referente a la constituci\u00f3n y funcionamiento del tribunal, incluyendo la posibilidad de que el doctorando o alg\u00fan miembro del tribunal participe en el acto de defensa mediante videoconferencia, el presidente del tribunal, o\u00eddos el resto de los miembros, tomar\u00e1 las decisiones que considere oportunas y que aseguren la calidad del acto acad\u00e9mico en todos sus apartados. En todo caso, se deber\u00e1 garantizar la confidencialidad de las deliberaciones del tribunal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">5. Durante la lectura, el doctorando deber\u00e1 exponer y defender el trabajo de investigaci\u00f3n elaborado ante el tribunal en un periodo no superior a una hora. Los miembros del tribunal expresar\u00e1n su opini\u00f3n y formular\u00e1n al doctorando las cuestiones o comentarios que consideren oportunos, en un periodo no superior a dos horas. Los doctores presentes en el acto p\u00fablico podr\u00e1n formular cuestiones en el momento y forma que se\u00f1ale el presidente. El presidente podr\u00e1 autorizar asimismo al director\/es de la tesis doctoral para que intervengan en el debate correspondiente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">6. Alternativamente, a propuesta del director de la tesis, el acto de defensa podr\u00e1 ser organizado de forma en que la intervenci\u00f3n del doctorando sea precedida por la exposici\u00f3n cr\u00edtica y dinamizadora del debate, de los m\u00e9ritos de investigaci\u00f3n del doctorando por parte de un ponente designado de entre los miembros del tribunal, durante 30 minutos. En esta f\u00f3rmula el doctorando centrar\u00e1 su ejercicio en los comentarios y preguntas del tribunal y doctores presentes en la sala. El ponente deber\u00e1 acreditar experiencia investigadora equivalente a tres sexenios de investigaci\u00f3n o equiparable.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Art\u00edculo 16.- Evaluaci\u00f3n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1. El tribunal dispondr\u00e1 del documento de actividades del doctorando, que constituir\u00e1 un instrumento de evaluaci\u00f3n cualitativa que complementar\u00e1 la evaluaci\u00f3n de la tesis doctoral. Dicho documento incluir\u00e1 las publicaciones o resultados a los que ha dado lugar la investigaci\u00f3n o la previsi\u00f3n de los mismos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2. Finalizado el acto de defensa, el tribunal emitir\u00e1 un informe y la calificaci\u00f3n global concedida a la tesis en t\u00e9rminos de \u00abapto\u00bb o \u00abno apto\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">3. El tribunal podr\u00e1 proponer que la tesis obtenga la menci\u00f3n de \u00abcum laude\u00bb, si se emite en tal sentido el voto secreto positivo por unanimidad. La Universidad habilitar\u00e1 los mecanismos precisos para la materializaci\u00f3n de la concesi\u00f3n final de dicha menci\u00f3n garantizando que el escrutinio de los votos para dicha concesi\u00f3n se realice en sesi\u00f3n diferente de la correspondiente a la de defensa de la tesis doctoral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Art\u00edculo 17-. Archivo y Documentaci\u00f3n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1. Una vez aprobada la tesis doctoral, el secretario del tribunal devolver\u00e1, en el plazo m\u00e1ximo de 5 d\u00edas h\u00e1biles, a los servicios administrativos de la Universidad, la documentaci\u00f3n del acto de defensa y el ejemplar original de la misma a efectos de archivo y documentaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2. Los servicios administrativos de la Universidad remitir\u00e1n, en formato electr\u00f3nico, un ejemplar de la misma, as\u00ed como toda la informaci\u00f3n complementaria que fuera necesaria, al Ministerio de Educaci\u00f3n a los efectos oportunos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">3. La Universidad de Las Palmas de Gran Canaria y en su caso la Universidad de La Laguna, con el consentimiento emitido por el doctorando, asignar\u00e1 un n\u00famero ISBN y establecer\u00e1 las normas de entrega a la Biblioteca Universitaria en soporte digital para garantizar la difusi\u00f3n en un repositorio institucional y la preservaci\u00f3n de la propiedad intelectual.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">4. En circunstancias excepcionales, determinadas por la Comisi\u00f3n Acad\u00e9mica del Programa de Doctorado, como pueden ser, entre otras, la participaci\u00f3n de empresas en el Programa, la existencia de convenios de confidencialidad o la posibilidad de generaci\u00f3n de patentes que deriven del contenido de la tesis, tanto en su defensa como en su archivo, se asegurar\u00e1 la no publicidad de los aspectos: metodolog\u00eda, resultados y conclusiones, que pudieran estar afectados y se incluir\u00e1 referencia y copia del documento a que est\u00e9 sujeto la privacidad de estos. Dicha documentaci\u00f3n, incluido el informe de la Comisi\u00f3n Acad\u00e9mica del Programa de Doctorado, se enviar\u00e1 en el momento de la propuesta del tribunal al Vicerrectorado con competencias en estudios de doctorado, para autorizar la defensa de \u00e9sta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Cap\u00edtulo V. Menci\u00f3n internacional en el t\u00edtulo de doctor<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Art\u00edculo 18.- Menci\u00f3n internacional en el t\u00edtulo de Doctor<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1. En el anverso del t\u00edtulo de Doctor o Doctora podr\u00e1 incluirse la menci\u00f3n \u00abDoctor internacional\u00bb, cuando concurran las siguientes circunstancias:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">a. Que, durante el periodo de formaci\u00f3n necesario para la obtenci\u00f3n del t\u00edtulo de Doctor, el doctorando haya realizado una estancia m\u00ednima de tres meses fuera de Espa\u00f1a en una instituci\u00f3n de ense\u00f1anza superior o centro de investigaci\u00f3n de prestigio, cursando estudios o realizando trabajos de investigaci\u00f3n. La estancia y las actividades han de ser avaladas por el director y autorizadas por la Comisi\u00f3n Acad\u00e9mica, y se incorporar\u00e1n al documento de actividades del doctorando.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">b. Que parte de la tesis doctoral, al menos el resumen y las conclusiones, se haya redactado y sea presentado en una de las lenguas habituales para la comunicaci\u00f3n cient\u00edfica en su campo de conocimiento, distinta a cualquiera de las lenguas oficiales en Espa\u00f1a. Esta norma no ser\u00e1 de aplicaci\u00f3n cuando las estancias, informes y expertos procedan de un pa\u00eds de habla hispana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">c. Que la tesis haya sido informada por un m\u00ednimo de dos expertos, doctores pertenecientes a alguna instituci\u00f3n de educaci\u00f3n superior o instituto de investigaci\u00f3n no espa\u00f1ola.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">d. Que, al menos, un experto perteneciente a alguna instituci\u00f3n de educaci\u00f3n superior o centro de investigaci\u00f3n no espa\u00f1ola, con el t\u00edtulo de doctor, y distinto del responsable de la estancia mencionada en el apartado 1, haya formado parte del tribunal evaluador de la tesis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2. La defensa de la tesis ha de efectuarse preferiblemente, en la Universidad en la que el doctorando est\u00e9 inscrito.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">3. La solicitud de la Menci\u00f3n internacional deber\u00e1 formularse simult\u00e1neamente a la presentaci\u00f3n de la tesis doctoral para su admisi\u00f3n a tr\u00e1mite (Impreso \u201cMenci\u00f3n Internacional Doctorado\u201d).<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-53ec762\" data-v=\"4\" data-block-id=\"53ec762\"><style>.stk-53ec762-inner-blocks{row-gap:0px !important;}.stk-53ec762 {padding-top:0px !important;padding-right:0px !important;padding-bottom:0px !important;padding-left:0px !important;}@media screen and (min-width: 768px){.stk-53ec762 {flex:var(--stk-flex-grow, 1) 1 33.3% !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-53ec762-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-53ec762-inner-blocks\">\n\n<ul class=\"widget-box\">\n<li class='contacto-header'>Informaci\u00f3n de contacto<\/li><li><i class=\"fa fa-map-marker\"><\/i> Avda. Astrof\u00edsico Francisco S\u00e1nchez, SN. Edificio Calabaza \u2013 AN.2D Apdo. 456 38200 San Crist\u00f3bal de La Laguna<\/li><li><i class=\"fa fa-envelope\"><\/i>  <a href=mailto:docteso@ull.es>docteso@ull.es<\/a><\/li><li><i class=\"fa fa-calendar\"><\/i><a href=\"http:\/\/citaprevia.ull.es\/index.php?s=edpo\"> Cita previa<\/a><\/li>\n<\/ul>\n\n\n<\/div><\/div><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Thesis presentation and reading regulations The theses reading regulations for this Program are set out in the Agreement for the organization of the doctoral program signed between the universities of Las Palmas de Gran Canaria and La Laguna, under which the general coordination falls to the ULPGC\u2026<\/p>","protected":false},"author":1,"featured_media":0,"parent":27,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/template-frontpage.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-74","page","type-page","status-publish","hentry"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 20:38:36","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.ull.es\/doctorados\/territorio-sociedad\/en\/wp-json\/wp\/v2\/pages\/74","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ull.es\/doctorados\/territorio-sociedad\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ull.es\/doctorados\/territorio-sociedad\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ull.es\/doctorados\/territorio-sociedad\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ull.es\/doctorados\/territorio-sociedad\/en\/wp-json\/wp\/v2\/comments?post=74"}],"version-history":[{"count":6,"href":"https:\/\/www.ull.es\/doctorados\/territorio-sociedad\/en\/wp-json\/wp\/v2\/pages\/74\/revisions"}],"predecessor-version":[{"id":357,"href":"https:\/\/www.ull.es\/doctorados\/territorio-sociedad\/en\/wp-json\/wp\/v2\/pages\/74\/revisions\/357"}],"up":[{"embeddable":true,"href":"https:\/\/www.ull.es\/doctorados\/territorio-sociedad\/en\/wp-json\/wp\/v2\/pages\/27"}],"wp:attachment":[{"href":"https:\/\/www.ull.es\/doctorados\/territorio-sociedad\/en\/wp-json\/wp\/v2\/media?parent=74"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}