{"id":60,"date":"2018-02-22T12:18:16","date_gmt":"2018-02-22T12:18:16","guid":{"rendered":"http:\/\/www.ull.es\/doctorados\/territorio-sociedad\/?page_id=60"},"modified":"2025-08-20T11:44:58","modified_gmt":"2025-08-20T11:44:58","slug":"actividades-formativas","status":"publish","type":"page","link":"https:\/\/www.ull.es\/doctorados\/territorio-sociedad\/fr\/organizacion-del-programa\/actividades-formativas\/","title":{"rendered":"Activit\u00e9s de formation"},"content":{"rendered":"\n<div class=\"wp-block-stackable-columns alignfull stk-block-columns stk-block stk-2314a6b\" data-block-id=\"2314a6b\"><style>.stk-2314a6b {padding-bottom:0px !important;margin-top:-100px !important;margin-bottom:0px !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-2314a6b-column alignfull\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-1d1764d\" data-v=\"4\" data-block-id=\"1d1764d\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-1d1764d-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-1d1764d-inner-blocks\"><style id=\"depicter-1-inline-pre-css\">\n\n.depicter-1:not(.depicter-ready){\n\theight:450px;\n}\n\n\/***** Tablet *****\/\n@media screen and (max-width: 1024px){\n\n.depicter-1:not(.depicter-ready){\n\theight:700px;\n}\n\n}\n\/***** Mobile *****\/\n@media screen and (max-width: 767px){\n\n.depicter-1:not(.depicter-ready){\n\theight:360px;\n}\n\n}\n<\/style>\n<div id=\"depicter-1\" class=\"depicter depicter-document depicter-revert depicter-1 depicter-layout-fullwidth\">\n\n<div class=\"depicter-loading-container depicter-loading dotFlashing-dark\"><div class=\"depicter-loading-dark depicter-dot-flashing\">\n   <span><\/span>\n   <span><\/span>\n   <span><\/span>\n<\/div>\n<\/div>\n<div id=\"depicter-1-section-1\" class=\"depicter-section depicter-1-section-1\" data-name=\"Section 1\" data-type=\"section\" data-local-id=\"section-1\">\n<picture class=\"depicter-bg\">\n<source data-depicter-srcset=\"https:\/\/www.ull.es\/doctorados\/territorio-sociedad\/wp-content\/uploads\/sites\/18\/2025\/05\/Headers-Doctorados_Doctorado-Territorio-y-Sociedad-768x248.jpg, https:\/\/www.ull.es\/doctorados\/territorio-sociedad\/wp-content\/uploads\/sites\/18\/2025\/05\/Headers-Doctorados_Doctorado-Territorio-y-Sociedad.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(max-width: 1024px)\" \/>\n\n<source data-depicter-srcset=\"https:\/\/www.ull.es\/doctorados\/territorio-sociedad\/wp-content\/uploads\/sites\/18\/2025\/05\/Headers-Doctorados_Doctorado-Territorio-y-Sociedad.jpg, https:\/\/www.ull.es\/doctorados\/territorio-sociedad\/wp-content\/uploads\/sites\/18\/2025\/05\/Headers-Doctorados_Doctorado-Territorio-y-Sociedad-2000x645.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(min-width: 1025px)\" \/>\n<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-ken-burns=\"false\" data-tablet-ken-burns=\"false\" data-mobile-ken-burns=\"false\" alt=\"\" data-depicter-src=\"https:\/\/www.ull.es\/doctorados\/territorio-sociedad\/wp-content\/uploads\/sites\/18\/2025\/05\/Headers-Doctorados_Doctorado-Territorio-y-Sociedad.jpg\" data-object-fit=\"custom,custom,\" data-object-position=\"center top,,\" data-crop=\"{&apos;focalPoint&apos;:{&apos;x&apos;:0.5,&apos;y&apos;:0.5},&apos;mediaSize&apos;:{&apos;width&apos;:1395.3488372093024736386723816394805908203125,&apos;height&apos;:450}}\" data-tablet-crop=\"{&apos;focalPoint&apos;:{&apos;x&apos;:0.5,&apos;y&apos;:0.5},&apos;mediaSize&apos;:{&apos;width&apos;:2170.54263565891460530110634863376617431640625,&apos;height&apos;:700}}\" data-mobile-crop=\"{&apos;focalPoint&apos;:{&apos;x&apos;:0.5,&apos;y&apos;:0.5},&apos;mediaSize&apos;:{&apos;width&apos;:2294.57364341085258274688385426998138427734375,&apos;height&apos;:740}}\" \/>\n<\/picture>\n\n\n<h1 id=\"depicter-1-element-5\" class=\"depicter-element depicter-layer depicter-1-element-5\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 2\" data-local-id=\"element-5\" data-offset=\"x:0px;y:100px;origin:tl\" data-tablet-offset=\"x:207px;y:236px;origin:tl\" data-mobile-offset=\"x:28px;y:104px;origin:tl\" data-width=\"1200px,auto,348px\" data-height=\"auto,auto,auto\" data-responsive-scale=\"true,,\">Programa de Doctorado en extinci\u00f3n DOCTESO Territorio y Sociedad<\/h1>\n\n<div id=\"depicter-1-element-10\" class=\"depicter-element depicter-layer depicter-1-element-10\" data-type=\"shape\" data-wrap=\"true\" data-name=\"Shape 1\" data-local-id=\"element-10\" data-offset=\"x:0px;y:356px;origin:tl\" data-tablet-offset=\"x:215px;y:396px;origin:tl\" data-mobile-offset=\"x:39px;y:303px;origin:tl\" data-width=\"950px,647px,288px\" data-height=\"8px,8px,8px\" data-responsive-scale=\"true,,\"><\/div>\n<\/div>\n<\/div>\n<script>\n(window.depicterSetups = window.depicterSetups || []).push(function(){\n\tDepicter.basePath = 'https:\/\/www.ull.es\/doctorados\/territorio-sociedad\/wp-content\/plugins\/depicter\/resources\/scripts\/player\/';\n\tconst dpPlayer = Depicter.setup('.depicter-1',\n\t\t{\"width\":[\"1200\",\"1024\",\"360\"],\"height\":[\"450\",\"700\",\"360\"],\"view\":\"basic\",\"keepAspectRatio\":true,\"preload\":0,\"layout\":\"fullwidth\",\"rtl\":false,\"initAfterAppear\":false,\"ajaxApiUrl\":\"https:\\\/\\\/www.ull.es\\\/doctorados\\\/territorio-sociedad\\\/wp-admin\\\/admin-ajax.php\",\"mouseSwipe\":true,\"touchSwipe\":true,\"useWatermark\":false}\n\t);\n});\n<\/script><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns alignfull stk-block-columns stk--hide-mobile stk-block stk-6394276 stk-block-background\" data-block-id=\"6394276\"><style>.stk-6394276 {background-color:#f33f4e !important;padding-top:10px !important;margin-bottom:0px !important;}.stk-6394276:before{background-color:#f33f4e !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-6394276-column alignfull\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-8a66885\" data-v=\"4\" data-block-id=\"8a66885\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-8a66885-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-8a66885-inner-blocks\">\n<div class=\"wp-block-stackable-spacer stk-block-spacer stk--no-padding stk-block stk-bc89b3e\" data-block-id=\"bc89b3e\"><style>.stk-bc89b3e {height:0px !important;}<\/style><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns stk-block-columns stk-block stk-8b59b96\" data-block-id=\"8b59b96\"><style>.stk-8b59b96 .stk--block-align-8b59b96{align-items:flex-start !important;}.stk-8b59b96 {margin-top:50px !important;}.stk-8b59b96-column{--stk-columns-spacing:0px !important;--stk-column-gap:50px !important;}<\/style><div class=\"stk-row stk-inner-blocks stk--block-align-8b59b96 stk-block-content stk-content-align stk-8b59b96-column\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-dbb7e15\" data-v=\"4\" data-block-id=\"dbb7e15\"><style>@media screen and (min-width: 768px){.stk-dbb7e15 {flex:var(--stk-flex-grow, 1) 1 66.7% !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-dbb7e15-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-dbb7e15-inner-blocks\">\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-cc0239e\" id=\"complementos-de-formacion\" data-block-id=\"cc0239e\"><style>.stk-cc0239e .stk-block-heading__text{color:#000000 !important;font-weight:500 !important;}<\/style><h1 class=\"stk-block-heading__text has-text-color\">Actividades formativas<\/h1><\/div>\n\n\n\n<details class=\"wp-block-stackable-accordion stk-block-accordion stk-inner-blocks stk-block-content stk-block stk-7c390cd is-style-default\" id=\"difusion\" data-block-id=\"7c390cd\"><style>.stk-7c390cd {border-style:solid !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;margin-bottom:11px !important;}<\/style>\n<summary class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-c927805 stk--container-small stk-block-accordion__heading\" data-v=\"4\" data-block-id=\"c927805\"><style>.stk-c927805 {padding-top:2px !important;padding-right:2px !important;padding-bottom:2px !important;padding-left:2px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-c927805-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-c927805-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-7935446\" data-block-id=\"7935446\"><style>.stk-7935446 .stk-inner-blocks{gap:39px !important;}@media screen and (max-width: 1023px){.stk-7935446 .stk-inner-blocks{gap:39px !important;}}@media screen and (max-width: 767px){.stk-7935446 .stk-inner-blocks{gap:39px !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-icon stk-block-icon stk-block stk-9a468d5\" data-block-id=\"9a468d5\"><style>.stk-9a468d5 .stk--svg-wrapper .stk--inner-svg svg:last-child{height:25px !important;width:25px !important;}.stk-9a468d5 .stk--svg-wrapper .stk--inner-svg svg:last-child, .stk-9a468d5 .stk--svg-wrapper .stk--inner-svg svg:last-child :is(g, path, rect, polygon, ellipse){fill:#f33f4e !important;}<\/style><span class=\"stk--svg-wrapper stk--has-icon2\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-9a468d5\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-9-a-468-d-5-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-9-a-468-d-5-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M256 288A144 144 0 1 0 256 0a144 144 0 1 0 0 288zm-94.7 32C72.2 320 0 392.2 0 481.3c0 17 13.8 30.7 30.7 30.7H481.3c17 0 30.7-13.8 30.7-30.7C512 392.2 439.8 320 350.7 320H161.3z\"><\/path><\/svg><\/div><div class=\"stk--inner-svg stk--icon-2\" style=\"display:none\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-9a468d5\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-9-a-468-d-5-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-9-a-468-d-5-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M304 128a80 80 0 1 0 -160 0 80 80 0 1 0 160 0zM96 128a128 128 0 1 1 256 0A128 128 0 1 1 96 128zM49.3 464H398.7c-8.9-63.3-63.3-112-129-112H178.3c-65.7 0-120.1 48.7-129 112zM0 482.3C0 383.8 79.8 304 178.3 304h91.4C368.2 304 448 383.8 448 482.3c0 16.4-13.3 29.7-29.7 29.7H29.7C13.3 512 0 498.7 0 482.3z\"><\/path><\/svg><\/div><\/span><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-31863c1\" id=\"difusion-de-la-investigacion\" data-block-id=\"31863c1\"><style>.stk-31863c1 .stk-block-heading__text{color:#000000 !important;font-weight:500 !important;font-family:\"ArgentumSans\", Sans-serif !important;}<\/style><h4 class=\"stk-block-heading__text has-text-color\">Difusi\u00f3n de la investigaci\u00f3n<\/h4><\/div>\n<\/div><\/div>\n<\/div><\/div><\/summary>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-5222666 stk-block-accordion__content\" data-v=\"4\" data-block-id=\"5222666\"><style>.stk-5222666 {margin-top:-30px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-5222666-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-5222666-inner-blocks\">\n<ul class=\"wp-block-list\">\n<li>N\u00famero de horas: 20<\/li>\n\n\n\n<li>Car\u00e1cter: Obligatorio<\/li>\n\n\n\n<li>Estudiantes a tiempo completo:&nbsp;Primer semestre del primer a\u00f1o (sesiones de 2 horas semanales, semanas de la 4 a la 13 del semestre)<\/li>\n\n\n\n<li>Estudiantes a tiempo parcial:&nbsp;Primer semestre del primer a\u00f1o (sesiones de 2 horas semanales, semanas de la 4 a la 13 del semestre)<\/li>\n\n\n\n<li>Descripci\u00f3n:&nbsp;Se pretende acercar a los\/as estudiantes a las estrategias m\u00e1s aconsejables en el proceso de difusi\u00f3n de los resultados obtenidos, mediante la selecci\u00f3n de los medios m\u00e1s adecuados, en funci\u00f3n de su calidad, su formato y su accesibilidad.<br>Tambi\u00e9n se presentar\u00e1n los principales criterios de valoraci\u00f3n de los distintos formatos por las Agencias de Calidad.<\/li>\n\n\n\n<li>Contenidos:<\/li>\n\n\n\n<li>1. Formatos de publicaciones y adecuaci\u00f3n al tipo de informaci\u00f3n que se presenta<\/li>\n\n\n\n<li>2. Criterios de calidad de una publicaci\u00f3n cient\u00edfica: valoraci\u00f3n de la revista, \u00edndices de impacto, bases de datos, revistas indexadas y no indexadas, editoriales de prestigio.<\/li>\n\n\n\n<li>3. Valoraci\u00f3n de la investigaci\u00f3n por las Agencias de Calidad.<\/li>\n\n\n\n<li>Competencias:\n<ul class=\"wp-block-list\">\n<li>CB14. Capacidad de realizar un an\u00e1lisis cr\u00edtico y de evaluaci\u00f3n y s\u00edntesis de ideas nuevas y complejas.<\/li>\n\n\n\n<li>CB15. Capacidad de comunicaci\u00f3n con la comunidad acad\u00e9mica y cient\u00edfica y con la sociedad en general acerca de sus \u00e1mbitos&nbsp;de conocimiento en los modos e idiomas de uso habitual en su comunidad cient\u00edfica internacional.<\/li>\n\n\n\n<li>CB16. Capacidad de fomentar, en contextos acad\u00e9micos y profesionales, el avance cient\u00edfico, tecnol\u00f3gico, social, art\u00edstico&nbsp;o cultural dentro de una sociedad basada en el conocimiento.<\/li>\n\n\n\n<li>CP05. Integrar conocimientos, enfrentarse a la complejidad y formular juicios con informaci\u00f3n limitada.<\/li>\n\n\n\n<li>CP06. Tener capacidad de cr\u00edtica y de defensa intelectual de&nbsp;soluciones.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Actividades desarrolladas por el doctorando:\n<ul class=\"wp-block-list\">\n<li>Preparaci\u00f3n de un dossier con la evaluaci\u00f3n de la calidad de la bibliograf\u00eda recogida en tres publicaciones espec\u00edficas de la l\u00ednea de investigaci\u00f3n de su proyecto de tesis doctoral.<\/li>\n\n\n\n<li>Manejo competente de las bases de datos bibliogr\u00e1ficas de distintas plataformas virtuales (preferentemente de acceso libre).<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Procedimientos de control:<\/li>\n<\/ul>\n<\/div><\/div><\/div>\n<\/details>\n\n\n\n<details class=\"wp-block-stackable-accordion stk-block-accordion stk-inner-blocks stk-block-content stk-block stk-269744c is-style-default\" id=\"comunicacion\" data-block-id=\"269744c\"><style>.stk-269744c {border-style:solid !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;margin-bottom:11px !important;}<\/style>\n<summary class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-f352a66 stk--container-small stk-block-accordion__heading\" data-v=\"4\" data-block-id=\"f352a66\"><style>.stk-f352a66 {padding-top:2px !important;padding-right:2px !important;padding-bottom:2px !important;padding-left:2px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-f352a66-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-f352a66-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-cef9962\" data-block-id=\"cef9962\"><style>.stk-cef9962 .stk-inner-blocks{gap:39px !important;}@media screen and (max-width: 1023px){.stk-cef9962 .stk-inner-blocks{gap:39px !important;}}@media screen and (max-width: 767px){.stk-cef9962 .stk-inner-blocks{gap:39px !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-icon stk-block-icon stk-block stk-ebb4252\" data-block-id=\"ebb4252\"><style>.stk-ebb4252 .stk--svg-wrapper .stk--inner-svg svg:last-child{height:25px !important;width:25px !important;}.stk-ebb4252 .stk--svg-wrapper .stk--inner-svg svg:last-child, .stk-ebb4252 .stk--svg-wrapper .stk--inner-svg svg:last-child :is(g, path, rect, polygon, ellipse){fill:#f33f4e !important;}<\/style><span class=\"stk--svg-wrapper stk--has-icon2\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-ebb4252\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-ebb-4252-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-ebb-4252-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 640 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M208 352c114.9 0 208-78.8 208-176S322.9 0 208 0S0 78.8 0 176c0 38.6 14.7 74.3 39.6 103.4c-3.5 9.4-8.7 17.7-14.2 24.7c-4.8 6.2-9.7 11-13.3 14.3c-1.8 1.6-3.3 2.9-4.3 3.7c-.5 .4-.9 .7-1.1 .8l-.2 .2 0 0 0 0C1 327.2-1.4 334.4 .8 340.9S9.1 352 16 352c21.8 0 43.8-5.6 62.1-12.5c9.2-3.5 17.8-7.4 25.3-11.4C134.1 343.3 169.8 352 208 352zM448 176c0 112.3-99.1 196.9-216.5 207C255.8 457.4 336.4 512 432 512c38.2 0 73.9-8.7 104.7-23.9c7.5 4 16 7.9 25.2 11.4c18.3 6.9 40.3 12.5 62.1 12.5c6.9 0 13.1-4.5 15.2-11.1c2.1-6.6-.2-13.8-5.8-17.9l0 0 0 0-.2-.2c-.2-.2-.6-.4-1.1-.8c-1-.8-2.5-2-4.3-3.7c-3.6-3.3-8.5-8.1-13.3-14.3c-5.5-7-10.7-15.4-14.2-24.7c24.9-29 39.6-64.7 39.6-103.4c0-92.8-84.9-168.9-192.6-175.5c.4 5.1 .6 10.3 .6 15.5z\"><\/path><\/svg><\/div><div class=\"stk--inner-svg stk--icon-2\" style=\"display:none\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-ebb4252\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-ebb-4252-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-ebb-4252-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 640 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M88.2 309.1c9.8-18.3 6.8-40.8-7.5-55.8C59.4 230.9 48 204 48 176c0-63.5 63.8-128 160-128s160 64.5 160 128s-63.8 128-160 128c-13.1 0-25.8-1.3-37.8-3.6c-10.4-2-21.2-.6-30.7 4.2c-4.1 2.1-8.3 4.1-12.6 6c-16 7.2-32.9 13.5-49.9 18c2.8-4.6 5.4-9.1 7.9-13.6c1.1-1.9 2.2-3.9 3.2-5.9zM0 176c0 41.8 17.2 80.1 45.9 110.3c-.9 1.7-1.9 3.5-2.8 5.1c-10.3 18.4-22.3 36.5-36.6 52.1c-6.6 7-8.3 17.2-4.6 25.9C5.8 378.3 14.4 384 24 384c43 0 86.5-13.3 122.7-29.7c4.8-2.2 9.6-4.5 14.2-6.8c15.1 3 30.9 4.5 47.1 4.5c114.9 0 208-78.8 208-176S322.9 0 208 0S0 78.8 0 176zM432 480c16.2 0 31.9-1.6 47.1-4.5c4.6 2.3 9.4 4.6 14.2 6.8C529.5 498.7 573 512 616 512c9.6 0 18.2-5.7 22-14.5c3.8-8.8 2-19-4.6-25.9c-14.2-15.6-26.2-33.7-36.6-52.1c-.9-1.7-1.9-3.4-2.8-5.1C622.8 384.1 640 345.8 640 304c0-94.4-87.9-171.5-198.2-175.8c4.1 15.2 6.2 31.2 6.2 47.8l0 .6c87.2 6.7 144 67.5 144 127.4c0 28-11.4 54.9-32.7 77.2c-14.3 15-17.3 37.6-7.5 55.8c1.1 2 2.2 4 3.2 5.9c2.5 4.5 5.2 9 7.9 13.6c-17-4.5-33.9-10.7-49.9-18c-4.3-1.9-8.5-3.9-12.6-6c-9.5-4.8-20.3-6.2-30.7-4.2c-12.1 2.4-24.7 3.6-37.8 3.6c-61.7 0-110-26.5-136.8-62.3c-16 5.4-32.8 9.4-50 11.8C279 439.8 350 480 432 480z\"><\/path><\/svg><\/div><\/span><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-2822238\" id=\"comunicacion-oral-en-el-ambito-cientifico\" data-block-id=\"2822238\"><style>.stk-2822238 .stk-block-heading__text{color:#000000 !important;font-weight:500 !important;font-family:\"ArgentumSans\", Sans-serif !important;}<\/style><h4 class=\"stk-block-heading__text has-text-color\">Comunicaci\u00f3n oral en el \u00e1mbito cient\u00edfico<\/h4><\/div>\n<\/div><\/div>\n<\/div><\/div><\/summary>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-8d57570 stk-block-accordion__content\" data-v=\"4\" data-block-id=\"8d57570\"><style>.stk-8d57570 {margin-top:-30px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-8d57570-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-8d57570-inner-blocks\">\n<ul class=\"wp-block-list\">\n<li>N\u00famero de horas: 20<\/li>\n\n\n\n<li>Car\u00e1cter: Obligatorio<\/li>\n\n\n\n<li>Estudiantes a tiempo completo:&nbsp;Segundo semestre del primer a\u00f1o (sesiones de 2 horas&nbsp;semanales de la semana 4 a la 13)<\/li>\n\n\n\n<li>Estudiantes a tiempo parcial:&nbsp;Segundo semestre del primer a\u00f1o (sesiones de 2 horas semanales de la semana 4 a la 13)<\/li>\n\n\n\n<li>Descripci\u00f3n:&nbsp;El objetivo de la actividad es potenciar la capacidad de comunicaci\u00f3n del\/a doctorando\/a para establecer un marco de interrelaci\u00f3n con la comunidad cient\u00edfica en su conjunto y con la sociedad en general acerca de los resultados de su investigaci\u00f3n en su \u00e1mbito de conocimiento. Como preparaci\u00f3n para una futura estancia en el extranjero dicha presentaci\u00f3n se realizar\u00e1 en ingl\u00e9s.<\/li>\n\n\n\n<li>Contenidos:<\/li>\n\n\n\n<li>1. Tipos de presentaci\u00f3n oral de la investigaci\u00f3n I (congresos, tribunales, presentaci\u00f3n de informes).<\/li>\n\n\n\n<li>2. Tipos de presentaci\u00f3n oral de la investigaci\u00f3n II (conferencias de divulgaci\u00f3n, mesas redondas, debates).<\/li>\n\n\n\n<li>3. T\u00e9cnicas de comunicaci\u00f3n oral.<\/li>\n\n\n\n<li>4. Comunicaci\u00f3n oral y TICS.<\/li>\n\n\n\n<li>Competencias:\n<ul class=\"wp-block-list\">\n<li>CB14. Capacidad de realizar un an\u00e1lisis cr\u00edtico y de evaluaci\u00f3n y s\u00edntesis de ideas nuevas y complejas.<\/li>\n\n\n\n<li>CB15. Capacidad de comunicaci\u00f3n con la comunidad acad\u00e9mica y cient\u00edfica y con la sociedad en general acerca de sus \u00e1mbitos de conocimiento en los modos e idiomas de uso habitual en su comunidad cient\u00edfica internacional.<\/li>\n\n\n\n<li>CB6. Capacidad de fomentar, en contextos acad\u00e9micos y profesionales, el avance cient\u00edfico, tecnol\u00f3gico, social, art\u00edstico o cultural dentro de una sociedad basada en el conocimiento.<\/li>\n\n\n\n<li>CP04. Trabajar tanto en equipo como de manera aut\u00f3noma en un contexto internacional o multidisciplinar.<\/li>\n\n\n\n<li>CP05. Integrar conocimientos, enfrentarse a la complejidad&nbsp;y formular juicios con informaci\u00f3n limitada.<\/li>\n\n\n\n<li>CP06. Tener capacidad de cr\u00edtica y de defensa intelectual de soluciones.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Actividades desarrolladas por el doctorando:\n<ul class=\"wp-block-list\">\n<li>Preparaci\u00f3n de la presentaci\u00f3n en PowerPoint<\/li>\n\n\n\n<li>Exposici\u00f3n en ingl\u00e9s de dicha presentaci\u00f3n<\/li>\n\n\n\n<li>Responder a las preguntas realizadas por el p\u00fablico asistente tambi\u00e9n en idioma ingl\u00e9s<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Procedimientos de control:\n<ul class=\"wp-block-list\">\n<li>Evaluaci\u00f3n de la actividad:\n<ul class=\"wp-block-list\">\n<li>Calidad de la presentaci\u00f3n en ppt: 50%<\/li>\n\n\n\n<li>Calidad de la exposici\u00f3n oral y respuestas: 50%<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Las actividades formativas 1, 2 y 3 ser\u00e1n evaluadas por el profesorado que las imparta. En la actividad 3 se tendr\u00e1 en cuenta adem\u00e1s la opini\u00f3n del director&nbsp;de la tesis, el cu\u00e1l valorar\u00e1 las observaciones que haya recibido cada estudiante por parte de los evaluadores externos. En cuanto a las ponderaciones,&nbsp;La actividad 4 se evaluar\u00e1 a partir de la acreditaci\u00f3n de la asistencia a las 20 horas de conferencias y seminarios (La Comisi\u00f3n Acad\u00e9mica pondr\u00e1&nbsp;a disposici\u00f3n del alumnado un formulario espec\u00edfico para realizar tal acreditaci\u00f3n que deber\u00e1 ser supervisado por el organizador del evento). Cada&nbsp;actividad formativa se eval\u00faa con un m\u00e1ximo de 10 puntos, que resultar\u00e1 del sumatorio de cada uno de los criterios que se proponen.. La actividad 5&nbsp;de movilidad ser\u00e1 evaluada por la Comisi\u00f3n Acad\u00e9mica atendiendo al informe de la persona responsable de la estancia y a la acreditaci\u00f3n de la misma.<br>En las fichas de las actividades formativas se especifica la temporalizaci\u00f3n de las actividades en funci\u00f3n de si se cursan a Tiempo Completo E.T.C. o a&nbsp;tiempo parcial E.T.P.<br>A modo de resumen El estudiantado a tiempo completo tendr\u00e1 la siguiente secuencia: La actividad formativa 1 se cursar\u00e1 en el primer semestre del primer&nbsp;a\u00f1o; la 2 en el segundo semestres del primer a\u00f1o; la tres en el primer o segundo semestre del tercer a\u00f1o y la 4 durante todo el periodo de matr\u00edcula.<br>El estudiantado a tiempo parcial cursar\u00e1 la actividad formativa 1 en el primer semestre del primer a\u00f1o; la dos en el segundo semestre, del primer a\u00f1o;&nbsp;la tres a partir del segundo a\u00f1o y la 4 durante todo el periodo de matr\u00edcula.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/div><\/div><\/div>\n<\/details>\n\n\n\n<details class=\"wp-block-stackable-accordion stk-block-accordion stk-inner-blocks stk-block-content stk-block stk-1893d1d is-style-default\" id=\"presentacion\" data-block-id=\"1893d1d\"><style>.stk-1893d1d {border-style:solid !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;margin-bottom:11px !important;}<\/style>\n<summary class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-572ba50 stk--container-small stk-block-accordion__heading\" data-v=\"4\" data-block-id=\"572ba50\"><style>.stk-572ba50 {padding-top:2px !important;padding-right:2px !important;padding-bottom:2px !important;padding-left:2px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-572ba50-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-572ba50-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-fcb2298\" data-block-id=\"fcb2298\"><style>.stk-fcb2298 .stk-inner-blocks{gap:39px !important;}@media screen and (max-width: 1023px){.stk-fcb2298 .stk-inner-blocks{gap:39px !important;}}@media screen and (max-width: 767px){.stk-fcb2298 .stk-inner-blocks{gap:39px !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-icon stk-block-icon stk-block stk-a546e8c\" data-block-id=\"a546e8c\"><style>.stk-a546e8c .stk--svg-wrapper .stk--inner-svg svg:last-child{height:25px !important;width:25px !important;}.stk-a546e8c .stk--svg-wrapper .stk--inner-svg svg:last-child, .stk-a546e8c .stk--svg-wrapper .stk--inner-svg svg:last-child :is(g, path, rect, polygon, ellipse){fill:#f33f4e !important;}<\/style><span class=\"stk--svg-wrapper stk--has-icon2\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-a546e8c\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-a-546-e-8-c-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-a-546-e-8-c-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M208 0H332.1c12.7 0 24.9 5.1 33.9 14.1l67.9 67.9c9 9 14.1 21.2 14.1 33.9V336c0 26.5-21.5 48-48 48H208c-26.5 0-48-21.5-48-48V48c0-26.5 21.5-48 48-48zM48 128h80v64H64V448H256V416h64v48c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V176c0-26.5 21.5-48 48-48z\"><\/path><\/svg><\/div><div class=\"stk--inner-svg stk--icon-2\" style=\"display:none\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-a546e8c\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-a-546-e-8-c-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-a-546-e-8-c-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M384 336H192c-8.8 0-16-7.2-16-16V64c0-8.8 7.2-16 16-16l140.1 0L400 115.9V320c0 8.8-7.2 16-16 16zM192 384H384c35.3 0 64-28.7 64-64V115.9c0-12.7-5.1-24.9-14.1-33.9L366.1 14.1c-9-9-21.2-14.1-33.9-14.1H192c-35.3 0-64 28.7-64 64V320c0 35.3 28.7 64 64 64zM64 128c-35.3 0-64 28.7-64 64V448c0 35.3 28.7 64 64 64H256c35.3 0 64-28.7 64-64V416H272v32c0 8.8-7.2 16-16 16H64c-8.8 0-16-7.2-16-16V192c0-8.8 7.2-16 16-16H96V128H64z\"><\/path><\/svg><\/div><\/span><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-ecc88dd\" id=\"presentacion-de-un-aspecto-teorico-y-o-metodologico-derivado-de-la-tesis-en-un-contexto-publico-congreso-seminario-workshop-especializado-en-una-o-varias-de-las-lineas-de-investigacion-del-doctorado\" data-block-id=\"ecc88dd\"><style>.stk-ecc88dd .stk-block-heading__text{color:#000000 !important;font-weight:500 !important;font-family:\"ArgentumSans\", Sans-serif !important;}<\/style><h4 class=\"stk-block-heading__text has-text-color\">Presentaci\u00f3n de un aspecto te\u00f3rico y\/o metodol\u00f3gico, derivado de la Tesis en un contexto p\u00fablico (Congreso, Seminario, Workshop) especializado en una o varias de las l\u00edneas de investigaci\u00f3n del doctorado<\/h4><\/div>\n<\/div><\/div>\n<\/div><\/div><\/summary>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-221465e stk-block-accordion__content\" data-v=\"4\" data-block-id=\"221465e\"><style>.stk-221465e {margin-top:-30px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-221465e-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-221465e-inner-blocks\">\n<ul class=\"wp-block-list\">\n<li>N\u00famero de horas: 3 horas<\/li>\n\n\n\n<li>Descripci\u00f3n:&nbsp;Cada estudiante deber\u00e1 presentar al menos un seminario sobre su trabajo de investigaci\u00f3n. En \u00e9l expondr\u00e1 ante otros alumnos y profesores del programa de doctorado los fundamentos del proyecto de investigaci\u00f3n, incluyendo la hip\u00f3tesis de trabajo, objetivos, metodolog\u00eda empleada, resultados y conclusiones. Adem\u00e1s debe debatir y contestar a las cuestiones que se le planteen.<\/li>\n\n\n\n<li>Planificaci\u00f3n temporal:&nbsp;Estudiantes con dedicaci\u00f3n a tiempo completo: Una vez a lo largo del segundo o tercer a\u00f1o del doctorado. Estudiantes con dedicaci\u00f3n a tiempo parcial: Una vez a lo largo del tercer o cuarto a\u00f1o.<\/li>\n\n\n\n<li>Justificaci\u00f3n:&nbsp;Potenciaci\u00f3n de las competencias b\u00e1sicas CB12 y CB15, y la capacidad CA06.<\/li>\n\n\n\n<li>Resultados del aprendizaje: Demostrar capacidad de s\u00edntesis, claridad en la exposici\u00f3n y comunicaci\u00f3n de resultados cient\u00edficos de forma oral. Capacidad para debatir y responder a cuestiones espec\u00edficas<\/li>\n\n\n\n<li>Idioma: Espa\u00f1ol\/ingl\u00e9s<\/li>\n\n\n\n<li>Car\u00e1cter: Obligatorio<\/li>\n\n\n\n<li>Procedimiento de control:&nbsp;Informe del tutor\/director y de los profesores de la l\u00ednea de investigaci\u00f3n que asisten al seminario. El informe debe valorar la profundidad de conocimientos de los antecedentes, claridad de exposici\u00f3n, abordaje del tema y capacidad de debate y discusi\u00f3n que ha mostrado el doctorando. El resumen del seminario incluyendo aspectos del debate y los informes se incluir\u00e1n en el documento personalizado de registro de actividades.<\/li>\n\n\n\n<li>Movilidad:&nbsp;No se prev\u00e9n acciones de movilidad<\/li>\n<\/ul>\n<\/div><\/div><\/div>\n<\/details>\n\n\n\n<details class=\"wp-block-stackable-accordion stk-block-accordion stk-inner-blocks stk-block-content stk-block stk-984a9a8 is-style-default\" id=\"seminarios\" data-block-id=\"984a9a8\"><style>.stk-984a9a8 {border-style:solid !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;margin-bottom:11px !important;}<\/style>\n<summary class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-86f5592 stk--container-small stk-block-accordion__heading\" data-v=\"4\" data-block-id=\"86f5592\"><style>.stk-86f5592 {padding-top:2px !important;padding-right:2px !important;padding-bottom:2px !important;padding-left:2px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-86f5592-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-86f5592-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-1dc0018\" data-block-id=\"1dc0018\"><style>.stk-1dc0018 .stk-inner-blocks{gap:39px !important;}@media screen and (max-width: 1023px){.stk-1dc0018 .stk-inner-blocks{gap:39px !important;}}@media screen and (max-width: 767px){.stk-1dc0018 .stk-inner-blocks{gap:39px !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-icon stk-block-icon stk-block stk-70b1cce\" data-block-id=\"70b1cce\"><style>.stk-70b1cce .stk--svg-wrapper .stk--inner-svg svg:last-child{height:25px !important;width:25px !important;}.stk-70b1cce .stk--svg-wrapper .stk--inner-svg svg:last-child, .stk-70b1cce .stk--svg-wrapper .stk--inner-svg svg:last-child :is(g, path, rect, polygon, ellipse){fill:#f33f4e !important;}<\/style><span class=\"stk--svg-wrapper stk--has-icon2\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-70b1cce\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-70-b-1-cce-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-70-b-1-cce-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M266.3 48.3L232.5 73.6c-5.4 4-8.5 10.4-8.5 17.1v9.1c0 6.8 5.5 12.3 12.3 12.3c2.4 0 4.8-.7 6.8-2.1l41.8-27.9c2-1.3 4.4-2.1 6.8-2.1h1c6.2 0 11.3 5.1 11.3 11.3c0 3-1.2 5.9-3.3 8l-19.9 19.9c-5.8 5.8-12.9 10.2-20.7 12.8l-26.5 8.8c-5.8 1.9-9.6 7.3-9.6 13.4c0 3.7-1.5 7.3-4.1 10l-17.9 17.9c-6.4 6.4-9.9 15-9.9 24v4.3c0 16.4 13.6 29.7 29.9 29.7c11 0 21.2-6.2 26.1-16l4-8.1c2.4-4.8 7.4-7.9 12.8-7.9c4.5 0 8.7 2.1 11.4 5.7l16.3 21.7c2.1 2.9 5.5 4.5 9.1 4.5c8.4 0 13.9-8.9 10.1-16.4l-1.1-2.3c-3.5-7 0-15.5 7.5-18l21.2-7.1c7.6-2.5 12.7-9.6 12.7-17.6c0-10.3 8.3-18.6 18.6-18.6H400c8.8 0 16 7.2 16 16s-7.2 16-16 16H379.3c-7.2 0-14.2 2.9-19.3 8l-4.7 4.7c-2.1 2.1-3.3 5-3.3 8c0 6.2 5.1 11.3 11.3 11.3h11.3c6 0 11.8 2.4 16 6.6l6.5 6.5c1.8 1.8 2.8 4.3 2.8 6.8s-1 5-2.8 6.8l-7.5 7.5C386 262 384 266.9 384 272s2 10 5.7 13.7L408 304c10.2 10.2 24.1 16 38.6 16H454c6.5-20.2 10-41.7 10-64c0-111.4-87.6-202.4-197.7-207.7zm172 307.9c-3.7-2.6-8.2-4.1-13-4.1c-6 0-11.8-2.4-16-6.6L396 332c-7.7-7.7-18-12-28.9-12c-9.7 0-19.2-3.5-26.6-9.8L314 287.4c-11.6-9.9-26.4-15.4-41.7-15.4H251.4c-12.6 0-25 3.7-35.5 10.7L188.5 301c-17.8 11.9-28.5 31.9-28.5 53.3v3.2c0 17 6.7 33.3 18.7 45.3l16 16c8.5 8.5 20 13.3 32 13.3H248c13.3 0 24 10.7 24 24c0 2.5 .4 5 1.1 7.3c71.3-5.8 132.5-47.6 165.2-107.2zM0 256a256 256 0 1 1 512 0A256 256 0 1 1 0 256zM187.3 100.7c-6.2-6.2-16.4-6.2-22.6 0l-32 32c-6.2 6.2-6.2 16.4 0 22.6s16.4 6.2 22.6 0l32-32c6.2-6.2 6.2-16.4 0-22.6z\"><\/path><\/svg><\/div><div class=\"stk--inner-svg stk--icon-2\" style=\"display:none\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-70b1cce\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-70-b-1-cce-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-70-b-1-cce-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M57.7 193l9.4 16.4c8.3 14.5 21.9 25.2 38 29.8L163 255.7c17.2 4.9 29 20.6 29 38.5v39.9c0 11 6.2 21 16 25.9s16 14.9 16 25.9v39c0 15.6 14.9 26.9 29.9 22.6c16.1-4.6 28.6-17.5 32.7-33.8l2.8-11.2c4.2-16.9 15.2-31.4 30.3-40l8.1-4.6c15-8.5 24.2-24.5 24.2-41.7v-8.3c0-12.7-5.1-24.9-14.1-33.9l-3.9-3.9c-9-9-21.2-14.1-33.9-14.1H257c-11.1 0-22.1-2.9-31.8-8.4l-34.5-19.7c-4.3-2.5-7.6-6.5-9.2-11.2c-3.2-9.6 1.1-20 10.2-24.5l5.9-3c6.6-3.3 14.3-3.9 21.3-1.5l23.2 7.7c8.2 2.7 17.2-.4 21.9-7.5c4.7-7 4.2-16.3-1.2-22.8l-13.6-16.3c-10-12-9.9-29.5 .3-41.3l15.7-18.3c8.8-10.3 10.2-25 3.5-36.7l-2.4-4.2c-3.5-.2-6.9-.3-10.4-.3C163.1 48 84.4 108.9 57.7 193zM464 256c0-36.8-9.6-71.4-26.4-101.5L412 164.8c-15.7 6.3-23.8 23.8-18.5 39.8l16.9 50.7c3.5 10.4 12 18.3 22.6 20.9l29.1 7.3c1.2-9 1.8-18.2 1.8-27.5zM0 256a256 256 0 1 1 512 0A256 256 0 1 1 0 256z\"><\/path><\/svg><\/div><\/span><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-44cf24b\" id=\"seminarios-de-investigacion\" data-block-id=\"44cf24b\"><style>.stk-44cf24b .stk-block-heading__text{color:#000000 !important;font-weight:500 !important;font-family:\"ArgentumSans\", Sans-serif !important;}<\/style><h4 class=\"stk-block-heading__text has-text-color\">Seminarios de investigaci\u00f3n<\/h4><\/div>\n<\/div><\/div>\n<\/div><\/div><\/summary>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-03c2f07 stk-block-accordion__content\" data-v=\"4\" data-block-id=\"03c2f07\"><style>.stk-03c2f07 {margin-top:-30px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-03c2f07-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-03c2f07-inner-blocks\">\n<ul class=\"wp-block-list\">\n<li>N\u00famero&nbsp;de horas: 20<\/li>\n\n\n\n<li>Car\u00e1cter: Obligatorio<\/li>\n\n\n\n<li>Estudiantes a tiempo completo:&nbsp;Todos los semestres<\/li>\n\n\n\n<li>Estudiantes a tiempo parcial: Todos los semestres<\/li>\n\n\n\n<li>Descripci\u00f3n:&nbsp;La actividad consiste en la asistencia participativa a conferencias y seminarios impartidos por investigadores del programa de doctoraro, o aquellos que por medio de convenio u otro tipo de acuerdo hayan aceptado participar en el programa, as\u00ed como otros investigadores que se encuentren en alguna de las dos universidades para impartir cursos o conferencias que est\u00e9n ligados a alguna de las l\u00edneas de investigaci\u00f3n del programa.<\/li>\n\n\n\n<li>Contenidos:&nbsp;A discreci\u00f3n de los investigadores invitados, siempre que tengan relaci\u00f3n con las l\u00edneas de investigaci\u00f3n del programa.<\/li>\n\n\n\n<li>Competencias:\n<ul class=\"wp-block-list\">\n<li>CB11 Capacidad de demostrar una comprensi\u00f3n sistem\u00e1tica de cada campo de estudio y el dominio de las habilidades y m\u00e9todos de investigaci\u00f3n relacionados con \u00e9l.<\/li>\n\n\n\n<li>CB12 Capacidad de concebir, dise\u00f1ar, poner en pr\u00e1ctica y&nbsp;adoptar un proceso de investigaci\u00f3n con rigor acad\u00e9mico.<\/li>\n\n\n\n<li>CB13 Capacidad de realizar una contribuci\u00f3n cient\u00edfica, a trav\u00e9s de una investigaci\u00f3n original, que ampl\u00ede las fronteras del conocimiento en este campo, y que merezca&nbsp;la publicaci\u00f3n referenciada a nivel nacional o internacional.<\/li>\n\n\n\n<li>CB14. Capacidad de realizar un an\u00e1lisis cr\u00edtico y de evaluaci\u00f3n y s\u00edntesis de ideas nuevas y complejas.<\/li>\n\n\n\n<li>CB15. Capacidad de comunicaci\u00f3n con la comunidad acad\u00e9mica&nbsp;y cient\u00edfica y con la sociedad en general acerca de sus \u00e1mbitos de conocimiento en los modos e idiomas de uso habitual en su comunidad cient\u00edfica internacional.<\/li>\n\n\n\n<li>CB16. Capacidad de fomentar, en contextos acad\u00e9micos y profesionales,&nbsp;el avance cient\u00edfico, tecnol\u00f3gico, social, art\u00edstico o cultural dentro de una sociedad basada en el conocimiento.<\/li>\n\n\n\n<li>CP01. Capacidad de desenvolverse en contextos donde hay poca informaci\u00f3n espec\u00edfica.<\/li>\n\n\n\n<li>CP02. Capacidad de proponer las preguntas claves que hay que responder para resolver un problema complejo en relaci\u00f3n con cada campo de estudio.<\/li>\n\n\n\n<li>CP03. Capacidad de dise\u00f1ar proyectos innovadores en los \u00e1mbitos de la geograf\u00eda, la historia, la arqueolog\u00eda y la gesti\u00f3n del patrimonio.<\/li>\n\n\n\n<li>CP04. Trabajar tanto en equipo como de manera aut\u00f3noma en un contexto internacional o multidisciplinar.<\/li>\n\n\n\n<li>CP05. Integrar conocimientos, enfrentarse a la complejidad y formular juicios con informaci\u00f3n limitada.<\/li>\n\n\n\n<li>CP06. Tener capacidad de cr\u00edtica y de defensa intelectual de soluciones.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Actividades desarrolladas por el doctorando:&nbsp;Asistencia participativa en las conferencias y seminarios.<\/li>\n\n\n\n<li>Procedimientos de&nbsp;control:\n<ul class=\"wp-block-list\">\n<li>Evaluaci\u00f3n de la actividad:\n<ul class=\"wp-block-list\">\n<li>Acreditaci\u00f3n de la asistencia: 100%<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Las actividades formativas 1, 2 y 3 ser\u00e1n evaluadas por el profesorado que las imparta. En la actividad 3 se tendr\u00e1 en cuenta adem\u00e1s la opini\u00f3n del director&nbsp;de la tesis, el cu\u00e1l valorar\u00e1 las observaciones que haya recibido cada estudiante por parte de los evaluadores externos. En cuanto a las ponderaciones,&nbsp;La actividad 4 se evaluar\u00e1 a partir de la acreditaci\u00f3n de la asistencia a las 20 horas de conferencias y seminarios (La Comisi\u00f3n Acad\u00e9mica pondr\u00e1&nbsp;a disposici\u00f3n del alumnado un formulario espec\u00edfico para realizar tal acreditaci\u00f3n que deber\u00e1 ser supervisado por el organizador del evento). Cada&nbsp;actividad formativa se eval\u00faa con un m\u00e1ximo de 10 puntos, que resultar\u00e1 del sumatorio de cada uno de los criterios que se proponen.. La actividad 5&nbsp;de movilidad ser\u00e1 evaluada por la Comisi\u00f3n Acad\u00e9mica atendiendo al informe de la persona responsable de la estancia y a la acreditaci\u00f3n de la misma.<br>En las fichas de las actividades formativas se especifica la temporalizaci\u00f3n de las actividades en funci\u00f3n de si se cursan a Tiempo Completo E.T.C. o a&nbsp;tiempo parcial E.T.P.<br>A modo de resumen El estudiantado a tiempo completo tendr\u00e1 la siguiente secuencia: La actividad formativa 1 se cursar\u00e1 en el primer semestre del primer&nbsp;a\u00f1o; la 2 en el segundo semestres del primer a\u00f1o; la tres en el primer o segundo semestre del tercer a\u00f1o y la 4 durante todo el periodo de matr\u00edcula.<br>El estudiantado a tiempo parcial cursar\u00e1 la actividad formativa 1 en el primer semestre del primer a\u00f1o; la dos en el segundo semestre, del primer a\u00f1o;&nbsp;la tres a partir del segundo a\u00f1o y la 4 durante todo el periodo de matr\u00edcula.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/div><\/div><\/div>\n<\/details>\n\n\n\n<details class=\"wp-block-stackable-accordion stk-block-accordion stk-inner-blocks stk-block-content stk-block stk-e2afeed is-style-default\" id=\"movilidad\" data-block-id=\"e2afeed\"><style>.stk-e2afeed {border-style:solid !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;margin-bottom:11px !important;}<\/style>\n<summary class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-b716f05 stk--container-small stk-block-accordion__heading\" data-v=\"4\" data-block-id=\"b716f05\"><style>.stk-b716f05 {padding-top:2px !important;padding-right:2px !important;padding-bottom:2px !important;padding-left:2px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-b716f05-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-b716f05-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-fd1f34a\" data-block-id=\"fd1f34a\"><style>.stk-fd1f34a .stk-inner-blocks{gap:39px !important;}@media screen and (max-width: 1023px){.stk-fd1f34a .stk-inner-blocks{gap:39px !important;}}@media screen and (max-width: 767px){.stk-fd1f34a .stk-inner-blocks{gap:39px !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-icon stk-block-icon stk-block stk-b19d67d\" data-block-id=\"b19d67d\"><style>.stk-b19d67d .stk--svg-wrapper .stk--inner-svg svg:last-child{height:25px !important;width:25px !important;}.stk-b19d67d .stk--svg-wrapper .stk--inner-svg svg:last-child, .stk-b19d67d .stk--svg-wrapper .stk--inner-svg svg:last-child :is(g, path, rect, polygon, ellipse){fill:#f33f4e !important;}<\/style><span class=\"stk--svg-wrapper stk--has-icon2\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-b19d67d\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-b-19-d-67-d-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-b-19-d-67-d-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 640 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M381 114.9L186.1 41.8c-16.7-6.2-35.2-5.3-51.1 2.7L89.1 67.4C78 73 77.2 88.5 87.6 95.2l146.9 94.5L136 240 77.8 214.1c-8.7-3.9-18.8-3.7-27.3 .6L18.3 230.8c-9.3 4.7-11.8 16.8-5 24.7l73.1 85.3c6.1 7.1 15 11.2 24.3 11.2H248.4c5 0 9.9-1.2 14.3-3.4L535.6 212.2c46.5-23.3 82.5-63.3 100.8-112C645.9 75 627.2 48 600.2 48H542.8c-20.2 0-40.2 4.8-58.2 14L381 114.9zM0 480c0 17.7 14.3 32 32 32H608c17.7 0 32-14.3 32-32s-14.3-32-32-32H32c-17.7 0-32 14.3-32 32z\"><\/path><\/svg><\/div><div class=\"stk--inner-svg stk--icon-2\" style=\"display:none\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-b19d67d\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-b-19-d-67-d-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-b-19-d-67-d-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 640 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M.3 166.9L0 68C0 57.7 9.5 50.1 19.5 52.3l35.6 7.9c10.6 2.3 19.2 9.9 23 20L96 128l127.3 37.6L181.8 20.4C178.9 10.2 186.6 0 197.2 0h40.1c11.6 0 22.2 6.2 27.9 16.3l109 193.8 107.2 31.7c15.9 4.7 30.8 12.5 43.7 22.8l34.4 27.6c24 19.2 18.1 57.3-10.7 68.2c-41.2 15.6-86.2 18.1-128.8 7L121.7 289.8c-11.1-2.9-21.2-8.7-29.3-16.9L9.5 189.4c-5.9-6-9.3-14.1-9.3-22.5zM32 448H608c17.7 0 32 14.3 32 32s-14.3 32-32 32H32c-17.7 0-32-14.3-32-32s14.3-32 32-32zm96-80a32 32 0 1 1 64 0 32 32 0 1 1 -64 0zm128-16a32 32 0 1 1 0 64 32 32 0 1 1 0-64z\"><\/path><\/svg><\/div><\/span><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-baaa203\" id=\"movilidad\" data-block-id=\"baaa203\"><style>.stk-baaa203 .stk-block-heading__text{color:#000000 !important;font-weight:500 !important;font-family:\"ArgentumSans\", Sans-serif !important;}<\/style><h4 class=\"stk-block-heading__text has-text-color\">Movilidad<\/h4><\/div>\n<\/div><\/div>\n<\/div><\/div><\/summary>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-ea32acc stk-block-accordion__content\" data-v=\"4\" data-block-id=\"ea32acc\"><style>.stk-ea32acc {margin-top:-30px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-ea32acc-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-ea32acc-inner-blocks\">\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-ee8b8a3\" data-block-id=\"ee8b8a3\"><p class=\"stk-block-text__text\">La comisi\u00f3n acad\u00e9mica podr\u00e1 reconocer actividades de movilidad previas a la acci\u00f3n de matr\u00edcula en el Programa. Esta acci\u00f3n facilita la integraci\u00f3n en este programa de personas que hayan estado matriculadas en otros programas de doctorado y por alguna raz\u00f3n quieran incorporarse a este. Tambi\u00e9n para poder satisfacer las expectativas de determinados investigadores, incluso algunos con becas de investigaci\u00f3n en curso, que no han podido matricularse en un programa de doctorado de la ULPGC o de la ULL acorde a sus l\u00edneas de investigaci\u00f3n, porque desde 2010 no se ha ofertado ninguno.<\/p><\/div>\n<\/div><\/div><\/div>\n<\/details>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-53ec762\" data-v=\"4\" data-block-id=\"53ec762\"><style>.stk-53ec762-inner-blocks{row-gap:0px !important;}.stk-53ec762 {padding-top:0px !important;padding-right:0px !important;padding-bottom:0px !important;padding-left:0px !important;}@media screen and (min-width: 768px){.stk-53ec762 {flex:var(--stk-flex-grow, 1) 1 33.3% !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-53ec762-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-53ec762-inner-blocks\">\n\n<ul class=\"widget-box\">\n<li class='contacto-header'>Informaci\u00f3n de contacto<\/li><li><i class=\"fa fa-map-marker\"><\/i> Avda. Astrof\u00edsico Francisco S\u00e1nchez, SN. Edificio Calabaza \u2013 AN.2D Apdo. 456 38200 San Crist\u00f3bal de La Laguna<\/li><li><i class=\"fa fa-envelope\"><\/i>  <a href=mailto:docteso@ull.es>docteso@ull.es<\/a><\/li><li><i class=\"fa fa-calendar\"><\/i><a href=\"http:\/\/citaprevia.ull.es\/index.php?s=edpo\"> Cita previa<\/a><\/li>\n<\/ul>\n\n\n<\/div><\/div><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Activit\u00e9s de formation Diffusion de la recherche Communication orale dans le domaine scientifique Pr\u00e9sentation d&#039;un aspect th\u00e9orique et\/ou m\u00e9thodologique, issu de la th\u00e8se dans un contexte public (Congr\u00e8s, S\u00e9minaire, Workshop) sp\u00e9cialis\u00e9 dans un ou plusieurs axes de recherche du doctorat S\u00e9minaires de recherche Mobilit\u00e9 Le comit\u00e9 acad\u00e9mique peut reconna\u00eetre les activit\u00e9s de mobilit\u00e9 ant\u00e9rieures\u2026<\/p>","protected":false},"author":1,"featured_media":0,"parent":27,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/template-frontpage.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-60","page","type-page","status-publish","hentry"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 19:37:14","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.ull.es\/doctorados\/territorio-sociedad\/fr\/wp-json\/wp\/v2\/pages\/60","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ull.es\/doctorados\/territorio-sociedad\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ull.es\/doctorados\/territorio-sociedad\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ull.es\/doctorados\/territorio-sociedad\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ull.es\/doctorados\/territorio-sociedad\/fr\/wp-json\/wp\/v2\/comments?post=60"}],"version-history":[{"count":12,"href":"https:\/\/www.ull.es\/doctorados\/territorio-sociedad\/fr\/wp-json\/wp\/v2\/pages\/60\/revisions"}],"predecessor-version":[{"id":354,"href":"https:\/\/www.ull.es\/doctorados\/territorio-sociedad\/fr\/wp-json\/wp\/v2\/pages\/60\/revisions\/354"}],"up":[{"embeddable":true,"href":"https:\/\/www.ull.es\/doctorados\/territorio-sociedad\/fr\/wp-json\/wp\/v2\/pages\/27"}],"wp:attachment":[{"href":"https:\/\/www.ull.es\/doctorados\/territorio-sociedad\/fr\/wp-json\/wp\/v2\/media?parent=60"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}