{"id":4240,"date":"2026-04-06T13:45:23","date_gmt":"2026-04-06T13:45:23","guid":{"rendered":"https:\/\/www.ull.es\/formacion-permanente\/?p=4240"},"modified":"2026-04-27T14:26:08","modified_gmt":"2026-04-27T14:26:08","slug":"estrategias-para-el-abordaje-integral-de-los-pacientes-polimedicados","status":"publish","type":"post","link":"https:\/\/www.ull.es\/formacion-permanente\/blog\/estrategias-para-el-abordaje-integral-de-los-pacientes-polimedicados\/","title":{"rendered":"Estrategias para el abordaje integral de los pacientes polimedicados"},"content":{"rendered":"\n<div class=\"wp-block-stackable-columns alignfull stk-block-columns stk-block stk-2314a6b\" data-block-id=\"2314a6b\"><style>.stk-2314a6b {padding-bottom:0px !important;margin-bottom:0px !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-2314a6b-column alignfull\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-1d1764d\" data-v=\"4\" data-block-id=\"1d1764d\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-1d1764d-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-1d1764d-inner-blocks\"><style id=\"depicter-246-inline-pre-css\">\n\n.depicter-246:not(.depicter-ready){\n\theight:450px;\n}\n\n\/***** Tablet *****\/\n@media screen and (max-width: 1024px){\n\n.depicter-246:not(.depicter-ready){\n\theight:700px;\n}\n\n}\n\/***** Mobile *****\/\n@media screen and (max-width: 767px){\n\n.depicter-246:not(.depicter-ready){\n\theight:450px;\n}\n\n}\n<\/style>\n<div id=\"depicter-246\" class=\"depicter depicter-document depicter-revert depicter-246 depicter-layout-fullwidth\">\n\n<div class=\"depicter-loading-container depicter-loading dotFlashing-dark\"><div class=\"depicter-loading-dark depicter-dot-flashing\">\n   <span><\/span>\n   <span><\/span>\n   <span><\/span>\n<\/div>\n<\/div>\n<div id=\"depicter-246-section-1\" class=\"depicter-section depicter-246-section-1\" data-name=\"Section 1\" data-type=\"section\" data-local-id=\"section-1\">\n<picture class=\"depicter-bg\">\n<source data-depicter-srcset=\"https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Headers_microcredenciales_Introduccion_a_la_Computacion_Cuantica-768x248.jpg, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Headers_microcredenciales_Introduccion_a_la_Computacion_Cuantica.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(max-width: 1024px)\" \/>\n\n<source data-depicter-srcset=\"https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Headers_microcredenciales_Introduccion_a_la_Computacion_Cuantica.jpg, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Headers_microcredenciales_Introduccion_a_la_Computacion_Cuantica-2500x807.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(min-width: 1025px)\" \/>\n<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-ken-burns=\"false\" data-tablet-ken-burns=\"false\" data-mobile-ken-burns=\"false\" alt=\"\" data-depicter-src=\"https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Headers_microcredenciales_Introduccion_a_la_Computacion_Cuantica.jpg\" data-object-fit=\"custom,custom,\" data-object-position=\"center top,,\" data-crop=\"{'focalPoint':{'x':0.5,'y':0.5},'mediaSize':{'width':1394.052044609665472307824529707431793212890625,'height':450}}\" data-tablet-crop=\"{'focalPoint':{'x':0.5,'y':0.5},'mediaSize':{'width':2168.5254027261462397291325032711029052734375,'height':700}}\" data-mobile-crop=\"{'focalPoint':{'x':0.5,'y':0.5},'mediaSize':{'width':1394.052044609665472307824529707431793212890625,'height':450}}\" \/>\n<\/picture>\n\n\n<h1 id=\"depicter-246-element-5\" class=\"depicter-element depicter-layer depicter-246-element-5\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 2\" data-local-id=\"element-5\" data-offset=\"x:-34px;y:141px;origin:tl\" data-tablet-offset=\"x:189px;y:206px;origin:tl\" data-mobile-offset=\"x:0px;y:153px;origin:tl\" data-width=\"1269px,646px,360px\" data-height=\"auto,auto,auto\" data-responsive-scale=\"true,,\">Estrategias para el abordaje integral de los pacientes polimedicados<br><\/h1>\n\n<div id=\"depicter-246-element-10\" class=\"depicter-element depicter-layer depicter-246-element-10\" data-type=\"shape\" data-wrap=\"true\" data-name=\"Shape 1\" data-local-id=\"element-10\" data-offset=\"x:-28px;y:315px;origin:tl\" data-tablet-offset=\"x:189px;y:507px;origin:tl\" data-mobile-offset=\"x:0px;y:304px;origin:tl\" data-width=\"1256px,646px,360px\" data-height=\"8px,8px,8px\" data-responsive-scale=\"true,,\"><\/div>\n<\/div>\n<\/div>\n<script>\n(window.depicterSetups = window.depicterSetups || []).push(function(){\n\tDepicter.basePath = 'https:\/\/www.ull.es\/formacion-permanente\/wp-content\/plugins\/depicter\/resources\/scripts\/player\/';\n\tconst dpPlayer = Depicter.setup('.depicter-246',\n\t\t{\"width\":[\"1200\",\"1024\",\"360\"],\"height\":[\"450\",\"700\",\"450\"],\"view\":\"basic\",\"keepAspectRatio\":true,\"preload\":0,\"layout\":\"fullwidth\",\"rtl\":false,\"initAfterAppear\":false,\"ajaxApiUrl\":\"https:\\\/\\\/www.ull.es\\\/formacion-permanente\\\/wp-admin\\\/admin-ajax.php\",\"mouseSwipe\":true,\"touchSwipe\":true,\"useWatermark\":false}\n\t);\n});\n<\/script><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading alignfull stk-block-heading stk--hide-mobile stk-block-heading--v2 stk-block stk-67e3263 stk-block-background menu-wrapper\" data-block-id=\"67e3263\"><style>.stk-67e3263 {background-color:#fd6921 !important;padding-top:15px !important;padding-bottom:15px !important;margin-bottom:58px !important;}.stk-67e3263:before{background-color:#fd6921 !important;}.stk-67e3263 .stk-block-heading__text{font-size:20px !important;color:#ffffff !important;font-weight:500 !important;font-family:\"ArgentumSans\", Sans-serif !important;}@media screen and (max-width: 1023px){.stk-67e3263 .stk-block-heading__text{font-size:20px !important;}}<\/style><h2 class=\"stk-block-heading__text has-text-color has-text-align-center\"><\/h2><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns alignwide stk-block-columns stk--hide-mobile stk-block stk-dd54c47 menu-fijo\" data-block-id=\"dd54c47\"><style>.stk-dd54c47 .stk--block-align-dd54c47{align-items:center !important;}.stk-dd54c47 {padding-right:10% !important;padding-left:10% !important;margin-bottom:70px !important;}@media screen and (max-width: 767px){.stk-dd54c47 {padding-right:5% !important;padding-left:5% !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk--block-align-dd54c47 stk-block-content stk-content-align stk-dd54c47-column alignwide\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-db7e4bf stk-block-background\" data-v=\"4\" target=\"_self\" data-block-id=\"db7e4bf\"><style>.stk-db7e4bf {background-color:#f4f4f4 !important;border-style:solid !important;border-top-width:0px !important;border-right-width:1px !important;border-bottom-width:0px !important;border-left-width:0px !important;}.stk-db7e4bf:before{background-color:#f4f4f4 !important;}@media screen and (min-width: 768px){.stk-db7e4bf {flex:var(--stk-flex-grow, 1) 1 25% !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-db7e4bf-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-db7e4bf-inner-blocks\">\n<a href=\"https:\/\/www.ull.es\/formacion-permanente\/blog\/estrategias-para-el-abordaje-integral-de-los-pacientes-polimedicados\/#estrategias-para-el-abordaje-integral-de-los-pacientes-polimedicados\/\" target=\"_self\" style=\"color:black;text-align:center\" target=\"_blank\" rel=\"noopener\">Presentaci\u00f3n<\/a>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-419bce9 stk-block-background\" data-v=\"4\" data-block-id=\"419bce9\"><style>.stk-419bce9 {background-color:#f4f4f4 !important;border-style:solid !important;border-top-width:0px !important;border-right-width:1px !important;border-bottom-width:0px !important;border-left-width:0px !important;}.stk-419bce9:before{background-color:#f4f4f4 !important;}@media screen and (min-width: 768px){.stk-419bce9 {flex:var(--stk-flex-grow, 1) 1 25% !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-419bce9-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-419bce9-inner-blocks\">\n<a href=\"https:\/\/www.ull.es\/formacion-permanente\/blog\/estrategias-para-el-abordaje-integral-de-los-pacientes-polimedicados\/#contenidos\" target=\"_self\" style=\"color:black;text-align:center\" target=\"_blank\" rel=\"noopener\">Programa acad\u00e9mico<\/a>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-71eca22 stk-block-background\" data-v=\"4\" data-block-id=\"71eca22\"><style>.stk-71eca22 {background-color:#f4f4f4 !important;border-style:solid !important;border-top-width:0px !important;border-right-width:1px !important;border-bottom-width:0px !important;border-left-width:0px !important;}.stk-71eca22:before{background-color:#f4f4f4 !important;}@media screen and (min-width: 768px){.stk-71eca22 {flex:var(--stk-flex-grow, 1) 1 25% !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-71eca22-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-71eca22-inner-blocks\">\n<a href=\"https:\/\/www.ull.es\/formacion-permanente\/blog\/estrategias-para-el-abordaje-integral-de-los-pacientes-polimedicados\/#equipo-docente\" target=\"_self\" style=\"color:black;text-align:center\" target=\"_blank\" rel=\"noopener\">Equipo Docente<\/a>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-5551571 stk-block-background\" data-v=\"4\" data-block-id=\"5551571\"><style>.stk-5551571 {background-color:#f4f4f4 !important;}.stk-5551571:before{background-color:#f4f4f4 !important;}@media screen and (min-width: 768px){.stk-5551571 {flex:var(--stk-flex-grow, 1) 1 25% !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-5551571-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-5551571-inner-blocks\">\n<a href=\"https:\/\/www.ull.es\/formacion-permanente\/blog\/estrategias-para-el-abordaje-integral-de-los-pacientes-polimedicados\/#matricula\" target=\"_self\" style=\"color:black;text-align:center\" target=\"_blank\" rel=\"noopener\">Matr\u00edcula<\/a>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns alignfull stk-block-columns stk--hide-desktop stk--hide-tablet stk-block stk-f591b63 menu-mobile\" data-block-id=\"f591b63\"><style>.stk-f591b63 .stk--block-align-f591b63{align-items:center !important;}.stk-f591b63 {padding-top:0% !important;padding-right:10% !important;padding-bottom:0% !important;padding-left:10% !important;margin-bottom:70px !important;}@media screen and (max-width: 767px){.stk-f591b63 {padding-right:0% !important;padding-left:0% !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk--block-align-f591b63 stk-block-content stk-content-align stk-f591b63-column alignfull\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-b5f91f6 stk-block-background\" data-v=\"4\" target=\"_self\" data-block-id=\"b5f91f6\"><style>.stk-b5f91f6 {background-color:#f4f4f4 !important;border-style:solid !important;border-top-width:0px !important;border-right-width:1px !important;border-bottom-width:0px !important;border-left-width:0px !important;}.stk-b5f91f6:before{background-color:#f4f4f4 !important;}@media screen and (min-width: 768px){.stk-b5f91f6 {flex:var(--stk-flex-grow, 1) 1 25% !important;}}@media screen and (max-width: 767px){.stk-b5f91f6 {padding-top:10px !important;padding-right:0px !important;padding-bottom:10px !important;padding-left:0px !important;flex:var(--stk-flex-grow, 1) 1 calc(25% - var(--stk-column-gap, 0px) * 3 \/ 4 ) !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-b5f91f6-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-b5f91f6-inner-blocks\">\n<a href=\"https:\/\/www.ull.es\/formacion-permanente\/blog\/estrategias-para-el-abordaje-integral-de-los-pacientes-polimedicados\/#estrategias-para-el-abordaje-integral-de-los-pacientes-polimedicados\/\" target=\"_self\" style=\"color:black;text-align:center\" target=\"_blank\" rel=\"noopener\">Presentaci\u00f3n<\/a>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-324f3d4 stk-block-background\" data-v=\"4\" data-block-id=\"324f3d4\"><style>.stk-324f3d4 {background-color:#f4f4f4 !important;border-style:solid !important;border-top-width:0px !important;border-right-width:1px !important;border-bottom-width:0px !important;border-left-width:0px !important;}.stk-324f3d4:before{background-color:#f4f4f4 !important;}@media screen and (min-width: 768px){.stk-324f3d4 {flex:var(--stk-flex-grow, 1) 1 25% !important;}}@media screen and (max-width: 767px){.stk-324f3d4 {padding-top:0px !important;padding-right:0px !important;padding-bottom:0px !important;padding-left:0px !important;flex:var(--stk-flex-grow, 1) 1 calc(25% - var(--stk-column-gap, 0px) * 3 \/ 4 ) !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-324f3d4-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-324f3d4-inner-blocks\">\n<a href=\"https:\/\/www.ull.es\/formacion-permanente\/blog\/estrategias-para-el-abordaje-integral-de-los-pacientes-polimedicados\/#contenidos\" target=\"_self\" style=\"color:black;text-align:center\" target=\"_blank\" rel=\"noopener\">Programa acad\u00e9mico<\/a>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-772438d stk-block-background\" data-v=\"4\" data-block-id=\"772438d\"><style>.stk-772438d {background-color:#f4f4f4 !important;border-style:solid !important;border-top-width:0px !important;border-right-width:1px !important;border-bottom-width:0px !important;border-left-width:0px !important;}.stk-772438d:before{background-color:#f4f4f4 !important;}@media screen and (min-width: 768px){.stk-772438d {flex:var(--stk-flex-grow, 1) 1 25% !important;}}@media screen and (max-width: 767px){.stk-772438d {padding-top:0px !important;padding-right:0px !important;padding-bottom:0px !important;padding-left:0px !important;flex:var(--stk-flex-grow, 1) 1 calc(25% - var(--stk-column-gap, 0px) * 3 \/ 4 ) !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-772438d-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-772438d-inner-blocks\">\n<a href=\"https:\/\/www.ull.es\/formacion-permanente\/blog\/estrategias-para-el-abordaje-integral-de-los-pacientes-polimedicados\/#equipo-docente\" target=\"_self\" style=\"color:black;text-align:center\" target=\"_blank\" rel=\"noopener\">Equipo Docente<\/a>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-631f8d7 stk-block-background\" data-v=\"4\" data-block-id=\"631f8d7\"><style>.stk-631f8d7 {background-color:#f4f4f4 !important;}.stk-631f8d7:before{background-color:#f4f4f4 !important;}@media screen and (min-width: 768px){.stk-631f8d7 {flex:var(--stk-flex-grow, 1) 1 25% !important;}}@media screen and (max-width: 767px){.stk-631f8d7 {padding-top:10px !important;padding-right:0px !important;padding-bottom:10px !important;padding-left:0px !important;flex:var(--stk-flex-grow, 1) 1 calc(25% - var(--stk-column-gap, 0px) * 3 \/ 4 ) !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-631f8d7-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-631f8d7-inner-blocks\">\n<a href=\"https:\/\/www.ull.es\/formacion-permanente\/blog\/estrategias-para-el-abordaje-integral-de-los-pacientes-polimedicados\/#matricula\" target=\"_self\" style=\"color:black;text-align:center\" target=\"_blank\" rel=\"noopener\">Matr\u00edcula<\/a>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns alignwide stk-block-columns stk-block stk-7f3676f\" id=\"comparte-esta-microcredencial\" data-block-id=\"7f3676f\"><style>.stk-7f3676f {padding-right:10% !important;padding-left:10% !important;}.stk-7f3676f-column{--stk-column-gap:var(--stk--preset--spacing--70, 3.38rem) !important;}@media screen and (max-width: 767px){.stk-7f3676f {padding-right:5% !important;padding-left:5% !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-7f3676f-column alignwide\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-3867cc3\" data-v=\"4\" data-block-id=\"3867cc3\"><style>@media screen and (min-width: 768px){.stk-3867cc3 {flex:var(--stk-flex-grow, 1) 1 calc(50% - var(--stk-column-gap, 0px) * 1 \/ 2 ) !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-3867cc3-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-3867cc3-inner-blocks\">\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-7db7207\" id=\"estrategias-para-el-abordaje-integral-de-los-pacientes-polimedicados\" data-block-id=\"7db7207\"><style>.stk-7db7207 .stk-block-heading__text{color:#fd6921 !important;}<\/style><h2 class=\"stk-block-heading__text has-text-color\">Estrategias para el abordaje integral de los pacientes polimedicados<\/h2><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-68a4c23\" id=\"descripcion-general\" data-block-id=\"68a4c23\"><style>.stk-68a4c23 {margin-bottom:10px !important;}<\/style><h3 class=\"stk-block-heading__text\">Descripci\u00f3n general<\/h3><\/div>\n\n\n\n<p class=\"has-text-align-left\">El objetivo general de la microcredencial Estrategias para el abordaje integral de los pacientes polimedicados es capacitar al estudiantado para identificar, evaluar y abordar de manera integral la polimedicaci\u00f3n, aplicando un enfoque cl\u00ednico, cr\u00edtico y \u00e9tico que permita optimizar la adecuaci\u00f3n terap\u00e9utica, mejorar la seguridad del paciente y favorecer una atenci\u00f3n centrada en la persona, desde una perspectiva multidisciplinar, comunitaria y sociosanitaria.<\/p>\n\n\n\n<details class=\"wp-block-stackable-accordion stk-block-accordion stk-inner-blocks stk-block-content stk-block stk-8f5d083 is-style-default\" id=\"objetivos\" data-block-id=\"8f5d083\"><style>.stk-8f5d083 {margin-bottom:15px !important;}<\/style>\n<summary class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-f46ef39 stk--container-small stk-block-accordion__heading\" data-v=\"4\" data-block-id=\"f46ef39\"><style>.stk-f46ef39 {border-style:solid !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-f46ef39-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-f46ef39-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-3eb1407\" data-block-id=\"3eb1407\"><style>.stk-3eb1407 .stk-inner-blocks{gap:40px !important;}@media screen and (max-width: 1023px){.stk-3eb1407 .stk-inner-blocks{gap:40px !important;}}@media screen and (max-width: 767px){.stk-3eb1407 .stk-inner-blocks{gap:40px !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-icon stk-block-icon stk-block stk-aa6d684\" data-block-id=\"aa6d684\"><style>.stk-aa6d684 .stk--svg-wrapper .stk--inner-svg svg:last-child{height:24px !important;width:24px !important;}.stk-aa6d684 .stk--svg-wrapper .stk--inner-svg svg:last-child, .stk-aa6d684 .stk--svg-wrapper .stk--inner-svg svg:last-child :is(g, path, rect, polygon, ellipse){fill:#fd6921 !important;}<\/style><span class=\"stk--svg-wrapper stk--has-icon2\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-aa6d684\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-aa-6-d-684-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-aa-6-d-684-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M256 512A256 256 0 1 0 256 0a256 256 0 1 0 0 512zm0-352a96 96 0 1 1 0 192 96 96 0 1 1 0-192z\" \/><\/svg><\/div><div class=\"stk--inner-svg stk--icon-2\" style=\"display:none\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-aa6d684\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-aa-6-d-684-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-aa-6-d-684-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M464 256A208 208 0 1 0 48 256a208 208 0 1 0 416 0zM0 256a256 256 0 1 1 512 0A256 256 0 1 1 0 256zm256-96a96 96 0 1 1 0 192 96 96 0 1 1 0-192z\" \/><\/svg><\/div><\/span><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-1e75567\" id=\"objetivos\" data-block-id=\"1e75567\"><style>.stk-1e75567 .stk-block-heading__text{font-size:18px !important;font-weight:700 !important;font-family:\"Montserrat\", Sans-serif !important;}@media screen and (max-width: 1023px){.stk-1e75567 .stk-block-heading__text{font-size:18px !important;}}<\/style><p class=\"stk-block-heading__text\">Objetivos<\/p><\/div>\n<\/div><\/div>\n<\/div><\/div><\/summary>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-fd365ab stk-block-accordion__content\" data-v=\"4\" data-block-id=\"fd365ab\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-fd365ab-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-fd365ab-inner-blocks\">\n<p>Al finalizar la microcredencial, el estudiantado ser\u00e1 capaz de:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Reconocer la polimedicaci\u00f3n como un factor determinante en la salud de los pacientes, comprendiendo su impacto cl\u00ednico, funcional y social, as\u00ed como su relaci\u00f3n con la seguridad del paciente y la calidad de la atenci\u00f3n sanitaria.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Valorar la importancia del abordaje multidisciplinar de la polimedicaci\u00f3n, identificando el papel de los distintos profesionales implicados y la necesidad de coordinaci\u00f3n entre niveles asistenciales, especialmente en los \u00e1mbitos comunitario y sociosanitario.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Adquirir habilidades para la valoraci\u00f3n integral del paciente polimedicado, incluyendo la identificaci\u00f3n de problemas relacionados con los medicamentos y la evaluaci\u00f3n de la adecuaci\u00f3n terap\u00e9utica mediante criterios cl\u00ednicos y herramientas de apoyo a la prescripci\u00f3n y dispensaci\u00f3n.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Conocer y aplicar las nociones b\u00e1sicas de los sistemas de evaluaci\u00f3n de la prescripci\u00f3n y dispensaci\u00f3n en pacientes polimedicados, incorporando criterios de seguridad, eficacia y racionalidad terap\u00e9utica en la toma de decisiones.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Desarrollar un razonamiento cr\u00edtico y \u00e9tico en la toma de decisiones farmacoterap\u00e9uticas, integrando principios de seguridad del paciente y participando en el dise\u00f1o y gesti\u00f3n de programas de apoyo al paciente polimedicado orientados a la mejora de los resultados en salud.<\/li>\n<\/ul>\n<\/div><\/div><\/div>\n<\/details>\n\n\n\n<details class=\"wp-block-stackable-accordion stk-block-accordion stk-inner-blocks stk-block-content stk-block stk-63b0e61 is-style-default\" id=\"requisitos-acceso\" data-block-id=\"63b0e61\"><style>.stk-63b0e61 {margin-bottom:35px !important;}<\/style>\n<summary class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-7a88921 stk--container-small stk-block-accordion__heading\" data-v=\"4\" data-block-id=\"7a88921\"><style>.stk-7a88921 {border-style:solid !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-7a88921-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-7a88921-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-2d4eaa7\" data-block-id=\"2d4eaa7\"><style>.stk-2d4eaa7 .stk-inner-blocks{gap:40px !important;}@media screen and (max-width: 1023px){.stk-2d4eaa7 .stk-inner-blocks{gap:40px !important;}}@media screen and (max-width: 767px){.stk-2d4eaa7 .stk-inner-blocks{gap:40px !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-icon stk-block-icon stk-block stk-673f014\" data-block-id=\"673f014\"><style>.stk-673f014 .stk--svg-wrapper .stk--inner-svg svg:last-child{height:24px !important;width:24px !important;}.stk-673f014 .stk--svg-wrapper .stk--inner-svg svg:last-child, .stk-673f014 .stk--svg-wrapper .stk--inner-svg svg:last-child :is(g, path, rect, polygon, ellipse){fill:#fd6921 !important;}<\/style><span class=\"stk--svg-wrapper stk--has-icon2\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-673f014\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-673-f-014-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-673-f-014-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M256 512A256 256 0 1 0 256 0a256 256 0 1 0 0 512zM369 209L241 337c-9.4 9.4-24.6 9.4-33.9 0l-64-64c-9.4-9.4-9.4-24.6 0-33.9s24.6-9.4 33.9 0l47 47L335 175c9.4-9.4 24.6-9.4 33.9 0s9.4 24.6 0 33.9z\" \/><\/svg><\/div><div class=\"stk--inner-svg stk--icon-2\" style=\"display:none\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-673f014\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-673-f-014-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-673-f-014-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M256 48a208 208 0 1 1 0 416 208 208 0 1 1 0-416zm0 464A256 256 0 1 0 256 0a256 256 0 1 0 0 512zM369 209c9.4-9.4 9.4-24.6 0-33.9s-24.6-9.4-33.9 0l-111 111-47-47c-9.4-9.4-24.6-9.4-33.9 0s-9.4 24.6 0 33.9l64 64c9.4 9.4 24.6 9.4 33.9 0L369 209z\" \/><\/svg><\/div><\/span><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-279d68b\" id=\"requisitos-de-acceso\" data-block-id=\"279d68b\"><style>.stk-279d68b .stk-block-heading__text{font-size:18px !important;font-weight:700 !important;font-family:\"Montserrat\", Sans-serif !important;}@media screen and (max-width: 1023px){.stk-279d68b .stk-block-heading__text{font-size:18px !important;}}<\/style><p class=\"stk-block-heading__text\">Requisitos de acceso<\/p><\/div>\n<\/div><\/div>\n<\/div><\/div><\/summary>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-cd2e899 stk-block-accordion__content\" data-v=\"4\" data-block-id=\"cd2e899\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-cd2e899-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-cd2e899-inner-blocks\">\n<p>Para beneficiarse de esta acci\u00f3n formativa bonificada deber\u00e1 cumplir los siguientes requisitos:<\/p>\n\n\n\n<p>1. Ser nacional del territorio espa\u00f1ol.<\/p>\n\n\n\n<p>2. Tener entre 25 y 64 a\u00f1os de edad cumplidos a la fecha de comienzo de la formaci\u00f3n.<\/p>\n\n\n\n<p>3. Disponer de titulaci\u00f3n o experiencia profesional relacionada:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>t\u00edtulo universitario oficial espa\u00f1ol u otro expedido por una instituci\u00f3n de educaci\u00f3n superior perteneciente a otro Estado miembro del Espacio Europeo de Educaci\u00f3n Superior, adscrito a la rama de Ciencias de la Salud o a titulaciones afines directamente relacionadas con el \u00e1mbito sanitario, que faculte en el mismo para el acceso a ense\u00f1anzas de m\u00e1ster.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li> t\u00edtulo de T\u00e9cnico\/a o equivalente y acreditar una experiencia laboral m\u00ednima de cinco a\u00f1os en el sector farmac\u00e9utico, especialmente en \u00e1mbitos relacionados con la farmacia comunitaria, la atenci\u00f3n sociosanitaria o la salud p\u00fablica.<\/li>\n<\/ul>\n<\/div><\/div><\/div>\n<\/details>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-74b59eb\" id=\"programa-academico\" data-block-id=\"74b59eb\"><style>.stk-74b59eb .stk-block-heading__text{color:#fd6921 !important;}<\/style><h2 class=\"stk-block-heading__text has-text-color\">Programa acad\u00e9mico<\/h2><\/div>\n\n\n\n<details class=\"wp-block-stackable-accordion stk-block-accordion stk-inner-blocks stk-block-content stk-block stk-5ab3ca3 is-style-default\" id=\"contenidos\" data-block-id=\"5ab3ca3\"><style>.stk-5ab3ca3 {margin-bottom:15px !important;}<\/style>\n<summary class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-0196266 stk--container-small stk-block-accordion__heading\" data-v=\"4\" data-block-id=\"0196266\"><style>.stk-0196266 {border-style:solid !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-0196266-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-0196266-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-860907b\" data-block-id=\"860907b\"><style>.stk-860907b .stk-inner-blocks{gap:40px !important;}@media screen and (max-width: 1023px){.stk-860907b .stk-inner-blocks{gap:40px !important;}}@media screen and (max-width: 767px){.stk-860907b .stk-inner-blocks{gap:40px !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-icon stk-block-icon stk-block stk-6db21f4\" data-block-id=\"6db21f4\"><style>.stk-6db21f4 .stk--svg-wrapper .stk--inner-svg svg:last-child{height:24px !important;width:24px !important;}.stk-6db21f4 .stk--svg-wrapper .stk--inner-svg svg:last-child, .stk-6db21f4 .stk--svg-wrapper .stk--inner-svg svg:last-child :is(g, path, rect, polygon, ellipse){fill:#fd6921 !important;}<\/style><span class=\"stk--svg-wrapper stk--has-icon2\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-6db21f4\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-6-db-21-f-4-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-6-db-21-f-4-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M96 0C43 0 0 43 0 96V416c0 53 43 96 96 96H384h32c17.7 0 32-14.3 32-32s-14.3-32-32-32V384c17.7 0 32-14.3 32-32V32c0-17.7-14.3-32-32-32H384 96zm0 384H352v64H96c-17.7 0-32-14.3-32-32s14.3-32 32-32zm32-240c0-8.8 7.2-16 16-16H336c8.8 0 16 7.2 16 16s-7.2 16-16 16H144c-8.8 0-16-7.2-16-16zm16 48H336c8.8 0 16 7.2 16 16s-7.2 16-16 16H144c-8.8 0-16-7.2-16-16s7.2-16 16-16z\" \/><\/svg><\/div><div class=\"stk--inner-svg stk--icon-2\" style=\"display:none\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-6db21f4\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-6-db-21-f-4-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-6-db-21-f-4-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 576 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M249.6 471.5c10.8 3.8 22.4-4.1 22.4-15.5V78.6c0-4.2-1.6-8.4-5-11C247.4 52 202.4 32 144 32C93.5 32 46.3 45.3 18.1 56.1C6.8 60.5 0 71.7 0 83.8V454.1c0 11.9 12.8 20.2 24.1 16.5C55.6 460.1 105.5 448 144 448c33.9 0 79 14 105.6 23.5zm76.8 0C353 462 398.1 448 432 448c38.5 0 88.4 12.1 119.9 22.6c11.3 3.8 24.1-4.6 24.1-16.5V83.8c0-12.1-6.8-23.3-18.1-27.6C529.7 45.3 482.5 32 432 32c-58.4 0-103.4 20-123 35.6c-3.3 2.6-5 6.8-5 11V456c0 11.4 11.7 19.3 22.4 15.5z\" \/><\/svg><\/div><\/span><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-045e742\" id=\"contenidos\" data-block-id=\"045e742\"><style>.stk-045e742 .stk-block-heading__text{font-size:18px !important;font-weight:700 !important;font-family:\"Montserrat\", Sans-serif !important;}@media screen and (max-width: 1023px){.stk-045e742 .stk-block-heading__text{font-size:18px !important;}}<\/style><p class=\"stk-block-heading__text\">Contenidos<\/p><\/div>\n<\/div><\/div>\n<\/div><\/div><\/summary>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-cd51cf6 stk-block-accordion__content\" data-v=\"4\" data-block-id=\"cd51cf6\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-cd51cf6-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-cd51cf6-inner-blocks\">\n<p>Contenidos te\u00f3rico-pr\u00e1cticos de la asignatura:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Sesi\u00f3n 1: Concepto y factores determinantes de la polimedicaci\u00f3n.<br>Conceptos fundamentales, causas y factores determinantes de la polimedicaci\u00f3n.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Sesi\u00f3n 2: Implicaciones y consecuencias de la polimedicaci\u00f3n. <br>Importancia e implicaciones en la salud, implicaciones cl\u00ednicas, legales, \u00e9ticas, econ\u00f3micas y sociales.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Sesi\u00f3n 3: El fen\u00f3meno global de la polimedicaci\u00f3n dentro y fuera del sistema sanitario.<br>Elementos implicados en la polimedicaci\u00f3n y estrategias de abordaje y coordinaci\u00f3n.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Sesi\u00f3n 4: Concepto de adecuaci\u00f3n terap\u00e9utica.<br>Significado e implicaciones del concepto de adecuaci\u00f3n terap\u00e9utica.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Sesi\u00f3n 5: Abordaje biopsicosocial del paciente polimedicado.<br>Participaci\u00f3n desde las diferentes disciplinas sociosanitarias: medicina, enfermer\u00eda, farmacia, trabajo social y otros (auxiliares de farmacia, de enfermer\u00eda y administrativos). Coordinaci\u00f3n entre distintos profesionales, sectores, \u00e1mbitos de trabajo y niveles asistenciales.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Sesi\u00f3n 6: Criterios expl\u00edcitos e impl\u00edcitos para evaluar la adecuaci\u00f3n terap\u00e9utica.<br>Criterios de Lipton, Medication Appropriateness Index, Beers, DUR, etc. Indicaciones, diferencias, limitaciones de cada uno.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Sesi\u00f3n 7: Optimizaci\u00f3n de la adecuaci\u00f3n terap\u00e9utica en pacientes polimedicados.<br>Modelos de intervenci\u00f3n sobre pacientes polimedicados. Adecuaci\u00f3n terap\u00e9utica basada en la Evidencia. Planificaci\u00f3n, estrategias de implementaci\u00f3n y evaluaci\u00f3n de los distintos modelos. Seguimiento farmacoterap\u00e9utico multidisciplinar. Evidencia de los distintos modelos de intervenci\u00f3n sobre la adecuaci\u00f3n terap\u00e9utica.<\/li>\n<\/ul>\n<\/div><\/div><\/div>\n<\/details>\n\n\n\n<details class=\"wp-block-stackable-accordion stk-block-accordion stk-inner-blocks stk-block-content stk-block stk-eb46160 is-style-default\" id=\"metodologia-y-actividades\" data-block-id=\"eb46160\"><style>.stk-eb46160 {margin-bottom:15px !important;}<\/style>\n<summary class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-cbfaa79 stk--container-small stk-block-accordion__heading\" data-v=\"4\" data-block-id=\"cbfaa79\"><style>.stk-cbfaa79 {border-style:solid !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-cbfaa79-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-cbfaa79-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-343cacc\" data-block-id=\"343cacc\"><style>.stk-343cacc .stk-inner-blocks{gap:40px !important;}@media screen and (max-width: 1023px){.stk-343cacc .stk-inner-blocks{gap:40px !important;}}@media screen and (max-width: 767px){.stk-343cacc .stk-inner-blocks{gap:40px !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-icon stk-block-icon stk-block stk-a606fb3\" data-block-id=\"a606fb3\"><style>.stk-a606fb3 .stk--svg-wrapper .stk--inner-svg svg:last-child{height:24px !important;width:24px !important;}.stk-a606fb3 .stk--svg-wrapper .stk--inner-svg svg:last-child, .stk-a606fb3 .stk--svg-wrapper .stk--inner-svg svg:last-child :is(g, path, rect, polygon, ellipse){fill:#fd6921 !important;}<\/style><span class=\"stk--svg-wrapper stk--has-icon2\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-a606fb3\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-a-606-fb-3-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-a-606-fb-3-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M471.6 21.7c-21.9-21.9-57.3-21.9-79.2 0L362.3 51.7l97.9 97.9 30.1-30.1c21.9-21.9 21.9-57.3 0-79.2L471.6 21.7zm-299.2 220c-6.1 6.1-10.8 13.6-13.5 21.9l-29.6 88.8c-2.9 8.6-.6 18.1 5.8 24.6s15.9 8.7 24.6 5.8l88.8-29.6c8.2-2.7 15.7-7.4 21.9-13.5L437.7 172.3 339.7 74.3 172.4 241.7zM96 64C43 64 0 107 0 160V416c0 53 43 96 96 96H352c53 0 96-43 96-96V320c0-17.7-14.3-32-32-32s-32 14.3-32 32v96c0 17.7-14.3 32-32 32H96c-17.7 0-32-14.3-32-32V160c0-17.7 14.3-32 32-32h96c17.7 0 32-14.3 32-32s-14.3-32-32-32H96z\" \/><\/svg><\/div><div class=\"stk--inner-svg stk--icon-2\" style=\"display:none\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-a606fb3\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-a-606-fb-3-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-a-606-fb-3-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M441 58.9L453.1 71c9.4 9.4 9.4 24.6 0 33.9L424 134.1 377.9 88 407 58.9c9.4-9.4 24.6-9.4 33.9 0zM209.8 256.2L344 121.9 390.1 168 255.8 302.2c-2.9 2.9-6.5 5-10.4 6.1l-58.5 16.7 16.7-58.5c1.1-3.9 3.2-7.5 6.1-10.4zM373.1 25L175.8 222.2c-8.7 8.7-15 19.4-18.3 31.1l-28.6 100c-2.4 8.4-.1 17.4 6.1 23.6s15.2 8.5 23.6 6.1l100-28.6c11.8-3.4 22.5-9.7 31.1-18.3L487 138.9c28.1-28.1 28.1-73.7 0-101.8L474.9 25C446.8-3.1 401.2-3.1 373.1 25zM88 64C39.4 64 0 103.4 0 152V424c0 48.6 39.4 88 88 88H360c48.6 0 88-39.4 88-88V312c0-13.3-10.7-24-24-24s-24 10.7-24 24V424c0 22.1-17.9 40-40 40H88c-22.1 0-40-17.9-40-40V152c0-22.1 17.9-40 40-40H200c13.3 0 24-10.7 24-24s-10.7-24-24-24H88z\" \/><\/svg><\/div><\/span><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-35720bb\" id=\"metodologia-y-actividades\" data-block-id=\"35720bb\"><style>.stk-35720bb .stk-block-heading__text{font-size:18px !important;font-weight:700 !important;font-family:\"Montserrat\", Sans-serif !important;}@media screen and (max-width: 1023px){.stk-35720bb .stk-block-heading__text{font-size:18px !important;}}<\/style><p class=\"stk-block-heading__text\">Metodolog\u00eda y actividades<\/p><\/div>\n<\/div><\/div>\n<\/div><\/div><\/summary>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-e67fe82 stk-block-accordion__content\" data-v=\"4\" data-block-id=\"e67fe82\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-e67fe82-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-e67fe82-inner-blocks\">\n<p>Las actividades formativas que desarrollar durante la impartici\u00f3n de la microcredencial ser\u00e1n:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Clases te\u00f3ricas: sesiones expositivas, explicativas o de demostraci\u00f3n de los contenidos y conocimientos.<\/li>\n\n\n\n<li>Clases pr\u00e1cticas: sesiones de aplicaci\u00f3n pr\u00e1ctica de los contenidos desarrollados en las clases te\u00f3ricas, mediante la resoluci\u00f3n de ejercicios, problemas o supuestos te\u00f3rico-pr\u00e1cticos.<\/li>\n\n\n\n<li>Seminarios-Talleres u otras actividades complementarias (foros de debate, simulaciones&#8230;): sesiones monogr\u00e1ficas en las que se fomenta la participaci\u00f3n del estudiantado. Son supervisadas por el profesorado de la asignatura.<\/li>\n\n\n\n<li>Trabajo: elaboraci\u00f3n de un estudio, ensayo, trabajo&#8230; propuesto en la asignatura, bien de manera individual o grupal siguiendo unas directrices establecidas.<\/li>\n\n\n\n<li>Trabajo aut\u00f3nomo: actividad independiente y autorregulada del estudiante a partir de la documentaci\u00f3n y directrices propuestas en la asignatura, preparaci\u00f3n de clases y ex\u00e1menes, elaboraci\u00f3n de memorias finales, informes de pr\u00e1cticas &#8230;<\/li>\n\n\n\n<li>Exposiciones, debates y defensas de trabajos y proyectos: actividad a trav\u00e9s de la cual el estudiantado presenta trabajos, ejercicios, proyectos&#8230; en base a unos criterios establecidos,demostrando suficiencia y madurez en la adquisici\u00f3n de las competencias previstas.<\/li>\n\n\n\n<li>Tutor\u00eda (individuales, grupales&#8230;): actividad en la que el profesorado atiende, facilita y orienta a uno o varios estudiantes en el proceso formativo.<\/li>\n\n\n\n<li>Evaluaci\u00f3n: realizaci\u00f3n de pruebas de evaluaci\u00f3n continua y ex\u00e1menes finales. Las pruebas podr\u00e1n ser presenciales o virtuales, y desarrollarse de manera escrita, oral o consistir en la ejecuci\u00f3n de pr\u00e1cticas.<\/li>\n<\/ul>\n\n\n\n<p>En cuanto a la manera de organizar la ense\u00f1anza para conseguir los objetivos planteados en la microcredencial se seguir\u00e1 la modalidad organizativa que se resumen a continuaci\u00f3n:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Lecciones magistrales\/m\u00e9todo expositivo: presentaci\u00f3n o explicaci\u00f3n por parte del profesorado.<\/li>\n\n\n\n<li>Seminarios: realizaci\u00f3n de ejercicios, resoluci\u00f3n de problemas o casos pr\u00e1cticos, otros.<\/li>\n\n\n\n<li>Trabajo individual: preparaci\u00f3n individual de trabajos\/proyectos\/informes, portafolio&#8230;<\/li>\n\n\n\n<li>Trabajo en grupo: preparaci\u00f3n grupal de trabajos, proyectos\/informes&#8230;<\/li>\n\n\n\n<li>Estudio personal: preparaci\u00f3n de pruebas, ex\u00e1menes&#8230;<\/li>\n\n\n\n<li> Evaluaci\u00f3n: pruebas escritas, orales, pr\u00e1cticas&#8230;<\/li>\n\n\n\n<li>Tutor\u00eda: per\u00edodo de instrucci\u00f3n en el que interact\u00faan profesorado y estudiante con el objetivo de revisar y discutir materiales y temas presentados en clase.<\/li>\n\n\n\n<li>Exposiciones, debates y presentaci\u00f3n de trabajos y proyectos: actividades supervisadas por el profesorado.<\/li>\n\n\n\n<li>Metodolog\u00edas activas: aprendizaje cooperativo, aprendizaje basado en proyectos, aula invertida,aprendizaje servicio, aprendizaje basado en el juego, estudio de casos, resoluci\u00f3n de problemas \u2026 Est\u00e1n dirigidas a hacer del aprendizaje un proceso participativo y est\u00e1n basadas en el protagonismo del estudiantado.<\/li>\n<\/ul>\n<\/div><\/div><\/div>\n<\/details>\n\n\n\n<details class=\"wp-block-stackable-accordion stk-block-accordion stk-inner-blocks stk-block-content stk-block stk-d585e9a is-style-default\" id=\"criterios-evaluacion\" data-block-id=\"d585e9a\"><style>.stk-d585e9a {margin-bottom:35px !important;}<\/style>\n<summary class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-22a1934 stk--container-small stk-block-accordion__heading\" data-v=\"4\" data-block-id=\"22a1934\"><style>.stk-22a1934 {border-style:solid !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-22a1934-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-22a1934-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-84ea9dc\" data-block-id=\"84ea9dc\"><style>.stk-84ea9dc .stk-inner-blocks{gap:40px !important;}@media screen and (max-width: 1023px){.stk-84ea9dc .stk-inner-blocks{gap:40px !important;}}@media screen and (max-width: 767px){.stk-84ea9dc .stk-inner-blocks{gap:40px !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-icon stk-block-icon stk-block stk-d6b404e\" data-block-id=\"d6b404e\"><style>.stk-d6b404e .stk--svg-wrapper .stk--inner-svg svg:last-child{height:24px !important;width:24px !important;}.stk-d6b404e .stk--svg-wrapper .stk--inner-svg svg:last-child, .stk-d6b404e .stk--svg-wrapper .stk--inner-svg svg:last-child :is(g, path, rect, polygon, ellipse){fill:#fd6921 !important;}<\/style><span class=\"stk--svg-wrapper stk--has-icon2\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-d6b404e\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-d-6-b-404-e-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-d-6-b-404-e-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M256 512A256 256 0 1 0 256 0a256 256 0 1 0 0 512zM216 336h24V272H216c-13.3 0-24-10.7-24-24s10.7-24 24-24h48c13.3 0 24 10.7 24 24v88h8c13.3 0 24 10.7 24 24s-10.7 24-24 24H216c-13.3 0-24-10.7-24-24s10.7-24 24-24zm40-208a32 32 0 1 1 0 64 32 32 0 1 1 0-64z\" \/><\/svg><\/div><div class=\"stk--inner-svg stk--icon-2\" style=\"display:none\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-d6b404e\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-d-6-b-404-e-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-d-6-b-404-e-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 192 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M48 80a48 48 0 1 1 96 0A48 48 0 1 1 48 80zM0 224c0-17.7 14.3-32 32-32H96c17.7 0 32 14.3 32 32V448h32c17.7 0 32 14.3 32 32s-14.3 32-32 32H32c-17.7 0-32-14.3-32-32s14.3-32 32-32H64V256H32c-17.7 0-32-14.3-32-32z\" \/><\/svg><\/div><\/span><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-4b52ff4\" id=\"criterios-de-evaluacion\" data-block-id=\"4b52ff4\"><style>.stk-4b52ff4 .stk-block-heading__text{font-size:18px !important;font-weight:700 !important;font-family:\"Montserrat\", Sans-serif !important;}@media screen and (max-width: 1023px){.stk-4b52ff4 .stk-block-heading__text{font-size:18px !important;}}<\/style><p class=\"stk-block-heading__text\">Criterios de evaluaci\u00f3n<\/p><\/div>\n<\/div><\/div>\n<\/div><\/div><\/summary>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-8193c31 stk-block-accordion__content\" data-v=\"4\" data-block-id=\"8193c31\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-8193c31-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-8193c31-inner-blocks\">\n<p>La microcredencial contara con un sistema de evaluaci\u00f3n (SE) basado en las siguientes pruebas de evaluaci\u00f3n:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Pruebas objetivas (verdadero\/falso, elecci\u00f3n m\u00faltiple, tipo test, de completar, ordenar, etc.): son instrumentos de medida que permiten evaluar los conocimientos, capacidades, rendimiento, aptitudes, etc. Las respuestas son cerradas y a la hora de su correcci\u00f3n se favorece la objetividad.<\/li>\n\n\n\n<li>Pruebas de respuesta corta o breve: tipolog\u00eda de las pruebas objetivas en las que el estudiantado no se extiende en su respuesta debiendo responder a la informaci\u00f3n espec\u00edfica que se le exige.<\/li>\n\n\n\n<li>Resoluci\u00f3n de casos, ejercicios y problemas: pruebas en las que el estudiantado debe resolver de forma razonada, en un tiempo determinado, y acorde a los criterios establecidos, los casos, ejercicios o problemas planteados por el profesorado, con la finalidad de aplicar los conocimientos adquiridos.<\/li>\n\n\n\n<li>Asistencia, participaci\u00f3n o actitud en actividades docentes, seminarios, tutor\u00edas, etc.: control de la asistencia y la participaci\u00f3n del estudiantado en las actividades docentes, realizaci\u00f3n de actividades en el transcurso de las sesiones docentes.<\/li>\n\n\n\n<li>Trabajos, memorias, memorias de pr\u00e1cticas, informes y proyectos escritos: documento elaborado sobre un tema o actividad realizada, siguiendo las instrucciones establecidas por el profesorado.<\/li>\n\n\n\n<li>Presentaci\u00f3n oral y defensa de temas, trabajos, etc.: presentaci\u00f3n oral sobre un tema correspondiente a los contenidos de la microcredencial o sobre los resultados de un trabajo, ejercicio o proyecto, con posterior debate con el profesorado. Puede realizarse individual o en grupo<\/li>\n\n\n\n<li>Portafolio, diarios, cuadernos de notas o pr\u00e1cticas, etc.: recopilaci\u00f3n del trabajo del estudiantado a trav\u00e9s del que se muestra su progreso y logros. La compilaci\u00f3n las evidencias de la autorreflexi\u00f3n.<\/li>\n\n\n\n<li>T\u00e9cnicas de observaci\u00f3n (registros, listas de control, escalas de actitud, etc.): aplicaci\u00f3n de m\u00e9todos para describir y registrar las manifestaciones del comportamiento del estudiantado.<\/li>\n<\/ul>\n<\/div><\/div><\/div>\n<\/details>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-4cb92f3\" data-v=\"4\" data-block-id=\"4cb92f3\"><style>@media screen and (min-width: 768px){.stk-4cb92f3 {flex:var(--stk-flex-grow, 1) 1 calc(50% - var(--stk-column-gap, 0px) * 1 \/ 2 ) !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-4cb92f3-container stk--no-background stk--no-padding\"><div class=\"has-text-align-left stk-block-content stk-inner-blocks stk-4cb92f3-inner-blocks\">\n<div class=\"wp-block-stackable-columns alignwide stk-block-columns stk-block stk-3ee4b85 stk-block-background\" data-block-id=\"3ee4b85\"><style>.stk-3ee4b85 {background-color:#f4f4f4 !important;margin-bottom:50px !important;}.stk-3ee4b85:before{background-color:#f4f4f4 !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-3ee4b85-column alignwide\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-8de1e02\" data-v=\"4\" data-block-id=\"8de1e02\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-8de1e02-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-8de1e02-inner-blocks\">\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-ccb61fc\" id=\"informacion-general\" data-block-id=\"ccb61fc\"><style>.stk-ccb61fc .stk-block-heading__text{color:#fd6921 !important;}<\/style><h2 class=\"stk-block-heading__text has-text-color\">Informaci\u00f3n general<\/h2><\/div>\n\n\n\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-6b7fba9\" data-block-id=\"6b7fba9\"><style>.stk-6b7fba9 {margin-bottom:6px !important;}<\/style><p class=\"stk-block-text__text\"><strong>Cr\u00e9ditos:<\/strong> 3 ECTS<\/p><\/div>\n\n\n\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-6317692\" data-block-id=\"6317692\"><style>.stk-6317692 {margin-bottom:6px !important;}<\/style><p class=\"stk-block-text__text\"><strong>Duraci\u00f3n:<\/strong> 11\/05\/2026 &#8211; 22\/05\/2026<\/p><\/div>\n\n\n\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-ba8c994\" data-block-id=\"ba8c994\"><style>.stk-ba8c994 {margin-bottom:6px !important;}<\/style><p class=\"stk-block-text__text\"><strong>Modalidad de ense\u00f1anza:<\/strong> Virtualo<\/p><\/div>\n\n\n\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-b6f5ecf\" data-block-id=\"b6f5ecf\"><p class=\"stk-block-text__text\"><strong>Lugar de impartici\u00f3n:<\/strong> Campus virtual de la Universidad de La Laguna<\/p><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns alignwide stk-block-columns stk-block stk-bc2d4d9 stk-block-background\" id=\"matricula\" data-block-id=\"bc2d4d9\"><style>.stk-bc2d4d9 {background-color:#f4f4f4 !important;padding-right:12% !important;padding-left:12% !important;margin-bottom:50px !important;}.stk-bc2d4d9:before{background-color:#f4f4f4 !important;}.stk-bc2d4d9-column{--stk-column-gap:var(--stk--preset--spacing--60, 2.25rem) !important;}@media screen and (max-width: 767px){.stk-bc2d4d9 {padding-right:5% !important;padding-left:5% !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-bc2d4d9-column alignwide\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-aaf46cf\" data-v=\"4\" data-block-id=\"aaf46cf\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-aaf46cf-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-aaf46cf-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-4a6dbf6\" data-block-id=\"4a6dbf6\"><style>.stk-4a6dbf6 {margin-bottom:10px !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-icon stk-block-icon has-text-align-left stk-block stk-1943f0f\" data-block-id=\"1943f0f\"><style>.stk-1943f0f .stk--svg-wrapper .stk--inner-svg svg:last-child, .stk-1943f0f .stk--svg-wrapper .stk--inner-svg svg:last-child :is(g, path, rect, polygon, ellipse){fill:#fd6921 !important;}<\/style><span class=\"stk--svg-wrapper\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-1943f0f\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-1943-f-0-f-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-1943-f-0-f-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 576 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M312 24V34.5c6.4 1.2 12.6 2.7 18.2 4.2c12.8 3.4 20.4 16.6 17 29.4s-16.6 20.4-29.4 17c-10.9-2.9-21.1-4.9-30.2-5c-7.3-.1-14.7 1.7-19.4 4.4c-2.1 1.3-3.1 2.4-3.5 3c-.3 .5-.7 1.2-.7 2.8c0 .3 0 .5 0 .6c.2 .2 .9 1.2 3.3 2.6c5.8 3.5 14.4 6.2 27.4 10.1l.9 .3c11.1 3.3 25.9 7.8 37.9 15.3c13.7 8.6 26.1 22.9 26.4 44.9c.3 22.5-11.4 38.9-26.7 48.5c-6.7 4.1-13.9 7-21.3 8.8V232c0 13.3-10.7 24-24 24s-24-10.7-24-24V220.6c-9.5-2.3-18.2-5.3-25.6-7.8c-2.1-.7-4.1-1.4-6-2c-12.6-4.2-19.4-17.8-15.2-30.4s17.8-19.4 30.4-15.2c2.6 .9 5 1.7 7.3 2.5c13.6 4.6 23.4 7.9 33.9 8.3c8 .3 15.1-1.6 19.2-4.1c1.9-1.2 2.8-2.2 3.2-2.9c.4-.6 .9-1.8 .8-4.1l0-.2c0-1 0-2.1-4-4.6c-5.7-3.6-14.3-6.4-27.1-10.3l-1.9-.6c-10.8-3.2-25-7.5-36.4-14.4c-13.5-8.1-26.5-22-26.6-44.1c-.1-22.9 12.9-38.6 27.7-47.4c6.4-3.8 13.3-6.4 20.2-8.2V24c0-13.3 10.7-24 24-24s24 10.7 24 24zM568.2 336.3c13.1 17.8 9.3 42.8-8.5 55.9L433.1 485.5c-23.4 17.2-51.6 26.5-80.7 26.5H192 32c-17.7 0-32-14.3-32-32V416c0-17.7 14.3-32 32-32H68.8l44.9-36c22.7-18.2 50.9-28 80-28H272h16 64c17.7 0 32 14.3 32 32s-14.3 32-32 32H288 272c-8.8 0-16 7.2-16 16s7.2 16 16 16H392.6l119.7-88.2c17.8-13.1 42.8-9.3 55.9 8.5zM193.6 384l0 0-.9 0c.3 0 .6 0 .9 0z\" \/><\/svg><\/div><\/span><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-4034cc0\" id=\"matricula-65-25-\u20ac\" data-block-id=\"4034cc0\"><style>.stk-4034cc0 .stk-block-heading__text{color:#fd6921 !important;}<\/style><h2 class=\"stk-block-heading__text has-text-color\">Matr\u00edcula: 65,25\u20ac<\/h2><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-2c7fd56\" id=\"valorado-en-217-50-\u20ac\" data-block-id=\"2c7fd56\"><style>.stk-2c7fd56 .stk-block-heading__text{color:#333333 !important;}<\/style><h3 class=\"stk-block-heading__text has-text-color\">Valorado en: 217,50\u20ac<\/h3><\/div>\n\n\n\n<div class=\"wp-block-stackable-button-group stk-block-button-group stk-block stk-499e036\" data-block-id=\"499e036\"><style>.stk-499e036 .stk-block-button, .stk-499e036 .stk-block-icon-button{flex:1 0 0% !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-button-group\">\n<div class=\"wp-block-stackable-button stk-block-button stk-block stk-f6ba549\" data-block-id=\"f6ba549\"><style>.stk-f6ba549 .stk-button{background:#fd6921 !important;}<\/style><a class=\"stk-link stk-button stk--hover-effect-darken\" href=\"https:\/\/sede.fg.ull.es\/es\/curso\/detalle?code=a26030201&amp;name=estrategias-para-el-abordaje-integral-de-los-pacientes-polimedicados\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\"><span class=\"stk-button__inner-text\">Inscripci\u00f3n<\/span><\/a><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-button-group stk-block-button-group stk-block stk-d374209\" data-block-id=\"d374209\"><style>.stk-d374209 .stk-block-button, .stk-d374209 .stk-block-icon-button{flex:1 0 0% !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-button-group\">\n<div class=\"wp-block-stackable-button stk-block-button stk-block stk-253965d\" data-block-id=\"253965d\"><style>.stk-253965d .stk-button{background:#333333 !important;}<\/style><a class=\"stk-link stk-button stk--hover-effect-darken\" href=\"https:\/\/share.hsforms.com\/1RPwF2gFzR6asbIBP3yxJqAc29k2\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\"><span class=\"stk-button__inner-text\">M\u00e1s info y ayuda a la inscripci\u00f3n<\/span><\/a><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-2272359\" data-block-id=\"2272359\"><p class=\"stk-block-text__text\">El coste de la matr\u00edcula de esta Microcredencal estar\u00e1 subvencionado por el &#8216;Plan para el desarrollo de microcredenciales universitarias&#8217;, inversi\u00f3n 6 del componente 21 de la Adenda del &#8216;Plan de recuperaci\u00f3n, transformaci\u00f3n y resiliencia&#8217;, financiado por la Uni\u00f3n Europea &#8211; Next Generation EU, ejercicio 2025.<\/p><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns alignwide stk-block-columns stk-block stk-6f11dd8\" data-block-id=\"6f11dd8\"><style>.stk-6f11dd8 .stk--block-align-6f11dd8{align-items:center !important;}.stk-6f11dd8 {box-shadow:0px 0px 10px 8px #f4f4f4 !important;padding-top:5% !important;padding-right:5% !important;padding-bottom:5% !important;padding-left:5% !important;margin-bottom:50px !important;}.stk-6f11dd8-column{--stk-column-gap:35px !important;}@media screen and (max-width: 767px){.stk-6f11dd8 {padding-right:5% !important;padding-left:5% !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk--block-align-6f11dd8 stk-block-content stk-content-align stk-6f11dd8-column alignwide\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-3a306da\" data-v=\"4\" data-block-id=\"3a306da\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-3a306da-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-3a306da-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label aligncenter stk-block-icon-label stk-block stk-6f742e0\" id=\"strong-flexibilidad-strong\" data-block-id=\"6f742e0\"><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-icon stk-block-icon has-text-align-left stk-block stk-fabbc9a\" data-block-id=\"fabbc9a\"><style>.stk-fabbc9a .stk--svg-wrapper .stk--inner-svg svg:last-child, .stk-fabbc9a .stk--svg-wrapper .stk--inner-svg svg:last-child :is(g, path, rect, polygon, ellipse){fill:#fd6921 !important;}<\/style><span class=\"stk--svg-wrapper\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-fabbc9a\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-fabbc-9-a-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-fabbc-9-a-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M464 256A208 208 0 1 1 48 256a208 208 0 1 1 416 0zM0 256a256 256 0 1 0 512 0A256 256 0 1 0 0 256zM232 120V256c0 8 4 15.5 10.7 20l96 64c11 7.4 25.9 4.4 33.3-6.7s4.4-25.9-6.7-33.3L280 243.2V120c0-13.3-10.7-24-24-24s-24 10.7-24 24z\" \/><\/svg><\/div><\/span><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-e357f4b\" id=\"strong-flexibilidad-strong\" data-block-id=\"e357f4b\"><style>.stk-e357f4b .stk-block-heading__text{font-size:16px !important;color:#fd6921 !important;}@media screen and (max-width: 1023px){.stk-e357f4b .stk-block-heading__text{font-size:16px !important;}}<\/style><h4 class=\"stk-block-heading__text has-text-color\"><strong>Flexibilidad<\/strong><\/h4><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-921bc2d\" data-block-id=\"921bc2d\"><p class=\"stk-block-text__text\">De corta duraci\u00f3n y en diversas modalidades (presencial, online o h\u00edbrida). Ideal para aprender sin interrumpir tu vida profesional.<\/p><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns alignwide stk-block-columns stk-block stk-c466dd9\" data-block-id=\"c466dd9\"><style>.stk-c466dd9 .stk--block-align-c466dd9{align-items:center !important;}.stk-c466dd9 {box-shadow:0px 0px 10px 8px #f4f4f4 !important;padding-top:5% !important;padding-right:5% !important;padding-bottom:5% !important;padding-left:5% !important;margin-bottom:50px !important;}.stk-c466dd9-column{--stk-column-gap:35px !important;}@media screen and (max-width: 767px){.stk-c466dd9 {padding-right:5% !important;padding-left:5% !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk--block-align-c466dd9 stk-block-content stk-content-align stk-c466dd9-column alignwide\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-4002da8\" data-v=\"4\" data-block-id=\"4002da8\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-4002da8-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-4002da8-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label aligncenter stk-block-icon-label stk-block stk-5d57d9b\" id=\"strong-empleabilidad-strong\" data-block-id=\"5d57d9b\"><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-icon stk-block-icon has-text-align-left stk-block stk-90ccf77\" data-block-id=\"90ccf77\"><style>.stk-90ccf77 .stk--svg-wrapper .stk--inner-svg svg:last-child, .stk-90ccf77 .stk--svg-wrapper .stk--inner-svg svg:last-child :is(g, path, rect, polygon, ellipse){fill:#fd6921 !important;}<\/style><span class=\"stk--svg-wrapper\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-90ccf77\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-90-ccf-77-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-90-ccf-77-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M156.6 384.9L125.7 354c-8.5-8.5-11.5-20.8-7.7-32.2c3-8.9 7-20.5 11.8-33.8L24 288c-8.6 0-16.6-4.6-20.9-12.1s-4.2-16.7 .2-24.1l52.5-88.5c13-21.9 36.5-35.3 61.9-35.3l82.3 0c2.4-4 4.8-7.7 7.2-11.3C289.1-4.1 411.1-8.1 483.9 5.3c11.6 2.1 20.6 11.2 22.8 22.8c13.4 72.9 9.3 194.8-111.4 276.7c-3.5 2.4-7.3 4.8-11.3 7.2v82.3c0 25.4-13.4 49-35.3 61.9l-88.5 52.5c-7.4 4.4-16.6 4.5-24.1 .2s-12.1-12.2-12.1-20.9V380.8c-14.1 4.9-26.4 8.9-35.7 11.9c-11.2 3.6-23.4 .5-31.8-7.8zM384 168a40 40 0 1 0 0-80 40 40 0 1 0 0 80z\" \/><\/svg><\/div><\/span><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-89bd60a\" id=\"strong-empleabilidad-strong\" data-block-id=\"89bd60a\"><style>.stk-89bd60a .stk-block-heading__text{font-size:16px !important;color:#fd6921 !important;}@media screen and (max-width: 1023px){.stk-89bd60a .stk-block-heading__text{font-size:16px !important;}}<\/style><h4 class=\"stk-block-heading__text has-text-color\"><strong>Empleabilidad<\/strong><\/h4><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-cf25970\" data-block-id=\"cf25970\"><p class=\"stk-block-text__text\">Contenidos creados e impartidos por profesionales y expertos en la materia, pensando en su aplicaci\u00f3n inmediata.<\/p><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns alignwide stk-block-columns stk-block stk-a57c11d\" data-block-id=\"a57c11d\"><style>.stk-a57c11d .stk--block-align-a57c11d{align-items:center !important;}.stk-a57c11d {box-shadow:0px 0px 10px 8px #f4f4f4 !important;padding-top:5% !important;padding-right:5% !important;padding-bottom:5% !important;padding-left:5% !important;margin-bottom:15px !important;}.stk-a57c11d-column{--stk-column-gap:35px !important;}@media screen and (max-width: 767px){.stk-a57c11d {padding-right:5% !important;padding-left:5% !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk--block-align-a57c11d stk-block-content stk-content-align stk-a57c11d-column alignwide\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-3bfecfc\" data-v=\"4\" data-block-id=\"3bfecfc\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-3bfecfc-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-3bfecfc-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label aligncenter stk-block-icon-label stk-block stk-420b283\" id=\"strong-certificacion-strong\" data-block-id=\"420b283\"><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-icon stk-block-icon has-text-align-left stk-block stk-18f8001\" data-block-id=\"18f8001\"><style>.stk-18f8001 .stk--svg-wrapper .stk--inner-svg svg:last-child, .stk-18f8001 .stk--svg-wrapper .stk--inner-svg svg:last-child :is(g, path, rect, polygon, ellipse){fill:#fd6921 !important;}<\/style><span class=\"stk--svg-wrapper\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-18f8001\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-18-f-8001-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-18-f-8001-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 384 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M64 0C28.7 0 0 28.7 0 64V448c0 35.3 28.7 64 64 64H320c35.3 0 64-28.7 64-64V64c0-35.3-28.7-64-64-64H64zm96 320h64c44.2 0 80 35.8 80 80c0 8.8-7.2 16-16 16H96c-8.8 0-16-7.2-16-16c0-44.2 35.8-80 80-80zm-32-96a64 64 0 1 1 128 0 64 64 0 1 1 -128 0zM144 64h96c8.8 0 16 7.2 16 16s-7.2 16-16 16H144c-8.8 0-16-7.2-16-16s7.2-16 16-16z\" \/><\/svg><\/div><\/span><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-2aede23\" id=\"strong-certificacion-strong\" data-block-id=\"2aede23\"><style>.stk-2aede23 .stk-block-heading__text{font-size:16px !important;color:#fd6921 !important;}@media screen and (max-width: 1023px){.stk-2aede23 .stk-block-heading__text{font-size:16px !important;}}<\/style><h4 class=\"stk-block-heading__text has-text-color\"><strong>Certificaci\u00f3n<\/strong><\/h4><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-7a2805a\" data-block-id=\"7a2805a\"><p class=\"stk-block-text__text\">Avalado por la Universidad de La Laguna. Recibir\u00e1s un certificado oficial ECTS, v\u00e1lido en el Espacio Europeo de Educaci\u00f3n Superior.<\/p><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns alignwide stk-block-columns stk-block stk-5374452\" id=\"comparte-esta-microcredencial\" data-block-id=\"5374452\"><style>.stk-5374452 {padding-right:12% !important;padding-left:12% !important;margin-bottom:50px !important;}.stk-5374452-column{--stk-column-gap:var(--stk--preset--spacing--60, 2.25rem) !important;}@media screen and (max-width: 767px){.stk-5374452 {padding-right:5% !important;padding-left:5% !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-5374452-column alignwide\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-335769f\" data-v=\"4\" data-block-id=\"335769f\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-335769f-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-335769f-inner-blocks\">\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-831cb3a\" id=\"equipo-docente\" data-block-id=\"831cb3a\"><style>.stk-831cb3a .stk-block-heading__text{color:#fd6921 !important;}<\/style><h2 class=\"stk-block-heading__text has-text-color\">Equipo docente<\/h2><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns alignwide stk-block-columns stk-block stk-eb91c80\" data-block-id=\"eb91c80\"><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-eb91c80-column alignwide\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-0fb7fe0\" data-v=\"4\" data-block-id=\"0fb7fe0\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-0fb7fe0-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-0fb7fe0-inner-blocks\">\n<div class=\"wp-block-stackable-columns stk-block-columns stk-block stk-e5f65e9\" data-block-id=\"e5f65e9\"><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-e5f65e9-column\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-faac7b5\" data-v=\"4\" data-block-id=\"faac7b5\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-faac7b5-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-faac7b5-inner-blocks\">\n<div class=\"wp-block-stackable-image stk-block-image stk-block stk-315eeab\" data-block-id=\"315eeab\"><figure><span class=\"stk-img-wrapper stk-image--shape-stretch\"><img loading=\"lazy\" decoding=\"async\" class=\"stk-img wp-image-4250\" src=\"https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2026\/04\/sandra_devora-2.png\" width=\"500\" height=\"500\" srcset=\"https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2026\/04\/sandra_devora-2.png 500w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2026\/04\/sandra_devora-2-300x300.png 300w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2026\/04\/sandra_devora-2-150x150.png 150w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2026\/04\/sandra_devora-2-12x12.png 12w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2026\/04\/sandra_devora-2-200x200.png 200w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2026\/04\/sandra_devora-2-375x375.png 375w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2026\/04\/sandra_devora-2-50x50.png 50w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/span><\/figure><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-1cd0453\" data-v=\"4\" data-block-id=\"1cd0453\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-1cd0453-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-1cd0453-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-6d0434b\" data-block-id=\"6d0434b\"><style>.stk-6d0434b {border-color:#dfdad1 !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;padding-top:12px !important;padding-right:12px !important;padding-bottom:12px !important;padding-left:12px !important;margin-bottom:12px !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-1ab66f1\" id=\"sandra-devora-gutierrez-br\" data-block-id=\"1ab66f1\"><style>.stk-1ab66f1 .stk-block-heading__text{color:#000000 !important;font-weight:600 !important;font-family:\"Montserrat\", Sans-serif !important;}@media screen and (max-width: 767px){.stk-1ab66f1 .stk-block-heading__text{font-size:15px !important;}}<\/style><h4 class=\"stk-block-heading__text has-text-color\">Sandra D\u00e9vora Guti\u00e9rrez&nbsp;<br><\/h4><\/div>\n\n\n\n<div class=\"wp-block-stackable-icon stk-block-icon has-text-align-left stk-block stk-f74aa05\" data-block-id=\"f74aa05\"><style>@media screen and (max-width: 767px){.stk-f74aa05 .stk--svg-wrapper .stk--inner-svg svg:last-child{height:20px !important;width:20px !important;}}<\/style><a class=\"stk-link\" href=\"https:\/\/portalciencia.ull.es\/investigadores\/82029\/detalle\" target=\"_blank\" rel=\"noopener\"><span class=\"stk--svg-wrapper\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-f74aa05\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-f-74-aa-05-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-f-74-aa-05-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg class=\"ugb-custom-icon\" viewBox=\"0 0 64 64\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" width=\"32\" height=\"32\">\n  <circle cx=\"32\" cy=\"32\" r=\"32\" fill=\"#FD6921\" \/>\n  <path d=\"M26 22h16v16h-6v-7.17L24.83 42 22 39.17 33.17 28H26v-6z\" fill=\"#FFFFFF\" \/>\n<\/svg><\/div><\/span><\/a><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-f6ae997\" data-block-id=\"f6ae997\"><p class=\"stk-block-text__text\">Profesora del \u00e1rea de Farmacolog\u00eda de la Facultad de Farmacia. Su investigaci\u00f3n se centra en la Atenci\u00f3n Farmac\u00e9utica y el estudio del consumo de medicamentos.<\/p><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-1242881\" data-v=\"4\" data-block-id=\"1242881\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-1242881-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-1242881-inner-blocks\">\n<div class=\"wp-block-stackable-image stk-block-image stk-block stk-19a19c1\" data-block-id=\"19a19c1\"><figure><span class=\"stk-img-wrapper stk-image--shape-stretch\"><img loading=\"lazy\" decoding=\"async\" class=\"stk-img wp-image-4252\" src=\"https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2026\/04\/antonio_c-1.png\" width=\"500\" height=\"500\" srcset=\"https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2026\/04\/antonio_c-1.png 500w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2026\/04\/antonio_c-1-300x300.png 300w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2026\/04\/antonio_c-1-150x150.png 150w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2026\/04\/antonio_c-1-12x12.png 12w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2026\/04\/antonio_c-1-200x200.png 200w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2026\/04\/antonio_c-1-375x375.png 375w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2026\/04\/antonio_c-1-50x50.png 50w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/span><\/figure><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-335053d\" data-v=\"4\" data-block-id=\"335053d\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-335053d-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-335053d-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-bde1d42\" data-block-id=\"bde1d42\"><style>.stk-bde1d42 {border-color:#dfdad1 !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;padding-top:12px !important;padding-right:12px !important;padding-bottom:12px !important;padding-left:12px !important;margin-bottom:12px !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-f6a0560\" id=\"antonio-villafaina-barroso\" data-block-id=\"f6a0560\"><style>.stk-f6a0560 .stk-block-heading__text{color:#000000 !important;font-weight:600 !important;font-family:\"Montserrat\", Sans-serif !important;}@media screen and (max-width: 767px){.stk-f6a0560 .stk-block-heading__text{font-size:15px !important;}}<\/style><h4 class=\"stk-block-heading__text has-text-color\">Antonio Villafaina Barroso<\/h4><\/div>\n\n\n\n<div class=\"wp-block-stackable-icon stk-block-icon has-text-align-left stk-block stk-443ba7c\" data-block-id=\"443ba7c\"><style>@media screen and (max-width: 767px){.stk-443ba7c .stk--svg-wrapper .stk--inner-svg svg:last-child{height:20px !important;width:20px !important;}}<\/style><span class=\"stk--svg-wrapper\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-443ba7c\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-443-ba-7-c-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-443-ba-7-c-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg class=\"ugb-custom-icon\" viewBox=\"0 0 64 64\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" width=\"32\" height=\"32\">\n  <circle cx=\"32\" cy=\"32\" r=\"32\" fill=\"#FD6921\" \/>\n  <path d=\"M26 22h16v16h-6v-7.17L24.83 42 22 39.17 33.17 28H26v-6z\" fill=\"#FFFFFF\" \/>\n<\/svg><\/div><\/span><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-8522049\" data-block-id=\"8522049\"><p class=\"stk-block-text__text\">Dr. en Farmacia, Farmac\u00e9utico comunitario y presidente de F\u00dcNDEC.<br><\/p><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns stk-block-columns stk-block stk-84ddbe3\" data-block-id=\"84ddbe3\"><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-84ddbe3-column\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-969ce3f\" data-v=\"4\" data-block-id=\"969ce3f\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-969ce3f-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-969ce3f-inner-blocks\">\n<div class=\"wp-block-stackable-image stk-block-image stk-block stk-bf7335f\" data-block-id=\"bf7335f\"><figure><span class=\"stk-img-wrapper stk-image--shape-stretch\"><img loading=\"lazy\" decoding=\"async\" class=\"stk-img wp-image-4253\" src=\"https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2026\/04\/susana_c-1-1.png\" width=\"500\" height=\"500\" srcset=\"https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2026\/04\/susana_c-1-1.png 500w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2026\/04\/susana_c-1-1-300x300.png 300w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2026\/04\/susana_c-1-1-150x150.png 150w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2026\/04\/susana_c-1-1-12x12.png 12w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2026\/04\/susana_c-1-1-200x200.png 200w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2026\/04\/susana_c-1-1-375x375.png 375w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2026\/04\/susana_c-1-1-50x50.png 50w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/span><\/figure><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-4491353\" data-v=\"4\" data-block-id=\"4491353\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-4491353-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-4491353-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-871515a\" data-block-id=\"871515a\"><style>.stk-871515a {border-color:#dfdad1 !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;padding-top:12px !important;padding-right:12px !important;padding-bottom:12px !important;padding-left:12px !important;margin-bottom:12px !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-ca52414\" id=\"susana-perez-garcia\" data-block-id=\"ca52414\"><style>.stk-ca52414 .stk-block-heading__text{color:#000000 !important;font-weight:600 !important;font-family:\"Montserrat\", Sans-serif !important;}@media screen and (max-width: 767px){.stk-ca52414 .stk-block-heading__text{font-size:15px !important;}}<\/style><h4 class=\"stk-block-heading__text has-text-color\">Susana P\u00e9rez Garc\u00eda<\/h4><\/div>\n\n\n\n<div class=\"wp-block-stackable-icon stk-block-icon has-text-align-left stk-block stk-bfbca83\" data-block-id=\"bfbca83\"><style>@media screen and (max-width: 767px){.stk-bfbca83 .stk--svg-wrapper .stk--inner-svg svg:last-child{height:20px !important;width:20px !important;}}<\/style><span class=\"stk--svg-wrapper\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-bfbca83\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-bfbca-83-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-bfbca-83-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg class=\"ugb-custom-icon\" viewBox=\"0 0 64 64\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" width=\"32\" height=\"32\">\n  <circle cx=\"32\" cy=\"32\" r=\"32\" fill=\"#FD6921\" \/>\n  <path d=\"M26 22h16v16h-6v-7.17L24.83 42 22 39.17 33.17 28H26v-6z\" fill=\"#FFFFFF\" \/>\n<\/svg><\/div><\/span><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-9fb6e61\" data-block-id=\"9fb6e61\"><p class=\"stk-block-text__text\">Dra. en Farmacolog\u00eda por la Universidad de Valladolid y Licenciada en Farmacia por la Universidad de Salamanca. Farmac\u00e9utica comunitaria con experiencia investigadora y publicaciones cient\u00edficas, miembro activo de sociedades cient\u00edficas del \u00e1mbito sanitario y profesional.<\/p><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-6f7e13b\" data-v=\"4\" data-block-id=\"6f7e13b\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-6f7e13b-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-6f7e13b-inner-blocks\">\n<div class=\"wp-block-stackable-image stk-block-image stk-block stk-e5a873b\" data-block-id=\"e5a873b\"><figure><span class=\"stk-img-wrapper stk-image--shape-stretch\"><img loading=\"lazy\" decoding=\"async\" class=\"stk-img wp-image-1521\" src=\"https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Introduccion_al_Machine_Learning_Recursos_Sin_foto.png\" width=\"532\" height=\"532\" srcset=\"https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Introduccion_al_Machine_Learning_Recursos_Sin_foto.png 532w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Introduccion_al_Machine_Learning_Recursos_Sin_foto-300x300.png 300w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Introduccion_al_Machine_Learning_Recursos_Sin_foto-150x150.png 150w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Introduccion_al_Machine_Learning_Recursos_Sin_foto-12x12.png 12w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Introduccion_al_Machine_Learning_Recursos_Sin_foto-200x200.png 200w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Introduccion_al_Machine_Learning_Recursos_Sin_foto-375x375.png 375w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Introduccion_al_Machine_Learning_Recursos_Sin_foto-50x50.png 50w\" sizes=\"auto, (max-width: 532px) 100vw, 532px\" \/><\/span><\/figure><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-24b48ce\" data-v=\"4\" data-block-id=\"24b48ce\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-24b48ce-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-24b48ce-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-61a228a\" data-block-id=\"61a228a\"><style>.stk-61a228a {border-color:#dfdad1 !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;padding-top:12px !important;padding-right:12px !important;padding-bottom:12px !important;padding-left:12px !important;margin-bottom:12px !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-fb5beb8\" id=\"mikel-baza-bueno\" data-block-id=\"fb5beb8\"><style>.stk-fb5beb8 .stk-block-heading__text{color:#000000 !important;font-weight:600 !important;font-family:\"Montserrat\", Sans-serif !important;}@media screen and (max-width: 767px){.stk-fb5beb8 .stk-block-heading__text{font-size:15px !important;}}<\/style><h4 class=\"stk-block-heading__text has-text-color\">Mikel Baza Bueno<\/h4><\/div>\n\n\n\n<div class=\"wp-block-stackable-icon stk-block-icon has-text-align-left stk-block stk-f454582\" data-block-id=\"f454582\"><style>@media screen and (max-width: 767px){.stk-f454582 .stk--svg-wrapper .stk--inner-svg svg:last-child{height:20px !important;width:20px !important;}}<\/style><span class=\"stk--svg-wrapper\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-f454582\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-f-454582-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-f-454582-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg class=\"ugb-custom-icon\" viewBox=\"0 0 64 64\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" width=\"32\" height=\"32\">\n  <circle cx=\"32\" cy=\"32\" r=\"32\" fill=\"#FD6921\" \/>\n  <path d=\"M26 22h16v16h-6v-7.17L24.83 42 22 39.17 33.17 28H26v-6z\" fill=\"#FFFFFF\" \/>\n<\/svg><\/div><\/span><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-042557e\" data-block-id=\"042557e\"><p class=\"stk-block-text__text\">M\u00e9dico de familias y comunidades en Zeberio (Bizkaia) y coordinador de la Unidad de Atenci\u00f3n Primaria de Arrigorriaga. Tengo un especial inter\u00e9s en la atenci\u00f3n centrada en las personas, la prescripci\u00f3n prudente y la orientaci\u00f3n comunitaria de los servicios sanitarios. Colaboro en proyectos comunitarios e innovadores de salud desde F\u00dcNDEC, Osatzen y el grupo de investigaci\u00f3n OPIK de la UPV-EHU.<\/p><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns stk-block-columns stk-block stk-16bdb48\" data-block-id=\"16bdb48\"><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-16bdb48-column\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-ba10787\" data-v=\"4\" data-block-id=\"ba10787\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-ba10787-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-ba10787-inner-blocks\">\n<div class=\"wp-block-stackable-image stk-block-image stk-block stk-84ec97f\" data-block-id=\"84ec97f\"><figure><span class=\"stk-img-wrapper stk-image--shape-stretch\"><img loading=\"lazy\" decoding=\"async\" class=\"stk-img wp-image-1521\" src=\"https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Introduccion_al_Machine_Learning_Recursos_Sin_foto.png\" width=\"532\" height=\"532\" srcset=\"https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Introduccion_al_Machine_Learning_Recursos_Sin_foto.png 532w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Introduccion_al_Machine_Learning_Recursos_Sin_foto-300x300.png 300w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Introduccion_al_Machine_Learning_Recursos_Sin_foto-150x150.png 150w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Introduccion_al_Machine_Learning_Recursos_Sin_foto-12x12.png 12w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Introduccion_al_Machine_Learning_Recursos_Sin_foto-200x200.png 200w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Introduccion_al_Machine_Learning_Recursos_Sin_foto-375x375.png 375w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Introduccion_al_Machine_Learning_Recursos_Sin_foto-50x50.png 50w\" sizes=\"auto, (max-width: 532px) 100vw, 532px\" \/><\/span><\/figure><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-c72fdd9\" data-v=\"4\" data-block-id=\"c72fdd9\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-c72fdd9-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-c72fdd9-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-af13799\" data-block-id=\"af13799\"><style>.stk-af13799 {border-color:#dfdad1 !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;padding-top:12px !important;padding-right:12px !important;padding-bottom:12px !important;padding-left:12px !important;margin-bottom:12px !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-87d6925\" id=\"mba-bee-nchama\" data-block-id=\"87d6925\"><style>.stk-87d6925 .stk-block-heading__text{color:#000000 !important;font-weight:600 !important;font-family:\"Montserrat\", Sans-serif !important;}@media screen and (max-width: 767px){.stk-87d6925 .stk-block-heading__text{font-size:15px !important;}}<\/style><h4 class=\"stk-block-heading__text has-text-color\">Mba Bee Nchama<\/h4><\/div>\n\n\n\n<div class=\"wp-block-stackable-icon stk-block-icon has-text-align-left stk-block stk-3559c09\" data-block-id=\"3559c09\"><style>@media screen and (max-width: 767px){.stk-3559c09 .stk--svg-wrapper .stk--inner-svg svg:last-child{height:20px !important;width:20px !important;}}<\/style><span class=\"stk--svg-wrapper\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-3559c09\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-3559-c-09-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-3559-c-09-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg class=\"ugb-custom-icon\" viewBox=\"0 0 64 64\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" width=\"32\" height=\"32\">\n  <circle cx=\"32\" cy=\"32\" r=\"32\" fill=\"#FD6921\" \/>\n  <path d=\"M26 22h16v16h-6v-7.17L24.83 42 22 39.17 33.17 28H26v-6z\" fill=\"#FFFFFF\" \/>\n<\/svg><\/div><\/span><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-c88b9dd\" data-block-id=\"c88b9dd\"><p class=\"stk-block-text__text\"><\/p><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-d8039a8\" data-v=\"4\" data-block-id=\"d8039a8\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-d8039a8-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-d8039a8-inner-blocks\">\n<div class=\"wp-block-stackable-image stk-block-image stk-block stk-38797ad\" data-block-id=\"38797ad\"><figure><span class=\"stk-img-wrapper stk-image--shape-stretch\"><img loading=\"lazy\" decoding=\"async\" class=\"stk-img wp-image-4251\" src=\"https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2026\/04\/laura_delgado-1.jpg\" width=\"1086\" height=\"1086\" srcset=\"https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2026\/04\/laura_delgado-1.jpg 1086w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2026\/04\/laura_delgado-1-300x300.jpg 300w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2026\/04\/laura_delgado-1-1024x1024.jpg 1024w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2026\/04\/laura_delgado-1-150x150.jpg 150w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2026\/04\/laura_delgado-1-768x768.jpg 768w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2026\/04\/laura_delgado-1-12x12.jpg 12w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2026\/04\/laura_delgado-1-200x200.jpg 200w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2026\/04\/laura_delgado-1-600x600.jpg 600w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2026\/04\/laura_delgado-1-375x375.jpg 375w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2026\/04\/laura_delgado-1-750x750.jpg 750w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2026\/04\/laura_delgado-1-50x50.jpg 50w\" sizes=\"auto, (max-width: 1086px) 100vw, 1086px\" \/><\/span><\/figure><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-dd9ca9e\" data-v=\"4\" data-block-id=\"dd9ca9e\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-dd9ca9e-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-dd9ca9e-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-85315fc\" data-block-id=\"85315fc\"><style>.stk-85315fc {border-color:#dfdad1 !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;padding-top:12px !important;padding-right:12px !important;padding-bottom:12px !important;padding-left:12px !important;margin-bottom:12px !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-6422370\" id=\"laura-delgado-martin\" data-block-id=\"6422370\"><style>.stk-6422370 .stk-block-heading__text{color:#000000 !important;font-weight:600 !important;font-family:\"Montserrat\", Sans-serif !important;}@media screen and (max-width: 767px){.stk-6422370 .stk-block-heading__text{font-size:15px !important;}}<\/style><h4 class=\"stk-block-heading__text has-text-color\">Laura Delgado Mart\u00edn<\/h4><\/div>\n\n\n\n<div class=\"wp-block-stackable-icon stk-block-icon has-text-align-left stk-block stk-590e635\" data-block-id=\"590e635\"><style>@media screen and (max-width: 767px){.stk-590e635 .stk--svg-wrapper .stk--inner-svg svg:last-child{height:20px !important;width:20px !important;}}<\/style><span class=\"stk--svg-wrapper\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-590e635\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-590-e-635-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-590-e-635-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg class=\"ugb-custom-icon\" viewBox=\"0 0 64 64\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" width=\"32\" height=\"32\">\n  <circle cx=\"32\" cy=\"32\" r=\"32\" fill=\"#FD6921\" \/>\n  <path d=\"M26 22h16v16h-6v-7.17L24.83 42 22 39.17 33.17 28H26v-6z\" fill=\"#FFFFFF\" \/>\n<\/svg><\/div><\/span><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-b1176a3\" data-block-id=\"b1176a3\"><p class=\"stk-block-text__text\">Soy Laura Delgado Mart\u00edn. M\u00e9dica de Familia y Comunitaria trabajando en la Gerencia de Atenci\u00f3n Primaria de Tenerife.<\/p><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns stk-block-columns stk-block stk-86543f5\" data-block-id=\"86543f5\"><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-86543f5-column\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-505334f\" data-v=\"4\" data-block-id=\"505334f\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-505334f-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-505334f-inner-blocks\">\n<div class=\"wp-block-stackable-image stk-block-image stk-block stk-e051084\" data-block-id=\"e051084\"><figure><span class=\"stk-img-wrapper stk-image--shape-stretch\"><img loading=\"lazy\" decoding=\"async\" class=\"stk-img wp-image-1521\" src=\"https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Introduccion_al_Machine_Learning_Recursos_Sin_foto.png\" width=\"532\" height=\"532\" srcset=\"https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Introduccion_al_Machine_Learning_Recursos_Sin_foto.png 532w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Introduccion_al_Machine_Learning_Recursos_Sin_foto-300x300.png 300w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Introduccion_al_Machine_Learning_Recursos_Sin_foto-150x150.png 150w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Introduccion_al_Machine_Learning_Recursos_Sin_foto-12x12.png 12w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Introduccion_al_Machine_Learning_Recursos_Sin_foto-200x200.png 200w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Introduccion_al_Machine_Learning_Recursos_Sin_foto-375x375.png 375w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Introduccion_al_Machine_Learning_Recursos_Sin_foto-50x50.png 50w\" sizes=\"auto, (max-width: 532px) 100vw, 532px\" \/><\/span><\/figure><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-98acbf0\" data-v=\"4\" data-block-id=\"98acbf0\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-98acbf0-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-98acbf0-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-920ef5f\" data-block-id=\"920ef5f\"><style>.stk-920ef5f {border-color:#dfdad1 !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;padding-top:12px !important;padding-right:12px !important;padding-bottom:12px !important;padding-left:12px !important;margin-bottom:12px !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-695b0b3\" id=\"leonor-rodriguez-delgado\" data-block-id=\"695b0b3\"><style>.stk-695b0b3 .stk-block-heading__text{color:#000000 !important;font-weight:600 !important;font-family:\"Montserrat\", Sans-serif !important;}@media screen and (max-width: 767px){.stk-695b0b3 .stk-block-heading__text{font-size:15px !important;}}<\/style><h4 class=\"stk-block-heading__text has-text-color\">Leonor Rodr\u00edguez Delgado<\/h4><\/div>\n\n\n\n<div class=\"wp-block-stackable-icon stk-block-icon has-text-align-left stk-block stk-ccb2509\" data-block-id=\"ccb2509\"><style>@media screen and (max-width: 767px){.stk-ccb2509 .stk--svg-wrapper .stk--inner-svg svg:last-child{height:20px !important;width:20px !important;}}<\/style><span class=\"stk--svg-wrapper\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-ccb2509\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-ccb-2509-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-ccb-2509-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg class=\"ugb-custom-icon\" viewBox=\"0 0 64 64\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" width=\"32\" height=\"32\">\n  <circle cx=\"32\" cy=\"32\" r=\"32\" fill=\"#FD6921\" \/>\n  <path d=\"M26 22h16v16h-6v-7.17L24.83 42 22 39.17 33.17 28H26v-6z\" fill=\"#FFFFFF\" \/>\n<\/svg><\/div><\/span><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-60743b4\" data-block-id=\"60743b4\"><p class=\"stk-block-text__text\">Farmac\u00e9utica licenciada con m\u00e1s de 20 a\u00f1os de experiencia en farmacia comunitaria, especializada en Atenci\u00f3n Farmac\u00e9utica Integral y seguimiento farmacoterap\u00e9utico de pacientes cr\u00f3nicos y polimedicados. Amplia formaci\u00f3n acreditada en servicios profesionales asistenciales, seguridad del paciente, indicaci\u00f3n farmac\u00e9utica y prevenci\u00f3n en salud. Cuento adem\u00e1s con experiencia en docencia y educaci\u00f3n sanitaria, tanto en formaci\u00f3n reglada como en actividades divulgativas dirigidas a poblaci\u00f3n general y personas mayores. Profesional con marcada vocaci\u00f3n asistencial, orientada a la calidad y a la atenci\u00f3n centrada en el paciente.<\/p><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-9eb5490\" data-v=\"4\" data-block-id=\"9eb5490\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-9eb5490-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-9eb5490-inner-blocks\">\n<div class=\"wp-block-stackable-image stk-block-image stk-block stk-f747c91\" data-block-id=\"f747c91\"><figure><span class=\"stk-img-wrapper stk-image--shape-stretch\"><img loading=\"lazy\" decoding=\"async\" class=\"stk-img wp-image-1521\" src=\"https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Introduccion_al_Machine_Learning_Recursos_Sin_foto.png\" width=\"532\" height=\"532\" srcset=\"https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Introduccion_al_Machine_Learning_Recursos_Sin_foto.png 532w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Introduccion_al_Machine_Learning_Recursos_Sin_foto-300x300.png 300w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Introduccion_al_Machine_Learning_Recursos_Sin_foto-150x150.png 150w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Introduccion_al_Machine_Learning_Recursos_Sin_foto-12x12.png 12w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Introduccion_al_Machine_Learning_Recursos_Sin_foto-200x200.png 200w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Introduccion_al_Machine_Learning_Recursos_Sin_foto-375x375.png 375w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Introduccion_al_Machine_Learning_Recursos_Sin_foto-50x50.png 50w\" sizes=\"auto, (max-width: 532px) 100vw, 532px\" \/><\/span><\/figure><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-7b23545\" data-v=\"4\" data-block-id=\"7b23545\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-7b23545-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-7b23545-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-0a09caf\" data-block-id=\"0a09caf\"><style>.stk-0a09caf {border-color:#dfdad1 !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;padding-top:12px !important;padding-right:12px !important;padding-bottom:12px !important;padding-left:12px !important;margin-bottom:12px !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-1c86b2d\" id=\"barbara-nayelis-hernandez-calero\" data-block-id=\"1c86b2d\"><style>.stk-1c86b2d .stk-block-heading__text{color:#000000 !important;font-weight:600 !important;font-family:\"Montserrat\", Sans-serif !important;}@media screen and (max-width: 767px){.stk-1c86b2d .stk-block-heading__text{font-size:15px !important;}}<\/style><h4 class=\"stk-block-heading__text has-text-color\">B\u00e1rbara Nayelis Hern\u00e1ndez Calero<\/h4><\/div>\n\n\n\n<div class=\"wp-block-stackable-icon stk-block-icon has-text-align-left stk-block stk-e3f2f86\" data-block-id=\"e3f2f86\"><style>@media screen and (max-width: 767px){.stk-e3f2f86 .stk--svg-wrapper .stk--inner-svg svg:last-child{height:20px !important;width:20px !important;}}<\/style><span class=\"stk--svg-wrapper\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-e3f2f86\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-e-3-f-2-f-86-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-e-3-f-2-f-86-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg class=\"ugb-custom-icon\" viewBox=\"0 0 64 64\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" width=\"32\" height=\"32\">\n  <circle cx=\"32\" cy=\"32\" r=\"32\" fill=\"#FD6921\" \/>\n  <path d=\"M26 22h16v16h-6v-7.17L24.83 42 22 39.17 33.17 28H26v-6z\" fill=\"#FFFFFF\" \/>\n<\/svg><\/div><\/span><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-f2103cc\" data-block-id=\"f2103cc\"><p class=\"stk-block-text__text\">Graduada en Farmacia, con un profundo inter\u00e9s por el \u00e1mbito sanitario, motivada por comprender en profundidad los tratamientos y su impacto en la calidad de vida de los pacientes, buscando siempre, dentro de mis posibilidades, contribuir de manera positiva a su bienestar. Esta inquietud me impulsa a seguir form\u00e1ndome y actualiz\u00e1ndome de manera continua<\/p><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns stk-block-columns stk-block stk-3230948\" data-block-id=\"3230948\"><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-3230948-column\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-c1e26ca\" data-v=\"4\" data-block-id=\"c1e26ca\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-c1e26ca-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-c1e26ca-inner-blocks\">\n<div class=\"wp-block-stackable-image stk-block-image stk-block stk-9d692d5\" data-block-id=\"9d692d5\"><figure><span class=\"stk-img-wrapper stk-image--shape-stretch\"><img loading=\"lazy\" decoding=\"async\" class=\"stk-img wp-image-1521\" src=\"https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Introduccion_al_Machine_Learning_Recursos_Sin_foto.png\" width=\"532\" height=\"532\" srcset=\"https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Introduccion_al_Machine_Learning_Recursos_Sin_foto.png 532w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Introduccion_al_Machine_Learning_Recursos_Sin_foto-300x300.png 300w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Introduccion_al_Machine_Learning_Recursos_Sin_foto-150x150.png 150w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Introduccion_al_Machine_Learning_Recursos_Sin_foto-12x12.png 12w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Introduccion_al_Machine_Learning_Recursos_Sin_foto-200x200.png 200w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Introduccion_al_Machine_Learning_Recursos_Sin_foto-375x375.png 375w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Introduccion_al_Machine_Learning_Recursos_Sin_foto-50x50.png 50w\" sizes=\"auto, (max-width: 532px) 100vw, 532px\" \/><\/span><\/figure><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-34cf31a\" data-v=\"4\" data-block-id=\"34cf31a\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-34cf31a-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-34cf31a-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-08af096\" data-block-id=\"08af096\"><style>.stk-08af096 {border-color:#dfdad1 !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;padding-top:12px !important;padding-right:12px !important;padding-bottom:12px !important;padding-left:12px !important;margin-bottom:12px !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-9a35e75\" id=\"lincoln-gerardo-gonzalez-gonzalez\" data-block-id=\"9a35e75\"><style>.stk-9a35e75 .stk-block-heading__text{color:#000000 !important;font-weight:600 !important;font-family:\"Montserrat\", Sans-serif !important;}@media screen and (max-width: 767px){.stk-9a35e75 .stk-block-heading__text{font-size:15px !important;}}<\/style><h4 class=\"stk-block-heading__text has-text-color\">Lincoln Gerardo Gonz\u00e1lez Gonz\u00e1lez<\/h4><\/div>\n\n\n\n<div class=\"wp-block-stackable-icon stk-block-icon has-text-align-left stk-block stk-5442a73\" data-block-id=\"5442a73\"><style>@media screen and (max-width: 767px){.stk-5442a73 .stk--svg-wrapper .stk--inner-svg svg:last-child{height:20px !important;width:20px !important;}}<\/style><span class=\"stk--svg-wrapper\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-5442a73\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-5442-a-73-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-5442-a-73-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg class=\"ugb-custom-icon\" viewBox=\"0 0 64 64\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" width=\"32\" height=\"32\">\n  <circle cx=\"32\" cy=\"32\" r=\"32\" fill=\"#FD6921\" \/>\n  <path d=\"M26 22h16v16h-6v-7.17L24.83 42 22 39.17 33.17 28H26v-6z\" fill=\"#FFFFFF\" \/>\n<\/svg><\/div><\/span><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-60393f7\" data-block-id=\"60393f7\"><p class=\"stk-block-text__text\">Mi nombre es Lincoln. Nacido en La Habana y criado en Tenerife. Soy farmac\u00e9utico y nutricionista. Apasionado por el deporte, la cocina y el saber.<\/p><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-9772f50\" data-v=\"4\" data-block-id=\"9772f50\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-9772f50-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-9772f50-inner-blocks\">\n<div class=\"wp-block-stackable-image stk-block-image stk-block stk-4a461ce\" data-block-id=\"4a461ce\"><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-aa8a859\" data-v=\"4\" data-block-id=\"aa8a859\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-aa8a859-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-aa8a859-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-de4d6b5\" data-block-id=\"de4d6b5\"><style>.stk-de4d6b5 {border-color:#dfdad1 !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;padding-top:12px !important;padding-right:12px !important;padding-bottom:12px !important;padding-left:12px !important;margin-bottom:12px !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-e2c0865\" data-block-id=\"e2c0865\"><style>.stk-e2c0865 .stk-block-heading__text{color:#000000 !important;font-weight:600 !important;font-family:\"Montserrat\", Sans-serif !important;}@media screen and (max-width: 767px){.stk-e2c0865 .stk-block-heading__text{font-size:15px !important;}}<\/style><h4 class=\"stk-block-heading__text has-text-color\"><\/h4><\/div>\n\n\n\n<div class=\"wp-block-stackable-icon stk-block-icon has-text-align-left stk--hide-desktop stk--hide-tablet stk--hide-mobile stk-block stk-70382ce\" data-block-id=\"70382ce\"><style>@media screen and (max-width: 767px){.stk-70382ce .stk--svg-wrapper .stk--inner-svg svg:last-child{height:20px !important;width:20px !important;}}<\/style><span class=\"stk--svg-wrapper\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-70382ce\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-70382-ce-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-70382-ce-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg class=\"ugb-custom-icon\" viewBox=\"0 0 64 64\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" width=\"32\" height=\"32\">\n  <circle cx=\"32\" cy=\"32\" r=\"32\" fill=\"#FD6921\" \/>\n  <path d=\"M26 22h16v16h-6v-7.17L24.83 42 22 39.17 33.17 28H26v-6z\" fill=\"#FFFFFF\" \/>\n<\/svg><\/div><\/span><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-6c468b9\" data-block-id=\"6c468b9\"><p class=\"stk-block-text__text\"><\/p><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns alignwide stk-block-columns stk-block stk-1f562b1\" id=\"comparte-esta-microcredencial\" data-block-id=\"1f562b1\"><style>.stk-1f562b1 {padding-right:12% !important;padding-left:12% !important;margin-bottom:50px !important;}.stk-1f562b1-column{--stk-column-gap:var(--stk--preset--spacing--60, 2.25rem) !important;}@media screen and (max-width: 767px){.stk-1f562b1 {padding-right:5% !important;padding-left:5% !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-1f562b1-column alignwide\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-eb56efe\" data-v=\"4\" data-block-id=\"eb56efe\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-eb56efe-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-eb56efe-inner-blocks\">\n<div class=\"wp-block-stackable-image stk-block-image stk-block stk-d8dba7b\" data-block-id=\"d8dba7b\"><style>.stk-d8dba7b .stk-img-wrapper{width:100% !important;}<\/style><figure><span class=\"stk-img-wrapper stk-image--shape-stretch\"><img loading=\"lazy\" decoding=\"async\" class=\"stk-img wp-image-1788\" src=\"https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Logos_UE_microcredenciales___ULL_color.png\" width=\"2560\" height=\"162\" srcset=\"https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Logos_UE_microcredenciales___ULL_color.png 2560w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Logos_UE_microcredenciales___ULL_color-300x19.png 300w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Logos_UE_microcredenciales___ULL_color-1024x65.png 1024w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Logos_UE_microcredenciales___ULL_color-768x49.png 768w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Logos_UE_microcredenciales___ULL_color-1536x97.png 1536w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Logos_UE_microcredenciales___ULL_color-2048x130.png 2048w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Logos_UE_microcredenciales___ULL_color-18x1.png 18w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Logos_UE_microcredenciales___ULL_color-200x13.png 200w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Logos_UE_microcredenciales___ULL_color-375x24.png 375w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Logos_UE_microcredenciales___ULL_color-750x47.png 750w, https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Logos_UE_microcredenciales___ULL_color-1140x72.png 1140w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/span><\/figure><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns alignwide stk-block-columns stk-block stk-c7ca28a\" id=\"comparte-esta-microcredencial\" data-block-id=\"c7ca28a\"><style>.stk-c7ca28a {padding-right:12% !important;padding-left:12% !important;}.stk-c7ca28a-column{--stk-column-gap:var(--stk--preset--spacing--60, 2.25rem) !important;}@media screen and (max-width: 767px){.stk-c7ca28a {padding-right:5% !important;padding-left:5% !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-c7ca28a-column alignwide\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-64303b6\" data-v=\"4\" data-block-id=\"64303b6\"><style>.stk-64303b6 {align-self:center !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-64303b6-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-64303b6-inner-blocks\">\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-f56551f\" id=\"comparte-esta-microcredencial\" data-block-id=\"f56551f\"><style>.stk-f56551f .stk-block-heading__text{color:#0f0e17 !important;}<\/style><h2 class=\"stk-block-heading__text has-text-color\">Comparte esta microcredencial<\/h2><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-d382740\" data-v=\"4\" data-block-id=\"d382740\"><style>.stk-d382740 {align-self:center !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-d382740-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-d382740-inner-blocks\">\n<div class=\"row\">\n    <div class=\"col-md-5 col-12 ms-auto text-end\"> <!-- Alineado a la derecha, ocupa todo en m\u00f3vil -->\n        <!-- Botones de compartir -->\n        <a href=\"#\" onclick=\"shareFacebook()\" title=\"Compartir en Facebook\" class=\"share-btn\" target=\"_blank\" rel=\"noopener\">\n            <i class=\"fab fa-facebook-f\"><\/i>\n        <\/a>\n        <a href=\"#\" onclick=\"shareLinkedIn()\" title=\"Compartir en LinkedIn\" class=\"share-btn\" target=\"_blank\" rel=\"noopener\">\n            <i class=\"fab fa-linkedin-in\"><\/i>\n        <\/a>\n        <a href=\"#\" onclick=\"shareTelegram()\" title=\"Compartir en Telegram\" class=\"share-btn\" target=\"_blank\" rel=\"noopener\">\n            <i class=\"fab fa-telegram-plane\"><\/i>\n        <\/a>\n        <a href=\"#\" onclick=\"shareWhatsApp()\" title=\"Compartir en WhatsApp\" class=\"share-btn\" target=\"_blank\" rel=\"noopener\">\n            <i class=\"fab fa-whatsapp\"><\/i>\n        <\/a>\n<!-- Email: ahora como enlace normal (sin window.open ni onclick) -->\n        <a href=\"#\" onclick=\"shareByEmail(); return false;\" title=\"Compartir por email\" class=\"share-btn\" target=\"_blank\" rel=\"noopener\">\n            <i class=\"fas fa-envelope\"><\/i>\n        <\/a>\n    <\/div>\n<\/div>\n\n<style>\n    .share-btn {\n        display: inline-flex;\n        align-items: center;\n        justify-content: center;\n        width: 40px;\n        height: 40px;\n        color: white;\n        padding-top: 5px !important;\n        padding-right: 5px !important;\n        padding-bottom: 5px !important;\n        padding-left: 5px !important;\n        background: #fd6921 !important;\n        border-top-left-radius: 5px !important;\n        border-top-right-radius: 5px !important;\n        border-bottom-right-radius: 5px !important;\n        border-bottom-left-radius: 5px !important;\n    }\n\n    .share-btn:hover {\n        background-color: #fd6921;       \/* naranja un poco m\u00e1s oscuro al pasar el rat\u00f3n *\/\n        transform: translateY(-2px);\n        color: white;\n        text-decoration: none;\n        box-shadow: 0 4px 8px rgba(0,0,0,0.15);\n    }\n\n    .share-btn:active {\n        background-color: #fd6921;       \/* naranja un poco m\u00e1s oscuro al pasar el rat\u00f3n *\/\n        transform: translateY(-2px);\n        color: white;\n        text-decoration: none;\n        box-shadow: 0 4px 8px rgba(0,0,0,0.15);\n    }\n\n    .share-btn i {\n        line-height: 1;\n        font-size: 25px;\n    }\n\n    @media (max-width: 576px) {\n        .share-btn {\n            width: 36px;\n            height: 36px;\n            font-size: 1rem;\n            margin-left: 6px;\n        }\n    }\n<\/style>\n\n<script>\n\n\/\/ Variables comunes (mejoramos el encoding para email)\nconst pageUrl = window.location.href;\nconst pageTitle = document.title;\n\n\/\/ Funciones de compartir (las de redes con window.open siguen iguales, pero agregamos return false para evitar salto de p\u00e1gina)\nfunction shareFacebook() {\n    window.open(`https:\/\/www.facebook.com\/sharer\/sharer.php?u=${encodeURIComponent(pageUrl)}`, '_blank', 'width=600,height=400');\n}\nfunction shareLinkedIn() {\n    window.open(`https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=${encodeURIComponent(pageUrl)}`, '_blank', 'width=600,height=500');\n}\nfunction shareTelegram() {\n    window.open(`https:\/\/t.me\/share\/url?url=${encodeURIComponent(pageUrl)}&text=${encodeURIComponent(pageTitle)}`, '_blank', 'width=600,height=400');\n}\nfunction shareWhatsApp() {\n    window.open(`https:\/\/api.whatsapp.com\/send?text=${encodeURIComponent(pageTitle + ' ' + pageUrl)}`, '_blank');\n}\n\n\/\/ Funci\u00f3n para compartir por email (copia al portapapeles + fallback Gmail)\nfunction shareByEmail() {\n    const pageUrl = window.location.href;\n    const pageTitle = document.title.trim();\n\n    \/\/ Texto listo para pegar en email (con salto de l\u00ednea)\n    const emailText = `${pageTitle}\\n${pageUrl}\\n\\nTe comparto este art\u00edculo interesante.`;\n\n    \/\/ Intentamos copiar al portapapeles\n    if (navigator.clipboard && navigator.clipboard.writeText) {\n        navigator.clipboard.writeText(emailText).then(() => {\n            \/\/ Mensaje de \u00e9xito (puedes usar alert, toast o un div temporal)\n            alert('\u00a1Enlace copiado al portapapeles!\\nP\u00e9galo en tu email (Ctrl+V).');\n        }).catch(err => {\n            console.error('Error al copiar:', err);\n            fallbackToGmail();\n        });\n    } else {\n        \/\/ Si no soporta clipboard (navegadores muy viejos)\n        fallbackToGmail();\n    }\n}\n\nfunction fallbackToGmail() {\n    const pageUrl = encodeURIComponent(window.location.href);\n    const pageTitle = encodeURIComponent(document.title);\n    const body = encodeURIComponent(document.title + '\\n' + window.location.href + '\\n\\nTe comparto esto:');\n\n    \/\/ Abre compose de Gmail\n    window.open(`https:\/\/mail.google.com\/mail\/?view=cm&fs=1&su=${pageTitle}&body=${body}`, '_blank', 'width=800,height=600');\n}\n<\/script>\n\n<!-- Font Awesome (si no lo tienes ya cargado en todo el sitio, mantenlo) -->\n<link rel=\"stylesheet\" href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/font-awesome\/6.5.0\/css\/all.min.css\" integrity=\"sha512-S...\" crossorigin=\"anonymous\" referrerpolicy=\"no-referrer\" \/>\n<\/div><\/div><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Presentaci\u00f3n Programa acad\u00e9mico Equipo Docente Matr\u00edcula Presentaci\u00f3n Programa acad\u00e9mico Equipo Docente Matr\u00edcula Estrategias para el abordaje integral de los pacientes polimedicados Descripci\u00f3n general El objetivo general de la microcredencial Estrategias para el abordaje integral de los pacientes polimedicados es capacitar al estudiantado para identificar, evaluar y abordar de manera integral la polimedicaci\u00f3n, aplicando un enfoque&#8230;<\/p>\n","protected":false},"author":28,"featured_media":1687,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/template-frontpage.php","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4240","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Estrategias para el abordaje integral de los pacientes polimedicados - Formaci\u00f3n Permanente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ull.es\/formacion-permanente\/blog\/estrategias-para-el-abordaje-integral-de-los-pacientes-polimedicados\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estrategias para el abordaje integral de los pacientes polimedicados - Formaci\u00f3n Permanente\" \/>\n<meta property=\"og:description\" content=\"Presentaci\u00f3n Programa acad\u00e9mico Equipo Docente Matr\u00edcula Presentaci\u00f3n Programa acad\u00e9mico Equipo Docente Matr\u00edcula Estrategias para el abordaje integral de los pacientes polimedicados Descripci\u00f3n general El objetivo general de la microcredencial Estrategias para el abordaje integral de los pacientes polimedicados es capacitar al estudiantado para identificar, evaluar y abordar de manera integral la polimedicaci\u00f3n, aplicando un enfoque...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ull.es\/formacion-permanente\/blog\/estrategias-para-el-abordaje-integral-de-los-pacientes-polimedicados\/\" \/>\n<meta property=\"og:site_name\" content=\"Formaci\u00f3n Permanente\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-06T13:45:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-27T14:26:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Headers_microcredenciales_Introduccion_a_la_Computacion_Cuantica.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2500\" \/>\n\t<meta property=\"og:image:height\" content=\"807\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"gestooolsjcasaseca\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"gestooolsjcasaseca\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ull.es\\\/formacion-permanente\\\/blog\\\/estrategias-para-el-abordaje-integral-de-los-pacientes-polimedicados\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ull.es\\\/formacion-permanente\\\/blog\\\/estrategias-para-el-abordaje-integral-de-los-pacientes-polimedicados\\\/\"},\"author\":{\"name\":\"gestooolsjcasaseca\",\"@id\":\"https:\\\/\\\/www.ull.es\\\/formacion-permanente\\\/#\\\/schema\\\/person\\\/0a3aa27133923807a70e04f3a6929388\"},\"headline\":\"Estrategias para el abordaje integral de los pacientes polimedicados\",\"datePublished\":\"2026-04-06T13:45:23+00:00\",\"dateModified\":\"2026-04-27T14:26:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ull.es\\\/formacion-permanente\\\/blog\\\/estrategias-para-el-abordaje-integral-de-los-pacientes-polimedicados\\\/\"},\"wordCount\":1991,\"image\":{\"@id\":\"https:\\\/\\\/www.ull.es\\\/formacion-permanente\\\/blog\\\/estrategias-para-el-abordaje-integral-de-los-pacientes-polimedicados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ull.es\\\/formacion-permanente\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Headers_microcredenciales_Introduccion_a_la_Computacion_Cuantica.jpg\",\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ull.es\\\/formacion-permanente\\\/blog\\\/estrategias-para-el-abordaje-integral-de-los-pacientes-polimedicados\\\/\",\"url\":\"https:\\\/\\\/www.ull.es\\\/formacion-permanente\\\/blog\\\/estrategias-para-el-abordaje-integral-de-los-pacientes-polimedicados\\\/\",\"name\":\"Estrategias para el abordaje integral de los pacientes polimedicados - Formaci\u00f3n Permanente\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ull.es\\\/formacion-permanente\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ull.es\\\/formacion-permanente\\\/blog\\\/estrategias-para-el-abordaje-integral-de-los-pacientes-polimedicados\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ull.es\\\/formacion-permanente\\\/blog\\\/estrategias-para-el-abordaje-integral-de-los-pacientes-polimedicados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ull.es\\\/formacion-permanente\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Headers_microcredenciales_Introduccion_a_la_Computacion_Cuantica.jpg\",\"datePublished\":\"2026-04-06T13:45:23+00:00\",\"dateModified\":\"2026-04-27T14:26:08+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.ull.es\\\/formacion-permanente\\\/#\\\/schema\\\/person\\\/0a3aa27133923807a70e04f3a6929388\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ull.es\\\/formacion-permanente\\\/blog\\\/estrategias-para-el-abordaje-integral-de-los-pacientes-polimedicados\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ull.es\\\/formacion-permanente\\\/blog\\\/estrategias-para-el-abordaje-integral-de-los-pacientes-polimedicados\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ull.es\\\/formacion-permanente\\\/blog\\\/estrategias-para-el-abordaje-integral-de-los-pacientes-polimedicados\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ull.es\\\/formacion-permanente\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Headers_microcredenciales_Introduccion_a_la_Computacion_Cuantica.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ull.es\\\/formacion-permanente\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Headers_microcredenciales_Introduccion_a_la_Computacion_Cuantica.jpg\",\"width\":2500,\"height\":807},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ull.es\\\/formacion-permanente\\\/blog\\\/estrategias-para-el-abordaje-integral-de-los-pacientes-polimedicados\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ull.es\\\/formacion-permanente\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estrategias para el abordaje integral de los pacientes polimedicados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ull.es\\\/formacion-permanente\\\/#website\",\"url\":\"https:\\\/\\\/www.ull.es\\\/formacion-permanente\\\/\",\"name\":\"Formaci\u00f3n Permanente\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ull.es\\\/formacion-permanente\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ull.es\\\/formacion-permanente\\\/#\\\/schema\\\/person\\\/0a3aa27133923807a70e04f3a6929388\",\"name\":\"gestooolsjcasaseca\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/33beea45bf05aba27f9cb2a6d6a7f4a33ebcb05c48c00b886e86d215312cd7ef?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/33beea45bf05aba27f9cb2a6d6a7f4a33ebcb05c48c00b886e86d215312cd7ef?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/33beea45bf05aba27f9cb2a6d6a7f4a33ebcb05c48c00b886e86d215312cd7ef?s=96&d=mm&r=g\",\"caption\":\"gestooolsjcasaseca\"},\"url\":\"https:\\\/\\\/www.ull.es\\\/formacion-permanente\\\/blog\\\/author\\\/gestooolsjcasaseca\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estrategias para el abordaje integral de los pacientes polimedicados - Formaci\u00f3n Permanente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ull.es\/formacion-permanente\/blog\/estrategias-para-el-abordaje-integral-de-los-pacientes-polimedicados\/","og_locale":"es_ES","og_type":"article","og_title":"Estrategias para el abordaje integral de los pacientes polimedicados - Formaci\u00f3n Permanente","og_description":"Presentaci\u00f3n Programa acad\u00e9mico Equipo Docente Matr\u00edcula Presentaci\u00f3n Programa acad\u00e9mico Equipo Docente Matr\u00edcula Estrategias para el abordaje integral de los pacientes polimedicados Descripci\u00f3n general El objetivo general de la microcredencial Estrategias para el abordaje integral de los pacientes polimedicados es capacitar al estudiantado para identificar, evaluar y abordar de manera integral la polimedicaci\u00f3n, aplicando un enfoque...","og_url":"https:\/\/www.ull.es\/formacion-permanente\/blog\/estrategias-para-el-abordaje-integral-de-los-pacientes-polimedicados\/","og_site_name":"Formaci\u00f3n Permanente","article_published_time":"2026-04-06T13:45:23+00:00","article_modified_time":"2026-04-27T14:26:08+00:00","og_image":[{"width":2500,"height":807,"url":"https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Headers_microcredenciales_Introduccion_a_la_Computacion_Cuantica.jpg","type":"image\/jpeg"}],"author":"gestooolsjcasaseca","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"gestooolsjcasaseca","Tiempo de lectura":"12 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ull.es\/formacion-permanente\/blog\/estrategias-para-el-abordaje-integral-de-los-pacientes-polimedicados\/#article","isPartOf":{"@id":"https:\/\/www.ull.es\/formacion-permanente\/blog\/estrategias-para-el-abordaje-integral-de-los-pacientes-polimedicados\/"},"author":{"name":"gestooolsjcasaseca","@id":"https:\/\/www.ull.es\/formacion-permanente\/#\/schema\/person\/0a3aa27133923807a70e04f3a6929388"},"headline":"Estrategias para el abordaje integral de los pacientes polimedicados","datePublished":"2026-04-06T13:45:23+00:00","dateModified":"2026-04-27T14:26:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ull.es\/formacion-permanente\/blog\/estrategias-para-el-abordaje-integral-de-los-pacientes-polimedicados\/"},"wordCount":1991,"image":{"@id":"https:\/\/www.ull.es\/formacion-permanente\/blog\/estrategias-para-el-abordaje-integral-de-los-pacientes-polimedicados\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Headers_microcredenciales_Introduccion_a_la_Computacion_Cuantica.jpg","inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.ull.es\/formacion-permanente\/blog\/estrategias-para-el-abordaje-integral-de-los-pacientes-polimedicados\/","url":"https:\/\/www.ull.es\/formacion-permanente\/blog\/estrategias-para-el-abordaje-integral-de-los-pacientes-polimedicados\/","name":"Estrategias para el abordaje integral de los pacientes polimedicados - Formaci\u00f3n Permanente","isPartOf":{"@id":"https:\/\/www.ull.es\/formacion-permanente\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ull.es\/formacion-permanente\/blog\/estrategias-para-el-abordaje-integral-de-los-pacientes-polimedicados\/#primaryimage"},"image":{"@id":"https:\/\/www.ull.es\/formacion-permanente\/blog\/estrategias-para-el-abordaje-integral-de-los-pacientes-polimedicados\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Headers_microcredenciales_Introduccion_a_la_Computacion_Cuantica.jpg","datePublished":"2026-04-06T13:45:23+00:00","dateModified":"2026-04-27T14:26:08+00:00","author":{"@id":"https:\/\/www.ull.es\/formacion-permanente\/#\/schema\/person\/0a3aa27133923807a70e04f3a6929388"},"breadcrumb":{"@id":"https:\/\/www.ull.es\/formacion-permanente\/blog\/estrategias-para-el-abordaje-integral-de-los-pacientes-polimedicados\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ull.es\/formacion-permanente\/blog\/estrategias-para-el-abordaje-integral-de-los-pacientes-polimedicados\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ull.es\/formacion-permanente\/blog\/estrategias-para-el-abordaje-integral-de-los-pacientes-polimedicados\/#primaryimage","url":"https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Headers_microcredenciales_Introduccion_a_la_Computacion_Cuantica.jpg","contentUrl":"https:\/\/www.ull.es\/formacion-permanente\/wp-content\/uploads\/2025\/12\/Headers_microcredenciales_Introduccion_a_la_Computacion_Cuantica.jpg","width":2500,"height":807},{"@type":"BreadcrumbList","@id":"https:\/\/www.ull.es\/formacion-permanente\/blog\/estrategias-para-el-abordaje-integral-de-los-pacientes-polimedicados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ull.es\/formacion-permanente\/"},{"@type":"ListItem","position":2,"name":"Estrategias para el abordaje integral de los pacientes polimedicados"}]},{"@type":"WebSite","@id":"https:\/\/www.ull.es\/formacion-permanente\/#website","url":"https:\/\/www.ull.es\/formacion-permanente\/","name":"Formaci\u00f3n Permanente","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ull.es\/formacion-permanente\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.ull.es\/formacion-permanente\/#\/schema\/person\/0a3aa27133923807a70e04f3a6929388","name":"gestooolsjcasaseca","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/33beea45bf05aba27f9cb2a6d6a7f4a33ebcb05c48c00b886e86d215312cd7ef?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/33beea45bf05aba27f9cb2a6d6a7f4a33ebcb05c48c00b886e86d215312cd7ef?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/33beea45bf05aba27f9cb2a6d6a7f4a33ebcb05c48c00b886e86d215312cd7ef?s=96&d=mm&r=g","caption":"gestooolsjcasaseca"},"url":"https:\/\/www.ull.es\/formacion-permanente\/blog\/author\/gestooolsjcasaseca\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ull.es\/formacion-permanente\/wp-json\/wp\/v2\/posts\/4240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ull.es\/formacion-permanente\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ull.es\/formacion-permanente\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ull.es\/formacion-permanente\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ull.es\/formacion-permanente\/wp-json\/wp\/v2\/comments?post=4240"}],"version-history":[{"count":9,"href":"https:\/\/www.ull.es\/formacion-permanente\/wp-json\/wp\/v2\/posts\/4240\/revisions"}],"predecessor-version":[{"id":5409,"href":"https:\/\/www.ull.es\/formacion-permanente\/wp-json\/wp\/v2\/posts\/4240\/revisions\/5409"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ull.es\/formacion-permanente\/wp-json\/wp\/v2\/media\/1687"}],"wp:attachment":[{"href":"https:\/\/www.ull.es\/formacion-permanente\/wp-json\/wp\/v2\/media?parent=4240"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ull.es\/formacion-permanente\/wp-json\/wp\/v2\/categories?post=4240"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ull.es\/formacion-permanente\/wp-json\/wp\/v2\/tags?post=4240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}