{"id":270,"date":"2017-07-11T13:21:36","date_gmt":"2017-07-11T13:21:36","guid":{"rendered":"http:\/\/www.ull.es\/masteres\/desarrollo-y-gestion-de-recursos-humanos\/?page_id=270"},"modified":"2018-06-07T13:12:15","modified_gmt":"2018-06-07T13:12:15","slug":"plan-de-estudios","status":"publish","type":"page","link":"https:\/\/www.ull.es\/grados\/bellas-artes\/en\/plan-de-estudios\/","title":{"rendered":"Curriculum"},"content":{"rendered":"<p>[vc_row][vc_column][vc_column_text]<\/p>\n<h1>Plan de estudios<\/h1>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=\u00bb2\/3&#8243;][vc_column_text]<\/p>\n<ul>\n<li><a href=\"https:\/\/www.ull.es\/grados\/bellas-artes\/plan-de-estudios\/estructura-del-plan-de-estudios\/\" target=\"_blank\" rel=\"noopener\">Estructura del plan de estudios<\/a><\/li>\n<li><a href=\"https:\/\/www.ull.es\/grados\/bellas-artes\/plan-de-estudios\/guias-docentes\/\" target=\"_blank\" rel=\"noopener\">Gu\u00edas docentes<\/a><\/li>\n<li><a href=\"https:\/\/www.ull.es\/grados\/bellas-artes\/plan-de-estudios\/competencias\/\" target=\"_blank\" rel=\"noopener\">Competencias<\/a><\/li>\n<li><a href=\"https:\/\/www.ull.es\/grados\/bellas-artes\/plan-de-estudios\/trabajo-fin-de-grado\/\" target=\"_blank\" rel=\"noopener\">Trabajo Fin de Grado<\/a><\/li>\n<li><a href=\"https:\/\/www.ull.es\/grados\/bellas-artes\/plan-de-estudios\/practicas-externas\/\" target=\"_blank\" rel=\"noopener\">Pr\u00e1cticas Externas<\/a><\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column][vc_column width=\u00bb1\/3&#8243;][vc_column_text]\n<ul class=\"widget-box\">\n<li class='contacto-header'>Informaci\u00f3n de contacto<\/li><li><i class=\"fa fa-map-marker\"><\/i> Calle Radio Aficionados s\/n. Campus de Guajara. Apartado 456. C\u00f3digo postal 38200. San Crist\u00f3bal de La Laguna. S\/C Tenerife<\/li><li><i class=\"fa fa-phone\"><\/i> (+34) 922 31 97 30<\/li><li><i class=\"fa fa-envelope\"><\/i>  <a href=mailto:secbbaa@ull.es>secbbaa@ull.es<\/a><\/li><li><i class=\"fa fa-globe\"><\/i><a href=\"https:\/\/www.ull.es\/centros\/facultad-bellas-artes\"> Web de Facultad de Bellas Artes<\/a><\/li><li><i class=\"fa fa-calendar\"><\/i><a href=\"http:\/\/citaprevia.ull.es\/index.php?s=humanidades\"> Cita previa<\/a><\/li>\n<\/ul>\n\n[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text] Plan de estudios [\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=\u00bb2\/3&#8243;][vc_column_text] Estructura del plan de estudios Gu\u00edas docentes Competencias Trabajo Fin de Grado Pr\u00e1cticas Externas [\/vc_column_text][\/vc_column][vc_column width=\u00bb1\/3&#8243;][vc_column_text][\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-270","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.ull.es\/grados\/bellas-artes\/en\/wp-json\/wp\/v2\/pages\/270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ull.es\/grados\/bellas-artes\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ull.es\/grados\/bellas-artes\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ull.es\/grados\/bellas-artes\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ull.es\/grados\/bellas-artes\/en\/wp-json\/wp\/v2\/comments?post=270"}],"version-history":[{"count":3,"href":"https:\/\/www.ull.es\/grados\/bellas-artes\/en\/wp-json\/wp\/v2\/pages\/270\/revisions"}],"predecessor-version":[{"id":851,"href":"https:\/\/www.ull.es\/grados\/bellas-artes\/en\/wp-json\/wp\/v2\/pages\/270\/revisions\/851"}],"wp:attachment":[{"href":"https:\/\/www.ull.es\/grados\/bellas-artes\/en\/wp-json\/wp\/v2\/media?parent=270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}