{"id":202,"date":"2017-07-11T10:11:11","date_gmt":"2017-07-11T10:11:11","guid":{"rendered":"http:\/\/www.ull.es\/masteres\/desarrollo-y-gestion-de-recursos-humanos\/?page_id=202"},"modified":"2025-11-10T08:46:04","modified_gmt":"2025-11-10T08:46:04","slug":"acceso-admision-y-matricula","status":"publish","type":"page","link":"https:\/\/www.ull.es\/grados\/biologia\/fr\/informacion-academica\/acceso-admision-y-matricula\/","title":{"rendered":"Acc\u00e8s, admission et inscription"},"content":{"rendered":"\n<div class=\"wp-block-stackable-columns alignfull stk-block-columns stk-block stk-8657999\" data-block-id=\"8657999\"><style>.stk-8657999 {padding-bottom:0px !important;margin-top:-30px !important;margin-bottom:0px !important;}@media screen and (max-width: 767px){.stk-8657999 {margin-top:-10% !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-8657999-column alignfull\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-914f03e\" data-v=\"4\" data-block-id=\"914f03e\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-914f03e-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-914f03e-inner-blocks\"><style id=\"depicter-1-inline-pre-css\">\n\n.depicter-1:not(.depicter-ready){\n\theight:500px;\n}\n\n\/***** Tablet *****\/\n@media screen and (max-width: 1024px){\n\n.depicter-1:not(.depicter-ready){\n\theight:700px;\n}\n\n}\n\/***** Mobile *****\/\n@media screen and (max-width: 767px){\n\n.depicter-1:not(.depicter-ready){\n\theight:360px;\n}\n\n}\n<\/style>\n<div id=\"depicter-1\" class=\"depicter depicter-document depicter-revert depicter-1 depicter-layout-fullwidth\">\n\n<div class=\"depicter-loading-container depicter-loading dotFlashing-dark\"><div class=\"depicter-loading-dark depicter-dot-flashing\">\n   <span><\/span>\n   <span><\/span>\n   <span><\/span>\n<\/div>\n<\/div>\n<div id=\"depicter-1-section-1\" class=\"depicter-section depicter-1-section-1\" data-name=\"Section 1\" data-type=\"section\" data-local-id=\"section-1\">\n<picture class=\"depicter-bg\">\n<source data-depicter-srcset=\"https:\/\/www.ull.es\/grados\/biologia\/wp-content\/uploads\/sites\/43\/2025\/03\/Banner_Biologia-768x217.jpg, https:\/\/www.ull.es\/grados\/biologia\/wp-content\/uploads\/sites\/43\/2025\/03\/Banner_Biologia.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(max-width: 1024px)\" \/>\n\n<source data-depicter-srcset=\"https:\/\/www.ull.es\/grados\/biologia\/wp-content\/uploads\/sites\/43\/2025\/03\/Banner_Biologia.jpg, https:\/\/www.ull.es\/grados\/biologia\/wp-content\/uploads\/sites\/43\/2025\/03\/Banner_Biologia-1600x453.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(min-width: 1025px)\" \/>\n<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-ken-burns=\"false\" data-tablet-ken-burns=\"false\" data-mobile-ken-burns=\"false\" alt=\"\" data-depicter-src=\"https:\/\/www.ull.es\/grados\/biologia\/wp-content\/uploads\/sites\/43\/2025\/03\/Banner_Biologia.jpg\" data-object-fit=\"custom,custom,\" data-object-position=\"center top,,\" data-crop=\"{'focalPoint':{'x':0.5,'y':0.560000000000000053290705182007513940334320068359375},'mediaSize':{'width':1792,'height':507}}\" data-tablet-crop=\"{'focalPoint':{'x':0.5,'y':0.5},'mediaSize':{'width':2472.40618101545260287821292877197265625,'height':700}}\" data-mobile-crop=\"{'focalPoint':{'x':0.5,'y':0.5},'mediaSize':{'width':1271.523178807947033419623039662837982177734375,'height':360}}\" \/>\n<\/picture>\n\n\n<h1 id=\"depicter-1-element-5\" class=\"depicter-element depicter-layer depicter-1-element-5\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 2\" data-local-id=\"element-5\" data-offset=\"x:217px;y:207px;origin:tl\" data-tablet-offset=\"x:299px;y:321px;origin:tl\" data-mobile-offset=\"x:6px;y:-144px;origin:tl\" data-width=\"767px,589px,309px\" data-height=\"auto,auto,auto\" data-responsive-scale=\"true,,\">Grado en Biolog\u00eda<\/h1>\n\n<div id=\"depicter-1-element-10\" class=\"depicter-element depicter-layer depicter-1-element-10\" data-type=\"shape\" data-wrap=\"true\" data-name=\"Shape 1\" data-local-id=\"element-10\" data-offset=\"x:226px;y:315px;origin:tl\" data-tablet-offset=\"x:299px;y:391px;origin:tl\" data-mobile-offset=\"x:6px;y:-35px;origin:tl\" data-width=\"748px,425px,309px\" data-height=\"8px,8px,8px\" data-responsive-scale=\"true,,\"><\/div>\n<\/div>\n<\/div>\n<script>\n(window.depicterSetups = window.depicterSetups || []).push(function(){\n\tDepicter.basePath = 'https:\/\/www.ull.es\/grados\/biologia\/wp-content\/plugins\/depicter\/resources\/scripts\/player\/';\n\tconst dpPlayer = Depicter.setup('.depicter-1',\n\t\t{\"width\":[\"1200\",\"1024\",\"360\"],\"height\":[\"500\",\"700\",\"360\"],\"view\":\"basic\",\"keepAspectRatio\":true,\"preload\":0,\"layout\":\"fullwidth\",\"rtl\":false,\"initAfterAppear\":false,\"ajaxApiUrl\":\"https:\\\/\\\/www.ull.es\\\/grados\\\/biologia\\\/wp-admin\\\/admin-ajax.php\",\"mouseSwipe\":true,\"touchSwipe\":true,\"useWatermark\":false}\n\t);\n});\n<\/script><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns alignfull stk-block-columns stk--hide-mobile stk-block stk-ceecbdc stk-block-background\" data-block-id=\"ceecbdc\"><style>.stk-ceecbdc {background-color:#360060 !important;padding-top:35px !important;padding-right:0px !important;padding-bottom:2px !important;padding-left:0px !important;margin-top:-20px !important;margin-bottom:70px !important;}.stk-ceecbdc:before{background-color:#360060 !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-ceecbdc-column alignfull\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-fc60a5d\" data-v=\"4\" data-block-id=\"fc60a5d\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-fc60a5d-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-fc60a5d-inner-blocks\">\n<div class=\"wp-block-stackable-spacer stk-block-spacer stk--no-padding stk-block stk-a3a8a68\" data-block-id=\"a3a8a68\"><style>.stk-a3a8a68 {height:0px !important;}<\/style><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns stk-block-columns stk-block stk-8b59b96\" data-block-id=\"8b59b96\"><style>.stk-8b59b96 .stk--block-align-8b59b96{align-items:flex-start !important;}.stk-8b59b96 {margin-top:25px !important;}.stk-8b59b96-column{--stk-columns-spacing:0px !important;--stk-column-gap:50px !important;}@media screen and (max-width: 767px){.stk-8b59b96-column{row-gap:var(--stk--preset--spacing--60, 2.25rem) !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk--block-align-8b59b96 stk-block-content stk-content-align stk-8b59b96-column\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-dbb7e15\" data-v=\"4\" data-block-id=\"dbb7e15\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-dbb7e15-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-dbb7e15-inner-blocks\">\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-689c258\" id=\"acceso-admision-y-matricula\" data-block-id=\"689c258\"><style>.stk-689c258 .stk-block-heading__text{color:#5c068c !important;}<\/style><h1 class=\"stk-block-heading__text has-text-color\">Acceso, admisi\u00f3n y matr\u00edcula<\/h1><\/div>\n\n\n\n<details class=\"wp-block-stackable-accordion stk-block-accordion stk-inner-blocks stk-block-content stk-block stk-7c390cd is-style-default\" id=\"acceso\" data-block-id=\"7c390cd\"><style>.stk-7c390cd {border-style:solid !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;margin-bottom:11px !important;}<\/style>\n<summary class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-c927805 stk--container-small stk-block-accordion__heading\" data-v=\"4\" data-block-id=\"c927805\"><style>.stk-c927805 {padding-top:2px !important;padding-right:2px !important;padding-bottom:2px !important;padding-left:2px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-c927805-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-c927805-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-7935446\" data-block-id=\"7935446\"><style>.stk-7935446 .stk-inner-blocks{gap:39px !important;}@media screen and (max-width: 1023px){.stk-7935446 .stk-inner-blocks{gap:39px !important;}}@media screen and (max-width: 767px){.stk-7935446 .stk-inner-blocks{gap:39px !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-icon stk-block-icon stk-block stk-9a468d5\" data-block-id=\"9a468d5\"><style>.stk-9a468d5 .stk--svg-wrapper .stk--inner-svg svg:last-child{height:25px !important;width:25px !important;}.stk-9a468d5 .stk--svg-wrapper .stk--inner-svg svg:last-child, .stk-9a468d5 .stk--svg-wrapper .stk--inner-svg svg:last-child :is(g, path, rect, polygon, ellipse){fill:#5c068c !important;}<\/style><span class=\"stk--svg-wrapper stk--has-icon2\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-9a468d5\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-9-a-468-d-5-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-9-a-468-d-5-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M224 256A128 128 0 1 0 224 0a128 128 0 1 0 0 256zm-45.7 48C79.8 304 0 383.8 0 482.3C0 498.7 13.3 512 29.7 512H418.3c16.4 0 29.7-13.3 29.7-29.7C448 383.8 368.2 304 269.7 304H178.3z\"><\/path><\/svg><\/div><div class=\"stk--inner-svg stk--icon-2\" style=\"display:none\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-9a468d5\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-9-a-468-d-5-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-9-a-468-d-5-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M219.3 .5c3.1-.6 6.3-.6 9.4 0l200 40C439.9 42.7 448 52.6 448 64s-8.1 21.3-19.3 23.5L352 102.9V160c0 70.7-57.3 128-128 128s-128-57.3-128-128V102.9L48 93.3v65.1l15.7 78.4c.9 4.7-.3 9.6-3.3 13.3s-7.6 5.9-12.4 5.9H16c-4.8 0-9.3-2.1-12.4-5.9s-4.3-8.6-3.3-13.3L16 158.4V86.6C6.5 83.3 0 74.3 0 64C0 52.6 8.1 42.7 19.3 40.5l200-40zM111.9 327.7c10.5-3.4 21.8 .4 29.4 8.5l71 75.5c6.3 6.7 17 6.7 23.3 0l71-75.5c7.6-8.1 18.9-11.9 29.4-8.5C401 348.6 448 409.4 448 481.3c0 17-13.8 30.7-30.7 30.7H30.7C13.8 512 0 498.2 0 481.3c0-71.9 47-132.7 111.9-153.6z\"><\/path><\/svg><\/div><\/span><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-31863c1\" id=\"acceso\" data-block-id=\"31863c1\"><style>.stk-31863c1 .stk-block-heading__text{color:#000000 !important;font-weight:500 !important;font-family:\"ArgentumSans\", Sans-serif !important;}<\/style><h4 class=\"stk-block-heading__text has-text-color\"><span style=\"color: #000000;\" class=\"stk-highlight\">Acceso<\/span><\/h4><\/div>\n<\/div><\/div>\n<\/div><\/div><\/summary>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-5222666 stk-block-accordion__content\" data-v=\"4\" data-block-id=\"5222666\"><style>.stk-5222666 {margin-top:-30px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-5222666-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-5222666-inner-blocks\">\n<p>El acceso es el conjunto de requisitos establecidos para cursar las ense\u00f1anzas universitarias oficiales de grado. Su cumplimiento es necesario y previo para poder solicitar plaza en las titulaciones oficiales de la ULL, mediante el procedimiento de admisi\u00f3n a la universidad.<\/p>\n\n\n\n<p>Se pueden consultar los requisitos de acceso a los estudios de grado en el siguiente&nbsp;<a href=\"https:\/\/www.ull.es\/admision-becas\/que-es-el-acceso\/\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">enlace<\/a>.<\/p>\n\n\n\n<p>Existen diferentes modalidades de acceso. Pueden acceder a la informaci\u00f3n detallada de las principales modalidades desde los siguientes enlaces:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.ull.es\/admision-becas\/ebau\/\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">EBAU<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.ull.es\/admision-becas\/acceso-mayores\/\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">Mayores de 25, 40 y 45 a\u00f1os<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.ull.es\/admision-becas\/acceso-extranjeros\/\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">Extranjeros<\/a><\/li>\n<\/ul>\n\n\n\n<p>Para el Grado en Biolog\u00eda no es necesario realizar ninguna prueba especial de acceso.<\/p>\n<\/div><\/div><\/div>\n<\/details>\n\n\n\n<details class=\"wp-block-stackable-accordion stk-block-accordion stk-inner-blocks stk-block-content stk-block stk-88a7c9c is-style-default\" id=\"admision\" data-block-id=\"88a7c9c\"><style>.stk-88a7c9c {border-style:solid !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;margin-bottom:10px !important;}<\/style>\n<summary class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-27019df stk--container-small stk-block-accordion__heading\" data-v=\"4\" data-block-id=\"27019df\"><style>.stk-27019df {padding-top:2px !important;padding-right:2px !important;padding-bottom:2px !important;padding-left:2px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-27019df-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-27019df-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-9c9ce7e\" data-block-id=\"9c9ce7e\"><style>.stk-9c9ce7e .stk-inner-blocks{gap:39px !important;}@media screen and (max-width: 1023px){.stk-9c9ce7e .stk-inner-blocks{gap:39px !important;}}@media screen and (max-width: 767px){.stk-9c9ce7e .stk-inner-blocks{gap:39px !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-icon stk-block-icon stk-block stk-61c8ad3\" data-block-id=\"61c8ad3\"><style>.stk-61c8ad3 .stk--svg-wrapper .stk--inner-svg svg:last-child{height:25px !important;width:25px !important;}.stk-61c8ad3 .stk--svg-wrapper .stk--inner-svg svg:last-child, .stk-61c8ad3 .stk--svg-wrapper .stk--inner-svg svg:last-child :is(g, path, rect, polygon, ellipse){fill:#5c068c !important;}<\/style><span class=\"stk--svg-wrapper stk--has-icon2\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-61c8ad3\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-61-c-8-ad-3-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-61-c-8-ad-3-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M256 512A256 256 0 1 0 256 0a256 256 0 1 0 0 512zM369 209L241 337c-9.4 9.4-24.6 9.4-33.9 0l-64-64c-9.4-9.4-9.4-24.6 0-33.9s24.6-9.4 33.9 0l47 47L335 175c9.4-9.4 24.6-9.4 33.9 0s9.4 24.6 0 33.9z\"><\/path><\/svg><\/div><div class=\"stk--inner-svg stk--icon-2\" style=\"display:none\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-61c8ad3\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-61-c-8-ad-3-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-61-c-8-ad-3-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M256 48a208 208 0 1 1 0 416 208 208 0 1 1 0-416zm0 464A256 256 0 1 0 256 0a256 256 0 1 0 0 512zM369 209c9.4-9.4 9.4-24.6 0-33.9s-24.6-9.4-33.9 0l-111 111-47-47c-9.4-9.4-24.6-9.4-33.9 0s-9.4 24.6 0 33.9l64 64c9.4 9.4 24.6 9.4 33.9 0L369 209z\"><\/path><\/svg><\/div><\/span><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-bcb6d4e\" id=\"span-style-color-000000-class-stk-highlight-admision-solitud-de-plaza-span\" data-block-id=\"bcb6d4e\"><style>.stk-bcb6d4e .stk-block-heading__text{color:#000000 !important;font-weight:500 !important;font-family:\"ArgentumSans\", Sans-serif !important;}<\/style><h4 class=\"stk-block-heading__text has-text-color\"><span style=\"color: #000000;\" class=\"stk-highlight\">Admisi\u00f3n (solitud de plaza)<\/span><\/h4><\/div>\n<\/div><\/div>\n<\/div><\/div><\/summary>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-76d605c stk-block-accordion__content\" data-v=\"4\" data-block-id=\"76d605c\"><style>.stk-76d605c {margin-top:-30px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-76d605c-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-76d605c-inner-blocks\">\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-5a7cc25\" data-block-id=\"5a7cc25\"><p class=\"stk-block-text__text\">La admisi\u00f3n es el proceso de la adjudicaci\u00f3n de las plazas ofertadas por la ULL para cursar ense\u00f1anzas oficiales universitarias entre quienes, cumpliendo con alguno de los requisitos de acceso, las han solicitado.<\/p><\/div>\n\n\n\n<p>En el&nbsp;Grado en Biolog\u00eda se oferta un cupo limitado de 100 plazas de nuevo ingreso.<\/p>\n\n\n\n<p>Los procedimientos de admisi\u00f3n que existen en la ULL son los siguientes:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.ull.es\/admision-becas\/solicitud-plaza-grados__trashed\/preinscripcion\/\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">Preinscripci\u00f3n<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.ull.es\/admision-becas\/traslado-de-expediente\/\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">Cambio de universidad y\/o estudios universitarios oficiales espa\u00f1oles (traslado de expediente)<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.ull.es\/admision-becas\/acceso-extranjeros\/convalidacion-estudios-parciales-extranjeros\/\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">Estudios universitarios extranjeros (convalidaci\u00f3n parcial de estudios extranjeros)<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.ull.es\/admision-becas\/simultaneidad\/\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">Simultaneidad de estudios<\/a><\/li>\n<\/ol>\n<\/div><\/div><\/div>\n<\/details>\n\n\n\n<details class=\"wp-block-stackable-accordion stk-block-accordion stk-inner-blocks stk-block-content stk-block stk-9d40cce is-style-default\" id=\"matricula\" data-block-id=\"9d40cce\"><style>.stk-9d40cce {border-style:solid !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;margin-bottom:8px !important;}<\/style>\n<summary class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-ef7f17a stk--container-small stk-block-accordion__heading\" data-v=\"4\" data-block-id=\"ef7f17a\"><style>.stk-ef7f17a {padding-top:2px !important;padding-right:2px !important;padding-bottom:2px !important;padding-left:2px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-ef7f17a-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-ef7f17a-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-da3b93e\" data-block-id=\"da3b93e\"><style>.stk-da3b93e .stk-inner-blocks{gap:39px !important;}@media screen and (max-width: 1023px){.stk-da3b93e .stk-inner-blocks{gap:39px !important;}}@media screen and (max-width: 767px){.stk-da3b93e .stk-inner-blocks{gap:39px !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-icon stk-block-icon stk-block stk-8c84b2d\" data-block-id=\"8c84b2d\"><style>.stk-8c84b2d .stk--svg-wrapper .stk--inner-svg svg:last-child{height:25px !important;width:25px !important;}.stk-8c84b2d .stk--svg-wrapper .stk--inner-svg svg:last-child, .stk-8c84b2d .stk--svg-wrapper .stk--inner-svg svg:last-child :is(g, path, rect, polygon, ellipse){fill:#5c068c !important;}<\/style><span class=\"stk--svg-wrapper stk--has-icon2\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-8c84b2d\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-8-c-84-b-2-d-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-8-c-84-b-2-d-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 384 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M64 0C28.7 0 0 28.7 0 64V448c0 35.3 28.7 64 64 64H320c35.3 0 64-28.7 64-64V160H256c-17.7 0-32-14.3-32-32V0H64zM256 0V128H384L256 0zM112 256H272c8.8 0 16 7.2 16 16s-7.2 16-16 16H112c-8.8 0-16-7.2-16-16s7.2-16 16-16zm0 64H272c8.8 0 16 7.2 16 16s-7.2 16-16 16H112c-8.8 0-16-7.2-16-16s7.2-16 16-16zm0 64H272c8.8 0 16 7.2 16 16s-7.2 16-16 16H112c-8.8 0-16-7.2-16-16s7.2-16 16-16z\"><\/path><\/svg><\/div><div class=\"stk--inner-svg stk--icon-2\" style=\"display:none\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-8c84b2d\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-8-c-84-b-2-d-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-8-c-84-b-2-d-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 384 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M64 464c-8.8 0-16-7.2-16-16V64c0-8.8 7.2-16 16-16H224v80c0 17.7 14.3 32 32 32h80V448c0 8.8-7.2 16-16 16H64zM64 0C28.7 0 0 28.7 0 64V448c0 35.3 28.7 64 64 64H320c35.3 0 64-28.7 64-64V154.5c0-17-6.7-33.3-18.7-45.3L274.7 18.7C262.7 6.7 246.5 0 229.5 0H64zm56 256c-13.3 0-24 10.7-24 24s10.7 24 24 24H264c13.3 0 24-10.7 24-24s-10.7-24-24-24H120zm0 96c-13.3 0-24 10.7-24 24s10.7 24 24 24H264c13.3 0 24-10.7 24-24s-10.7-24-24-24H120z\"><\/path><\/svg><\/div><\/span><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-d69e378\" id=\"span-style-color-000000-class-stk-highlight-matricula-span\" data-block-id=\"d69e378\"><style>.stk-d69e378 .stk-block-heading__text{color:#000000 !important;font-weight:500 !important;font-family:\"ArgentumSans\", Sans-serif !important;}<\/style><h4 class=\"stk-block-heading__text has-text-color\"><span style=\"color: #000000;\" class=\"stk-highlight\">Matr\u00edcula<\/span><\/h4><\/div>\n<\/div><\/div>\n<\/div><\/div><\/summary>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-9404ebc stk-block-accordion__content\" data-v=\"4\" data-block-id=\"9404ebc\"><style>.stk-9404ebc {margin-top:-30px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-9404ebc-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-9404ebc-inner-blocks\">\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-d0d311c\" data-block-id=\"d0d311c\"><p class=\"stk-block-text__text\">La matr\u00edcula es el instrumento a trav\u00e9s del que se adquiere la condici\u00f3n de estudiante universitario\/a. Para realizar la matr\u00edcula, el alumnado de nuevo ingreso debe reunir alguno de los requisitos de acceso y haber obtenido plaza a trav\u00e9s del procedimiento de admisi\u00f3n correspondiente.<\/p><\/div>\n\n\n\n<p>Cada curso acad\u00e9mico se publica un documento denominado \u201cInstrucci\u00f3n de admisi\u00f3n y matr\u00edcula\u201d (ver&nbsp;<a href=\"https:\/\/www.ull.es\/admision-becas\/matricula\/#normativa\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">enlace<\/a>), que recoge contiene la informaci\u00f3n necesaria para su correcto desarrollo (modalidades, periodos, calendario, documentaci\u00f3n a presentar, formas de pago,\u2026).<\/p>\n\n\n\n<p>Pueden acceder a la informaci\u00f3n en detalle sobre el proceso de matr\u00edcula en los estudios de grado en el siguiente&nbsp;<a href=\"https:\/\/www.ull.es\/admision-becas\/matricula\/\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">enlace<\/a>.<\/p>\n<\/div><\/div><\/div>\n<\/details>\n<\/div><\/div><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Acc\u00e8s, admission et inscription. Acc\u00e8s\u00a0: L\u2019acc\u00e8s d\u00e9signe l\u2019ensemble des conditions requises pour entreprendre des \u00e9tudes universitaires de premier cycle. Le respect de ces conditions est une condition pr\u00e9alable \u00e0 toute candidature \u00e0 un programme menant \u00e0 un dipl\u00f4me \u00e0 l\u2019Universit\u00e9 de La Laguna (ULL), par le biais de la proc\u00e9dure d\u2019admission. Les conditions d\u2019acc\u00e8s sont disponibles\u2026<\/p>","protected":false},"author":1,"featured_media":0,"parent":252,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"templates\/template-frontpage.php","meta":{"footnotes":""},"class_list":["post-202","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.ull.es\/grados\/biologia\/fr\/wp-json\/wp\/v2\/pages\/202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ull.es\/grados\/biologia\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ull.es\/grados\/biologia\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ull.es\/grados\/biologia\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ull.es\/grados\/biologia\/fr\/wp-json\/wp\/v2\/comments?post=202"}],"version-history":[{"count":42,"href":"https:\/\/www.ull.es\/grados\/biologia\/fr\/wp-json\/wp\/v2\/pages\/202\/revisions"}],"predecessor-version":[{"id":1539,"href":"https:\/\/www.ull.es\/grados\/biologia\/fr\/wp-json\/wp\/v2\/pages\/202\/revisions\/1539"}],"up":[{"embeddable":true,"href":"https:\/\/www.ull.es\/grados\/biologia\/fr\/wp-json\/wp\/v2\/pages\/252"}],"wp:attachment":[{"href":"https:\/\/www.ull.es\/grados\/biologia\/fr\/wp-json\/wp\/v2\/media?parent=202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}