{"id":264,"date":"2017-07-11T12:47:32","date_gmt":"2017-07-11T12:47:32","guid":{"rendered":"http:\/\/www.ull.es\/masteres\/desarrollo-y-gestion-de-recursos-humanos\/?page_id=264"},"modified":"2025-10-27T13:57:12","modified_gmt":"2025-10-27T13:57:12","slug":"reclamaciones-quejas-y-sugerencias","status":"publish","type":"page","link":"https:\/\/www.ull.es\/grados\/estudios-clasicos\/fr\/calidad-y-resultados\/reclamaciones-quejas-y-sugerencias\/","title":{"rendered":"Plaintes, suggestions et compliments"},"content":{"rendered":"\n<div class=\"wp-block-stackable-columns alignfull stk-block-columns stk-block stk-8657999\" data-block-id=\"8657999\"><style>.stk-8657999 {padding-bottom:0px !important;margin-top:-30px !important;margin-bottom:0px !important;}@media screen and (max-width: 767px){.stk-8657999 {margin-top:-10% !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-8657999-column alignfull\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-914f03e\" data-v=\"4\" data-block-id=\"914f03e\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-914f03e-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-914f03e-inner-blocks\"><style id=\"depicter-1-inline-pre-css\">\n\n.depicter-1:not(.depicter-ready){\n\theight:500px;\n}\n\n\/***** Tablet *****\/\n@media screen and (max-width: 1024px){\n\n.depicter-1:not(.depicter-ready){\n\theight:700px;\n}\n\n}\n\/***** Mobile *****\/\n@media screen and (max-width: 767px){\n\n.depicter-1:not(.depicter-ready){\n\theight:360px;\n}\n\n}\n<\/style>\n<div id=\"depicter-1\" class=\"depicter depicter-document depicter-revert depicter-1 depicter-layout-fullwidth\">\n\n<div class=\"depicter-loading-container depicter-loading dotFlashing-dark\"><div class=\"depicter-loading-dark depicter-dot-flashing\">\n   <span><\/span>\n   <span><\/span>\n   <span><\/span>\n<\/div>\n<\/div>\n<div id=\"depicter-1-section-1\" class=\"depicter-section depicter-1-section-1\" data-name=\"Section 1\" data-type=\"section\" data-local-id=\"section-1\">\n<picture class=\"depicter-bg\">\n<source data-depicter-srcset=\"https:\/\/www.ull.es\/grados\/estudios-clasicos\/wp-content\/uploads\/sites\/35\/2025\/04\/Slider_Estudios_Clasicos-768x248.jpg, https:\/\/www.ull.es\/grados\/estudios-clasicos\/wp-content\/uploads\/sites\/35\/2025\/04\/Slider_Estudios_Clasicos.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(max-width: 1024px)\" \/>\n\n<source data-depicter-srcset=\"https:\/\/www.ull.es\/grados\/estudios-clasicos\/wp-content\/uploads\/sites\/35\/2025\/04\/Slider_Estudios_Clasicos.jpg, https:\/\/www.ull.es\/grados\/estudios-clasicos\/wp-content\/uploads\/sites\/35\/2025\/04\/Slider_Estudios_Clasicos-1920x620.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(min-width: 1025px)\" \/>\n<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-ken-burns=\"false\" data-tablet-ken-burns=\"false\" data-mobile-ken-burns=\"false\" alt=\"\" data-depicter-src=\"https:\/\/www.ull.es\/grados\/estudios-clasicos\/wp-content\/uploads\/sites\/35\/2025\/04\/Slider_Estudios_Clasicos.jpg\" data-object-fit=\"custom,custom,\" data-object-position=\"center top,,\" data-crop=\"{'focalPoint':{'x':0.5,'y':0.5},'mediaSize':{'width':1393.54838709677414954057894647121429443359375,'height':450}}\" data-tablet-crop=\"{'focalPoint':{'x':0.5,'y':0.5},'mediaSize':{'width':2167.7419354838712024502456188201904296875,'height':700.0000000000001136868377216160297393798828125}}\" data-mobile-crop=\"{'focalPoint':{'x':0.5,'y':0.5},'mediaSize':{'width':1114.8387096774195015314035117626190185546875,'height':360}}\" \/>\n<\/picture>\n\n\n<h1 id=\"depicter-1-element-5\" class=\"depicter-element depicter-layer depicter-1-element-5\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 2\" data-local-id=\"element-5\" data-offset=\"x:226px;y:149px;origin:tl\" data-tablet-offset=\"x:322px;y:293px;origin:tl\" data-mobile-offset=\"x:6px;y:-113px;origin:tl\" data-width=\"749px,589px,348px\" data-height=\"auto,auto,auto\" data-responsive-scale=\"true,,\">Grado en <br>Estudios Cl\u00e1sicos<\/h1>\n\n<div id=\"depicter-1-element-10\" class=\"depicter-element depicter-layer depicter-1-element-10\" data-type=\"shape\" data-wrap=\"true\" data-name=\"Shape 1\" data-local-id=\"element-10\" data-offset=\"x:238px;y:350px;origin:tl\" data-tablet-offset=\"x:322px;y:418px;origin:tl\" data-mobile-offset=\"x:6px;y:15px;origin:tl\" data-width=\"708px,410px,348px\" data-height=\"8px,8px,8px\" data-responsive-scale=\"true,,\"><\/div>\n<\/div>\n<\/div>\n<script>\n(window.depicterSetups = window.depicterSetups || []).push(function(){\n\tDepicter.basePath = 'https:\/\/www.ull.es\/grados\/estudios-clasicos\/wp-content\/plugins\/depicter\/resources\/scripts\/player\/';\n\tconst dpPlayer = Depicter.setup('.depicter-1',\n\t\t{\"width\":[\"1200\",\"1024\",\"360\"],\"height\":[\"500\",\"700\",\"360\"],\"view\":\"basic\",\"keepAspectRatio\":true,\"preload\":0,\"layout\":\"fullwidth\",\"rtl\":false,\"initAfterAppear\":false,\"ajaxApiUrl\":\"https:\\\/\\\/www.ull.es\\\/grados\\\/estudios-clasicos\\\/wp-admin\\\/admin-ajax.php\",\"mouseSwipe\":true,\"touchSwipe\":true,\"useWatermark\":false}\n\t);\n});\n<\/script><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns alignfull stk-block-columns stk--hide-mobile stk-block stk-ceecbdc stk-block-background\" data-block-id=\"ceecbdc\"><style>.stk-ceecbdc {background-color:#360060 !important;padding-top:35px !important;padding-right:0px !important;padding-bottom:2px !important;padding-left:0px !important;margin-top:-20px !important;margin-bottom:70px !important;}.stk-ceecbdc:before{background-color:#360060 !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-ceecbdc-column alignfull\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-fc60a5d\" data-v=\"4\" data-block-id=\"fc60a5d\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-fc60a5d-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-fc60a5d-inner-blocks\">\n<div class=\"wp-block-stackable-spacer stk-block-spacer stk--no-padding stk-block stk-a3a8a68\" data-block-id=\"a3a8a68\"><style>.stk-a3a8a68 {height:0px !important;}<\/style><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns stk-block-columns stk-block stk-8b59b96\" data-block-id=\"8b59b96\"><style>.stk-8b59b96 .stk--block-align-8b59b96{align-items:flex-start !important;}.stk-8b59b96 {margin-top:25px !important;}.stk-8b59b96-column{--stk-columns-spacing:0px !important;--stk-column-gap:50px !important;}@media screen and (max-width: 767px){.stk-8b59b96-column{row-gap:var(--stk--preset--spacing--60, 2.25rem) !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk--block-align-8b59b96 stk-block-content stk-content-align stk-8b59b96-column\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-dbb7e15\" data-v=\"4\" data-block-id=\"dbb7e15\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-dbb7e15-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-dbb7e15-inner-blocks\">\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-689c258\" id=\"quejas-sugerencias-y-felicitaciones\" data-block-id=\"689c258\"><style>.stk-689c258 .stk-block-heading__text{color:#5c068c !important;}<\/style><h1 class=\"stk-block-heading__text has-text-color\">Quejas, sugerencias y felicitaciones<\/h1><\/div>\n\n\n\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-82992b2\" data-block-id=\"82992b2\"><p class=\"stk-block-text__text\">El Sistema de Garant\u00eda Interno de Calidad de la Facultad de Filolog\u00eda contempla un procedimiento para la gesti\u00f3n de incidencias, reclamaciones y sugerencias (PR_09) que pudieran formularse derivadas de la actividad del Centro.<\/p><\/div>\n\n\n\n<p>La persona que desee presentar una sugerencia o informar de una incidencia deber\u00e1 rellenar el impreso de&nbsp;<a href=\"https:\/\/drive.google.com\/open?id=1gsGsO33GZyV4wCHn019abqCYFJs4Tdyq\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">instancia general<\/a>&nbsp;disponible a trav\u00e9s de este enlace, o bien solicitarlo en la Secretar\u00eda o en la Conserjer\u00eda de la Facultad. Una vez cumplimentado, debe entregarse en la Secretar\u00eda de la Facultad.<\/p>\n\n\n\n<p>Tras ser recibido el documento que recoge la incidencia o sugerencia el Equipo de Direcci\u00f3n se encargar\u00e1 de iniciar el procedimiento con la finalidad de dar respuesta al interesado.<\/p>\n\n\n\n<p><a href=\"https:\/\/riull.ull.es\/xmlui\/bitstream\/handle\/915\/12607\/Acuerdo%2014_1_02_19.pdf?sequence=1&amp;isAllowed=y\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">Reglamento de Quejas, Sugerencias y Felicitaciones de la ULL<\/a><\/p>\n<\/div><\/div><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Quejas, sugerencias y felicitaciones El Sistema de Garant\u00eda Interno de Calidad de la Facultad de Filolog\u00eda contempla un procedimiento para la gesti\u00f3n de incidencias, reclamaciones y sugerencias (PR_09) que pudieran formularse derivadas de la actividad del Centro. La persona que desee presentar una sugerencia o informar de una incidencia deber\u00e1 rellenar el impreso de&nbsp;instancia general&nbsp;disponible&#8230;<\/p>","protected":false},"author":1,"featured_media":0,"parent":261,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/template-frontpage.php","meta":{"footnotes":""},"class_list":["post-264","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.ull.es\/grados\/estudios-clasicos\/fr\/wp-json\/wp\/v2\/pages\/264","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ull.es\/grados\/estudios-clasicos\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ull.es\/grados\/estudios-clasicos\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ull.es\/grados\/estudios-clasicos\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ull.es\/grados\/estudios-clasicos\/fr\/wp-json\/wp\/v2\/comments?post=264"}],"version-history":[{"count":10,"href":"https:\/\/www.ull.es\/grados\/estudios-clasicos\/fr\/wp-json\/wp\/v2\/pages\/264\/revisions"}],"predecessor-version":[{"id":1411,"href":"https:\/\/www.ull.es\/grados\/estudios-clasicos\/fr\/wp-json\/wp\/v2\/pages\/264\/revisions\/1411"}],"up":[{"embeddable":true,"href":"https:\/\/www.ull.es\/grados\/estudios-clasicos\/fr\/wp-json\/wp\/v2\/pages\/261"}],"wp:attachment":[{"href":"https:\/\/www.ull.es\/grados\/estudios-clasicos\/fr\/wp-json\/wp\/v2\/media?parent=264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}