{"id":42,"date":"2017-06-28T13:01:59","date_gmt":"2017-06-28T13:01:59","guid":{"rendered":"http:\/\/www.ull.es\/masteres\/desarrollo-y-gestion-de-recursos-humanos\/?page_id=42"},"modified":"2025-11-17T16:18:53","modified_gmt":"2025-11-17T16:18:53","slug":"coordinacion-docente","status":"publish","type":"page","link":"https:\/\/www.ull.es\/grados\/fisioterapia\/en\/informacion-academica\/coordinacion-docente\/","title":{"rendered":"Teaching coordination"},"content":{"rendered":"\n<div class=\"wp-block-stackable-columns alignfull stk-block-columns stk-block stk-8657999\" data-block-id=\"8657999\"><style>.stk-8657999 {padding-bottom:0px !important;margin-top:-30px !important;margin-bottom:0px !important;}@media screen and (max-width: 767px){.stk-8657999 {margin-top:-10% !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-8657999-column alignfull\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-914f03e\" data-v=\"4\" data-block-id=\"914f03e\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-914f03e-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-914f03e-inner-blocks\"><style id=\"depicter-1-inline-pre-css\">\n\n.depicter-1:not(.depicter-ready){\n\theight:450px;\n}\n\n\/***** Tablet *****\/\n@media screen and (max-width: 1024px){\n\n.depicter-1:not(.depicter-ready){\n\theight:700px;\n}\n\n}\n\/***** Mobile *****\/\n@media screen and (max-width: 767px){\n\n.depicter-1:not(.depicter-ready){\n\theight:360px;\n}\n\n}\n<\/style>\n<div id=\"depicter-1\" class=\"depicter depicter-document depicter-revert depicter-1 depicter-layout-fullwidth\">\n\n<div class=\"depicter-loading-container depicter-loading dotFlashing-dark\"><div class=\"depicter-loading-dark depicter-dot-flashing\">\n   <span><\/span>\n   <span><\/span>\n   <span><\/span>\n<\/div>\n<\/div>\n<div id=\"depicter-1-section-1\" class=\"depicter-section depicter-1-section-1\" data-name=\"Section 1\" data-type=\"section\" data-local-id=\"section-1\">\n<picture class=\"depicter-bg\">\n<source data-depicter-srcset=\"https:\/\/www.ull.es\/grados\/fisioterapia\/wp-content\/uploads\/sites\/28\/2025\/03\/Slider_Fisioterapia-768x248.jpg, https:\/\/www.ull.es\/grados\/fisioterapia\/wp-content\/uploads\/sites\/28\/2025\/03\/Slider_Fisioterapia.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(max-width: 1024px)\" \/>\n\n<source data-depicter-srcset=\"https:\/\/www.ull.es\/grados\/fisioterapia\/wp-content\/uploads\/sites\/28\/2025\/03\/Slider_Fisioterapia.jpg, https:\/\/www.ull.es\/grados\/fisioterapia\/wp-content\/uploads\/sites\/28\/2025\/03\/Slider_Fisioterapia-1920x620.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(min-width: 1025px)\" \/>\n<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-ken-burns=\"false\" data-tablet-ken-burns=\"false\" data-mobile-ken-burns=\"false\" alt=\"\" data-depicter-src=\"https:\/\/www.ull.es\/grados\/fisioterapia\/wp-content\/uploads\/sites\/28\/2025\/03\/Slider_Fisioterapia.jpg\" data-object-fit=\"custom,custom,\" data-object-position=\"center top,,\" data-crop=\"{&apos;focalPoint&apos;:{&apos;x&apos;:0.5,&apos;y&apos;:0.5},&apos;mediaSize&apos;:{&apos;width&apos;:1393.54838709677414954057894647121429443359375,&apos;height&apos;:450}}\" data-tablet-crop=\"{&apos;focalPoint&apos;:{&apos;x&apos;:0.5,&apos;y&apos;:0.5},&apos;mediaSize&apos;:{&apos;width&apos;:2167.7419354838712024502456188201904296875,&apos;height&apos;:700.0000000000001136868377216160297393798828125}}\" data-mobile-crop=\"{&apos;focalPoint&apos;:{&apos;x&apos;:0.5,&apos;y&apos;:0.5},&apos;mediaSize&apos;:{&apos;width&apos;:1114.8387096774195015314035117626190185546875,&apos;height&apos;:360}}\" \/>\n<\/picture>\n\n\n<h1 id=\"depicter-1-element-5\" class=\"depicter-element depicter-layer depicter-1-element-5\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 2\" data-local-id=\"element-5\" data-offset=\"x:118px;y:175px;origin:tl\" data-tablet-offset=\"x:306px;y:304px;origin:tl\" data-mobile-offset=\"x:45px;y:-105px;origin:tl\" data-width=\"906px,413px,348px\" data-height=\"auto,auto,auto\" data-responsive-scale=\"true,,\">Grado en Fisioterapia<\/h1>\n\n<div id=\"depicter-1-element-10\" class=\"depicter-element depicter-layer depicter-1-element-10\" data-type=\"shape\" data-wrap=\"true\" data-name=\"Shape 1\" data-local-id=\"element-10\" data-offset=\"x:129px;y:276px;origin:tl\" data-tablet-offset=\"x:306px;y:356px;origin:tl\" data-mobile-offset=\"x:45px;y:0px;origin:tl\" data-width=\"871px,401px,236px\" data-height=\"8px,8px,8px\" data-responsive-scale=\"true,,\"><\/div>\n<\/div>\n<\/div>\n<script>\n(window.depicterSetups = window.depicterSetups || []).push(function(){\n\tDepicter.basePath = 'https:\/\/www.ull.es\/grados\/fisioterapia\/wp-content\/plugins\/depicter\/resources\/scripts\/player\/';\n\tconst dpPlayer = Depicter.setup('.depicter-1',\n\t\t{\"width\":[\"1200\",\"1024\",\"360\"],\"height\":[\"450\",\"700\",\"360\"],\"view\":\"basic\",\"keepAspectRatio\":true,\"preload\":0,\"layout\":\"fullwidth\",\"rtl\":false,\"initAfterAppear\":false,\"ajaxApiUrl\":\"https:\\\/\\\/www.ull.es\\\/grados\\\/fisioterapia\\\/wp-admin\\\/admin-ajax.php\",\"mouseSwipe\":true,\"touchSwipe\":true,\"useWatermark\":false}\n\t);\n});\n<\/script><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns alignfull stk-block-columns stk--hide-mobile stk-block stk-ceecbdc stk-block-background\" data-block-id=\"ceecbdc\"><style>.stk-ceecbdc {background-color:#360060 !important;padding-top:35px !important;padding-right:0px !important;padding-bottom:2px !important;padding-left:0px !important;margin-top:-20px !important;margin-bottom:70px !important;}.stk-ceecbdc:before{background-color:#360060 !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-ceecbdc-column alignfull\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-fc60a5d\" data-v=\"4\" data-block-id=\"fc60a5d\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-fc60a5d-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-fc60a5d-inner-blocks\">\n<div class=\"wp-block-stackable-spacer stk-block-spacer stk--no-padding stk-block stk-a3a8a68\" data-block-id=\"a3a8a68\"><style>.stk-a3a8a68 {height:0px !important;}<\/style><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns stk-block-columns stk-block stk-8b59b96\" data-block-id=\"8b59b96\"><style>.stk-8b59b96 .stk--block-align-8b59b96{align-items:flex-start !important;}.stk-8b59b96 {margin-top:25px !important;}.stk-8b59b96-column{--stk-columns-spacing:0px !important;--stk-column-gap:50px !important;}@media screen and (max-width: 767px){.stk-8b59b96-column{row-gap:var(--stk--preset--spacing--60, 2.25rem) !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk--block-align-8b59b96 stk-block-content stk-content-align stk-8b59b96-column\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-dbb7e15\" data-v=\"4\" data-block-id=\"dbb7e15\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-dbb7e15-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-dbb7e15-inner-blocks\">\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-689c258\" id=\"coordinacion-docente\" data-block-id=\"689c258\"><style>.stk-689c258 .stk-block-heading__text{color:#5c068c !important;}<\/style><h1 class=\"stk-block-heading__text has-text-color\">Coordinaci\u00f3n docente<\/h1><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">El Equipo de Direcci\u00f3n del Centro se encarga de:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Elaborar los horarios y el calendario de ex\u00e1menes<\/li>\n\n\n\n<li>Elaborar los grupos para la realizaci\u00f3n de las distintas actividades, de forma coordinada en todas las asignaturas del curso<\/li>\n\n\n\n<li>Asignar aulas, sala de demostraciones y laboratorios para la realizaci\u00f3n de las distintas actividades programadas (para esta tarea se cuenta con la colaboraci\u00f3n de un coordinador de espacios)<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">La Comisi\u00f3n de Titulaci\u00f3n del Centro se encarga de:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Establecer los mecanismos de coordinaci\u00f3n horizontal y vertical de todos los aspectos involucrados en la puesta en marcha, seguimiento y evaluaci\u00f3n del t\u00edtulo de Grado.<\/li>\n\n\n\n<li>Revisar las gu\u00edas docentes de todas las asignaturas del plan de estudios comprobando los contenidos y la correspondencia con las competencias de la titulaci\u00f3n.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">La Comisi\u00f3n de Pr\u00e1cticas del Centro, en la que est\u00e1n integrados todos los coordinadores de las asignaturas de pr\u00e1cticas cl\u00ednicas, se encarga de:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Planificar las pr\u00e1cticas cl\u00ednicas.<\/li>\n\n\n\n<li>Realizar la convocatoria de pr\u00e1cticas cl\u00ednicas.<\/li>\n\n\n\n<li>Elaborar los grupos y asignar alumnos a los mismos.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">La Comisi\u00f3n de Movilidad del Centro, en la que est\u00e1n integrados los coordinadores de los programas de movilidad nacional e internacional, se encargan de:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Desarrollar las actividades de promoci\u00f3n de la movilidad<\/li>\n\n\n\n<li>Obtener informaci\u00f3n sobre el desarrollo y resultados de los programas de movilidad<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Los coordinadores de asignaturas se encargan de:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Elaborar la gu\u00eda docente de la asignatura, acordando con el resto del equipo docente los contenidos, la metodolog\u00eda y los criterios de evaluaci\u00f3n de la asignatura.<\/li>\n\n\n\n<li>Convocar las reuniones con el equipo docente de la asignatura.<\/li>\n\n\n\n<li>Coordinar la asignatura, adecuando los contenidos y la temporalizaci\u00f3n de las distintas actividades.<\/li>\n\n\n\n<li>Planificar las pr\u00e1cticas cl\u00ednicas en el caso de que est\u00e9n incluidas en la asignatura.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/drive.google.com\/file\/d\/1vq58TzbNrfJRmDZ_yeBpXvJQ6YFkQKX5\/view?usp=sharing\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">Relaci\u00f3n de Profesores Coordinadores de Asignaturas<\/a><\/p>\n<\/div><\/div><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Teaching Coordination The Center&#039;s Management Team is responsible for: The Center&#039;s Degree Committee is responsible for: The Center&#039;s Clinical Practice Committee, which includes all the coordinators of the clinical practice subjects, is responsible for: The Center&#039;s Mobility Committee, which includes\u2026<\/p>","protected":false},"author":1,"featured_media":0,"parent":252,"menu_order":6,"comment_status":"closed","ping_status":"closed","template":"templates\/template-frontpage.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-42","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.ull.es\/grados\/fisioterapia\/en\/wp-json\/wp\/v2\/pages\/42","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ull.es\/grados\/fisioterapia\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ull.es\/grados\/fisioterapia\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ull.es\/grados\/fisioterapia\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ull.es\/grados\/fisioterapia\/en\/wp-json\/wp\/v2\/comments?post=42"}],"version-history":[{"count":17,"href":"https:\/\/www.ull.es\/grados\/fisioterapia\/en\/wp-json\/wp\/v2\/pages\/42\/revisions"}],"predecessor-version":[{"id":963,"href":"https:\/\/www.ull.es\/grados\/fisioterapia\/en\/wp-json\/wp\/v2\/pages\/42\/revisions\/963"}],"up":[{"embeddable":true,"href":"https:\/\/www.ull.es\/grados\/fisioterapia\/en\/wp-json\/wp\/v2\/pages\/252"}],"wp:attachment":[{"href":"https:\/\/www.ull.es\/grados\/fisioterapia\/en\/wp-json\/wp\/v2\/media?parent=42"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}