{"id":840,"date":"2017-06-28T12:47:36","date_gmt":"2017-06-28T12:47:36","guid":{"rendered":"http:\/\/www.ull.es\/masteres\/desarrollo-y-gestion-de-recursos-humanos\/?page_id=18"},"modified":"2025-11-17T08:32:39","modified_gmt":"2025-11-17T08:32:39","slug":"apoyo-y-orientacion","status":"publish","type":"page","link":"https:\/\/www.ull.es\/grados\/nutricion-humana-dietetica\/en\/informacion-academica\/apoyo-y-orientacion\/","title":{"rendered":"Support and guidance"},"content":{"rendered":"\n<div class=\"wp-block-stackable-columns alignfull stk-block-columns stk-block stk-8657999\" data-block-id=\"8657999\"><style>.stk-8657999 {padding-bottom:0px !important;margin-top:-30px !important;margin-bottom:0px !important;}@media screen and (max-width: 767px){.stk-8657999 {margin-top:-10% !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-8657999-column alignfull\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-914f03e\" data-v=\"4\" data-block-id=\"914f03e\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-914f03e-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-914f03e-inner-blocks\"><style id=\"depicter-1-inline-pre-css\">\n\n.depicter-1:not(.depicter-ready){\n\theight:500px;\n}\n\n\/***** Tablet *****\/\n@media screen and (max-width: 1024px){\n\n.depicter-1:not(.depicter-ready){\n\theight:700px;\n}\n\n}\n\/***** Mobile *****\/\n@media screen and (max-width: 767px){\n\n.depicter-1:not(.depicter-ready){\n\theight:360px;\n}\n\n}\n<\/style>\n<div id=\"depicter-1\" class=\"depicter depicter-document depicter-revert depicter-1 depicter-layout-fullwidth\">\n\n<div class=\"depicter-loading-container depicter-loading dotFlashing-dark\"><div class=\"depicter-loading-dark depicter-dot-flashing\">\n   <span><\/span>\n   <span><\/span>\n   <span><\/span>\n<\/div>\n<\/div>\n<div id=\"depicter-1-section-1\" class=\"depicter-section depicter-1-section-1\" data-name=\"Section 1\" data-type=\"section\" data-local-id=\"section-1\">\n<picture class=\"depicter-bg\">\n<source data-depicter-srcset=\"https:\/\/www.ull.es\/grados\/nutricion-humana-dietetica\/wp-content\/uploads\/sites\/48\/2025\/03\/Slider_Nutricion-768x248.jpg, https:\/\/www.ull.es\/grados\/nutricion-humana-dietetica\/wp-content\/uploads\/sites\/48\/2025\/03\/Slider_Nutricion.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(max-width: 1024px)\" \/>\n\n<source data-depicter-srcset=\"https:\/\/www.ull.es\/grados\/nutricion-humana-dietetica\/wp-content\/uploads\/sites\/48\/2025\/03\/Slider_Nutricion.jpg, https:\/\/www.ull.es\/grados\/nutricion-humana-dietetica\/wp-content\/uploads\/sites\/48\/2025\/03\/Slider_Nutricion-1920x620.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(min-width: 1025px)\" \/>\n<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-ken-burns=\"false\" data-tablet-ken-burns=\"false\" data-mobile-ken-burns=\"false\" alt=\"\" data-depicter-src=\"https:\/\/www.ull.es\/grados\/nutricion-humana-dietetica\/wp-content\/uploads\/sites\/48\/2025\/03\/Slider_Nutricion.jpg\" data-object-fit=\"custom,custom,\" data-object-position=\"center top,,\" data-crop=\"{&apos;focalPoint&apos;:{&apos;x&apos;:0.5,&apos;y&apos;:0.59999999999999997779553950749686919152736663818359375},&apos;mediaSize&apos;:{&apos;width&apos;:1792,&apos;height&apos;:578}}\" data-tablet-crop=\"{&apos;focalPoint&apos;:{&apos;x&apos;:0.5,&apos;y&apos;:0.5},&apos;mediaSize&apos;:{&apos;width&apos;:2167.7419354838712024502456188201904296875,&apos;height&apos;:700.0000000000001136868377216160297393798828125}}\" data-mobile-crop=\"{&apos;focalPoint&apos;:{&apos;x&apos;:0.5,&apos;y&apos;:0.5},&apos;mediaSize&apos;:{&apos;width&apos;:1114.8387096774195015314035117626190185546875,&apos;height&apos;:360}}\" \/>\n<\/picture>\n\n\n<h1 id=\"depicter-1-element-5\" class=\"depicter-element depicter-layer depicter-1-element-5\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 2\" data-local-id=\"element-5\" data-offset=\"x:87px;y:149px;origin:tl\" data-tablet-offset=\"x:232px;y:293px;origin:tl\" data-mobile-offset=\"x:6px;y:-136px;origin:tl\" data-width=\"1027px,589px,348px\" data-height=\"auto,auto,auto\" data-responsive-scale=\"true,,\">Grado en Nutrici\u00f3n y Diet\u00e9tica<\/h1>\n\n<div id=\"depicter-1-element-10\" class=\"depicter-element depicter-layer depicter-1-element-10\" data-type=\"shape\" data-wrap=\"true\" data-name=\"Shape 1\" data-local-id=\"element-10\" data-offset=\"x:77px;y:354px;origin:tl\" data-tablet-offset=\"x:232px;y:426px;origin:tl\" data-mobile-offset=\"x:6px;y:15px;origin:tl\" data-width=\"897px,555px,309px\" data-height=\"8px,8px,8px\" data-responsive-scale=\"true,,\"><\/div>\n<\/div>\n<\/div>\n<script>\n(window.depicterSetups = window.depicterSetups || []).push(function(){\n\tDepicter.basePath = 'https:\/\/www.ull.es\/grados\/nutricion-humana-dietetica\/wp-content\/plugins\/depicter\/resources\/scripts\/player\/';\n\tconst dpPlayer = Depicter.setup('.depicter-1',\n\t\t{\"width\":[\"1200\",\"1024\",\"360\"],\"height\":[\"500\",\"700\",\"360\"],\"view\":\"basic\",\"keepAspectRatio\":true,\"preload\":0,\"layout\":\"fullwidth\",\"rtl\":false,\"initAfterAppear\":false,\"ajaxApiUrl\":\"https:\\\/\\\/www.ull.es\\\/grados\\\/nutricion-humana-dietetica\\\/wp-admin\\\/admin-ajax.php\",\"mouseSwipe\":true,\"touchSwipe\":true,\"useWatermark\":false}\n\t);\n});\n<\/script><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns alignfull stk-block-columns stk--hide-mobile stk-block stk-ceecbdc stk-block-background\" data-block-id=\"ceecbdc\"><style>.stk-ceecbdc {background-color:#360060 !important;padding-top:35px !important;padding-right:0px !important;padding-bottom:2px !important;padding-left:0px !important;margin-top:-20px !important;margin-bottom:70px !important;}.stk-ceecbdc:before{background-color:#360060 !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-ceecbdc-column alignfull\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-fc60a5d\" data-v=\"4\" data-block-id=\"fc60a5d\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-fc60a5d-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-fc60a5d-inner-blocks\">\n<div class=\"wp-block-stackable-spacer stk-block-spacer stk--no-padding stk-block stk-a3a8a68\" data-block-id=\"a3a8a68\"><style>.stk-a3a8a68 {height:0px !important;}<\/style><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns stk-block-columns stk-block stk-8b59b96\" data-block-id=\"8b59b96\"><style>.stk-8b59b96 .stk--block-align-8b59b96{align-items:flex-start !important;}.stk-8b59b96 {margin-top:25px !important;}.stk-8b59b96-column{--stk-columns-spacing:0px !important;--stk-column-gap:50px !important;}@media screen and (max-width: 767px){.stk-8b59b96-column{row-gap:var(--stk--preset--spacing--60, 2.25rem) !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk--block-align-8b59b96 stk-block-content stk-content-align stk-8b59b96-column\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-dbb7e15\" data-v=\"4\" data-block-id=\"dbb7e15\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-dbb7e15-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-dbb7e15-inner-blocks\">\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-689c258\" id=\"apoyo-y-orientacion\" data-block-id=\"689c258\"><style>.stk-689c258 .stk-block-heading__text{color:#5c068c !important;}<\/style><h1 class=\"stk-block-heading__text has-text-color\">Apoyo y orientaci\u00f3n<\/h1><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Los centros de la Universidad de La Laguna ponen en marcha, cada curso acad\u00e9mico, los Planes de Orientaci\u00f3n y Acci\u00f3n Tutorial (POAT) a desarrollar en sus titulaciones para proporcionar a los estudiantes sistemas de apoyo y orientaci\u00f3n una vez matriculados. El actual POAT del Grado en Nutrici\u00f3n Humana y Diet\u00e9tica se basa en las&nbsp;<a href=\"https:\/\/drive.google.com\/file\/d\/1sR2_rc67b70HIYi0QaOtuXcz9PhIdqZa\/view?usp=drive_link\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">directrices<\/a>&nbsp;que la Universidad de La Laguna ha adoptado desde la aprobaci\u00f3n de la Ley Org\u00e1nica 6\/2001, de 21 de diciembre, de universidades (BOE, 24 de diciembre 2001) y suponen una actualizaci\u00f3n a las directrices que regulan los Planes de Orientaci\u00f3n y Acci\u00f3n Tutorial (POAT) aprobadas en Consejo de Gobierno el 31 de enero de 2012.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las actividades formativas, incluidas en el POAT, abordan diversas tem\u00e1ticas a trav\u00e9s de las que pretende facilitar al alumnado su toma de decisiones acad\u00e9mico-profesional en sus diferentes etapas (acogida e integraci\u00f3n en el centro y la universidad, orientaci\u00f3n a lo largo de la titulaci\u00f3n y para su incorporaci\u00f3n al mercado laboral), que le permita superar con \u00e9xito la titulaci\u00f3n y adaptarse a las nuevas demandas: estrategias de aprendizaje aut\u00f3nomo, trabajo en equipo, mejora de resultados de rendimiento acad\u00e9mico, resoluci\u00f3n de dificultades, informaci\u00f3n y asesoramiento sobre pr\u00e1cticas externas y trabajo fin de grado, orientaci\u00f3n sobre los programas de movilidad existentes, exigencias y caracter\u00edsticas del mercado laboral, etc.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al estar matriculado en la ULL el alumnado de la titulaci\u00f3n puede participar en el POAT de su centro, benefici\u00e1ndose de:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Las\u00a0<strong>actividades de formaci\u00f3n e informaci\u00f3n<\/strong>\u00a0proporcionadas a lo largo del curso, repartidas en los dos cuatrimestres.<\/li>\n\n\n\n<li>El\u00a0<strong>asesoramiento\u00a0<\/strong>del\u00a0profesorado-tutor, que le apoyar\u00e1 en sus inquietudes intelectuales, acad\u00e9micas y profesionales.<\/li>\n\n\n\n<li>El\u00a0<strong>asesoramiento\u00a0<\/strong>de\u00a0alumnado-mentor, estudiantes de la misma titulaci\u00f3n que realizan tareas de apoyo al desarrollo del POAT.<\/li>\n\n\n\n<li>Su reconocimiento en cr\u00e9ditos\u00a0<strong>ECTS \u2013 3<\/strong>\u00a0por curso acad\u00e9mico-, tal y como se recoge en el Reglamento de Reconocimiento de Cr\u00e9ditos por Participaci\u00f3n en Actividades Universitarias en Ense\u00f1anzas Oficiales de Grado.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Los&nbsp;<strong>objetivos&nbsp;<\/strong>a lograr a trav\u00e9s del POAT son los siguientes:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Que el alumnado se integre y se adapte a la Universidad, a la Facultad, a la titulaci\u00f3n y al grupo.<\/li>\n\n\n\n<li>Que el alumnado adquiera las competencias para el aprendizaje aut\u00f3nomo y un \u00f3ptimo rendimiento acad\u00e9mico.<\/li>\n\n\n\n<li>Que el alumnado adquiera las competencias transversales importantes en relaci\u00f3n al perfil profesional de la titulaci\u00f3n que cursa.<\/li>\n\n\n\n<li>Que el alumnado cuente con la motivaci\u00f3n suficiente para alcanzar los resultados de aprendizaje previstos.<\/li>\n\n\n\n<li>Que el alumnado defina su itinerario formativo y construya su proyecto acad\u00e9mico profesional.<\/li>\n\n\n\n<li>Que el alumnado adquiera las competencias para su desarrollo profesional y para la inserci\u00f3n en un mercado laboral cambiante.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Los alumnos de nuevo ingreso ser\u00e1n autom\u00e1ticamente matriculados al comienzo de su primer curso acad\u00e9mico en el Aula Virtual del POAT de la Facultad a trav\u00e9s de la&nbsp;<a href=\"https:\/\/wp.ull.es\/udv\/\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">Unidad para la Docencia Virtual<\/a>&nbsp;de la ULL. Tanto los profesores-tutores, como los mentores como la coordinaci\u00f3n del POAT, se pondr\u00e1n en contacto con ellos a trav\u00e9s de dicho aula y ellos podr\u00e1n consultar cualquier duda, as\u00ed como el desarrollo del programa mediante consulta en el aula virtual.<\/p>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns stk-block-columns stk-block stk-1q2bmlz\" data-block-id=\"1q2bmlz\"><style>.stk-1q2bmlz .stk--block-align-1q2bmlz{align-items:flex-start !important;}.stk-1q2bmlz {margin-top:25px !important;}.stk-1q2bmlz-column{--stk-columns-spacing:0px !important;--stk-column-gap:50px !important;}@media screen and (max-width: 767px){.stk-1q2bmlz-column{row-gap:var(--stk--preset--spacing--60, 2.25rem) !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk--block-align-1q2bmlz stk-block-content stk-content-align stk-1q2bmlz-column\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-soh82a4\" data-v=\"4\" data-block-id=\"soh82a4\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-soh82a4-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-soh82a4-inner-blocks\">\n<details class=\"wp-block-stackable-accordion stk-block-accordion stk-inner-blocks stk-block-content stk-block stk-7c390cd is-style-default\" id=\"organizacion-poat\" data-block-id=\"7c390cd\"><style>.stk-7c390cd {border-style:solid !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;margin-bottom:11px !important;}<\/style>\n<summary class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-c927805 stk--container-small stk-block-accordion__heading\" data-v=\"4\" data-block-id=\"c927805\"><style>.stk-c927805 {padding-top:2px !important;padding-right:2px !important;padding-bottom:2px !important;padding-left:2px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-c927805-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-c927805-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-7935446\" data-block-id=\"7935446\"><style>.stk-7935446 .stk-inner-blocks{gap:39px !important;}@media screen and (max-width: 1023px){.stk-7935446 .stk-inner-blocks{gap:39px !important;}}@media screen and (max-width: 767px){.stk-7935446 .stk-inner-blocks{gap:39px !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-icon stk-block-icon stk-block stk-9a468d5\" data-block-id=\"9a468d5\"><style>.stk-9a468d5 .stk--svg-wrapper .stk--inner-svg svg:last-child{height:25px !important;width:25px !important;}.stk-9a468d5 .stk--svg-wrapper .stk--inner-svg svg:last-child, .stk-9a468d5 .stk--svg-wrapper .stk--inner-svg svg:last-child :is(g, path, rect, polygon, ellipse){fill:#5c068c !important;}<\/style><span class=\"stk--svg-wrapper stk--has-icon2\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-9a468d5\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-9-a-468-d-5-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-9-a-468-d-5-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 640 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M144 0a80 80 0 1 1 0 160A80 80 0 1 1 144 0zM512 0a80 80 0 1 1 0 160A80 80 0 1 1 512 0zM0 298.7C0 239.8 47.8 192 106.7 192h42.7c15.9 0 31 3.5 44.6 9.7c-1.3 7.2-1.9 14.7-1.9 22.3c0 38.2 16.8 72.5 43.3 96c-.2 0-.4 0-.7 0H21.3C9.6 320 0 310.4 0 298.7zM405.3 320c-.2 0-.4 0-.7 0c26.6-23.5 43.3-57.8 43.3-96c0-7.6-.7-15-1.9-22.3c13.6-6.3 28.7-9.7 44.6-9.7h42.7C592.2 192 640 239.8 640 298.7c0 11.8-9.6 21.3-21.3 21.3H405.3zM224 224a96 96 0 1 1 192 0 96 96 0 1 1 -192 0zM128 485.3C128 411.7 187.7 352 261.3 352H378.7C452.3 352 512 411.7 512 485.3c0 14.7-11.9 26.7-26.7 26.7H154.7c-14.7 0-26.7-11.9-26.7-26.7z\"><\/path><\/svg><\/div><div class=\"stk--inner-svg stk--icon-2\" style=\"display:none\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-9a468d5\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-9-a-468-d-5-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-9-a-468-d-5-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 640 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M48 48h88c13.3 0 24-10.7 24-24s-10.7-24-24-24H32C14.3 0 0 14.3 0 32V136c0 13.3 10.7 24 24 24s24-10.7 24-24V48zM175.8 224a48 48 0 1 0 0-96 48 48 0 1 0 0 96zm-26.5 32C119.9 256 96 279.9 96 309.3c0 14.7 11.9 26.7 26.7 26.7h56.1c8-34.1 32.8-61.7 65.2-73.6c-7.5-4.1-16.2-6.4-25.3-6.4H149.3zm368 80c14.7 0 26.7-11.9 26.7-26.7c0-29.5-23.9-53.3-53.3-53.3H421.3c-9.2 0-17.8 2.3-25.3 6.4c32.4 11.9 57.2 39.5 65.2 73.6h56.1zm-89.4 0c-8.6-24.3-29.9-42.6-55.9-47c-3.9-.7-7.9-1-12-1H280c-4.1 0-8.1 .3-12 1c-26 4.4-47.3 22.7-55.9 47c-2.7 7.5-4.1 15.6-4.1 24c0 13.3 10.7 24 24 24H408c13.3 0 24-10.7 24-24c0-8.4-1.4-16.5-4.1-24zM464 224a48 48 0 1 0 0-96 48 48 0 1 0 0 96zm-80-32a64 64 0 1 0 -128 0 64 64 0 1 0 128 0zM504 48h88v88c0 13.3 10.7 24 24 24s24-10.7 24-24V32c0-17.7-14.3-32-32-32H504c-13.3 0-24 10.7-24 24s10.7 24 24 24zM48 464V376c0-13.3-10.7-24-24-24s-24 10.7-24 24V480c0 17.7 14.3 32 32 32H136c13.3 0 24-10.7 24-24s-10.7-24-24-24H48zm456 0c-13.3 0-24 10.7-24 24s10.7 24 24 24H608c17.7 0 32-14.3 32-32V376c0-13.3-10.7-24-24-24s-24 10.7-24 24v88H504z\"><\/path><\/svg><\/div><\/span><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-31863c1\" id=\"acceso\" data-block-id=\"31863c1\"><style>.stk-31863c1 .stk-block-heading__text{color:#000000 !important;font-weight:500 !important;font-family:\"ArgentumSans\", Sans-serif !important;}<\/style><h4 class=\"stk-block-heading__text has-text-color\"><span style=\"color: #000000;\" class=\"stk-highlight\">Organizaci\u00f3n del POAT<\/span><\/h4><\/div>\n<\/div><\/div>\n<\/div><\/div><\/summary>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-5222666 stk-block-accordion__content\" data-v=\"4\" data-block-id=\"5222666\"><style>.stk-5222666 {margin-top:-30px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-5222666-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-5222666-inner-blocks\">\n<p class=\"wp-block-paragraph\">En la planificaci\u00f3n del POAT se incluyen distintas actividades para ser desarrolladas con el alumnado de primer curso. Para la realizaci\u00f3n de dichas actividades se cuenta con la participaci\u00f3n de profesorado de la Facultad de Farmacia y de diferentes Servicios y Unidades de la ULL: Servicio de Informaci\u00f3n y Orientaci\u00f3n (SIO), Servicio de Tecnolog\u00edas de la Informaci\u00f3n y la Comunicaci\u00f3n (STIC), Vicerrectorado de Internalizaci\u00f3n, \u00c1reas de formaci\u00f3n y de Empleo de la FGULL, entre otros.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Conjunto de charlas o seminarios impartidas por expertos .\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/drive.google.com\/file\/d\/15VsgzAnzfEK2k0PfLcn3wtMO_0mRAaXz\/view?usp=sharing\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">Plan POAT 2024-25<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/drive.google.com\/file\/d\/13tF4VBuN1E6tTlNCodWWRsorNZ7zF2CG\/view?usp=sharing\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">Memoria POAT 2023-24<\/a><\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Reuniones de cada profesorado-tutor con su grupo de alumnado repartidas a lo largo del curso.<\/li>\n\n\n\n<li>Reuniones de cada alumnado-mentor con su grupo de alumnado repartidas a lo largo del curso.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Aquellos alumnos que consigan superar el 80% de asistencia entre todas las actividades arriba mencionadas podr\u00e1n solicitar el certificado para la obtenci\u00f3n de los 3 \u2013 ECTS.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Tutor\u00edas<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Durante su primer curso acad\u00e9mico, el alumnado recibir\u00e1 el asesoramiento del profesorado-tutor asignado, que le apoyar\u00e1 en sus inquietudes intelectuales, acad\u00e9micas y profesionales<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">TUTORES DE CARRERA<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Curso 2020-2021\n<ul class=\"wp-block-list\">\n<li>Jos\u00e9 Luis Ravelo Socas\u00a0<a href=\"mailto:jravelo@ull.es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">jravelo@ull.es<\/a><\/li>\n\n\n\n<li>Carmen M\u00aa Rodr\u00edguez P\u00e9rez\u00a0<a href=\"mailto:cmrodri@ull.es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">cmrodri@ull.es<\/a><\/li>\n\n\n\n<li>\u00c1ngel J. Guti\u00e9rrez Fern\u00e1ndez\u00a0<a href=\"mailto:ajguti@ull.es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">ajguti@ull.es<\/a><\/li>\n\n\n\n<li>Jos\u00e9 E. Pi\u00f1ero Barroso\u00a0<a href=\"mailto:jpinero@ull.es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">jpinero@ull.es<\/a><\/li>\n\n\n\n<li>Carmen Rubio Armend\u00e1riz\u00a0<a href=\"mailto:crubio@ull.es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">crubio@ull.es<\/a><\/li>\n\n\n\n<li>Carolina P\u00e9rez Reyes\u00a0<a href=\"mailto:cpreyes@ull.es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">cpreyes@ull.es<\/a><\/li>\n\n\n\n<li>Guadalberto Hern\u00e1ndez Hern\u00e1ndez\u00a0<a href=\"mailto:ghernan@ull.es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">ghernan@ull.es<\/a><\/li>\n\n\n\n<li>Javier R. Castro Hern\u00e1ndez<a href=\"mailto:jrchdez@ull.es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">\u00a0jrchdez@ull.es<\/a><\/li>\n\n\n\n<li>Ana B. Lago Blanco\u00a0<a href=\"mailto:alagobla@ull.es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">alagobla@ull.es<\/a><\/li>\n\n\n\n<li>Elena M\u00aa Rodr\u00edguez Rodr\u00edguez\u00a0<a href=\"mailto:emrguez@ull.es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">emrguez@ull.es<\/a><\/li>\n\n\n\n<li>Atteneri L\u00f3pez Arencibia\u00a0<a href=\"mailto:atlopez@ull.edu.es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">atlopez@ull.es<\/a><\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Curso 2021-2022\n<ul class=\"wp-block-list\">\n<li>Carmen M\u00aa Rodr\u00edguez P\u00e9rez\u00a0<a href=\"mailto:cmrodri@ull.es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">cmrodri@ull.es<\/a><\/li>\n\n\n\n<li>\u00c1ngel J. Guti\u00e9rrez Fern\u00e1ndez\u00a0<a href=\"mailto:ajguti@ull.es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">ajguti@ull.es<\/a><\/li>\n\n\n\n<li>Jos\u00e9 E. Pi\u00f1ero Barroso\u00a0<a href=\"mailto:jpinero@ull.es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">jpinero@ull.es<\/a><\/li>\n\n\n\n<li>Javier R. Castro Hern\u00e1ndez<a href=\"mailto:jrchdez@ull.es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">\u00a0jrchdez@ull.es<\/a><\/li>\n\n\n\n<li>Ana B. Lago Blanco\u00a0<a href=\"mailto:alagobla@ull.es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">alagobla@ull.es<\/a><\/li>\n\n\n\n<li>Atteneri L\u00f3pez Arencibia\u00a0<a href=\"mailto:atlopez@ull.es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">atlopez@ull.es<\/a><\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Curso 2022-2023\n<ul class=\"wp-block-list\">\n<li>Carmen M\u00aa Rodr\u00edguez P\u00e9rez\u00a0<a href=\"mailto:cmrodri@ull.es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">cmrodri@ull.es<\/a><\/li>\n\n\n\n<li>\u00c1ngel J. Guti\u00e9rrez Fern\u00e1ndez\u00a0<a href=\"mailto:ajguti@ull.es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">ajguti@ull.es<\/a><\/li>\n\n\n\n<li>Jos\u00e9 E. Pi\u00f1ero Barroso\u00a0<a href=\"mailto:jpinero@ull.es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">jpinero@ull.es<\/a><\/li>\n\n\n\n<li>Nereida Mar\u00eda Rancel Rodr\u00edguez<\/li>\n\n\n\n<li>Natalia Dom\u00ednguez Reyes<\/li>\n\n\n\n<li>Leandro Jes\u00fas de Le\u00f3n Guerra<\/li>\n\n\n\n<li>Atteneri L\u00f3pez Arencibia\u00a0<a href=\"mailto:atlopez@ull.es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">atlopez@ull.es<\/a><\/li>\n\n\n\n<li>Mar\u00eda Reyes Batlle\u00a0<a href=\"mailto:mreyesba@ull.es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">mreyesba@ull.es<\/a><\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Curso 2023-2024\n<ul class=\"wp-block-list\">\n<li>Miriam Candelaria Rodr\u00edguez Gonz\u00e1lez<\/li>\n\n\n\n<li>Carmen M\u00aa Rodr\u00edguez P\u00e9rez\u00a0<a href=\"mailto:cmrodri@ull.es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">cmrodri@ull.es<\/a><\/li>\n\n\n\n<li>\u00c1ngel J. Guti\u00e9rrez Fern\u00e1ndez\u00a0<a href=\"mailto:ajguti@ull.es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">ajguti@ull.es<\/a><\/li>\n\n\n\n<li>Jos\u00e9 E. Pi\u00f1ero Barroso\u00a0<a href=\"mailto:jpinero@ull.es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">jpinero@ull.es<\/a><\/li>\n\n\n\n<li>Nereida Mar\u00eda Rancel Rodr\u00edguez\u00a0<a href=\"mailto:nrrodri@ull.es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">nrrodri@ull.es<\/a><\/li>\n\n\n\n<li>Natalia Dom\u00ednguez Reyes\u00a0<a href=\"mailto:ndomrey@ull.es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">ndomrey@ull.es<\/a><\/li>\n\n\n\n<li>Leandro Jes\u00fas de Le\u00f3n Guerra\u00a0<a href=\"mailto:lleongue@ull.es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">lleongue@ull.es<\/a><\/li>\n\n\n\n<li>Atteneri L\u00f3pez Arencibia\u00a0<a href=\"mailto:atlopez@ull.es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">atlopez@ull.es<\/a><\/li>\n\n\n\n<li>Mar\u00eda Reyes Batlle\u00a0<a href=\"mailto:mreyesba@ull.es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">mreyesba@ull.es<\/a><\/li>\n\n\n\n<li>Itahisa Marcelino Rodr\u00edguez\u00a0<a href=\"mailto:imarceli@ull.es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">imarceli@ull.es<\/a><\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Curso 2024-2025\n<ul class=\"wp-block-list\">\n<li>Miriam Candelaria Rodr\u00edguez Gonz\u00e1lez<\/li>\n\n\n\n<li>Carmen M\u00aa Rodr\u00edguez P\u00e9rez\u00a0<a href=\"mailto:cmrodri@ull.es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">cmrodri@ull.es<\/a><\/li>\n\n\n\n<li>\u00c1ngel J. Guti\u00e9rrez Fern\u00e1ndez\u00a0<a href=\"mailto:ajguti@ull.es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">ajguti@ull.es<\/a><\/li>\n\n\n\n<li>Jos\u00e9 E. Pi\u00f1ero Barroso\u00a0<a href=\"mailto:jpinero@ull.es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">jpinero@ull.es<\/a><\/li>\n\n\n\n<li>Nereida Mar\u00eda Rancel Rodr\u00edguez\u00a0<a href=\"mailto:nrrodri@ull.es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">nrrodri@ull.es<\/a><\/li>\n\n\n\n<li>Leandro Jes\u00fas de Le\u00f3n Guerra<a href=\"mailto:lleongue@ull.es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">\u00a0lleongue@ull.es<\/a><\/li>\n\n\n\n<li>Atteneri L\u00f3pez Arencibia\u00a0<a href=\"mailto:atlopez@ull.es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">atlopez@ull.es<\/a><\/li>\n\n\n\n<li>Mar\u00eda Reyes Batlle\u00a0<a href=\"mailto:mreyesba@ull.es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">mreyesba@ull.es<\/a><\/li>\n\n\n\n<li>Itahisa Marcelino Rodr\u00edguez\u00a0<a href=\"mailto:imarceli@ull.es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">imarceli@ull.es<\/a><\/li>\n\n\n\n<li>Elena Ramos Trujillo\u00a0<a href=\"mailto:eramostr@ull.es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">eramostr@ull.es<\/a><\/li>\n\n\n\n<li>Beatriz Rodr\u00edguez Gald\u00f3n\u00a0<a href=\"mailto:bgaldon@ull.es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">bgaldon@ull.es<\/a><\/li>\n\n\n\n<li>Elena M\u00aa Rodr\u00edguez Rodr\u00edguez\u00a0<a href=\"mailto:emrguez@ull.es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">emrguez@ull.es<\/a><\/li>\n\n\n\n<li>Israel P\u00e9rez Vargas\u00a0<a href=\"mailto:ispeva@ull.es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">ispeva@ull.es<\/a><\/li>\n\n\n\n<li>Javier Rafael Castro Hern\u00e1ndez\u00a0<a href=\"mailto:jrchdez@ull.es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">jrchdez@ull.es<\/a><\/li>\n\n\n\n<li>Jes\u00fas de las Heras Roger\u00a0<a href=\"mailto:jherasro@ull.es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">jherasro@ull.es<\/a><\/li>\n\n\n\n<li>N\u00e9stor Ben\u00edtez Brito\u00a0<a href=\"mailto:nbenitez@ull.es\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">nbenitez@ull.es<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Charlas\/Seminarios<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">El desarrollo de las actividades para todos los cursos se lleva a cabo seg\u00fan lo planificado al comienzo de curso. Dichas actividades se reparten entre los dos cuatrimestres en las fechas y horarios establecidos en el horario semanal de la titulaci\u00f3n, y su funci\u00f3n ser\u00e1 tanto la orientaci\u00f3n acad\u00e9mica, como de adaptaci\u00f3n al entorno universitario o de orientaci\u00f3n profesional. Las actividades ser\u00e1n comunicadas a trav\u00e9s del Aula Virtual y mediante carteler\u00eda en la facultad y ser\u00e1n planificadas de manera que se atienda a las necesidad del perfil del alumnado de nuevo ingreso.&nbsp;&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Mentor\u00edas<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Las mentor\u00edas ser\u00e1n llevadas a cabo por estudiantes de \u00faltimos cursos de grado, de manera que aconsejen al alumnado de nuevo ingreso para facilitar la transici\u00f3n al entorno universitario. El programa de mentor\u00edas consiste en un seguimiento del alumnado por parte de los mentores, a trav\u00e9s de una serie de reuniones programadas donde pondr\u00e1n a disposici\u00f3n del estudiante su experiencia, de manera que se cree un v\u00ednculo m\u00e1s fluido entre ambos, facilitando as\u00ed la labor del profesorado-tutor.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">EQUIPO MENTOR<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Este grupo de trabajo se crea por primera vez en el curso acad\u00e9mico 21\/22 y pretende ser un programa de acompa\u00f1amiento del alumnado de nuevo ingreso durante su primer curso. El alumnado-mentor tendr\u00e1 un grupo de alumnos asignado con los que tendr\u00e1 una serie de reuniones informativas repartidas entre ambos cuatrimestres. Los miembros de dicho grupo de trabajo se actualizan cada a\u00f1o y por curso acad\u00e9mico que los estudiantes desarrollen la figura de mentor reciben ECTS \u2013 1.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Miembros Equipo Mentor 24\/25<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Alberto Gonz\u00e1lez Diez<\/li>\n\n\n\n<li>Ana Miranda de Z\u00e1rate<\/li>\n\n\n\n<li>Andrea Pinto<\/li>\n\n\n\n<li>Ane Madariaga<\/li>\n\n\n\n<li>Antonio Ballester Gonz\u00e1lez<\/li>\n\n\n\n<li>Belinda Flores Caro<\/li>\n\n\n\n<li>Bentor Rodr\u00edguez Farrais<\/li>\n\n\n\n<li>Carlota Chinea Almeida<\/li>\n\n\n\n<li>Claudia Alejandra C\u00e1ceres G\u00f3mez<\/li>\n\n\n\n<li>Irene Santana P\u00e9rez<\/li>\n\n\n\n<li>Luc\u00eda de la Caridad Mallo Vel\u00e1zquez<\/li>\n\n\n\n<li>Paola Rom\u00e1n Sosa<\/li>\n\n\n\n<li>Ver\u00f3nica Go\u00f1i Rivero<\/li>\n\n\n\n<li>Yolanda Caballero Rodr\u00edguez<\/li>\n<\/ul>\n<\/div><\/div><\/div>\n<\/details>\n\n\n\n<details class=\"wp-block-stackable-accordion stk-block-accordion stk-inner-blocks stk-block-content stk-block stk-88a7c9c is-style-default\" id=\"normativa\" data-block-id=\"88a7c9c\"><style>.stk-88a7c9c {border-style:solid !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;margin-bottom:10px !important;}<\/style>\n<summary class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-27019df stk--container-small stk-block-accordion__heading\" data-v=\"4\" data-block-id=\"27019df\"><style>.stk-27019df {padding-top:2px !important;padding-right:2px !important;padding-bottom:2px !important;padding-left:2px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-27019df-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-27019df-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-9c9ce7e\" data-block-id=\"9c9ce7e\"><style>.stk-9c9ce7e .stk-inner-blocks{gap:39px !important;}@media screen and (max-width: 1023px){.stk-9c9ce7e .stk-inner-blocks{gap:39px !important;}}@media screen and (max-width: 767px){.stk-9c9ce7e .stk-inner-blocks{gap:39px !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-icon stk-block-icon stk-block stk-61c8ad3\" data-block-id=\"61c8ad3\"><style>.stk-61c8ad3 .stk--svg-wrapper .stk--inner-svg svg:last-child{height:25px !important;width:25px !important;}.stk-61c8ad3 .stk--svg-wrapper .stk--inner-svg svg:last-child, .stk-61c8ad3 .stk--svg-wrapper .stk--inner-svg svg:last-child :is(g, path, rect, polygon, ellipse){fill:#5c068c !important;}<\/style><span class=\"stk--svg-wrapper stk--has-icon2\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-61c8ad3\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-61-c-8-ad-3-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-61-c-8-ad-3-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M96 0C43 0 0 43 0 96V416c0 53 43 96 96 96H384h32c17.7 0 32-14.3 32-32s-14.3-32-32-32V384c17.7 0 32-14.3 32-32V32c0-17.7-14.3-32-32-32H384 96zm0 384H352v64H96c-17.7 0-32-14.3-32-32s14.3-32 32-32zm32-240c0-8.8 7.2-16 16-16H336c8.8 0 16 7.2 16 16s-7.2 16-16 16H144c-8.8 0-16-7.2-16-16zm16 48H336c8.8 0 16 7.2 16 16s-7.2 16-16 16H144c-8.8 0-16-7.2-16-16s7.2-16 16-16z\"><\/path><\/svg><\/div><div class=\"stk--inner-svg stk--icon-2\" style=\"display:none\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-61c8ad3\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-61-c-8-ad-3-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-61-c-8-ad-3-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 576 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M249.6 471.5c10.8 3.8 22.4-4.1 22.4-15.5V78.6c0-4.2-1.6-8.4-5-11C247.4 52 202.4 32 144 32C93.5 32 46.3 45.3 18.1 56.1C6.8 60.5 0 71.7 0 83.8V454.1c0 11.9 12.8 20.2 24.1 16.5C55.6 460.1 105.5 448 144 448c33.9 0 79 14 105.6 23.5zm76.8 0C353 462 398.1 448 432 448c38.5 0 88.4 12.1 119.9 22.6c11.3 3.8 24.1-4.6 24.1-16.5V83.8c0-12.1-6.8-23.3-18.1-27.6C529.7 45.3 482.5 32 432 32c-58.4 0-103.4 20-123 35.6c-3.3 2.6-5 6.8-5 11V456c0 11.4 11.7 19.3 22.4 15.5z\"><\/path><\/svg><\/div><\/span><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-bcb6d4e\" id=\"span-style-color-000000-class-stk-highlight-normativa-span\" data-block-id=\"bcb6d4e\"><style>.stk-bcb6d4e .stk-block-heading__text{color:#000000 !important;font-weight:500 !important;font-family:\"ArgentumSans\", Sans-serif !important;}<\/style><h4 class=\"stk-block-heading__text has-text-color\"><span style=\"color: #000000;\" class=\"stk-highlight\">Normativa<\/span><\/h4><\/div>\n<\/div><\/div>\n<\/div><\/div><\/summary>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-76d605c stk-block-accordion__content\" data-v=\"4\" data-block-id=\"76d605c\"><style>.stk-76d605c {margin-top:-30px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-76d605c-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-76d605c-inner-blocks\">\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/drive.google.com\/file\/d\/1A7KsXZx0wN_ogokGaZmnQps9n_y1BBvk\/view\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">Reglamento de Reconocimiento de Cr\u00e9ditos por Participaci\u00f3n en Actividades Universitarias en Ense\u00f1anzas Oficiales de Grado<\/a>.<\/li>\n\n\n\n<li><a href=\"https:\/\/drive.google.com\/file\/d\/1sR2_rc67b70HIYi0QaOtuXcz9PhIdqZa\/view?usp=drive_link\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">Directrices<\/a>\u00a0<a href=\"https:\/\/drive.google.com\/file\/d\/1sR2_rc67b70HIYi0QaOtuXcz9PhIdqZa\/view?usp=drive_link\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">que la Universidad de La Laguna ha adoptado desde la aprobaci\u00f3n de la Ley Org\u00e1nica 6\/2001, de 21 de diciembre, de universidades (BOE, 24 de diciembre 2001) y suponen una actualizaci\u00f3n a las directrices que regulan los Planes de Orientaci\u00f3n y Acci\u00f3n Tutorial (POAT) aprobadas en Consejo de Gobierno el 31 de enero de 2012.\u00a0<\/a><\/li>\n<\/ul>\n<\/div><\/div><\/div>\n<\/details>\n<\/div><\/div><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Support and Guidance: Each academic year, the centers of the University of La Laguna implement Guidance and Tutoring Action Plans (POATs) for their degree programs to provide students with support and guidance systems once enrolled. The current POAT for the Bachelor&#039;s Degree in Human Nutrition and Dietetics is based on\u2026<\/p>","protected":false},"author":9,"featured_media":0,"parent":252,"menu_order":7,"comment_status":"closed","ping_status":"closed","template":"templates\/template-frontpage.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-840","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.ull.es\/grados\/nutricion-humana-dietetica\/en\/wp-json\/wp\/v2\/pages\/840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ull.es\/grados\/nutricion-humana-dietetica\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ull.es\/grados\/nutricion-humana-dietetica\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ull.es\/grados\/nutricion-humana-dietetica\/en\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ull.es\/grados\/nutricion-humana-dietetica\/en\/wp-json\/wp\/v2\/comments?post=840"}],"version-history":[{"count":16,"href":"https:\/\/www.ull.es\/grados\/nutricion-humana-dietetica\/en\/wp-json\/wp\/v2\/pages\/840\/revisions"}],"predecessor-version":[{"id":1300,"href":"https:\/\/www.ull.es\/grados\/nutricion-humana-dietetica\/en\/wp-json\/wp\/v2\/pages\/840\/revisions\/1300"}],"up":[{"embeddable":true,"href":"https:\/\/www.ull.es\/grados\/nutricion-humana-dietetica\/en\/wp-json\/wp\/v2\/pages\/252"}],"wp:attachment":[{"href":"https:\/\/www.ull.es\/grados\/nutricion-humana-dietetica\/en\/wp-json\/wp\/v2\/media?parent=840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}