{"id":518,"date":"2017-10-11T10:05:01","date_gmt":"2017-10-11T10:05:01","guid":{"rendered":"https:\/\/www.ull.es\/grados\/quimica\/?page_id=518"},"modified":"2025-11-13T16:57:23","modified_gmt":"2025-11-13T16:57:23","slug":"juntas-centro-comisiones","status":"publish","type":"page","link":"https:\/\/www.ull.es\/grados\/quimica\/fr\/informacion-academica\/juntas-centro-comisiones\/","title":{"rendered":"Conseils des centres et des commissions"},"content":{"rendered":"\n<div class=\"wp-block-stackable-columns alignfull stk-block-columns stk-block stk-8657999\" data-block-id=\"8657999\"><style>.stk-8657999 {padding-bottom:0px !important;margin-top:-30px !important;margin-bottom:0px !important;}@media screen and (max-width: 767px){.stk-8657999 {margin-top:-10% !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-8657999-column alignfull\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-914f03e\" data-v=\"4\" data-block-id=\"914f03e\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-914f03e-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-914f03e-inner-blocks\"><style id=\"depicter-1-inline-pre-css\">\n\n.depicter-1:not(.depicter-ready){\n\theight:500px;\n}\n\n\/***** Tablet *****\/\n@media screen and (max-width: 1024px){\n\n.depicter-1:not(.depicter-ready){\n\theight:700px;\n}\n\n}\n\/***** Mobile *****\/\n@media screen and (max-width: 767px){\n\n.depicter-1:not(.depicter-ready){\n\theight:360px;\n}\n\n}\n<\/style>\n<div id=\"depicter-1\" class=\"depicter depicter-document depicter-revert depicter-1 depicter-layout-fullwidth\">\n\n<div class=\"depicter-loading-container depicter-loading dotFlashing-dark\"><div class=\"depicter-loading-dark depicter-dot-flashing\">\n   <span><\/span>\n   <span><\/span>\n   <span><\/span>\n<\/div>\n<\/div>\n<div id=\"depicter-1-section-1\" class=\"depicter-section depicter-1-section-1\" data-name=\"Section 1\" data-type=\"section\" data-local-id=\"section-1\">\n<picture class=\"depicter-bg\">\n<source data-depicter-srcset=\"https:\/\/www.ull.es\/grados\/quimica\/wp-content\/uploads\/sites\/46\/2025\/02\/still-life-laboratory-samples-768x512.jpg, https:\/\/www.ull.es\/grados\/quimica\/wp-content\/uploads\/sites\/46\/2025\/02\/still-life-laboratory-samples.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(max-width: 1024px)\" \/>\n\n<source data-depicter-srcset=\"https:\/\/www.ull.es\/grados\/quimica\/wp-content\/uploads\/sites\/46\/2025\/02\/still-life-laboratory-samples.jpg, https:\/\/www.ull.es\/grados\/quimica\/wp-content\/uploads\/sites\/46\/2025\/02\/still-life-laboratory-samples-2000x1333.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(min-width: 1025px)\" \/>\n<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-ken-burns=\"false\" data-tablet-ken-burns=\"false\" data-mobile-ken-burns=\"false\" alt=\"\" data-depicter-src=\"https:\/\/www.ull.es\/grados\/quimica\/wp-content\/uploads\/sites\/46\/2025\/02\/still-life-laboratory-samples.jpg\" data-object-fit=\"custom,custom,\" data-object-position=\"center top,,\" data-crop=\"{&apos;focalPoint&apos;:{&apos;x&apos;:0.5,&apos;y&apos;:0.58999999999999996891375531049561686813831329345703125},&apos;mediaSize&apos;:{&apos;width&apos;:1792,&apos;height&apos;:1194}}\" data-tablet-crop=\"{&apos;focalPoint&apos;:{&apos;x&apos;:0.5,&apos;y&apos;:0.5},&apos;mediaSize&apos;:{&apos;width&apos;:1050.262565641410446914960630238056182861328125,&apos;height&apos;:700}}\" data-mobile-crop=\"{&apos;focalPoint&apos;:{&apos;x&apos;:0.5,&apos;y&apos;:0.5},&apos;mediaSize&apos;:{&apos;width&apos;:540.1350337584395902013056911528110504150390625,&apos;height&apos;:360}}\" \/>\n<\/picture>\n\n\n<h1 id=\"depicter-1-element-5\" class=\"depicter-element depicter-layer depicter-1-element-5\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 2\" data-local-id=\"element-5\" data-offset=\"x:212px;y:200px;origin:tl\" data-tablet-offset=\"x:331px;y:327px;origin:tl\" data-mobile-offset=\"x:67px;y:-108px;origin:tl\" data-width=\"777px,362px,348px\" data-height=\"auto,auto,auto\" data-responsive-scale=\"true,,\">Grado en Qu\u00edmica<\/h1>\n\n<div id=\"depicter-1-element-10\" class=\"depicter-element depicter-layer depicter-1-element-10\" data-type=\"shape\" data-wrap=\"true\" data-name=\"Shape 1\" data-local-id=\"element-10\" data-offset=\"x:226px;y:313px;origin:tl\" data-tablet-offset=\"x:338px;y:379px;origin:tl\" data-mobile-offset=\"x:67px;y:7px;origin:tl\" data-width=\"749px,337px,190px\" data-height=\"8px,8px,8px\" data-responsive-scale=\"true,,\"><\/div>\n<\/div>\n<\/div>\n<script>\n(window.depicterSetups = window.depicterSetups || []).push(function(){\n\tDepicter.basePath = 'https:\/\/www.ull.es\/grados\/quimica\/wp-content\/plugins\/depicter\/resources\/scripts\/player\/';\n\tconst dpPlayer = Depicter.setup('.depicter-1',\n\t\t{\"width\":[\"1200\",\"1024\",\"360\"],\"height\":[\"500\",\"700\",\"360\"],\"view\":\"basic\",\"keepAspectRatio\":true,\"preload\":0,\"layout\":\"fullwidth\",\"rtl\":false,\"initAfterAppear\":false,\"ajaxApiUrl\":\"https:\\\/\\\/www.ull.es\\\/grados\\\/quimica\\\/wp-admin\\\/admin-ajax.php\",\"mouseSwipe\":true,\"touchSwipe\":true,\"useWatermark\":false}\n\t);\n});\n<\/script><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns alignfull stk-block-columns stk--hide-mobile stk-block stk-ceecbdc stk-block-background\" data-block-id=\"ceecbdc\"><style>.stk-ceecbdc {background-color:#360060 !important;padding-top:35px !important;padding-right:0px !important;padding-bottom:2px !important;padding-left:0px !important;margin-top:-20px !important;margin-bottom:70px !important;}.stk-ceecbdc:before{background-color:#360060 !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-ceecbdc-column alignfull\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-fc60a5d\" data-v=\"4\" data-block-id=\"fc60a5d\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-fc60a5d-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-fc60a5d-inner-blocks\">\n<div class=\"wp-block-stackable-spacer stk-block-spacer stk--no-padding stk-block stk-a3a8a68\" data-block-id=\"a3a8a68\"><style>.stk-a3a8a68 {height:0px !important;}<\/style><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns stk-block-columns stk-block stk-8b59b96\" data-block-id=\"8b59b96\"><style>.stk-8b59b96 .stk--block-align-8b59b96{align-items:flex-start !important;}.stk-8b59b96 {margin-top:25px !important;}.stk-8b59b96-column{--stk-columns-spacing:0px !important;--stk-column-gap:50px !important;}@media screen and (max-width: 767px){.stk-8b59b96-column{row-gap:var(--stk--preset--spacing--60, 2.25rem) !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk--block-align-8b59b96 stk-block-content stk-content-align stk-8b59b96-column\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-dbb7e15\" data-v=\"4\" data-block-id=\"dbb7e15\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-dbb7e15-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-dbb7e15-inner-blocks\">\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-689c258\" id=\"juntas-de-centro-y-comisiones\" data-block-id=\"689c258\"><style>.stk-689c258 .stk-block-heading__text{color:#5c068c !important;}<\/style><h1 class=\"stk-block-heading__text has-text-color\">Juntas de Centro y Comisiones<\/h1><\/div>\n\n\n\n<details class=\"wp-block-stackable-accordion stk-block-accordion stk-inner-blocks stk-block-content stk--is-open stk-block stk-7c390cd is-style-default\" open id=\"junta-facultad\" data-block-id=\"7c390cd\"><style>.stk-7c390cd {border-style:solid !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;margin-bottom:11px !important;}<\/style>\n<summary class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-c927805 stk--container-small stk-block-accordion__heading\" data-v=\"4\" data-block-id=\"c927805\"><style>.stk-c927805 {padding-top:2px !important;padding-right:2px !important;padding-bottom:2px !important;padding-left:2px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-c927805-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-c927805-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-7935446\" data-block-id=\"7935446\"><style>.stk-7935446 .stk-inner-blocks{gap:39px !important;}@media screen and (max-width: 1023px){.stk-7935446 .stk-inner-blocks{gap:39px !important;}}@media screen and (max-width: 767px){.stk-7935446 .stk-inner-blocks{gap:39px !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-icon stk-block-icon stk-block stk-9a468d5\" data-block-id=\"9a468d5\"><style>.stk-9a468d5 .stk--svg-wrapper .stk--inner-svg svg:last-child{height:25px !important;width:25px !important;}.stk-9a468d5 .stk--svg-wrapper .stk--inner-svg svg:last-child, .stk-9a468d5 .stk--svg-wrapper .stk--inner-svg svg:last-child :is(g, path, rect, polygon, ellipse){fill:#5c068c !important;}<\/style><span class=\"stk--svg-wrapper stk--has-icon2\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-9a468d5\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-9-a-468-d-5-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-9-a-468-d-5-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 640 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M323.4 85.2l-96.8 78.4c-16.1 13-19.2 36.4-7 53.1c12.9 17.8 38 21.3 55.3 7.8l99.3-77.2c7-5.4 17-4.2 22.5 2.8s4.2 17-2.8 22.5l-20.9 16.2L512 316.8V128h-.7l-3.9-2.5L434.8 79c-15.3-9.8-33.2-15-51.4-15c-21.8 0-43 7.5-60 21.2zm22.8 124.4l-51.7 40.2C263 274.4 217.3 268 193.7 235.6c-22.2-30.5-16.6-73.1 12.7-96.8l83.2-67.3c-11.6-4.9-24.1-7.4-36.8-7.4C234 64 215.7 69.6 200 80l-72 48V352h28.2l91.4 83.4c19.6 17.9 49.9 16.5 67.8-3.1c5.5-6.1 9.2-13.2 11.1-20.6l17 15.6c19.5 17.9 49.9 16.6 67.8-2.9c4.5-4.9 7.8-10.6 9.9-16.5c19.4 13 45.8 10.3 62.1-7.5c17.9-19.5 16.6-49.9-2.9-67.8l-134.2-123zM16 128c-8.8 0-16 7.2-16 16V352c0 17.7 14.3 32 32 32H64c17.7 0 32-14.3 32-32V128H16zM48 320a16 16 0 1 1 0 32 16 16 0 1 1 0-32zM544 128V352c0 17.7 14.3 32 32 32h32c17.7 0 32-14.3 32-32V144c0-8.8-7.2-16-16-16H544zm32 208a16 16 0 1 1 32 0 16 16 0 1 1 -32 0z\"><\/path><\/svg><\/div><div class=\"stk--inner-svg stk--icon-2\" style=\"display:none\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-9a468d5\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-9-a-468-d-5-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-9-a-468-d-5-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 640 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M272.2 64.6l-51.1 51.1c-15.3 4.2-29.5 11.9-41.5 22.5L153 161.9C142.8 171 129.5 176 115.8 176H96V304c20.4 .6 39.8 8.9 54.3 23.4l35.6 35.6 7 7 0 0L219.9 397c6.2 6.2 16.4 6.2 22.6 0c1.7-1.7 3-3.7 3.7-5.8c2.8-7.7 9.3-13.5 17.3-15.3s16.4 .6 22.2 6.5L296.5 393c11.6 11.6 30.4 11.6 41.9 0c5.4-5.4 8.3-12.3 8.6-19.4c.4-8.8 5.6-16.6 13.6-20.4s17.3-3 24.4 2.1c9.4 6.7 22.5 5.8 30.9-2.6c9.4-9.4 9.4-24.6 0-33.9L340.1 243l-35.8 33c-27.3 25.2-69.2 25.6-97 .9c-31.7-28.2-32.4-77.4-1.6-106.5l70.1-66.2C303.2 78.4 339.4 64 377.1 64c36.1 0 71 13.3 97.9 37.2L505.1 128H544h40 40c8.8 0 16 7.2 16 16V352c0 17.7-14.3 32-32 32H576c-11.8 0-22.2-6.4-27.7-16H463.4c-3.4 6.7-7.9 13.1-13.5 18.7c-17.1 17.1-40.8 23.8-63 20.1c-3.6 7.3-8.5 14.1-14.6 20.2c-27.3 27.3-70 30-100.4 8.1c-25.1 20.8-62.5 19.5-86-4.1L159 404l-7-7-35.6-35.6c-5.5-5.5-12.7-8.7-20.4-9.3C96 369.7 81.6 384 64 384H32c-17.7 0-32-14.3-32-32V144c0-8.8 7.2-16 16-16H56 96h19.8c2 0 3.9-.7 5.3-2l26.5-23.6C175.5 77.7 211.4 64 248.7 64H259c4.4 0 8.9 .2 13.2 .6zM544 320V176H496c-5.9 0-11.6-2.2-15.9-6.1l-36.9-32.8c-18.2-16.2-41.7-25.1-66.1-25.1c-25.4 0-49.8 9.7-68.3 27.1l-70.1 66.2c-10.3 9.8-10.1 26.3 .5 35.7c9.3 8.3 23.4 8.1 32.5-.3l71.9-66.4c9.7-9 24.9-8.4 33.9 1.4s8.4 24.9-1.4 33.9l-.8 .8 74.4 74.4c10 10 16.5 22.3 19.4 35.1H544zM64 336a16 16 0 1 0 -32 0 16 16 0 1 0 32 0zm528 16a16 16 0 1 0 0-32 16 16 0 1 0 0 32z\"><\/path><\/svg><\/div><\/span><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-31863c1\" id=\"acceso\" data-block-id=\"31863c1\"><style>.stk-31863c1 .stk-block-heading__text{color:#000000 !important;font-weight:500 !important;font-family:\"ArgentumSans\", Sans-serif !important;}<\/style><h4 class=\"stk-block-heading__text has-text-color\"><span style=\"color: #000000;\" class=\"stk-highlight\">Junta de Facultad<\/span><\/h4><\/div>\n<\/div><\/div>\n<\/div><\/div><\/summary>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-5222666 stk-block-accordion__content\" data-v=\"4\" data-block-id=\"5222666\"><style>.stk-5222666 {margin-top:-30px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-5222666-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-5222666-inner-blocks\">\n<p class=\"wp-block-paragraph\">La Junta de Facultad es el \u00f3rgano m\u00e1ximo de representaci\u00f3n y gobierno de la Facultad de Ciencias con competencias propias en materia de organizaci\u00f3n, coordinaci\u00f3n y gesti\u00f3n. Le corresponde el ejercicio de las siguientes funciones:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Definir y aprobar la pol\u00edtica de actuaci\u00f3n de la Facultad, tanto en lo que concierne a la docencia como en lo relativo a su r\u00e9gimen administrativo y econ\u00f3mico.<\/li>\n\n\n\n<li>Aprobar los planes de ordenaci\u00f3n docente de la Facultad y proponer e informar la modificaci\u00f3n de sus planes de estudio.<\/li>\n\n\n\n<li>Aprobar la distribuci\u00f3n de los fondos asignados a la Facultad con cargo a los Presupuestos de la Universidad de La Laguna.<\/li>\n\n\n\n<li>Supervisar y conocer la actuaci\u00f3n de los \u00f3rganos colegiados y unipersonales de gobierno de la Facultad y de sus servicios, de conformidad con lo previsto en el apartado segundo del presente art\u00edculo.<\/li>\n\n\n\n<li>Proponer la concesi\u00f3n de los honores y distinciones que se contemplan en el Reglamento correspondiente como expresi\u00f3n p\u00fablica de su reconocimiento a las personas individuales o entidades de reconocido prestigio en la docencia, investigaci\u00f3n y gesti\u00f3n en el campo de la Ciencia, o que hayan prestado servicios destacados a la Facultad de Ciencias en sus fines esenciales.<\/li>\n\n\n\n<li>Ejercer cualesquiera otras funciones que le asignen los \u00f3rganos superiores de gobierno universitario o le reconozca la normativa vigente.<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">A fin de garantizar un funcionamiento m\u00e1s \u00e1gil y eficaz de la Facultad de Ciencias se han establecido las Secciones de Biolog\u00eda, F\u00edsica, Matem\u00e1ticas y Qu\u00edmica. A efectos de organizaci\u00f3n interna se ha establecido que la adscripci\u00f3n de los t\u00edtulos responsabilidad acad\u00e9mica de la Facultad sea:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Secci\u00f3n de Biolog\u00eda: Grado en Biolog\u00eda<\/li>\n\n\n\n<li>Secci\u00f3n de F\u00edsica: Grado en F\u00edsica<\/li>\n\n\n\n<li>Secci\u00f3n de Matem\u00e1ticas: Grado en Matem\u00e1ticas<\/li>\n\n\n\n<li>Secci\u00f3n de Qu\u00edmica: Grado en Qu\u00edmica y Grado en Ciencias Ambientales<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Se entiende que son miembros de las Secciones respectivas todo el personal docente e investigador que imparta docencia en las titulaciones adscritas a ellas, el alumnado que se encuentre matriculado en las correspondientes ense\u00f1anzas y el personal de administraci\u00f3n y servicios que desempe\u00f1e&nbsp;en ellas sus funciones. De acuerdo con el Reglamento de R\u00e9gimen interno (RRI) del centro, cada Secci\u00f3n tiene autonom\u00eda para organizar su r\u00e9gimen de funcionamiento interno, sin perjuicio de las competencias en materia de control contempladas en el RRI y atribuidas a la Junta de Facultad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para m\u00e1s informaci\u00f3n consulte&nbsp;<a href=\"https:\/\/www.ull.es\/centros\/facultad-ciencias\/informacion-general\/junta-de-facultad-y-comisiones\/#comisiones\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">la web de la Facultad de Ciencias<\/a><\/p>\n<\/div><\/div><\/div>\n<\/details>\n\n\n\n<details class=\"wp-block-stackable-accordion stk-block-accordion stk-inner-blocks stk-block-content stk-block stk-88a7c9c is-style-default\" id=\"junta-seccion-quimica\" data-block-id=\"88a7c9c\"><style>.stk-88a7c9c {border-style:solid !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;margin-bottom:10px !important;}<\/style>\n<summary class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-27019df stk--container-small stk-block-accordion__heading\" data-v=\"4\" data-block-id=\"27019df\"><style>.stk-27019df {padding-top:2px !important;padding-right:2px !important;padding-bottom:2px !important;padding-left:2px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-27019df-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-27019df-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-9c9ce7e\" data-block-id=\"9c9ce7e\"><style>.stk-9c9ce7e .stk-inner-blocks{gap:39px !important;}@media screen and (max-width: 1023px){.stk-9c9ce7e .stk-inner-blocks{gap:39px !important;}}@media screen and (max-width: 767px){.stk-9c9ce7e .stk-inner-blocks{gap:39px !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-icon stk-block-icon stk-block stk-61c8ad3\" data-block-id=\"61c8ad3\"><style>.stk-61c8ad3 .stk--svg-wrapper .stk--inner-svg svg:last-child{height:25px !important;width:25px !important;}.stk-61c8ad3 .stk--svg-wrapper .stk--inner-svg svg:last-child, .stk-61c8ad3 .stk--svg-wrapper .stk--inner-svg svg:last-child :is(g, path, rect, polygon, ellipse){fill:#5c068c !important;}<\/style><span class=\"stk--svg-wrapper stk--has-icon2\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-61c8ad3\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-61-c-8-ad-3-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-61-c-8-ad-3-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 640 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M175 389.4c-9.8 16-15 34.3-15 53.1c-10 3.5-20.8 5.5-32 5.5c-53 0-96-43-96-96V64C14.3 64 0 49.7 0 32S14.3 0 32 0H96h64 64c17.7 0 32 14.3 32 32s-14.3 32-32 32V309.9l-49 79.6zM96 64v96h64V64H96zM352 0H480h32c17.7 0 32 14.3 32 32s-14.3 32-32 32V214.9L629.7 406.2c6.7 10.9 10.3 23.5 10.3 36.4c0 38.3-31.1 69.4-69.4 69.4H261.4c-38.3 0-69.4-31.1-69.4-69.4c0-12.8 3.6-25.4 10.3-36.4L320 214.9V64c-17.7 0-32-14.3-32-32s14.3-32 32-32h32zm32 64V224c0 5.9-1.6 11.7-4.7 16.8L330.5 320h171l-48.8-79.2c-3.1-5-4.7-10.8-4.7-16.8V64H384z\"><\/path><\/svg><\/div><div class=\"stk--inner-svg stk--icon-2\" style=\"display:none\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-61c8ad3\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-61-c-8-ad-3-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-61-c-8-ad-3-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M0 64C0 46.3 14.3 32 32 32H88h48 56c17.7 0 32 14.3 32 32s-14.3 32-32 32V400c0 44.2-35.8 80-80 80s-80-35.8-80-80V96C14.3 96 0 81.7 0 64zM136 96H88V256h48V96zM288 64c0-17.7 14.3-32 32-32h56 48 56c17.7 0 32 14.3 32 32s-14.3 32-32 32V400c0 44.2-35.8 80-80 80s-80-35.8-80-80V96c-17.7 0-32-14.3-32-32zM424 96H376V256h48V96z\"><\/path><\/svg><\/div><\/span><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-bcb6d4e\" id=\"span-style-color-000000-class-stk-highlight-junta-de-seccion-de-quimica-span\" data-block-id=\"bcb6d4e\"><style>.stk-bcb6d4e .stk-block-heading__text{color:#000000 !important;font-weight:500 !important;font-family:\"ArgentumSans\", Sans-serif !important;}<\/style><h4 class=\"stk-block-heading__text has-text-color\"><span style=\"color: #000000;\" class=\"stk-highlight\">Junta de Secci\u00f3n de Qu\u00edmica<\/span><\/h4><\/div>\n<\/div><\/div>\n<\/div><\/div><\/summary>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-76d605c stk-block-accordion__content\" data-v=\"4\" data-block-id=\"76d605c\"><style>.stk-76d605c {margin-top:-30px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-76d605c-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-76d605c-inner-blocks\">\n<p class=\"wp-block-paragraph\">Cada Secci\u00f3n cuenta con una Junta que estar\u00e1 presidida por la persona titular del Decanato, pudiendo delegar la presidencia en una de las personas que ocupe uno de los vicedecanatos. Asimismo, la Secretar\u00eda de cada Junta de Secci\u00f3n ser\u00e1 ejercida por la persona que ocupe la de la Facultad, o por la persona que designe el titular del Decanato. Asimismo, cada Junta de Secci\u00f3n contar\u00e1 con un m\u00ednimo de miembros tal que permita su constituci\u00f3n, respet\u00e1ndose en su composici\u00f3n la proporci\u00f3n entre los distintos sectores que marca la normativa vigente.<br>Las Juntas de Secci\u00f3n deber\u00e1n incluir en su composici\u00f3n un 51% de miembros pertenecientes al personal docente e investigador con vinculaci\u00f3n permanente, que incluir\u00e1 a quienes ejerzan la Direcci\u00f3n de los departamentos con al menos el 25% de su docencia en la Secci\u00f3n correspondiente y sean miembros de la Junta de Facultad. Asimismo, contar\u00e1n con un 9% del personal docente e investigador con vinculaci\u00f3n no permanente, un 30% de miembros en representaci\u00f3n del sector del alumnado y un 10% de representantes del personal de administraci\u00f3n y servicios, que ser\u00e1n elegidos por sus respectivos sectores de entre sus miembros en la Junta de Facultad que hayan sido electos por la circunscripci\u00f3n electoral correspondiente. En todos los casos deber\u00e1n ser miembros de la Junta de Facultad.<br>La Junta de Facultad delega en las Juntas de Secci\u00f3n las competencias que se refieran exclusivamente a materias de inter\u00e9s propio de las respectivas Secciones, correspondiendo a cada Junta de Secci\u00f3n el conocimiento y resoluci\u00f3n de cualquier otro asunto que la Junta de Facultad delegue expresamente en ella, con las salvedades recogidas en la normativa vigente. En las Juntas de Facultad de Ciencias se informar\u00e1 de los acuerdos adoptados por las Juntas de Secci\u00f3n celebradas previamente, pudiendo el Pleno revocar en todo momento la delegaci\u00f3n efectuada, recuperando el ejercicio de las competencias delegadas.<\/p>\n<\/div><\/div><\/div>\n<\/details>\n\n\n\n<details class=\"wp-block-stackable-accordion stk-block-accordion stk-inner-blocks stk-block-content stk-block stk-9d40cce is-style-default\" id=\"matricula\" data-block-id=\"9d40cce\"><style>.stk-9d40cce {border-style:solid !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;margin-bottom:8px !important;}<\/style>\n<summary class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-ef7f17a stk--container-small stk-block-accordion__heading\" data-v=\"4\" data-block-id=\"ef7f17a\"><style>.stk-ef7f17a {padding-top:2px !important;padding-right:2px !important;padding-bottom:2px !important;padding-left:2px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-ef7f17a-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-ef7f17a-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-da3b93e\" data-block-id=\"da3b93e\"><style>.stk-da3b93e .stk-inner-blocks{gap:39px !important;}@media screen and (max-width: 1023px){.stk-da3b93e .stk-inner-blocks{gap:39px !important;}}@media screen and (max-width: 767px){.stk-da3b93e .stk-inner-blocks{gap:39px !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-icon stk-block-icon stk-block stk-8c84b2d\" data-block-id=\"8c84b2d\"><style>.stk-8c84b2d .stk--svg-wrapper .stk--inner-svg svg:last-child{height:25px !important;width:25px !important;}.stk-8c84b2d .stk--svg-wrapper .stk--inner-svg svg:last-child, .stk-8c84b2d .stk--svg-wrapper .stk--inner-svg svg:last-child :is(g, path, rect, polygon, ellipse){fill:#5c068c !important;}<\/style><span class=\"stk--svg-wrapper stk--has-icon2\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-8c84b2d\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-8-c-84-b-2-d-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-8-c-84-b-2-d-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 640 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M144 0a80 80 0 1 1 0 160A80 80 0 1 1 144 0zM512 0a80 80 0 1 1 0 160A80 80 0 1 1 512 0zM0 298.7C0 239.8 47.8 192 106.7 192h42.7c15.9 0 31 3.5 44.6 9.7c-1.3 7.2-1.9 14.7-1.9 22.3c0 38.2 16.8 72.5 43.3 96c-.2 0-.4 0-.7 0H21.3C9.6 320 0 310.4 0 298.7zM405.3 320c-.2 0-.4 0-.7 0c26.6-23.5 43.3-57.8 43.3-96c0-7.6-.7-15-1.9-22.3c13.6-6.3 28.7-9.7 44.6-9.7h42.7C592.2 192 640 239.8 640 298.7c0 11.8-9.6 21.3-21.3 21.3H405.3zM224 224a96 96 0 1 1 192 0 96 96 0 1 1 -192 0zM128 485.3C128 411.7 187.7 352 261.3 352H378.7C452.3 352 512 411.7 512 485.3c0 14.7-11.9 26.7-26.7 26.7H154.7c-14.7 0-26.7-11.9-26.7-26.7z\"><\/path><\/svg><\/div><div class=\"stk--inner-svg stk--icon-2\" style=\"display:none\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-8c84b2d\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-8-c-84-b-2-d-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-8-c-84-b-2-d-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 640 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M48 48h88c13.3 0 24-10.7 24-24s-10.7-24-24-24H32C14.3 0 0 14.3 0 32V136c0 13.3 10.7 24 24 24s24-10.7 24-24V48zM175.8 224a48 48 0 1 0 0-96 48 48 0 1 0 0 96zm-26.5 32C119.9 256 96 279.9 96 309.3c0 14.7 11.9 26.7 26.7 26.7h56.1c8-34.1 32.8-61.7 65.2-73.6c-7.5-4.1-16.2-6.4-25.3-6.4H149.3zm368 80c14.7 0 26.7-11.9 26.7-26.7c0-29.5-23.9-53.3-53.3-53.3H421.3c-9.2 0-17.8 2.3-25.3 6.4c32.4 11.9 57.2 39.5 65.2 73.6h56.1zm-89.4 0c-8.6-24.3-29.9-42.6-55.9-47c-3.9-.7-7.9-1-12-1H280c-4.1 0-8.1 .3-12 1c-26 4.4-47.3 22.7-55.9 47c-2.7 7.5-4.1 15.6-4.1 24c0 13.3 10.7 24 24 24H408c13.3 0 24-10.7 24-24c0-8.4-1.4-16.5-4.1-24zM464 224a48 48 0 1 0 0-96 48 48 0 1 0 0 96zm-80-32a64 64 0 1 0 -128 0 64 64 0 1 0 128 0zM504 48h88v88c0 13.3 10.7 24 24 24s24-10.7 24-24V32c0-17.7-14.3-32-32-32H504c-13.3 0-24 10.7-24 24s10.7 24 24 24zM48 464V376c0-13.3-10.7-24-24-24s-24 10.7-24 24V480c0 17.7 14.3 32 32 32H136c13.3 0 24-10.7 24-24s-10.7-24-24-24H48zm456 0c-13.3 0-24 10.7-24 24s10.7 24 24 24H608c17.7 0 32-14.3 32-32V376c0-13.3-10.7-24-24-24s-24 10.7-24 24v88H504z\"><\/path><\/svg><\/div><\/span><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-d69e378\" id=\"span-style-color-000000-class-stk-highlight-comisiones-del-centro-y-del-titulo-span\" data-block-id=\"d69e378\"><style>.stk-d69e378 .stk-block-heading__text{color:#000000 !important;font-weight:500 !important;font-family:\"ArgentumSans\", Sans-serif !important;}<\/style><h4 class=\"stk-block-heading__text has-text-color\"><span style=\"color: #000000;\" class=\"stk-highlight\">Comisiones del centro y del t\u00edtulo<\/span><\/h4><\/div>\n<\/div><\/div>\n<\/div><\/div><\/summary>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-9404ebc stk-block-accordion__content\" data-v=\"4\" data-block-id=\"9404ebc\"><style>.stk-9404ebc {margin-top:-30px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-9404ebc-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-9404ebc-inner-blocks\">\n<p class=\"wp-block-paragraph\">Las&nbsp;<a href=\"https:\/\/docs.google.com\/spreadsheets\/d\/e\/2PACX-1vSqcu_04xuz8QkOC6A1nPodOK2pxq1pRvbSFmlFzoA0AIg8ZPK7plK0hkcecubVImWDaGSNbfNLVh4w\/pubhtml\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\"><strong>Comisiones de la Facultad<\/strong><\/a>&nbsp;de Ciencias son:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Comisi\u00f3n Permanente<\/li>\n\n\n\n<li>Comisi\u00f3n de Calidad<\/li>\n\n\n\n<li>Comisi\u00f3n de Pr\u00e1cticas Externas (COPYPE)<\/li>\n\n\n\n<li>Comisi\u00f3n de Movilidad<\/li>\n\n\n\n<li>Comisi\u00f3n Pol\u00edticas de Igualdad<\/li>\n\n\n\n<li>Comisi\u00f3n Sostenibilidad<\/li>\n\n\n\n<li>Comisi\u00f3n Valoraci\u00f3n Premios Extraordinarios Fin de Titulaci\u00f3n<\/li>\n\n\n\n<li>Comisi\u00f3n de Evaluaci\u00f3n Curricular por Compensaci\u00f3n<\/li>\n\n\n\n<li>Comisi\u00f3n Electoral<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Las&nbsp;<a href=\"https:\/\/docs.google.com\/spreadsheets\/d\/e\/2PACX-1vR_7m7m_Y4ueCAeYlGOYT7GFOfBcRw2E0xT8VKKNvPtDusDzRS7kpEEi2H8wGOETDIhGuR4AyTP65Nf\/pubhtml\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\"><strong>Comisiones espec\u00edficas de la Secci\u00f3n de Qu\u00edmica<\/strong>,<\/a>&nbsp;son:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Comisi\u00f3n de Divulgaci\u00f3n<\/li>\n\n\n\n<li>Comisi\u00f3n \u201cMejor Tesis de Egresados de la Secci\u00f3n de Qu\u00edmica\u201d<\/li>\n\n\n\n<li>Comisi\u00f3n de Reconocimiento de cr\u00e9ditos<\/li>\n\n\n\n<li>Comisi\u00f3n de Pr\u00e1cticas Externas (COPYPE) de la Secci\u00f3n<\/li>\n\n\n\n<li>Comisi\u00f3n de T\u00edtulo del Grado en Ciencias Ambientales<\/li>\n\n\n\n<li>Comisi\u00f3n de Trabajo Fin de Grado de Ciencias Ambientales<\/li>\n\n\n\n<li>Comisi\u00f3n de T\u00edtulo del Grado en Qu\u00edmica<\/li>\n\n\n\n<li>Comisi\u00f3n de Trabajo Fin de Grado de Qu\u00edmica<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">En el siguiente enlace puede&nbsp;<a href=\"https:\/\/docs.google.com\/spreadsheets\/d\/e\/2PACX-1vSqcu_04xuz8QkOC6A1nPodOK2pxq1pRvbSFmlFzoA0AIg8ZPK7plK0hkcecubVImWDaGSNbfNLVh4w\/pubhtml\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">consultar la composici\u00f3n de todas las Comisiones de la Junta de Facultad de Ciencias<\/a>&nbsp;en vigor y las de cursos previos.<\/p>\n<\/div><\/div><\/div>\n<\/details>\n<\/div><\/div><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Conseils et comit\u00e9s de facult\u00e9 Le Conseil de facult\u00e9 est l&#039;organe repr\u00e9sentatif et directeur supr\u00eame de la Facult\u00e9 des sciences. Il dispose de pouvoirs propres en mati\u00e8re d&#039;organisation, de coordination et de gestion. Il est responsable des fonctions suivantes\u00a0: Afin de garantir un fonctionnement plus agile et efficace\u2026<\/p>","protected":false},"author":1,"featured_media":0,"parent":252,"menu_order":7,"comment_status":"closed","ping_status":"closed","template":"templates\/template-frontpage.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-518","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.ull.es\/grados\/quimica\/fr\/wp-json\/wp\/v2\/pages\/518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ull.es\/grados\/quimica\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ull.es\/grados\/quimica\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ull.es\/grados\/quimica\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ull.es\/grados\/quimica\/fr\/wp-json\/wp\/v2\/comments?post=518"}],"version-history":[{"count":33,"href":"https:\/\/www.ull.es\/grados\/quimica\/fr\/wp-json\/wp\/v2\/pages\/518\/revisions"}],"predecessor-version":[{"id":1551,"href":"https:\/\/www.ull.es\/grados\/quimica\/fr\/wp-json\/wp\/v2\/pages\/518\/revisions\/1551"}],"up":[{"embeddable":true,"href":"https:\/\/www.ull.es\/grados\/quimica\/fr\/wp-json\/wp\/v2\/pages\/252"}],"wp:attachment":[{"href":"https:\/\/www.ull.es\/grados\/quimica\/fr\/wp-json\/wp\/v2\/media?parent=518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}