{"id":26,"date":"2017-06-28T12:58:08","date_gmt":"2017-06-28T12:58:08","guid":{"rendered":"http:\/\/www.ull.es\/masteres\/desarrollo-y-gestion-de-recursos-humanos\/?page_id=26"},"modified":"2025-07-23T05:34:20","modified_gmt":"2025-07-23T05:34:20","slug":"descripcion-del-titulo","status":"publish","type":"page","link":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/en\/informacion-academica\/descripcion-del-titulo\/","title":{"rendered":"Title Description"},"content":{"rendered":"\n<div class=\"wp-block-stackable-columns alignfull stk-block-columns stk-block stk-2314a6b\" data-block-id=\"2314a6b\"><style>.stk-2314a6b {padding-bottom:0px !important;margin-top:-100px !important;margin-bottom:0px !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-2314a6b-column alignfull\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-1d1764d\" data-v=\"4\" data-block-id=\"1d1764d\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-1d1764d-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-1d1764d-inner-blocks\"><style id=\"depicter-1-inline-pre-css\">\n\n.depicter-1:not(.depicter-ready){\n\theight:450px;\n}\n\n\/***** Tablet *****\/\n@media screen and (max-width: 1024px){\n\n.depicter-1:not(.depicter-ready){\n\theight:700px;\n}\n\n}\n\/***** Mobile *****\/\n@media screen and (max-width: 767px){\n\n.depicter-1:not(.depicter-ready){\n\theight:360px;\n}\n\n}\n<\/style>\n<div id=\"depicter-1\" class=\"depicter depicter-document depicter-revert depicter-1 depicter-layout-fullwidth\">\n\n<div class=\"depicter-loading-container depicter-loading dotFlashing-dark\"><div class=\"depicter-loading-dark depicter-dot-flashing\">\n   <span><\/span>\n   <span><\/span>\n   <span><\/span>\n<\/div>\n<\/div>\n<div id=\"depicter-1-section-1\" class=\"depicter-section depicter-1-section-1\" data-name=\"Section 1\" data-type=\"section\" data-local-id=\"section-1\">\n<picture class=\"depicter-bg\">\n<source data-depicter-srcset=\"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/wp-content\/uploads\/sites\/26\/2025\/06\/Headers-Masteres_Ciencias-de-las-religiones-768x248.jpg, https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/wp-content\/uploads\/sites\/26\/2025\/06\/Headers-Masteres_Ciencias-de-las-religiones.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(max-width: 1024px)\" \/>\n\n<source data-depicter-srcset=\"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/wp-content\/uploads\/sites\/26\/2025\/06\/Headers-Masteres_Ciencias-de-las-religiones.jpg, https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/wp-content\/uploads\/sites\/26\/2025\/06\/Headers-Masteres_Ciencias-de-las-religiones-1280x413.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(min-width: 1025px)\" \/>\n<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-ken-burns=\"false\" data-tablet-ken-burns=\"false\" data-mobile-ken-burns=\"false\" alt=\"\" data-depicter-src=\"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/wp-content\/uploads\/sites\/26\/2025\/06\/Headers-Masteres_Ciencias-de-las-religiones.jpg\" data-object-fit=\"custom,custom,\" data-object-position=\"center top,,\" data-crop=\"{'focalPoint':{'x':0.5,'y':0.479999999999999982236431605997495353221893310546875},'mediaSize':{'width':1792,'height':578}}\" data-tablet-crop=\"{'focalPoint':{'x':0.5,'y':0.5},'mediaSize':{'width':2169.4915254237284898408688604831695556640625,'height':700}}\" data-mobile-crop=\"{'focalPoint':{'x':0.5,'y':0.5},'mediaSize':{'width':1394.6731234866829254315234720706939697265625,'height':450}}\" \/>\n<\/picture>\n\n\n<h1 id=\"depicter-1-element-5\" class=\"depicter-element depicter-layer depicter-1-element-5\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 2\" data-local-id=\"element-5\" data-offset=\"x:0px;y:118px;origin:tl\" data-tablet-offset=\"x:109px;y:220px;origin:tl\" data-mobile-offset=\"x:0px;y:78px;origin:tl\" data-width=\"1200px,808px,399px\" data-height=\"auto,auto,auto\" data-responsive-scale=\"true,,\">M\u00e1ster Universitario en Ciencias de las Religiones: Historia y Sociedad (Interuniversitario)<br><\/h1>\n\n<div id=\"depicter-1-element-10\" class=\"depicter-element depicter-layer depicter-1-element-10\" data-type=\"shape\" data-wrap=\"true\" data-name=\"Shape 1\" data-local-id=\"element-10\" data-offset=\"x:0px;y:366px;origin:tl\" data-tablet-offset=\"x:124px;y:521px;origin:tl\" data-mobile-offset=\"x:-9px;y:295px;origin:tl\" data-width=\"1126px,778px,408px\" data-height=\"8px,8px,8px\" data-responsive-scale=\"true,,\"><\/div>\n<\/div>\n<\/div>\n<script>\n(window.depicterSetups = window.depicterSetups || []).push(function(){\n\tDepicter.basePath = 'https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/wp-content\/plugins\/depicter\/resources\/scripts\/player\/';\n\tconst dpPlayer = Depicter.setup('.depicter-1',\n\t\t{\"width\":[\"1200\",\"1024\",\"360\"],\"height\":[\"450\",\"700\",\"360\"],\"view\":\"basic\",\"keepAspectRatio\":true,\"preload\":0,\"layout\":\"fullwidth\",\"rtl\":false,\"initAfterAppear\":false,\"ajaxApiUrl\":\"https:\\\/\\\/www.ull.es\\\/masteres\\\/ciencias-de-las-religiones\\\/wp-admin\\\/admin-ajax.php\",\"mouseSwipe\":true,\"touchSwipe\":true,\"useWatermark\":false}\n\t);\n});\n<\/script><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns alignfull stk-block-columns stk--hide-mobile stk-block stk-6394276 stk-block-background\" data-block-id=\"6394276\"><style>.stk-6394276 {background-color:#fa6199 !important;padding-top:50px !important;padding-right:0px !important;padding-bottom:1px !important;padding-left:0px !important;margin-top:-40px !important;margin-bottom:0px !important;}.stk-6394276:before{background-color:#fa6199 !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-6394276-column alignfull\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-8a66885\" data-v=\"4\" data-block-id=\"8a66885\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-8a66885-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-8a66885-inner-blocks\">\n<div class=\"wp-block-stackable-spacer stk-block-spacer stk--no-padding stk-block stk-bc89b3e\" data-block-id=\"bc89b3e\"><style>.stk-bc89b3e {height:0px !important;}<\/style><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns stk-block-columns stk-block stk-8b59b96\" data-block-id=\"8b59b96\"><style>.stk-8b59b96 .stk--block-align-8b59b96{align-items:flex-start !important;}.stk-8b59b96 {margin-top:50px !important;}.stk-8b59b96-column{--stk-columns-spacing:0px !important;--stk-column-gap:50px !important;}@media screen and (max-width: 767px){.stk-8b59b96-column{row-gap:var(--stk--preset--spacing--60, 2.25rem) !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk--block-align-8b59b96 stk-block-content stk-content-align stk-8b59b96-column\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-dbb7e15\" data-v=\"4\" data-block-id=\"dbb7e15\"><style>@media screen and (min-width: 768px){.stk-dbb7e15 {flex:var(--stk-flex-grow, 1) 1 66.7% !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-dbb7e15-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-dbb7e15-inner-blocks\">\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-cc0239e\" id=\"complementos-de-formacion\" data-block-id=\"cc0239e\"><style>.stk-cc0239e .stk-block-heading__text{color:#fa6199 !important;font-weight:500 !important;}<\/style><h1 class=\"stk-block-heading__text has-text-color\">Descripci\u00f3n del t\u00edtulo<\/h1><\/div>\n\n\n\n<table class=\"grales\" width=\"100%\">\n<tbody>\n<tr>\n<td class=\"bluecolumn\">Nombre del t\u00edtulo:<\/td>\n<td class=\"td1Izda\">M\u00e1ster Universitario en Ciencias de las Religiones: Historia y Sociedad\u00a0por la <a href=\"https:\/\/www.uc3m.es\/ss\/Satellite\/Postgrado\/es\/Detalle\/Estudio_C\/1371231732227\/1371219633369\/UC3M_-_Master_Interuniversitario_en_Ciencias_de_las_Religiones:_Historia_y_Sociedad\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\" rel=\"noopener\">Universidad Carlos III de Madrid<\/a>; la Universidad de La Laguna y la <a href=\"https:\/\/www.upo.es\/postgrado\/Master-Oficial-Ciencias-de-las-Religiones-Historia-y-Sociedad\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\" rel=\"noopener\">Universidad Pablo de Olavide<\/a><\/td>\n<\/tr>\n<tr>\n<td class=\"bluecolumn\">Universidad y centros responsables:<\/td>\n<td class=\"td2Izda\"><a href=\"https:\/\/www.upo.es\/portal\/impe\/web\/portada\/\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\" rel=\"noopener\">Universidad Pablo de Olavide<\/a><\/td>\n<\/tr>\n<tr>\n<td class=\"bluecolumn\">Modalidad de ense\u00f1anza:<\/td>\n<td class=\"td1Izda\">Online<\/td>\n<\/tr>\n<tr>\n<td class=\"bluecolumn\" width=\"30%\">Plazas ofertadas:<\/td>\n<td class=\"td2Izda\" width=\"70%\">Universidad Pablo de Olavide: 20\nUniversidad de La Laguna: 20\nUniversidad Carlos III: 20<\/td>\n<\/tr>\n<tr>\n<td class=\"bluecolumn\">N\u00famero de cr\u00e9ditos:<\/td>\n<td class=\"td1Izda\">60 ECTS (Precio cr\u00e9dito curso 2021\/2022: 12,45 \u20ac)\n\nGrado de experimentalidad 4<\/td>\n<\/tr>\n<tr>\n<td class=\"bluecolumn\">Lugar de impartici\u00f3n:<\/td>\n<td class=\"td2Izda\">Universidad de La Laguna.\u00a0<a href=\"https:\/\/www.ull.es\/centros\/escuela-doctorado-estudios-posgrado\/\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\" rel=\"noopener\">Escuela de Doctorado y Estudios de Posgrado<\/a>\n\nUniversidad Pablo de Olavide.\u00a0<a href=\"https:\/\/www.upo.es\/postgrado\/\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\" rel=\"noopener\">Centro de Estudios de Postgrado.<\/a>\n\nUniversidad Carlos III de Madrid. <a href=\"https:\/\/www.uc3m.es\/ss\/Satellite\/Postgrado\/es\/TextoDosColumnas\/1371223604509\/Centro_de_Postgrado\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\" rel=\"noopener\">Centro de Postgrado<\/a><\/td>\n<\/tr>\n<tr>\n<td class=\"bluecolumn\">Duraci\u00f3n m\u00e1ster:<\/td>\n<td class=\"td1Izda\">1 curso acad\u00e9mico<\/td>\n<\/tr>\n<tr>\n<td class=\"bluecolumn\">Idiomas en los que se imparte:<\/td>\n<td class=\"td2Izda\">Espa\u00f1ol<\/td>\n<\/tr>\n<tr>\n<td class=\"bluecolumn\">Orientaci\u00f3n:<\/td>\n<td class=\"td2Izda\">Investigadora<\/td>\n<\/tr>\n<tr>\n<td class=\"bluecolumn\">Especialidades\/Itinerarios:<\/td>\n<td class=\"td1Izda\">Consta de dos especializaciones:\n1) Especialidad en: Historia de las Religiones \/ History of Religions (25 ECTS)\n2) Especialidad en: Gesti\u00f3n de la diversidad religiosa y cultural \/ Management of religious and cultural diversity (25 ECTS)<\/td>\n<\/tr>\n<tr>\n<td class=\"bluecolumn\">Justificaci\u00f3n del t\u00edtulo<\/td>\n<td class=\"td1Izda\"><a href=\"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones-historia-y-sociedad\/justificacion-del-titulo\/\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\" rel=\"noopener\">Acceso a la justificaci\u00f3n<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-53ec762\" data-v=\"4\" data-block-id=\"53ec762\"><style>.stk-53ec762-inner-blocks{row-gap:0px !important;}.stk-53ec762 {padding-top:0px !important;padding-right:0px !important;padding-bottom:0px !important;padding-left:0px !important;}@media screen and (min-width: 768px){.stk-53ec762 {flex:var(--stk-flex-grow, 1) 1 33.3% !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-53ec762-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-53ec762-inner-blocks\">\n\n<ul class=\"widget-box\">\n<li class='contacto-header'>Informaci\u00f3n de contacto<\/li><li><i class=\"fa fa-map-marker\"><\/i> Avda. Astrof\u00edsico Francisco S\u00e1nchez, SN. Edificio Calabaza \u2013 AN.2D Apdo. 456 38200 San Crist\u00f3bal de La Laguna<\/li><li><i class=\"fa fa-envelope\"><\/i>  <a href=mailto:master.religiones@ull.es>master.religiones@ull.es<\/a><\/li><li><i class=\"fa fa-archive\"><\/i><a href=\"https:\/\/sede.ull.es\/ecivilis-site\/catalog\/showProcedure\/484\"> Procedimiento para quejas, sugerencias y felicitaciones<\/a><\/li>\n<\/ul>\n\n\n<\/div><\/div><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Title Description Title: Master&#039;s Degree in Religious Sciences: History and Society from Carlos III University of Madrid, the University of La Laguna, and Pablo de Olavide University. University and responsible institutions: Pablo de Olavide University. Teaching method: Online. Places available: Pablo de Olavide University: 20. University of La\u2026<\/p>","protected":false},"author":1,"featured_media":0,"parent":252,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/template-frontpage.php","meta":{"footnotes":""},"class_list":["post-26","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Descripci\u00f3n del t\u00edtulo - M\u00e1ster Universitario en Ciencias de las Religiones: Historia y Sociedad<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/en\/informacion-academica\/descripcion-del-titulo\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Descripci\u00f3n del t\u00edtulo - M\u00e1ster Universitario en Ciencias de las Religiones: Historia y Sociedad\" \/>\n<meta property=\"og:description\" content=\"Descripci\u00f3n del t\u00edtulo Nombre del t\u00edtulo: M\u00e1ster Universitario en Ciencias de las Religiones: Historia y Sociedad\u00a0por la Universidad Carlos III de Madrid; la Universidad de La Laguna y la Universidad Pablo de Olavide Universidad y centros responsables: Universidad Pablo de Olavide Modalidad de ense\u00f1anza: Online Plazas ofertadas: Universidad Pablo de Olavide: 20 Universidad de La...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/en\/informacion-academica\/descripcion-del-titulo\/\" \/>\n<meta property=\"og:site_name\" content=\"M\u00e1ster Universitario en Ciencias de las Religiones: Historia y Sociedad\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-23T05:34:20+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ull.es\\\/masteres\\\/ciencias-de-las-religiones\\\/informacion-academica\\\/descripcion-del-titulo\\\/\",\"url\":\"https:\\\/\\\/www.ull.es\\\/masteres\\\/ciencias-de-las-religiones\\\/informacion-academica\\\/descripcion-del-titulo\\\/\",\"name\":\"Descripci\u00f3n del t\u00edtulo - M\u00e1ster Universitario en Ciencias de las Religiones: Historia y Sociedad\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ull.es\\\/masteres\\\/ciencias-de-las-religiones\\\/#website\"},\"datePublished\":\"2017-06-28T12:58:08+00:00\",\"dateModified\":\"2025-07-23T05:34:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ull.es\\\/masteres\\\/ciencias-de-las-religiones\\\/informacion-academica\\\/descripcion-del-titulo\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ull.es\\\/masteres\\\/ciencias-de-las-religiones\\\/informacion-academica\\\/descripcion-del-titulo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ull.es\\\/masteres\\\/ciencias-de-las-religiones\\\/informacion-academica\\\/descripcion-del-titulo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ull.es\\\/masteres\\\/ciencias-de-las-religiones\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Informaci\u00f3n Acad\u00e9mica\",\"item\":\"https:\\\/\\\/www.ull.es\\\/masteres\\\/ciencias-de-las-religiones\\\/informacion-academica\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Descripci\u00f3n del t\u00edtulo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ull.es\\\/masteres\\\/ciencias-de-las-religiones\\\/#website\",\"url\":\"https:\\\/\\\/www.ull.es\\\/masteres\\\/ciencias-de-las-religiones\\\/\",\"name\":\"M\u00e1ster Universitario en Ciencias de las Religiones: Historia y Sociedad\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ull.es\\\/masteres\\\/ciencias-de-las-religiones\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Title Description - Master&#039;s Degree in Religious Sciences: History and Society","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/en\/informacion-academica\/descripcion-del-titulo\/","og_locale":"en_GB","og_type":"article","og_title":"Descripci\u00f3n del t\u00edtulo - M\u00e1ster Universitario en Ciencias de las Religiones: Historia y Sociedad","og_description":"Descripci\u00f3n del t\u00edtulo Nombre del t\u00edtulo: M\u00e1ster Universitario en Ciencias de las Religiones: Historia y Sociedad\u00a0por la Universidad Carlos III de Madrid; la Universidad de La Laguna y la Universidad Pablo de Olavide Universidad y centros responsables: Universidad Pablo de Olavide Modalidad de ense\u00f1anza: Online Plazas ofertadas: Universidad Pablo de Olavide: 20 Universidad de La...","og_url":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/en\/informacion-academica\/descripcion-del-titulo\/","og_site_name":"M\u00e1ster Universitario en Ciencias de las Religiones: Historia y Sociedad","article_modified_time":"2025-07-23T05:34:20+00:00","twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/informacion-academica\/descripcion-del-titulo\/","url":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/informacion-academica\/descripcion-del-titulo\/","name":"Title Description - Master&#039;s Degree in Religious Sciences: History and Society","isPartOf":{"@id":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/#website"},"datePublished":"2017-06-28T12:58:08+00:00","dateModified":"2025-07-23T05:34:20+00:00","breadcrumb":{"@id":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/informacion-academica\/descripcion-del-titulo\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/informacion-academica\/descripcion-del-titulo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/informacion-academica\/descripcion-del-titulo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/"},{"@type":"ListItem","position":2,"name":"Informaci\u00f3n Acad\u00e9mica","item":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/informacion-academica\/"},{"@type":"ListItem","position":3,"name":"Descripci\u00f3n del t\u00edtulo"}]},{"@type":"WebSite","@id":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/#website","url":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/","name":"Master&#039;s Degree in Religious Sciences: History and Society","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/en\/wp-json\/wp\/v2\/pages\/26","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/en\/wp-json\/wp\/v2\/comments?post=26"}],"version-history":[{"count":21,"href":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/en\/wp-json\/wp\/v2\/pages\/26\/revisions"}],"predecessor-version":[{"id":1081,"href":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/en\/wp-json\/wp\/v2\/pages\/26\/revisions\/1081"}],"up":[{"embeddable":true,"href":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/en\/wp-json\/wp\/v2\/pages\/252"}],"wp:attachment":[{"href":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/en\/wp-json\/wp\/v2\/media?parent=26"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}