{"id":270,"date":"2017-07-11T13:21:36","date_gmt":"2017-07-11T13:21:36","guid":{"rendered":"http:\/\/www.ull.es\/masteres\/desarrollo-y-gestion-de-recursos-humanos\/?page_id=270"},"modified":"2025-08-21T05:12:30","modified_gmt":"2025-08-21T05:12:30","slug":"plan-de-estudios","status":"publish","type":"page","link":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/plan-de-estudios\/","title":{"rendered":"Plan de estudios"},"content":{"rendered":"\n<div class=\"wp-block-stackable-columns alignfull stk-block-columns stk-block stk-2314a6b\" data-block-id=\"2314a6b\"><style>.stk-2314a6b {padding-bottom:0px !important;margin-top:-100px !important;margin-bottom:0px !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-2314a6b-column alignfull\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-1d1764d\" data-v=\"4\" data-block-id=\"1d1764d\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-1d1764d-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-1d1764d-inner-blocks\"><style id=\"depicter-1-inline-pre-css\">\n\n.depicter-1:not(.depicter-ready){\n\theight:450px;\n}\n\n\/***** Tablet *****\/\n@media screen and (max-width: 1024px){\n\n.depicter-1:not(.depicter-ready){\n\theight:700px;\n}\n\n}\n\/***** Mobile *****\/\n@media screen and (max-width: 767px){\n\n.depicter-1:not(.depicter-ready){\n\theight:360px;\n}\n\n}\n<\/style>\n<div id=\"depicter-1\" class=\"depicter depicter-document depicter-revert depicter-1 depicter-layout-fullwidth\">\n\n<div class=\"depicter-loading-container depicter-loading dotFlashing-dark\"><div class=\"depicter-loading-dark depicter-dot-flashing\">\n   <span><\/span>\n   <span><\/span>\n   <span><\/span>\n<\/div>\n<\/div>\n<div id=\"depicter-1-section-1\" class=\"depicter-section depicter-1-section-1\" data-name=\"Section 1\" data-type=\"section\" data-local-id=\"section-1\">\n<picture class=\"depicter-bg\">\n<source data-depicter-srcset=\"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/wp-content\/uploads\/sites\/26\/2025\/06\/Headers-Masteres_Ciencias-de-las-religiones-768x248.jpg, https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/wp-content\/uploads\/sites\/26\/2025\/06\/Headers-Masteres_Ciencias-de-las-religiones.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(max-width: 1024px)\" \/>\n\n<source data-depicter-srcset=\"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/wp-content\/uploads\/sites\/26\/2025\/06\/Headers-Masteres_Ciencias-de-las-religiones.jpg, https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/wp-content\/uploads\/sites\/26\/2025\/06\/Headers-Masteres_Ciencias-de-las-religiones-1280x413.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(min-width: 1025px)\" \/>\n<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-ken-burns=\"false\" data-tablet-ken-burns=\"false\" data-mobile-ken-burns=\"false\" alt=\"\" data-depicter-src=\"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/wp-content\/uploads\/sites\/26\/2025\/06\/Headers-Masteres_Ciencias-de-las-religiones.jpg\" data-object-fit=\"custom,custom,\" data-object-position=\"center top,,\" data-crop=\"{'focalPoint':{'x':0.5,'y':0.479999999999999982236431605997495353221893310546875},'mediaSize':{'width':1792,'height':578}}\" data-tablet-crop=\"{'focalPoint':{'x':0.5,'y':0.5},'mediaSize':{'width':2169.4915254237284898408688604831695556640625,'height':700}}\" data-mobile-crop=\"{'focalPoint':{'x':0.5,'y':0.5},'mediaSize':{'width':1394.6731234866829254315234720706939697265625,'height':450}}\" \/>\n<\/picture>\n\n\n<h1 id=\"depicter-1-element-5\" class=\"depicter-element depicter-layer depicter-1-element-5\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 2\" data-local-id=\"element-5\" data-offset=\"x:0px;y:118px;origin:tl\" data-tablet-offset=\"x:109px;y:220px;origin:tl\" data-mobile-offset=\"x:0px;y:78px;origin:tl\" data-width=\"1200px,808px,399px\" data-height=\"auto,auto,auto\" data-responsive-scale=\"true,,\">M\u00e1ster Universitario en Ciencias de las Religiones: Historia y Sociedad (Interuniversitario)<br><\/h1>\n\n<div id=\"depicter-1-element-10\" class=\"depicter-element depicter-layer depicter-1-element-10\" data-type=\"shape\" data-wrap=\"true\" data-name=\"Shape 1\" data-local-id=\"element-10\" data-offset=\"x:0px;y:366px;origin:tl\" data-tablet-offset=\"x:124px;y:521px;origin:tl\" data-mobile-offset=\"x:-9px;y:295px;origin:tl\" data-width=\"1126px,778px,408px\" data-height=\"8px,8px,8px\" data-responsive-scale=\"true,,\"><\/div>\n<\/div>\n<\/div>\n<script>\n(window.depicterSetups = window.depicterSetups || []).push(function(){\n\tDepicter.basePath = 'https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/wp-content\/plugins\/depicter\/resources\/scripts\/player\/';\n\tconst dpPlayer = Depicter.setup('.depicter-1',\n\t\t{\"width\":[\"1200\",\"1024\",\"360\"],\"height\":[\"450\",\"700\",\"360\"],\"view\":\"basic\",\"keepAspectRatio\":true,\"preload\":0,\"layout\":\"fullwidth\",\"rtl\":false,\"initAfterAppear\":false,\"ajaxApiUrl\":\"https:\\\/\\\/www.ull.es\\\/masteres\\\/ciencias-de-las-religiones\\\/wp-admin\\\/admin-ajax.php\",\"mouseSwipe\":true,\"touchSwipe\":true,\"useWatermark\":false}\n\t);\n});\n<\/script><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns alignfull stk-block-columns stk--hide-mobile stk-block stk-6394276 stk-block-background\" data-block-id=\"6394276\"><style>.stk-6394276 {background-color:#fa6199 !important;padding-top:50px !important;padding-right:0px !important;padding-bottom:1px !important;padding-left:0px !important;margin-top:-40px !important;margin-bottom:0px !important;}.stk-6394276:before{background-color:#fa6199 !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-6394276-column alignfull\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-8a66885\" data-v=\"4\" data-block-id=\"8a66885\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-8a66885-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-8a66885-inner-blocks\">\n<div class=\"wp-block-stackable-spacer stk-block-spacer stk--no-padding stk-block stk-bc89b3e\" data-block-id=\"bc89b3e\"><style>.stk-bc89b3e {height:0px !important;}<\/style><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns stk-block-columns stk-block stk-8b59b96\" data-block-id=\"8b59b96\"><style>.stk-8b59b96 .stk--block-align-8b59b96{align-items:flex-start !important;}.stk-8b59b96 {margin-top:50px !important;}.stk-8b59b96-column{--stk-columns-spacing:0px !important;--stk-column-gap:50px !important;}@media screen and (max-width: 767px){.stk-8b59b96-column{row-gap:var(--stk--preset--spacing--60, 2.25rem) !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk--block-align-8b59b96 stk-block-content stk-content-align stk-8b59b96-column\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-dbb7e15\" data-v=\"4\" data-block-id=\"dbb7e15\"><style>@media screen and (min-width: 768px){.stk-dbb7e15 {flex:var(--stk-flex-grow, 1) 1 66.7% !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-dbb7e15-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-dbb7e15-inner-blocks\">\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-cc0239e\" id=\"complementos-de-formacion\" data-block-id=\"cc0239e\"><style>.stk-cc0239e .stk-block-heading__text{color:#fa6199 !important;font-weight:500 !important;}<\/style><h1 class=\"stk-block-heading__text has-text-color\">Plan de estudios<\/h1><\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"http:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones-historia-y-sociedad\/plan-de-estudios\/estructura-del-plan-de-estudios\/\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">Estructura del plan de estudios<\/a><\/li>\n\n\n\n<li><a href=\"http:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones-historia-y-sociedad\/plan-de-estudios\/competencias\/\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">Competencias<\/a><\/li>\n\n\n\n<li><a href=\"http:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones-historia-y-sociedad\/plan-de-estudios\/guias-docentes\/\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">Gu\u00edas docentes<\/a><\/li>\n\n\n\n<li><a href=\"http:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones-historia-y-sociedad\/plan-de-estudios\/trabajo-fin-de-master\/\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">Trabajo Fin de M\u00e1ster<\/a><\/li>\n<\/ul>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-53ec762\" data-v=\"4\" data-block-id=\"53ec762\"><style>.stk-53ec762-inner-blocks{row-gap:0px !important;}.stk-53ec762 {padding-top:0px !important;padding-right:0px !important;padding-bottom:0px !important;padding-left:0px !important;}@media screen and (min-width: 768px){.stk-53ec762 {flex:var(--stk-flex-grow, 1) 1 33.3% !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-53ec762-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-53ec762-inner-blocks\">\n\n<ul class=\"widget-box\">\n<li class='contacto-header'>Informaci\u00f3n de contacto<\/li><li><i class=\"fa fa-map-marker\"><\/i> Avda. Astrof\u00edsico Francisco S\u00e1nchez, SN. Edificio Calabaza \u2013 AN.2D Apdo. 456 38200 San Crist\u00f3bal de La Laguna<\/li><li><i class=\"fa fa-envelope\"><\/i>  <a href=mailto:master.religiones@ull.es>master.religiones@ull.es<\/a><\/li><li><i class=\"fa fa-archive\"><\/i><a href=\"https:\/\/sede.ull.es\/ecivilis-site\/catalog\/showProcedure\/484\"> Procedimiento para quejas, sugerencias y felicitaciones<\/a><\/li>\n<\/ul>\n\n\n<\/div><\/div><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Plan de estudios<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/template-frontpage.php","meta":{"footnotes":""},"class_list":["post-270","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Plan de estudios - M\u00e1ster Universitario en Ciencias de las Religiones: Historia y Sociedad<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/plan-de-estudios\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plan de estudios - M\u00e1ster Universitario en Ciencias de las Religiones: Historia y Sociedad\" \/>\n<meta property=\"og:description\" content=\"Plan de estudios\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/plan-de-estudios\/\" \/>\n<meta property=\"og:site_name\" content=\"M\u00e1ster Universitario en Ciencias de las Religiones: Historia y Sociedad\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-21T05:12:30+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ull.es\\\/masteres\\\/ciencias-de-las-religiones\\\/plan-de-estudios\\\/\",\"url\":\"https:\\\/\\\/www.ull.es\\\/masteres\\\/ciencias-de-las-religiones\\\/plan-de-estudios\\\/\",\"name\":\"Plan de estudios - M\u00e1ster Universitario en Ciencias de las Religiones: Historia y Sociedad\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ull.es\\\/masteres\\\/ciencias-de-las-religiones\\\/#website\"},\"datePublished\":\"2017-07-11T13:21:36+00:00\",\"dateModified\":\"2025-08-21T05:12:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ull.es\\\/masteres\\\/ciencias-de-las-religiones\\\/plan-de-estudios\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ull.es\\\/masteres\\\/ciencias-de-las-religiones\\\/plan-de-estudios\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ull.es\\\/masteres\\\/ciencias-de-las-religiones\\\/plan-de-estudios\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ull.es\\\/masteres\\\/ciencias-de-las-religiones\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Plan de estudios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ull.es\\\/masteres\\\/ciencias-de-las-religiones\\\/#website\",\"url\":\"https:\\\/\\\/www.ull.es\\\/masteres\\\/ciencias-de-las-religiones\\\/\",\"name\":\"M\u00e1ster Universitario en Ciencias de las Religiones: Historia y Sociedad\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ull.es\\\/masteres\\\/ciencias-de-las-religiones\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Plan de estudios - M\u00e1ster Universitario en Ciencias de las Religiones: Historia y Sociedad","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/plan-de-estudios\/","og_locale":"es_ES","og_type":"article","og_title":"Plan de estudios - M\u00e1ster Universitario en Ciencias de las Religiones: Historia y Sociedad","og_description":"Plan de estudios","og_url":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/plan-de-estudios\/","og_site_name":"M\u00e1ster Universitario en Ciencias de las Religiones: Historia y Sociedad","article_modified_time":"2025-08-21T05:12:30+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/plan-de-estudios\/","url":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/plan-de-estudios\/","name":"Plan de estudios - M\u00e1ster Universitario en Ciencias de las Religiones: Historia y Sociedad","isPartOf":{"@id":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/#website"},"datePublished":"2017-07-11T13:21:36+00:00","dateModified":"2025-08-21T05:12:30+00:00","breadcrumb":{"@id":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/plan-de-estudios\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/plan-de-estudios\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/plan-de-estudios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/"},{"@type":"ListItem","position":2,"name":"Plan de estudios"}]},{"@type":"WebSite","@id":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/#website","url":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/","name":"M\u00e1ster Universitario en Ciencias de las Religiones: Historia y Sociedad","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/wp-json\/wp\/v2\/pages\/270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/wp-json\/wp\/v2\/comments?post=270"}],"version-history":[{"count":5,"href":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/wp-json\/wp\/v2\/pages\/270\/revisions"}],"predecessor-version":[{"id":1119,"href":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/wp-json\/wp\/v2\/pages\/270\/revisions\/1119"}],"wp:attachment":[{"href":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/wp-json\/wp\/v2\/media?parent=270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}