{"id":302,"date":"2017-07-11T13:50:27","date_gmt":"2017-07-11T13:50:27","guid":{"rendered":"http:\/\/www.ull.es\/masteres\/desarrollo-y-gestion-de-recursos-humanos\/?page_id=302"},"modified":"2025-08-20T12:49:57","modified_gmt":"2025-08-20T12:49:57","slug":"documentacion-de-evaluacion-del-titulo","status":"publish","type":"page","link":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/calidad-y-resultados\/documentacion-de-evaluacion-del-titulo\/","title":{"rendered":"Documentaci\u00f3n de evaluaci\u00f3n del t\u00edtulo"},"content":{"rendered":"\n<div class=\"wp-block-stackable-columns alignfull stk-block-columns stk-block stk-2314a6b\" data-block-id=\"2314a6b\"><style>.stk-2314a6b {padding-bottom:0px !important;margin-top:-100px !important;margin-bottom:0px !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-2314a6b-column alignfull\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-1d1764d\" data-v=\"4\" data-block-id=\"1d1764d\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-1d1764d-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-1d1764d-inner-blocks\"><style id=\"depicter-1-inline-pre-css\">\n\n.depicter-1:not(.depicter-ready){\n\theight:450px;\n}\n\n\/***** Tablet *****\/\n@media screen and (max-width: 1024px){\n\n.depicter-1:not(.depicter-ready){\n\theight:700px;\n}\n\n}\n\/***** Mobile *****\/\n@media screen and (max-width: 767px){\n\n.depicter-1:not(.depicter-ready){\n\theight:360px;\n}\n\n}\n<\/style>\n<div id=\"depicter-1\" class=\"depicter depicter-document depicter-revert depicter-1 depicter-layout-fullwidth\">\n\n<div class=\"depicter-loading-container depicter-loading dotFlashing-dark\"><div class=\"depicter-loading-dark depicter-dot-flashing\">\n   <span><\/span>\n   <span><\/span>\n   <span><\/span>\n<\/div>\n<\/div>\n<div id=\"depicter-1-section-1\" class=\"depicter-section depicter-1-section-1\" data-name=\"Section 1\" data-type=\"section\" data-local-id=\"section-1\">\n<picture class=\"depicter-bg\">\n<source data-depicter-srcset=\"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/wp-content\/uploads\/sites\/26\/2025\/06\/Headers-Masteres_Ciencias-de-las-religiones-768x248.jpg, https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/wp-content\/uploads\/sites\/26\/2025\/06\/Headers-Masteres_Ciencias-de-las-religiones.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(max-width: 1024px)\" \/>\n\n<source data-depicter-srcset=\"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/wp-content\/uploads\/sites\/26\/2025\/06\/Headers-Masteres_Ciencias-de-las-religiones.jpg, https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/wp-content\/uploads\/sites\/26\/2025\/06\/Headers-Masteres_Ciencias-de-las-religiones-1280x413.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(min-width: 1025px)\" \/>\n<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-ken-burns=\"false\" data-tablet-ken-burns=\"false\" data-mobile-ken-burns=\"false\" alt=\"\" data-depicter-src=\"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/wp-content\/uploads\/sites\/26\/2025\/06\/Headers-Masteres_Ciencias-de-las-religiones.jpg\" data-object-fit=\"custom,custom,\" data-object-position=\"center top,,\" data-crop=\"{'focalPoint':{'x':0.5,'y':0.479999999999999982236431605997495353221893310546875},'mediaSize':{'width':1792,'height':578}}\" data-tablet-crop=\"{'focalPoint':{'x':0.5,'y':0.5},'mediaSize':{'width':2169.4915254237284898408688604831695556640625,'height':700}}\" data-mobile-crop=\"{'focalPoint':{'x':0.5,'y':0.5},'mediaSize':{'width':1394.6731234866829254315234720706939697265625,'height':450}}\" \/>\n<\/picture>\n\n\n<h1 id=\"depicter-1-element-5\" class=\"depicter-element depicter-layer depicter-1-element-5\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 2\" data-local-id=\"element-5\" data-offset=\"x:0px;y:118px;origin:tl\" data-tablet-offset=\"x:109px;y:220px;origin:tl\" data-mobile-offset=\"x:0px;y:78px;origin:tl\" data-width=\"1200px,808px,399px\" data-height=\"auto,auto,auto\" data-responsive-scale=\"true,,\">M\u00e1ster Universitario en Ciencias de las Religiones: Historia y Sociedad (Interuniversitario)<br><\/h1>\n\n<div id=\"depicter-1-element-10\" class=\"depicter-element depicter-layer depicter-1-element-10\" data-type=\"shape\" data-wrap=\"true\" data-name=\"Shape 1\" data-local-id=\"element-10\" data-offset=\"x:0px;y:366px;origin:tl\" data-tablet-offset=\"x:124px;y:521px;origin:tl\" data-mobile-offset=\"x:-9px;y:295px;origin:tl\" data-width=\"1126px,778px,408px\" data-height=\"8px,8px,8px\" data-responsive-scale=\"true,,\"><\/div>\n<\/div>\n<\/div>\n<script>\n(window.depicterSetups = window.depicterSetups || []).push(function(){\n\tDepicter.basePath = 'https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/wp-content\/plugins\/depicter\/resources\/scripts\/player\/';\n\tconst dpPlayer = Depicter.setup('.depicter-1',\n\t\t{\"width\":[\"1200\",\"1024\",\"360\"],\"height\":[\"450\",\"700\",\"360\"],\"view\":\"basic\",\"keepAspectRatio\":true,\"preload\":0,\"layout\":\"fullwidth\",\"rtl\":false,\"initAfterAppear\":false,\"ajaxApiUrl\":\"https:\\\/\\\/www.ull.es\\\/masteres\\\/ciencias-de-las-religiones\\\/wp-admin\\\/admin-ajax.php\",\"mouseSwipe\":true,\"touchSwipe\":true,\"useWatermark\":false}\n\t);\n});\n<\/script><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns alignfull stk-block-columns stk--hide-mobile stk-block stk-6394276 stk-block-background\" data-block-id=\"6394276\"><style>.stk-6394276 {background-color:#fa6199 !important;padding-top:50px !important;padding-right:0px !important;padding-bottom:1px !important;padding-left:0px !important;margin-top:-40px !important;margin-bottom:0px !important;}.stk-6394276:before{background-color:#fa6199 !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-6394276-column alignfull\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-8a66885\" data-v=\"4\" data-block-id=\"8a66885\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-8a66885-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-8a66885-inner-blocks\">\n<div class=\"wp-block-stackable-spacer stk-block-spacer stk--no-padding stk-block stk-bc89b3e\" data-block-id=\"bc89b3e\"><style>.stk-bc89b3e {height:0px !important;}<\/style><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns stk-block-columns stk-block stk-8b59b96\" data-block-id=\"8b59b96\"><style>.stk-8b59b96 .stk--block-align-8b59b96{align-items:flex-start !important;}.stk-8b59b96 {margin-top:50px !important;}.stk-8b59b96-column{--stk-columns-spacing:0px !important;--stk-column-gap:50px !important;}@media screen and (max-width: 767px){.stk-8b59b96-column{row-gap:var(--stk--preset--spacing--60, 2.25rem) !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk--block-align-8b59b96 stk-block-content stk-content-align stk-8b59b96-column\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-dbb7e15\" data-v=\"4\" data-block-id=\"dbb7e15\"><style>@media screen and (min-width: 768px){.stk-dbb7e15 {flex:var(--stk-flex-grow, 1) 1 66.7% !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-dbb7e15-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-dbb7e15-inner-blocks\">\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-cc0239e\" id=\"complementos-de-formacion\" data-block-id=\"cc0239e\"><style>.stk-cc0239e .stk-block-heading__text{color:#fa6199 !important;font-weight:500 !important;}<\/style><h1 class=\"stk-block-heading__text has-text-color\">Documentaci\u00f3n de evaluaci\u00f3n del t\u00edtulo<\/h1><\/div>\n\n\n\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-44a67f6\" data-block-id=\"44a67f6\"><p class=\"stk-block-text__text\">Las titulaciones oficiales de Grado, M\u00e1ster y Doctorado est\u00e1n sometidas, a un modelo de evaluaci\u00f3n dividido en tres fases que conforman su ciclo de vida (ciclo VSMA): ex ante (Verificaci\u00f3n), durante (Seguimiento y Modificaci\u00f3n) y ex post (renovaci\u00f3n de la Acreditaci\u00f3n). Este proceso de evaluaci\u00f3n, revisi\u00f3n y mejora se realiza con el objetivo de garantizar la calidad de las titulaciones y asegurar que se cumple con los requisitos y criterios establecidos en el marco del Espacio Europeo de Educaci\u00f3n Superior (EEES).<\/p><\/div>\n\n\n\n<p>El modelo queda recogido en la&nbsp;<a href=\"https:\/\/www.boe.es\/buscar\/act.php?id=BOE-A-2023-7500\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">Ley Org\u00e1nica 2\/2023<\/a>, del Sistema Universitario (LOSU) y en los Reales Decretos de ordenaci\u00f3n de las ense\u00f1anzas universitarias: fundamentalmente el&nbsp;<a href=\"https:\/\/www.boe.es\/buscar\/act.php?id=BOE-A-2021-15781\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">RD 822\/2021<\/a>, por el que se establece la organizaci\u00f3n de las ense\u00f1anzas universitarias y del procedimiento de aseguramiento de su calidad; el&nbsp;<a href=\"https:\/\/www.boe.es\/buscar\/act.php?id=BOE-A-2011-2541\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">RD 99\/2011<\/a>, por el que se regulan las ense\u00f1anzas oficiales de doctorado y el&nbsp;<a href=\"https:\/\/www.boe.es\/buscar\/act.php?id=BOE-A-2021-12613\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">RD 640\/2021<\/a>, de creaci\u00f3n, reconocimiento y autorizaci\u00f3n de universidades y centros universitarios, y acreditaci\u00f3n institucional de centros universitarios.<\/p>\n\n\n\n<p>Puede consultarse la documentaci\u00f3n oficial de los procesos de evaluaci\u00f3n del t\u00edtulo que certifica el cumplimiento de los est\u00e1ndares de calidad en los siguientes apartados.<\/p>\n\n\n\n<details class=\"wp-block-stackable-accordion stk-block-accordion stk-inner-blocks stk-block-content stk-block stk-7c390cd is-style-default\" id=\"verificacion\" data-block-id=\"7c390cd\"><style>.stk-7c390cd {border-style:solid !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;margin-bottom:11px !important;}<\/style>\n<summary class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-c927805 stk--container-small stk-block-accordion__heading\" data-v=\"4\" data-block-id=\"c927805\"><style>.stk-c927805 {padding-top:2px !important;padding-right:2px !important;padding-bottom:2px !important;padding-left:2px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-c927805-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-c927805-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-7935446\" data-block-id=\"7935446\"><style>.stk-7935446 .stk-inner-blocks{gap:39px !important;}@media screen and (max-width: 1023px){.stk-7935446 .stk-inner-blocks{gap:39px !important;}}@media screen and (max-width: 767px){.stk-7935446 .stk-inner-blocks{gap:39px !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-icon stk-block-icon stk-block stk-9a468d5\" data-block-id=\"9a468d5\"><style>.stk-9a468d5 .stk--svg-wrapper .stk--inner-svg svg:last-child{height:25px !important;width:25px !important;}.stk-9a468d5 .stk--svg-wrapper .stk--inner-svg svg:last-child, .stk-9a468d5 .stk--svg-wrapper .stk--inner-svg svg:last-child :is(g, path, rect, polygon, ellipse){fill:#fa6199 !important;}<\/style><span class=\"stk--svg-wrapper stk--has-icon2\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-9a468d5\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-9-a-468-d-5-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-9-a-468-d-5-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M256 512A256 256 0 1 0 256 0a256 256 0 1 0 0 512zM369 209L241 337c-9.4 9.4-24.6 9.4-33.9 0l-64-64c-9.4-9.4-9.4-24.6 0-33.9s24.6-9.4 33.9 0l47 47L335 175c9.4-9.4 24.6-9.4 33.9 0s9.4 24.6 0 33.9z\"><\/path><\/svg><\/div><div class=\"stk--inner-svg stk--icon-2\" style=\"display:none\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-9a468d5\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-9-a-468-d-5-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-9-a-468-d-5-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M256 48a208 208 0 1 1 0 416 208 208 0 1 1 0-416zm0 464A256 256 0 1 0 256 0a256 256 0 1 0 0 512zM369 209c9.4-9.4 9.4-24.6 0-33.9s-24.6-9.4-33.9 0l-111 111-47-47c-9.4-9.4-24.6-9.4-33.9 0s-9.4 24.6 0 33.9l64 64c9.4 9.4 24.6 9.4 33.9 0L369 209z\"><\/path><\/svg><\/div><\/span><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-31863c1\" id=\"verificacion-modificacion\" data-block-id=\"31863c1\"><style>.stk-31863c1 .stk-block-heading__text{color:#000000 !important;font-weight:500 !important;font-family:\"ArgentumSans\", Sans-serif !important;}<\/style><h4 class=\"stk-block-heading__text has-text-color\">Verificaci\u00f3n \/ Modificaci\u00f3n<\/h4><\/div>\n<\/div><\/div>\n<\/div><\/div><\/summary>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-5222666 stk-block-accordion__content\" data-v=\"4\" data-block-id=\"5222666\"><style>.stk-5222666 {margin-top:-30px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-5222666-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-5222666-inner-blocks\">\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-dfbe2d6\" data-block-id=\"dfbe2d6\"><p class=\"stk-block-text__text\"><strong>Memoria de Verificaci\u00f3n\/Modificaci\u00f3n<\/strong><\/p><\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/drive.google.com\/file\/d\/19YOvppDbdQv62yiv4l8-lQ6vU-0OrbaP\/view?usp=sharing\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">Memoria del M\u00e1ster en Ciencias de las Religiones<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.educacion.gob.es\/ruct\/estudio.action?codigoCiclo=SC&amp;codigoTipo=M&amp;CodigoEstudio=4316234&amp;actual=estudios\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">Enlace al Registro de Universidades, Centros y T\u00edtulos (RUCT)<\/a><\/li>\n<\/ul>\n\n\n\n<p><strong>Documentos de tr\u00e1mite: ANECA-Consejo Universidades (Ministerio Educaci\u00f3n)<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Informe Final Favorable de Verificaci\u00f3n<\/li>\n\n\n\n<li>Resoluci\u00f3n de Verificaci\u00f3n del Consejo de Universidades<\/li>\n<\/ul>\n\n\n\n<p><strong>Documentos de tr\u00e1mite:&nbsp;<\/strong><strong>ACCUEE-<\/strong><strong>ACECAU (CCAA Canarias)<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/drive.google.com\/open?id=1b7WmYGf52slCdaitrZxu64ojJlnJm3lb\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">Informe Definitivo Favorable de Autorizaci\u00f3n de la Implantaci\u00f3n (2017)<\/a><\/li>\n<\/ul>\n\n\n\n<p><strong>Publicaci\u00f3n Plan de Estudios (BOC-BOE)<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"http:\/\/www.gobiernodecanarias.org\/boc\/2018\/021\/005.html\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">Publicaci\u00f3n BOC (Decreto 1\/2018, de 22 de enero: autorizaci\u00f3n)<\/a><\/li>\n\n\n\n<li>Publicaci\u00f3n BOE<\/li>\n<\/ul>\n<\/div><\/div><\/div>\n<\/details>\n\n\n\n<details class=\"wp-block-stackable-accordion stk-block-accordion stk-inner-blocks stk-block-content stk-block stk-88a7c9c is-style-default\" id=\"seguimiento\" data-block-id=\"88a7c9c\"><style>.stk-88a7c9c {border-style:solid !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;margin-bottom:10px !important;}<\/style>\n<summary class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-27019df stk--container-small stk-block-accordion__heading\" data-v=\"4\" data-block-id=\"27019df\"><style>.stk-27019df {padding-top:2px !important;padding-right:2px !important;padding-bottom:2px !important;padding-left:2px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-27019df-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-27019df-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-9c9ce7e\" data-block-id=\"9c9ce7e\"><style>.stk-9c9ce7e .stk-inner-blocks{gap:39px !important;}@media screen and (max-width: 1023px){.stk-9c9ce7e .stk-inner-blocks{gap:39px !important;}}@media screen and (max-width: 767px){.stk-9c9ce7e .stk-inner-blocks{gap:39px !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-icon stk-block-icon stk-block stk-61c8ad3\" data-block-id=\"61c8ad3\"><style>.stk-61c8ad3 .stk--svg-wrapper .stk--inner-svg svg:last-child{height:25px !important;width:25px !important;}.stk-61c8ad3 .stk--svg-wrapper .stk--inner-svg svg:last-child, .stk-61c8ad3 .stk--svg-wrapper .stk--inner-svg svg:last-child :is(g, path, rect, polygon, ellipse){fill:#fa6199 !important;}<\/style><span class=\"stk--svg-wrapper stk--has-icon2\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-61c8ad3\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-61-c-8-ad-3-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-61-c-8-ad-3-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M256 512A256 256 0 1 0 256 0a256 256 0 1 0 0 512zM216 336h24V272H216c-13.3 0-24-10.7-24-24s10.7-24 24-24h48c13.3 0 24 10.7 24 24v88h8c13.3 0 24 10.7 24 24s-10.7 24-24 24H216c-13.3 0-24-10.7-24-24s10.7-24 24-24zm40-208a32 32 0 1 1 0 64 32 32 0 1 1 0-64z\"><\/path><\/svg><\/div><div class=\"stk--inner-svg stk--icon-2\" style=\"display:none\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-61c8ad3\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-61-c-8-ad-3-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-61-c-8-ad-3-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 192 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M48 80a48 48 0 1 1 96 0A48 48 0 1 1 48 80zM0 224c0-17.7 14.3-32 32-32H96c17.7 0 32 14.3 32 32V448h32c17.7 0 32 14.3 32 32s-14.3 32-32 32H32c-17.7 0-32-14.3-32-32s14.3-32 32-32H64V256H32c-17.7 0-32-14.3-32-32z\"><\/path><\/svg><\/div><\/span><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-bcb6d4e\" id=\"seguimiento\" data-block-id=\"bcb6d4e\"><style>.stk-bcb6d4e .stk-block-heading__text{color:#000000 !important;font-weight:500 !important;font-family:\"ArgentumSans\", Sans-serif !important;}<\/style><h4 class=\"stk-block-heading__text has-text-color\">Seguimiento<\/h4><\/div>\n<\/div><\/div>\n<\/div><\/div><\/summary>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-76d605c stk-block-accordion__content\" data-v=\"4\" data-block-id=\"76d605c\"><style>.stk-76d605c {margin-top:-30px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-76d605c-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-76d605c-inner-blocks\">\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-0b5bcfd\" data-block-id=\"0b5bcfd\"><p class=\"stk-block-text__text\">En l\u00ednea con las directrices establecidas a nivel nacional (RD 822\/2021), la agencia de evaluaci\u00f3n establece el Protocolo de Seguimiento que deben seguir las Titulaciones Oficiales implantadas. Este seguimiento se centra, por un lado, en comprobar el cumplimiento del proyecto establecido en la Memoria de Verificaci\u00f3n vigente y en constatar el adecuado desarrollo de la implantaci\u00f3n, actualizaci\u00f3n y mejora del t\u00edtulo.<\/p><\/div>\n\n\n\n<p><a href=\"https:\/\/www.upo.es\/postgrado\/Master-Oficial-Ciencias-de-las-Religiones-Historia-y-Sociedad\/#compromiso-calidad\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">Informes de Seguimiento Internos<\/a>&nbsp;(v\u00e9ase web de la universidad coordinadora)<\/p>\n\n\n\n<p>Informes de Seguimiento Externos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Cat\u00e1logo de T\u00edtulos oficiales \u2013 Consulta de Informes de evaluaci\u00f3n (<a href=\"https:\/\/ws262.juntadeandalucia.es\/accua\/?id=informestitulos\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">ACCUA \u2013 Andaluc\u00eda<\/a>)<\/li>\n<\/ul>\n<\/div><\/div><\/div>\n<\/details>\n\n\n\n<details class=\"wp-block-stackable-accordion stk-block-accordion stk-inner-blocks stk-block-content stk-block stk-6320006 is-style-default\" id=\"acreditacion\" data-block-id=\"6320006\"><style>.stk-6320006 {border-style:solid !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;margin-bottom:9px !important;}<\/style>\n<summary class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-ae2ad76 stk--container-small stk-block-accordion__heading\" data-v=\"4\" data-block-id=\"ae2ad76\"><style>.stk-ae2ad76 {padding-top:2px !important;padding-right:2px !important;padding-bottom:2px !important;padding-left:2px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-ae2ad76-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-ae2ad76-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-16db2af\" data-block-id=\"16db2af\"><style>.stk-16db2af .stk-inner-blocks{gap:39px !important;}@media screen and (max-width: 1023px){.stk-16db2af .stk-inner-blocks{gap:39px !important;}}@media screen and (max-width: 767px){.stk-16db2af .stk-inner-blocks{gap:39px !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-icon stk-block-icon stk-block stk-38bb3f8\" data-block-id=\"38bb3f8\"><style>.stk-38bb3f8 .stk--svg-wrapper .stk--inner-svg svg:last-child{height:25px !important;width:25px !important;}.stk-38bb3f8 .stk--svg-wrapper .stk--inner-svg svg:last-child, .stk-38bb3f8 .stk--svg-wrapper .stk--inner-svg svg:last-child :is(g, path, rect, polygon, ellipse){fill:#fa6199 !important;}<\/style><span class=\"stk--svg-wrapper stk--has-icon2\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-38bb3f8\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-38-bb-3-f-8-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-38-bb-3-f-8-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 576 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M64 32C28.7 32 0 60.7 0 96V416c0 35.3 28.7 64 64 64H512c35.3 0 64-28.7 64-64V96c0-35.3-28.7-64-64-64H64zm80 256h64c44.2 0 80 35.8 80 80c0 8.8-7.2 16-16 16H80c-8.8 0-16-7.2-16-16c0-44.2 35.8-80 80-80zm-32-96a64 64 0 1 1 128 0 64 64 0 1 1 -128 0zm256-32H496c8.8 0 16 7.2 16 16s-7.2 16-16 16H368c-8.8 0-16-7.2-16-16s7.2-16 16-16zm0 64H496c8.8 0 16 7.2 16 16s-7.2 16-16 16H368c-8.8 0-16-7.2-16-16s7.2-16 16-16zm0 64H496c8.8 0 16 7.2 16 16s-7.2 16-16 16H368c-8.8 0-16-7.2-16-16s7.2-16 16-16z\"><\/path><\/svg><\/div><div class=\"stk--inner-svg stk--icon-2\" style=\"display:none\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-38bb3f8\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-38-bb-3-f-8-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-38-bb-3-f-8-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 576 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M512 80c8.8 0 16 7.2 16 16V416c0 8.8-7.2 16-16 16H64c-8.8 0-16-7.2-16-16V96c0-8.8 7.2-16 16-16H512zM64 32C28.7 32 0 60.7 0 96V416c0 35.3 28.7 64 64 64H512c35.3 0 64-28.7 64-64V96c0-35.3-28.7-64-64-64H64zM208 256a64 64 0 1 0 0-128 64 64 0 1 0 0 128zm-32 32c-44.2 0-80 35.8-80 80c0 8.8 7.2 16 16 16H304c8.8 0 16-7.2 16-16c0-44.2-35.8-80-80-80H176zM376 144c-13.3 0-24 10.7-24 24s10.7 24 24 24h80c13.3 0 24-10.7 24-24s-10.7-24-24-24H376zm0 96c-13.3 0-24 10.7-24 24s10.7 24 24 24h80c13.3 0 24-10.7 24-24s-10.7-24-24-24H376z\"><\/path><\/svg><\/div><\/span><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-a35761a\" id=\"acreditacion\" data-block-id=\"a35761a\"><style>.stk-a35761a .stk-block-heading__text{color:#000000 !important;font-weight:500 !important;font-family:\"ArgentumSans\", Sans-serif !important;}<\/style><h4 class=\"stk-block-heading__text has-text-color\">Acreditaci\u00f3n<\/h4><\/div>\n<\/div><\/div>\n<\/div><\/div><\/summary>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-81ecc51 stk-block-accordion__content\" data-v=\"4\" data-block-id=\"81ecc51\"><style>.stk-81ecc51 {margin-top:-30px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-81ecc51-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-81ecc51-inner-blocks\">\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-1433ccd\" data-block-id=\"1433ccd\"><p class=\"stk-block-text__text\">Dentro del proceso de Renovaci\u00f3n de la Acreditaci\u00f3n, y una vez finalizada la fase de evaluaci\u00f3n interna, se procede a la publicaci\u00f3n del \u00faltimo Informe de Autoevaluaci\u00f3n (IA):<\/p><\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.upo.es\/postgrado\/Master-Oficial-Ciencias-de-las-Religiones-Historia-y-Sociedad\/#compromiso-calidad\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">Informes de Autoevaluaci\u00f3n renovaci\u00f3n de la acreditaci\u00f3n<\/a>&nbsp;(v\u00e9ase web de la universidad coordinadora)<\/li>\n<\/ul>\n\n\n\n<p>Como resultado se obtiene la Renovaci\u00f3n de la Acreditaci\u00f3n en t\u00e9rminos FAVORABLES.<\/p>\n\n\n\n<p>Informes Finales de Acreditaci\u00f3n (externos):<\/p>\n\n\n\n<p>Cat\u00e1logo de T\u00edtulos oficiales \u2013 Consulta de Informes de evaluaci\u00f3n (<a href=\"https:\/\/ws262.juntadeandalucia.es\/accua\/?id=informestitulos\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">ACCUA \u2013 Andaluc\u00eda<\/a>)<\/p>\n<\/div><\/div><\/div>\n<\/details>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-53ec762\" data-v=\"4\" data-block-id=\"53ec762\"><style>.stk-53ec762-inner-blocks{row-gap:0px !important;}.stk-53ec762 {padding-top:0px !important;padding-right:0px !important;padding-bottom:0px !important;padding-left:0px !important;}@media screen and (min-width: 768px){.stk-53ec762 {flex:var(--stk-flex-grow, 1) 1 33.3% !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-53ec762-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-53ec762-inner-blocks\">\n\n<ul class=\"widget-box\">\n<li class='contacto-header'>Informaci\u00f3n de contacto<\/li><li><i class=\"fa fa-map-marker\"><\/i> Avda. Astrof\u00edsico Francisco S\u00e1nchez, SN. Edificio Calabaza \u2013 AN.2D Apdo. 456 38200 San Crist\u00f3bal de La Laguna<\/li><li><i class=\"fa fa-envelope\"><\/i>  <a href=mailto:master.religiones@ull.es>master.religiones@ull.es<\/a><\/li><li><i class=\"fa fa-archive\"><\/i><a href=\"https:\/\/sede.ull.es\/ecivilis-site\/catalog\/showProcedure\/484\"> Procedimiento para quejas, sugerencias y felicitaciones<\/a><\/li>\n<\/ul>\n\n\n<\/div><\/div><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Documentaci\u00f3n de evaluaci\u00f3n del t\u00edtulo Las titulaciones oficiales de Grado, M\u00e1ster y Doctorado est\u00e1n sometidas, a un modelo de evaluaci\u00f3n dividido en tres fases que conforman su ciclo de vida (ciclo VSMA): ex ante (Verificaci\u00f3n), durante (Seguimiento y Modificaci\u00f3n) y ex post (renovaci\u00f3n de la Acreditaci\u00f3n). Este proceso de evaluaci\u00f3n, revisi\u00f3n y mejora se realiza&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":261,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/template-frontpage.php","meta":{"footnotes":""},"class_list":["post-302","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Documentaci\u00f3n de evaluaci\u00f3n del t\u00edtulo - M\u00e1ster Universitario en Ciencias de las Religiones: Historia y Sociedad<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/calidad-y-resultados\/documentacion-de-evaluacion-del-titulo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Documentaci\u00f3n de evaluaci\u00f3n del t\u00edtulo - M\u00e1ster Universitario en Ciencias de las Religiones: Historia y Sociedad\" \/>\n<meta property=\"og:description\" content=\"Documentaci\u00f3n de evaluaci\u00f3n del t\u00edtulo Las titulaciones oficiales de Grado, M\u00e1ster y Doctorado est\u00e1n sometidas, a un modelo de evaluaci\u00f3n dividido en tres fases que conforman su ciclo de vida (ciclo VSMA): ex ante (Verificaci\u00f3n), durante (Seguimiento y Modificaci\u00f3n) y ex post (renovaci\u00f3n de la Acreditaci\u00f3n). Este proceso de evaluaci\u00f3n, revisi\u00f3n y mejora se realiza...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/calidad-y-resultados\/documentacion-de-evaluacion-del-titulo\/\" \/>\n<meta property=\"og:site_name\" content=\"M\u00e1ster Universitario en Ciencias de las Religiones: Historia y Sociedad\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-20T12:49:57+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ull.es\\\/masteres\\\/ciencias-de-las-religiones\\\/calidad-y-resultados\\\/documentacion-de-evaluacion-del-titulo\\\/\",\"url\":\"https:\\\/\\\/www.ull.es\\\/masteres\\\/ciencias-de-las-religiones\\\/calidad-y-resultados\\\/documentacion-de-evaluacion-del-titulo\\\/\",\"name\":\"Documentaci\u00f3n de evaluaci\u00f3n del t\u00edtulo - M\u00e1ster Universitario en Ciencias de las Religiones: Historia y Sociedad\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ull.es\\\/masteres\\\/ciencias-de-las-religiones\\\/#website\"},\"datePublished\":\"2017-07-11T13:50:27+00:00\",\"dateModified\":\"2025-08-20T12:49:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ull.es\\\/masteres\\\/ciencias-de-las-religiones\\\/calidad-y-resultados\\\/documentacion-de-evaluacion-del-titulo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ull.es\\\/masteres\\\/ciencias-de-las-religiones\\\/calidad-y-resultados\\\/documentacion-de-evaluacion-del-titulo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ull.es\\\/masteres\\\/ciencias-de-las-religiones\\\/calidad-y-resultados\\\/documentacion-de-evaluacion-del-titulo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ull.es\\\/masteres\\\/ciencias-de-las-religiones\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Calidad y resultados\",\"item\":\"https:\\\/\\\/www.ull.es\\\/masteres\\\/ciencias-de-las-religiones\\\/en\\\/calidad-y-resultados\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Documentaci\u00f3n de evaluaci\u00f3n del t\u00edtulo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ull.es\\\/masteres\\\/ciencias-de-las-religiones\\\/#website\",\"url\":\"https:\\\/\\\/www.ull.es\\\/masteres\\\/ciencias-de-las-religiones\\\/\",\"name\":\"M\u00e1ster Universitario en Ciencias de las Religiones: Historia y Sociedad\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ull.es\\\/masteres\\\/ciencias-de-las-religiones\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Documentaci\u00f3n de evaluaci\u00f3n del t\u00edtulo - M\u00e1ster Universitario en Ciencias de las Religiones: Historia y Sociedad","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/calidad-y-resultados\/documentacion-de-evaluacion-del-titulo\/","og_locale":"es_ES","og_type":"article","og_title":"Documentaci\u00f3n de evaluaci\u00f3n del t\u00edtulo - M\u00e1ster Universitario en Ciencias de las Religiones: Historia y Sociedad","og_description":"Documentaci\u00f3n de evaluaci\u00f3n del t\u00edtulo Las titulaciones oficiales de Grado, M\u00e1ster y Doctorado est\u00e1n sometidas, a un modelo de evaluaci\u00f3n dividido en tres fases que conforman su ciclo de vida (ciclo VSMA): ex ante (Verificaci\u00f3n), durante (Seguimiento y Modificaci\u00f3n) y ex post (renovaci\u00f3n de la Acreditaci\u00f3n). Este proceso de evaluaci\u00f3n, revisi\u00f3n y mejora se realiza...","og_url":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/calidad-y-resultados\/documentacion-de-evaluacion-del-titulo\/","og_site_name":"M\u00e1ster Universitario en Ciencias de las Religiones: Historia y Sociedad","article_modified_time":"2025-08-20T12:49:57+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/calidad-y-resultados\/documentacion-de-evaluacion-del-titulo\/","url":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/calidad-y-resultados\/documentacion-de-evaluacion-del-titulo\/","name":"Documentaci\u00f3n de evaluaci\u00f3n del t\u00edtulo - M\u00e1ster Universitario en Ciencias de las Religiones: Historia y Sociedad","isPartOf":{"@id":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/#website"},"datePublished":"2017-07-11T13:50:27+00:00","dateModified":"2025-08-20T12:49:57+00:00","breadcrumb":{"@id":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/calidad-y-resultados\/documentacion-de-evaluacion-del-titulo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/calidad-y-resultados\/documentacion-de-evaluacion-del-titulo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/calidad-y-resultados\/documentacion-de-evaluacion-del-titulo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/"},{"@type":"ListItem","position":2,"name":"Calidad y resultados","item":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/en\/calidad-y-resultados\/"},{"@type":"ListItem","position":3,"name":"Documentaci\u00f3n de evaluaci\u00f3n del t\u00edtulo"}]},{"@type":"WebSite","@id":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/#website","url":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/","name":"M\u00e1ster Universitario en Ciencias de las Religiones: Historia y Sociedad","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/wp-json\/wp\/v2\/pages\/302","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/wp-json\/wp\/v2\/comments?post=302"}],"version-history":[{"count":28,"href":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/wp-json\/wp\/v2\/pages\/302\/revisions"}],"predecessor-version":[{"id":1115,"href":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/wp-json\/wp\/v2\/pages\/302\/revisions\/1115"}],"up":[{"embeddable":true,"href":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/wp-json\/wp\/v2\/pages\/261"}],"wp:attachment":[{"href":"https:\/\/www.ull.es\/masteres\/ciencias-de-las-religiones\/wp-json\/wp\/v2\/media?parent=302"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}