{"id":16,"date":"2017-06-28T12:47:07","date_gmt":"2017-06-28T12:47:07","guid":{"rendered":"http:\/\/www.ull.es\/masteres\/desarrollo-y-gestion-de-recursos-humanos\/?page_id=16"},"modified":"2025-08-21T09:01:13","modified_gmt":"2025-08-21T09:01:13","slug":"sistema-de-garantia-interna-de-calidad","status":"publish","type":"page","link":"https:\/\/www.ull.es\/masteres\/desarrollo-regional\/calidad-y-resultados\/sistema-de-garantia-interna-de-calidad\/","title":{"rendered":"Sistema de Garant\u00eda Interna de Calidad"},"content":{"rendered":"\n<div class=\"wp-block-stackable-columns alignfull stk-block-columns stk-block stk-2314a6b\" data-block-id=\"2314a6b\"><style>.stk-2314a6b {padding-bottom:0px !important;margin-top:-100px !important;margin-bottom:0px !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-2314a6b-column alignfull\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-1d1764d\" data-v=\"4\" data-block-id=\"1d1764d\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-1d1764d-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-1d1764d-inner-blocks\"><style id=\"depicter-1-inline-pre-css\">\n\n.depicter-1:not(.depicter-ready){\n\theight:450px;\n}\n\n\/***** Tablet *****\/\n@media screen and (max-width: 1024px){\n\n.depicter-1:not(.depicter-ready){\n\theight:700px;\n}\n\n}\n\/***** Mobile *****\/\n@media screen and (max-width: 767px){\n\n.depicter-1:not(.depicter-ready){\n\theight:360px;\n}\n\n}\n<\/style>\n<div id=\"depicter-1\" class=\"depicter depicter-document depicter-revert depicter-1 depicter-layout-fullwidth\">\n\n<div class=\"depicter-loading-container depicter-loading dotFlashing-dark\"><div class=\"depicter-loading-dark depicter-dot-flashing\">\n   <span><\/span>\n   <span><\/span>\n   <span><\/span>\n<\/div>\n<\/div>\n<div id=\"depicter-1-section-1\" class=\"depicter-section depicter-1-section-1\" data-name=\"Section 1\" data-type=\"section\" data-local-id=\"section-1\">\n<picture class=\"depicter-bg\">\n<source data-depicter-srcset=\"https:\/\/www.ull.es\/masteres\/desarrollo-regional\/wp-content\/uploads\/sites\/29\/2025\/07\/Headers-Masteres_Desarrollo-Regional-768x248.jpg, https:\/\/www.ull.es\/masteres\/desarrollo-regional\/wp-content\/uploads\/sites\/29\/2025\/07\/Headers-Masteres_Desarrollo-Regional.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(max-width: 1024px)\" \/>\n\n<source data-depicter-srcset=\"https:\/\/www.ull.es\/masteres\/desarrollo-regional\/wp-content\/uploads\/sites\/29\/2025\/07\/Headers-Masteres_Desarrollo-Regional.jpg, https:\/\/www.ull.es\/masteres\/desarrollo-regional\/wp-content\/uploads\/sites\/29\/2025\/07\/Headers-Masteres_Desarrollo-Regional-1280x413.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(min-width: 1025px)\" \/>\n<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-ken-burns=\"false\" data-tablet-ken-burns=\"false\" data-mobile-ken-burns=\"false\" alt=\"\" data-depicter-src=\"https:\/\/www.ull.es\/masteres\/desarrollo-regional\/wp-content\/uploads\/sites\/29\/2025\/07\/Headers-Masteres_Desarrollo-Regional.jpg\" data-object-fit=\"custom,custom,\" data-object-position=\"center top,,\" data-crop=\"{'focalPoint':{'x':0.5,'y':0.5},'mediaSize':{'width':1394.6731234866829254315234720706939697265625,'height':450}}\" data-tablet-crop=\"{'focalPoint':{'x':0.5,'y':0.5},'mediaSize':{'width':2169.4915254237284898408688604831695556640625,'height':700}}\" data-mobile-crop=\"{'focalPoint':{'x':0.5,'y':0.5},'mediaSize':{'width':1394.6731234866829254315234720706939697265625,'height':450}}\" \/>\n<\/picture>\n\n\n<h1 id=\"depicter-1-element-5\" class=\"depicter-element depicter-layer depicter-1-element-5\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 2\" data-local-id=\"element-5\" data-offset=\"x:0px;y:141px;origin:tl\" data-tablet-offset=\"x:196px;y:223px;origin:tl\" data-mobile-offset=\"x:0px;y:84px;origin:tl\" data-width=\"1200px,633px,398px\" data-height=\"auto,auto,auto\" data-responsive-scale=\"true,,\">M\u00e1ster Universitario en Desarrollo Regional<br><\/h1>\n\n<div id=\"depicter-1-element-10\" class=\"depicter-element depicter-layer depicter-1-element-10\" data-type=\"shape\" data-wrap=\"true\" data-name=\"Shape 1\" data-local-id=\"element-10\" data-offset=\"x:0px;y:318px;origin:tl\" data-tablet-offset=\"x:189px;y:455px;origin:tl\" data-mobile-offset=\"x:-16px;y:290px;origin:tl\" data-width=\"1200px,647px,408px\" data-height=\"8px,8px,8px\" data-responsive-scale=\"true,,\"><\/div>\n<\/div>\n<\/div>\n<script>\n(window.depicterSetups = window.depicterSetups || []).push(function(){\n\tDepicter.basePath = 'https:\/\/www.ull.es\/masteres\/desarrollo-regional\/wp-content\/plugins\/depicter\/resources\/scripts\/player\/';\n\tconst dpPlayer = Depicter.setup('.depicter-1',\n\t\t{\"width\":[\"1200\",\"1024\",\"360\"],\"height\":[\"450\",\"700\",\"360\"],\"view\":\"basic\",\"keepAspectRatio\":true,\"preload\":0,\"layout\":\"fullwidth\",\"rtl\":false,\"initAfterAppear\":false,\"ajaxApiUrl\":\"https:\\\/\\\/www.ull.es\\\/masteres\\\/desarrollo-regional\\\/wp-admin\\\/admin-ajax.php\",\"mouseSwipe\":true,\"touchSwipe\":true,\"useWatermark\":false}\n\t);\n});\n<\/script><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns alignfull stk-block-columns stk--hide-mobile stk-block stk-6394276 stk-block-background\" data-block-id=\"6394276\"><style>.stk-6394276 {background-color:#fa6199 !important;padding-top:50px !important;padding-right:0px !important;padding-bottom:1px !important;padding-left:0px !important;margin-top:-40px !important;margin-bottom:0px !important;}.stk-6394276:before{background-color:#fa6199 !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-6394276-column alignfull\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-8a66885\" data-v=\"4\" data-block-id=\"8a66885\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-8a66885-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-8a66885-inner-blocks\">\n<div class=\"wp-block-stackable-spacer stk-block-spacer stk--no-padding stk-block stk-bc89b3e\" data-block-id=\"bc89b3e\"><style>.stk-bc89b3e {height:0px !important;}<\/style><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns stk-block-columns stk-block stk-8b59b96\" data-block-id=\"8b59b96\"><style>.stk-8b59b96 .stk--block-align-8b59b96{align-items:flex-start !important;}.stk-8b59b96 {margin-top:50px !important;}.stk-8b59b96-column{--stk-columns-spacing:0px !important;--stk-column-gap:50px !important;}@media screen and (max-width: 767px){.stk-8b59b96-column{row-gap:var(--stk--preset--spacing--60, 2.25rem) !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk--block-align-8b59b96 stk-block-content stk-content-align stk-8b59b96-column\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-dbb7e15\" data-v=\"4\" data-block-id=\"dbb7e15\"><style>@media screen and (min-width: 768px){.stk-dbb7e15 {flex:var(--stk-flex-grow, 1) 1 66.7% !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-dbb7e15-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-dbb7e15-inner-blocks\">\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-cc0239e\" id=\"complementos-de-formacion\" data-block-id=\"cc0239e\"><style>.stk-cc0239e .stk-block-heading__text{color:#fa6199 !important;font-weight:500 !important;}<\/style><h1 class=\"stk-block-heading__text has-text-color\">Sistema de Garant\u00eda Interna de Calidad<\/h1><\/div>\n\n\n\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-44a67f6\" data-block-id=\"44a67f6\"><p class=\"stk-block-text__text\">El Sistema de Aseguramiento Interno de Calidad del T\u00edtulo (SAIC) (anteriormente Sistema de Garant\u00eda Interna de Calidad -SGIC-) constituye el compromiso de la universidad con el establecimiento y despliegue de la cultura de calidad en los programas formativos, la mejora continua y la rendici\u00f3n de cuentas.<\/p><\/div>\n\n\n\n<p>Contempla procedimientos dise\u00f1ados a partir de los criterios y directrices para el aseguramiento de la calidad establecidas en el EEES (<a href=\"https:\/\/www.enqa.eu\/esg-standards-and-guidelines-for-quality-assurance-in-the-european-higher-education-area\/\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">ESG, 2015<\/a>), en la normativa nacional y desarrollados en los programas de evaluaci\u00f3n de las agencias de calidad. Est\u00e1n centrados en actividades relacionadas con la gesti\u00f3n, an\u00e1lisis, revisi\u00f3n y mejora de los t\u00edtulos, la&nbsp;<strong>ense\u00f1anza-aprendizaje<\/strong>&nbsp;centrada en el estudiantado, la actividad docente del&nbsp;<strong>profesorado<\/strong>, la&nbsp;<strong>satisfacci\u00f3n y opini\u00f3n<\/strong>&nbsp;de los grupos de inter\u00e9s, la&nbsp;<strong>inserci\u00f3n&nbsp;<\/strong><strong>laboral<\/strong>&nbsp;de las personas egresadas y la&nbsp;<strong>informaci\u00f3n<\/strong>&nbsp;<strong>p\u00fablica<\/strong>, entre otras.<\/p>\n\n\n\n<p>A trav\u00e9s de los mecanismos y procedimientos establecidos en el SAIC se garantiza la recogida y el an\u00e1lisis continuo de la informaci\u00f3n y de los resultados relevantes para la gesti\u00f3n eficaz del t\u00edtulo, as\u00ed como la participaci\u00f3n de los&nbsp;<a href=\"https:\/\/drive.google.com\/file\/d\/1_n3Iax-W7ps4WAmP2yLyd3fHS-rktzu0\/view?usp=share_link\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">grupos de inter\u00e9s<\/a>.<\/p>\n\n\n\n<p>La informaci\u00f3n sobre cada uno de los procedimientos del SAIC puede consultarse en los apartados siguientes.<\/p>\n\n\n\n<details class=\"wp-block-stackable-accordion stk-block-accordion stk-inner-blocks stk-block-content stk-block stk-7c390cd is-style-default\" id=\"responsables\" data-block-id=\"7c390cd\"><style>.stk-7c390cd {border-style:solid !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;margin-bottom:11px !important;}<\/style>\n<summary class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-c927805 stk--container-small stk-block-accordion__heading\" data-v=\"4\" data-block-id=\"c927805\"><style>.stk-c927805 {padding-top:2px !important;padding-right:2px !important;padding-bottom:2px !important;padding-left:2px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-c927805-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-c927805-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-7935446\" data-block-id=\"7935446\"><style>.stk-7935446 .stk-inner-blocks{gap:39px !important;}@media screen and (max-width: 1023px){.stk-7935446 .stk-inner-blocks{gap:39px !important;}}@media screen and (max-width: 767px){.stk-7935446 .stk-inner-blocks{gap:39px !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-icon stk-block-icon stk-block stk-9a468d5\" data-block-id=\"9a468d5\"><style>.stk-9a468d5 .stk--svg-wrapper .stk--inner-svg svg:last-child{height:25px !important;width:25px !important;}.stk-9a468d5 .stk--svg-wrapper .stk--inner-svg svg:last-child, .stk-9a468d5 .stk--svg-wrapper .stk--inner-svg svg:last-child :is(g, path, rect, polygon, ellipse){fill:#fa6199 !important;}<\/style><span class=\"stk--svg-wrapper stk--has-icon2\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-9a468d5\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-9-a-468-d-5-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-9-a-468-d-5-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M224 256A128 128 0 1 0 224 0a128 128 0 1 0 0 256zm-45.7 48C79.8 304 0 383.8 0 482.3C0 498.7 13.3 512 29.7 512H418.3c16.4 0 29.7-13.3 29.7-29.7C448 383.8 368.2 304 269.7 304H178.3z\"><\/path><\/svg><\/div><div class=\"stk--inner-svg stk--icon-2\" style=\"display:none\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-9a468d5\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-9-a-468-d-5-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-9-a-468-d-5-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M304 128a80 80 0 1 0 -160 0 80 80 0 1 0 160 0zM96 128a128 128 0 1 1 256 0A128 128 0 1 1 96 128zM49.3 464H398.7c-8.9-63.3-63.3-112-129-112H178.3c-65.7 0-120.1 48.7-129 112zM0 482.3C0 383.8 79.8 304 178.3 304h91.4C368.2 304 448 383.8 448 482.3c0 16.4-13.3 29.7-29.7 29.7H29.7C13.3 512 0 498.7 0 482.3z\"><\/path><\/svg><\/div><\/span><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-31863c1\" id=\"responsables\" data-block-id=\"31863c1\"><style>.stk-31863c1 .stk-block-heading__text{color:#000000 !important;font-weight:500 !important;font-family:\"ArgentumSans\", Sans-serif !important;}<\/style><h4 class=\"stk-block-heading__text has-text-color\">Responsables<\/h4><\/div>\n<\/div><\/div>\n<\/div><\/div><\/summary>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-5222666 stk-block-accordion__content\" data-v=\"4\" data-block-id=\"5222666\"><style>.stk-5222666 {margin-top:-30px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-5222666-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-5222666-inner-blocks\">\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-dfbe2d6\" data-block-id=\"dfbe2d6\"><p class=\"stk-block-text__text\">Los \u00f3rganos responsables del SAIC asumen el compromiso de garantizar la calidad de las titulaciones que se imparten en la universidad y sus centros y velar por la mejora continua de sus resultados. Se estructuran en dos niveles:<\/p><\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Institucional<\/strong><\/li>\n\n\n\n<li>\n<ul class=\"wp-block-list\">\n<li>Vicerrectorado con competencias en calidad<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<p>Dirigir e impulsar la implantaci\u00f3n y desarrollo de los SAIC, en tanto que suponen un refuerzo a la garant\u00eda de la calidad y mejora continua de los centros y titulaciones, facilitando los procesos de seguimiento, acreditaci\u00f3n y certificaci\u00f3n. Asimismo, es responsable de proporcionar el soporte institucional adecuado para el desarrollo de los programas de evaluaci\u00f3n y calidad, garantizando su sostenibilidad en el tiempo.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\n<ul class=\"wp-block-list\">\n<li>Unidad de Evaluaci\u00f3n y Mejora de la Calidad-Unidad T\u00e9cnica de Calidad<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<p>La Unidad&nbsp;de Evaluaci\u00f3n y Mejora de&nbsp;la Calidad (UEMC), y su Unidad T\u00e9cnica de Calidad (UTC), se encargan de la gesti\u00f3n y planificaci\u00f3n de los procesos de dise\u00f1o, implantaci\u00f3n y evaluaci\u00f3n del SAIC, necesarios para garantizar la mejora continua en el centro y sus titulaciones, as\u00ed como la consecuci\u00f3n de los objetivos establecidos, dando respuesta a las necesidades y expectativas de los grupos de inter\u00e9s.<\/p>\n\n\n\n<p>Asimismo, la UTC se encarga de elaborar y aportar la documentaci\u00f3n marco relacionada con los programas de evaluaci\u00f3n y calidad, y de proporcionar el asesoramiento t\u00e9cnico y la formaci\u00f3n a los agentes implicados. Impulsa el desarrollo de los procesos mediante una adecuada coordinaci\u00f3n con los responsables acad\u00e9micos y de calidad, comisiones, grupos de trabajo de autoevaluaci\u00f3n, agencias de calidad y otros \u00f3rganos\/entidades implicadas.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Centro\/Titulaci\u00f3n<\/strong><\/li>\n\n\n\n<li>\n<ul class=\"wp-block-list\">\n<li>Equipo Directivo del Centro<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<p>Este \u00f3rgano y, en particular, su Decano\/a o Director\/a, asume la responsabilidad de dirigir e impulsar los programas de evaluaci\u00f3n y calidad en el centro. Forma parte de su equipo un responsable de calidad de Centro, que ser\u00e1 el encargado de coordinar y desarrollar la gesti\u00f3n de los procesos relativos a la implantaci\u00f3n y evaluaci\u00f3n del SAIC y la evaluaci\u00f3n de titulaciones.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\n<ul class=\"wp-block-list\">\n<li>Responsable\/s de Calidad del Centro\/T\u00edtulo<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<p>Los responsables de calidad de centro\/t\u00edtulo, que se integrar\u00e1n como miembros en la Comisi\u00f3n de Calidad, ejercer\u00e1n funciones generales de coordinaci\u00f3n, entre las que destacan:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Apoyar al equipo decanal en el desarrollo de los programas de evaluaci\u00f3n y calidad en el centro<\/li>\n\n\n\n<li>Impulsar y liderar la implantaci\u00f3n del SAIC<\/li>\n\n\n\n<li>Participar en el dise\u00f1o, implantaci\u00f3n y evaluaci\u00f3n de los t\u00edtulos<\/li>\n<\/ul>\n\n\n\n<p><strong>En relaci\u00f3n al Sistema de Aseguramiento de Calidad de T\u00edtulo (SAIC)<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Gestionar, revisar y actualizar la documentaci\u00f3n del SAIC.<\/li>\n\n\n\n<li>Realizar los an\u00e1lisis de informaci\u00f3n derivados de los procedimientos del SAIC e informar a la Comisi\u00f3n de Calidad de su desarrollo (desajustes, acciones de mejora\u2026).<\/li>\n\n\n\n<li>Gestionar la comunicaci\u00f3n interna con los agentes implicados en el SAIC.<\/li>\n\n\n\n<li>Canalizar las reclamaciones, quejas y sugerencias hacia la Comisi\u00f3n de Calidad y articular las acciones de respuesta.<\/li>\n\n\n\n<li>Promover la cultura de evaluaci\u00f3n y calidad entre los diferentes grupos de inter\u00e9s.<\/li>\n\n\n\n<li>Garantizar la transparencia y rendici\u00f3n de cuentas a los grupos de inter\u00e9s, supervisando la actualizaci\u00f3n del contenido de la Web (publicaci\u00f3n de la informaci\u00f3n, resultados relevantes del t\u00edtulo, etc.)..<\/li>\n\n\n\n<li>Servir de interlocutor con el Vicerrectorado con competencias en calidad y la UTC en todas aquellas acciones relacionadas con el \u00e1mbito de la evaluaci\u00f3n y calidad institucional<\/li>\n<\/ul>\n\n\n\n<p><strong>En relaci\u00f3n a las titulaciones<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Impulsar y participar en los procesos de dise\u00f1o, modificaci\u00f3n, seguimiento y renovaci\u00f3n de la acreditaci\u00f3n de las titulaciones oficiales.<\/li>\n\n\n\n<li>Supervisar la implantaci\u00f3n de las titulaciones, conforme a lo establecido en la Memoria de Verificaci\u00f3n del T\u00edtulo y\/o sus posteriores modificaciones, y realizar, junto a la Comisi\u00f3n de Calidad, su seguimiento.<\/li>\n\n\n\n<li>Participar en el an\u00e1lisis, evoluci\u00f3n, reflexi\u00f3n y propuesta de acciones de mejora a partir de los resultados de rendimiento acad\u00e9mico y de satisfacci\u00f3n de las titulaciones.<\/li>\n\n\n\n<li>Apoyar a la Comisi\u00f3n de Calidad en la gesti\u00f3n de las Gu\u00edas Docentes de las titulaciones oficiales.<\/li>\n\n\n\n<li>\n<ul class=\"wp-block-list\">\n<li>Comisi\u00f3n de Calidad de Centro\/Secci\u00f3n\/T\u00edtulo<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<p>Es un \u00f3rgano que interviene en las tareas de planificaci\u00f3n y seguimiento del SAIC, y act\u00faa como uno de los mecanismos de participaci\u00f3n efectiva de los grupos de inter\u00e9s a trav\u00e9s del que se garantiza la calidad y mejora continua del centro y sus titulaciones. Est\u00e1 compuesta por el equipo directivo, responsable de calidad y representantes de los distintos grupos de inter\u00e9s del centro (PDI, estudiantes-egresados, PAS, empleadores, etc.). Entre las funciones que realiza destacan, entre otras:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Participar en el dise\u00f1o, revisi\u00f3n y actualizaci\u00f3n de la documentaci\u00f3n del SAIC.<\/li>\n\n\n\n<li>Verificar el seguimiento e implantaci\u00f3n del SAIC.<\/li>\n\n\n\n<li>Analizar y resolver, junto al responsable de calidad, las reclamaciones, quejas y sugerencias.<\/li>\n\n\n\n<li>Estudiar y en su caso aprobar la implantaci\u00f3n de las propuestas de mejora del SAIC y de sus titulaciones.<\/li>\n\n\n\n<li>Garantizar los procesos de revisi\u00f3n, evaluaci\u00f3n y mejora de los programas formativos.<\/li>\n\n\n\n<li>Supervisar el seguimiento y la implantaci\u00f3n de las titulaciones, conforme a lo establecido en la Memoria de Verificaci\u00f3n del T\u00edtulo y\/o sus posteriores modificaciones.<\/li>\n\n\n\n<li>Realizar el an\u00e1lisis, evoluci\u00f3n y reflexi\u00f3n a partir de los indicadores y resultados asociados (satisfacci\u00f3n, tasas de rendimiento acad\u00e9mico\u2026).<\/li>\n\n\n\n<li>Aprobar las Gu\u00edas Docentes de las titulaciones oficiales.<\/li>\n<\/ul>\n<\/div><\/div><\/div>\n<\/details>\n\n\n\n<details class=\"wp-block-stackable-accordion stk-block-accordion stk-inner-blocks stk-block-content stk-block stk-88a7c9c is-style-default\" id=\"procedimientos\" data-block-id=\"88a7c9c\"><style>.stk-88a7c9c {border-style:solid !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;margin-bottom:10px !important;}<\/style>\n<summary class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-27019df stk--container-small stk-block-accordion__heading\" data-v=\"4\" data-block-id=\"27019df\"><style>.stk-27019df {padding-top:2px !important;padding-right:2px !important;padding-bottom:2px !important;padding-left:2px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-27019df-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-27019df-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-9c9ce7e\" data-block-id=\"9c9ce7e\"><style>.stk-9c9ce7e .stk-inner-blocks{gap:39px !important;}@media screen and (max-width: 1023px){.stk-9c9ce7e .stk-inner-blocks{gap:39px !important;}}@media screen and (max-width: 767px){.stk-9c9ce7e .stk-inner-blocks{gap:39px !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-icon stk-block-icon stk-block stk-61c8ad3\" data-block-id=\"61c8ad3\"><style>.stk-61c8ad3 .stk--svg-wrapper .stk--inner-svg svg:last-child{height:25px !important;width:25px !important;}.stk-61c8ad3 .stk--svg-wrapper .stk--inner-svg svg:last-child, .stk-61c8ad3 .stk--svg-wrapper .stk--inner-svg svg:last-child :is(g, path, rect, polygon, ellipse){fill:#fa6199 !important;}<\/style><span class=\"stk--svg-wrapper stk--has-icon2\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-61c8ad3\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-61-c-8-ad-3-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-61-c-8-ad-3-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 384 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M64 0C28.7 0 0 28.7 0 64V448c0 35.3 28.7 64 64 64H320c35.3 0 64-28.7 64-64V160H256c-17.7 0-32-14.3-32-32V0H64zM256 0V128H384L256 0zM112 256H272c8.8 0 16 7.2 16 16s-7.2 16-16 16H112c-8.8 0-16-7.2-16-16s7.2-16 16-16zm0 64H272c8.8 0 16 7.2 16 16s-7.2 16-16 16H112c-8.8 0-16-7.2-16-16s7.2-16 16-16zm0 64H272c8.8 0 16 7.2 16 16s-7.2 16-16 16H112c-8.8 0-16-7.2-16-16s7.2-16 16-16z\"><\/path><\/svg><\/div><div class=\"stk--inner-svg stk--icon-2\" style=\"display:none\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-61c8ad3\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-61-c-8-ad-3-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-61-c-8-ad-3-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 384 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M64 464c-8.8 0-16-7.2-16-16V64c0-8.8 7.2-16 16-16H224v80c0 17.7 14.3 32 32 32h80V448c0 8.8-7.2 16-16 16H64zM64 0C28.7 0 0 28.7 0 64V448c0 35.3 28.7 64 64 64H320c35.3 0 64-28.7 64-64V154.5c0-17-6.7-33.3-18.7-45.3L274.7 18.7C262.7 6.7 246.5 0 229.5 0H64zm56 256c-13.3 0-24 10.7-24 24s10.7 24 24 24H264c13.3 0 24-10.7 24-24s-10.7-24-24-24H120zm0 96c-13.3 0-24 10.7-24 24s10.7 24 24 24H264c13.3 0 24-10.7 24-24s-10.7-24-24-24H120z\"><\/path><\/svg><\/div><\/span><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-bcb6d4e\" id=\"procedimientos\" data-block-id=\"bcb6d4e\"><style>.stk-bcb6d4e .stk-block-heading__text{color:#000000 !important;font-weight:500 !important;font-family:\"ArgentumSans\", Sans-serif !important;}<\/style><h4 class=\"stk-block-heading__text has-text-color\">Procedimientos<\/h4><\/div>\n<\/div><\/div>\n<\/div><\/div><\/summary>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-76d605c stk-block-accordion__content\" data-v=\"4\" data-block-id=\"76d605c\"><style>.stk-76d605c {margin-top:-30px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-76d605c-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-76d605c-inner-blocks\">\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-0b5bcfd\" data-block-id=\"0b5bcfd\"><p class=\"stk-block-text__text\">A continuaci\u00f3n, se detallan los procedimientos establecidos en el SAIC del t\u00edtulo, vinculados a diferentes aspectos de la gesti\u00f3n, evaluaci\u00f3n y mejora de los programas formativos:<\/p><\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Evaluaci\u00f3n y calidad de titulaciones oficiales\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/drive.google.com\/open?id=1sZ1utYOJXwgkCueD1K9poBqHqma0kGXN\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">SUB PR-1 Dise\u00f1o y Verificaci\u00f3n de t\u00edtulos oficiales<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/drive.google.com\/file\/d\/1F-mjrPCalHsGdJ_lJElJGpuwl2AEOfCJ\/view?usp=sharing\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">SUB_PR-2 Seguimiento, Modificaci\u00f3n y Acreditaci\u00f3n de T\u00edtulos Oficiales<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/drive.google.com\/open?id=16DSY-uc-67wiqcUhzHe2QqLq4tQ-9pe9\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">SUB_PR-3 Extinci\u00f3n de T\u00edtulos Oficiales<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Desarrollo y evaluaci\u00f3n de la ense\u00f1anza\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/drive.google.com\/open?id=1kGLevFOa4Gr6N1rwIyPmyWFlYwXsbGIA\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">SUB_PR-1 Evaluaci\u00f3n del aprendizaje<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/drive.google.com\/open?id=1f8v3sURKkgXXw_0iBMU5hlZ5XR36gf5E\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">SUB_PR-2 Gesti\u00f3n de pr\u00e1cticas externas<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Personal docente:\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/drive.google.com\/open?id=1opsc5ObUwRHU-qDhCwy0Rs36bRrUCdK8\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">PR-Evaluaci\u00f3n y Reconocimiento del PDI<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Gesti\u00f3n de la informaci\u00f3n y resultados:\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/drive.google.com\/open?id=1oQbRezmP-ot3mvBxYHVQqT9jGC0eWQW0\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">PR-Gesti\u00f3n de la movilidad de estudiantes<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/drive.google.com\/open?id=13I4-PipNqtW1mSf8v1-CBq7jTrSPo2tm\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">PR-Inserci\u00f3n laboral de los egresados<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/drive.google.com\/open?id=1DZ0nJL-r5MjtrGVgoE_6gtST09H_cmiv\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">PR-Satisfacci\u00f3n de los grupos de inter\u00e9s<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/drive.google.com\/open?id=13MC8qimAidBdspJW9KSQtMr7JHQn07gd\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">PR-Gesti\u00f3n Reclamaciones, Quejas y Sugerencias<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/drive.google.com\/file\/d\/1S3ZoGTFXzlvvMcVeOCfELXN7hnK0G5bw\/view?usp=sharing\" target=\"_blank\" rel=\"noreferrer noopener\" target=\"_blank\" rel=\"noopener\">PR-Informaci\u00f3n p\u00fablica<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/div><\/div><\/div>\n<\/details>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-53ec762\" data-v=\"4\" data-block-id=\"53ec762\"><style>.stk-53ec762-inner-blocks{row-gap:0px !important;}.stk-53ec762 {padding-top:0px !important;padding-right:0px !important;padding-bottom:0px !important;padding-left:0px !important;}@media screen and (min-width: 768px){.stk-53ec762 {flex:var(--stk-flex-grow, 1) 1 33.3% !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-53ec762-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-53ec762-inner-blocks\">\n\n<ul class=\"widget-box\">\n<li class='contacto-header'>Informaci\u00f3n de contacto<\/li><li><i class=\"fa fa-map-marker\"><\/i> Avda. Astrof\u00edsico Francisco S\u00e1nchez, SN. Edificio Calabaza \u2013 AN.2D Apdo. 456 38200 San Crist\u00f3bal de La Laguna.<\/li><li><i class=\"fa fa-envelope\"><\/i>  <a href=mailto:master.dregional@ull.es>master.dregional@ull.es<\/a><\/li><li><i class=\"fa fa-archive\"><\/i><a href=\"https:\/\/sede.ull.es\/ecivilis-site\/catalog\/showProcedure\/484\"> Procedimiento para quejas, sugerencias y felicitaciones<\/a><\/li>\n<\/ul>\n\n\n<\/div><\/div><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Sistema de Garant\u00eda Interna de Calidad El Sistema de Aseguramiento Interno de Calidad del T\u00edtulo (SAIC) (anteriormente Sistema de Garant\u00eda Interna de Calidad -SGIC-) constituye el compromiso de la universidad con el establecimiento y despliegue de la cultura de calidad en los programas formativos, la mejora continua y la rendici\u00f3n de cuentas. Contempla procedimientos dise\u00f1ados&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":261,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/template-frontpage.php","meta":{"footnotes":""},"class_list":["post-16","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sistema de Garant\u00eda Interna de Calidad - M\u00e1ster Universitario en Desarrollo Regional<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ull.es\/masteres\/desarrollo-regional\/calidad-y-resultados\/sistema-de-garantia-interna-de-calidad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sistema de Garant\u00eda Interna de Calidad - M\u00e1ster Universitario en Desarrollo Regional\" \/>\n<meta property=\"og:description\" content=\"Sistema de Garant\u00eda Interna de Calidad El Sistema de Aseguramiento Interno de Calidad del T\u00edtulo (SAIC) (anteriormente Sistema de Garant\u00eda Interna de Calidad -SGIC-) constituye el compromiso de la universidad con el establecimiento y despliegue de la cultura de calidad en los programas formativos, la mejora continua y la rendici\u00f3n de cuentas. Contempla procedimientos dise\u00f1ados...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ull.es\/masteres\/desarrollo-regional\/calidad-y-resultados\/sistema-de-garantia-interna-de-calidad\/\" \/>\n<meta property=\"og:site_name\" content=\"M\u00e1ster Universitario en Desarrollo Regional\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-21T09:01:13+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ull.es\\\/masteres\\\/desarrollo-regional\\\/fr\\\/calidad-y-resultados\\\/sistema-de-garantia-interna-de-calidad\\\/\",\"url\":\"https:\\\/\\\/www.ull.es\\\/masteres\\\/desarrollo-regional\\\/fr\\\/calidad-y-resultados\\\/sistema-de-garantia-interna-de-calidad\\\/\",\"name\":\"Sistema de Garant\u00eda Interna de Calidad - M\u00e1ster Universitario en Desarrollo Regional\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ull.es\\\/masteres\\\/desarrollo-regional\\\/fr\\\/#website\"},\"datePublished\":\"2017-06-28T12:47:07+00:00\",\"dateModified\":\"2025-08-21T09:01:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ull.es\\\/masteres\\\/desarrollo-regional\\\/fr\\\/calidad-y-resultados\\\/sistema-de-garantia-interna-de-calidad\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ull.es\\\/masteres\\\/desarrollo-regional\\\/fr\\\/calidad-y-resultados\\\/sistema-de-garantia-interna-de-calidad\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ull.es\\\/masteres\\\/desarrollo-regional\\\/fr\\\/calidad-y-resultados\\\/sistema-de-garantia-interna-de-calidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ull.es\\\/masteres\\\/desarrollo-regional\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Calidad y resultados\",\"item\":\"https:\\\/\\\/www.ull.es\\\/masteres\\\/desarrollo-regional\\\/calidad-y-resultados\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sistema de Garant\u00eda Interna de Calidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ull.es\\\/masteres\\\/desarrollo-regional\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.ull.es\\\/masteres\\\/desarrollo-regional\\\/fr\\\/\",\"name\":\"M\u00e1ster Universitario en Desarrollo Regional\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ull.es\\\/masteres\\\/desarrollo-regional\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sistema de Garant\u00eda Interna de Calidad - M\u00e1ster Universitario en Desarrollo Regional","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ull.es\/masteres\/desarrollo-regional\/calidad-y-resultados\/sistema-de-garantia-interna-de-calidad\/","og_locale":"es_ES","og_type":"article","og_title":"Sistema de Garant\u00eda Interna de Calidad - M\u00e1ster Universitario en Desarrollo Regional","og_description":"Sistema de Garant\u00eda Interna de Calidad El Sistema de Aseguramiento Interno de Calidad del T\u00edtulo (SAIC) (anteriormente Sistema de Garant\u00eda Interna de Calidad -SGIC-) constituye el compromiso de la universidad con el establecimiento y despliegue de la cultura de calidad en los programas formativos, la mejora continua y la rendici\u00f3n de cuentas. Contempla procedimientos dise\u00f1ados...","og_url":"https:\/\/www.ull.es\/masteres\/desarrollo-regional\/calidad-y-resultados\/sistema-de-garantia-interna-de-calidad\/","og_site_name":"M\u00e1ster Universitario en Desarrollo Regional","article_modified_time":"2025-08-21T09:01:13+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ull.es\/masteres\/desarrollo-regional\/fr\/calidad-y-resultados\/sistema-de-garantia-interna-de-calidad\/","url":"https:\/\/www.ull.es\/masteres\/desarrollo-regional\/fr\/calidad-y-resultados\/sistema-de-garantia-interna-de-calidad\/","name":"Sistema de Garant\u00eda Interna de Calidad - M\u00e1ster Universitario en Desarrollo Regional","isPartOf":{"@id":"https:\/\/www.ull.es\/masteres\/desarrollo-regional\/fr\/#website"},"datePublished":"2017-06-28T12:47:07+00:00","dateModified":"2025-08-21T09:01:13+00:00","breadcrumb":{"@id":"https:\/\/www.ull.es\/masteres\/desarrollo-regional\/fr\/calidad-y-resultados\/sistema-de-garantia-interna-de-calidad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ull.es\/masteres\/desarrollo-regional\/fr\/calidad-y-resultados\/sistema-de-garantia-interna-de-calidad\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ull.es\/masteres\/desarrollo-regional\/fr\/calidad-y-resultados\/sistema-de-garantia-interna-de-calidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ull.es\/masteres\/desarrollo-regional\/"},{"@type":"ListItem","position":2,"name":"Calidad y resultados","item":"https:\/\/www.ull.es\/masteres\/desarrollo-regional\/calidad-y-resultados\/"},{"@type":"ListItem","position":3,"name":"Sistema de Garant\u00eda Interna de Calidad"}]},{"@type":"WebSite","@id":"https:\/\/www.ull.es\/masteres\/desarrollo-regional\/fr\/#website","url":"https:\/\/www.ull.es\/masteres\/desarrollo-regional\/fr\/","name":"M\u00e1ster Universitario en Desarrollo Regional","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ull.es\/masteres\/desarrollo-regional\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.ull.es\/masteres\/desarrollo-regional\/wp-json\/wp\/v2\/pages\/16","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ull.es\/masteres\/desarrollo-regional\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ull.es\/masteres\/desarrollo-regional\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ull.es\/masteres\/desarrollo-regional\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ull.es\/masteres\/desarrollo-regional\/wp-json\/wp\/v2\/comments?post=16"}],"version-history":[{"count":14,"href":"https:\/\/www.ull.es\/masteres\/desarrollo-regional\/wp-json\/wp\/v2\/pages\/16\/revisions"}],"predecessor-version":[{"id":1101,"href":"https:\/\/www.ull.es\/masteres\/desarrollo-regional\/wp-json\/wp\/v2\/pages\/16\/revisions\/1101"}],"up":[{"embeddable":true,"href":"https:\/\/www.ull.es\/masteres\/desarrollo-regional\/wp-json\/wp\/v2\/pages\/261"}],"wp:attachment":[{"href":"https:\/\/www.ull.es\/masteres\/desarrollo-regional\/wp-json\/wp\/v2\/media?parent=16"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}