{"id":38,"date":"2017-06-28T13:01:07","date_gmt":"2017-06-28T13:01:07","guid":{"rendered":"http:\/\/www.ull.es\/masteres\/desarrollo-y-gestion-de-recursos-humanos\/?page_id=38"},"modified":"2025-08-21T09:57:22","modified_gmt":"2025-08-21T09:57:22","slug":"competencias","status":"publish","type":"page","link":"https:\/\/www.ull.es\/masteres\/formacion-profesorado\/plan-de-estudios\/competencias\/","title":{"rendered":"Competencias"},"content":{"rendered":"\n<div class=\"wp-block-stackable-columns alignfull stk-block-columns stk-block stk-2314a6b\" data-block-id=\"2314a6b\"><style>.stk-2314a6b {padding-bottom:0px !important;margin-top:-100px !important;margin-bottom:0px !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-2314a6b-column alignfull\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-1d1764d\" data-v=\"4\" data-block-id=\"1d1764d\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-1d1764d-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-1d1764d-inner-blocks\"><style id=\"depicter-1-inline-pre-css\">\n\n.depicter-1:not(.depicter-ready){\n\theight:450px;\n}\n\n\/***** Tablet *****\/\n@media screen and (max-width: 1024px){\n\n.depicter-1:not(.depicter-ready){\n\theight:700px;\n}\n\n}\n\/***** Mobile *****\/\n@media screen and (max-width: 767px){\n\n.depicter-1:not(.depicter-ready){\n\theight:450px;\n}\n\n}\n<\/style>\n<div id=\"depicter-1\" class=\"depicter depicter-document depicter-revert depicter-1 depicter-layout-fullwidth\">\n\n<div class=\"depicter-loading-container depicter-loading dotFlashing-dark\"><div class=\"depicter-loading-dark depicter-dot-flashing\">\n   <span><\/span>\n   <span><\/span>\n   <span><\/span>\n<\/div>\n<\/div>\n<div id=\"depicter-1-section-1\" class=\"depicter-section depicter-1-section-1\" data-name=\"Section 1\" data-type=\"section\" data-local-id=\"section-1\">\n<picture class=\"depicter-bg\">\n<source data-depicter-srcset=\"https:\/\/www.ull.es\/masteres\/formacion-profesorado\/wp-content\/uploads\/sites\/23\/2025\/07\/Headers-Masteres_Formacion-del-Profesorado-768x248.jpg, https:\/\/www.ull.es\/masteres\/formacion-profesorado\/wp-content\/uploads\/sites\/23\/2025\/07\/Headers-Masteres_Formacion-del-Profesorado.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(max-width: 1024px)\" \/>\n\n<source data-depicter-srcset=\"https:\/\/www.ull.es\/masteres\/formacion-profesorado\/wp-content\/uploads\/sites\/23\/2025\/07\/Headers-Masteres_Formacion-del-Profesorado.jpg, https:\/\/www.ull.es\/masteres\/formacion-profesorado\/wp-content\/uploads\/sites\/23\/2025\/07\/Headers-Masteres_Formacion-del-Profesorado-1280x413.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" media=\"(min-width: 1025px)\" \/>\n<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-ken-burns=\"false\" data-tablet-ken-burns=\"false\" data-mobile-ken-burns=\"false\" alt=\"\" data-depicter-src=\"https:\/\/www.ull.es\/masteres\/formacion-profesorado\/wp-content\/uploads\/sites\/23\/2025\/07\/Headers-Masteres_Formacion-del-Profesorado.jpg\" data-object-fit=\"custom,custom,\" data-object-position=\"center top,,\" data-crop=\"{'focalPoint':{'x':0.5,'y':0.5},'mediaSize':{'width':1394.6731234866829254315234720706939697265625,'height':450}}\" data-tablet-crop=\"{'focalPoint':{'x':0.5,'y':0.5},'mediaSize':{'width':2169.4915254237284898408688604831695556640625,'height':700}}\" data-mobile-crop=\"{'focalPoint':{'x':0.5,'y':0.5},'mediaSize':{'width':1394.6731234866829254315234720706939697265625,'height':450}}\" \/>\n<\/picture>\n\n\n<h1 id=\"depicter-1-element-5\" class=\"depicter-element depicter-layer depicter-1-element-5\" data-type=\"text\" data-wrap=\"true\" data-name=\"Text 2\" data-local-id=\"element-5\" data-offset=\"x:0px;y:57px;origin:tl\" data-tablet-offset=\"x:196px;y:134px;origin:tl\" data-mobile-offset=\"x:-16px;y:81px;origin:tl\" data-width=\"1200px,633px,408px\" data-height=\"auto,auto,auto\" data-responsive-scale=\"true,,\">M\u00e1ster Universitario del Prof. de ESO y Bachillerato, FP y Ense\u00f1anza de Idiomas (Interuniversitario)<br><\/h1>\n\n<div id=\"depicter-1-element-10\" class=\"depicter-element depicter-layer depicter-1-element-10\" data-type=\"shape\" data-wrap=\"true\" data-name=\"Shape 1\" data-local-id=\"element-10\" data-offset=\"x:0px;y:401px;origin:tl\" data-tablet-offset=\"x:189px;y:575px;origin:tl\" data-mobile-offset=\"x:-16px;y:384px;origin:tl\" data-width=\"1135px,647px,408px\" data-height=\"8px,8px,8px\" data-responsive-scale=\"true,,\"><\/div>\n<\/div>\n<\/div>\n<script>\n(window.depicterSetups = window.depicterSetups || []).push(function(){\n\tDepicter.basePath = 'https:\/\/www.ull.es\/masteres\/formacion-profesorado\/wp-content\/plugins\/depicter\/resources\/scripts\/player\/';\n\tconst dpPlayer = Depicter.setup('.depicter-1',\n\t\t{\"width\":[\"1200\",\"1024\",\"360\"],\"height\":[\"450\",\"700\",\"450\"],\"view\":\"basic\",\"keepAspectRatio\":true,\"preload\":0,\"layout\":\"fullwidth\",\"rtl\":false,\"initAfterAppear\":false,\"ajaxApiUrl\":\"https:\\\/\\\/www.ull.es\\\/masteres\\\/formacion-profesorado\\\/wp-admin\\\/admin-ajax.php\",\"mouseSwipe\":true,\"touchSwipe\":true,\"useWatermark\":false}\n\t);\n});\n<\/script><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns alignfull stk-block-columns stk--hide-mobile stk-block stk-6394276 stk-block-background\" data-block-id=\"6394276\"><style>.stk-6394276 {background-color:#fa6199 !important;padding-top:50px !important;padding-right:0px !important;padding-bottom:1px !important;padding-left:0px !important;margin-top:-40px !important;margin-bottom:0px !important;}.stk-6394276:before{background-color:#fa6199 !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-6394276-column alignfull\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-8a66885\" data-v=\"4\" data-block-id=\"8a66885\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-8a66885-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-8a66885-inner-blocks\">\n<div class=\"wp-block-stackable-spacer stk-block-spacer stk--no-padding stk-block stk-bc89b3e\" data-block-id=\"bc89b3e\"><style>.stk-bc89b3e {height:0px !important;}<\/style><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns stk-block-columns stk-block stk-8b59b96\" data-block-id=\"8b59b96\"><style>.stk-8b59b96 .stk--block-align-8b59b96{align-items:flex-start !important;}.stk-8b59b96 {margin-top:50px !important;}.stk-8b59b96-column{--stk-columns-spacing:0px !important;--stk-column-gap:50px !important;}@media screen and (max-width: 767px){.stk-8b59b96-column{row-gap:var(--stk--preset--spacing--60, 2.25rem) !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk--block-align-8b59b96 stk-block-content stk-content-align stk-8b59b96-column\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-dbb7e15\" data-v=\"4\" data-block-id=\"dbb7e15\"><style>@media screen and (min-width: 768px){.stk-dbb7e15 {flex:var(--stk-flex-grow, 1) 1 66.7% !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-dbb7e15-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-dbb7e15-inner-blocks\">\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-cc0239e\" id=\"complementos-de-formacion\" data-block-id=\"cc0239e\"><style>.stk-cc0239e .stk-block-heading__text{color:#fa6199 !important;font-weight:500 !important;}<\/style><h1 class=\"stk-block-heading__text has-text-color\">Competencias<\/h1><\/div>\n\n\n\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-44a67f6\" data-block-id=\"44a67f6\"><p class=\"stk-block-text__text\">Las competencias son el conjunto de conocimientos, habilidades y actitudes a adquirir por el alumnado, a lo largo de la titulaci\u00f3n, orientadas a la preparaci\u00f3n del ejercicio de actividades de car\u00e1cter profesional.<\/p><\/div>\n\n\n\n<details class=\"wp-block-stackable-accordion stk-block-accordion stk-inner-blocks stk-block-content stk-block stk-7c390cd is-style-default\" id=\"basicas\" data-block-id=\"7c390cd\"><style>.stk-7c390cd {border-style:solid !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;margin-bottom:11px !important;}<\/style>\n<summary class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-c927805 stk--container-small stk-block-accordion__heading\" data-v=\"4\" data-block-id=\"c927805\"><style>.stk-c927805 {padding-top:2px !important;padding-right:2px !important;padding-bottom:2px !important;padding-left:2px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-c927805-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-c927805-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-7935446\" data-block-id=\"7935446\"><style>.stk-7935446 .stk-inner-blocks{gap:39px !important;}@media screen and (max-width: 1023px){.stk-7935446 .stk-inner-blocks{gap:39px !important;}}@media screen and (max-width: 767px){.stk-7935446 .stk-inner-blocks{gap:39px !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-icon stk-block-icon stk-block stk-9a468d5\" data-block-id=\"9a468d5\"><style>.stk-9a468d5 .stk--svg-wrapper .stk--inner-svg svg:last-child{height:25px !important;width:25px !important;}.stk-9a468d5 .stk--svg-wrapper .stk--inner-svg svg:last-child, .stk-9a468d5 .stk--svg-wrapper .stk--inner-svg svg:last-child :is(g, path, rect, polygon, ellipse){fill:#fa6199 !important;}<\/style><span class=\"stk--svg-wrapper stk--has-icon2\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-9a468d5\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-9-a-468-d-5-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-9-a-468-d-5-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M256 512A256 256 0 1 0 256 0a256 256 0 1 0 0 512zM216 336h24V272H216c-13.3 0-24-10.7-24-24s10.7-24 24-24h48c13.3 0 24 10.7 24 24v88h8c13.3 0 24 10.7 24 24s-10.7 24-24 24H216c-13.3 0-24-10.7-24-24s10.7-24 24-24zm40-208a32 32 0 1 1 0 64 32 32 0 1 1 0-64z\"><\/path><\/svg><\/div><div class=\"stk--inner-svg stk--icon-2\" style=\"display:none\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-9a468d5\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-9-a-468-d-5-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-9-a-468-d-5-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 192 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M48 80a48 48 0 1 1 96 0A48 48 0 1 1 48 80zM0 224c0-17.7 14.3-32 32-32H96c17.7 0 32 14.3 32 32V448h32c17.7 0 32 14.3 32 32s-14.3 32-32 32H32c-17.7 0-32-14.3-32-32s14.3-32 32-32H64V256H32c-17.7 0-32-14.3-32-32z\"><\/path><\/svg><\/div><\/span><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-31863c1\" id=\"competencias-basicas\" data-block-id=\"31863c1\"><style>.stk-31863c1 .stk-block-heading__text{color:#000000 !important;font-weight:500 !important;font-family:\"ArgentumSans\", Sans-serif !important;}<\/style><h4 class=\"stk-block-heading__text has-text-color\">Competencias B\u00e1sicas<\/h4><\/div>\n<\/div><\/div>\n<\/div><\/div><\/summary>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-5222666 stk-block-accordion__content\" data-v=\"4\" data-block-id=\"5222666\"><style>.stk-5222666 {margin-top:-30px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-5222666-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-5222666-inner-blocks\">\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-3abb527\" data-block-id=\"3abb527\"><p class=\"stk-block-text__text\">CB6 \u2013 Poseer y comprender conocimientos que aporten una base u oportunidad de ser originales en el desarrollo y\/o aplicaci\u00f3n de&nbsp;ideas, a menudo en un contexto de investigaci\u00f3n.<\/p><\/div>\n\n\n\n<p>CB7 \u2013 Que los estudiantes sepan aplicar los conocimientos adquiridos y su capacidad de resoluci\u00f3n de problemas en entornos&nbsp;nuevos o poco conocidos dentro de contextos m\u00e1s amplios (o multidisciplinares) relacionados con su \u00e1rea de estudio.<\/p>\n\n\n\n<p>CB8 \u2013 Que los estudiantes sean capaces de integrar conocimientos y enfrentarse a la complejidad de formular juicios a partir de una informaci\u00f3n que, siendo incompleta o limitada, incluya reflexiones sobre las responsabilidades sociales y \u00e9ticas vinculadas a la aplicaci\u00f3n de sus conocimientos y juicios.<\/p>\n\n\n\n<p>CB9 \u2013 Que los estudiantes sepan comunicar sus conclusiones y los conocimientos y razones \u00faltimas que las sustentan a p\u00fablicos especializados y no especializados de un modo claro y sin ambig\u00fcedades.<\/p>\n\n\n\n<p>CB10 \u2013 Que los estudiantes posean las habilidades de aprendizaje que les permitan continuar estudiando de un modo que habr\u00e1 de ser en gran medida autodirigido o aut\u00f3nomo.<\/p>\n<\/div><\/div><\/div>\n<\/details>\n\n\n\n<details class=\"wp-block-stackable-accordion stk-block-accordion stk-inner-blocks stk-block-content stk-block stk-88a7c9c is-style-default\" id=\"generales\" data-block-id=\"88a7c9c\"><style>.stk-88a7c9c {border-style:solid !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;margin-bottom:10px !important;}<\/style>\n<summary class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-27019df stk--container-small stk-block-accordion__heading\" data-v=\"4\" data-block-id=\"27019df\"><style>.stk-27019df {padding-top:2px !important;padding-right:2px !important;padding-bottom:2px !important;padding-left:2px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-27019df-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-27019df-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-9c9ce7e\" data-block-id=\"9c9ce7e\"><style>.stk-9c9ce7e .stk-inner-blocks{gap:39px !important;}@media screen and (max-width: 1023px){.stk-9c9ce7e .stk-inner-blocks{gap:39px !important;}}@media screen and (max-width: 767px){.stk-9c9ce7e .stk-inner-blocks{gap:39px !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-icon stk-block-icon stk-block stk-61c8ad3\" data-block-id=\"61c8ad3\"><style>.stk-61c8ad3 .stk--svg-wrapper .stk--inner-svg svg:last-child{height:25px !important;width:25px !important;}.stk-61c8ad3 .stk--svg-wrapper .stk--inner-svg svg:last-child, .stk-61c8ad3 .stk--svg-wrapper .stk--inner-svg svg:last-child :is(g, path, rect, polygon, ellipse){fill:#fa6199 !important;}<\/style><span class=\"stk--svg-wrapper stk--has-icon2\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-61c8ad3\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-61-c-8-ad-3-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-61-c-8-ad-3-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 640 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M144 0a80 80 0 1 1 0 160A80 80 0 1 1 144 0zM512 0a80 80 0 1 1 0 160A80 80 0 1 1 512 0zM0 298.7C0 239.8 47.8 192 106.7 192h42.7c15.9 0 31 3.5 44.6 9.7c-1.3 7.2-1.9 14.7-1.9 22.3c0 38.2 16.8 72.5 43.3 96c-.2 0-.4 0-.7 0H21.3C9.6 320 0 310.4 0 298.7zM405.3 320c-.2 0-.4 0-.7 0c26.6-23.5 43.3-57.8 43.3-96c0-7.6-.7-15-1.9-22.3c13.6-6.3 28.7-9.7 44.6-9.7h42.7C592.2 192 640 239.8 640 298.7c0 11.8-9.6 21.3-21.3 21.3H405.3zM224 224a96 96 0 1 1 192 0 96 96 0 1 1 -192 0zM128 485.3C128 411.7 187.7 352 261.3 352H378.7C452.3 352 512 411.7 512 485.3c0 14.7-11.9 26.7-26.7 26.7H154.7c-14.7 0-26.7-11.9-26.7-26.7z\"><\/path><\/svg><\/div><div class=\"stk--inner-svg stk--icon-2\" style=\"display:none\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-61c8ad3\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-61-c-8-ad-3-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-61-c-8-ad-3-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 640 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M211.2 96a64 64 0 1 0 -128 0 64 64 0 1 0 128 0zM32 256c0 17.7 14.3 32 32 32h85.6c10.1-39.4 38.6-71.5 75.8-86.6c-9.7-6-21.2-9.4-33.4-9.4H96c-35.3 0-64 28.7-64 64zm461.6 32H576c17.7 0 32-14.3 32-32c0-35.3-28.7-64-64-64H448c-11.7 0-22.7 3.1-32.1 8.6c38.1 14.8 67.4 47.3 77.7 87.4zM391.2 226.4c-6.9-1.6-14.2-2.4-21.6-2.4h-96c-8.5 0-16.7 1.1-24.5 3.1c-30.8 8.1-55.6 31.1-66.1 60.9c-3.5 10-5.5 20.8-5.5 32c0 17.7 14.3 32 32 32h224c17.7 0 32-14.3 32-32c0-11.2-1.9-22-5.5-32c-10.8-30.7-36.8-54.2-68.9-61.6zM563.2 96a64 64 0 1 0 -128 0 64 64 0 1 0 128 0zM321.6 192a80 80 0 1 0 0-160 80 80 0 1 0 0 160zM32 416c-17.7 0-32 14.3-32 32s14.3 32 32 32H608c17.7 0 32-14.3 32-32s-14.3-32-32-32H32z\"><\/path><\/svg><\/div><\/span><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-bcb6d4e\" id=\"competencias-generales\" data-block-id=\"bcb6d4e\"><style>.stk-bcb6d4e .stk-block-heading__text{color:#000000 !important;font-weight:500 !important;font-family:\"ArgentumSans\", Sans-serif !important;}<\/style><h4 class=\"stk-block-heading__text has-text-color\">Competencias Generales<\/h4><\/div>\n<\/div><\/div>\n<\/div><\/div><\/summary>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-76d605c stk-block-accordion__content\" data-v=\"4\" data-block-id=\"76d605c\"><style>.stk-76d605c {margin-top:-30px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-76d605c-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-76d605c-inner-blocks\">\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-4bc3cf6\" data-block-id=\"4bc3cf6\"><p class=\"stk-block-text__text\">G1 \u2013 Adquirir el conocimiento de las funciones que caracterizan al profesor de Educaci\u00f3n Secundaria Obligatoria, Bachillerato,&nbsp;Formaci\u00f3n Profesional y Ense\u00f1anza de Idiomas.<\/p><\/div>\n\n\n\n<p>G2 \u2013 Ser capaz de programar, desarrollar y evaluar el proceso educativo de ense\u00f1anza-aprendizaje vinculado al nivel y el contexto&nbsp;donde se desarrolle.<\/p>\n\n\n\n<p>G3 \u2013 Trabajar en equipo de manera coordinada en la tarea docente, en la acci\u00f3n tutorial y en la participaci\u00f3n de proyectos y aprendizajes.<\/p>\n\n\n\n<p>G4 \u2013 Desarrollar actitudes de participaci\u00f3n activa en procesos de mejora e innovaci\u00f3n, as\u00ed como en la mejora respuesta educativa a&nbsp;la diversidad del alumnado.<\/p>\n\n\n\n<p>G5 \u2013 Adquirir actitudes de formaci\u00f3n personal y actualizaci\u00f3n continua y dominio de nuevas competencias.<\/p>\n\n\n\n<p>G6 \u2013 Adquirir estrategias b\u00e1sicas vinculadas a la iniciaci\u00f3n a la innovaci\u00f3n y a la investigaci\u00f3n educativa.<\/p>\n\n\n\n<p>G7 \u2013 Buscar, obtener, procesar y comunicar informaci\u00f3n (oral, impresa, audiovisual, digital o multimedia), transformarla en conocimiento y aplicarla en los procesos de ense\u00f1anza y aprendizaje en las materias propias de la&nbsp; especializaci\u00f3n cursada.<\/p>\n\n\n\n<p>G8 \u2013 Dise\u00f1ar y desarrollar espacios de aprendizaje con especial atenci\u00f3n a la equidad, la educaci\u00f3n emocional y en valores, la igualdad de derechos y oportunidades entre hombres y mujeres, la formaci\u00f3n ciudadana y el respeto de los derechos humanos que faciliten la vida en sociedad, la toma de decisiones y la construcci\u00f3n de un futuro sostenible.<\/p>\n\n\n\n<p>G9 \u2013 Adquirir estrategias para estimular el esfuerzo del estudiante y promover su capacidad para aprender por s\u00ed mismo y con otros, y desarrollar habilidades de pensamiento y de decisi\u00f3n que faciliten la autonom\u00eda, la confianza e iniciativa personales.<\/p>\n\n\n\n<p>G10 \u2013 Conocer la normativa y organizaci\u00f3n institucional del sistema educativo y modelos de mejora de la calidad con aplicaci\u00f3n a los centros de ense\u00f1anza.<\/p>\n\n\n\n<p>G11 \u2013 Informar y asesorar a las familias acerca del proceso de ense\u00f1anza y aprendizaje y sobre la orientaci\u00f3n personal, acad\u00e9mica y profesional de sus hijos.<\/p>\n<\/div><\/div><\/div>\n<\/details>\n\n\n\n<details class=\"wp-block-stackable-accordion stk-block-accordion stk-inner-blocks stk-block-content stk-block stk-6320006 is-style-default\" id=\"especificas\" data-block-id=\"6320006\"><style>.stk-6320006 {border-style:solid !important;border-top-width:0px !important;border-right-width:0px !important;border-bottom-width:1px !important;border-left-width:0px !important;margin-bottom:9px !important;}<\/style>\n<summary class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-ae2ad76 stk--container-small stk-block-accordion__heading\" data-v=\"4\" data-block-id=\"ae2ad76\"><style>.stk-ae2ad76 {padding-top:2px !important;padding-right:2px !important;padding-bottom:2px !important;padding-left:2px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-ae2ad76-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-ae2ad76-inner-blocks\">\n<div class=\"wp-block-stackable-icon-label stk-block-icon-label stk-block stk-16db2af\" data-block-id=\"16db2af\"><style>.stk-16db2af .stk-inner-blocks{gap:39px !important;}@media screen and (max-width: 1023px){.stk-16db2af .stk-inner-blocks{gap:39px !important;}}@media screen and (max-width: 767px){.stk-16db2af .stk-inner-blocks{gap:39px !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content\">\n<div class=\"wp-block-stackable-icon stk-block-icon stk-block stk-38bb3f8\" data-block-id=\"38bb3f8\"><style>.stk-38bb3f8 .stk--svg-wrapper .stk--inner-svg svg:last-child{height:25px !important;width:25px !important;}.stk-38bb3f8 .stk--svg-wrapper .stk--inner-svg svg:last-child, .stk-38bb3f8 .stk--svg-wrapper .stk--inner-svg svg:last-child :is(g, path, rect, polygon, ellipse){fill:#fa6199 !important;}<\/style><span class=\"stk--svg-wrapper stk--has-icon2\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-38bb3f8\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-38-bb-3-f-8-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-38-bb-3-f-8-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M256 512A256 256 0 1 0 256 0a256 256 0 1 0 0 512zM169.8 165.3c7.9-22.3 29.1-37.3 52.8-37.3h58.3c34.9 0 63.1 28.3 63.1 63.1c0 22.6-12.1 43.5-31.7 54.8L280 264.4c-.2 13-10.9 23.6-24 23.6c-13.3 0-24-10.7-24-24V250.5c0-8.6 4.6-16.5 12.1-20.8l44.3-25.4c4.7-2.7 7.6-7.7 7.6-13.1c0-8.4-6.8-15.1-15.1-15.1H222.6c-3.4 0-6.4 2.1-7.5 5.3l-.4 1.2c-4.4 12.5-18.2 19-30.6 14.6s-19-18.2-14.6-30.6l.4-1.2zM224 352a32 32 0 1 1 64 0 32 32 0 1 1 -64 0z\"><\/path><\/svg><\/div><div class=\"stk--inner-svg stk--icon-2\" style=\"display:none\"><svg style=\"height:0;width:0\"><defs><linearGradient id=\"linear-gradient-38bb3f8\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-38-bb-3-f-8-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-38-bb-3-f-8-color-2)\"><\/stop><\/linearGradient><\/defs><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M464 256A208 208 0 1 0 48 256a208 208 0 1 0 416 0zM0 256a256 256 0 1 1 512 0A256 256 0 1 1 0 256zm169.8-90.7c7.9-22.3 29.1-37.3 52.8-37.3h58.3c34.9 0 63.1 28.3 63.1 63.1c0 22.6-12.1 43.5-31.7 54.8L280 264.4c-.2 13-10.9 23.6-24 23.6c-13.3 0-24-10.7-24-24V250.5c0-8.6 4.6-16.5 12.1-20.8l44.3-25.4c4.7-2.7 7.6-7.7 7.6-13.1c0-8.4-6.8-15.1-15.1-15.1H222.6c-3.4 0-6.4 2.1-7.5 5.3l-.4 1.2c-4.4 12.5-18.2 19-30.6 14.6s-19-18.2-14.6-30.6l.4-1.2zM224 352a32 32 0 1 1 64 0 32 32 0 1 1 -64 0z\"><\/path><\/svg><\/div><\/span><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-a35761a\" id=\"competencias-especificas\" data-block-id=\"a35761a\"><style>.stk-a35761a .stk-block-heading__text{color:#000000 !important;font-weight:500 !important;font-family:\"ArgentumSans\", Sans-serif !important;}<\/style><h4 class=\"stk-block-heading__text has-text-color\">Competencias Espec\u00edficas<\/h4><\/div>\n<\/div><\/div>\n<\/div><\/div><\/summary>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-81ecc51 stk-block-accordion__content\" data-v=\"4\" data-block-id=\"81ecc51\"><style>.stk-81ecc51 {margin-top:-30px !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-81ecc51-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-81ecc51-inner-blocks\">\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-63a170b\" data-block-id=\"63a170b\"><p class=\"stk-block-text__text\">CE1 \u2013 Conocer las caracter\u00edsticas de los estudiantes, sus contextos sociales y motivaciones.<\/p><\/div>\n\n\n\n<p>CE2 \u2013 Comprender el desarrollo de la personalidad de estos estudiantes y las posibles disfunciones que afectan al aprendizaje.<\/p>\n\n\n\n<p>CE3 \u2013 Elaborar propuestas basadas en la adquisici\u00f3n de conocimientos, destrezas y aptitudes intelectuales y emocionales.<\/p>\n\n\n\n<p>CE4 \u2013 Identificar y planificar la resoluci\u00f3n de situaciones educativas que afectan a estudiantes con diferentes capacidades y diferentes ritmos de aprendizaje.<\/p>\n\n\n\n<p>CE5 \u2013 Conocer los procesos de interacci\u00f3n y comunicaci\u00f3n en el aula y en el centro, abordar y resolver posibles problemas.<\/p>\n\n\n\n<p>CE6 \u2013 Conocer la evoluci\u00f3n hist\u00f3rica del sistema educativo en nuestro pa\u00eds.<\/p>\n\n\n\n<p>CE7 \u2013 Conocer y aplicar recursos y estrategias de informaci\u00f3n, tutor\u00eda y orientaci\u00f3n acad\u00e9mica y profesional.<\/p>\n\n\n\n<p>CE8 \u2013 Promover acciones de educaci\u00f3n emocional, en valores y formaci\u00f3n ciudadana.<\/p>\n\n\n\n<p>CE9 \u2013 Participar en la definici\u00f3n del proyecto educativo y en las actividades generales del centro atendiendo a criterios de mejora de la calidad, atenci\u00f3n a la diversidad, prevenci\u00f3n de problemas de aprendizaje y convivencia.<\/p>\n\n\n\n<p>C910 \u2013 Analizar las caracter\u00edsticas hist\u00f3ricas de la profesi\u00f3n docente, sus caracter\u00edsticas particulares en Canarias su situaci\u00f3n actual, perspectivas e interrelaci\u00f3n con la realidad social de cada \u00e9poca.<\/p>\n\n\n\n<p>CE11 \u2013 Conocer la evoluci\u00f3n hist\u00f3rica de la familia, sus diferentes tipos y la incidencia del contexto familiar en la educaci\u00f3n.<\/p>\n\n\n\n<p>CE13 \u2013 Conocer el valor formativo y cultural de las materias correspondientes a la especializaci\u00f3n y los contenidos que se cursan en las respectivas ense\u00f1anzas<br>CE10 \u2013 Analizar las caracter\u00edsticas hist\u00f3ricas de la profesi\u00f3n docente, sus caracter\u00edsticas particulares en Canarias su situaci\u00f3n actual, perspectivas e interrelaci\u00f3n con la realidad social de cada \u00e9poca.<\/p>\n\n\n\n<p>CE12 \u2013 Adquirir habilidades sociales en la relaci\u00f3n y orientaci\u00f3n familiar.<\/p>\n\n\n\n<p>CE14 \u2013 Conocer la historia y los desarrollos recientes de las materias y sus perspectivas para poder transmitir una visi\u00f3n din\u00e1mica de las mismas.<\/p>\n\n\n\n<p>CE15 \u2013 Conocer contextos y situaciones en que se usan o aplican los diversos contenidos curriculares.<\/p>\n\n\n\n<p>CE16 \u2013 En formaci\u00f3n profesional, conocer la evoluci\u00f3n del mundo laboral, la interacci\u00f3n entre sociedad, trabajo y calidad de vida, as\u00ed como la necesidad de adquirir la formaci\u00f3n adecuada para la adaptaci\u00f3n a los cambios y transformaciones que puedan requerir las profesiones.<\/p>\n\n\n\n<p>CE17 \u2013 Conocer los desarrollos te\u00f3rico-pr\u00e1cticos de la ense\u00f1anza y el aprendizaje de las materias correspondientes.<\/p>\n\n\n\n<p>CE18 \u2013 Transformar los curr\u00edculos en programas de actividades y de trabajo.<\/p>\n\n\n\n<p>CE19 \u2013 Adquirir criterios de selecci\u00f3n y elaboraci\u00f3n de materiales educativos.<\/p>\n\n\n\n<p>CE20 \u2013 Fomentar un clima que facilite el aprendizaje y ponga en valor las aportaciones de los estudiantes.<\/p>\n\n\n\n<p>CE21 \u2013 Integrar la formaci\u00f3n en comunicaci\u00f3n audiovisual y multimedia en el proceso de ense\u00f1anza- aprendizaje.<\/p>\n\n\n\n<p>CE22 \u2013 Conocer estrategias y t\u00e9cnicas de evaluaci\u00f3n y entender la evaluaci\u00f3n como un instrumento de regulaci\u00f3n y est\u00edmulo al esfuerzo.<\/p>\n\n\n\n<p>CE23 \u2013 Conocer y aplicar propuestas docentes innovadoras en el \u00e1mbito de la especializaci\u00f3n cursada.<\/p>\n\n\n\n<p>CE24 \u2013 Analizar cr\u00edticamente el desempe\u00f1o de la docencia, de las buenas pr\u00e1cticas y de la orientaci\u00f3n utilizando indicadores de calidad.<\/p>\n\n\n\n<p>CE25 \u2013 Identificar los problemas relativos a la ense\u00f1anza y aprendizaje de las materias de la especializaci\u00f3n y plantear alternativas y soluciones.<\/p>\n\n\n\n<p>CE26 \u2013 Conocer y aplicar metodolog\u00edas y t\u00e9cnicas b\u00e1sicas de investigaci\u00f3n y evaluaci\u00f3n educativas y ser capaz de dise\u00f1ar y desarrollar proyectos de investigaci\u00f3n, innovaci\u00f3n y evaluaci\u00f3n.<\/p>\n\n\n\n<p>CE27 \u2013 Adquirir experiencia en la planificaci\u00f3n, la docencia y la evaluaci\u00f3n de las materias correspondientes a la especializaci\u00f3n. Acreditar un buen dominio de la expresi\u00f3n oral y escrita en la pr\u00e1ctica docente. Dominar las destrezas y habilidades sociales necesarias para fomentar un clima que facilite el aprendizaje y la convivencia. Participar en las propuestas de mejora en los distintos \u00e1mbitos de actuaci\u00f3n a partir de la reflexi\u00f3n basada en la pr\u00e1ctica. Para la formaci\u00f3n profesional, conocer la tipolog\u00eda empresarial<br>correspondiente a los sectores productivos y comprender los sistemas organizativos m\u00e1s comunes en las empresas.<\/p>\n<\/div><\/div><\/div>\n<\/details>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-53ec762\" data-v=\"4\" data-block-id=\"53ec762\"><style>.stk-53ec762-inner-blocks{row-gap:0px !important;}.stk-53ec762 {padding-top:0px !important;padding-right:0px !important;padding-bottom:0px !important;padding-left:0px !important;}@media screen and (min-width: 768px){.stk-53ec762 {flex:var(--stk-flex-grow, 1) 1 33.3% !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-53ec762-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-53ec762-inner-blocks\">\n\n<ul class=\"widget-box\">\n<li class='contacto-header'>Informaci\u00f3n de contacto<\/li><li><i class=\"fa fa-map-marker\"><\/i> Avda. Astrof\u00edsico Francisco S\u00e1nchez, SN. Edificio Calabaza \u2013 AN.2D Apdo. 456 38200 San Crist\u00f3bal de La Laguna<\/li><li><i class=\"fa fa-envelope\"><\/i>  <a href=mailto:master.profesorado@ull.es>master.profesorado@ull.es<\/a><\/li><li><i class=\"fa fa-archive\"><\/i><a href=\"https:\/\/sede.ull.es\/ecivilis-site\/catalog\/showProcedure\/484\"> Procedimiento para quejas, sugerencias y felicitaciones<\/a><\/li>\n<\/ul>\n\n\n<\/div><\/div><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Competencias Las competencias son el conjunto de conocimientos, habilidades y actitudes a adquirir por el alumnado, a lo largo de la titulaci\u00f3n, orientadas a la preparaci\u00f3n del ejercicio de actividades de car\u00e1cter profesional. Competencias B\u00e1sicas CB6 \u2013 Poseer y comprender conocimientos que aporten una base u oportunidad de ser originales en el desarrollo y\/o aplicaci\u00f3n&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":270,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"templates\/template-frontpage.php","meta":{"footnotes":""},"class_list":["post-38","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Competencias - M\u00e1ster en Formaci\u00f3n del Prof. de E.S.O. y Bachillerato, F.P. y Ense\u00f1anza de Idiomas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ull.es\/masteres\/formacion-profesorado\/plan-de-estudios\/competencias\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Competencias - M\u00e1ster en Formaci\u00f3n del Prof. de E.S.O. y Bachillerato, F.P. y Ense\u00f1anza de Idiomas\" \/>\n<meta property=\"og:description\" content=\"Competencias Las competencias son el conjunto de conocimientos, habilidades y actitudes a adquirir por el alumnado, a lo largo de la titulaci\u00f3n, orientadas a la preparaci\u00f3n del ejercicio de actividades de car\u00e1cter profesional. Competencias B\u00e1sicas CB6 \u2013 Poseer y comprender conocimientos que aporten una base u oportunidad de ser originales en el desarrollo y\/o aplicaci\u00f3n...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ull.es\/masteres\/formacion-profesorado\/plan-de-estudios\/competencias\/\" \/>\n<meta property=\"og:site_name\" content=\"M\u00e1ster en Formaci\u00f3n del Prof. de E.S.O. y Bachillerato, F.P. y Ense\u00f1anza de Idiomas\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-21T09:57:22+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ull.es\\\/masteres\\\/formacion-profesorado\\\/plan-de-estudios\\\/competencias\\\/\",\"url\":\"https:\\\/\\\/www.ull.es\\\/masteres\\\/formacion-profesorado\\\/plan-de-estudios\\\/competencias\\\/\",\"name\":\"Competencias - M\u00e1ster en Formaci\u00f3n del Prof. de E.S.O. y Bachillerato, F.P. y Ense\u00f1anza de Idiomas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ull.es\\\/masteres\\\/formacion-profesorado\\\/#website\"},\"datePublished\":\"2017-06-28T13:01:07+00:00\",\"dateModified\":\"2025-08-21T09:57:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ull.es\\\/masteres\\\/formacion-profesorado\\\/plan-de-estudios\\\/competencias\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ull.es\\\/masteres\\\/formacion-profesorado\\\/plan-de-estudios\\\/competencias\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ull.es\\\/masteres\\\/formacion-profesorado\\\/plan-de-estudios\\\/competencias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ull.es\\\/masteres\\\/formacion-profesorado\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Plan de estudios\",\"item\":\"https:\\\/\\\/www.ull.es\\\/masteres\\\/formacion-profesorado\\\/plan-de-estudios\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Competencias\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ull.es\\\/masteres\\\/formacion-profesorado\\\/#website\",\"url\":\"https:\\\/\\\/www.ull.es\\\/masteres\\\/formacion-profesorado\\\/\",\"name\":\"M\u00e1ster en Formaci\u00f3n del Prof. de E.S.O. y Bachillerato, F.P. y Ense\u00f1anza de Idiomas\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ull.es\\\/masteres\\\/formacion-profesorado\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Competencias - M\u00e1ster en Formaci\u00f3n del Prof. de E.S.O. y Bachillerato, F.P. y Ense\u00f1anza de Idiomas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ull.es\/masteres\/formacion-profesorado\/plan-de-estudios\/competencias\/","og_locale":"es_ES","og_type":"article","og_title":"Competencias - M\u00e1ster en Formaci\u00f3n del Prof. de E.S.O. y Bachillerato, F.P. y Ense\u00f1anza de Idiomas","og_description":"Competencias Las competencias son el conjunto de conocimientos, habilidades y actitudes a adquirir por el alumnado, a lo largo de la titulaci\u00f3n, orientadas a la preparaci\u00f3n del ejercicio de actividades de car\u00e1cter profesional. Competencias B\u00e1sicas CB6 \u2013 Poseer y comprender conocimientos que aporten una base u oportunidad de ser originales en el desarrollo y\/o aplicaci\u00f3n...","og_url":"https:\/\/www.ull.es\/masteres\/formacion-profesorado\/plan-de-estudios\/competencias\/","og_site_name":"M\u00e1ster en Formaci\u00f3n del Prof. de E.S.O. y Bachillerato, F.P. y Ense\u00f1anza de Idiomas","article_modified_time":"2025-08-21T09:57:22+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ull.es\/masteres\/formacion-profesorado\/plan-de-estudios\/competencias\/","url":"https:\/\/www.ull.es\/masteres\/formacion-profesorado\/plan-de-estudios\/competencias\/","name":"Competencias - M\u00e1ster en Formaci\u00f3n del Prof. de E.S.O. y Bachillerato, F.P. y Ense\u00f1anza de Idiomas","isPartOf":{"@id":"https:\/\/www.ull.es\/masteres\/formacion-profesorado\/#website"},"datePublished":"2017-06-28T13:01:07+00:00","dateModified":"2025-08-21T09:57:22+00:00","breadcrumb":{"@id":"https:\/\/www.ull.es\/masteres\/formacion-profesorado\/plan-de-estudios\/competencias\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ull.es\/masteres\/formacion-profesorado\/plan-de-estudios\/competencias\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ull.es\/masteres\/formacion-profesorado\/plan-de-estudios\/competencias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ull.es\/masteres\/formacion-profesorado\/en\/"},{"@type":"ListItem","position":2,"name":"Plan de estudios","item":"https:\/\/www.ull.es\/masteres\/formacion-profesorado\/plan-de-estudios\/"},{"@type":"ListItem","position":3,"name":"Competencias"}]},{"@type":"WebSite","@id":"https:\/\/www.ull.es\/masteres\/formacion-profesorado\/#website","url":"https:\/\/www.ull.es\/masteres\/formacion-profesorado\/","name":"M\u00e1ster en Formaci\u00f3n del Prof. de E.S.O. y Bachillerato, F.P. y Ense\u00f1anza de Idiomas","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ull.es\/masteres\/formacion-profesorado\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.ull.es\/masteres\/formacion-profesorado\/wp-json\/wp\/v2\/pages\/38","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ull.es\/masteres\/formacion-profesorado\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ull.es\/masteres\/formacion-profesorado\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ull.es\/masteres\/formacion-profesorado\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ull.es\/masteres\/formacion-profesorado\/wp-json\/wp\/v2\/comments?post=38"}],"version-history":[{"count":13,"href":"https:\/\/www.ull.es\/masteres\/formacion-profesorado\/wp-json\/wp\/v2\/pages\/38\/revisions"}],"predecessor-version":[{"id":1609,"href":"https:\/\/www.ull.es\/masteres\/formacion-profesorado\/wp-json\/wp\/v2\/pages\/38\/revisions\/1609"}],"up":[{"embeddable":true,"href":"https:\/\/www.ull.es\/masteres\/formacion-profesorado\/wp-json\/wp\/v2\/pages\/270"}],"wp:attachment":[{"href":"https:\/\/www.ull.es\/masteres\/formacion-profesorado\/wp-json\/wp\/v2\/media?parent=38"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}