{"id":23890,"date":"2022-04-07T10:09:13","date_gmt":"2022-04-07T10:09:13","guid":{"rendered":"https:\/\/www.ull.es\/portal\/agenda\/?post_type=tribe_events&#038;p=23890"},"modified":"2022-04-25T10:12:08","modified_gmt":"2022-04-25T10:12:08","slug":"competencias-internacionales-e-interculturales-we-are-international-4","status":"publish","type":"tribe_events","link":"https:\/\/www.ull.es\/portal\/agenda\/evento\/competencias-internacionales-e-interculturales-we-are-international-4\/","title":{"rendered":"Competencias internacionales e interculturales: We are international"},"content":{"rendered":"<p>Este curso de formaci\u00f3n en competencias internacionales e interculturales forma parte de la estrategia de Internacionalizaci\u00f3n en casa<em>\u00a0(Internationalization at home)\u00a0<\/em>promovida por el Vicerrectorado de Proyecci\u00f3n, Internacional y Cooperaci\u00f3n, con la colaboraci\u00f3n del Vicerrectorado de Cultura y Participaci\u00f3n Social, y financiado por el Cabildo Insular de Tenerife, que se celebrar\u00e1 en\u00a0<strong>modalidad presencial<\/strong>\u00a0en la Facultad de Econom\u00eda, Empresa y Turismo entre el\u00a0<strong> 25 de abril y el 20 de mayo <\/strong>de 2022<strong>, reconocible por 1 cr\u00e9dito ECTS.<\/strong><\/p>\n<p>La idea de este curso es proporcionar al alumnado herramientas para desenvolverse mejor en un mundo cada vez m\u00e1s globalizado. Para ello, las actividades y contenidos est\u00e1n dise\u00f1ados para la adquisici\u00f3n y mejora de competencias clave para el desarrollo profesional (competencias profesionales) y la cohesi\u00f3n social (respeto a la diferencia, inclusi\u00f3n y solidaridad).<\/p>\n<p>Queremos que sea una experiencia de reflexi\u00f3n, de comunicaci\u00f3n y, sobre todo, que nos ayude a pensar conjuntamente c\u00f3mo podemos prepararnos y aportar para construir una sociedad mejor.<\/p>\n<p>Se trata de un curso eminentemente pr\u00e1ctico y de utilidad. Contamos con un grupo de personas que incluyen representantes del Consejo de Estudiantes, de asociaciones estudiantiles, expertas en trabajo colaborativo y profesorado de la ULL que quiere ense\u00f1ar, pero tambi\u00e9n aprender y fomentar el debate entre los participantes.<\/p>\n<p>El objetivo final del curso es trazar un relato a lo largo de los m\u00f3dulos que desemboque en un acto final en el que las personas participantes puedan mostrar a la comunidad universitaria lo que han aprendido. El alumnado trabajar\u00e1 conjuntamente y tendr\u00e1 que elegir con otros compa\u00f1eros\/as un tema para presentar en ese acto de clausura.<\/p>\n<p>Se trata de una actividad distinta, donde no hay ex\u00e1menes ni se eval\u00faan los conocimientos del modo tradicional. Lo que pretendemos es animar al alumnado a expresarse, a comunicarse, a conocerse y a darse a conocer.<\/p>\n<p>Dirigen:<\/p>\n<ul>\n<li>Javier Mendoza Jim\u00e9nez. Profesor Ayudante Doctor, Departamento de Direcci\u00f3n de Empresas e Historia Econom\u00eda de la ULL.<\/li>\n<li>Cristina S\u00e1nchez De La Rosa. Profesora de Formaci\u00f3n Profesional. CIFP La Laguna.<\/li>\n<\/ul>\n<p><strong>CERTIFICADO DE ASISTENCIA, APTITUD Y RECONOCIMIENTO POR CR\u00c9DITO ECTS<\/strong><\/p>\n<p>La ULL, a trav\u00e9s del Vicerrectorado de Cultura, Participaci\u00f3n Social y Campus Ofra y La Palma, emitir\u00e1 un certificado de asistencia a todas aquellas personas que asistan a un m\u00ednimo del 80% de las horas lectivas. Asimismo, aquellas personas que superen el trabajo aut\u00f3nomo del alumnado, recibir\u00e1n un certificado de asistencia y aprovechamiento, reconocible a su vez por un cr\u00e9dito ECTS.<\/p>\n<p><a href=\"https:\/\/sede.fg.ull.es\/es\/curso\/detalle\/a22020114\/competencias-internacionales-e-interculturales-we-are-international\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\" rel=\"noopener\"><strong><u>M\u00e1s informaci\u00f3n e inscripci\u00f3n aqu\u00ed.<\/u><\/strong><\/a><\/p>\n<p><span style=\"color: #ff0000\"><strong>\u00a1PLAZAS AGOTADAS!<\/strong><\/span><\/p>\n<p><strong>Contacto: 922 319 616 \/ 922 319 626 \u2013\u00a0<\/strong><a href=\"mailto:extuni@ull.edu.es\" target=\"_blank\" rel=\"noopener\"><strong>extuni@ull.es<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este curso de formaci\u00f3n en competencias internacionales e interculturales forma parte de la estrategia de Internacionalizaci\u00f3n en casa\u00a0(Internationalization at home)\u00a0promovida por el Vicerrectorado de Proyecci\u00f3n, Internacional y Cooperaci\u00f3n, con la colaboraci\u00f3n del Vicerrectorado de Cultura y Participaci\u00f3n Social, y financiado por el Cabildo Insular de Tenerife, que se celebrar\u00e1 en\u00a0modalidad presencial\u00a0en la Facultad de Econom\u00eda,&#8230;<\/p>\n","protected":false},"author":43,"featured_media":23891,"comment_status":"closed","ping_status":"closed","template":"","tags":[4259,977,3812,3751],"tribe_events_cat":[472,4,345,186],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Competencias internacionales e interculturales: We are international - ULL - Agenda<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ull.es\/portal\/agenda\/evento\/competencias-internacionales-e-interculturales-we-are-international-4\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Competencias internacionales e interculturales: We are international - ULL - Agenda\" \/>\n<meta property=\"og:description\" content=\"Este curso de formaci\u00f3n en competencias internacionales e interculturales forma parte de la estrategia de Internacionalizaci\u00f3n en casa\u00a0(Internationalization at home)\u00a0promovida por el Vicerrectorado de Proyecci\u00f3n, Internacional y Cooperaci\u00f3n, con la colaboraci\u00f3n del Vicerrectorado de Cultura y Participaci\u00f3n Social, y financiado por el Cabildo Insular de Tenerife, que se celebrar\u00e1 en\u00a0modalidad presencial\u00a0en la Facultad de Econom\u00eda,...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ull.es\/portal\/agenda\/evento\/competencias-internacionales-e-interculturales-we-are-international-4\/\" \/>\n<meta property=\"og:site_name\" content=\"ULL - Agenda\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-25T10:12:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ull.es\/portal\/agenda\/wp-content\/uploads\/sites\/12\/2022\/04\/BannerInternational.png\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ull.es\/portal\/agenda\/evento\/competencias-internacionales-e-interculturales-we-are-international-4\/\",\"url\":\"https:\/\/www.ull.es\/portal\/agenda\/evento\/competencias-internacionales-e-interculturales-we-are-international-4\/\",\"name\":\"Competencias internacionales e interculturales: We are international - ULL - Agenda\",\"isPartOf\":{\"@id\":\"https:\/\/www.ull.es\/portal\/agenda\/#website\"},\"datePublished\":\"2022-04-07T10:09:13+00:00\",\"dateModified\":\"2022-04-25T10:12:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ull.es\/portal\/agenda\/evento\/competencias-internacionales-e-interculturales-we-are-international-4\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ull.es\/portal\/agenda\/evento\/competencias-internacionales-e-interculturales-we-are-international-4\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ull.es\/portal\/agenda\/evento\/competencias-internacionales-e-interculturales-we-are-international-4\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.ull.es\/portal\/agenda\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Competencias internacionales e interculturales: We are international\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ull.es\/portal\/agenda\/#website\",\"url\":\"https:\/\/www.ull.es\/portal\/agenda\/\",\"name\":\"ULL - Agenda\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ull.es\/portal\/agenda\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Competencias internacionales e interculturales: We are international - ULL - Agenda","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ull.es\/portal\/agenda\/evento\/competencias-internacionales-e-interculturales-we-are-international-4\/","og_locale":"es_ES","og_type":"article","og_title":"Competencias internacionales e interculturales: We are international - ULL - Agenda","og_description":"Este curso de formaci\u00f3n en competencias internacionales e interculturales forma parte de la estrategia de Internacionalizaci\u00f3n en casa\u00a0(Internationalization at home)\u00a0promovida por el Vicerrectorado de Proyecci\u00f3n, Internacional y Cooperaci\u00f3n, con la colaboraci\u00f3n del Vicerrectorado de Cultura y Participaci\u00f3n Social, y financiado por el Cabildo Insular de Tenerife, que se celebrar\u00e1 en\u00a0modalidad presencial\u00a0en la Facultad de Econom\u00eda,...","og_url":"https:\/\/www.ull.es\/portal\/agenda\/evento\/competencias-internacionales-e-interculturales-we-are-international-4\/","og_site_name":"ULL - Agenda","article_modified_time":"2022-04-25T10:12:08+00:00","og_image":[{"width":700,"height":350,"url":"https:\/\/www.ull.es\/portal\/agenda\/wp-content\/uploads\/sites\/12\/2022\/04\/BannerInternational.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ull.es\/portal\/agenda\/evento\/competencias-internacionales-e-interculturales-we-are-international-4\/","url":"https:\/\/www.ull.es\/portal\/agenda\/evento\/competencias-internacionales-e-interculturales-we-are-international-4\/","name":"Competencias internacionales e interculturales: We are international - ULL - Agenda","isPartOf":{"@id":"https:\/\/www.ull.es\/portal\/agenda\/#website"},"datePublished":"2022-04-07T10:09:13+00:00","dateModified":"2022-04-25T10:12:08+00:00","breadcrumb":{"@id":"https:\/\/www.ull.es\/portal\/agenda\/evento\/competencias-internacionales-e-interculturales-we-are-international-4\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ull.es\/portal\/agenda\/evento\/competencias-internacionales-e-interculturales-we-are-international-4\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ull.es\/portal\/agenda\/evento\/competencias-internacionales-e-interculturales-we-are-international-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ull.es\/portal\/agenda\/"},{"@type":"ListItem","position":2,"name":"Competencias internacionales e interculturales: We are international"}]},{"@type":"WebSite","@id":"https:\/\/www.ull.es\/portal\/agenda\/#website","url":"https:\/\/www.ull.es\/portal\/agenda\/","name":"ULL - Agenda","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ull.es\/portal\/agenda\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.ull.es\/portal\/agenda\/wp-json\/wp\/v2\/tribe_events\/23890"}],"collection":[{"href":"https:\/\/www.ull.es\/portal\/agenda\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.ull.es\/portal\/agenda\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.ull.es\/portal\/agenda\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ull.es\/portal\/agenda\/wp-json\/wp\/v2\/comments?post=23890"}],"version-history":[{"count":2,"href":"https:\/\/www.ull.es\/portal\/agenda\/wp-json\/wp\/v2\/tribe_events\/23890\/revisions"}],"predecessor-version":[{"id":24220,"href":"https:\/\/www.ull.es\/portal\/agenda\/wp-json\/wp\/v2\/tribe_events\/23890\/revisions\/24220"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ull.es\/portal\/agenda\/wp-json\/wp\/v2\/media\/23891"}],"wp:attachment":[{"href":"https:\/\/www.ull.es\/portal\/agenda\/wp-json\/wp\/v2\/media?parent=23890"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ull.es\/portal\/agenda\/wp-json\/wp\/v2\/tags?post=23890"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.ull.es\/portal\/agenda\/wp-json\/wp\/v2\/tribe_events_cat?post=23890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}