{"id":21113,"date":"2013-08-27T13:19:11","date_gmt":"2013-08-27T13:19:11","guid":{"rendered":"http:\/\/ddigital.webs.ull.es\/doce-graduados-en-bellas-artes-realizaran-durante-un-ano-el-nuevo-mural-del-puerto-de-los-cristianos\/"},"modified":"2013-08-27T13:19:11","modified_gmt":"2013-08-27T13:19:11","slug":"doce-graduados-en-bellas-artes-realizaran-durante-un-ano-el-nuevo-mural-del-puerto-de-los-cristianos","status":"publish","type":"post","link":"https:\/\/www.ull.es\/portal\/noticias\/2013\/doce-graduados-en-bellas-artes-realizaran-durante-un-ano-el-nuevo-mural-del-puerto-de-los-cristianos\/","title":{"rendered":"Doce graduados en Bellas Artes realizar\u00e1n durante un a\u00f1o el nuevo mural del puerto de Los Cristianos"},"content":{"rendered":"<p> \tDoce graduados en Bellas Artes por la Universidad de La Laguna (ULL) trabajar&aacute;n durante un a&ntilde;o en el nuevo mural del puerto de Los Cristianos, que bajo la denominaci&oacute;n &ldquo;Tres Orillas&rdquo; es obra de la estudiante Paula Calavera Candela, ganadora del concurso convocado al efecto por Puertos de Tenerife y la ULL.<\/p>\n<p> \tEl futuro mural fue presentado recientemente en el transcurso de un acto que fue de la mano del titular de Puertos de Tenerife, Pedro Rodr&iacute;guez Zaragoza; el decano de la Facultad de Bellas Artes, Alfonso Ruiz Rallo; el profesor de dicha Facultad, Severo Acosta Hern&aacute;ndez, la joven ganadora del concurso y los estudiantes integran el grupo de trabajo.<\/p>\n<p> \tEl mural representar&aacute; los fondos marinos de Canarias, tanto en flora como en fauna y, de acuerdo con Paula Calavera, cumple con una estructura lineal, narrativa, que va &ldquo;desde la orilla hasta lo m&aacute;s profundo&rdquo;. La ganadora del concurso indic&oacute; que los trabajos comenzar&aacute;n en la parte del dique m&aacute;s cercana a la Playa de Las Vistas, ocupando el primer tramo del mismo unos 138 metros.<\/p>\n<p> \tRodr&iacute;guez Zaragoza resalt&oacute; el gran nivel de las obras presentadas, lo que condujo a la concesi&oacute;n de un acc&eacute;sit, inicialmente no previsto, al trabajo &ldquo;Cromarina&rdquo;, de la estudiante Sara Rodr&iacute;guez Concepci&oacute;n. El titular de Puertos de Tenerife record&oacute; que el citado dique cuenta con 500 metros de largo y cinco de alto, o lo que es lo mismo, una superficie de 2.500 metros cuadrados, en la que se espera se comience a realizar el mural el pr&oacute;ximo mes de septiembre.<\/p>\n<p> \tEl decano Ruiz Tallo valor&oacute; como &ldquo;condiciones impresionantes&rdquo; las que hay que afrontar para la ejecuci&oacute;n del mural, apreciando asimismo de manera especial la repercusi&oacute;n que &eacute;ste tendr&aacute; una vez concluido gracias a los miles de turistas que visitan el enclave sure&ntilde;o y utilizan su puerto, uno de los que m&aacute;s pasajeros mueve en todo el territorio nacional.<\/p>\n<p> \tNo menos impresionante, es, en palabras del decano, que en estos tiempos de crisis esta iniciativa permita a doce alumnos de inmediata graduaci&oacute;n &ldquo;trabajar en lo que a ellos les gusta durante un a&ntilde;o y en unas m&aacute;s que buenas condiciones laborales&rdquo;.<\/p>\n<p> \tAl respecto, Severo Acosta, director y supervisor del procedimiento creativo, asegur&oacute; que la ejecuci&oacute;n del proyecto &ldquo;ser&aacute; un gran reto art&iacute;stico y t&eacute;cnico&rdquo;, pero que, al ser ejecutado por un grupo de las mejores promociones de la Facultad sin duda &ldquo;resultar&aacute; de una calidad magn&iacute;fica&rdquo;.<\/p>\n<p> \tAcosta adelant&oacute; que el mural, altamente figurativo, se ir&aacute; ejecutando en fragmentos de seis metros de largo, esperando tener concluido en Navidad el primer tramo. El equipo de trabajo ya est&aacute; activado, trabajando actualmente en la selecci&oacute;n de la pintura a utilizar, que deber&aacute; ser de unas caracter&iacute;sticas muy particulares para resistir las inclemencias del tiempo.<\/p>\n<p> \t(Nota y foto cedidas por la autoridad Portuaria de Tenerife)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Doce graduados en Bellas Artes por la Universidad de La Laguna (ULL) trabajar&aacute;n durante un a&ntilde;o en el nuevo mural&#8230;<\/p>\n","protected":false},"author":21,"featured_media":21114,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[344,1],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Doce graduados en Bellas Artes realizar\u00e1n durante un a\u00f1o el nuevo mural del puerto de Los Cristianos - ULL - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ull.es\/portal\/noticias\/2013\/doce-graduados-en-bellas-artes-realizaran-durante-un-ano-el-nuevo-mural-del-puerto-de-los-cristianos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Doce graduados en Bellas Artes realizar\u00e1n durante un a\u00f1o el nuevo mural del puerto de Los Cristianos - ULL - Noticias\" \/>\n<meta property=\"og:description\" content=\"Doce graduados en Bellas Artes por la Universidad de La Laguna (ULL) trabajar&aacute;n durante un a&ntilde;o en el nuevo mural...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ull.es\/portal\/noticias\/2013\/doce-graduados-en-bellas-artes-realizaran-durante-un-ano-el-nuevo-mural-del-puerto-de-los-cristianos\/\" \/>\n<meta property=\"og:site_name\" content=\"ULL - Noticias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/universidaddelalaguna\/\" \/>\n<meta property=\"article:published_time\" content=\"2013-08-27T13:19:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ull.es\/portal\/noticias\/wp-content\/uploads\/sites\/13\/2015\/07\/bbaa_puerto.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"440\" \/>\n\t<meta property=\"og:image:height\" content=\"247\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"prensa2\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CanalULL\" \/>\n<meta name=\"twitter:site\" content=\"@CanalULL\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"prensa2\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ull.es\/portal\/noticias\/2013\/doce-graduados-en-bellas-artes-realizaran-durante-un-ano-el-nuevo-mural-del-puerto-de-los-cristianos\/\",\"url\":\"https:\/\/www.ull.es\/portal\/noticias\/2013\/doce-graduados-en-bellas-artes-realizaran-durante-un-ano-el-nuevo-mural-del-puerto-de-los-cristianos\/\",\"name\":\"Doce graduados en Bellas Artes realizar\u00e1n durante un a\u00f1o el nuevo mural del puerto de Los Cristianos - ULL - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/www.ull.es\/portal\/noticias\/#website\"},\"datePublished\":\"2013-08-27T13:19:11+00:00\",\"dateModified\":\"2013-08-27T13:19:11+00:00\",\"author\":{\"@id\":\"https:\/\/www.ull.es\/portal\/noticias\/#\/schema\/person\/c3b2aa857797592927a03740d6664376\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ull.es\/portal\/noticias\/2013\/doce-graduados-en-bellas-artes-realizaran-durante-un-ano-el-nuevo-mural-del-puerto-de-los-cristianos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ull.es\/portal\/noticias\/2013\/doce-graduados-en-bellas-artes-realizaran-durante-un-ano-el-nuevo-mural-del-puerto-de-los-cristianos\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ull.es\/portal\/noticias\/2013\/doce-graduados-en-bellas-artes-realizaran-durante-un-ano-el-nuevo-mural-del-puerto-de-los-cristianos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.ull.es\/portal\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Doce graduados en Bellas Artes realizar\u00e1n durante un a\u00f1o el nuevo mural del puerto de Los Cristianos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ull.es\/portal\/noticias\/#website\",\"url\":\"https:\/\/www.ull.es\/portal\/noticias\/\",\"name\":\"ULL - Noticias\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ull.es\/portal\/noticias\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ull.es\/portal\/noticias\/#\/schema\/person\/c3b2aa857797592927a03740d6664376\",\"name\":\"prensa2\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.ull.es\/portal\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b58f310a5de5feb33d1e026d2493f23c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b58f310a5de5feb33d1e026d2493f23c?s=96&d=mm&r=g\",\"caption\":\"prensa2\"},\"url\":\"https:\/\/www.ull.es\/portal\/noticias\/author\/prensa2\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Doce graduados en Bellas Artes realizar\u00e1n durante un a\u00f1o el nuevo mural del puerto de Los Cristianos - ULL - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ull.es\/portal\/noticias\/2013\/doce-graduados-en-bellas-artes-realizaran-durante-un-ano-el-nuevo-mural-del-puerto-de-los-cristianos\/","og_locale":"es_ES","og_type":"article","og_title":"Doce graduados en Bellas Artes realizar\u00e1n durante un a\u00f1o el nuevo mural del puerto de Los Cristianos - ULL - Noticias","og_description":"Doce graduados en Bellas Artes por la Universidad de La Laguna (ULL) trabajar&aacute;n durante un a&ntilde;o en el nuevo mural...","og_url":"https:\/\/www.ull.es\/portal\/noticias\/2013\/doce-graduados-en-bellas-artes-realizaran-durante-un-ano-el-nuevo-mural-del-puerto-de-los-cristianos\/","og_site_name":"ULL - Noticias","article_publisher":"https:\/\/www.facebook.com\/universidaddelalaguna\/","article_published_time":"2013-08-27T13:19:11+00:00","og_image":[{"width":440,"height":247,"url":"https:\/\/www.ull.es\/portal\/noticias\/wp-content\/uploads\/sites\/13\/2015\/07\/bbaa_puerto.jpg","type":"image\/jpeg"}],"author":"prensa2","twitter_card":"summary_large_image","twitter_creator":"@CanalULL","twitter_site":"@CanalULL","twitter_misc":{"Escrito por":"prensa2","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ull.es\/portal\/noticias\/2013\/doce-graduados-en-bellas-artes-realizaran-durante-un-ano-el-nuevo-mural-del-puerto-de-los-cristianos\/","url":"https:\/\/www.ull.es\/portal\/noticias\/2013\/doce-graduados-en-bellas-artes-realizaran-durante-un-ano-el-nuevo-mural-del-puerto-de-los-cristianos\/","name":"Doce graduados en Bellas Artes realizar\u00e1n durante un a\u00f1o el nuevo mural del puerto de Los Cristianos - ULL - Noticias","isPartOf":{"@id":"https:\/\/www.ull.es\/portal\/noticias\/#website"},"datePublished":"2013-08-27T13:19:11+00:00","dateModified":"2013-08-27T13:19:11+00:00","author":{"@id":"https:\/\/www.ull.es\/portal\/noticias\/#\/schema\/person\/c3b2aa857797592927a03740d6664376"},"breadcrumb":{"@id":"https:\/\/www.ull.es\/portal\/noticias\/2013\/doce-graduados-en-bellas-artes-realizaran-durante-un-ano-el-nuevo-mural-del-puerto-de-los-cristianos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ull.es\/portal\/noticias\/2013\/doce-graduados-en-bellas-artes-realizaran-durante-un-ano-el-nuevo-mural-del-puerto-de-los-cristianos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ull.es\/portal\/noticias\/2013\/doce-graduados-en-bellas-artes-realizaran-durante-un-ano-el-nuevo-mural-del-puerto-de-los-cristianos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ull.es\/portal\/noticias\/"},{"@type":"ListItem","position":2,"name":"Doce graduados en Bellas Artes realizar\u00e1n durante un a\u00f1o el nuevo mural del puerto de Los Cristianos"}]},{"@type":"WebSite","@id":"https:\/\/www.ull.es\/portal\/noticias\/#website","url":"https:\/\/www.ull.es\/portal\/noticias\/","name":"ULL - Noticias","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ull.es\/portal\/noticias\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.ull.es\/portal\/noticias\/#\/schema\/person\/c3b2aa857797592927a03740d6664376","name":"prensa2","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ull.es\/portal\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b58f310a5de5feb33d1e026d2493f23c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b58f310a5de5feb33d1e026d2493f23c?s=96&d=mm&r=g","caption":"prensa2"},"url":"https:\/\/www.ull.es\/portal\/noticias\/author\/prensa2\/"}]}},"primary_category":null,"featured_image_thumbnail_url":"https:\/\/www.ull.es\/portal\/noticias\/wp-content\/uploads\/sites\/13\/2015\/07\/bbaa_puerto-300x168.jpg","_links":{"self":[{"href":"https:\/\/www.ull.es\/portal\/noticias\/wp-json\/wp\/v2\/posts\/21113"}],"collection":[{"href":"https:\/\/www.ull.es\/portal\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ull.es\/portal\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ull.es\/portal\/noticias\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ull.es\/portal\/noticias\/wp-json\/wp\/v2\/comments?post=21113"}],"version-history":[{"count":0,"href":"https:\/\/www.ull.es\/portal\/noticias\/wp-json\/wp\/v2\/posts\/21113\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ull.es\/portal\/noticias\/wp-json\/wp\/v2\/media\/21114"}],"wp:attachment":[{"href":"https:\/\/www.ull.es\/portal\/noticias\/wp-json\/wp\/v2\/media?parent=21113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ull.es\/portal\/noticias\/wp-json\/wp\/v2\/categories?post=21113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ull.es\/portal\/noticias\/wp-json\/wp\/v2\/tags?post=21113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}