{"id":32938,"date":"2017-09-26T11:46:38","date_gmt":"2017-09-26T11:46:38","guid":{"rendered":"https:\/\/www.ull.es\/portal\/noticias\/?p=32938"},"modified":"2017-09-26T12:26:24","modified_gmt":"2017-09-26T12:26:24","slug":"la-ull-celebra-las-iv-jornadas-calidad-los-servicios-revisar-mejorar-sistema-gestion","status":"publish","type":"post","link":"https:\/\/www.ull.es\/portal\/noticias\/2017\/la-ull-celebra-las-iv-jornadas-calidad-los-servicios-revisar-mejorar-sistema-gestion\/","title":{"rendered":"La ULL celebra las IV Jornadas de Calidad de los Servicios para revisar y mejorar su sistema de gesti\u00f3n"},"content":{"rendered":"<p><a href=\"https:\/\/www.ull.es\/portal\/noticias\/wp-content\/uploads\/sites\/13\/2017\/09\/calidad4.jpg\" target=\"_blank\" rel=\"noopener\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-32939\" src=\"https:\/\/www.ull.es\/portal\/noticias\/wp-content\/uploads\/sites\/13\/2017\/09\/calidad4-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.ull.es\/portal\/noticias\/wp-content\/uploads\/sites\/13\/2017\/09\/calidad4-300x200.jpg 300w, https:\/\/www.ull.es\/portal\/noticias\/wp-content\/uploads\/sites\/13\/2017\/09\/calidad4-768x512.jpg 768w, https:\/\/www.ull.es\/portal\/noticias\/wp-content\/uploads\/sites\/13\/2017\/09\/calidad4.jpg 1024w, https:\/\/www.ull.es\/portal\/noticias\/wp-content\/uploads\/sites\/13\/2017\/09\/calidad4-375x250.jpg 375w, https:\/\/www.ull.es\/portal\/noticias\/wp-content\/uploads\/sites\/13\/2017\/09\/calidad4-750x500.jpg 750w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<div>Foto: Emeterio Su\u00e1rez (CC BY 3.0)<\/div>\n<p>&nbsp;<\/p>\n<p>La Universidad de La Laguna celebr\u00f3 hoy las IV Jornadas de Calidad en la Gesti\u00f3n de los Servicios, una iniciativa pensada como espacio de reflexi\u00f3n del centro acad\u00e9mico acerca de los sistemas de gesti\u00f3n de la instituci\u00f3n y, de paso, como herramienta para conocer casos pr\u00e1cticos de otras universidades espa\u00f1olas, tal y como destac\u00f3 la gerente, Lidia Pereira, en el acto de inauguraci\u00f3n.<\/p>\n<p style=\"text-align: center\"><a href=\"https:\/\/drive.google.com\/drive\/folders\/0ByNgObFV1P0eZlU4cnROX3VHV0k?usp=sharing\" target=\"_blank\" rel=\"noopener\" target=\"_blank\" rel=\"noopener\"><strong>Ver galer\u00eda de im\u00e1genes<\/strong><\/a><\/p>\n<p>Para el rector, Antonio Martin\u00f3n, este tipo de actividades forman parte de las cosas importantes que han de hacerse dentro de la universidad. \u201cEs un deber de los servidores p\u00fablicos el hacer las cosas bien, con calidad y excelencia y de la mejor manera posible. No se trata de hacer lo que siempre se ha hecho, sino de producir una mejora sustancial en nuestros procesos\u201d, explic\u00f3.<\/p>\n<p>\u201cLa imagen que damos est\u00e1 muy impactada por la forma en la que prestamos el servicio p\u00fablico, lo que adem\u00e1s repercute en el clima dentro de la propia universidad\u201d, a\u00f1adi\u00f3 el rector. La aparici\u00f3n de numerosas universidades privadas, alrededor de treinta en los \u00faltimos quince a\u00f1os, \u201chace que aquellos que defendemos lo p\u00fablico hagamos un mayor esfuerzo\u201d, sostuvo Martin\u00f3n, para quien resulta imprescindible contar con recursos y con una eficaz organizaci\u00f3n, \u201cpero tambi\u00e9n con la voluntad con la que hacemos nuestro trabajo\u201d, precis\u00f3. \u201cEl tiempo dedicado a la funci\u00f3n p\u00fablica debe ser honesto e intenso. Todos tenemos un papel que jugar en la universidad y les pido que lo hagan con la mayor calidad posible\u201d, concluy\u00f3 el rector.<\/p>\n<p><strong>M\u00e1s personal cualificado<\/strong><\/p>\n<p>El que fuera profesor titular de la Universidad de M\u00e1laga y gerente de la Universidad de Ja\u00e9n, Juan Hern\u00e1ndez Armenteros, adem\u00e1s de director del informe de la CRUE \u2018La Universidad en Cifras\u2019, ofreci\u00f3 la primera ponencia de la ma\u00f1ana, dedicada a la profesionalizaci\u00f3n del personal de administraci\u00f3n y servicios (PAS).<\/p>\n<p>El experto hizo un repaso por el modelo de gesti\u00f3n con el que han funcionado las universidades desde finales de la dictadura hasta ahora. Se\u00f1al\u00f3 que durante muchos a\u00f1os hemos tenido un sistema universitario centralizado y homog\u00e9neo, hasta 1983, lo que exig\u00eda que el apoyo t\u00e9cnico de gesti\u00f3n fuera reducido y poco cualificado porque las principales competencias eran ministeriales. Este modelo se rompe con la aprobaci\u00f3n de la Ley de Reforma Universitaria y el inicio del traspaso de competencias a las comunidades aut\u00f3nomas.<\/p>\n<p>La funci\u00f3n de la actividad docente se ampl\u00eda entonces y se democratiza el acceso a la universidad, con una expansi\u00f3n del sistema universitario y un crecimiento de la oferta de t\u00edtulos de grado y posgrado, sin especializaci\u00f3n de unas universidades a otras. El impulso de la actividad investigadora, y la ausencia de PAS cualificado, ha hecho que la gesti\u00f3n haya estado muy participada por el profesorado, indic\u00f3 el ponente. \u201cEsto aflora en la medida en que los usuarios presionan cada vez m\u00e1s a la administraci\u00f3n para que le ofrezca un servicio \u00e1gil y moderno y \u00e9sta no sabe responderle\u201d.<\/p>\n<p>\u201cTenemos un modelo de gesti\u00f3n y de gobierno en las universidades que apenas ha cambiado desde 1983, un modelo tan tupido y con tanta representaci\u00f3n que los usuarios no saben ad\u00f3nde dirigirse\u201d, agreg\u00f3. Hern\u00e1ndez Armenteros a\u00f1adi\u00f3 que la definici\u00f3n de funciones ha de recaer en los equipos de direcci\u00f3n y \u00f3rganos de financiaci\u00f3n y representaci\u00f3n, pero que la ejecuci\u00f3n de esos planes, la evaluaci\u00f3n y la gesti\u00f3n son reservadas al PAS.<\/p>\n<p>Mejorar la relaci\u00f3n PAS\/PDI, aumentar la cualificaci\u00f3n del personal y la flexibilidad en la estructura de PAS resultan claves para profesionalizar la gesti\u00f3n, asegur\u00f3 el experto. \u201cLa profesionalizaci\u00f3n no es solo subir el nivel y ganar m\u00e1s, eso no es suficiente\u201d. Hay que generar cambios y adaptarse a nuevos entornos, explic\u00f3, al tiempo que tener claro el recorrido de una carrera profesional, que no consiste en ir de un puesto a otro, tan solo con la perspectiva de una promoci\u00f3n vertical, sino saber estar en los puestos y profesionalizarlos.<\/p>\n<p>La gesti\u00f3n de la investigaci\u00f3n en las universidades est\u00e1 mal gestionada, con personal sin perfiles especializados, sostuvo Armenteros, quien consider\u00f3 que cuanta m\u00e1s cualificaci\u00f3n tiene el personal mejor es la gesti\u00f3n que realiza. Con todo, si bien el comportamiento del PAS ha sido muy diferente de unas universidades a otras, s\u00ed ha habido un crecimiento del PAS de gesti\u00f3n en todas ellas, para lograr ser m\u00e1s transparentes, m\u00e1s eficaces y capaces de desarrollar pol\u00edticas de calidad y de investigaci\u00f3n.<\/p>\n<p>En el caso de La Laguna, el d\u00e9ficit de PAS de gesti\u00f3n es muy elevado, asever\u00f3. \u201cCualificar una gesti\u00f3n es muy dif\u00edcil, pero deben de cambiar su estructura de gesti\u00f3n, ya que de lo contrario es muy dif\u00edcil ofrecer una gesti\u00f3n profesional\u201d. Lo que no supone un valor a\u00f1adido, aunque sea necesario, puede externalizarse, pero lo que resulta estrat\u00e9gico debe profesionalizarse dentro de la propia corporaci\u00f3n, explic\u00f3.<\/p>\n<p>En su opini\u00f3n, hay una presi\u00f3n sindical para mejorar las retribuciones de los distintos niveles funcionariales, y de ello resulta que se engorda los niveles no cualificados y se deja sin cubrir los puestos de alto nivel y cualificados. Por otro lado, apunt\u00f3 la idea de reducir los cargos directivos del profesorado y aumentar las responsabilidades de PAS en este \u00e1mbito, retribuy\u00e9ndole adecuadamente, pero tambi\u00e9n exigi\u00e9ndole m\u00e1s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hern\u00e1ndez Armenteros asegura que es necesario contar con m\u00e1s personal de administraci\u00f3n y servicios cualificado para profesionalizar los equipos<\/p>\n","protected":false},"author":20,"featured_media":32939,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"image","meta":{"inline_featured_image":false,"footnotes":""},"categories":[345,348,2765],"tags":[3403,3402,3404,3405,2527,2560],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La ULL celebra las IV Jornadas de Calidad de los Servicios para revisar y mejorar su sistema de gesti\u00f3n<\/title>\n<meta name=\"description\" content=\"La ULL celebra las IV Jornadas de Calidad de los Servicios para revisar y mejorar su sistema de gesti\u00f3n, una iniciativa pensada como espacio de reflexi\u00f3n\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ull.es\/portal\/noticias\/2017\/la-ull-celebra-las-iv-jornadas-calidad-los-servicios-revisar-mejorar-sistema-gestion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La ULL celebra las IV Jornadas de Calidad de los Servicios para revisar y mejorar su sistema de gesti\u00f3n\" \/>\n<meta property=\"og:description\" content=\"La ULL celebra las IV Jornadas de Calidad de los Servicios para revisar y mejorar su sistema de gesti\u00f3n, una iniciativa pensada como espacio de reflexi\u00f3n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ull.es\/portal\/noticias\/2017\/la-ull-celebra-las-iv-jornadas-calidad-los-servicios-revisar-mejorar-sistema-gestion\/\" \/>\n<meta property=\"og:site_name\" content=\"ULL - Noticias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/universidaddelalaguna\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-09-26T11:46:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-09-26T12:26:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ull.es\/portal\/noticias\/wp-content\/uploads\/sites\/13\/2017\/09\/calidad4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"prensa1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CanalULL\" \/>\n<meta name=\"twitter:site\" content=\"@CanalULL\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"prensa1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ull.es\/portal\/noticias\/2017\/la-ull-celebra-las-iv-jornadas-calidad-los-servicios-revisar-mejorar-sistema-gestion\/\",\"url\":\"https:\/\/www.ull.es\/portal\/noticias\/2017\/la-ull-celebra-las-iv-jornadas-calidad-los-servicios-revisar-mejorar-sistema-gestion\/\",\"name\":\"La ULL celebra las IV Jornadas de Calidad de los Servicios para revisar y mejorar su sistema de gesti\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.ull.es\/portal\/noticias\/#website\"},\"datePublished\":\"2017-09-26T11:46:38+00:00\",\"dateModified\":\"2017-09-26T12:26:24+00:00\",\"author\":{\"@id\":\"https:\/\/www.ull.es\/portal\/noticias\/#\/schema\/person\/ea9b721b26bc001d9f8820a760100f96\"},\"description\":\"La ULL celebra las IV Jornadas de Calidad de los Servicios para revisar y mejorar su sistema de gesti\u00f3n, una iniciativa pensada como espacio de reflexi\u00f3n\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ull.es\/portal\/noticias\/2017\/la-ull-celebra-las-iv-jornadas-calidad-los-servicios-revisar-mejorar-sistema-gestion\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ull.es\/portal\/noticias\/2017\/la-ull-celebra-las-iv-jornadas-calidad-los-servicios-revisar-mejorar-sistema-gestion\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ull.es\/portal\/noticias\/2017\/la-ull-celebra-las-iv-jornadas-calidad-los-servicios-revisar-mejorar-sistema-gestion\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.ull.es\/portal\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La ULL celebra las IV Jornadas de Calidad de los Servicios para revisar y mejorar su sistema de gesti\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ull.es\/portal\/noticias\/#website\",\"url\":\"https:\/\/www.ull.es\/portal\/noticias\/\",\"name\":\"ULL - Noticias\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ull.es\/portal\/noticias\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ull.es\/portal\/noticias\/#\/schema\/person\/ea9b721b26bc001d9f8820a760100f96\",\"name\":\"prensa1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.ull.es\/portal\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/94b9dcabd35142d3e94c7343cd1c6ca0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/94b9dcabd35142d3e94c7343cd1c6ca0?s=96&d=mm&r=g\",\"caption\":\"prensa1\"},\"url\":\"https:\/\/www.ull.es\/portal\/noticias\/author\/prensa1\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La ULL celebra las IV Jornadas de Calidad de los Servicios para revisar y mejorar su sistema de gesti\u00f3n","description":"La ULL celebra las IV Jornadas de Calidad de los Servicios para revisar y mejorar su sistema de gesti\u00f3n, una iniciativa pensada como espacio de reflexi\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ull.es\/portal\/noticias\/2017\/la-ull-celebra-las-iv-jornadas-calidad-los-servicios-revisar-mejorar-sistema-gestion\/","og_locale":"es_ES","og_type":"article","og_title":"La ULL celebra las IV Jornadas de Calidad de los Servicios para revisar y mejorar su sistema de gesti\u00f3n","og_description":"La ULL celebra las IV Jornadas de Calidad de los Servicios para revisar y mejorar su sistema de gesti\u00f3n, una iniciativa pensada como espacio de reflexi\u00f3n","og_url":"https:\/\/www.ull.es\/portal\/noticias\/2017\/la-ull-celebra-las-iv-jornadas-calidad-los-servicios-revisar-mejorar-sistema-gestion\/","og_site_name":"ULL - Noticias","article_publisher":"https:\/\/www.facebook.com\/universidaddelalaguna\/","article_published_time":"2017-09-26T11:46:38+00:00","article_modified_time":"2017-09-26T12:26:24+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/www.ull.es\/portal\/noticias\/wp-content\/uploads\/sites\/13\/2017\/09\/calidad4.jpg","type":"image\/jpeg"}],"author":"prensa1","twitter_card":"summary_large_image","twitter_creator":"@CanalULL","twitter_site":"@CanalULL","twitter_misc":{"Escrito por":"prensa1","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ull.es\/portal\/noticias\/2017\/la-ull-celebra-las-iv-jornadas-calidad-los-servicios-revisar-mejorar-sistema-gestion\/","url":"https:\/\/www.ull.es\/portal\/noticias\/2017\/la-ull-celebra-las-iv-jornadas-calidad-los-servicios-revisar-mejorar-sistema-gestion\/","name":"La ULL celebra las IV Jornadas de Calidad de los Servicios para revisar y mejorar su sistema de gesti\u00f3n","isPartOf":{"@id":"https:\/\/www.ull.es\/portal\/noticias\/#website"},"datePublished":"2017-09-26T11:46:38+00:00","dateModified":"2017-09-26T12:26:24+00:00","author":{"@id":"https:\/\/www.ull.es\/portal\/noticias\/#\/schema\/person\/ea9b721b26bc001d9f8820a760100f96"},"description":"La ULL celebra las IV Jornadas de Calidad de los Servicios para revisar y mejorar su sistema de gesti\u00f3n, una iniciativa pensada como espacio de reflexi\u00f3n","breadcrumb":{"@id":"https:\/\/www.ull.es\/portal\/noticias\/2017\/la-ull-celebra-las-iv-jornadas-calidad-los-servicios-revisar-mejorar-sistema-gestion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ull.es\/portal\/noticias\/2017\/la-ull-celebra-las-iv-jornadas-calidad-los-servicios-revisar-mejorar-sistema-gestion\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ull.es\/portal\/noticias\/2017\/la-ull-celebra-las-iv-jornadas-calidad-los-servicios-revisar-mejorar-sistema-gestion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ull.es\/portal\/noticias\/"},{"@type":"ListItem","position":2,"name":"La ULL celebra las IV Jornadas de Calidad de los Servicios para revisar y mejorar su sistema de gesti\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/www.ull.es\/portal\/noticias\/#website","url":"https:\/\/www.ull.es\/portal\/noticias\/","name":"ULL - Noticias","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ull.es\/portal\/noticias\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.ull.es\/portal\/noticias\/#\/schema\/person\/ea9b721b26bc001d9f8820a760100f96","name":"prensa1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ull.es\/portal\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/94b9dcabd35142d3e94c7343cd1c6ca0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/94b9dcabd35142d3e94c7343cd1c6ca0?s=96&d=mm&r=g","caption":"prensa1"},"url":"https:\/\/www.ull.es\/portal\/noticias\/author\/prensa1\/"}]}},"primary_category":{"id":348,"name":"Instituci\u00f3n","slug":"institucion","link":"https:\/\/www.ull.es\/portal\/noticias\/category\/institucion\/"},"featured_image_thumbnail_url":"https:\/\/www.ull.es\/portal\/noticias\/wp-content\/uploads\/sites\/13\/2017\/09\/calidad4-300x200.jpg","_links":{"self":[{"href":"https:\/\/www.ull.es\/portal\/noticias\/wp-json\/wp\/v2\/posts\/32938"}],"collection":[{"href":"https:\/\/www.ull.es\/portal\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ull.es\/portal\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ull.es\/portal\/noticias\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ull.es\/portal\/noticias\/wp-json\/wp\/v2\/comments?post=32938"}],"version-history":[{"count":4,"href":"https:\/\/www.ull.es\/portal\/noticias\/wp-json\/wp\/v2\/posts\/32938\/revisions"}],"predecessor-version":[{"id":32944,"href":"https:\/\/www.ull.es\/portal\/noticias\/wp-json\/wp\/v2\/posts\/32938\/revisions\/32944"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ull.es\/portal\/noticias\/wp-json\/wp\/v2\/media\/32939"}],"wp:attachment":[{"href":"https:\/\/www.ull.es\/portal\/noticias\/wp-json\/wp\/v2\/media?parent=32938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ull.es\/portal\/noticias\/wp-json\/wp\/v2\/categories?post=32938"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ull.es\/portal\/noticias\/wp-json\/wp\/v2\/tags?post=32938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}