{"id":52296,"date":"2020-10-01T11:41:16","date_gmt":"2020-10-01T11:41:16","guid":{"rendered":"https:\/\/www.ull.es\/portal\/noticias\/?p=52296"},"modified":"2020-10-01T11:41:16","modified_gmt":"2020-10-01T11:41:16","slug":"jornada-de-bienvenida-al-alumnado-de-primero-del-grado-en-ingenieria-agricola-y-del-medio-rural","status":"publish","type":"post","link":"https:\/\/www.ull.es\/portal\/noticias\/2020\/jornada-de-bienvenida-al-alumnado-de-primero-del-grado-en-ingenieria-agricola-y-del-medio-rural\/","title":{"rendered":"Jornada de Bienvenida al alumnado de primero del Grado en Ingenier\u00eda Agr\u00edcola y del Medio Rural"},"content":{"rendered":"<p>La Jornada de Bienvenida de la Secci\u00f3n de Ingenier\u00eda Agraria de la Escuela Polit\u00e9cnica Superior de Ingenier\u00eda se celebrar\u00e1 este a\u00f1o, debido a las restricciones de aforo, de forma on-line, con conexi\u00f3n a trav\u00e9s de Google Meet mediante el siguiente <a href=\"https:\/\/meet.google.com\/pkt-gimb-twa\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\" rel=\"noopener\">enlace.\u00a0<\/a>Tendr\u00e1 lugar el 6 de octubre a partir de las 12:00 horas.<\/p>\n<p>Esta Jornada est\u00e1 destinada al alumnado de nuevo ingreso de primer curso, aunque est\u00e1 invitado todo el alumnado de la Secci\u00f3n.<\/p>\n<p>En la misma nos presentaremos como Equipo de Direcci\u00f3n, Servicios (Biblioteca, etc.), Docentes, Biblioteca, Personal de Administraci\u00f3n y Servicio, Biblioteca, escenarios de Docencia ante esta Pandemia, etc.<\/p>\n<p>Para m\u00e1s informaci\u00f3n, pulse este <a href=\"https:\/\/drive.google.com\/file\/d\/1XQNaJDzisZZBcfrcsReRKTtCLN396JwE\/view?usp=sharing\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\" rel=\"noopener\">enlace.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Jornada de Bienvenida de la Secci\u00f3n de Ingenier\u00eda Agraria de la Escuela Polit\u00e9cnica Superior de Ingenier\u00eda se celebrar\u00e1 este&#8230;<\/p>\n","protected":false},"author":65,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[3845],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Jornada de Bienvenida al alumnado de primero del Grado en Ingenier\u00eda Agr\u00edcola y del Medio Rural - ULL - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ull.es\/portal\/noticias\/2020\/jornada-de-bienvenida-al-alumnado-de-primero-del-grado-en-ingenieria-agricola-y-del-medio-rural\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jornada de Bienvenida al alumnado de primero del Grado en Ingenier\u00eda Agr\u00edcola y del Medio Rural - ULL - Noticias\" \/>\n<meta property=\"og:description\" content=\"La Jornada de Bienvenida de la Secci\u00f3n de Ingenier\u00eda Agraria de la Escuela Polit\u00e9cnica Superior de Ingenier\u00eda se celebrar\u00e1 este...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ull.es\/portal\/noticias\/2020\/jornada-de-bienvenida-al-alumnado-de-primero-del-grado-en-ingenieria-agricola-y-del-medio-rural\/\" \/>\n<meta property=\"og:site_name\" content=\"ULL - Noticias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/universidaddelalaguna\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-01T11:41:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ull.es\/portal\/noticias\/wp-content\/uploads\/sites\/13\/2023\/06\/logo-redimensionado.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"gcom4\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CanalULL\" \/>\n<meta name=\"twitter:site\" content=\"@CanalULL\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"gcom4\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ull.es\/portal\/noticias\/2020\/jornada-de-bienvenida-al-alumnado-de-primero-del-grado-en-ingenieria-agricola-y-del-medio-rural\/\",\"url\":\"https:\/\/www.ull.es\/portal\/noticias\/2020\/jornada-de-bienvenida-al-alumnado-de-primero-del-grado-en-ingenieria-agricola-y-del-medio-rural\/\",\"name\":\"Jornada de Bienvenida al alumnado de primero del Grado en Ingenier\u00eda Agr\u00edcola y del Medio Rural - ULL - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/www.ull.es\/portal\/noticias\/#website\"},\"datePublished\":\"2020-10-01T11:41:16+00:00\",\"dateModified\":\"2020-10-01T11:41:16+00:00\",\"author\":{\"@id\":\"https:\/\/www.ull.es\/portal\/noticias\/#\/schema\/person\/9924518fb1ad37d4428e7b5d6f311773\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ull.es\/portal\/noticias\/2020\/jornada-de-bienvenida-al-alumnado-de-primero-del-grado-en-ingenieria-agricola-y-del-medio-rural\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ull.es\/portal\/noticias\/2020\/jornada-de-bienvenida-al-alumnado-de-primero-del-grado-en-ingenieria-agricola-y-del-medio-rural\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ull.es\/portal\/noticias\/2020\/jornada-de-bienvenida-al-alumnado-de-primero-del-grado-en-ingenieria-agricola-y-del-medio-rural\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.ull.es\/portal\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jornada de Bienvenida al alumnado de primero del Grado en Ingenier\u00eda Agr\u00edcola y del Medio Rural\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ull.es\/portal\/noticias\/#website\",\"url\":\"https:\/\/www.ull.es\/portal\/noticias\/\",\"name\":\"ULL - Noticias\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ull.es\/portal\/noticias\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ull.es\/portal\/noticias\/#\/schema\/person\/9924518fb1ad37d4428e7b5d6f311773\",\"name\":\"gcom4\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.ull.es\/portal\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a5d1f5573f10617ccfcc209aaf6aa7fb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a5d1f5573f10617ccfcc209aaf6aa7fb?s=96&d=mm&r=g\",\"caption\":\"gcom4\"},\"url\":\"https:\/\/www.ull.es\/portal\/noticias\/author\/gcom4\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jornada de Bienvenida al alumnado de primero del Grado en Ingenier\u00eda Agr\u00edcola y del Medio Rural - ULL - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ull.es\/portal\/noticias\/2020\/jornada-de-bienvenida-al-alumnado-de-primero-del-grado-en-ingenieria-agricola-y-del-medio-rural\/","og_locale":"es_ES","og_type":"article","og_title":"Jornada de Bienvenida al alumnado de primero del Grado en Ingenier\u00eda Agr\u00edcola y del Medio Rural - ULL - Noticias","og_description":"La Jornada de Bienvenida de la Secci\u00f3n de Ingenier\u00eda Agraria de la Escuela Polit\u00e9cnica Superior de Ingenier\u00eda se celebrar\u00e1 este...","og_url":"https:\/\/www.ull.es\/portal\/noticias\/2020\/jornada-de-bienvenida-al-alumnado-de-primero-del-grado-en-ingenieria-agricola-y-del-medio-rural\/","og_site_name":"ULL - Noticias","article_publisher":"https:\/\/www.facebook.com\/universidaddelalaguna\/","article_published_time":"2020-10-01T11:41:16+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.ull.es\/portal\/noticias\/wp-content\/uploads\/sites\/13\/2023\/06\/logo-redimensionado.png","type":"image\/png"}],"author":"gcom4","twitter_card":"summary_large_image","twitter_creator":"@CanalULL","twitter_site":"@CanalULL","twitter_misc":{"Escrito por":"gcom4","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ull.es\/portal\/noticias\/2020\/jornada-de-bienvenida-al-alumnado-de-primero-del-grado-en-ingenieria-agricola-y-del-medio-rural\/","url":"https:\/\/www.ull.es\/portal\/noticias\/2020\/jornada-de-bienvenida-al-alumnado-de-primero-del-grado-en-ingenieria-agricola-y-del-medio-rural\/","name":"Jornada de Bienvenida al alumnado de primero del Grado en Ingenier\u00eda Agr\u00edcola y del Medio Rural - ULL - Noticias","isPartOf":{"@id":"https:\/\/www.ull.es\/portal\/noticias\/#website"},"datePublished":"2020-10-01T11:41:16+00:00","dateModified":"2020-10-01T11:41:16+00:00","author":{"@id":"https:\/\/www.ull.es\/portal\/noticias\/#\/schema\/person\/9924518fb1ad37d4428e7b5d6f311773"},"breadcrumb":{"@id":"https:\/\/www.ull.es\/portal\/noticias\/2020\/jornada-de-bienvenida-al-alumnado-de-primero-del-grado-en-ingenieria-agricola-y-del-medio-rural\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ull.es\/portal\/noticias\/2020\/jornada-de-bienvenida-al-alumnado-de-primero-del-grado-en-ingenieria-agricola-y-del-medio-rural\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ull.es\/portal\/noticias\/2020\/jornada-de-bienvenida-al-alumnado-de-primero-del-grado-en-ingenieria-agricola-y-del-medio-rural\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ull.es\/portal\/noticias\/"},{"@type":"ListItem","position":2,"name":"Jornada de Bienvenida al alumnado de primero del Grado en Ingenier\u00eda Agr\u00edcola y del Medio Rural"}]},{"@type":"WebSite","@id":"https:\/\/www.ull.es\/portal\/noticias\/#website","url":"https:\/\/www.ull.es\/portal\/noticias\/","name":"ULL - Noticias","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ull.es\/portal\/noticias\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.ull.es\/portal\/noticias\/#\/schema\/person\/9924518fb1ad37d4428e7b5d6f311773","name":"gcom4","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ull.es\/portal\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a5d1f5573f10617ccfcc209aaf6aa7fb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a5d1f5573f10617ccfcc209aaf6aa7fb?s=96&d=mm&r=g","caption":"gcom4"},"url":"https:\/\/www.ull.es\/portal\/noticias\/author\/gcom4\/"}]}},"primary_category":{"id":3845,"name":"Grado en Ingenier\u00eda Agr\u00edcola y del Medio Rural","slug":"grado-en-ingenieria-agricola-y-del-medio-rural","link":"https:\/\/www.ull.es\/portal\/noticias\/category\/noticias-grados\/grado-en-ingenieria-agricola-y-del-medio-rural\/"},"featured_image_thumbnail_url":null,"_links":{"self":[{"href":"https:\/\/www.ull.es\/portal\/noticias\/wp-json\/wp\/v2\/posts\/52296"}],"collection":[{"href":"https:\/\/www.ull.es\/portal\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ull.es\/portal\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ull.es\/portal\/noticias\/wp-json\/wp\/v2\/users\/65"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ull.es\/portal\/noticias\/wp-json\/wp\/v2\/comments?post=52296"}],"version-history":[{"count":1,"href":"https:\/\/www.ull.es\/portal\/noticias\/wp-json\/wp\/v2\/posts\/52296\/revisions"}],"predecessor-version":[{"id":52297,"href":"https:\/\/www.ull.es\/portal\/noticias\/wp-json\/wp\/v2\/posts\/52296\/revisions\/52297"}],"wp:attachment":[{"href":"https:\/\/www.ull.es\/portal\/noticias\/wp-json\/wp\/v2\/media?parent=52296"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ull.es\/portal\/noticias\/wp-json\/wp\/v2\/categories?post=52296"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ull.es\/portal\/noticias\/wp-json\/wp\/v2\/tags?post=52296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}