{"id":88578,"date":"2026-05-11T13:57:14","date_gmt":"2026-05-11T13:57:14","guid":{"rendered":"https:\/\/www.ull.es\/portal\/noticias\/?p=88578"},"modified":"2026-05-11T13:57:14","modified_gmt":"2026-05-11T13:57:14","slug":"convenios-colegios-logopedia-pedagogia","status":"publish","type":"post","link":"https:\/\/www.ull.es\/portal\/noticias\/2026\/convenios-colegios-logopedia-pedagogia\/","title":{"rendered":"Dos convenios con los colegios de Logopedia y Pedagog\u00eda refuerzan los v\u00ednculos de la ULL con el mundo profesional"},"content":{"rendered":"<p>La Universidad de La Laguna ha formalizado hoy, lunes 11 de mayo, dos convenios generales de colaboraci\u00f3n con los que la instituci\u00f3n acad\u00e9mica refuerza sus v\u00ednculos con las organizaciones profesionales. Las entidades firmantes han sido, concretamente, el Colegio Profesional de Logopedas de Canarias y el Colegio Profesional de la Pedagog\u00eda y de la Psicopedagog\u00eda de Santa Cruz de Tenerife.<\/p>\n<p>El rector, Francisco J. Garc\u00eda Rodr\u00edguez, ha se\u00f1alado que la firma de estos acuerdos supone una muestra m\u00e1s del compromiso de la universidad con la formaci\u00f3n en todos los \u00e1mbitos, ya que con ellos se impulsar\u00e1 la formaci\u00f3n no solo de grado, sino tambi\u00e9n a lo largo de la vida. En ese sentido, record\u00f3 que el programa de microcredenciales que est\u00e1 siendo impulsado en la actualidad permite ofrecer una formaci\u00f3n acorde con las necedades de profesionales en ejercicio y, de ese modo, ser a\u00fan m\u00e1s \u00fatiles a la sociedad.<\/p>\n<p><strong>Logopedia<\/strong><\/p>\n<p>La firmante del primer convenio fue la presidenta del Colegio Profesional e Logopedas de Canarias, Susana Nieto Trujillo, quien se\u00f1al\u00f3 que este acuerdo supone el reconocimiento al trabajo conjunto desde los cinco a\u00f1os que lleva en marcha la organizaci\u00f3n colegial con el doble objetivo de acercarse al alumnado y mejorar la formaci\u00f3n de grado.<\/p>\n<p>Para ello, Nieto consider\u00f3 importante contar con m\u00e1s profesorado especializado en esta disciplina, lo cual pasa por incentivar el doctorado en Logopedia. Otro punto importante que se\u00f1al\u00f3 fue la mejora de las pr\u00e1cticas acad\u00e9micas \u201cque no deben considerarse un mero tr\u00e1mite y deben realizarse en centros acreditados y con profesionales colegiados\u201d para garantizar la calidad y seguridad para el alumnado y la ciudadan\u00eda. La presidenta tambi\u00e9n aprovecho la ocasi\u00f3n para manifestar su apoyo a la universidad p\u00fablica, gesto que el rector le agradeci\u00f3.<\/p>\n<p>El decano de la Facultad de Psicolog\u00eda y Logopedia de la Universidad de La Laguna, Juan Manuel Bethencourt P\u00e9rez, tambi\u00e9n estuvo presente en el acto y resalt\u00f3 que este acuerdo era \u201cpositivo para el alumnado, los egresados, los profesionales, la academia y la sociedad\u201d. El acuerdo tiene una vigencia de cuatro a\u00f1os y pondr\u00e1 especial \u00e9nfasis en las actividades de acercamiento y difusi\u00f3n de la Logopedia mediante charlas, seminarios, cursos y otras actividades.<\/p>\n<div id=\"attachment_88580\" style=\"width: 310px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.ull.es\/portal\/noticias\/wp-content\/uploads\/sites\/13\/2026\/05\/convenio-pedagogia-002.jpg\" target=\"_blank\" rel=\"noopener\" target=\"_blank\" rel=\"noopener\"><img aria-describedby=\"caption-attachment-88580\" decoding=\"async\" loading=\"lazy\" class=\"wp-image-88580 size-medium\" src=\"https:\/\/www.ull.es\/portal\/noticias\/wp-content\/uploads\/sites\/13\/2026\/05\/convenio-pedagogia-002-300x200.jpg\" alt=\"Firma con el Colegio Profesional de la Pedagog\u00eda y de la Psicopedagog\u00eda de Santa Cruz de Tenerife.\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.ull.es\/portal\/noticias\/wp-content\/uploads\/sites\/13\/2026\/05\/convenio-pedagogia-002-300x200.jpg 300w, https:\/\/www.ull.es\/portal\/noticias\/wp-content\/uploads\/sites\/13\/2026\/05\/convenio-pedagogia-002-1024x683.jpg 1024w, https:\/\/www.ull.es\/portal\/noticias\/wp-content\/uploads\/sites\/13\/2026\/05\/convenio-pedagogia-002-768x512.jpg 768w, https:\/\/www.ull.es\/portal\/noticias\/wp-content\/uploads\/sites\/13\/2026\/05\/convenio-pedagogia-002-375x250.jpg 375w, https:\/\/www.ull.es\/portal\/noticias\/wp-content\/uploads\/sites\/13\/2026\/05\/convenio-pedagogia-002-750x500.jpg 750w, https:\/\/www.ull.es\/portal\/noticias\/wp-content\/uploads\/sites\/13\/2026\/05\/convenio-pedagogia-002-1140x760.jpg 1140w, https:\/\/www.ull.es\/portal\/noticias\/wp-content\/uploads\/sites\/13\/2026\/05\/convenio-pedagogia-002.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-88580\" class=\"wp-caption-text\">Firma con el Colegio Profesional de la Pedagog\u00eda y de la Psicopedagog\u00eda de Santa Cruz de Tenerife.<\/p><\/div>\n<p><strong>Pedagog\u00eda y psicopedagog\u00eda<\/strong><\/p>\n<p>A continuaci\u00f3n fue rubricado del acuerdo con el Colegio Profesional de la Pedagog\u00eda y de la Psicopedagog\u00eda de Santa Cruz de Tenerife por parte de su presidenta, In\u00e9s L\u00f3pez Medinilla, que agradeci\u00f3 al a Universidad de La Laguna y, especialmente, a la actual decana de la Facultad de Educaci\u00f3n, Esperanza Ceballos, su ayuda para poder poner en marcha esta organizaci\u00f3n colegial de reciente creaci\u00f3n, que ha visto la luz tras treinta a\u00f1os siendo una aspiraci\u00f3n de la profesi\u00f3n. Explico que resulta relevante contar con esta organizaci\u00f3n en un contexto en el que otras especialidades est\u00e1n solapando sus competencias con las de la pedagog\u00eda y la psicopedagog\u00eda.<\/p>\n<p>Sobre esa cuesti\u00f3n, la vicedecana del colegio, M\u00f3nica Yballa Gonz\u00e1lez, record\u00f3 que el colegio est\u00e1 tratando de negociar con las autoridades que la colegiaci\u00f3n sea obligatoria para poder ejercer la profesi\u00f3n en la provincia, tal y como sucede en la Comunidad Valenciana.<\/p>\n<p>El vicerrector de Docencia de la universidad, Jos\u00e9 Manuel Garc\u00eda Fraga, tambi\u00e9n estuvo en el acto y valor\u00f3 que para los y las profesionales, contar con el respaldo de un colegio \u201cvisibiliza y refuerza\u201d, por lo que es importante respaldar su actividad. El acuerdo tiene una vigencia de dos a\u00f1os prorrogables por un periodo similar, y favorecer\u00e1 el desarrollo de actividades de formaci\u00f3n, investigaci\u00f3n, difusi\u00f3n y defensa de los valores sociales y c\u00edvicos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Universidad de La Laguna ha formalizado hoy, lunes 11 de mayo, dos convenios generales de colaboraci\u00f3n con los que&#8230;<\/p>\n","protected":false},"author":21,"featured_media":88579,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[345,348,2765],"tags":[12655,12654,910,12657,10363,12656],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ULL firma convenios con los colegios de Logopedia y Pedagog\u00eda<\/title>\n<meta name=\"description\" content=\"Estas formas refuerzan el compromiso de la universidad con la formaci\u00f3n a lo largo de la vida y la colaboraci\u00f3n institucional.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ull.es\/portal\/noticias\/2026\/convenios-colegios-logopedia-pedagogia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ULL firma convenios con los colegios de Logopedia y Pedagog\u00eda\" \/>\n<meta property=\"og:description\" content=\"Estas formas refuerzan el compromiso de la universidad con la formaci\u00f3n a lo largo de la vida y la colaboraci\u00f3n institucional.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ull.es\/portal\/noticias\/2026\/convenios-colegios-logopedia-pedagogia\/\" \/>\n<meta property=\"og:site_name\" content=\"ULL - Noticias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/universidaddelalaguna\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-11T13:57:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ull.es\/portal\/noticias\/wp-content\/uploads\/sites\/13\/2026\/05\/colegio-logopedas-003.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"prensa2\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CanalULL\" \/>\n<meta name=\"twitter:site\" content=\"@CanalULL\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"prensa2\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ull.es\/portal\/noticias\/2026\/convenios-colegios-logopedia-pedagogia\/\",\"url\":\"https:\/\/www.ull.es\/portal\/noticias\/2026\/convenios-colegios-logopedia-pedagogia\/\",\"name\":\"ULL firma convenios con los colegios de Logopedia y Pedagog\u00eda\",\"isPartOf\":{\"@id\":\"https:\/\/www.ull.es\/portal\/noticias\/#website\"},\"datePublished\":\"2026-05-11T13:57:14+00:00\",\"dateModified\":\"2026-05-11T13:57:14+00:00\",\"author\":{\"@id\":\"https:\/\/www.ull.es\/portal\/noticias\/#\/schema\/person\/c3b2aa857797592927a03740d6664376\"},\"description\":\"Estas formas refuerzan el compromiso de la universidad con la formaci\u00f3n a lo largo de la vida y la colaboraci\u00f3n institucional.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ull.es\/portal\/noticias\/2026\/convenios-colegios-logopedia-pedagogia\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ull.es\/portal\/noticias\/2026\/convenios-colegios-logopedia-pedagogia\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ull.es\/portal\/noticias\/2026\/convenios-colegios-logopedia-pedagogia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.ull.es\/portal\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dos convenios con los colegios de Logopedia y Pedagog\u00eda refuerzan los v\u00ednculos de la ULL con el mundo profesional\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ull.es\/portal\/noticias\/#website\",\"url\":\"https:\/\/www.ull.es\/portal\/noticias\/\",\"name\":\"ULL - Noticias\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ull.es\/portal\/noticias\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ull.es\/portal\/noticias\/#\/schema\/person\/c3b2aa857797592927a03740d6664376\",\"name\":\"prensa2\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.ull.es\/portal\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b58f310a5de5feb33d1e026d2493f23c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b58f310a5de5feb33d1e026d2493f23c?s=96&d=mm&r=g\",\"caption\":\"prensa2\"},\"url\":\"https:\/\/www.ull.es\/portal\/noticias\/author\/prensa2\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ULL firma convenios con los colegios de Logopedia y Pedagog\u00eda","description":"Estas formas refuerzan el compromiso de la universidad con la formaci\u00f3n a lo largo de la vida y la colaboraci\u00f3n institucional.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ull.es\/portal\/noticias\/2026\/convenios-colegios-logopedia-pedagogia\/","og_locale":"es_ES","og_type":"article","og_title":"ULL firma convenios con los colegios de Logopedia y Pedagog\u00eda","og_description":"Estas formas refuerzan el compromiso de la universidad con la formaci\u00f3n a lo largo de la vida y la colaboraci\u00f3n institucional.","og_url":"https:\/\/www.ull.es\/portal\/noticias\/2026\/convenios-colegios-logopedia-pedagogia\/","og_site_name":"ULL - Noticias","article_publisher":"https:\/\/www.facebook.com\/universidaddelalaguna\/","article_published_time":"2026-05-11T13:57:14+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.ull.es\/portal\/noticias\/wp-content\/uploads\/sites\/13\/2026\/05\/colegio-logopedas-003.jpg","type":"image\/jpeg"}],"author":"prensa2","twitter_card":"summary_large_image","twitter_creator":"@CanalULL","twitter_site":"@CanalULL","twitter_misc":{"Escrito por":"prensa2","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ull.es\/portal\/noticias\/2026\/convenios-colegios-logopedia-pedagogia\/","url":"https:\/\/www.ull.es\/portal\/noticias\/2026\/convenios-colegios-logopedia-pedagogia\/","name":"ULL firma convenios con los colegios de Logopedia y Pedagog\u00eda","isPartOf":{"@id":"https:\/\/www.ull.es\/portal\/noticias\/#website"},"datePublished":"2026-05-11T13:57:14+00:00","dateModified":"2026-05-11T13:57:14+00:00","author":{"@id":"https:\/\/www.ull.es\/portal\/noticias\/#\/schema\/person\/c3b2aa857797592927a03740d6664376"},"description":"Estas formas refuerzan el compromiso de la universidad con la formaci\u00f3n a lo largo de la vida y la colaboraci\u00f3n institucional.","breadcrumb":{"@id":"https:\/\/www.ull.es\/portal\/noticias\/2026\/convenios-colegios-logopedia-pedagogia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ull.es\/portal\/noticias\/2026\/convenios-colegios-logopedia-pedagogia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ull.es\/portal\/noticias\/2026\/convenios-colegios-logopedia-pedagogia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ull.es\/portal\/noticias\/"},{"@type":"ListItem","position":2,"name":"Dos convenios con los colegios de Logopedia y Pedagog\u00eda refuerzan los v\u00ednculos de la ULL con el mundo profesional"}]},{"@type":"WebSite","@id":"https:\/\/www.ull.es\/portal\/noticias\/#website","url":"https:\/\/www.ull.es\/portal\/noticias\/","name":"ULL - Noticias","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ull.es\/portal\/noticias\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.ull.es\/portal\/noticias\/#\/schema\/person\/c3b2aa857797592927a03740d6664376","name":"prensa2","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ull.es\/portal\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b58f310a5de5feb33d1e026d2493f23c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b58f310a5de5feb33d1e026d2493f23c?s=96&d=mm&r=g","caption":"prensa2"},"url":"https:\/\/www.ull.es\/portal\/noticias\/author\/prensa2\/"}]}},"primary_category":{"id":345,"name":"Destacado","slug":"destacado","link":"https:\/\/www.ull.es\/portal\/noticias\/category\/destacado\/"},"featured_image_thumbnail_url":"https:\/\/www.ull.es\/portal\/noticias\/wp-content\/uploads\/sites\/13\/2026\/05\/colegio-logopedas-003-300x200.jpg","_links":{"self":[{"href":"https:\/\/www.ull.es\/portal\/noticias\/wp-json\/wp\/v2\/posts\/88578"}],"collection":[{"href":"https:\/\/www.ull.es\/portal\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ull.es\/portal\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ull.es\/portal\/noticias\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ull.es\/portal\/noticias\/wp-json\/wp\/v2\/comments?post=88578"}],"version-history":[{"count":1,"href":"https:\/\/www.ull.es\/portal\/noticias\/wp-json\/wp\/v2\/posts\/88578\/revisions"}],"predecessor-version":[{"id":88581,"href":"https:\/\/www.ull.es\/portal\/noticias\/wp-json\/wp\/v2\/posts\/88578\/revisions\/88581"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ull.es\/portal\/noticias\/wp-json\/wp\/v2\/media\/88579"}],"wp:attachment":[{"href":"https:\/\/www.ull.es\/portal\/noticias\/wp-json\/wp\/v2\/media?parent=88578"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ull.es\/portal\/noticias\/wp-json\/wp\/v2\/categories?post=88578"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ull.es\/portal\/noticias\/wp-json\/wp\/v2\/tags?post=88578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}