{"id":7663,"date":"2023-11-09T10:48:14","date_gmt":"2023-11-09T10:48:14","guid":{"rendered":"https:\/\/www.ull.es\/servicios\/publicaciones\/?post_type=publicacion&#038;p=7663"},"modified":"2023-11-09T11:06:58","modified_gmt":"2023-11-09T11:06:58","slug":"la-economia-las-finanzas-y-la-desigualdad","status":"publish","type":"publicacion","link":"https:\/\/www.ull.es\/servicios\/publicaciones\/publicacion\/la-economia-las-finanzas-y-la-desigualdad\/","title":{"rendered":"La econom\u00eda, las finanzas y la desigualdad"},"content":{"rendered":"","protected":false},"featured_media":7673,"template":"","class_list":["post-7663","publicacion","type-publicacion","status-publish","has-post-thumbnail","hentry","taxonomia_publicacion-publicaciones-institucionales","taxonomia_serie-economia","taxonomia_autor-medina-hernandez-urbano"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.ull.es\/servicios\/publicaciones\/wp-json\/wp\/v2\/publicacion\/7663","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ull.es\/servicios\/publicaciones\/wp-json\/wp\/v2\/publicacion"}],"about":[{"href":"https:\/\/www.ull.es\/servicios\/publicaciones\/wp-json\/wp\/v2\/types\/publicacion"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ull.es\/servicios\/publicaciones\/wp-json\/wp\/v2\/media\/7673"}],"wp:attachment":[{"href":"https:\/\/www.ull.es\/servicios\/publicaciones\/wp-json\/wp\/v2\/media?parent=7663"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}