{"id":1,"date":"2022-12-16T12:36:48","date_gmt":"2022-12-16T12:36:48","guid":{"rendered":"https:\/\/www.ull.es\/vive-la-universidad\/?p=1"},"modified":"2022-12-16T12:36:48","modified_gmt":"2022-12-16T12:36:48","slug":"hola-mundo","status":"publish","type":"post","link":"https:\/\/www.ull.es\/vive-la-universidad\/blog\/2022\/12\/16\/hola-mundo\/","title":{"rendered":"\u00a1Hola, mundo!"},"content":{"rendered":"\n<p>Bienvenido a WordPress. Esta es tu primera entrada. Ed\u00edtala o b\u00f3rrala, \u00a1luego empieza a escribir!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bienvenido a WordPress. Esta es tu primera entrada. Ed\u00edtala o b\u00f3rrala, \u00a1luego empieza a escribir!<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00a1Hola, mundo! - Vive la Universidad<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ull.es\/vive-la-universidad\/blog\/2022\/12\/16\/hola-mundo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00a1Hola, mundo! - Vive la Universidad\" \/>\n<meta property=\"og:description\" content=\"Bienvenido a WordPress. Esta es tu primera entrada. Ed\u00edtala o b\u00f3rrala, \u00a1luego empieza a escribir!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ull.es\/vive-la-universidad\/blog\/2022\/12\/16\/hola-mundo\/\" \/>\n<meta property=\"og:site_name\" content=\"Vive la Universidad\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-16T12:36:48+00:00\" \/>\n<meta name=\"author\" content=\"adminull\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"adminull\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ull.es\/vive-la-universidad\/blog\/2022\/12\/16\/hola-mundo\/\",\"url\":\"https:\/\/www.ull.es\/vive-la-universidad\/blog\/2022\/12\/16\/hola-mundo\/\",\"name\":\"\u00a1Hola, mundo! - Vive la Universidad\",\"isPartOf\":{\"@id\":\"https:\/\/www.ull.es\/vive-la-universidad\/#website\"},\"datePublished\":\"2022-12-16T12:36:48+00:00\",\"author\":{\"@id\":\"https:\/\/www.ull.es\/vive-la-universidad\/#\/schema\/person\/50a450d794a361df20cde0e6531bf23c\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ull.es\/vive-la-universidad\/blog\/2022\/12\/16\/hola-mundo\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ull.es\/vive-la-universidad\/blog\/2022\/12\/16\/hola-mundo\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ull.es\/vive-la-universidad\/blog\/2022\/12\/16\/hola-mundo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.ull.es\/vive-la-universidad\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00a1Hola, mundo!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ull.es\/vive-la-universidad\/#website\",\"url\":\"https:\/\/www.ull.es\/vive-la-universidad\/\",\"name\":\"Vive la Universidad\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ull.es\/vive-la-universidad\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ull.es\/vive-la-universidad\/#\/schema\/person\/50a450d794a361df20cde0e6531bf23c\",\"name\":\"adminull\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.ull.es\/vive-la-universidad\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0799dfc0fd1cb35732f52c4dff715eff?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0799dfc0fd1cb35732f52c4dff715eff?s=96&d=mm&r=g\",\"caption\":\"adminull\"},\"sameAs\":[\"https:\/\/www.ull.es\/vive-la-universidad\"],\"url\":\"https:\/\/www.ull.es\/vive-la-universidad\/blog\/author\/adminull\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00a1Hola, mundo! - Vive la Universidad","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ull.es\/vive-la-universidad\/blog\/2022\/12\/16\/hola-mundo\/","og_locale":"es_ES","og_type":"article","og_title":"\u00a1Hola, mundo! - Vive la Universidad","og_description":"Bienvenido a WordPress. Esta es tu primera entrada. Ed\u00edtala o b\u00f3rrala, \u00a1luego empieza a escribir!","og_url":"https:\/\/www.ull.es\/vive-la-universidad\/blog\/2022\/12\/16\/hola-mundo\/","og_site_name":"Vive la Universidad","article_published_time":"2022-12-16T12:36:48+00:00","author":"adminull","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"adminull"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ull.es\/vive-la-universidad\/blog\/2022\/12\/16\/hola-mundo\/","url":"https:\/\/www.ull.es\/vive-la-universidad\/blog\/2022\/12\/16\/hola-mundo\/","name":"\u00a1Hola, mundo! - Vive la Universidad","isPartOf":{"@id":"https:\/\/www.ull.es\/vive-la-universidad\/#website"},"datePublished":"2022-12-16T12:36:48+00:00","author":{"@id":"https:\/\/www.ull.es\/vive-la-universidad\/#\/schema\/person\/50a450d794a361df20cde0e6531bf23c"},"breadcrumb":{"@id":"https:\/\/www.ull.es\/vive-la-universidad\/blog\/2022\/12\/16\/hola-mundo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ull.es\/vive-la-universidad\/blog\/2022\/12\/16\/hola-mundo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ull.es\/vive-la-universidad\/blog\/2022\/12\/16\/hola-mundo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ull.es\/vive-la-universidad\/"},{"@type":"ListItem","position":2,"name":"\u00a1Hola, mundo!"}]},{"@type":"WebSite","@id":"https:\/\/www.ull.es\/vive-la-universidad\/#website","url":"https:\/\/www.ull.es\/vive-la-universidad\/","name":"Vive la Universidad","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ull.es\/vive-la-universidad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.ull.es\/vive-la-universidad\/#\/schema\/person\/50a450d794a361df20cde0e6531bf23c","name":"adminull","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ull.es\/vive-la-universidad\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0799dfc0fd1cb35732f52c4dff715eff?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0799dfc0fd1cb35732f52c4dff715eff?s=96&d=mm&r=g","caption":"adminull"},"sameAs":["https:\/\/www.ull.es\/vive-la-universidad"],"url":"https:\/\/www.ull.es\/vive-la-universidad\/blog\/author\/adminull\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ull.es\/vive-la-universidad\/wp-json\/wp\/v2\/posts\/1"}],"collection":[{"href":"https:\/\/www.ull.es\/vive-la-universidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ull.es\/vive-la-universidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ull.es\/vive-la-universidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ull.es\/vive-la-universidad\/wp-json\/wp\/v2\/comments?post=1"}],"version-history":[{"count":0,"href":"https:\/\/www.ull.es\/vive-la-universidad\/wp-json\/wp\/v2\/posts\/1\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.ull.es\/vive-la-universidad\/wp-json\/wp\/v2\/media?parent=1"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ull.es\/vive-la-universidad\/wp-json\/wp\/v2\/categories?post=1"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ull.es\/vive-la-universidad\/wp-json\/wp\/v2\/tags?post=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}